{"id":74419,"date":"2012-01-16T07:26:02","date_gmt":"2012-01-16T07:26:02","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/01\/16\/le-systeme-de-la-communication-militaire-us-est-indefendable\/"},"modified":"2012-01-16T07:26:02","modified_gmt":"2012-01-16T07:26:02","slug":"le-systeme-de-la-communication-militaire-us-est-indefendable","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/01\/16\/le-systeme-de-la-communication-militaire-us-est-indefendable\/","title":{"rendered":"Le syst\u00e8me de la communication militaire US est \u201cind\u00e9fendable\u201d"},"content":{"rendered":"<p><p>Cette affirmation est d&rsquo;un expert en la mati\u00e8re, en fait elle est de l&rsquo;homme qui, \u00e0 l&rsquo;int\u00e9rieur du syst\u00e8me de l&rsquo;am\u00e9ricanisme en tant que branche principale du Syst\u00e8me, est charg\u00e9 de d\u00e9fendre le syst\u00e8me de la communication de l&rsquo;appareil militariste US. Il s&rsquo;agit du g\u00e9n\u00e9ral Keith Alexander, directeur de la National Security Agency (NSA) et chef du nouveau commandement US de cyberguerre, le U.S. Cyber Command.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est <em>Danger Room<\/em> qui a recueilli les d\u00e9clarations d&rsquo;Alexander, qui sont reproduites sur le site, le <a href=\"http:\/\/www.wired.com\/dangerroom\/2012\/01\/nsa-cant-defend\/\" class=\"gen\">12 janvier 2012<\/a>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Gen. Keith Alexander, head of both the secretive National Security Agency and the military&rsquo;s new U.S. Cyber Command, has tens of thousands of hackers, cryptologists, and system administrators serving under him. But at the moment, their ability to protect the Defense Department&rsquo;s information infrastructure  let alone the broader civilian internet  is limited. The Pentagon&rsquo;s patchwork quilt of 15,000 different networks is too haphazard to safeguard.<\/em> [] <em>15,000 enclaves: You can&rsquo;t see em all. You cannot defend them all, Alexander told an FBI-sponsored gathering of law enforcement and cybersecurity professionals at New York&rsquo;s Fordham University. You&rsquo;ve got to have an infrastructure that is defensible.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Cybersecurity has become a top priority in the Pentagon  one of the few areas of the Defense Department set to increase during a time of budget cutbacks. For Alexander, one of the top cybersecurity priorities is to drastically consolidate the number of military networks, data centers, and help desks into a more manageable number  3,000, instead of 15,000. Meanwhile, he wants the Defense Department to move towards cloud computing, which he contends is both cheaper and easier to protect. We know where we are today is not defensible, he said. We are pushing very hard for both the Defense Department and the intelligence community to move down this road. The National Security Agency&rsquo;s going there first. We&rsquo;re doing this first to show  if it&rsquo;s good for us, it&rsquo;ll be good for others.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLa suite du texte d\u00e9taille divers plans du g\u00e9n\u00e9ral Alexander pour passer d&rsquo;une situation o\u00f9 le syst\u00e8me de la communication US est ind\u00e9fendable \u00e0 une situation o\u00f9 il le serait. Il s&rsquo;agit de r\u00e9duire le nombre de r\u00e9seaux sp\u00e9cifiques au syst\u00e8me militariste du syst\u00e8me de l&rsquo;am\u00e9ricanisme qu&rsquo;il faut prot\u00e9ger, et la fa\u00e7on d&rsquo;y arriver, et l&rsquo;esp\u00e9rance de la NSA d&rsquo;obtenir un r\u00e9sultat acceptable pour 2016. (On voit que la r\u00e9duction de 15.000 \u00e0 3.000 r\u00e9seaux serait une mesure acceptable pour ce d\u00e9lai, selon Alexander.) L&rsquo;alarme est donc sonn\u00e9e, le plan est en train d&rsquo;\u00eatre trac\u00e9.<\/p>\n<\/p>\n<p><p>\tIl reste qu&rsquo;on peut entretenir des doutes consid\u00e9rables sur sa r\u00e9ussite. Alexander pr\u00e9cise qu&rsquo;il a d\u00e9j\u00e0 commenc\u00e9 sa r\u00e9forme \u00e0 la NSA, en passant de 900 \u00e0 450 r\u00e9seaux, avec le but d&rsquo;arriver \u00e0 20 ; la reforme est donc en cours et elle donne des r\u00e9sultats, proclame Alexander, qui pr\u00eache en l&rsquo;occurrence pour sa paroisse (la NSA), en ayant dans ce cas pour but de d\u00e9montrer la vertu de sa gestion et celle de l&rsquo;agence qu&rsquo;il dirige. Rien que ces seules circonstances pour la NSA nous feraient \u00e9mettre un doute sur la situation en cours d&rsquo;am\u00e9lioration telle qu&rsquo;Alexander la pr\u00e9sente ; par cons\u00e9quent, nous nous permettrons de douter de son succ\u00e8s, et, par cons\u00e9quent, du succ\u00e8s des projets de faire passer le nombre de r\u00e9seaux des diff\u00e9rents services du syst\u00e8me militariste de 15.000 \u00e0 3.000 en quatre ans.<\/p>\n<\/p>\n<p><p>\tLa bureaucratie est un monstre complexe, et l&rsquo;utilisation extensive et selon un rythme exponentiel du syst\u00e8me de la communication, essentiellement depuis les ann\u00e9es 1990, ne le rend pas moins complexe ; on comprend que c&rsquo;est exactement le contraire, d&rsquo;une fa\u00e7on monstrueuse et sur un rythme d\u00e9mentiel. Au d\u00e9part, lorsque ce qu&rsquo;on a coutume de nommer la r\u00e9volution de la communication a commenc\u00e9, il \u00e9tait \u00e9vident qu&rsquo;on se trouvait devant une formule mariant id\u00e9alement l&rsquo;autonomie de chacun et la centralisation du tout. Les deux situations \u00e9taient n\u00e9cessaires, pour permettre une exploitation maximale de la communication en \u00e9largissant les capacit\u00e9s d&rsquo;initiative des forces et de toutes les ressources tout en conservant un contr\u00f4le sur l&rsquo;ensemble. Bien entendu, comme toujours avec la bureaucratie, plus ce type d&rsquo;\u00e9volution se d\u00e9veloppe, plus les besoins augmentent, les services se multipliant et r\u00e9clamant chacun leur autonomie, d&rsquo;autant plus ais\u00e9ment qu&rsquo;en th\u00e9orie la centralisation est assur\u00e9e. Renverser un tel mouvement semble une gageure insurmontable, de la sorte d&rsquo;une ambition de rendre soudain le programme JSF rentable, dans les temps et capable de remplir les missions pour lesquelles il a \u00e9t\u00e9 d\u00e9velopp\u00e9.<\/p>\n<\/p>\n<p><p>\tSelon notre appr\u00e9ciation plut\u00f4t intuitive des choses, il suffit d&rsquo;attendre le prochain ratage ou la prochaine erreur de la NSA pour voir remettre en cause la r\u00e9forme du g\u00e9n\u00e9ral Alexander, ou bien d\u00e9couvrir sa fausset\u00e9, et voir dans tous les cas le r\u00e9flexe de s\u00e9curit\u00e9 nationale conduire \u00e0 r\u00e9clamer l&rsquo;ouverture de nouveaux r\u00e9seaux, notamment des r\u00e9seaux de protection et de s\u00e9curisation, renversant le sens de la reforme vers la prolif\u00e9ration. Il en sera de m\u00eame pour tous les cas, tous les services, et ainsi de suite. Au reste, cette hypoth\u00e8se n&rsquo;en est pas une puisqu&rsquo;un exemple fameux existe d\u00e9j\u00e0 et montre ce processus. Des sources de l&rsquo;USAF ont d\u00e9j\u00e0 pr\u00e9cis\u00e9 qu&rsquo;\u00e0 la suite de la capture du RQ-170 par les Iraniens, \u00e0 partir de ce qui serait, selon les derni\u00e8res informations, un site de cyberguerre russo-iranien install\u00e9 en Syrie, de nouveaux r\u00e9seaux communication et de cyberguerre ont \u00e9t\u00e9 cr\u00e9\u00e9s au sein du commandement g\u00e9n\u00e9ral de l&rsquo;USAF et, en dessous, au sein de commandements locaux de cyberguerre de l&rsquo;USAF. Chaque \u00e9v\u00e9nement de cette sorte,  et il y en a constamment, des vrais et des suppos\u00e9s, et il y en aura de plus en plus,  am\u00e8ne et am\u00e8nera la cr\u00e9ation de nouveaux r\u00e9seaux. Le programme de r\u00e9forme du g\u00e9n\u00e9ral d&rsquo;Alexander se heurte \u00e0 la tendance habituelle de la bureaucratie du Pentagone, qui pourrait \u00eatre nomm\u00e9 tonneau des Dana\u00efdes. Il est de fait indiscutable et irr\u00e9formable qu&rsquo;une situation du type tonneau des Dana\u00efdes est \u00e9videmment ind\u00e9fendable. Il est de fait indiscutable et irr\u00e9formable que la continuelle mont\u00e9e en surpuissance du Syst\u00e8me alimente \u00e0 mesure sa continuelle chute dans l&rsquo;autodestruction.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 16 janvier 2012 \u00e0 07H26<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette affirmation est d&rsquo;un expert en la mati\u00e8re, en fait elle est de l&rsquo;homme qui, \u00e0 l&rsquo;int\u00e9rieur du syst\u00e8me de l&rsquo;am\u00e9ricanisme en tant que branche principale du Syst\u00e8me, est charg\u00e9 de d\u00e9fendre le syst\u00e8me de la communication de l&rsquo;appareil militariste US. Il s&rsquo;agit du g\u00e9n\u00e9ral Keith Alexander, directeur de la National Security Agency (NSA) et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2857,3273,10527,4718,3283,3871,6328,8590,11765],"class_list":["post-74419","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-alexander","tag-command","tag-cyber","tag-danger","tag-general","tag-nsa","tag-reseaux","tag-room","tag-rq-170"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74419"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74419\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}