{"id":74440,"date":"2012-01-23T04:46:42","date_gmt":"2012-01-23T04:46:42","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/01\/23\/drole-de-primaires-drole-de-campagne\/"},"modified":"2012-01-23T04:46:42","modified_gmt":"2012-01-23T04:46:42","slug":"drole-de-primaires-drole-de-campagne","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/01\/23\/drole-de-primaires-drole-de-campagne\/","title":{"rendered":"Dr\u00f4le de primaires, dr\u00f4le de campagne\u2026"},"content":{"rendered":"<p><p>La quatri\u00e8me place (13% des voix) de Ron Paul en Caroline du Sud para\u00eetrait une incontestable d\u00e9faite pour lui, alors que certains sondages lui pr\u00e9disaient  une troisi\u00e8me place, avec jusqu&rsquo;\u00e0 21%. Les sondages se sont av\u00e9r\u00e9s extr\u00eamement volatiles, avec une tr\u00e8s forte proportion d&rsquo;ind\u00e9cis (40%), qui ont \u00e9t\u00e9 surtout s\u00e9duits par la d\u00e9magogie de bulldozer de Gingrich, renforc\u00e9 par le d\u00e9part de Perry qui a appel\u00e9 \u00e0 voter pour lui (La plus forte d\u00e9ception \u00e0 cet \u00e9gard, pour Ron Paul, c&rsquo;est que  <em>Tea Party<\/em>, tr\u00e8s implant\u00e9 en Caroline du Sud, s&rsquo;est rang\u00e9 du c\u00f4t\u00e9 de Gingrich \u00e0 partir d&rsquo;arguments de circonstance, de la part d&rsquo;un candidat connu pour ses positions bellicistes qui impliquent un centre puissant, contre lequel <em>Tea Party<\/em> a depuis l&rsquo;origine bas\u00e9 sa justification et son action.)<\/p>\n<\/p>\n<p><p>\tMais, justement, cette victoire \u00e9crasante de Gingrich introduit un deuxi\u00e8me \u00e9l\u00e9ment, peut-\u00eatre bien plus important que le r\u00e9sultat d\u00e9cevant de Ron Paul. Gingrich est un candidat destructeur, dont le but principal est de d\u00e9truire la candidature de Romney. Ses chances de devenir le candidat r\u00e9publicain sont minimes, ne serait-ce que parce qu&rsquo;il est en d\u00e9faut de signatures de soutien dans deux \u00c9tats importants, et qu&rsquo;il lui est d\u00e9finitivement interdit, par d\u00e9cision sans appel, d&rsquo;y participer. (La m\u00eame chose pour Santorum, lui dans quatre \u00c9tats.) Du coup, sa victoire importante a pour cons\u00e9quence, du point de vue de l&rsquo;<em>establishment<\/em>, de plonger les primaires dans le chaos en imposant un brusque coup de frein \u00e0 la candidature de Romney. Pour l&rsquo;<em>establishment<\/em>, le candidat d\u00e9sign\u00e9, le seul possible, c&rsquo;est Romney, et Gingrich, avec son inconstance irresponsable, son extr\u00e9misme d\u00e9magogique, est presque aussi d\u00e9testable que Ron Paul, mais pour d&rsquo;autres raisons que Ron Paul.<\/p>\n<\/p>\n<p><p>\tUn partisan inconditionnel de Ron Paul donne cet argumentaire pour juger le r\u00e9sultat de Caroline du Sud, o\u00f9 Ron Paul est pass\u00e9 de 3% en 2008 \u00e0 13% de 2012, plut\u00f4t satisfaisant. Il constate la fragmentation du parti r\u00e9publicain, essentiellement du point de vue de l&rsquo;<em>establishment<\/em> qui cherche \u00e0 construire un bloc homog\u00e8ne et inexpugnable autour d&rsquo;un candidat,  Romney jusqu&rsquo;ici, en l&rsquo;occurrence. (Le <a href=\"http:\/\/www.dailypaul.com\/206898\/no-long-faces-ron-paul-supporters\" class=\"gen\">21 janvier 2012<\/a>, sur <em>DailyPaul.com<\/em>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Gingrich beating Romney in South Carolina is actually a good thing for Ron Paul. The delegates are getting all split up and it&rsquo;s going to be very difficult for Romney, or anyone to get enough, which could result in a brokered convention. Santorum will be dropping out soon as he has no money or organization to continue much further and isn&rsquo;t even on the ballot in 4 states. Gingrich, who is also missing from the ballot in 2 states, is going to split votes with Romney and take delegates away from him as Paul continues to pick them up little by little.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>This race is a marathon, not a sprint. The campaign has a plan. They have money, organization, and grassroots support in many upcoming states like Nevada, Missouri, Maine, Minnesota, Louisiana, Wyoming, Montana, South Dakota, etc. They never expected to do all that well in South Carolina or Florida, so this doesn&rsquo;t hurt his campaign much at all. He will be in the race all the way to the convention and possibly steal the nomination.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLa situation de la campagne elle-m\u00eame pr\u00e9sente des particularit\u00e9s qui sortent de l&rsquo;ordinaire. Jamais une campagne n&rsquo;a \u00e9t\u00e9 aussi r\u00e9gl\u00e9e d&rsquo;avance par l&rsquo;<em>establishment<\/em> pour le candidat pr\u00e9tendant (r\u00e9publicain dans ce cas), avec Romney comme candidat, et jamais ce candidat parti en tr\u00e8s forte position dans les sondages et les soutiens d&rsquo;argent ne s&rsquo;est montr\u00e9 aussi inconsistant ; jamais une campagne aussi vite r\u00e9duite \u00e0 quatre candidats, ne s&rsquo;est trouv\u00e9e aussi ouverte, aussi divis\u00e9e entre ces quatre candidats, dont au moins deux d&rsquo;entre eux sont plus ou moins frapp\u00e9s d&rsquo;interdit par l&rsquo;<em>establishment<\/em>. Steve Kornacki, de <em>Salon.com<\/em>, d\u00e9crit (le <a href=\"http:\/\/www.salon.com\/2012\/01\/22\/the_gop's_south_carolina_nightmare\/\" class=\"gen\">22 janvier 2012<\/a>) ce chaos r\u00e9publicain et termine son analyse sur quatre sc\u00e9narios, dont deux classiques et peut-\u00eatre, tr\u00e8s vite, apparaissant improbables (victoire compl\u00e8te de Romney apr\u00e8s r\u00e9tablissement, victoire compl\u00e8te de Gingrich) ; deux autres extr\u00eamement originaux et finalement pas du tout improbables, o\u00f9 Kornacki donne \u00e0 Ron Paul une position d&rsquo;<em>outsider<\/em> loin d&rsquo;\u00eatre n\u00e9gligeable  <\/p>\n<\/p>\n<p><p>\t\u00ab<strong><em>The long slog<\/em><\/strong><em>: Or maybe the Florida result won&rsquo;t prove much at all. The scenario is that South Carolina firmly establishes the GOP contest as a two-man race, with the Tea Party wing of the party largely uniting around Gingrich and everyone else siding with Romney. The two men would then trade wins and losses through a drawn-out, virtually momentum-less primary season  one reminiscent of Hillary\/Obama 2008, Hart\/Mondale 1984 and Reagan\/Ford 1976.<\/em> <strong><em>The wild card in this would be Ron Paul<\/em><\/strong><em>, whose strategy of targeting small and midsize February caucus states and gobbling up their delegates could make him much more relevant to the race than he&rsquo;s been.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<strong><em>The chaos theory<\/em><\/strong><em>: This is the really fun one, and the least likely. But after Saturday night, it at least warrants a mention. The basics: What if Romney suffers such a bad loss in Florida that his campaign melts down completely and elite Republicans lose confidence in his ability to stop Gingrich? If they really are committed to stopping the former speaker, these elites would then be in need of a Plan B, leading to the white knight scenario  a new candidate drafted into the race who could qualify for the late big-state primaries and to prevent Gingrich from racking up the delegates he&rsquo;d need for a first ballot nomination. There are many reasons to sniff at this possibility, not the least of which is that it&rsquo;s unclear if the GOP has any candidate on the sidelines who&rsquo;d be capable of this. But if Mitt can&rsquo;t get the job done in Florida, expect to hear it mentioned a lot.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCette primaire de Caroline du Sud contribue \u00e0 donner le ton d&rsquo;une campagne r\u00e9publicaine compl\u00e8tement exceptionnelle, o\u00f9 la plupart des candidats semblent mener des combats qui portent moins sur la nomination que sur des avatars de leur situation personnelle, cons\u00e9quence d&rsquo;une situation g\u00e9n\u00e9rale incontr\u00f4l\u00e9e. Romney, qui est le seul acceptable par l&rsquo;<em>establishment<\/em> et qui est super-favori, lutte contre un \u00e9trange processus de d\u00e9construction de lui-m\u00eame ; Gingrich n&rsquo;a qu&rsquo;une seule id\u00e9e, qui est de d\u00e9truire Romney, selon les consignes de son principal bailleur de fond ; Santorum \u00e9tait pr\u00eat \u00e0 abandonner d\u00e8s les premiers r\u00e9sultats parce qu&rsquo;il n&rsquo;a aucune organisation \u00e9lectorale, mais il se juge emp\u00each\u00e9 de le faire \u00e0 chaque r\u00e9sultat acceptable, contribuant \u00e0 l&rsquo;\u00e9clatement de l&rsquo;\u00e9lectorat ; Ron Paul lutte pour exister m\u00e9diatiquement, mais juge que son relatif anonymat et toute l&rsquo;attention port\u00e9e \u00e0 la bataille Romney-Gingrich lui permet de r\u00e9pandre ses id\u00e9es et de renforcer sa position sur le long terme. (Pour Paul, c&rsquo;est une th\u00e9orie de la tortue contre les li\u00e8vres, avec une strat\u00e9gie \u00e0 mesure, tr\u00e8s discr\u00e8te mais en th\u00e9orie tr\u00e8s efficace du point de vue du nombre de d\u00e9l\u00e9gu\u00e9s,  cela, montrant combien Paul est un constitutionnaliste, connaissant le fonctionnement du syst\u00e8me de l&rsquo;am\u00e9ricanisme.)<\/p>\n<\/p>\n<p><p>\tCe qui domine tout cela, c&rsquo;est l&rsquo;inqui\u00e9tude de l&rsquo;<em>establishment<\/em> qui, \u00e0 certains moments, se transforme en panique. Qu&rsquo;on puise envisager de faire intervenir <em>out of the blue<\/em> un candidat surprise si Romney n&rsquo;arrive pas \u00e0 r\u00e9affirmer sa position en Floride, alors qu&rsquo;aucune personnalit\u00e9 n&rsquo;existe pour tenir ce r\u00f4le de sauveur,  voil\u00e0 qui  mesure cet \u00e9tat d&rsquo;esprit. C&rsquo;est finalement le principal facteur de d\u00e9stabilisation potentielle de la campagne r\u00e9publicaine. Bien plus encore que les nominations elles-m\u00eames et les caract\u00e8res des candidats, cette campagne r\u00e9publicaine pr\u00e9sente une instabilit\u00e9 sans pr\u00e9c\u00e9dent, qui pourrait conduire \u00e0 des \u00e9v\u00e8nements in\u00e9dits dans le processus de l&rsquo;\u00e9lection pr\u00e9sidentielle. La cause en est que l&rsquo;<em>establishment<\/em> r\u00e9publicain attendait une ma\u00eetrise et un contr\u00f4le de la situation \u00e0 mesure de ce qu&rsquo;il assura au Congr\u00e8s, durant toute la pr\u00e9sidence Obama, m\u00eame lorsqu&rsquo;il \u00e9tait largement minoritaire (jusqu&rsquo;en novembre 2010) ; il n&rsquo;arrive \u00e0 retrouver ni ma\u00eetrise, ni contr\u00f4le, montrant par l\u00e0 que cette domination \u00e9tait le produit non de sa sup\u00e9riorit\u00e9 politicienne et id\u00e9ologique mais de la situation g\u00e9n\u00e9rale de crise du pouvoir washingtonien, et que dans ce processus \u00e9lectoral c&rsquo;est plut\u00f4t cette crise du pouvoir qui s&rsquo;exprime partout. Il est assur\u00e9 que l&rsquo;\u00e9lection US de 2012 ne sera semblable \u00e0 aucune autre. <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 23 janvier 2012 \u00e0 04H46<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La quatri\u00e8me place (13% des voix) de Ron Paul en Caroline du Sud para\u00eetrait une incontestable d\u00e9faite pour lui, alors que certains sondages lui pr\u00e9disaient une troisi\u00e8me place, avec jusqu&rsquo;\u00e0 21%. Les sondages se sont av\u00e9r\u00e9s extr\u00eamement volatiles, avec une tr\u00e8s forte proportion d&rsquo;ind\u00e9cis (40%), qui ont \u00e9t\u00e9 surtout s\u00e9duits par la d\u00e9magogie de bulldozer&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3350,2651,4118,7424,4566,3978,3140,7347,5310,6776,3310,11851,3300],"class_list":["post-74440","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-caroline","tag-du","tag-establishment","tag-floride","tag-gingrich","tag-newt","tag-paul","tag-primaires","tag-republicains","tag-romney","tag-ron","tag-santorum","tag-sud"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74440"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74440\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}