{"id":74471,"date":"2012-02-02T12:33:03","date_gmt":"2012-02-02T12:33:03","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/02\/02\/les-generaux-israeliens-face-a-liran-ou-face-a-netanyahou\/"},"modified":"2012-02-02T12:33:03","modified_gmt":"2012-02-02T12:33:03","slug":"les-generaux-israeliens-face-a-liran-ou-face-a-netanyahou","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/02\/02\/les-generaux-israeliens-face-a-liran-ou-face-a-netanyahou\/","title":{"rendered":"Les g\u00e9n\u00e9raux isra\u00e9liens, face \u00e0 l&rsquo;Iran ou face \u00e0 Netanyahou ?"},"content":{"rendered":"<p><p>C&rsquo;est une occurrence remarquable, ou bien une occurrence qui n&rsquo;en est pas vraiment une, de lire, presque parall\u00e8lement, deux interventions de deux g\u00e9n\u00e9raux isra\u00e9liens (en service ou \u00e0 la retraite active), exposant des positions complexes vis-\u00e0-vis de l&rsquo;Iran,  des positions peut-\u00eatre contradictoires, ou peut-\u00eatre pas du tout, et peut-\u00eatre compl\u00e9mentaires sinon coordonn\u00e9es, et largement divergentes de celles du pouvoir civil, c&rsquo;est-\u00e0-dire de l&rsquo;\u00e9quipe Netanyahou-Barak<\/p>\n<\/p>\n<p><p>\t D&rsquo;une part, il y a une conf\u00e9rence, mercredi 1er f\u00e9vrier, du g\u00e9n\u00e9ral Benny Gantz, commandant en chef des forces arm\u00e9es isra\u00e9liennes. <em>Haaretz<\/em> pr\u00e9sente cette conf\u00e9rence le <a href=\"http:\/\/www.haaretz.com\/misc\/article-print-page\/idf-chief-iran-s-nuclear-program-must-continue-to-be-disrupted-1.410465?trailingPath=2.169%2C2.216%2C2.217%2C\" class=\"gen\">1er f\u00e9vrier 2012<\/a>, tandis qu&rsquo;<em>Antiwar.com<\/em> la r\u00e9percute, avec d&rsquo;autres \u00e9l\u00e9ments critiques, le <a href=\"http:\/\/news.antiwar.com\/2012\/02\/01\/idf-chief-must-continue-counterproductive-iran-postures\/\" class=\"gen\">2 f\u00e9vrier 2012<\/a>. L&rsquo;ensemble rend un son assez ambigu sur la question centrale qui est, lorsqu&rsquo;il s&rsquo;agit d&rsquo;Isra\u00ebl, de savoir si ou quand une attaque de l&rsquo;Iran doit avoir lieu. <em>Antiwar.com<\/em> critique Gantz pour faire l&rsquo;apologie des pressions et des sanctions exerc\u00e9es contre l&rsquo;Iran et estimer qu&rsquo;il faut les poursuivre et les accentuer, alors que, estime le m\u00eame <em>Antiwar.com<\/em>, ces sanctions et ces pressions s&rsquo;av\u00e8rent inefficaces et rapprochent d&rsquo;une possibilit\u00e9 de guerre. (\u00ab<em>Actually, the sanctions and other aggressive postures have been detrimental to regional stability and have failed to deter Iran from its nuclear policy, precisely the opposite of what Grantz claimed.<\/em>\u00bb) Gantz utilise l&rsquo;argument de l&rsquo;annihilation d&rsquo;Isra\u00ebl et assure que l&rsquo;Iran veut produire une arme nucl\u00e9aire ; pour autant, lorsqu&rsquo;il s&rsquo;agit d&rsquo;une attaque contre l&rsquo;Iran, Gantz, comme on dit, botte en touche, avec un argument absolument sp\u00e9cieux et extraordinairement sophistique : c&rsquo;est \u00e0 l&rsquo;Iran de d\u00e9cider, par son comportement, si on doit l&rsquo;attaquer ou pas,  ce comportement \u00e9tant \u00e9valu\u00e9, bien entendu, par ceux qui lanceraient l&rsquo;attaque Le r\u00e9sultat est tout de m\u00eame que Gantz recommande implicitement de surtout ne pas se pr\u00e9cipiter vers une attaque. (Ci-apr\u00e8s, Selon <em>Haaretz<\/em>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Speaking to the Herzliya Conference, Gantz said that Iran&rsquo;s nuclear program is a global problem and a regional problem. He added that Iran could cross the nuclear threshold within a year, if it decides to do so. There is no doubt that Iran is seeking military nuclear capability, Gantz said.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Gantz said that Gulf states are just as concerned about Iran&rsquo;s nuclear program as Israel is. He added, however, that we must not forget one basic thing: Israel is the only country in the world which someone is calling for its destruction and which someone is building the tools to do so. This is something that cannot be ignored.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The world and the region must continue to isolate Iran, Gantz said. It is correct to continue economic pressure and sanctions, from which we are starting to see signs of achievement and progress in terms of what is going on in Iran. It is correct to act and continue to disrupt processes associated with the development of the Iranian nuclear project and to work to enhance oversight over what is happening.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Gantz said that there must be a strong military option, ready to be used if and when it is needed. Gantz estimated that only the Iranian regime will decide at the end of the day if it will give up on a military nuclear capability. But determined and consistent action will bring<\/em> [Iran] <em>to this strategic insight.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t D&rsquo;autre part, il y a une interview (exclusivit\u00e9 de <em>The Independent<\/em>, le <a href=\"http:\/\/www.independent.co.uk\/news\/world\/middle-east\/israels-military-leaders-warn-against-iran-attack-6298102.html\" class=\"gen\">2 f\u00e9vrier 2012<\/a>) d&rsquo;un g\u00e9n\u00e9ral isra\u00e9lien \u00e0 la retraite, mais semble-t-il toujours actif, et qui est, qui plus est, un proche du ministre de la d\u00e9fense Ehud Barak. Il s&rsquo;agit du lieutenant g\u00e9n\u00e9ral Amnon Lipkin-Shahak. Ses d\u00e9clarations sont extr\u00eamement alarmistes, ou dans tous les cas formul\u00e9es et pr\u00e9sent\u00e9es dans ce sens. Pour lui, une attaque contre l&rsquo;Iran aurait des cons\u00e9quences catastrophiques auxquelles les planificateurs ne semblent gu\u00e8re attacher d&rsquo;importance, impliquant les ripostes de l&rsquo;Iran, des interventions du Hamas et du Hezbollah, etc. Implicitement, Lipkin-Shahak laisse entendre que les sanctions contre l&rsquo;Iran commencent \u00e0 avoir de l&rsquo;effet, ce qui est une th\u00e8se largement contredite par tout un courant d&rsquo;analyse contraire, et que toute la hi\u00e9rarchie militaire et de s\u00e9curit\u00e9 isra\u00e9lienne (donc, Gantz compris) est contre une attaque contre l&rsquo;Iran au point o\u00f9 l&rsquo;on en est actuellement. En un sens, Lipkin-Shahak dit donc \u00e0 peu pr\u00e8s la m\u00eame chose que Gantz, mais en insistant sur l&rsquo;aspect catastrophique d&rsquo;une attaque pour l&rsquo;instant, sans nous instruire en quoi une attaque dans un an par exemple, s&rsquo;il s&rsquo;av\u00e9rait que les sanctions ne marchaient pas, serait moins catastrophique. En effet, consid\u00e9rant l&rsquo;\u00e9tat d&rsquo;armement et d&rsquo;alerte maximaux o\u00f9 se trouvent les agresseurs potentiels, essentiellement les USA et Isra\u00ebl, consid\u00e9rant la tendance de crise qui va vers la restriction des budgets militaires dans ces pays (particuli\u00e8rement les USA), consid\u00e9rant enfin les progr\u00e8s d\u00e9fensifs et contre-offensifs r\u00e9alis\u00e9s par les Iraniens depuis 7 ans et qu&rsquo;ils vont continuer \u00e0 d\u00e9velopper, on ne peut dire que le temps travaille dans le sens o\u00f9 une attaque dans un an aurait des effets moins catastrophiques qu&rsquo;aujourd&rsquo;hui. Manifestement, le but de Lipkin-Shahak est de d\u00e9courager l&rsquo;id\u00e9e d&rsquo;une attaque pour l&rsquo;instant sans se pr\u00e9occuper du reste&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Lt-Gen Amnon Lipkin-Shahak, who is close to Defence Minister Ehud Barak, said there had been little analysis of what happens the day after when the Tehran regime and its paramilitary allies retaliate. He warned that an assault may lead to Mahmoud Ahmadinejad benefiting from popular anger against foreign aggression.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>General Lipkin-Shahak stressed that Iran with a nuclear arsenal would be a hugely destabilising factor in the region. But, he said: It is quite clear that much if not all of the IDF [Israeli Defence Forces] leadership do not support military action at this point.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>General Lipkin-Shahak stressed he had no idea what decision the security cabinet would reach. He said the current Chief of General Staff (CGS), Lt-Gen Benny Gantz, and Mr Dagan&rsquo;s successor at Mossad, Tamir Pardo, would offer advice. We have to remember that the CGS and the head of Mossad are there to serve the State of Israel, they are not party political. They will no doubt offer judgement and advice on what is best for Israel, he said. In the past the advice of the head of the IDF and the head of Mossad had led to military action being stopped.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Sanctions on Iran imposed by the EU and the US, including an oil embargo, were stronger than many people had expected, said Lt-Gen Lipkin-Shahak. They are already having some impact on the Iranians on the street, they are worried. They may feel that it is the actions of the<\/em> [<em>Iranian<\/em>] <em>government which has created this situation. So one would think it would be worth seeing what impact the sanctions have before taking the next step.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tD\u00e9sordre, d\u00e9sordre Ainsi Gantz et Lipkin-Shahak disent-ils la m\u00eame chose sous des formes compl\u00e8tement diff\u00e9rentes, selon une tonalit\u00e9 diff\u00e9rente, mais tous les deux dans un seul but : gagner du temps par rapport aux intentions suppos\u00e9es de Netanyahou-Barak de lancer une attaque le plus rapidement possible. Le point de friction est que, pour les uns, les sanctions vont marcher et conduire les Iraniens \u00e0 la capitulation, et que, pour les autres, les sanctions ne marcheront pas et qu&rsquo;il faut donc attaquer tout de suite. <em>The Independent<\/em> ajoute une pr\u00e9cision sur une querelle entre Gentz et Netanyahou sur la nomination du nouveau chef de la force a\u00e9rienne ; Gentz vaut faire nommer un de ses hommes, le g\u00e9n\u00e9ral Eshel, Netanyahou veut faire nommer son ancien conseiller militaire, le g\u00e9n\u00e9ral Locker ; le second, on s&rsquo;en douterait, est suppos\u00e9 plus favorable que le premier \u00e0 une attaque contre l&rsquo;Iran Tous ces militaires isra\u00e9liens, en activit\u00e9 ou \u00e0 la retraite, qui parlent de toutes les fa\u00e7ons et sur des tons bien diff\u00e9rents, mais dans le m\u00eame sens qui est hostile \u00e0 Netanyahou, sont identifi\u00e9s par <em>The Independent<\/em> comme faisant partie du <a href=\"http:\/\/www.dedefensa.org\/article-9_11_en_septembre_2011_04_06_2011.html\" class=\"gen\">groupe<\/a> <a href=\"http:\/\/www.dedefensa.org\/article-les_nouveaux_negationnistes_israeliens_et_la_dissolution_du_monde_09_01_2012.html\" class=\"gen\">Dagan<\/a>.<\/p>\n<\/p>\n<p><p>\tOn ignore exactement qui fait quoi et qui tient les nuds de l&rsquo;affaire en Isra\u00ebl,  et pour cause, apr\u00e8s tout,  mais on commence \u00e0 observer un paysage particuli\u00e8rement chaotique avec ce qui ressemble de plus en plus \u00e0 une fronde organis\u00e9e des militaires et autres chefs des services de s\u00e9curit\u00e9. La phrase de Lipkin-Shahak, dite apr\u00e8s l&rsquo;affirmation que la hi\u00e9rarchie militaire et de s\u00e9curit\u00e9 nationale est contre l&rsquo;attaque, p\u00e8se de tout son poids, comme un avertissement au pouvoir civil isra\u00e9lien : \u00ab<em>In the past the advice of the head of the IDF and the head of Mossad had led to military action being stopped.<\/em>\u00bb Cela ne signifie pas qu&rsquo;on aille vers un basculement du pouvoir en Isra\u00ebl, mais plut\u00f4t qu&rsquo;on continue \u00e0 \u00e9voluer vers un fractionnement du pouvoir qui pourrait conduire \u00e0 la paralysie et \u00e0 l&rsquo;impuissance. Nous avons d\u00e9j\u00e0 envisag\u00e9 que l&rsquo;attaque contre l&rsquo;Iran pourrait bien d\u00e9sormais d\u00e9pendre d&rsquo;une sorte de coup d&rsquo;\u00c9tat de Netanyahou contre sa hi\u00e9rarchie de s\u00e9curit\u00e9 nationale, pour forcer dans une occurrence brutale \u00e0 une attaque, \u00e9ventuellement avec l&rsquo;aide de l&rsquo;une ou l&rsquo;autre provocation ; on est d\u00e9sormais conduit \u00e0 imaginer plus loin encore, que m\u00eame ce type de coup d&rsquo;\u00c9tat interne devienne impossible, si les hi\u00e9rarchies en place acqui\u00e8rent de plus en plus de poids et d&rsquo;audace, et qu&rsquo;on soit conduit au-del\u00e0, justement vers des situations d&rsquo;impuissance et de paralysie. Cela participe de cette \u00e9volution qu&rsquo;on a d\u00e9j\u00e0 d\u00e9crite, vers une <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_tension_figee_dans_le_golfe_20_01_2012.html\" class=\"gen\">tension fig\u00e9e<\/a>, et, dans tous les cas, vers toujours plus de d\u00e9sordre, dans le pays concern\u00e9, dans la crise concern\u00e9e, dans la r\u00e9gion o\u00f9 tout cela se d\u00e9roule et ainsi de suite<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 2 f\u00e9vrier 2012 \u00e0 12H36<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est une occurrence remarquable, ou bien une occurrence qui n&rsquo;en est pas vraiment une, de lire, presque parall\u00e8lement, deux interventions de deux g\u00e9n\u00e9raux isra\u00e9liens (en service ou \u00e0 la retraite active), exposant des positions complexes vis-\u00e0-vis de l&rsquo;Iran, des positions peut-\u00eatre contradictoires, ou peut-\u00eatre pas du tout, et peut-\u00eatre compl\u00e9mentaires sinon coordonn\u00e9es, et largement divergentes&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2870,2625,3889,9636,3356,14601,14610,5633,14611,5675,2790,14612,5733],"class_list":["post-74471","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-attaque","tag-coup","tag-detat","tag-dagan","tag-desordre","tag-figee","tag-gantz","tag-idf","tag-lipkin-shahak","tag-mossad","tag-netanyahou","tag-sanction","tag-tension"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74471"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74471\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}