{"id":74481,"date":"2012-02-07T13:08:15","date_gmt":"2012-02-07T13:08:15","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/02\/07\/le-syndrome-sioniste\/"},"modified":"2012-02-07T13:08:15","modified_gmt":"2012-02-07T13:08:15","slug":"le-syndrome-sioniste","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/02\/07\/le-syndrome-sioniste\/","title":{"rendered":"Le syndrome sioniste"},"content":{"rendered":"<p><h2 class=\"common-article2\">Le syndrome sioniste<\/h2>\n<\/p>\n<p><p>\tLa menace d&rsquo;attaques iraniennes contre des cibles isra\u00e9liennes et\/ou juives dans des villes aussi vari\u00e9es que New York, Toronto, Los Angeles ou Philadelphie serait croissante. Il s&rsquo;agit de la d\u00e9claration du chef de la s\u00e9curit\u00e9 int\u00e9rieure de l&rsquo;entit\u00e9 sioniste \u00e0 une audience restreinte. Il confiait n\u00e9anmoins ses inqui\u00e9tudes \u00e0 une assembl\u00e9e assez ouverte pour que ses appr\u00e9hensions se trouvent livr\u00e9es par la t\u00e9l\u00e9vision ABC News et publi\u00e9es sur  son site internet. La surveillance de sites officiels de repr\u00e9sentation du r\u00e9gime de Tel-Aviv comme celles de lieux culturels ou religieux juifs est s\u00e9rieusement renforc\u00e9e.<\/p>\n<\/p>\n<p><p>\tL&rsquo;alerte est maximale.<\/p>\n<\/p>\n<p><p>\tLes cibles potentielles ne se limitent pas \u00e0 l&rsquo;Am\u00e9rique du Nord, l&rsquo;Europe est <LIEN=http:\/\/abcnews.go.com\/Blotter\/israel-warns-us-jews-iran-strike\/story?id=15506257#.Ty0FGxyUmtB>\u00e9galement concern\u00e9e.<\/p>\n<\/p>\n<p><p>\t\u00catre adepte du sionisme est un labeur harassant et n\u00e9cessite une vigilance sans repos.<\/p>\n<\/p>\n<p><p>\tPour rendre coh\u00e9rente la th\u00e9orie du peuple juif toujours soumis \u00e0 la vindicte g\u00e9n\u00e9ralis\u00e9e, il faut traquer et mettre au jour inlassablement les innombrables complots qui le menacent.<\/p>\n<\/p>\n<p><p>\tSans doute, l&rsquo;appareil de s\u00e9curit\u00e9 sioniste suppose plausibles des r\u00e9torsions imminentes. Il  noublie pas son r\u00f4le r\u00e9cent dans l&rsquo;enl\u00e8vement du chercheur en physique nucl\u00e9aire Shahram Amiri en juin 2009 en Arabie S\u00e9oudite et  dans l&rsquo;assassinat de l&rsquo;ing\u00e9nieur Mostapha Ahmadi Rochan travaillant sur le site de Natanz en janvier 2012. Cette guerre-l\u00e0, il l&rsquo;a men\u00e9e aussi en Irak. Dans les premi\u00e8res semaines de l&rsquo;occupation occidentale d\u00e8s mars 2003, pr\u00e8s de 3000 professeurs d&rsquo;universit\u00e9, m\u00e9decins et ing\u00e9nieurs ont \u00e9t\u00e9 assassin\u00e9s. L&rsquo;assassinat dit cibl\u00e9 est une pratique constante de la machinerie politico-criminelle sioniste et cette technique de guerre est bien ant\u00e9rieure \u00e0 la revanche de Munich. <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Ghassan_Kanafani\" class=\"gen\">Ghassan Kanafani<\/a> \u00e9crivain et journaliste est le fondateur et th\u00e9oricien du Front populaire de lib\u00e9ration de la Palestine d&rsquo;ob\u00e9dience marxiste. Il d\u00e9c\u00e8de \u00e0 Beyrouth le 8 juillet 1972 dans un attentat \u00e0 la voiture pi\u00e9g\u00e9e et n&rsquo;aura \u00e9t\u00e9 qu&rsquo;un \u00e9l\u00e9ment d&rsquo;une longue liste d&rsquo;intellectuels palestiniens ou non liquid\u00e9s avec constance et conscience pour garantir la survie d&rsquo;un greffon exog\u00e8ne de nature incompatible avec le tissu de la r\u00e9gion o\u00f9 il a \u00e9t\u00e9 implant\u00e9. <\/p>\n<\/p>\n<p><p>\tSi l&rsquo;on admet l&rsquo;hypoth\u00e8se qu&rsquo;une collection d&rsquo;individus est dou\u00e9e d&rsquo;une structure psychologique propre, l&rsquo;entit\u00e9 sioniste peut \u00eatre vue anim\u00e9e d&rsquo;une n\u00e9vrose de pers\u00e9cution. Elle est afflig\u00e9e d&rsquo;une souffrance \u00e0 laquelle il ne lui est pas possible de renoncer sous peine de voir s&rsquo;\u00e9vanouir son identit\u00e9. Ce sympt\u00f4me lui est constitutif, il est son mode singulier d&rsquo;existence.<\/p>\n<\/p>\n<p><p>\tLe rejet, traduit dans une gamme qui a vari\u00e9 d&rsquo;une s\u00e9gr\u00e9gation \u00e0 des massacres en masse, dont les Juifs furent victimes en Occident est pass\u00e9 d&rsquo;un affect pur \u00e0 une repr\u00e9sentation. Celle-ci a perdu son lien avec l&rsquo;auteur de l&rsquo;exclusion initiale.<\/p>\n<\/p>\n<p><p>\tLe transfert de l&rsquo;affect n\u00e9gatif se fit sur le Palestinien.<\/p>\n<\/p>\n<p><p>\tD&rsquo;abord parce que le Palestinien est celui qui a \u00e9t\u00e9 rencontr\u00e9 sur le lieu qui aurait d\u00fb \u00eatre vide selon le fallacieux slogan d&rsquo;une terre sans peuple pour un peuple sans terre. Devoir le chasser, le faire dispara\u00eetre a n\u00e9cessit\u00e9 d&rsquo;\u00e9normes  investissements dans une strat\u00e9gie guerri\u00e8re, co\u00fbteuse en hommes et en finances. Mais ruineuse aussi dans des manuvres de  dissimulation symbolique puisque le grand homme politique que fut Golda Meir expliquait que le Peuple Palestinien n&rsquo;existe pas. Faire la guerre pendant plus d&rsquo;un si\u00e8cle, car il faut faire remonter le projet sioniste \u00e0 la date de son premier Congr\u00e8s de 1897 \u00e0 B\u00e2le, \u00e0 un ennemi qui n&rsquo;existe pas confine le seul bellig\u00e9rant \u00e0 un d\u00e9lire chronicis\u00e9.<\/p>\n<\/p>\n<p><p>\tLe Palestinien est aussi le vrai s\u00e9mite.<\/p>\n<\/p>\n<p><p>\tSa langue l&rsquo;a toujours \u00e9t\u00e9. Elle a \u00e9t\u00e9 canan\u00e9enne, h\u00e9breu, aram\u00e9enne, m\u00eal\u00e9e de grec et de  latin et enfin et le plus durablement, soit quatorze si\u00e8cles, arabe. La chute du royaume d&rsquo;Isra\u00ebl a eu lieu vers 724 lors de la conqu\u00eate assyrienne et celle du royaume de Juda vers 586 avec la domination des Babyloniens. Beaucoup plus tard, la dynastie des Hasmon\u00e9ens (167-63 avant l&rsquo;\u00e8re chr\u00e9tienne) a bien juda\u00efs\u00e9 les Idum\u00e9ens quand elle a annex\u00e9 leur territoire mais ces rois se faisaient appeler Basileus et \u00e9taient d\u00e9j\u00e0 passablement hell\u00e9nis\u00e9s. La conqu\u00eate romaine sous Pomp\u00e9e en 63 (avant JC) a latinis\u00e9 la r\u00e9gion pendant sept si\u00e8cles jusqu&rsquo;\u00e0 la conqu\u00eate arabe. Si l&rsquo;on admet que les Isra\u00e9lites furent unifi\u00e9s au XI\u00e8me- X\u00e8me si\u00e8cle avant l&rsquo;\u00e8re chr\u00e9tienne, la domination de la r\u00e9gion de Palestine par un ou deux royaumes juifs n&rsquo;exc\u00e8de pas cinq si\u00e8cles au total. La Palestine a progressivement adopt\u00e9 la langue arabe depuis le trait\u00e9 de Djabia sign\u00e9 en 640 entre Omar Ibn Khatab, deuxi\u00e8me khalife de l&rsquo;Islam et le patriarche Sophronius de J\u00e9rusalem, chef de l&rsquo;\u00c9glise orthodoxe <a href=\"http:\/\/www.mb-soft.com\/believe\/tfc\/monothel.htm\" class=\"gen\">oppos\u00e9 au monoth\u00e9lisme<\/a> pr\u00e9conis\u00e9 par l&rsquo;Empereur romain d&rsquo;Orient.<\/p>\n<\/p>\n<p><p>\tLe Palestinien est le faible que le Juif r\u00e9g\u00e9n\u00e9r\u00e9&rsquo; selon le terme de Herzl ne saurait plus \u00eatre. Pass\u00e9 sous protectorat occidental \u00e0 l&rsquo;issue des accords Sykes-Picot au lendemain du d\u00e9pe\u00e7age de l&rsquo;Empire ottoman, le Palestinien, sans arm\u00e9e nationale, serait un ennemi facile \u00e0 spolier et \u00e9liminer. Il est construit dans l&rsquo;imaginaire offert \u00e0 l&rsquo;\u00e9conomie psychique sioniste comme l&rsquo;antith\u00e8se du Juif. L&rsquo;image du juif faible, humili\u00e9 dans les ghettos et les pogroms s&rsquo;effacerait si elle est projet\u00e9e sur  le Palestinien r\u00e9duit \u00e0 un \u00e9cran mutique pour fantasmes sionistes. Cette op\u00e9ration de transposition de sa part humili\u00e9e \u00e0 l&rsquo;autre qu&rsquo;on humilie \u00e0 son tour pour se nettoyer de son statut de victime est \u00e0 toujours recommencer. La position de la haine-amour du Palestinien son vrai lui-m\u00eame, car il est l&rsquo;authentique s\u00e9mite qui n&rsquo;a jamais c\u00e9d\u00e9 au d\u00e9sir d&rsquo;aller chercher fortune ailleurs, installe une distance impossible \u00e0 tenir. Comment abandonner ce qui lui permet de subsister, le noyau de son \u00eatre est forg\u00e9 de la constellation de traits d\u00e9riv\u00e9s d&rsquo;une mythologie qui le peint comme le pers\u00e9cut\u00e9, contraint \u00e0 l&rsquo;exil par une Rome qui n&rsquo;a jamais effectu\u00e9 de transfert de population. Il n&rsquo;existe de plus nulle trace historique ni textuelle ni arch\u00e9ologique d&rsquo;une diaspora forc\u00e9e apr\u00e8s la destruction du Temple en 70 (p JC) Par un jeu d&rsquo;identification perverse et jamais aboutie, forcer le Palestinien \u00e0 l&rsquo;exil ent\u00e9rine la fausse v\u00e9rit\u00e9 historique de sa disparition de la Palestine \u00e0 l&rsquo;\u00e8re chr\u00e9tienne. (1)<\/p>\n<\/p>\n<p><p>\tSa folie parano\u00efaque condamne l&rsquo;entit\u00e9 \u00e0 devenir la grande manuvri\u00e8re du monde. Elle \u00e9tend par n\u00e9cessit\u00e9 vitale l&rsquo;impact de ses mesures s\u00e9curitaires pr\u00e9ventives aux pays qui la jouxtent et de proche en proche ses cibles se retrouvent dans des cercles concentriques de plus en plus larges. Cette n\u00e9vrose oblige le sujet qui en est atteint \u00e0 int\u00e9grer la moindre maille, le moindre trou dans le r\u00e9seau serr\u00e9 de son interpr\u00e9tation du monde qui l&rsquo;assigne \u00e0 figurer pour toujours le Pers\u00e9cut\u00e9. Le d\u00e9lire sioniste trouve d&rsquo;autant plus consistance dans son implacable argumentaire qu&rsquo;il a s\u00e9cr\u00e9t\u00e9 dans un contexte intellectuel occidental an\u00e9mi\u00e9, fibreux, d\u00e9bilit\u00e9 et st\u00e9rile un outillage dense de notions creuses. D\u00e9mocratie d\u00e9signation abusive d&rsquo;un syst\u00e8me parlementariste gangren\u00e9 par le pouvoir de l&rsquo;argent est le mode d&rsquo;existence sociale imp\u00e9rative applicable partout. Droitsdelhomme, \u00e9tiquette pour ing\u00e9rence et spoliation \u00e9conomique, est l&rsquo;\u00e9thique port\u00e9e en bandouli\u00e8re par les arm\u00e9es d&rsquo;occupation de ce temps nouveau.<\/p>\n<\/p>\n<p><p>\tLe sionisme est m\u00eame la vertu et le Sacr\u00e9 du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tUne de ses colonnes organisatrices.<\/p>\n<\/p>\n<p><p>\tIndiscutable.<\/p>\n<\/p>\n<p><p>\tJusques l\u00e0 son point aveugle.<\/p>\n<\/p>\n<p><p>\tD&rsquo;abord interrog\u00e9 \u00e0 la marge, le spectre d&rsquo;une guerre totale et g\u00e9n\u00e9ralis\u00e9e d&rsquo;une autre intensit\u00e9 que l&rsquo;actuelle avec la  mise en p\u00e9ril d&rsquo;autres cat\u00e9gories que les habituels r\u00e9sidents du Proche-Orient avive le questionnement du bien fond\u00e9 des axiomes de son id\u00e9ologie.<\/p>\n<\/p>\n<p><p>\tL&rsquo;entit\u00e9 sioniste pour rester homog\u00e8ne avec sa d\u00e9finition existentielle a hypertrophi\u00e9 son appareil s\u00e9curitaire pour se confondre avec lui. Isra\u00ebl n&rsquo;est pas un \u00c9tat qui dispose d&rsquo;une arm\u00e9e avec un renseignement et un espionnage tentaculaires mais une arm\u00e9e teint\u00e9e de th\u00e9ocratie qui b\u00e9n\u00e9ficie d&rsquo;un \u00c9tat.<\/p>\n<\/p>\n<p><p>\tPour autant, elle ne peut pr\u00e9tendre exercer une surveillance efficace sur la moindre de ses extensions en dehors de sa base en Palestine occup\u00e9e.<\/p>\n<\/p>\n<p><p>\tElle ne peut plus interdire la diffusion de la technologie  d&rsquo;agression dont elle a gard\u00e9 la supr\u00e9matie dans la r\u00e9gion. L&rsquo;AIEA, les Us(a) et l&rsquo;Europe ne sont que de vulgaires instruments qu&rsquo;elle a soumis \u00e0 ses vues, punir voire an\u00e9antir le moindre de ses comp\u00e9titeurs v\u00e9ritable ou seulement suppos\u00e9.<\/p>\n<\/p>\n<p><p>\tLa destruction de l&rsquo;Iran a \u00e9t\u00e9 programm\u00e9e. Plusieurs options sont \u00e0 l&rsquo;oeuvre.<\/p>\n<\/p>\n<p><p>\tL&rsquo;induction d&rsquo;un changement de r\u00e9gime peine \u00e0 advenir. Les p\u00e9n\u00e9trations d \u00e9l\u00e9ments arm\u00e9s depuis l&rsquo;Irak et l&rsquo;Afghanistan n&rsquo;ont pas manqu\u00e9. Le soutien logistique depuis des sites \u00e9tasuniens lors des \u00e9meutes vertes contestant les r\u00e9sultats des \u00e9lections de juin 2009 a \u00e9t\u00e9 impuissant \u00e0 aboutir.<\/p>\n<\/p>\n<p><p>\tL&rsquo;attaque militaire \u00e9clair est sans cesse remise depuis au moins 2005. Il est \u00e0 remarquer que lorsque  l&rsquo;alli\u00e9 protecteur vassal \u00e9tasunien d&rsquo;Isra\u00ebl tente de mod\u00e9rer les ardeurs belliqueuses sionistes, c&rsquo;est la France depuis 2007  qui donne de la voix.<\/p>\n<\/p>\n<p><p>\tEnfin, l&rsquo;isolement \u00e9conomique fonctionne depuis le fameux accord qui a mis fin \u00e0 l&rsquo;\u00e9pisode des otages de l&rsquo;ambassade des Us(a) \u00e0 T\u00e9h\u00e9ran sign\u00e9 \u00e0 Alger en <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Accords_d%27Alger_(1981)\" class=\"gen\">janvier 1981<\/a>.<\/p>\n<\/p>\n<p><p>\tD\u00e8s 1984, le gouvernement Reagan a \u00e9lu l&rsquo;Iran \u00c9tat exer\u00e7ant du terrorisme comme moyen politique, r\u00e9torsion \u00e0 son aide apport\u00e9e au Hezbollah qui n&rsquo;a vu le jour qu&rsquo;en raison de l&rsquo;invasion isra\u00e9lienne du Liban. En 1986 , l&rsquo;US Arm Export Control Act interdit l&rsquo;exportation d&rsquo;armes \u00e9tasuniennes \u00e0 l&rsquo;Iran.<\/p>\n<\/p>\n<p><p>\tEn 1992, ladministration Bush p\u00e8re renforce le dispositif l\u00e9gislatif punitif contre l&rsquo;Iran en raison d&rsquo;un rapport de la CIA. L&rsquo;Iran consacrerait 2 milliards de dollars par an \u00e0 l&rsquo;acquisition d&rsquo;armes de destruction massive. S&rsquo;en suivra un long chapelet de sanctions \u00e9conomiques reconduites et amplifi\u00e9es sous  Clinton ( l&rsquo;Iran-Libya Sanctions Act de 1996 promue sous la pression de l&rsquo;AIPAC), puis Bush fils avec renouvellement en ao\u00fbt 2001 de l&rsquo;ILSA et l&rsquo; extension de son aire d&rsquo;application qui mettait \u00e0 mal les int\u00e9r\u00eats des compagnies p\u00e9troli\u00e8res \u00e9tasuniennes. Bon nombre d&rsquo;\u00e9tudes ont \u00e9tabli que les industries \u00e9tasuniennes avaient perdu des milliards de dollars en raison des pertes d&rsquo;opportunit\u00e9 induites. Ici aussi, c&rsquo;est L&rsquo;AIPAC qui a impos\u00e9 cette mesure face \u00e0 un Collin Powell qui \u00e9tait demeur\u00e9 sceptique. <\/p>\n<\/p>\n<p><p>\tFin janvier 2012, le ministre des Finances de l&rsquo;entit\u00e9 sioniste a d\u00e9clar\u00e9 \u00e0 Blomberg Businessweek que devait \u00eatre appliqu\u00e9 \u00e0 l&rsquo;Iran <a href=\"http:\/\/www.businessweek.com\/news\/2012-01-26\/-massive-blockade-needed-to-stop-iran-threat-steinitz-says.html\" class=\"gen\">un blocus a\u00e9rien, maritime et terrestre analogue<\/a> \u00e0 celui inflig\u00e9 \u00e0 Cuba depuis 1962.  M. Yuval Steinitz confond Gaza, 1,5 million d&rsquo;humains sans armes \u00e0 mesure de l&rsquo;agression subie sur trois cents km2 \u00e0 sa porte et une R\u00e9publique affaiblie certes par dix ann\u00e9es de guerre livr\u00e9e par l&rsquo;occident par l&rsquo;entremise de Saddam Houssein mais inentam\u00e9e dans sa souverainet\u00e9.<\/p>\n<\/p>\n<p><p>\tLe faisceau des trois lignes d&rsquo;attaque est inop\u00e9rant.<\/p>\n<\/p>\n<p><p>\tL&rsquo;h\u00e9g\u00e9monie isra\u00e9lo-\u00e9tasunienne est devenu improbable en raison de la crise financi\u00e8re qu&rsquo;elle a diss\u00e9min\u00e9e. Elle est responsable de l&rsquo;entr\u00e9e en r\u00e9cession de sa sph\u00e8re d&rsquo;influence directe. Elle se trouve fractur\u00e9e par l&rsquo;expression affirm\u00e9e de puissances moyennes qui d\u00e9ploient une envergure en \u00e9volution rapide.<\/p>\n<\/p>\n<p><p>\tLe veto de la Chine et de la Russie \u00e0 la d\u00e9position de l&rsquo;actuel chef d&rsquo;\u00c9tat de la Syrie en est une bonne indication.<\/p>\n<\/p>\n<p><p>\tLe souvenir cuisant de <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Premi\u00e8re_guerre_de_l'opium\" class=\"gen\">la guerre de l&rsquo;opium<\/a> contre la Chine au 19\u00e8me si\u00e8cle, la descente aux enfers de la Russie \u00e0 la fin des ann\u00e9es 90 en raison de la th\u00e9rapie de choc pr\u00e9conis\u00e9e par les financiers pr\u00e9dateurs \u00e9tasuniens ne sont pas des cat\u00e9gories m\u00e9morielles fictives.<\/p>\n<\/p>\n<p><p>\tLa r\u00e9volution syrienne n&rsquo;est pas une affaire domestique \u00e9tasunienne et le golfe arabo-persique n&rsquo;est pas une mer int\u00e9rieure am\u00e9ricaine.<\/p>\n<\/p>\n<p><p>\tNul traitement ne peut \u00e9teindre le D\u00e9sir absolu du grand Pers\u00e9cut\u00e9.<\/p>\n<\/p>\n<p><p>\tSeule la dissolution de l&rsquo;entit\u00e9 sous l&rsquo;effet de sa propre autolyse en viendra \u00e0 bout.<\/p>\n<\/p>\n<p><p>\tSa d\u00e9gradation immunitaire sous l&rsquo;effet enzymatique de ses \u00e9l\u00e9ments constitutifs va bon train.<\/p>\n<\/p>\n<p>\n<p class=\"signature\"><\/p>\n<\/p>\n<h4>Note<\/h4>\n<p>(1) Le fameux trait\u00e9 qui scellait la reddition de la Palestine en 640 comportait une condition tout \u00e0 fait contraire aux dispositions habituellement prises vis-\u00e0-vis des Gens du Livre. En \u00e9change de la promesse de ne pas trahir le nouveau pouvoir musulman, de payer un imp\u00f4t qui les dispenserait de participer aux efforts de la conqu\u00eate, les Chr\u00e9tiens et les Juifs conservaient leurs biens et b\u00e9n\u00e9ficiaient du statut de prot\u00e9g\u00e9s.   La clause de l&rsquo;impossibilit\u00e9 pour les Juifs de s&rsquo;\u00e9tablit \u00e0 Y&rsquo;lia&rsquo; (J\u00e9rusalem)t est suffisamment exceptionnelle pour avoir \u00e9t\u00e9 soulign\u00e9e par tous les commentateurs. Elle devait r\u00e9pondre \u00e0 une demande de Sophronius et ent\u00e9rinait un statu quo \u00e9tabli depuis longtemps, perp\u00e9tu\u00e9 par les Perses et maintenu par H\u00e9raclius.<\/p>\n<\/p>\n<p><p>\tLe faux souvenir de l&rsquo;exil des Juifs doit remonter \u00e0 cette tradition initi\u00e9e tardivement par Byzance.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le syndrome sioniste La menace d&rsquo;attaques iraniennes contre des cibles isra\u00e9liennes et\/ou juives dans des villes aussi vari\u00e9es que New York, Toronto, Los Angeles ou Philadelphie serait croissante. Il s&rsquo;agit de la d\u00e9claration du chef de la s\u00e9curit\u00e9 int\u00e9rieure de l&rsquo;entit\u00e9 sioniste \u00e0 une audience restreinte. Il confiait n\u00e9anmoins ses inqui\u00e9tudes \u00e0 une assembl\u00e9e assez&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[14626,2773,2774,11983],"class_list":["post-74481","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-benjelloul","tag-iran","tag-israel","tag-sionisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74481"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74481\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}