{"id":74482,"date":"2012-02-08T05:26:24","date_gmt":"2012-02-08T05:26:24","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/02\/08\/les-militaires-egyptiens-contre-washington-pour-leur-sauvegarde\/"},"modified":"2012-02-08T05:26:24","modified_gmt":"2012-02-08T05:26:24","slug":"les-militaires-egyptiens-contre-washington-pour-leur-sauvegarde","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/02\/08\/les-militaires-egyptiens-contre-washington-pour-leur-sauvegarde\/","title":{"rendered":"Les militaires \u00e9gyptiens contre Washington, pour leur sauvegarde ?"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Les militaires \u00e9gyptiens contre Washington, pour leur sauvegarde ?<\/h3>\n<\/p>\n<p><p>\tEst-il si difficile de pr\u00e9voir qu&rsquo;un pouvoir aux abois, press\u00e9 par un m\u00e9contentement populaire tr\u00e8s puissant et qui a entre ses mains divers membres d&rsquo;organisations activistes d\u00e9pendant d&rsquo;une puissance \u00e9trang\u00e8re, dont il est ais\u00e9 de prouver l&rsquo;activisme dans le soutien des manifestations de certains aspects de ce m\u00e9contentement, trouve dans cette occurrence une voie id\u00e9ale pour tenter de d\u00e9samorcer une partie de ce m\u00e9contentement en d\u00e9non\u00e7ant une violation de la souverainet\u00e9 nationale ? Mais les USA ne s&rsquo;int\u00e9ressent pas \u00e0 cette sorte de prolongement, s&rsquo;ils l&rsquo;imaginent seulement.<\/p>\n<\/p>\n<p><p>\tPar cons\u00e9quent, c&rsquo;est une crise en aggravation rapide, qui s&rsquo;installe entre l&rsquo;\u00c9gypte et les USA. En cause, cette vilaine affaire d&rsquo;ONG, dont certaines de nationalit\u00e9 US bien entendu, qui sont d\u00e9sormais la cible privil\u00e9gi\u00e9e des autorit\u00e9s \u00e9gyptiennes, militaires et civiles r\u00e9unies en l&rsquo;occurrence. Les USA ont r\u00e9agi avec violence devant la perspective du jugement de 19 citoyens US impliqu\u00e9s dans des ONG de m\u00eame nationalit\u00e9, avec un discours o\u00f9 Clinton menace de suspendre l&rsquo;aide annuelle de $1,5 milliard \u00e0 l&rsquo;\u00c9gypte. Toujours la m\u00eame fine tactique, avec une l\u00e9g\u00e8ret\u00e9 de souliers clout\u00e9s et de bruits de bottes Les \u00c9gyptiens ont \u00e0 leur tour r\u00e9agi avec violence,  avec une d\u00e9l\u00e9gation militaire qui se trouvait \u00e0 Washington pour parler de cette affaire, annulant brutalement, pour repartir en \u00c9gypte, une rencontre avec des s\u00e9nateurs pompeux et puissants, crime de l\u00e8se-majest\u00e9 pour des visiteurs venus \u00e0 Washington selon un rituel d&rsquo;all\u00e9geance minutieusement conform\u00e9 aux conceptions de l&rsquo;<em>establishment<\/em> am\u00e9ricanistes Ce que r\u00e9sume ainsi <em>Russia Today<\/em> le <a href=\"http:\/\/rt.com\/news\/egypt-us-ngo-scandal-687\/\" class=\"gen\">7 f\u00e9vrier 2012<\/a><\/p>\n<\/p>\n<p><p>\t\u00ab<em>Egyptian military officials who were scheduled to meet with US Senators John McCain, Joseph Lieberman and Carl Levin on Tuesday were reportedly recalled to Egypt, according to Reuters. This comes following Hillary Clinton&rsquo;s warning that a crackdown by Egypt&rsquo;s military rulers on US and local pro-democracy groups could put aid for the Arab nation at risk.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Clinton said the US has worked very hard to put in place financial assistance and other support for the economic and political reforms in Egypt. However, under the current circumstances the aid will have to be reviewed. Problems that arise from this situation that can impact all the rest of our relationship with Egypt, she said. The US Secretary of State spoke to the media in Munich, where she met Egyptian Foreign Minister Mohamed Kamel Amr on the sidelines of an international security conference.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAuparavant, RT avait publi\u00e9 un texte plus g\u00e9n\u00e9ral sur la d\u00e9t\u00e9rioration continuelle des relations entre le pouvoir \u00e9gyptien et les USA, \u00e0 la lumi\u00e8re de cette affaire des ONG. (Le <a href=\"http:\/\/rt.com\/usa\/news\/us-egypt-revolution-trial-617\/\" class=\"gen\">6 f\u00e9vrier 2012<\/a>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The honeymoon between the United States and the new post-Mubarak government in Egypt didn&rsquo;t last long.<\/em> [] <em>The Egyptian government vows that they will bring 19 Americans to trial for allegedly influencing the violent revolutions after last year&rsquo;s ousting of former President Hosni Mubarak with the aid of foreign funds. Nearly 20 Americans have been named in an Egyptian investigation over how foreign pressure help fund unrest by way of international pro-democracy groups. An English-language website out of Egypt published the names of 43 persons being charged on Monday, including 19 Americans.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Washington initially vowed to impose sanctions on Egypt if they follow through with charges against the Americans. On Monday, Cairo ignored warnings and insisted that the 19 Americans will be brought to trial. Egyptian leaders say that during and after the fall of Mubarak, the nearly four dozen people in question used foreign funds to encourage violence, unrest and revolution in Egypt. Among the Americans that are facing trial are the son of US Transportation Secretary Ray LaHood, and Patrick Butler, the vice president of programs at the DC-based International Center for Journalists<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCette affaire est effectivement un feu de discorde qui sera difficile \u00e0 \u00e9teindre, car il y a une \u00e9preuve de force entre deux pouvoirs qui ont \u00e9galement mis leur prestige, ou ce qu&rsquo;il leur reste de prestige dans la balance ; et cette \u00e9preuve de force portant sur une proc\u00e9dure judiciaire, un proc\u00e8s, etc., toutes choses qui prennent du temps et entretiennent constamment la tension ; et, naturellement, cette \u00e9preuve de force avec un aspect public \u00e0 forte pression de communication, qui pousse encore plus \u00e0 l&rsquo;intransigeance les deux partis.<\/p>\n<\/p>\n<p><p>\tLes militaires au pouvoir en \u00c9gypte sont dans une situation extr\u00eamement pr\u00e9caire et, avec le pouvoir civil qu&rsquo;ils ont install\u00e9, ils sont de plus en plus irrit\u00e9s par les menaces US constantes de rupture de l&rsquo;aide annuelle des USA \u00e0 l&rsquo;Egypte. Ils le sont d&rsquo;autant plus qu&rsquo;ils sont persuad\u00e9s que cette menace est un pur moyen de pression et de chantage. Selon leurs sources \u00e0 Washington, et notamment avec le Pentagone, en effet, les militaires \u00e9gyptiens savent que le Pentagone est oppos\u00e9 \u00e0 cette mise en cause de l&rsquo;aide (essentiellement militaire), principal lien d&rsquo;influence et de coop\u00e9ration avec les forces arm\u00e9es \u00e9gyptiennes, qui constituent traditionnellement (constituaient ?) un point d&rsquo;appui puissant de sa pr\u00e9sence dans la r\u00e9gion Mais, dans cette affaire, le d\u00e9partement d&rsquo;Etat joue sa propre carte, avec soutien de la Maison-Blanche, et du Congr\u00e8s bien entendu, et cette ligne dure est pour l&rsquo;instant privil\u00e9gi\u00e9e \u00e0 Washington selon l&rsquo;\u00e9quation des pouvoirs impliqu\u00e9s et les pressions de communication. Certaines indications montrent que le Pentagone, ou dans tous les cas certaines fractions du Pentagone, encouragent secr\u00e8tement cette riposte \u00e9gyptienne dans l&rsquo;espoir qu&rsquo;elle brisera la politique dure du d\u00e9partement d&rsquo;Etat et permettra une d\u00e9tente avec l&rsquo;\u00c9gypte.<\/p>\n<\/p>\n<p><p>\tMais le jeu est d\u00e9licat, et il n&rsquo;est nullement assur\u00e9 que l&rsquo; \u00c9gypte ne se dirige pas, plus radicalement, vers une r\u00e9orientation radicale de sa politique \u00e0 l&rsquo;occasion de cette affaire des ONG. L&rsquo;intransigeance des militaires observ\u00e9e jusqu&rsquo;ici constitue une carte majeure de communication, pour tenter de d\u00e9samorcer le m\u00e9contentement populaire en jouant sur le r\u00e9flexe nationaliste et l&rsquo;exasp\u00e9ration g\u00e9n\u00e9rale des intrusions US dans les affaires int\u00e9rieures du pays. Parall\u00e8lement, le pouvoir militaire ne lutte gu\u00e8re contre les activit\u00e9s clandestines dans le Sina\u00ef (anti-isra\u00e9liennes, naturellement), dont un des effets est un tr\u00e8s r\u00e9cent ni\u00e8me attentat de rupture d&rsquo;une ol\u00e9oduc vers Isra\u00ebl. Enfin, il y a la possibilit\u00e9 pour l&rsquo;instant th\u00e9orique mais favoris\u00e9 \u00e9ventuellement par les \u00e9v\u00e8nements, d&rsquo;un rapprochement avec la Russie, voire de l&rsquo;\u00e9tablissements de liens in\u00e9dits avec la Chine, qui pourraient se faire en m\u00eame temps qu&rsquo;une \u00e9volution de l&rsquo;\u00c9gypte vers une opposition marqu\u00e9e \u00e0 la politique du bloc BAO en Syrie. Il s&rsquo;agit d&rsquo;options classiques d&rsquo;un dispositif de r\u00e9alignement de l&rsquo;\u00c9gypte, qui choisirait alors un r\u00e9alignement d&rsquo;abord international (et non pas r\u00e9gional en premier), par la seule n\u00e9cessit\u00e9 d&rsquo;une ferme prise de distance des USA et d&rsquo;une ouverture vers la tendance des pays du BRICS. A ce moment, le r\u00e9alignement r\u00e9gional suivrait naturellement, avec la confirmation de la politique de m\u00e9fiance vigilante contre Isra\u00ebl et une possible mise en cause du trait\u00e9 de paix de Camp-David, avec une plus grande implication anti-US en Syrie, avec la possibilit\u00e9 d&rsquo;une \u00e9volution vers des relations plus actives avec l&rsquo;Iran. Tout cela mettrait-il \u00e9galement en p\u00e9ril les relations de l&rsquo;Egypte avec l&rsquo;Arabie ? La direction \u00e9gyptienne n&rsquo;en est pas assur\u00e9e, estimant que l&rsquo;Arabie est beaucoup moins contrainte par sa politique activiste qu&rsquo;on ne croit, et qu&rsquo;elle est plus que jamais inqui\u00e8te des rapports et des \u00e9volutions politiques des USA et d&rsquo;Isra\u00ebl, dans les deux crises, syrienne et iranienne.<\/p>\n<\/p>\n<p><p>\tOn voit combien cette affaire des ONG, que Washington traite avec son habituelle arrogance, constitue bien plus qu&rsquo;un vif incident de parcours, combien elle pourrait servir de d\u00e9tonateur pour le pouvoir militaire \u00e9gyptien, pour un prolongement politique important dont il attendrait des dividendes int\u00e9rieurs, lui-m\u00eame dans cette situation pr\u00e9caire qu&rsquo;on sait. En d&rsquo;autres mots, l&rsquo;incident de parcours tomberait \u00e0 point pour justifier un tournant d\u00e9cisif vers une voie plus panarabe selon la vieille formule nass\u00e9rienne mais avec l&rsquo;apport islamiste suppos\u00e9 pacifi\u00e9 comme diff\u00e9rence et contre la tendance lib\u00e9rale pro-occidentaliste en \u00c9gypte, tout cela vu comme une voie d\u00e9cisive pour rompre le cercle vicieux de l&rsquo;impopularit\u00e9 et des troubles int\u00e9rieurs. Le sch\u00e9ma prend en compte \u00e9galement un r\u00e9alignement g\u00e9n\u00e9ral international de la situation avec la crise iranienne, et la potentialit\u00e9 d&rsquo;un activisme nouveau des pays du BRICS, qui constitue une des nouveaut\u00e9s potentielles r\u00e9volutionnaires dans le jeu des influences au Moyen-Orient. L&rsquo;essentiel \u00e0 retenir dans ces hypoth\u00e8ses est le climat dans la direction militaire \u00e9gyptienne : cette direction se trouve de plus en plus aux abois face aux pressions populaires et il lui faut trouver un \u00e9v\u00e8nement politique important qui rompe cette pression en constante augmentation, qui risque de lui faire perdre le contr\u00f4le de la situation. (Et, \u00e0 ce point du raisonnement, nous revenons \u00e0 notre point de d\u00e9part ; car les militaires, qui commencent \u00e0 bien conna\u00eetre les USA dans leur actuelle p\u00e9riode, soup\u00e7onnent des organisations US de continuer \u00e0 jouer un jeu de soutien subversif dans les troubles actuels,  soup\u00e7on qu&rsquo;on ne serait nullement surpris de voir justifi\u00e9.)<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis ebn ligne le 8 f\u00e9vrier 2012 \u00e0 05H16<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les militaires \u00e9gyptiens contre Washington, pour leur sauvegarde ? Est-il si difficile de pr\u00e9voir qu&rsquo;un pouvoir aux abois, press\u00e9 par un m\u00e9contentement populaire tr\u00e8s puissant et qui a entre ses mains divers membres d&rsquo;organisations activistes d\u00e9pendant d&rsquo;une puissance \u00e9trang\u00e8re, dont il est ais\u00e9 de prouver l&rsquo;activisme dans le soutien des manifestations de certains aspects de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[5110,3259,11035,3977,9550,2773,2774,3164,3538,2937,7718,9394,2730,2746,3867],"class_list":["post-74482","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-aide","tag-arabie","tag-brics","tag-chine","tag-egypte","tag-iran","tag-israel","tag-militaire","tag-militaires","tag-nationale","tag-ong","tag-realignement","tag-russie","tag-souverainete","tag-syrie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74482"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74482\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}