{"id":74498,"date":"2012-02-14T07:59:44","date_gmt":"2012-02-14T07:59:44","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/02\/14\/notes-sur-1982-revisite-des-malouines-a-la-crise-haute\/"},"modified":"2012-02-14T07:59:44","modified_gmt":"2012-02-14T07:59:44","slug":"notes-sur-1982-revisite-des-malouines-a-la-crise-haute","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/02\/14\/notes-sur-1982-revisite-des-malouines-a-la-crise-haute\/","title":{"rendered":"Notes sur 1982 revisit\u00e9, des Malouines \u00e0 la crise haute"},"content":{"rendered":"<p><h2 class=\"common-article\">Notes sur 1982 revisit\u00e9, des Malouines \u00e0 la crise haute<\/h2>\n<\/p>\n<p><p>\tCeux qui, vieillis sous le harnais, v\u00e9curent la guerre des Malouines en 1982, savent que ce cas fut l&rsquo;un des points de crise les plus critiques des relations sp\u00e9ciales USA-UK. Pendant quelques semaines, les USA, sous l&rsquo;influence de l&rsquo;ambassadrice US \u00e0 l&rsquo;ONU Jeane Kirkpatrick et du secr\u00e9taire \u00e0 la d\u00e9fense Weinberger, prirent une position qui n&rsquo;\u00e9tait pas loin de favoriser l&rsquo;Argentine contre le Royaume-Uni au nom de la solidarit\u00e9 transam\u00e9ricaine et pour favoriser l&rsquo;influence US sur un continent (l&rsquo;Am\u00e9rique du Sud) alors secou\u00e9 par diverses r\u00e9bellions et gu\u00e9rillas marxistes et castristes.<\/p>\n<\/p>\n<p><p>\tFinalement, la mise fut sauv\u00e9e par le secr\u00e9taire d&rsquo;Etat Haig qui, au nom de la solidarit\u00e9 transatlantique face \u00e0 l&rsquo;URSS (les relations avec l&rsquo;URSS \u00e9tait alors dans un \u00e9tat de tension maximale avec l&rsquo;affaire des <em>euromissiles<\/em>), convainquit l&rsquo;administration Reagan d&rsquo;observer une position d&rsquo;apparente neutralit\u00e9 et d&rsquo;aider militairement en sous-main le Royaume-Uni, avec un soutien de surveillance, de reconnaissance, et de logistique de ravitaillement en vol. L&rsquo;affaire devint alors le triomphe de Margaret Thatcher, qui assura, par la gloire de la victoire britannique ressuscitant en version moderniste la gloire de l&rsquo;Empire, une popularit\u00e9 qui la maintint au pouvoir jusqu&rsquo;en 1990. L&rsquo;humiliation encourue par l&rsquo;Argentine, malgr\u00e9 le formidable courage de ses aviateurs et les pertes s\u00e9v\u00e8res inflig\u00e9es \u00e0 la Royal Navy, entra\u00eena la chute des g\u00e9n\u00e9raux argentins.<\/p>\n<h3>Les relations sp\u00e9ciales \u00e0 l&rsquo;\u00e9preuve<\/h3>\n<\/p>\n<p><p>\tAujourd&rsquo;hui, trente ans plus tard, la crise des Malouines menace de se r\u00e9veiller. Cette fois, il n&rsquo;est pas s\u00fbr du tout que les USA ne prendront pas, jusqu&rsquo;au bout, l&rsquo;attitude qu&rsquo;ils eurent au d\u00e9but de la premi\u00e8re crise de 1982.<\/p>\n<\/p>\n<p><p>\tCette attitude consiste tactiquement dans une neutralit\u00e9 th\u00e9orique revenant \u00e0 dire que l&rsquo;Argentine et le Royaume-Uni doivent n\u00e9gocier sur la question de la souverainet\u00e9 sur l&rsquo;archipel. Concr\u00e8tement, cela revient \u00e0 prendre le parti argentin. Une telle n\u00e9gociation dans le cadre de l&rsquo;ONU,  toujours refus\u00e9e par le Royaume-Uni,  conduirait \u00e0 une probable victoire argentine puisqu&rsquo;elle se d\u00e9roulerait dans le cadre d&rsquo;une liste de 16 territoires jug\u00e9s encore colonis\u00e9s et attendant leur lib\u00e9ration, o\u00f9 se trouve class\u00e9 l&rsquo;archipel des Malouines, ainsi consid\u00e9r\u00e9 comme colonis\u00e9 par les Britanniques et donc <em>de facto<\/em> de souverainet\u00e9 argentine Cette prise de position US est ainsi rapport\u00e9e par <em>PressTV.com<\/em> le <a href=\"http:\/\/www.presstv.ir\/detail\/226112.html\" class=\"gen\">11 f\u00e9vrier 2012<\/a>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Argentina has also received signals from the US that suggest Washington is willing to see the dispute resolved through legal channels that would see London lose the argument to Buenos Aires.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>The US Acting Assistant Secretary for Western Hemisphere Affairs Roberta Jacobson, who is visiting South America, treated Argentina and Britain as equals in the Malvinas dispute who should settle the issue through talks. This is a problem between two of our partners. We do not want to change our position  We prefer that both countries negotiate a diplomatic solution in that matter, Jacobson said. Her remarks were echoed by State Department spokesman Victoria Nuland who said we are encouraging Argentina and the UK to work this out peacefully, to work it out through negotiations.<\/em> [] <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Therefore Washington&rsquo;s call is directly aimed at London, implicitly telling them that they are alone in this, and that also probably applies to a vote in the Security Council.<\/em> [] <em>As none of the other veto-wielding members of the UN Security Council has cared to even suggest backing for Britain&rsquo;s right to continue to occupy the islands, London would have a hard time justifying a veto against a lawful argument by Buenos Aires<\/em>\u00bb <\/p>\n<h3>Militarisation britannique ?<\/h3>\n<\/p>\n<p><p>\tLes Argentins ont manuvr\u00e9 avec une certaine maestria pour dramatiser la situation et ainsi justifier leur recours \u00e0 l&rsquo;ONU qui risque de mettre les Britanniques dans une situation d\u00e9licate. D\u00e8s qu&rsquo;il a \u00e9t\u00e9 \u00e0 nouveau question des revendications argentines sur les Malouines, les Britanniques ont agi pr\u00e9ventivement parce qu&rsquo;ils <a href=\"http:\/\/www.dedefensa.org\/article-l_ombre_symbolique_des_malouines-1982_30_01_2012.html\" class=\"gen\">n&rsquo;ont plus<\/a> les moyens d&rsquo;agir dans un cadre normal, par simple riposte, comme en 1982. Ils ont envoy\u00e9 sur place une unit\u00e9 navale (une fr\u00e9gate) de grandes capacit\u00e9s. Normalement, cette initiative est pr\u00e9sent\u00e9e comme une rotation normale, cette unit\u00e9 devant remplacer une autre sur place, mais de type plus ancien.<\/p>\n<\/p>\n<p><p>\tIl est aussi question d&rsquo;un sous-marin classe <em>Trafalgar<\/em> (sous-marin d&rsquo;attaque normal), mais aussi, plus r\u00e9cemment (voir <em>PressTV.com<\/em> du <a href=\"http:\/\/rt.com\/news\/falkland-islands-nuclear-row-077\/\" class=\"gen\">11 f\u00e9vrier 2011<\/a>), d&rsquo;un SLBM lanceur d&rsquo;engins strat\u00e9giques \u00e0 t\u00eates nucl\u00e9aire, un sous-marin de la classe <em>Vanguard<\/em>. Cela \u00e9toffe largement la plainte de l&rsquo;Argentine \u00e0 l&rsquo;ONU contre le Royaume-Uni, pour militarisation de l&rsquo;Atlantique Sud, m\u00eame si le cas reste discutable par certains aspects. L&rsquo;ambassadeur UK \u00e0 l&rsquo;ONU riposte que cette accusation, surtout concernant le sous-marin classe <em>Vanguard<\/em> \u00e0 capacit\u00e9s nucl\u00e9aires, est manifestement absurde.<\/p>\n<\/p>\n<p><p>\tPeut-\u00eatre, du point de vue militaire et op\u00e9rationnel, mais du point de vue de la communication l&rsquo;affaire se tient. On pourrait m\u00eame consid\u00e9rer qu&rsquo;il s&rsquo;est agi d&rsquo;un pi\u00e8ge dans lequel les Britanniques, trop faibles pour prendre des risques, ont \u00e9t\u00e9 oblig\u00e9s de donner t\u00eate baiss\u00e9e. Ils sont aujourd&rsquo;hui les fauteurs de guerre, ceux qui font monter la tension.<\/p>\n<h3>La gloire nationale et le p\u00e9trole<\/h3>\n<\/p>\n<p><p>\tPourquoi les Britanniques tiennent-ils tant aux Malouines ? Parce qu&rsquo;ils se sont battus victorieusement et glorieusement pour conserver l&rsquo;archipel, et parce qu&rsquo;ils estiment \u00eatre dans leur droit de puissance navale dans cette affaire. La gloire nationale, certes, est un argument psychologique fondamental. Dans cette p\u00e9riode de discr\u00e9dit des directions politiques jusqu&rsquo;\u00e0 leur dissolution, dans cette p\u00e9riode d&rsquo;effondrement du Syst\u00e8me et de fureur populaire contre les directions politiques, une telle posture patriotique et de puissance est un argument fondamental de communication. On en a si peu qu&rsquo;on y tient.<\/p>\n<\/p>\n<p><p>\tIl y a aussi une riche position de p\u00eache, pour les Britanniques, dans la zone de l&rsquo;archipel, d&rsquo;ailleurs dans des conditions d\u00e9nonc\u00e9es par les Argentins. Enfin, et surtout diront les experts et les comptables, il y a le mirage ou le miracle p\u00e9trolier, qui, pour le Royaume-Uni, fait miroiter un retour de quelque chose qui ressemblerait \u00e0 la manne du p\u00e9trole de la Mer du Nord. Selon le <em>Daily Telegraph<\/em> du <a href=\"http:\/\/www.telegraph.co.uk\/finance\/newsbysector\/energy\/oilandgas\/9076530\/Falklands-oilfields-could-yield-176bn-tax-windfall.html\" class=\"gen\">11 f\u00e9vrier 2012<\/a>, un rapport annonce des perspectives fabuleuses (\u00ab<em>The Falkland Islands stand to benefit from an enormous $176bn (\u00a3111.7bn) tax windfall from oil and gas exploration, according to a major new report.<\/em>\u00bb) Le rapport n&rsquo;est pas l\u00e0 pour apaiser les tensions, les Argentins estimant alors que cette manne p\u00e9troli\u00e8re leur revient<\/p>\n<\/p>\n<p><h3>Cristina et le fant\u00f4me d&rsquo;Evita<\/h3>\n<\/p>\n<p><p>\tDe l&rsquo;autre c\u00f4t\u00e9, du c\u00f4t\u00e9 argentin, il y a la pr\u00e9sidente, il y a Cristina Fernandez de Kirchner, que la presse britannique a prestement baptis\u00e9e (r\u00e9f\u00e9rence Thatcher) \u00ab<em>The iron lady of the Malvinas<\/em> \u00bb (<em>The Independent<\/em> du <a href=\"http:\/\/www.independent.co.uk\/news\/people\/profiles\/cristina-fernandez-de-kirchner-the-iron-lady-of-the-malvinas-6715348.html\" class=\"gen\">11 f\u00e9vrier 2012<\/a>). D&rsquo;accord, il est question de Thatcher (la dame de fer), mais en beaucoup plus attractive,  Cristina \u00e9tant \u00e0 peu pr\u00e8s aussi sexy que Maggie ne l&rsquo;\u00e9tait pas du tout.<\/p>\n<\/p>\n<p><p>\tMais Cristina, femme de t\u00eate m\u00eame si de t\u00eate agr\u00e9able, est aussi une personnalit\u00e9 de poids. Succ\u00e9dant \u00e0 la pr\u00e9sidence \u00e0 son mari Nestor en 2007 sur l&rsquo;insistance de celui-ci, qui aurait pu pourtant briguer un second mandat, elle a subi en 2010 un terrible choc avec la mort du m\u00eame Nestor Kirchner (depuis ce deuil, elle ne s&rsquo;habille plus que de noir). Cela a donn\u00e9 \u00e0 la Cristina sexy une dimension tragique qui, \u00e9ventuellement, la rapprocherait par sa propre voie de l&rsquo;h\u00e9ro\u00efne du pays, Evita (l&rsquo;h\u00e9ro\u00efque et exceptionnelle femme du m\u00e9diocre Peron). <\/p>\n<\/p>\n<p><p>\tComme elle (Evita), bien entendu, Cristina est de tradition p\u00e9roniste, et son surnom est devenu Botox Evita (Evita <em>relift\u00e9e<\/em> ?), apr\u00e8s le  <em>Bimbo<\/em> platement hollywoodien dont on l&rsquo;avait affubl\u00e9e ; Cristina devenue tragique montrant qu&rsquo;elle a quelque chose de la femme de fer (Maggie), sous une enveloppe plus agr\u00e9able. Il existe ainsi une veine de la femme argentine, h\u00e9ro\u00efque et politique. Celle-l\u00e0, Cristina, pourrait s&rsquo;arranger des Malouines pour soigner sa l\u00e9gende, et parce que, apr\u00e8s tout, c&rsquo;est une grande cause, parce que c&rsquo;est une juste cause du point de vue argentin.<\/p>\n<h3><em>Don&rsquo;t cry for Cristina, Argentina..<\/em><\/h3>\n<\/p>\n<p><p>\tUne telle personnalit\u00e9 attire les portraits o\u00f9 se m\u00e9langent une ironie dissimul\u00e9e, une raillerie de bon aloi, et une certaine admiration en m\u00eame temps. David Usborne, de <em>The Independent<\/em>, r\u00e9f\u00e9renc\u00e9 plus haut, en trace un, en fid\u00e8le sujet de Sa Majest\u00e9 qui sait d\u00e9sormais que Cristina, trait\u00e9e de pute par un site d&rsquo;information des Falklands, est un nouvel obstacle sur la route des Malouines, <em>alias<\/em> Malvinas..<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Don&rsquo;t cry for Cristina Fernandez de Kirchner because a Falkland Islands news site, the Penguin News, called her a bitch this week. Hearing of the slight in her apartments at the Casa Rosada palace in Buenos Aires, she surely allowed herself a sly smile. A wily politician and populist to her core, she knows nothing stirs sympathy at home more than an insult from abroad, especially one with a Union flag on it.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em> Insults and crises, meanwhile, are not the worst Ms Fernandez has suffered. After Christmas, the Casa Rosada announced to a shocked nation that she had thyroid cancer. The gland was removed last month but then the doctors said it hadn&rsquo;t been cancer after all. (The Cristina haters say the scar on her neck is really from plastic surgery.) Her biggest blow, however, was the sudden death in October 2010 of Nestor from a heart attack. She was personally devastated and their game of keeping the presidency in the family was over. Yet, his death bought her public sympathy and appears to have liberated her politically.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>She profited from Nestor&rsquo;s death because she was freed from his shadow and was able to begin operating politically on her own,\u00a0\u00bb notes Carolina Barros, editor-in-chief of the Buenos Aires Herald. Among her first steps: bringing into her circle members of a younger Peronist faction of 30- to 40-year-olds headed by her son, Maximo Kirchner. Her grief has allowed Ms Fernandez to tap into Argentina&rsquo;s sense of drama. She is a very good stage woman, says Ms Barros, who notes that the President is still wearing black 15 months after her husband&rsquo;s death and means to sanctify him in the minds of the population. Argentina is always trying to feel or follow a myth. We had Eva Peron and Juan Peron, and now she wants to add Nestor to that same list, she explains.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The new Falklands dispute is about theatre, too. Locals in Buenos Aires say the only thing she would mind more than being called a bitch is being likened to Margaret Thatcher, whose unwelcome presence has returned in the shape of Meryl Streep in The Iron Lady. The film opened in Argentina last month.<\/em><\/p>\n<\/p>\n<p><h3>De l&rsquo;Argentine \u00e0 l&rsquo;Am\u00e9rique du Sud<\/h3>\n<\/p>\n<p><p>\tIl y a une vindicte personnelle. N\u00e9e en Patagonie, comme son mari Hector, Cristina voue une rancune extr\u00eame aux Britanniques \u00e0 cause des Malouines, qu&rsquo;elle estime \u00eatre des terres absolument li\u00e9es \u00e0 cette province d\u00e9sol\u00e9e de l&rsquo;Argentine. Cet aspect personnel est un point important de l&rsquo;\u00e9quation de cette crise, d\u00e9marr\u00e9e d&rsquo;une fa\u00e7on bien incertaine et qui prend d\u00e9sormais des dimensions respectables.<\/p>\n<\/p>\n<p><p>\tLes analystes habituels, pleins de raison et de <em>realpolitik<\/em>, jugent que cette affaire, voulue par Cristina, lui permet de d\u00e9tourner l&rsquo;attention de ses probl\u00e8mes int\u00e9rieurs. Peut-\u00eatre, et elle ne serait pas la premi\u00e8re \u00e0 agir de la sorte. Il reste qu&rsquo;elle consid\u00e8re que les Malouines sont effectivement une juste cause qui peut nourrir une communication efficace sinon h\u00e9ro\u00efque, et qu&rsquo;elle y voit, \u00e0 la diff\u00e9rence de 1982, une bien meilleure position pour son pays.<\/p>\n<\/p>\n<p><p>\tIl y a alors une dimension int\u00e9ressante qui appara\u00eet, qui est celle d&rsquo;un affrontement de son pays, de l&rsquo;Am\u00e9rique du Sud, avec les puissances coloniales du Nord, dans un continent qui a eu tant \u00e0 souffrir \u00e0 cet \u00e9gard. On observera d\u00e9j\u00e0 que c&rsquo;est retrouver par une autre voie, par une autre orientation g\u00e9ographique que celles qu&rsquo;on suit habituellement, le conflit entre le bloc BAO et le reste, entre le Syst\u00e8me et ceux qui lui sont r\u00e9ticents. (Qu&rsquo;il y ait discorde \u00e0 l&rsquo;int\u00e9rieur du bloc BAO, particuli\u00e8rement entre USA et UK, c&rsquo;est une cerise d\u00e9licieuse sur le g\u00e2teau, qui ajoute au go\u00fbt)<\/p>\n<\/p>\n<p><p>\tLe <em>Guardian<\/em> du <a href=\"http:\/\/www.guardian.co.uk\/world\/2012\/feb\/10\/why-fernandez-reopening-falklands-wounds\" class=\"gen\">10 f\u00e9vrier 2012<\/a> observe \u00e0 cet \u00e9gard<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Fern\u00e1ndez has also been emboldened by the zeitgeist: South America has discovered it can, perhaps for the first time in its history, safely challenge the old colonial powers. A \u00ab\u00a0pink tide\u00a0\u00bb of nationalistic leftwing governments senses the region&rsquo;s time has come after centuries of marginalisation. China&rsquo;s rapid rise as a trading partner has further weakened European leverage. South America doesn&rsquo;t have the respect it used to have for Europe. It feels it is on top now and is flexing its new muscles, said a senior European diplomat.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Brazil&rsquo;s Luiz In\u00e1cio Lula da Silva made a global splash railing against western bankers, Venezuela&rsquo;s Hugo Ch\u00e1vez did the same railing against western imperialism and the Falklands gave Fern\u00e1ndez her own cause, said Romer. She is using Malvinas to expand her visibility on the international arena.<\/em>\u00bb<\/p>\n<h3>Les tristes restes de l&rsquo;Empire<\/h3>\n<\/p>\n<p><p>\tSi pi\u00e8ge il y a eu pour le Royaume-Uni (voir plus haut), il a march\u00e9 parce que les Britanniques ne sont plus que l&rsquo;ombre de leur ombre,  l&rsquo;ombre de l&rsquo;ombre des USA, puisque les USA ne sont plus eux-m\u00eames que l&rsquo;ombre d&rsquo;eux-m\u00eames ; mais, justement, l&rsquo;affaire se fera sans l&rsquo;ombre d&rsquo;un geste des USA en leur faveur. Les Britanniques sont dans un pi\u00e8ge qui peut devenir m\u00e9chant et ils sont <strong>seuls<\/strong>.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est moins une guerre classique qui est en jeu qu&rsquo;une guerre de communication, avec \u00e0 la clef, l&rsquo;humiliation, l&rsquo;horrible occurrence de perdre la face, face \u00e0 un pays dont on h\u00e9site \u00e0 peine \u00e0 dire, \u00e0 Londres, qu&rsquo;il est barbare et peupl\u00e9 de m\u00e9t\u00e8ques gomin\u00e9s Quelle trag\u00e9die pour l&rsquo;ancien empire qu&rsquo;est le Royaume-Uni, qui fonde les trois-quarts et plus des certitudes politiques de son action diplomatique sur la gloire de son pass\u00e9 imp\u00e9rial transpos\u00e9e en termes postmodernistes, d&rsquo;une part du <em>moral high ground<\/em> type-d\u00e9mocratie universelle, d&rsquo;autre part d&rsquo;une pens\u00e9e politique qui pr\u00e9tend \u00eatre \u00e0 la fois l&rsquo;inspiratrice et la donneuse de le\u00e7on du reste du monde plong\u00e9 dans la temp\u00eate dont elle est elle-m\u00eame la source. Pour la psychologie des dirigeants britanniques, les Malouines sont le seul lien les reliant \u00e0 un pass\u00e9 qui est, lui-m\u00eame, la seule justification du statut abusif auquel pr\u00e9tend aujourd&rsquo;hui ce pays en d\u00e9cr\u00e9pitude, et qui est soutenu par la constante r\u00e9f\u00e9rence aux relations sp\u00e9ciales avec les USA.<\/p>\n<\/p>\n<p><p>\tJustement, l\u00e0 est le b\u00e2t qui blesse. L&rsquo;Am\u00e9rique du Sud, comme l&rsquo;ont v\u00e9rifi\u00e9 les Britanniques en 1982, est le seul domaine du monde o\u00f9 ils peuvent retrouver les USA compl\u00e8tement contre eux, dans certaines circonstances. Leur cousinage avec les USA se trouve brutalement concurrenc\u00e9 par une fraternit\u00e9 transam\u00e9ricaine qui reste un des fruits les plus copieux,  du moins le croit-on \u00e0 Washington,  du capitalisme yankee, et le domaine r\u00e9serv\u00e9 de l&rsquo;antique mais toujours \u00e0 propos doctrine Monroe.<\/p>\n<\/p>\n<p><p>\tOn ne parle pas ici de pseudo sentiments ni de liens soi-disant affectifs, mais bien d&rsquo;investissements \u00e0 tirer des pseudo sentiments et des liens soi-disant affectifs. A cet \u00e9gard, Washington a gard\u00e9 des r\u00e9flexes d&rsquo;antan, qui lui font parfois, et peut-\u00eatre souvent, pr\u00e9f\u00e9rer son arri\u00e8re-cour latino-am\u00e9ricaine \u00e0 la basse-cour transatlantique. La crainte qu&rsquo;Obama, qui ne les aiment gu\u00e8re, ne l\u00e8ve pas le petit doigt pour eux, pousse les Britanniques \u00e0 agir vite,  peut-\u00eatre trop vite,  pour tenter d&rsquo;impressionner l&rsquo;Argentine et \u00e9viter une sorte d&rsquo;\u00e9preuve de force \u00e0 l&rsquo;ONU. Ce peut \u00eatre le r\u00e9sultat inverse, et les Britanniques se retrouveraient dans cette position qu&rsquo;ils ha\u00efssent d&rsquo;accus\u00e9 solitaire.<\/p>\n<\/p>\n<p><p>\t C&rsquo;est-\u00e0-dire que l&rsquo;affaire peut s&rsquo;envenimer d&rsquo;une fa\u00e7on int\u00e9ressante. C&rsquo;est alors qu&rsquo;il importe d&rsquo;envisager ce que seraient ses prolongements.<\/p>\n<\/p>\n<p><h3>Relations antagonistes entre Malouines-II et le bloc BAO<\/h3>\n<\/p>\n<p><p>\tLa crise en formation autour des Malouines, ou Malouines-II, appara\u00eet d&rsquo;abord comme une crise excentr\u00e9e, voire marginale, par rapport \u00e0 l&rsquo;ensemble crisique du cur du monde (Moyen-Orient, de la Libye \u00e0 la Syrie, \u00e0 l&rsquo;Iran, \u00e0 l&rsquo;Afghanistan, autour de l&rsquo;arc de crise ou du croissant de crises, etc.). Mais il faut y voir de plus pr\u00e8s, \u00e0 la lumi\u00e8re de ce que nous nommons le ph\u00e9nom\u00e8ne de cha\u00eene crisique transversale, clef op\u00e9rationnelle de notre concept de crise haute (voir le <a href=\"http:\/\/www.dedefensa.org\/article-la_crise_haute_03_02_2012.html\" class=\"gen\">3 f\u00e9vrier 2012<\/a> et <em>dde.crisis<\/em> du <a href=\"http:\/\/www.edde.eu\/publication-ddecrisis_du_10_fevrier_2012.html\" class=\"gen\">10 f\u00e9vrier 2012<\/a>)<\/p>\n<\/p>\n<p><p>\tLa crise des Malouines en formation est g\u00e9opolitiquement marginale, par sa g\u00e9ographie, mais elle est autre si on la prend du point de vue du syst\u00e8me de la communication. Ce dernier cas est l&rsquo;essentiel de l&rsquo;observation m\u00e9thodologique du ph\u00e9nom\u00e8ne puisque l&rsquo;on sait que, <a href=\"http:\/\/www.dedefensa.org\/article-politique_d_epoque_l_ere_psychopolitique_25_12_2006.html\" class=\"gen\">pour notre compte<\/a> <a href=\"http:\/\/www.dedefensa.org\/article-la_revolution_ou_comment_la_faire__10_11_2010.html\" class=\"gen\">certainement<\/a>, le syst\u00e8me de la communication a rel\u00e9gu\u00e9 la g\u00e9opolitique aux marges de l&rsquo;expression de la puissance, et exprime lui-m\u00eame le cur de la puissance. (C&rsquo;est l\u00e0 une grande diff\u00e9rence d&rsquo;avec la premi\u00e8re crise des Malouines, en 1982, quand la g\u00e9opolitique jouait encore un r\u00f4le essentiel.) De ce point de vue, la crise marginale devient potentiellement une crise de revers du plus int\u00e9ressant effet.<\/p>\n<\/p>\n<p><p>\t Nous y sommes d\u00e9j\u00e0 avec l&rsquo;analyse imm\u00e9diatement d\u00e9velopp\u00e9e selon laquelle cette crise impliquant l&rsquo;Argentine, pourrait impliquer, impliquerait en fait l&rsquo;Am\u00e9rique du Sud, et l&rsquo;Am\u00e9rique du Sud contre une puissance du bloc BAO, et contre le bloc BAO par cons\u00e9quent. (Pas les USA ? Certes pas dans un premier temps, comme on l&rsquo;a vu ; mais un tel r\u00e9flexe de solidarit\u00e9 continentale de l&rsquo;Am\u00e9rique du Sud, s&rsquo;il a lieu, conduirait les USA \u00e0 r\u00e9int\u00e9grer la logique du bloc BAO sans pour autant aider le Royaume-Uni sur le fait m\u00eame.) Le Chili a d\u00e9j\u00e0 annonc\u00e9 qu&rsquo;il soutenait l&rsquo;Argentine ; si l&rsquo;affaire se d\u00e9veloppe \u00e0 l&rsquo;ONU, des dirigeants radicaux comme Chavez et Morales suivraient, et un pays comme le Br\u00e9sil qui s&rsquo;estime investi du <em>leadership<\/em> continental ne devrait pas \u00e9carter une prise de position confortant sa position \u00e9rig\u00e9e en partie sur la d\u00e9nonciation des puissances du Nord dans l&rsquo;actuelle situation de crise g\u00e9n\u00e9rale du Syst\u00e8me. Une m\u00e9canique de solidarit\u00e9 continentale serait enclench\u00e9e. La crise marginale prendrait de l&rsquo;\u00e9paisseur dans sa transformation en crise de revers.<\/p>\n<\/p>\n<p><p>\t Dans ce cas, le Royaume-Uni, confront\u00e9, lui, au fant\u00f4me de Maggy Thatcher et \u00e0 la n\u00e9cessit\u00e9 de tenter de s&rsquo;en montrer digne, se verrait d\u00e9tourn\u00e9 du centre crisique (Moyen-Orient et le reste) par divers biais, y compris celui, \u00e9ventuellement, de ses moyens militaires n\u00e9cessaires, au moins pour faire pression sur l&rsquo;Argentine. Cela impliquerait une pression amoindrie du bloc BAO dans le centre crisique du Moyen-Orient, voire une discorde chez l&rsquo;ennemi (malaise entre USA et UK) qui n&rsquo;arrangerait pas la situation g\u00e9n\u00e9rale du bloc BAO. Un lien serait \u00e9tabli entre la crise excentr\u00e9e et la crise centrale du cur du monde, conduisant vers l&rsquo;int\u00e9gration de la premi\u00e8re dans la seconde.<\/p>\n<\/p>\n<p><p>\t On f\u00eatera le 30\u00e8me anniversaire de la crise et de la guerre des Malouines (Malouines-I) entre mars et juin. Si la crise se d\u00e9veloppe, cet anniversaire devrait \u00eatre exploit\u00e9 du point de vue de la communication, par la pr\u00e9sidente argentine, pour accentuer la pression et la tension de la crise au moment o\u00f9 se profilent certains des paroxysmes de tension pr\u00e9visibles, dans tous les cas du point de vue de la communication, autour de la crise iranienne (proximit\u00e9 de l&rsquo;entr\u00e9e en vigueur de l&#8217;embargo, alors que certains agitent la date de mai-juin pour une attaque isra\u00e9lienne contre l&rsquo;Iran). La pr\u00e9sence des Britanniques comme acteurs d&rsquo;une telle tension autour des Malouines en m\u00eame temps qu&rsquo;acteur de la crise centrale au Moyen-Orient offre la possibilit\u00e9 de l&rsquo;\u00e9tablissement d&rsquo;un lien important, conjoncturel mais paroxystique cette fois,  entre les deux<\/p>\n<h3>De l&rsquo;extension du domaine de la crise haute<\/h3>\n<\/p>\n<p><p>\tD&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale, l&rsquo;affaire Malouines-II se pr\u00e9sente comme une crise excentr\u00e9e d&rsquo;un point de vue g\u00e9opolitique (sans beaucoup d&rsquo;importance), qui peut entrer dans une dynamique de contestation du bloc BAO de la part d&rsquo;un pays, puis d&rsquo;un continent qui s&rsquo;est affirm\u00e9 ces derni\u00e8res ann\u00e9es sur un mode revendicatif \u00e0 l&rsquo;encontre de ce m\u00eame bloc BAO. Dans ce cas, si la dynamique de contestation cr\u00e9e  effectivement une crise de revers par rapport aux grandes lignes de la <a href=\"http:\/\/www.dedefensa.org\/article-le_c_ur_du_sujet_29_05_2009.html\" class=\"gen\">politique<\/a> de l&rsquo;id\u00e9ologie et de l&rsquo;instinct du bloc BAO, elle trouve sa place dans une sorte de Grand Jeu, non pas g\u00e9opolitique, mais m\u00e9tahistorique,  un Grand Jeu de la crise haute, en renfor\u00e7ant par le revers la tension g\u00e9n\u00e9rale du centre crisique.<\/p>\n<\/p>\n<p><p>\tLes moyens de ce Grand Jeu ne sont pas les int\u00e9r\u00eats g\u00e9opolitiques mais les pressions du syst\u00e8me de la communication et la perception de l&rsquo;affrontement autour de la logique-Syst\u00e8me que sert le bloc BAO, avec tout l&rsquo;encha\u00eenement de ses cons\u00e9quences renvoyant \u00e0 la logique de la crise g\u00e9n\u00e9rale, de la crise haute. Dans ce cadre qui implique une logique sp\u00e9cifique sans rapport avec la logique de puissance traditionnelle, il pourrait s&rsquo;\u00e9tablir des orientations nouvelles d&rsquo;extension et des connexions diverses (par exemple, l&rsquo;extension des liens d\u00e9j\u00e0 \u00e9tablis entre l&rsquo;Iran et l&rsquo;Am\u00e9rique du Sud, mais aussi, plus g\u00e9n\u00e9ralement, entre la Chine et l&rsquo;Am\u00e9rique du Sud). Il y aurait int\u00e9gration et l\u00e9gitimation de l&rsquo;hypoth\u00e9tique crise Malouines-II.<\/p>\n<\/p>\n<p><p>\tLa crise haute, c&rsquo;est le sch\u00e9ma g\u00e9n\u00e9ral qui accueille, et \u00e9ventuellement favorise l&rsquo;extension de la crise centrale vers tous les azimuts possibles, de fa\u00e7on \u00e0 cr\u00e9er une situation unitaire de crise rencontrant la logique de la crise g\u00e9n\u00e9rale du Syst\u00e8me. La condition <em>sine qua non<\/em>  est qu&rsquo;un membre \u00e9minent du bloc BAO soit impliqu\u00e9 ; c&rsquo;est le cas ici, car qu&rsquo;y a-t-il de plus \u00e9minent \u00e0 cet \u00e9gard que le Royaume-Uni ? Selon cette interpr\u00e9tation, l&rsquo;hypoth\u00e9tique crise Malouines-II, avec les potentialit\u00e9s d\u00e9crites, va incontestablement dans le sens d&rsquo;un progr\u00e8s sur la voie de la mise en cause radicale du Syst\u00e8me, dans le cadre de sa dynamique d&rsquo;autodestruction. Elle constitue un bon exemple, \u00e0 suivre avec attention et sollicitude, de ce processus essentiel d&rsquo;extension du domaine de la crise haute, qui rec\u00e8le la potentialit\u00e9 m\u00e9tahistorique de la concr\u00e9tisation finale de la crise d&rsquo;effondrement du Syst\u00e8me.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur 1982 revisit\u00e9, des Malouines \u00e0 la crise haute Ceux qui, vieillis sous le harnais, v\u00e9curent la guerre des Malouines en 1982, savent que ce cas fut l&rsquo;un des points de crise les plus critiques des relations sp\u00e9ciales USA-UK. Pendant quelques semaines, les USA, sous l&rsquo;influence de l&rsquo;ambassadrice US \u00e0 l&rsquo;ONU Jeane Kirkpatrick et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[3261,10900,6039,3228,14634,7501,14594,14633,5714,14595,9333,7502],"class_list":["post-74498","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-argentine","tag-bao","tag-bloc","tag-crise","tag-cristina","tag-evita","tag-falkland","tag-falklands","tag-haute","tag-kirchner","tag-malouines","tag-peron"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74498"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74498\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}