{"id":74505,"date":"2012-02-16T12:52:02","date_gmt":"2012-02-16T12:52:02","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/02\/16\/la-crise-profonde-de-la-democratie-elective\/"},"modified":"2012-02-16T12:52:02","modified_gmt":"2012-02-16T12:52:02","slug":"la-crise-profonde-de-la-democratie-elective","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/02\/16\/la-crise-profonde-de-la-democratie-elective\/","title":{"rendered":"La crise profonde de la d\u00e9mocratie \u00e9lective"},"content":{"rendered":"<p><h2 class=\"common-article2\">La crise profonde de la d\u00e9mocratie \u00e9lective<\/h2>\n<\/p>\n<p><p>\tLa fameuse phrase de Churchill (la d\u00e9mocratie est le pire des r\u00e9gimes \u00e0 l&rsquo;exclusion de tous les autres) est peut-\u00eatre v\u00e9ridique, mais personne ne peut la certifier, pour la simple raison que la d\u00e9mocratie est un id\u00e9al qui n&rsquo;a jamais \u00e9t\u00e9 atteint. En effet, tous les individus qui composent le peuple ne peuvent avoir le pouvoir sans que r\u00e8gne une v\u00e9ritable anarchie. Donc, la d\u00e9mocratie est un concept d\u00e9magogique qui d\u00e9signe un syst\u00e8me politique o\u00f9 les \u00e9lections donnent l&rsquo;impression \u00e0 un grand nombre de personnes qu&rsquo;ils poss\u00e8dent une partie du pouvoir. Nous voyons un peu partout, des signes de l&rsquo;enrayement de ce syst\u00e8me \u00e9lectif.  <\/p>\n<h3>Des juges \u00e9lectifs douteux <\/h3>\n<\/p>\n<p><p>\tLa confiance permet le bon fonctionnement de tout syst\u00e8me politique, or dans une p\u00e9riode de crise, elle s&rsquo;accorde plus difficilement. Dans les d\u00e9mocraties \u00e9lectives, les citoyens confient leur pouvoir \u00e0 des organismes charg\u00e9s de comptabiliser leur voix. Lorsque le r\u00e9sultat n&rsquo;est pas celui escompt\u00e9, l&rsquo;\u00e9lecteur \u00e9gocentrique a la sensation d&rsquo;avoir \u00e9t\u00e9 flou\u00e9.<\/p>\n<\/p>\n<p><p>\tL&rsquo;ann\u00e9e derni\u00e8re en C\u00f4te d&rsquo;Ivoire, les deux organismes charg\u00e9s de valider les r\u00e9sultats de l&rsquo;\u00e9lection pr\u00e9sidentielle (la Commission \u00e9lectorale et le Conseil Constitutionnel) ont d\u00e9clar\u00e9 un vainqueur diff\u00e9rent. Chaque camp a octroy\u00e9 sa confiance \u00e0 l&rsquo;organisme qui satisfaisait son d\u00e9sir. Les doutes sur l&rsquo;int\u00e9grit\u00e9 des juges \u00e9lectifs ont fatalement conduit les irr\u00e9conciliables \u00e0 une guerre civile. Le victorieux a \u00e9t\u00e9 celui qui avait b\u00e9n\u00e9fici\u00e9 des plus puissants appuis int\u00e9rieurs et ext\u00e9rieurs. Une telle situation peut se reproduire lorsqu&rsquo;un gentil candidat est aux prises avec un vaurien, lors d&rsquo;un second tour exacerbant les passions.<\/p>\n<\/p>\n<p><p>\tEn Russie, les l\u00e9gislatives de 2011 ont vu des r\u00e9sultats conformes aux sondages. Pour certains opposants, cela prouve que les instituts de sondages et la Commission \u00e9lectorale centrale sont complices du gouvernement. Les soup\u00e7ons devenant certitudes, des manifestations ont eu lieu. Le scrutin n&rsquo;\u00e9tant qu&rsquo;\u00e0 un tour, les contestataires \u00e9taient trop divis\u00e9s pour pr\u00e9tendre au pouvoir, mais se sont accord\u00e9s pour tenter de d\u00e9stabiliser la Russie Unie de Poutine (suivant le prototype des Guerres de 4\u00e8me G\u00e9n\u00e9ration).<\/p>\n<\/p>\n<p><p>\tDans la m\u00eame zone g\u00e9ographique, le cas de l&rsquo;Oss\u00e9tie du Sud est particuli\u00e8rement int\u00e9ressant. Cette derni\u00e8re n&rsquo;\u00e9tant reconnue que par six pays, la pr\u00e9sidentielle de novembre 2011 rev\u00eatait une symbolique particuli\u00e8re. Au second tour, le candidat ouvertement soutenu par le gouvernement russe, Bibilov, a obtenu 39% des suffrages. La Cour Supr\u00eame a invalid\u00e9 ces \u00e9lections en consid\u00e9rant qu&rsquo;il y avait eu des fraudes, provoquant l&rsquo;ire des partisans de Djio\u00efeva, la donn\u00e9e-gagnante par la commission \u00e9lectorale. Contrairement aux cas pr\u00e9c\u00e9dents, les gouvernements des pays d&rsquo;ordinaire si prompts \u00e0 juger de la probit\u00e9 des r\u00e9sultats \u00e9lectoraux n&rsquo;ont pas pris parti pour Djio\u00efeva, car cela signifiait reconna\u00eetre de facto cette entit\u00e9 ! Cette \u00e9lection a montr\u00e9 que les juges ext\u00e9rieurs (la dite Communaut\u00e9 Internationale) sont eux aussi soumis \u00e0 des imp\u00e9ratifs politiques et ne peuvent donc pas \u00eatre consid\u00e9r\u00e9s comme une source impartiale.<\/p>\n<h3>Une crise de l&rsquo;autorit\u00e9 politique<\/h3>\n<\/p>\n<p><p>\tDans une \u00e9lection, les candidats courtisent les votants, bien souvent en feignant d&rsquo;\u00eatre populaires, c&rsquo;est-\u00e0-dire en faisant leurs des habitudes du Peuple, ou du moins celles de la population cibl\u00e9e par leurs conseillers en communication. La plupart des candidats juge cette attitude payante, car ils consid\u00e8rent que para\u00eetre au-dessus de la m\u00eal\u00e9e des citoyens risque de froisser l&rsquo;\u00e9lectorat. Or, c&rsquo;est justement cette qualit\u00e9 qui symbolise le gouvernant. Par principe, le dirigeant ne doit plus faire partie de ceux qu&rsquo;il dirige, d&rsquo;apr\u00e8s l&rsquo;antique trait\u00e9 d&rsquo;Han Fei Zi (<em>L&rsquo;art de gouverner<\/em>). Souvent, un candidat s&rsquo;abaisse devant le peuple pour \u00eatre \u00e9lu, puis veut \u00eatre au-dessus de celui-ci pour gouverner.<\/p>\n<\/p>\n<p><p>\tLe chef d&rsquo;\u00c9tat se doit d&rsquo;\u00eatre un \u00e9quilibriste, qui peut tomber d\u00e8s son premier soir comme en France. Ce dernier a malgr\u00e9 tout conserv\u00e9 son poste nominal, mais pas celui de gouvernant qu&rsquo;il n&rsquo;a jamais eu. La comparaison entre De Villepin et Sarkozy est assez int\u00e9ressante de ce point de vue, si le premier ne pourra pas \u00eatre \u00e9lu (sans perdre son ancien prestige  par ailleurs d\u00e9j\u00e0 bien entam\u00e9), le second est dans l&rsquo;incapacit\u00e9 de gouverner (sa fonction ne l&rsquo;ayant pas transcend\u00e9).<\/p>\n<\/p>\n<p><p>\tAujourd&rsquo;hui, la plupart des gens conserve l&rsquo;id\u00e9al d\u00e9mocratique, bien que l&rsquo;\u00e9lection ne soit plus consid\u00e9r\u00e9e comme fiable. Celle-ci peut \u00eatre manipul\u00e9e et donn\u00e9e un semblant de pouvoir \u00e0 un homme d\u00e9pourvu d&rsquo;autorit\u00e9 v\u00e9ritable. D\u00e9s lors, une des mani\u00e8res envisageables est l&rsquo;arriv\u00e9e au pouvoir sans compromis \u00e9lectoral. Par exemple, si un candidat para\u00eet au-dessus d&rsquo;une contestation populaire (remettant en cause le r\u00e9sultat de l&rsquo;\u00e9lection), suivant le mod\u00e8le des r\u00e9volutions color\u00e9es. Il conserve (ou augmente) ainsi son prestige  s&rsquo;il en a  dans un troisi\u00e8me tour urbain et devient l&rsquo;homme providentiel. Aussi surprenant soit-il, un tel sc\u00e9nario est loin d&rsquo;\u00eatre inenvisageable dans des pays comme la France ou les \u00c9tats-Unis pour 2012. Le d\u00e9sordre cr\u00e9\u00e9 par les plus fervents des militants pousserait un des candidats \u00e0 rompre avec le syst\u00e8me qui pr\u00e9vaut actuellement<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Isma\u00ebl Malamati<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La crise profonde de la d\u00e9mocratie \u00e9lective La fameuse phrase de Churchill (la d\u00e9mocratie est le pire des r\u00e9gimes \u00e0 l&rsquo;exclusion de tous les autres) est peut-\u00eatre v\u00e9ridique, mais personne ne peut la certifier, pour la simple raison que la d\u00e9mocratie est un id\u00e9al qui n&rsquo;a jamais \u00e9t\u00e9 atteint. En effet, tous les individus qui&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[2825,11532,3555],"class_list":["post-74505","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-democratie","tag-ismael","tag-legitimite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74505"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74505\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}