{"id":74524,"date":"2012-02-24T07:02:00","date_gmt":"2012-02-24T07:02:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/02\/24\/lentrisme-des-islamistes-au-cur-de-ladministration-us\/"},"modified":"2012-02-24T07:02:00","modified_gmt":"2012-02-24T07:02:00","slug":"lentrisme-des-islamistes-au-cur-de-ladministration-us","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/02\/24\/lentrisme-des-islamistes-au-cur-de-ladministration-us\/","title":{"rendered":"L&rsquo;entrisme des islamistes au c\u0153ur de l&rsquo;administration US"},"content":{"rendered":"<p><p>On savait jusqu&rsquo;ici que les islamistes, et pr\u00e9cis\u00e9ment les Fr\u00e8res Musulmans en Egypte, avaient b\u00e9n\u00e9fici\u00e9, comme \u00e0 peu pr\u00e8s tout le monde d&rsquo;ailleurs en Egypte, de l&rsquo;aide de la CIA pendant un nombre divers mais substantiel d&rsquo;ann\u00e9es. La chose s&rsquo;est g\u00e9n\u00e9ralement traduite, pour une partie de l&rsquo;effet, par une pouss\u00e9e des islamistes partout, et des Fr\u00e8res Musulmans en Egypte, jusqu&rsquo;\u00e0 une position pr\u00e9\u00e9minente au niveau politique, avec des prises de position qui <a href=\" http:\/\/www.dedefensa.org\/article-egypte_versus_usa_crise_puis_rupture__17_02_2012.html\" class=\"gen\">contredisent<\/a> directement les int\u00e9r\u00eats US. La boucle de l&rsquo;inversion destructrice de l&rsquo;influence par la corruption est ainsi boucl\u00e9e.<\/p>\n<\/p>\n<p><p>\tCette fois, on passe \u00e0 un stade sup\u00e9rieur, comme nous en informe un texte de <em>Russia Today<\/em>, le <a href=\"http:\/\/rt.com\/news\/islamist-egypt-obama-lobby-003\/\" class=\"gen\">23 f\u00e9vrier 2012<\/a>. RT a interview\u00e9 un conseiller du gouvernement US pour les affaires antiterroristes, Walid Phares. Il s&rsquo;agit de parler du r\u00f4le des ONG, des activit\u00e9s de lobbying, etc. Ce type d&rsquo;activit\u00e9s classiques de l&rsquo;arsenal interventionniste US est cette fois consid\u00e9r\u00e9 dans son inversion pure, retourn\u00e9 contre les int\u00e9r\u00eats des USA dans ses effets g\u00e9n\u00e9raux. Phares parle de la fa\u00e7on dont les Fr\u00e8res Musulmans ont confisqu\u00e9 la r\u00e9volution \u00e9gyptienne, comment ils ont investi les positions du pouvoir. Il mentionne certes l&rsquo;aide que les pays du Golfe, financiers oblig\u00e9s de tout ce qui est islamiste, ont apport\u00e9e aux Fr\u00e8res Musulmans<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Phares points out that there is one crucial difference between the ordinary people who made the revolution and those who basically hijacked it, namely various Islamist forces, including the Muslim Brotherhood. The difference is that the latter enjoy generous support from the Gulf States in the form of petrodollars, satellite telecommunication and so on. This difference will play a decisive role when the time for the election comes, and those most organized and better funded will take over.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tMais ce sont certainement les d\u00e9tails que donne Phares en passant, sur la p\u00e9n\u00e9tration de l&rsquo;administration US par les islamistes sous forme de forces de lobbying, qui retiennent le plus notre attention. Ils sont r\u00e9v\u00e9lateurs d&rsquo;une tactique remarquable de retournement d&rsquo;une m\u00e9thode contre celui qui l&rsquo;a d\u00e9velopp\u00e9e pour installer des points d&rsquo;influence ext\u00e9rieurs en son cur. L&rsquo;outil est retourn\u00e9, effectivement, pour installer ces points d&rsquo;influence au cur du pouvoir US.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>And yet, perhaps, the most intriguing feature of the ongoing race for power in Egypt is those back-door games that take place as far from Cairo as in Washington. According to Phares, there is a powerful Islamist lobby within the American presidential administration itself. There are NGOsknown as lobbies, or pressure groups, which are trying to influence the<\/em> [Obama] <em>administration, so that they would be in line with the interests of the Muslim Brotherhood in Egypt and the Islamists in Libya and in Tunisia, and against the secular and liberal forces in the region, the advisor explained.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tOn comprend parfaitement le m\u00e9canisme en action. L&rsquo;on en voit des r\u00e9sultats chaque jour, aussi bien dans le d\u00e9sordre de la politique des USA soutenant successivement ou parall\u00e8lement des forces d&rsquo;opposition antagonistes des pouvoirs \u00e9tablis il y a longtemps par ces m\u00eames USA, que dans le soutien apport\u00e9 \u00e0 des forces (islamistes) dont la politique finale, une fois investi le pouvoir, ne peut manquer d&rsquo;\u00e9voluer vers des tendances anti-occidentalistes et anti-US.<\/p>\n<\/p>\n<p><p>\tCe qui est remarquable dans cette description succincte d&rsquo;une situation qui ne peut finalement surprendre, c&rsquo;est combien cette situation s&rsquo;accorde au d\u00e9sordre du pouvoir US lui-m\u00eame. Ce d\u00e9sordre est visible aussi bien au Congr\u00e8s que dans les diverses politiques suivies par les USA, particuli\u00e8rement dans ces r\u00e9gions strat\u00e9giques (le Moyen-Orient, et pr\u00e9cis\u00e9ment l&rsquo;Egypte pour ce qui nous importe). Dans cette situation de d\u00e9sordre, la porosit\u00e9 du cur du pouvoir US (l&rsquo;administration US) est lui-m\u00eame un facteur remarquable, d\u00e9coulant de la dissolution de ce pouvoir, de son absence de structures r\u00e9galiennes, du transfert massif de la puissance vers le syst\u00e8me de la communication dont le lobbying est un appendice corrupteur puissant, de la vuln\u00e9rabilit\u00e9 des services d&rsquo;\u00e9laboration de la politique US \u00e0 l&rsquo;influence de ce m\u00eame lobbying. Tout cela se conjugue bien entendu \u00e0 une parfaite m\u00e9connaissance (plut\u00f4t qu&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-de_l_inconnaissance_du_systeme_13_07_2011.html\" class=\"gen\">inconnaissance<\/a>, certes !) des caract\u00e9ristiques, des psychologies, de la culture, etc., des r\u00e9gions vis\u00e9es, qui rend ce pouvoir US effectivement vuln\u00e9rable \u00e0 tous les arguments, m\u00eame les plus simplistes et les plus sommaires, de l&rsquo;activit\u00e9 du lobbying.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit, dans le chef du pouvoir US, d&rsquo;un pouvoir d&rsquo;une extr\u00eame puissance, absolument ignorant des choses qu&rsquo;il doit traiter, suivant une ligne aveugle \u00e0 cause de la crise de ses structures en compl\u00e8te d\u00e9composition. L&rsquo;influence p\u00e9n\u00e8tre dans ce pouvoir comme dans du beurre, pour l&rsquo;orienter selon les int\u00e9r\u00eats de celui qui la manipuler ; et l&rsquo;on ne serait pas \u00e9tonn\u00e9, enfin, s&rsquo;il apparaissait que le lobbying des islamistes commen\u00e7ait \u00e0 se mesurer au lobbying sioniste (AIPAC) sur son propre terrain, et s&rsquo;il portait une certaine responsabilit\u00e9, au moins indirecte, dans les <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_l_amitie_usa-israel_23_02_2012.html\" class=\"gen\">difficult\u00e9s<\/a> de plus en plus grandes entre l&rsquo;administration Obama et Isra\u00ebl. Bien entendu, cette situation mesure avant tout la crise du pouvoir US, qui se dissout compl\u00e8tement par rapport \u00e0 ses int\u00e9r\u00eats et \u00e0 ses objectifs, et transforme \u00e9videmment sa surpuissance en autodestruction, sans ralentir en rien la dynamique qui anime le processus.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis enligne le 24 f\u00e9vrier 2012 \u00e0 07H01<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>On savait jusqu&rsquo;ici que les islamistes, et pr\u00e9cis\u00e9ment les Fr\u00e8res Musulmans en Egypte, avaient b\u00e9n\u00e9fici\u00e9, comme \u00e0 peu pr\u00e8s tout le monde d&rsquo;ailleurs en Egypte, de l&rsquo;aide de la CIA pendant un nombre divers mais substantiel d&rsquo;ann\u00e9es. La chose s&rsquo;est g\u00e9n\u00e9ralement traduite, pour une partie de l&rsquo;effet, par une pouss\u00e9e des islamistes partout, et des&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4270,3015,2631,10119,9550,11025,11201,2622,3687,3758,14652,14653,3769,11131,3014,2671,6532],"class_list":["post-74524","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-autodestruction","tag-communication","tag-de","tag-dissolution","tag-egypte","tag-freres","tag-inconnaissance","tag-la","tag-lobbying","tag-musulmans","tag-phares","tag-porosite","tag-pouvoir","tag-surpuissance","tag-systeme","tag-us","tag-vulnerabilite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74524"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74524\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}