{"id":74614,"date":"2012-03-31T16:19:42","date_gmt":"2012-03-31T16:19:42","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/03\/31\/technophilie-verte\/"},"modified":"2012-03-31T16:19:42","modified_gmt":"2012-03-31T16:19:42","slug":"technophilie-verte","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/03\/31\/technophilie-verte\/","title":{"rendered":"Technophilie verte"},"content":{"rendered":"<p><h4>Technophilie verte<\/h4>\n<p>Technophilie verte ou de la crise climatique comme source de nouveaux d\u00e9lires techniciens : <a href=\"http:\/\/www.pensee-unique.fr\/bonnetdane.html#liao\" class=\"gen\">http:\/\/www.pensee-unique.fr\/bonnetdane.html#liao<\/a><\/p>\n<\/p>\n<p><p>\tQuestion : Une des strat\u00e9gies d&rsquo;ing\u00e9nierie humaine que vous mentionnez consiste \u00e0 cr\u00e9er, par des moyens pharmaceutiques, une sorte d&rsquo;intol\u00e9rance \u00e0 la consommation de la viande. Vous sugg\u00e9rez que l&rsquo;on pourrait donner de la viande aux humains en l&rsquo;accompagnant d&rsquo;une m\u00e9dication qui d\u00e9clenche de violentes naus\u00e9es, ce qui pourrait entra\u00eener une aversion de longue dur\u00e9e \u00e0 la consommation de viande. Comment se fait-il que vous en attendiez un impact spectaculaire sur le changement climatique ?<\/p>\n<\/p>\n<p><p>\tLiao : Il existe un rapport, fr\u00e9quemment cit\u00e9, de l&rsquo;Organisation de l&rsquo;Alimentation et de l&rsquo;Agriculture de l&rsquo;ONU ( &#8230;) qui estime que 18% des \u00e9missions mondiales de gaz \u00e0 effet de serre et de leur \u00e9quivalent en CO2, proviennent de l&rsquo;\u00e9levage du b\u00e9tail, ce qui en fait un facteur plus important que celui des transports. Plus r\u00e9cemment, il a \u00e9t\u00e9 sugg\u00e9r\u00e9 que le b\u00e9tail compte pour pas moins de 51% des \u00e9missions de gaz \u00e0 effet de serre. De plus, il y a des estimations selon lesquelles pas moins de 9% des \u00e9missions humaines proviennent du fait de la d\u00e9forestation destin\u00e9e \u00e0 l&rsquo;agrandissement des p\u00e2turages pour le b\u00e9tail. Et ceci ne prend m\u00eame pas en compte les \u00e9missions qui proviennent des d\u00e9jections animales ou directement des animaux. Puisqu&rsquo;une grande fraction de ces vaches et des autres animaux de pacage sont \u00e9lev\u00e9s dans un but de consommation de viande il semble \u00e9vident que la r\u00e9duction de la consommation de ces viandes aurait des b\u00e9n\u00e9fices environnementaux consid\u00e9rables.<\/p>\n<\/p>\n<p><p>\t[&#8230;]<\/p>\n<\/p>\n<p><p>\tQuestion : Votre article discute \u00e9galement sur l&rsquo;utilisation de l&rsquo;ing\u00e9nierie humaine pour rapetisser les humains. En quoi cela serait-il une technique puissante pour lutter contre le r\u00e9chauffement climatique ?<\/p>\n<\/p>\n<p><p>\tLiao:  Eh bien, une des choses que nous avons remarqu\u00e9es est que les empreintes \u00e9cologiques des humains sont en partie corr\u00e9l\u00e9es avec leur taille. Chaque kilogramme de masse corporelle exige une certaine quantit\u00e9 de nourriture et de nutriments et ainsi, toutes choses \u00e9tant \u00e9gales par ailleurs, les personnes les plus grandes sont celles qui vont pomper plus de nourriture et d&rsquo;\u00e9nergie pendant leurs dur\u00e9es de vie. Il y a aussi d&rsquo;autres raisons, moins \u00e9videntes, pour lesquelles les personnes les plus grandes consomment plus d&rsquo;\u00e9nergie que les petites &#8211; par exemple, une automobile consomme plus de carburant au kilom\u00e8tre pour transporter une personne plus lourde et plus de tissus est n\u00e9cessaire pour habiller les grands. De m\u00eame, les personnes plus lourdes usent \u00e0 un rythme plus acc\u00e9l\u00e9r\u00e9 leurs chaussures, les tapis ainsi que les meubles que les personnes plus l\u00e9g\u00e8res, et ainsi de suite.<\/p>\n<\/p>\n<p><p>\tAinsi, la r\u00e9duction de taille pourrait \u00eatre une fa\u00e7on de r\u00e9duire l&#8217;empreinte \u00e9cologique d&rsquo;une personne. Par exemple, si vous r\u00e9duisez la taille moyenne aux USA de seulement 15 cm, vous pourriez r\u00e9duire la masse corporelle de 21% pour les hommes et de 25% pour les femmes, ce qui  correspondrait \u00e0 une r\u00e9duction des taux m\u00e9taboliques de quelques 15% \u00e0 18%, parce que moins de substance signifie moins d&rsquo;\u00e9nergie et moins de besoins alimentaires.<\/p>\n<\/p>\n<p><p>\t[&#8230;]<\/p>\n<\/p>\n<p><p>\tQuestion : Dans votre article, vous sugg\u00e9rez que certaines solutions d&rsquo;ing\u00e9nierie humaine peuvent, en fait, \u00eatre une source d&rsquo;accroissement de la libert\u00e9. Comment est-ce possible ?<\/p>\n<\/p>\n<p><p>\tLiao:  C&rsquo;est exact. Il a \u00e9t\u00e9 sugg\u00e9r\u00e9 qu&rsquo;\u00e9tant donn\u00e9 la gravit\u00e9 du changement climatique, nous devrions adopter des solutions telles que celle de la Chine avec un seul enfant par couple. Il y a eu un groupe de m\u00e9decins en Grande Bretagne qui ont r\u00e9cemment pr\u00f4n\u00e9 l&rsquo;id\u00e9e de n&rsquo;avoir que deux enfants au maximum. Mais, au final, ce sont des prescriptions grossi\u00e8res &#8211; ce dont nous avons besoin c&rsquo;est d&rsquo;une sorte de prescription d&rsquo;\u00e9missions de gaz \u00e0 effet de serre par famille. Dans ce cas, \u00e9tant donn\u00e9 certaines prescriptions fix\u00e9es d&rsquo;\u00e9mission de gaz \u00e0 effet de serre, l&rsquo;ing\u00e9nierie humaine pourrait laisser le choix aux familles de choisir entre deux enfants de taille moyenne, ou bien trois enfants de petite taille. Selon nous, ce serait plus en faveur de la libert\u00e9 de choix qu&rsquo;une politique qui dirait \u00ab\u00a0Vous ne pouvez avoir qu&rsquo;un ou deux enfants\u00a0\u00bb. Une famille pourrait d\u00e9sirer avoir un joueur de basket r\u00e9ellement performant et ainsi elle pourrait utiliser l&rsquo;ing\u00e9nierie humaine pour avoir un seul tr\u00e8s grand enfant.<\/p>\n<\/p>\n<p><p>\t[&#8230;]<\/p>\n<\/p>\n<p><p>\tQuestion : En consid\u00e9rant ceci dans la perspective de \u00ab\u00a0l&rsquo;\u00e9cologie extr\u00e9miste\u00a0\u00bb ( NdT : deep ecology en anglais) &#8211; peut-on dire au sujet de l&rsquo;id\u00e9e que, puisque le changement climatique est caus\u00e9 par l&rsquo;homme, alors l&rsquo;homme devrait \u00eatre chang\u00e9 pour le minimiser &#8211; que, d&rsquo;une certaine fa\u00e7on, nous devrions en supporter le co\u00fbt pour r\u00e9parer tout cela ?<\/p>\n<\/p>\n<p><p>\tLiao : C&rsquo;est en fait une des id\u00e9es qui nous ont pouss\u00e9 \u00e0 \u00e9crire cet article : L&rsquo;id\u00e9e que nous avons provoqu\u00e9 le changement climatique anthropique et donc que, peut-\u00eatre, nous devrions en supporter les co\u00fbts requis pour r\u00e9gler le probl\u00e8me. Mais ayant dit \u00e7a, nous voulons aussi rendre ceci attirant pour le public &#8211; Nous ne voulons pas que ceci soit un jeu \u00e0 somme nulle dans lequel c&rsquo;est juste le co\u00fbt que nous devons assumer. Beaucoup des solutions que nous proposons pourraient \u00eatre tout \u00e0 fait d\u00e9sirables pour le public, et en particulier le timbre pour la viande (NdT : le patch qui donne des naus\u00e9es quand on consomme de la viande). J&rsquo;ai donn\u00e9 r\u00e9cemment une conf\u00e9rence au sujet de cet article \u00e0 l&rsquo;Universit\u00e9 de Yale et il y avait un homme dans l&rsquo;auditoire qui travaillait pour une compagnie pharmaceutique; Il semblait penser qu&rsquo;il pouvait y avoir un gigantesque march\u00e9 pour des modifications comme celle-l\u00e0.<\/p>\n<\/p>\n<p><p>\tConclusion du site \u00ab\u00a0Pens\u00e9e unique pour les scientifique\u00a0\u00bb qui traduit cette entrevue:<\/p>\n<\/p>\n<p><p>\t\u00ab <em>Pour ma part, compte tenu des outrances et du caract\u00e8re totalement ridicule de certaines affirmations contenues dans cet article ou dans cet interview, j&rsquo;ai tout d&rsquo;abord pens\u00e9 qu&rsquo;ils&rsquo;agissait d&rsquo;un canular. On sait que l&rsquo;Universit\u00e9 d&rsquo;Oxford est friande d&rsquo;humour noir et de ce genre de plaisanterie.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb <em>Apr\u00e8s enqu\u00eate et tr\u00e8s malheureusement, je dois convenir, comme d&rsquo;autres, qu&rsquo;il n&rsquo;en est rien et que ce trio de jeunes chercheurs quelque peu d\u00e9jant\u00e9s n&rsquo;ont nulle envie de plaisanter. Pour s&rsquo;en convaincre, il suffit d&rsquo;examiner d&rsquo;un peu pr\u00e8s, les pr\u00e9c\u00e9dentes publications des diff\u00e9rents auteurs de cet article. Par exemple, le Dr Liao a r\u00e9dig\u00e9 plusieurs articles en faveur de l&rsquo;am\u00e9lioration \u00ab\u00a0g\u00e9n\u00e9tique\u00a0\u00bb des embryons humains. Il semble que, dans l&rsquo;esprit de ces trois jeunes auteurs, l&rsquo;un des plus grands tabous de nos civilisations mill\u00e9naires qui est le respect de l&rsquo;int\u00e9grit\u00e9 du corps humain, ait d\u00e9finitivement disparu. D\u00e8s lors, toutes les outrances deviennent possibles quand \u00ab\u00a0la cause\u00a0\u00bb (comme l&rsquo;appellent Michael Mann et quelques autres) para\u00eet \u00eatre une justification suffisante.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb <em>Je redoute que ce genre de publication, lorsqu&rsquo;elle sera connue et comment\u00e9e dans la grande presse (si elle l&rsquo;est un jour), ne renvoie au public l&rsquo;image d&rsquo;une science du XXI\u00e8me si\u00e8cle globalement d\u00e9voy\u00e9e. Il est ais\u00e9 de g\u00e9n\u00e9raliser m\u00eame si c&rsquo;est imm\u00e9rit\u00e9.<\/em> \u00bb<\/p>\n<\/p>\n<p>\n<p class=\"signature\"><em>GEO<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Technophilie verte Technophilie verte ou de la crise climatique comme source de nouveaux d\u00e9lires techniciens : http:\/\/www.pensee-unique.fr\/bonnetdane.html#liao Question : Une des strat\u00e9gies d&rsquo;ing\u00e9nierie humaine que vous mentionnez consiste \u00e0 cr\u00e9er, par des moyens pharmaceutiques, une sorte d&rsquo;intol\u00e9rance \u00e0 la consommation de la viande. Vous sugg\u00e9rez que l&rsquo;on pourrait donner de la viande aux humains en&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3392,3228,8809],"class_list":["post-74614","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-climatique","tag-crise","tag-geo"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74614"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74614\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}