{"id":74633,"date":"2012-04-09T09:05:59","date_gmt":"2012-04-09T09:05:59","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/04\/09\/la-crise-des-antimissiles-miroir-de-lepoque\/"},"modified":"2012-04-09T09:05:59","modified_gmt":"2012-04-09T09:05:59","slug":"la-crise-des-antimissiles-miroir-de-lepoque","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/04\/09\/la-crise-des-antimissiles-miroir-de-lepoque\/","title":{"rendered":"La crise des antimissiles, miroir de l&rsquo;\u00e9poque"},"content":{"rendered":"<p><h3 class=\"titrebloc\">La crise des antimissiles, miroir de l&rsquo;\u00e9poque<\/h3>\n<\/p>\n<p><p>\tLa crise quasi-perp\u00e9tuelle des euromissiles,  BMDE pour l&rsquo;Europe, ou GBMD pour la dimension globale,  tr\u00e8s larv\u00e9e de 2008 \u00e0 la mi-2011, est revenue au premier plan de l&rsquo;actualit\u00e9, \u00e0 cause des pressions US (du complexe militaro-industriel) pour l&rsquo;extension de la chose, \u00e0 l&rsquo;occasion d&rsquo;un affaiblissement notable du pouvoir washingtonien et d&rsquo;une situation politique tr\u00e8s instable de crise. L&rsquo;int\u00e9r\u00eat de cette crise, aujourd&rsquo;hui, se trouve dans son extr\u00eame diversification de sens et de forme, qui fait d&rsquo;elle un miroir de l&rsquo;\u00e9poque.<\/p>\n<\/p>\n<p><p>\tIl est bien entendu que les Russes sont de la partie Ce sont m\u00eame les <strong>seuls<\/strong> partenaires (comme eux-m\u00eames disent) des USA, le reste (OTAN, Europe, y compris la France totalement r\u00e9duite \u00e0 un vide doctrinal de servilit\u00e9 satisfaite) \u00e9tant align\u00e9 sur les USA. Les Russes sont bien entendu des partenaires extr\u00eamement critiques, qui s&rsquo;estiment comme les premiers vis\u00e9s par le r\u00e9seau antimissiles, puisque celui-ci a une potentialit\u00e9 de r\u00e9duction significative de leurs capacit\u00e9s offensives strat\u00e9giques actuelles, jusqu&rsquo;\u00e0 constituer dans des cas extr\u00eames un d\u00e9ni de la dissuasion.<\/p>\n<\/p>\n<p><p>\t(On observera avec int\u00e9r\u00eat que ce point constitue une convergence <em>de facto<\/em>, tr\u00e8s puissante et <strong>irr\u00e9sistible<\/strong>, jusqu&rsquo;ici non relev\u00e9e d&rsquo;une fa\u00e7on pr\u00e9cise mais extr\u00eamement <strong>significative<\/strong>, avec une des positions exprim\u00e9es dans le tr\u00e8s int\u00e9ressant discours de Jean-Luc M\u00e9lanchon, sur le programme de s\u00e9curit\u00e9 nationale du FdG [Front de Gauche], le <a href=\"http:\/\/www.jean-luc-melenchon.fr\/2012\/03\/30\/discours-pour-une-defense-souveraine-et-altermondialiste\/\" class=\"gen\">30 mars 2012<\/a> au Cercle R\u00e9publicain \u00e0 Paris. Il serait bon que nous envisagions de revenir plus en d\u00e9tails sur cette intervention, avant la date fatidique du premier tour des pr\u00e9sidentielles fran\u00e7aises. Nous tenterons d&rsquo;y veiller.)<\/p>\n<\/p>\n<p><p>\t C&rsquo;est par cons\u00e9quent de chez les Russes que viennent les nouvelles les plus int\u00e9ressantes sur la crise BMDE\/GBMD, attendu que, du c\u00f4t\u00e9 US, n&rsquo;existent aucune pens\u00e9e coh\u00e9rente, aucune conception structur\u00e9e, aucune pens\u00e9e \u00e9labor\u00e9e sur ce qui n&rsquo;est que l&rsquo;automatisme d&rsquo;une dynamique de surpuissance du syst\u00e8me du technologisme \u00e0 bout de souffle Mais il n&rsquo;y a pas que le syst\u00e8me du technologisme \u00e0 intervenir, justement ; et c&rsquo;est ce qui nous int\u00e9resse. Pour concr\u00e9tiser cet int\u00e9r\u00eat, et l&rsquo;expliciter, nous proposons deux nouvelles tr\u00e8s r\u00e9centes, toutes les deux d&rsquo;origine russe (<em>Russia Today<\/em>). On verra que la premi\u00e8re concerne le syst\u00e8me du technologisme, la seconde le syst\u00e8me de la communication.<\/p>\n<\/p>\n<p><p>\t  La premi\u00e8re concerne des d\u00e9clarations de Alexei Pouchkov, pr\u00e9sident de la Commission des affaires internationales \u00e0 la <em>Douma<\/em>, le <a href=\"http:\/\/rt.com\/politics\/iran-us-russia-missile-defense-war-431\/\" class=\"gen\">6 avril 2012<\/a>. Selon Pouchkov, le plan US d&rsquo;extension des antimissiles aux <a href=\"http:\/\/www.dedefensa.org\/article-voici_pour_faire_patienter_vlad__02_04_2012.html\" class=\"gen\">pays du Golfe<\/a> implique la possibilit\u00e9, sinon la probabilit\u00e9 d&rsquo;une attaque contre l&rsquo;Iran (des USA, d&rsquo;Isra\u00ebl, \u00e9ventuellement des pays du Golfe pendant qu&rsquo;on y est) \u00ab<em>The formation of the missile defense system is a new step to signal the possibility of a military strike on Iran, at least in a political context, Alexey Pushkov told a round table conference on Iran at the State Duma. A missile defense system is only needed in the event that Iran decides to retaliate, since there are no reasons to think that Iran would be the first to launch a strike all of a sudden, Pushkov said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t La seconde nouvelle concerne des pr\u00e9cisions concernant le symposium d&rsquo;un genre compl\u00e8tement nouveau que les Russes organisent les 3 et 4 mai prochains, \u00e0 Moscou. Nous avons d\u00e9j\u00e0 parl\u00e9 de ce projet le <a href=\"http:\/\/www.dedefensa.org\/article-les_anti-missiles_et_la_foire_aux_secrets__22_03_2012.html\" class=\"gen\">22 mars 2012<\/a>. Le <a href=\"http:\/\/rt.com\/politics\/missile-defense-conference-russia-425\/\" class=\"gen\">6 avril 2012<\/a>, <em>Russia Today<\/em> pr\u00e9sente le projet comme devant s&rsquo;av\u00e9rer \u00eatre un succ\u00e8s de communication consid\u00e9rable.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Russia has invited about 50 states, including the US and other NATO members, to participate in an international conference on missile defense, to be held in Moscow on May 3-4. The Russian Defense Ministry received even more positive replies to its invitations than expected, said Sergey Koshelev, the head of the body&rsquo;s Main Department for International Military Cooperation. He noted that only one country  a European NATO member-state  said that it would not take part in the summit.<\/em>  <\/p>\n<\/p>\n<p><p>\t\u00bb<em>In addition, Moscow sent invitations to about 40 foreign military experts from non-government organizations, Koshelev said. He added that last week, at a meeting with NATO leadership in Brussels, he was assured that the alliance would accept the invitation to the conference. Representatives of China, South Korea, Japan, the Commonwealth of Independent States (CIS) and member-states of the Collective Security Treaty Organization (CSTO) are also expected to attend the event.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>The Chief of the General Staff of Russian Armed Forces Nikolay Makarov will present a speech at the gathering explaining Moscow&rsquo;s official stance on the issue. We simply want to draw attention<\/em> [<em>of American colleagues and other partners<\/em>] <em>to Russian concerns so that they think about strategic consequences of their plans on missile defense, Koshelev said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCes deux nouvelles donnent un contraste saisissant qui concr\u00e9tise effectivement les traitements compl\u00e8tement diff\u00e9rents du m\u00eame probl\u00e8me, ou de la m\u00eame crise dans ce cas, selon qu&rsquo;elle est abord\u00e9e du point de vue du syst\u00e8me du technologisme ou du syst\u00e8me de la communication. Dans le premier cas, nous sommes plong\u00e9s dans la r\u00e9alit\u00e9 de la possibilit\u00e9 d&rsquo;une guerre (l&rsquo;attaque contre l&rsquo;Iran), selon les donn\u00e9es classiques de l&rsquo;affrontement g\u00e9opolitique, avec un r\u00f4le important donn\u00e9 au syst\u00e8me antimissiles pr\u00e9sent\u00e9 ici comme une des conditions de cet affrontement par la s\u00e9curit\u00e9 qu&rsquo;il assurerait aux pays du Golfe, dont on conna\u00eet l&rsquo;inqui\u00e9tude au cas o\u00f9 \u00e9claterait ce conflit. Dans le second cas, la m\u00eame crise est trait\u00e9e du point de vue du syst\u00e8me de la communication, par une manifestation internationale majeure, \u00e9videmment d\u00e9pourvue de tout son contexte direct d&rsquo;affrontement brutal de guerre, o\u00f9 l&rsquo;affrontement est transport\u00e9 directement sur le terrain de la communication.<\/p>\n<\/p>\n<p><p>\tOr, il y a des diff\u00e9rences majeures du point de vue de l&rsquo;op\u00e9rationnalit\u00e9, entre les deux cas. Dans le premier, l&rsquo;arrangement est sujet \u00e0 de consid\u00e9rables conditions, dont, notamment, l&rsquo;accomplissement concret est plac\u00e9 dans un champ hypoth\u00e9tique, chronologique, technologique et politique extr\u00eamement incertain. La proposition de d\u00e9ployer un r\u00e9seau antimissiles pour les pays du Golfe implique un laps de temps important, des conditions technologique et politiques tr\u00e8s complexes, que beaucoup d&rsquo;\u00e9l\u00e9ments hors du contr\u00f4le des instigateurs, et m\u00eame contre leurs int\u00e9r\u00eats, peuvent modifier, \u00e9ventuellement d&rsquo;une fa\u00e7on radicale, durant ce laps de temps. La situation est tr\u00e8s incertaine des points de vue politique et op\u00e9rationnel autour des possibilit\u00e9s d&rsquo;attaque de l&rsquo;Iran, les conditions sont tr\u00e8s lourdes du point de vue du syst\u00e8me du technologisme, et la mise en uvre est \u00e9galement extr\u00eamement incertaine et extr\u00eamement lourde. On peut d&rsquo;ailleurs noter que des interf\u00e9rences du syst\u00e8me de la communication peuvent jouer un r\u00f4le extr\u00eamement perturbateur, \u00e9galement au d\u00e9savantage des instigateurs.<\/p>\n<\/p>\n<p><p>\tDans le second cas, la situation est beaucoup plus nette, beaucoup plus rapide \u00e0 \u00eatre mise en place. Elle est tr\u00e8s dynamique et peut provoquer des changements importants, essentiellement \u00e0 l&rsquo;avantage des instigateurs (les Russes) si l&rsquo;on consid\u00e8re que l&rsquo;\u00e9tat d&rsquo;esprit est au d\u00e9part tr\u00e8s hostiles entre les deux groupes qui se rencontrent (les Russes, qui ont initi\u00e9 l&rsquo;affaire, et leurs amis d&rsquo;une part, les pays du bloc BAO qui veulent absolument imposer leur systeme antimissiles, d&rsquo;autre part). D&rsquo;une certaine fa\u00e7on, les instigateurs, qui n&rsquo;ont rien \u00e0 perdre, ne peuvent susciter par leur attitude que des surprises ou des interf\u00e9rences qui leur seraient b\u00e9n\u00e9fiques. Le climat cr\u00e9\u00e9 par l&rsquo;esprit d&rsquo;ouverture des Russes, si cet esprit l&rsquo;est effectivement, l&rsquo;effet \u00e9ventuel des explications des Russes de leur propre position, ne peuvent leur apporter que des changements b\u00e9n\u00e9fiques s&rsquo;il y a des changements, toujours en consid\u00e9rant que la situation de d\u00e9part est celle de l&rsquo;affrontement. On se trouve dans un cas beaucoup plus actuel o\u00f9 le syst\u00e8me de la communication joue \u00e0 plein, mais utilis\u00e9 par les Russes d&rsquo;une fa\u00e7on notablement habile dans un sens antiSyst\u00e8me, s&rsquo;ils parviennent par cette initiative \u00e0 \u00e9tablir un climat de confiance et \u00e0 modifier les psychologies.<\/p>\n<\/p>\n<p><p>\tNon seulement ces deux situations constituent effectivement un miroir de notre \u00e9poque, mais elles le constituent \u00e9galement d&rsquo;une fa\u00e7on dynamique, en \u00e9voquant l&rsquo;affaiblissement grandissant du r\u00f4le du syst\u00e8me du technologisme \u00e0 l&rsquo;avantage du syst\u00e8me de la communication. Comme nous l&rsquo;avions d\u00e9j\u00e0 observ\u00e9, il est remarquable que ce soit les Russes qui aient initi\u00e9 la chose, eux dont la r\u00e9putation h\u00e9rit\u00e9e de la Guerre froide, pour la perception du bloc BAO, est celle d&rsquo;une obsession du secret accompagn\u00e9 de maladresse et d&rsquo;inexp\u00e9rience en mati\u00e8re de communication (ce qui n&rsquo;est pas la propagande rigide et grossi\u00e8re). S&rsquo;ils ouvrent effectivement leurs dossiers avec le moins de restriction possible, alors que les USA, proposant eux-m\u00eames \u00e0 la Russie des donn\u00e9es significatives sur leur r\u00e9seau antimissiles, ne livrent que des informations sans importance (voir encore au <a href=\"http:\/\/www.dedefensa.org\/article-les_anti-missiles_et_la_foire_aux_secrets__22_03_2012.html\" class=\"gen\">22 mars 2012<\/a>), les Russes auront remport\u00e9 une bataille significative du point de vue de la communication. Une situation nouvelle peut alors se d\u00e9gager, bas\u00e9e sur la communication justement, et qui deviendrait un frein puissant \u00e0 toute initiative belliqueuse lourde li\u00e9e directement ou indirectement \u00e0 la crise des antimissiles. Le syst\u00e8me de la communication confirme une fois de plus son caract\u00e8re tr\u00e8s ambivalent et tr\u00e8s vari\u00e9 dans ses effets, selon qui en use (\u00e0 peu pr\u00e8s ce que nous nommons son caract\u00e8re <a href=\"http:\/\/www.dedefensa.org\/article-dialogues-13_de_la_sublimite_du_systeme_de_la_communication_08_11_2010.html\" class=\"gen\">Janus<\/a>). Dans ce cas qui montre son utilisation extensive par eux, le syst\u00e8me de la communication deviendrait aux mains des Russes une dynamique antiSyst\u00e8me, puisque capable de freiner les projets antimissiles US qui sont directement enfant\u00e9s par le Syst\u00e8me.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 9 avril 2012 \u00e0 09H06<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La crise des antimissiles, miroir de l&rsquo;\u00e9poque La crise quasi-perp\u00e9tuelle des euromissiles, BMDE pour l&rsquo;Europe, ou GBMD pour la dimension globale, tr\u00e8s larv\u00e9e de 2008 \u00e0 la mi-2011, est revenue au premier plan de l&rsquo;actualit\u00e9, \u00e0 cause des pressions US (du complexe militaro-industriel) pour l&rsquo;extension de la chose, \u00e0 l&rsquo;occasion d&rsquo;un affaiblissement notable du pouvoir&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4056,4646,2870,4314,3015,2631,14754,3723,2773,2622,2730,14755,14753,3014,4268],"class_list":["post-74633","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-antimissiles","tag-antisysteme","tag-attaque","tag-bmde","tag-communication","tag-de","tag-gbmd","tag-golfe","tag-iran","tag-la","tag-russie","tag-secrets","tag-seminaire","tag-systeme","tag-technologisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74633"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74633\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}