{"id":74664,"date":"2012-04-23T15:03:07","date_gmt":"2012-04-23T15:03:07","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/04\/23\/evidemment\/"},"modified":"2012-04-23T15:03:07","modified_gmt":"2012-04-23T15:03:07","slug":"evidemment","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/04\/23\/evidemment\/","title":{"rendered":"Evidemment"},"content":{"rendered":"<p><h4>Evidemment<\/h4>\n<p>Communiqu\u00e9 n\u00b0 1374, jeudi <a href=\"http:\/\/www.in-nocence.org\/index.php?page=communiques\" class=\"gen\">18 avril 2012<\/a>. Sur la situation \u00e9ditoriale de Renaud Camus :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Le parti de l&rsquo;In-nocence informe les personnes qui suivent habituellement ses communiqu\u00e9s et s&rsquo;int\u00e9ressent d&rsquo;une mani\u00e8re ou d&rsquo;une autre aux diverses publications de son pr\u00e9sident, Renaud Camus, que les \u00e9ditions Fayard, comme avant elles les \u00e9ditions P.O.L, viennent de prendre la d\u00e9cision de ne pas renouveler les contrats qui les lient \u00e0 cet \u00e9crivain. Les lecteurs de Renaud Camus doivent donc s&rsquo;attendre \u00e0 devoir, apr\u00e8s l&rsquo;ex\u00e9cution des contrats en cours, prendre connaissance de ses \u00e9crits par d&rsquo;autres voies, pas n\u00e9cessairement \u00e9ditoriales.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEvidemment , rien ne dit que la d\u00e9cision est li\u00e9e au r\u00e9cent ralliement de Renaud Camus \u00e0 la candidature de Marine Le Pen.<\/p>\n<\/p>\n<p>\n<p class=\"signature\"><em>GEO<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evidemment Communiqu\u00e9 n\u00b0 1374, jeudi 18 avril 2012. Sur la situation \u00e9ditoriale de Renaud Camus : \u00abLe parti de l&rsquo;In-nocence informe les personnes qui suivent habituellement ses communiqu\u00e9s et s&rsquo;int\u00e9ressent d&rsquo;une mani\u00e8re ou d&rsquo;une autre aux diverses publications de son pr\u00e9sident, Renaud Camus, que les \u00e9ditions Fayard, comme avant elles les \u00e9ditions P.O.L, viennent de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[2956,14778,8809,14777,2955],"class_list":["post-74664","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-camus","tag-fayard","tag-geo","tag-lepen","tag-renaud"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74664"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74664\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}