{"id":74676,"date":"2012-04-28T08:59:06","date_gmt":"2012-04-28T08:59:06","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/04\/28\/de-la-france-et-de-leurope-face-au-pietre-diktat-euro-allemand\/"},"modified":"2012-04-28T08:59:06","modified_gmt":"2012-04-28T08:59:06","slug":"de-la-france-et-de-leurope-face-au-pietre-diktat-euro-allemand","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/04\/28\/de-la-france-et-de-leurope-face-au-pietre-diktat-euro-allemand\/","title":{"rendered":"De la France et de l&rsquo;Europe, face au pi\u00e8tre <em>diktat<\/em> euro-allemand"},"content":{"rendered":"<p><h3 class=\"titrebloc\">De la France et de l&rsquo;Europe, face au pi\u00e8tre <em>diktat<\/em> euro-allemand<\/h3>\n<\/p>\n<p><p>\tUn titre : \u00ab<em>France&rsquo;s Francois Hollande and Germany&rsquo;s Angela Merkel clash over euro austerity pact<\/em>\u00bb, celui d&rsquo;un article de Emma Rowlet, dans le <em>Daily Telegraph<\/em> du <a href=\"http:\/\/www.telegraph.co.uk\/finance\/financialcrisis\/9232472\/Frances-Francois-Hollande-and-Germanys-Angela-Merkel-clash-over-euro-austerity-pact.html\" class=\"gen\">27 avril 2012<\/a>, mis en ligne hier en fin d&rsquo;apr\u00e8s-midi \u00e0 18H35. L&rsquo;article reste assez impr\u00e9cis sur les conditions de ce qu&rsquo;il d\u00e9signe comme un <em>clash<\/em>, mais il semble qu&rsquo;il s&rsquo;appuie sur, d&rsquo;une part des d\u00e9clarations de Hollande plus ou moins interpr\u00e9t\u00e9es, d&rsquo;autre part sur des d\u00e9clarations de Merkel faites \u00e0 la presse allemande (sans pr\u00e9cisions)  Quoi qu&rsquo;il en soit, l&rsquo;esprit de la chose est bien l\u00e0.<\/p>\n<\/p>\n<p><p>\tQuoi qu&rsquo;il en soit, en effet, tout se passe comme s&rsquo;il semblait de plus en plus acquis, en termes de communication dans le vaste champ de la situation de crise d&rsquo;Europe (crise de l&rsquo;existence d&rsquo;un concept nomm\u00e9 Europe, de plus en plus \u00e9vanescent et en pleine dissolution), que, Hollande \u00e9tant \u00e9lu selon l&rsquo;hypoth\u00e8se dominante, le premier acte de sa pr\u00e9sidence serait \u00e9galement son premier affrontement, direct, pressant, peut-\u00eatre m\u00eame g\u00e9n\u00e9rateur de l&rsquo;acc\u00e9l\u00e9ration et de la pr\u00e9cipitation d&rsquo;une nouvelle phase de la crise europ\u00e9enne. D&rsquo;autre part et si la perception qu&rsquo;on en a se confirme, ce qui appara\u00eet comme une  intrusion directe de l&rsquo;Allemagne dans la campagne \u00e9lectorale fran\u00e7aise devrait contribuer \u00e0 tendre consid\u00e9rablement les conditions de cette fin de campagne, m\u00eame si d&rsquo;une fa\u00e7on inconsciente qui ne serait pas n\u00e9cessairement exprim\u00e9e par les candidats. Cette perception devrait \u00e9voluer dramatiquement, selon laquelle il ne s&rsquo;agit plus seulement d&rsquo;un affrontement franco-fran\u00e7ais, mais d&rsquo;un un affrontement de la France avec l&rsquo;Allemagne arcbout\u00e9e sur la bureaucratie europ\u00e9enne, c&rsquo;est-\u00e0-dire un affrontement o\u00f9 la crise de l&rsquo;Europe mais aussi, du point de vue fran\u00e7ais, la souverainet\u00e9 de la France, sont devenus des facteurs d\u00e9cisifs <strong>voyants<\/strong>, des facteurs de communication mettant dramatiquement en \u00e9vidence la r\u00e9alit\u00e9 de l&rsquo;\u00e9v\u00e8nement. D&rsquo;un autre c\u00f4t\u00e9, la perception serait de plus en plus celle d&rsquo;une dictature euro-allemande, elle-m\u00eame sans la l\u00e9gitimit\u00e9 n\u00e9cessaire, mena\u00e7ant de peser sur la France,  mais aussi sur les autres nations et peuples de l&rsquo;Europe. Un bilan exaltant<\/p>\n<\/p>\n<p><p>\t\u00ab<em>It is not for Germany to decide for the rest of Europe, said Francois Hollande, the frontrunner to replace Nicolas Sarkozy as French president. If elected, Mr Hollande says that he will not pass the fiscal austerity pact agreed by the leaders of 25 European nations, unless it contains measures to spur on growth.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>His stance puts him on a collision course with Angela Merkel, the German Chancellor. She hit back at the French Socialist candidate&rsquo;s plans, warning the deal is not open to new negotiations. The fiscal pact is negotiated, it was signed by 25 government leaders and has already been ratified by Portugal and Greece, she told a German newspaper. Parliaments across Europe are on the verge of passing it. Ireland is having a referendum at the end of May.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tPour ajouter \u00e0 la tension, l&rsquo;article introduit deux autres \u00e9l\u00e9ments qui sont, chacun de leur c\u00f4t\u00e9, nettement illustratifs des positions extr\u00eames des uns et des autres dans cet aspect de la crise directement li\u00e9 \u00e0 l&rsquo;\u00e9lection pr\u00e9sidentielle fran\u00e7aise. Il s&rsquo;agit d&rsquo;une part d&rsquo;une intervention concert\u00e9e du Premier ministre italien Monti, eurocrate plac\u00e9 par l&rsquo;UE et l&rsquo;Allemagne \u00e0 ce poste comme un v\u00e9ritable proconsul de la mission g\u00e9n\u00e9rale d&rsquo;aust\u00e9rit\u00e9 caract\u00e9risant la politique europ\u00e9enne, et du pr\u00e9sident de la Commission europ\u00e9enne Barroso, autre s\u00e9duisant acteur de l&rsquo;op\u00e9ration, r\u00e9citant le <em>diktat<\/em> de sa bureaucratie et des objurgations autoritaires de la chanceli\u00e8re allemande ; il s&rsquo;agit d&rsquo;autre part de la position d\u00e9licate et de plus en plus affaiblie de la m\u00eame, Merkel, avec une opposition qui se durcit sur cette question de la politique d&rsquo;aust\u00e9rit\u00e9, et qui lie directement cette \u00e9volution \u00e0 l&rsquo;arriv\u00e9e probable de Hollande \u00e0 la pr\u00e9sidence. M\u00eame les dictateurs, dans ce temps du triomphe de l&rsquo;autodestruction du Syst\u00e8me, tiennent des positions falotes et assi\u00e9g\u00e9es par la mar\u00e9e montante. Ils sont <strong>les esclaves<\/strong> des \u00e9v\u00e8nements qu&rsquo;ils ont eux-m\u00eames suscit\u00e9s et qu&rsquo;ils alimentent avec la fi\u00e8vre de la derni\u00e8re chance.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>In an apparent rebuke to Mr Hollande, Italy&rsquo;s technocrat leader Mario Monti and European Commission chief Jose Manuel Barroso made a joint statement in which they criticised debt-fuelled growth measures. We agreed that the revival of growth must come through a relentless focus on improving competitiveness and not through higher levels of debt, they said after a meeting.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>However, Ms Merkel faced trouble at home as opposition politicians joined Mr Hollande in his bid to make the austerity pact more flexible. They complain that the one-size-fits-all rules do not suit Germany&rsquo;s individual states and municipalities.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;arri\u00e8re-plan de cet affrontement autour du deuxi\u00e8me tour des pr\u00e9sidentielles fran\u00e7aise n&rsquo;est fait que de crises nationales, avec la chute dramatique du gouvernement hollandais dimanche dernier et des \u00e9lections anticip\u00e9es qui risquent d&rsquo;aggraver encore une impasse, sinon une d\u00e9cision de retrait de l&rsquo;euro, avec la probabilit\u00e9 d&rsquo;un r\u00e9sultat accentuant une majorit\u00e9 parlementaire oppos\u00e9e aux mesures d&rsquo;aust\u00e9rit\u00e9 exig\u00e9es par la politique g\u00e9n\u00e9rale euro-allemande ; avec la chute, hier, du gouvernement roumain, qui n&rsquo;a pas obtenu le soutien du Parlement pour ces m\u00eames mesures d&rsquo;aust\u00e9rit\u00e9 ; avec l&rsquo;aggravation, notamment, de la situation espagnole, avec r\u00e9duction de deux niveaux de la cotation de l&rsquo;Espagne par l&rsquo;agence Standard &#038; Poor&rsquo;s, et de la situation irlandaise, avec une perspective de croissance r\u00e9duite de 1,3% \u00e0 0,7%. (Tout cela, pour la chronique imm\u00e9diate des quelques jours pass\u00e9s.) L&rsquo;aggravation des situations nationales comme cons\u00e9quences du plan euro-allemand est la marque, non pas de l&rsquo;aggravation de la crise europ\u00e9enne, mais de sa possible transformation de crise conjoncturelle d&rsquo;un ensemble encore maintenu dans cet \u00e9tat, en une crise de rupture de cet ensemble.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est dans ce contexte qu&rsquo;intervient l&rsquo;\u00e9lection pr\u00e9sidentielle fran\u00e7aise, ou, plut\u00f4t, dirait-on qu&rsquo;elle en constitue l&rsquo;\u00e9l\u00e9ment acc\u00e9l\u00e9rateur majeur. D&rsquo;ores et d\u00e9j\u00e0, dans le climat de cette \u00e9lection, avec des votes antiSyst\u00e8me au premier tour atteignant 35% de l&rsquo;\u00e9lectorat exprim\u00e9, l&rsquo;on peut dire que les deux candidats, chacun \u00e0 leur fa\u00e7on, sont de plus en plus enferm\u00e9s dans une n\u00e9cessit\u00e9 de r\u00e9action dans ce m\u00eame sens. C&rsquo;est le cas du probable vainqueur, Hollande, dont l&rsquo;\u00e9lection devient de plus en plus celle du refus du pacte de stabilit\u00e9, se transformant plus directement et d&rsquo;une fa\u00e7on plus imm\u00e9diatement confrontationnelle, en un refus du <em>diktat<\/em> euro-allemand, et cela, dans la perception qu&rsquo;on en a et <strong>quoiqu&rsquo;en veuille le candidat<\/strong> ; c&rsquo;est le cas de l&rsquo;improbable vainqueur, Sarkozy, qui ne pourrait l&rsquo;\u00eatre que par surprise et par d\u00e9faut de son adversaire, mais qui le serait alors selon <strong>une obligation<\/strong> d&rsquo;un durcissement consid\u00e9rable de sa position vis-\u00e0-vis de la politique euro-allemande puisqu&rsquo;il aurait \u00e9t\u00e9 \u00e9lu par un report massif (bien improbable, lui aussi) des voix du FN, exprimant plus que jamais le rejet de la politique euro-allemande. Les \u00e9v\u00e8nements <strong>m\u00e8nent<\/strong> d\u00e9sormais cette campagne et l&rsquo;aggravation acc\u00e9l\u00e9r\u00e9e de la crise g\u00e9n\u00e9rale, sans que l&rsquo;on puisse v\u00e9ritablement r\u00e9agir, et ils vont d\u00e9sormais dans le sens de la rupture.<\/p>\n<\/p>\n<p><p>\tAu-dessus de tout cela plane, pour les Fran\u00e7ais, et donc pour les candidats, la perception que le principe de la souverainet\u00e9 nationale (ce qu&rsquo;il en reste) est, dans cette \u00e9lection (<em>dito<\/em>, dans cette crise), l&rsquo;enjeu majeur. L&rsquo;\u00e9lection fran\u00e7aise, avec les crises collat\u00e9rales dans d&rsquo;autres pays europ\u00e9ens, a dramatis\u00e9 et port\u00e9 \u00e0 son paroxysme la situation qui met en opposition directe et confrontationnelle le principe de la souverainet\u00e9 et la politique du <em>diktat<\/em> euro-allemande. On ajoutera que m\u00eame les apprentis dictateurs europ\u00e9ens, que ce soit les eurocrates europ\u00e9ens ou une Merkel \u00e0 la fois autoritariste allemande et menac\u00e9e d&rsquo;\u00eatre mise en minorit\u00e9 dans son pays, s&rsquo;appuient sur une autorit\u00e9 d\u00e9faillante, c&rsquo;est-\u00e0-dire une l\u00e9gitimit\u00e9 quasiment nulle, autant dans son principe totalement faussaire dans ce cas, que dans la situation conjoncturelle. Il y aura un troisi\u00e8me tour en France, avec les l\u00e9gislatives qui seront bien plus qu&rsquo;un tour d&rsquo;enregistrement du scrutin pr\u00e9sidentiel (qui pour le confirmer, qui pour l&rsquo;\u00e9quilibrer), qui seront en r\u00e9alit\u00e9 l&rsquo;\u00e9v\u00e8nement pr\u00e9parateur ou accompagnateur du quatri\u00e8me tour,  c&rsquo;est-\u00e0-dire la crise europ\u00e9enne arriv\u00e9e \u00e0 sa maturit\u00e9 explosive et rupturielle, et peut-\u00eatre d\u00e9j\u00e0 d\u00e9clench\u00e9e parall\u00e8lement. Ce n&rsquo;est plus la crise de l&rsquo;euro ou la crise de la finance, c&rsquo;est-\u00e0-dire une crise interne au Syst\u00e8me, mais bien la crise des peuples, c&rsquo;est-\u00e0-dire une crise antiSyst\u00e8me,  <em>dito<\/em>, les peuples contre le Syst\u00e8me. Au moins, il n&rsquo;est plus question d&rsquo;artifice et l&rsquo;on sait d\u00e9sormais de quoi il est question.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 28 avril 2012 \u00e0 08H58<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De la France et de l&rsquo;Europe, face au pi\u00e8tre diktat euro-allemand Un titre : \u00abFrance&rsquo;s Francois Hollande and Germany&rsquo;s Angela Merkel clash over euro austerity pact\u00bb, celui d&rsquo;un article de Emma Rowlet, dans le Daily Telegraph du 27 avril 2012, mis en ligne hier en fin d&rsquo;apr\u00e8s-midi \u00e0 18H35. L&rsquo;article reste assez impr\u00e9cis sur les&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4646,9129,4335,5863,7784,398,3203,3555,4633,11975,4590,2746,5866,5630],"class_list":["post-74676","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-antisysteme","tag-austerite","tag-barroso","tag-dictature","tag-diktat","tag-europe","tag-hollande","tag-legitimite","tag-merkel","tag-monti","tag-sarkozy","tag-souverainete","tag-tour","tag-troisieme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74676"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74676\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}