{"id":74684,"date":"2012-05-02T12:31:50","date_gmt":"2012-05-02T12:31:50","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/05\/02\/le-f-22-menace-liran-selon-lhumeur-des-pilotes\/"},"modified":"2012-05-02T12:31:50","modified_gmt":"2012-05-02T12:31:50","slug":"le-f-22-menace-liran-selon-lhumeur-des-pilotes","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/05\/02\/le-f-22-menace-liran-selon-lhumeur-des-pilotes\/","title":{"rendered":"Le F-22 menace l&rsquo;Iran, \u2013 selon l&rsquo;humeur des pilotes&#8230;"},"content":{"rendered":"<p><h2 class=\"common-article\">Le F-22 menace l&rsquo;Iran, \u00a0selon l&rsquo;humeur des pilotes&#8230;<\/h2>\n<\/p>\n<p><p>\t2 mai 2012  La semaine derni\u00e8re, la nouvelle filtrait discr\u00e8tement, mais avec une discr\u00e9tion suffisamment ostentatoire pour qu&rsquo;on en soit inform\u00e9 : l&rsquo;USAF a d\u00e9ploy\u00e9 quelques exemplaires de son F-22 <em>Raptor<\/em> sur une base des Emirats Arabes Unis (EAU). (En g\u00e9n\u00e9ral, la presse-Syst\u00e8me d\u00e9crit le F-22 comme le <em>super-jet<\/em> ind\u00e9tectable, sinon invisible, de l&rsquo;USAF, et comme l&rsquo;avion de combat le plus puissant du monde ; ainsi tout est-il dit et sommes-nous rassur\u00e9s sur la p\u00e9rennit\u00e9 de cette puissance qui veille sur notre pr\u00e9cieuse civilisation.)  C&rsquo;est-\u00e0-dire que les F-22 sont \u00e0 distance acceptable de l&rsquo;Iran, pour figurer un renforcement hautement sophistiqu\u00e9 des forces US assembl\u00e9es dans la r\u00e9gion, face \u00e0 et autour de l&rsquo;Iran.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est le <a href=\"http:\/\/www.aviationweek.com\/Blogs.aspx?plckBlogId=Blog:27ec4a53-dcc8-42d0-bd3a-01329aef79a7&#038;plckPostId=Blog:27ec4a53-dcc8-42d0-bd3a-01329aef79a7Post:5a7a4dc2-52cf-4181-a1cb-32ab63d03fa2\" class=\"gen\">26 avril 2012<\/a> qu&rsquo;Amy Butler, d&rsquo;<em>Aviation Week &#038; Space Technology<\/em>, avait annonc\u00e9 la nouvelle du d\u00e9ploiement. Les termes \u00e9taient mesur\u00e9s et sans surprise. \u00ab<em>As tensions between Iran and the U.S. and Israel continue to mount over the former&rsquo;s pursuit of nuclear weapons technologies, the U.S. has quietly begun a deployment of its premier stealthy fighter, the twin-engine F-22, to the nearby United Arab Emirates.<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\tLe <a href=\"http:\/\/rt.com\/news\/us-deploying-jet-fighters-gulf-242\/\" class=\"gen\">28 avril 2012<\/a>, <em>Russia Today<\/em> reprenait l&rsquo;information, en insistant sur son aspect op\u00e9rationnel par rapport \u00e0 la situation de la crise. RT s&rsquo;adressait au commentateur US Jason Ditz, de <em>Antiwar.com<\/em>. \u00ab<em> If anything, it&rsquo;s going to increase tensions in the region, convince the Iranian government that next month&rsquo;s talks in Baghdad are not serious, and that the US is simply negotiating in bad faith once again, Ditz told RT. He noted that while the US and Israel were unlikely to launch an attack on Iran in the coming months, the move was nonetheless meant to be a provocation. The fact that they&rsquo;re rumored to be organizing a simulated attack on Iran, with the cooperation of Israel, would certainly be a strong symbolic move  particularly since it&rsquo;s supposed to come just two months ahead of the Baghdad talks, Ditz added.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDe son c\u00f4t\u00e9, <em>DEBKAFiles<\/em> ne manquait pas de commenter la nouvelle, d&rsquo;abord dans une analyse du <a href=\"http:\/\/www.debka.com\/article\/21955\/\" class=\"gen\">28 avril 2012<\/a>, o\u00f9 la chose \u00e9tait pr\u00e9sent\u00e9e comme un renforcement d\u00e9cisif des forces US dans le Golfe, et donc un signe important de la d\u00e9termination US sur le plan militaire, face \u00e0 l&rsquo;Iran. Plus encore, des d\u00e9tails \u00e9taient donn\u00e9s sur la mission des F-22, en m\u00eame temps que ces appareils se trouvaient plac\u00e9s dans la perspective du renforcement US g\u00e9n\u00e9ral. (C&rsquo;est une habitude du site, en g\u00e9n\u00e9ral assez [tr\u00e8s] critique de la mollesse, sinon de la trahison US par rapport aux intentions d&rsquo;attaque de l&rsquo;Iran. Lorsque la d\u00e9termination isra\u00e9lienne se trouve confront\u00e9e \u00e0 de graves probl\u00e8mes int\u00e9rieurs,  et ils ne l&rsquo;ont jamais \u00e9t\u00e9 <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_guerre_civile_isra_lienne_28_04_2012.html\" class=\"gen\">autant<\/a> \u00e0 <a href=\"http:\/\/www.dedefensa.org\/article-bibi_est-il_la_vraie_menace_existentielle_contre_isra_l__02_05_2012.html\" class=\"gen\">cet \u00e9gard<\/a>,  elle reporte son affection sur l&rsquo;affirmation d&rsquo;une soudaine et miraculeuse r\u00e9surgence de la d\u00e9termination US.) <\/p>\n<\/p>\n<p><p>\t\u00ab[<em>The F-22&rsquo;s mission<\/em>] <em> will be to destroy the Iranian air force and air defense batteries so as to clear the way for US and Israeli bombers to go into action against Iran&rsquo;s nuclear sites and the strategic infrastructure of its army and Revolutionary Guards Corps.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>This unprecedented US buildup of air might &#8211; supplementing the aircraft on the decks of the USS Abraham Lincoln and USS Enterprise, to be joined by a third carrier as soon as the offensive gets underway  shows Tehran that the Obama administration is serious about using military means as extra pressure on Iran to give way in diplomatic negotiations  both with the six powers and with the US through clandestine channels.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe <a href=\"http:\/\/www.debka.com\/article\/21964\/\" class=\"gen\">1er mai 2012<\/a>, \u00e0 nouveau <em>DEBKAFiles<\/em>, \u00e0 nouveau dans sa d\u00e9marche de pr\u00e9senter la miraculeuse renaissance de la d\u00e9termination US, cette fois \u00e9tendue \u00e0 des nouvelles triomphales concernant le r\u00e9seau antimissiles BMDE, tout cela puisque, comme on l&rsquo;a vu, les choses ne s&rsquo;arrangent toujours pas en Isra\u00ebl. On y ajoutera quelques consid\u00e9rations iraniennes sur le F-22, quelque peu conflictuelles, et dont on va s&rsquo;apercevoir qu&rsquo;il s&rsquo;agit d&rsquo;une incertitude qui affecte l&rsquo;avion lui-m\u00eame, et, par cons\u00e9quent, la valeur op\u00e9rationnelle de son d\u00e9ploiement.  <\/p>\n<\/p>\n<p><p>\t\u00ab<em>There was also an outpouring of comment from Tehran about last week&rsquo;s deployment of US F-22 Raptors in the UAE&rsquo;s Al Dhafra Air Base opposite Iran&rsquo;s southern shores. One spokesman said they posed no danger to Iran and had been moved in for psychological warfare; another that they threatened regional security and Gulf nations should not allow foreign armies to take up position on their shores.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>A week after the F-22 squadron was deployed in the Gulf, Elizabeth Sherwood-Randall, special assistant to President Obama and senior director for European affairs at the National Security Council, disclosed Monday that the completion of the initial phase of the US-backed missile network in Europe would be announced at the NATO summit meeting in Chicago on May 20. She added that additional work is underway in the next phase of the network, designed for protecting Europe and the Middle East from Iranian ballistic missile attack.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tMais voici soudain une intrusion du dehors, nous voulons dire, du dehors de la <em>narrative<\/em> de la crise iranienne. Elle vient du <em>blog<\/em> de Stephen Trimble, <em>DEW Line<\/em>, de <em>FlightGlobal.com<\/em>, sous la plume de Dave Majumdar, correspondant aux USA (le <a href=\"http:\/\/www.flightglobal.com\/blogs\/the-dewline\/2012\/05\/some-f-22-pilots-asking-not-to.html\" class=\"gen\">1er mai 2012<\/a>). La nouvelle concerne le F-22, sa v\u00e9rit\u00e9 op\u00e9rationnelle disons, et une humeur sans pr\u00e9c\u00e9dent des pilotes de l&rsquo;USAF. Ce que nous conte Majumbar, sans dire un mot de commentaire sur ce constat, c&rsquo;est une situation sans pr\u00e9c\u00e9dent dans l&rsquo;USAF, et dans aucune force a\u00e9rienne s\u00e9rieuse. (Et nous prions nos lecteurs de noter les diff\u00e9rentes formulations employ\u00e9es, entre demandant de [ne pas piloter le F-22],  et refusant de [piloter le F-22], que nous soulignons en gras) (<em>Russia Today<\/em> signale \u00e9galement cet incident, avec un texte dat\u00e9 du <a href=\"http:\/\/rt.com\/usa\/news\/f-22-us-oxygen-363\/\" class=\"gen\">1er mai 2012<\/a>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Some F-22 pilots<\/em> <strong><em>asking<\/em><\/strong> <MI>not to fly the jet<\/p>\n<\/p>\n<p><p>\t\u00bb<em>While I was unable to attend this (30 April) morning&rsquo;s briefing at Joint Base Langley-Eustis down in Hampton, Virginia, press reports from the event indicate that the US Air Force is admitting that a small number of Lockheed Martin F-22 Raptor pilots are<\/em> <strong><em>refusing<\/em><\/strong> <em>to fly the jet. Obviously it&rsquo;s a very sensitive thing because we are trying to ensure that the community fully understands all that we&rsquo;re doing to try to get to a solution, says Air Combat Command chief Gen Mike Hostage as quoted by the Associated Press.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The USAF has not found the root cause of 11 hypoxia-like cases since the Raptor fleet returned to flight in September after a near five-month stand-down.  The F-22 fleet has flown about 12,000 times since then. Incidentally, I had known that several pilots were planning on<\/em> <strong><em>asking not to fly<\/em><\/strong> <em>the Raptor for weeks, but could not report it because it might compromise the sources. I had asked USAF PA to confirm on the record&#8211;this appears to be it.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Hostage told the assembled reporters at Langley that he would get himself checked out in the Raptor and fly the jet until the cause of the F-22&rsquo;s oxygen woes are discovered and fixed. I&rsquo;m going to check out and fly the airplane so I can understand exactly what it is they&rsquo;re dealing with. The day we figure out what the problem is I will stop flying because we don&rsquo;t have enough sorties for all of our combat aviators to get as much training as they need, Hostage says  via AP.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCes nouvelles sont ironiques et pleines de contradictions charmantes qui si\u00e9ent \u00e0 notre \u00e9poque, mais aussi notablement alarmantes et significatives de l&rsquo;effondrement du Syst\u00e8me,  dans ce cas, un signe d&rsquo;autant plus int\u00e9ressant qu&rsquo;il para\u00eetrait mineur, mais qu&rsquo;il est en v\u00e9rit\u00e9, confront\u00e9 avec les grandes tendances qui vont dans le m\u00eame sens, une illustration puissante, parce que concr\u00e8te et imm\u00e9diatement accessible \u00e0 l&rsquo;entendement, de la <strong>v\u00e9rit\u00e9<\/strong> des choses, hors des <em>narratives<\/em> convenues. Cette attitude des pilotes de l&rsquo;USAF est tout simplement sans pr\u00e9c\u00e9dent ; en temps normal, elle rel\u00e8verait de l&rsquo;insubordination grave, et devrait \u00eatre trait\u00e9e comme telle. Mais les temps ne sont pas normaux du tout, et, derri\u00e8re le cas, il y a une position extraordinairement fautive et faite d&rsquo;une volont\u00e9 \u00e9chevel\u00e9e de l&rsquo;USAF de maintenir, au risque des plus graves d\u00e9boires, l&rsquo;apparence de la puissance malgr\u00e9 qu&rsquo;elle soit soumise \u00e0 une mise en cause radicale ; derri\u00e8re le cas, il y a une situation de d\u00e9cadence non moins extraordinaire de l&rsquo;USAF, cette puissance accoutum\u00e9e \u00e0 \u00eatre l&rsquo;incontest\u00e9e ma\u00eetresse des cieux du monde ; et une d\u00e9cadence autant quantitative que qualitative, selon ses normes qualitatives de fonctionnement.<\/p>\n<h3>L&rsquo;USAF, \u00e9l\u00e8ve-mod\u00e8le du processus surpuissance-autodestruction<\/h3>\n<\/p>\n<p><p>\tD\u00e9veloppons notre commentaire en plusieurs points, en partant des derniers faits que nous avons cit\u00e9s, en apparence assez \u00e9loign\u00e9s de la situation de la crise iranienne. L&rsquo;on verra que nous retrouverons \u00e9videmment, au terme du commentaire, cette situation de la crise iranienne puis, au-del\u00e0, une situation g\u00e9n\u00e9rale illustrative de la crise du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\t Le premier fait, fondamental, est que le <em>super-jet<\/em>&lsquo; ind\u00e9tectable, sinon invisible, de l&rsquo;USAF, et [] l&rsquo;avion de combat le plus puissant du monde <strong>ne marche pas<\/strong>, tout simplement. Outre divers probl\u00e8mes de fonctionnement g\u00e9n\u00e9raux, il est confront\u00e9 \u00e0 <a href=\"http:\/\/www.dedefensa.org\/article-l_etrange_cas_du_f-22_13_07_2011.html\" class=\"gen\">un probl\u00e8me<\/a> sp\u00e9cifique que l&rsquo;USAF ne parvient pas \u00e0 r\u00e9soudre, malgr\u00e9 deux <a href=\"http:\/\/www.dedefensa.org\/article-l_usaf_entre_l_iran_et_le_f-22_01_03_2012.html\" class=\"gen\">interdictions de vol<\/a> et les examens intensifs qui l&rsquo;accompagnent. Ce probl\u00e8me concerne le syst\u00e8me en alimentation en oxyg\u00e8ne des pilotes, qui est en service sur d&rsquo;autres avions des forces arm\u00e9es US (USAF et Navy) et n&rsquo;interdit pas \u00e0 ces avions de voler, ni n&rsquo;invite leurs pilotes \u00e0 refuser de les piloter. Sur le F-22, dans cette monstruosit\u00e9 informatique faites de millions de lignes code o\u00f9 l&rsquo;un ou l&rsquo;autre <em>buzz<\/em> s&rsquo;est gliss\u00e9, on ne parvient pas \u00e0 r\u00e9soudre ce probl\u00e8me qui, en d&rsquo;autres temps, ne serait qu&rsquo;un probl\u00e8me m\u00e9canique de fonctionnement. Pourtant l&rsquo;USAF a mis \u00e0 nouveau sa flotte de F-22 en service, ce qui est incontestablement une audacieuse et coupable prise de risque puisque cette question de l&rsquo;alimentation en oxyg\u00e8ne affecterait gravement la sant\u00e9 des pilotes et aurait m\u00eame cout\u00e9 la vie \u00e0 l&rsquo;un d&rsquo;eux (cette panne serait la cause de la perte d&rsquo;un F-22, avec mort du pilote, en Alaska il y a plus d&rsquo;un an).<\/p>\n<\/p>\n<p><p>\t Bien Si l&rsquo;USAF a pris ce risque, comme on l&rsquo;a sugg\u00e9r\u00e9 plus haut, c&rsquo;est parce qu&rsquo;elle veut maintenir l&rsquo;apparence de la puissance sans exemple des avions de combat modernes (dit de cinqui\u00e8me g\u00e9n\u00e9ration), ces usines \u00e0 gaz d&rsquo;informatique, sur lesquels elle a fond\u00e9 toute son existence et, surtout, son avenir et sa p\u00e9rennit\u00e9. Si le F-22 ne marche pas (ce qui est le cas), que reste-t-il de la puissance \u00e0 venir de l&rsquo;USAF ? L&rsquo;on sait que le programme F-35 (JSF), la super usine \u00e0 gaz d&rsquo;informatique bien pire que le F-22, est en chute libre, sans le moindre contr\u00f4le, en attendant le <em>crash<\/em> final. L&rsquo;on sait que les conditions budg\u00e9taires sont ce qu&rsquo;on en conna\u00eet et qu&rsquo;il faut faire avec ce qui est cours ; d&rsquo;ici \u00e0 ce qu&rsquo;on force l&rsquo;USAF \u00e0 racheter des F-16 d&rsquo;occasion \u00e0 la Hollande ou \u00e0 la Pologne pour boucher les trous&#8230; Il faut donc que le F-22 vole, ou donne l&rsquo;impression de voler, par ailleurs bourr\u00e9 de restrictions diverses qui font du plus puissant avion de combat du monde un handicap\u00e9 profond aux r\u00e9actions erratiques et au fonctionnement poussif. On en est \u00e0 un tel degr\u00e9 de rocambolesque que le g\u00e9n\u00e9ral Hostage, chef de l&rsquo;Air Combat Command, annonce qu&rsquo;il va voler lui-m\u00eame sur le F-22 pour comprendre le probl\u00e8me qu&rsquo;affrontent ses pilotes Comprendre, <em>k\u00e9sako<\/em> ? Qu&rsquo;y a-t-il \u00e0 comprendre lorsqu&rsquo;il s&rsquo;agit simplement de r\u00e9aliser que le syst\u00e8me d&rsquo;alimentation en oxyg\u00e8ne fonctionne mal et vous intoxique, ou vous conduit \u00e0 une syncope en pleine mission de combat ? Pauvre g\u00e9n\u00e9ral Hostage, le bien nomm\u00e9, otage du F-22 et de ses pilotes r\u00e9calcitrants.<\/p>\n<\/p>\n<p><p>\t Car les pilotes ne sont plus preneurs Situation sans pr\u00e9c\u00e9dent \u00e0 tous \u00e9gards, dans un milieu o\u00f9 c&rsquo;est un privil\u00e8ge formidable de pouvoir voler \u00e0 bord des avions les plus avanc\u00e9s de la flotte. Mais non, les pilotes refusent, et on ne leur dit rien. Il y a une bonne raison \u00e0 cette acceptation sans pli d&rsquo;une situation qui ressemble \u00e0 une r\u00e9volte dans la communaut\u00e9 (des pilotes de combat US), comme dit le g\u00e9n\u00e9ral Hostage, avec un langage tr\u00e8s tendance. L&rsquo;USAF sait parfaitement qu&rsquo;elle fait voler les F-22 dans des conditions tr\u00e8s p\u00e9rilleuses, et que le moindre incident peut avoir des cons\u00e9quences graves, et m\u00eame des cons\u00e9quences juridiques. Ainsi en est-il pour le pilote tu\u00e9 lors de l&rsquo;accident en Alaska. Apr\u00e8s les r\u00e9v\u00e9lations concernant le malfonctionnement du syst\u00e8me d&rsquo;alimentation en oxyg\u00e8ne, la femme du pilote a d\u00e9cid\u00e9 de porter plainte contre l&rsquo;USAF. Horrible perspective, si l&rsquo;USAF \u00e9tait condamn\u00e9e, si d&rsquo;autres accidents du m\u00eame genre survenaient Ainsi en arrive-t-on \u00e0 la situation <em>de facto<\/em>, rocambolesque et absurde pour une force a\u00e9rienne, o\u00f9 ne volent \u00e0 bord des F-22 que des volontaires (leur fait-on signer un engagement \u00e0 ne pas engager de poursuites en cas d&rsquo;incident \u00e0 bord du F-22 ou bien choisit-on des orphelins-c\u00e9libataires ?). On comprend ce qu&rsquo;il peut rester de discipline au sein de la communaut\u00e9 des pilotes de combat qui se voient reconna\u00eetre le droit de refuser de voler \u00e0 bord des avions qui leur sont affect\u00e9s, portant ainsi un jugement souverain sur les biens choisit par l&rsquo;autorit\u00e9 supr\u00eame pour la d\u00e9fense nationale<\/p>\n<\/p>\n<p><p>\t Ainsi en revient-on \u00e0 la situation iranienne. L&rsquo;incursion du F-22 vers l&rsquo;Iran est une vieille histoire. L&rsquo;USAF y a beaucoup pens\u00e9, comme un facteur permettant de mettre en \u00e9vidence les capacit\u00e9s extraordinaires de l&rsquo;avion, et ainsi assurer ou relancer une s\u00e9rie plus longue que les 186 exemplaires finalement produits. (Voir notamment nos textes du <a href=\"http:\/\/www.dedefensa.org\/article-le_f-22_vaut_bien_un_blitz_contre_l_iran_14_04_2006.html?\" class=\"gen\">14 avril 2006<\/a> et du <a href=\"http:\/\/www.dedefensa.org\/article-le_f-22_l_usaf_l_iran_et_robert_gates_07_07_2008.html?\" class=\"gen\">7 juillet 2008<\/a>.) Tr\u00e8s r\u00e9cemment sont apparues des interrogations \u00e0 propos de la possibilit\u00e9 d&rsquo;une pr\u00e9sence des F-22 dans la mobilisation g\u00e9n\u00e9rale des moyens US autour de l&rsquo;Iran depuis le d\u00e9but de l&rsquo;ann\u00e9e (voir \u00e0 nouveau le texte cit\u00e9 du <a href=\"http:\/\/www.dedefensa.org\/article-l_usaf_entre_l_iran_et_le_f-22_01_03_2012.html\" class=\"gen\">1er mars 2012<\/a>). Finalement, la d\u00e9cision a \u00e9t\u00e9 prise d&rsquo;un d\u00e9ploiement du F-22, qui est d\u00e9sign\u00e9 avec pr\u00e9caution comme temporaire, de routine, sans rapport avec la mobilisation autour de l&rsquo;Iran, etc. On comprend, \u00e0 la lumi\u00e8re de tout ce qui pr\u00e9c\u00e8de, que ce d\u00e9ploiement n&rsquo;a effectivement rien d&rsquo;op\u00e9rationnel, et que les plans de guerre tels que <em>DEBKAFiles<\/em> les d\u00e9taille pour nous rassurer sur les intentions belliqueuses des USA ne sont qu&rsquo;une simple <em>narrative<\/em> th\u00e9orique et de type <em>DisneyWorld<\/em>, courante chez les experts sensibles \u00e0 l&rsquo;id\u00e9ologie plus qu&rsquo;\u00e0 la technique op\u00e9rationnelle. Dans les conditions actuelles et avec ces r\u00e9v\u00e9lations extraordinaires sur le comportement des pilotes, le d\u00e9ploiement des quelques F-22 aux EAU n&rsquo;est m\u00eame pas un \u00e9pisode de la <em>psychological warfare<\/em>, tout juste une pi\u00e8tre action rat\u00e9e de relations publiques (RP), tant il est \u00e9vident que ces avions ne s&rsquo;aventureront jamais dans une offensive a\u00e9rienne o\u00f9 leur pr\u00e9sence accompagn\u00e9e de multiples mesures de protection serait un bien p\u00e9nible handicap pour l&rsquo;offensive a\u00e9rienne. On se demande effectivement quelle coordination de RP a fait que le g\u00e9n\u00e9ral Hostage ait donn\u00e9 toutes ces pr\u00e9cisions sur le comportement des pilotes de l&rsquo;Air Combat Command au moment du d\u00e9ploiement des F-22, sinon l&rsquo;effet de l&rsquo;habituel cloisonnement des esprits bureaucratiques aliment\u00e9s par l&rsquo;aveuglement de la psychologie am\u00e9ricaniste.<\/p>\n<\/p>\n<p><p>\tIl n&#8217;emp\u00eache, ce dossier du jour permet de mesurer \u00e0 quelle vitesse l&rsquo;USAF approche d&rsquo;une situation de complet blocage qui signale sa compl\u00e8te d\u00e9cadence. Elle se trouve aujourd&rsquo;hui totalement prisonni\u00e8re de ses choix d&rsquo;avancement technologique maximal, alors qu&rsquo;il se confirme que la technologie, arriv\u00e9e \u00e0 l&rsquo;actuel point de complexit\u00e9 o\u00f9 elle se trouve, bascule dans le domaine de l&rsquo;inefficacit\u00e9 et m\u00eame de la production d&rsquo;impuissance active comme r\u00e9sultat d&rsquo;une dynamique antagoniste de l&rsquo;efficacit\u00e9, tendant \u00e0 rendre impuissants des processus qui fonctionnent bien eux-m\u00eames. Le cas actuel du F-22 (l&rsquo;alimentation en oxyg\u00e8ne), sur lequel travaillent les ing\u00e9nieurs depuis l&rsquo;entr\u00e9e en service op\u00e9rationnel complet du F-22 il y a 4-5 ans, n&rsquo;a absolument progress\u00e9 en rien sur la voie de sa r\u00e9solution. Le probl\u00e8me remarquable est qu&rsquo;il affecte une fonction vitale mais aussi fort simple du syst\u00e8me, et que le malfonctionnement de cette fonction n&rsquo;est pas la cons\u00e9quence d&rsquo;un vice interne mais de la d\u00e9pendance o\u00f9 on l&rsquo;a mise de l&rsquo;architecture informatique g\u00e9n\u00e9rale du syst\u00e8me : ainsi la technologie avanc\u00e9e tend-elle d\u00e9sormais, en plus de se d\u00e9truire elle-m\u00eame, de produire des effets collat\u00e9raux d\u00e9vastateurs en d\u00e9truisant des processus annexes qui fonctionnent bien. Cette logique qui illustre parfaitement le passage de la surpuissance \u00e0 l&rsquo;autodestruction montre la d\u00e9pendance absolue o\u00f9 tend \u00e0 se mettre l&rsquo;essentiel de nos activit\u00e9s techniques d&rsquo;un syst\u00e8me du technologisme d\u00e9sormais vici\u00e9 et pr\u00e9dateur de lui-m\u00eame comme de tout son environnement.<\/p>\n<\/p>\n<p><p>\tA c\u00f4t\u00e9 de cette situation dramatique, les capacit\u00e9s de r\u00e9action de l&rsquo;USAF sont r\u00e9duites au <em>minimum minimorum<\/em>, de par les obligations qu&rsquo;elle doit au syst\u00e8me de communication : d&rsquo;abord, la n\u00e9cessit\u00e9 de se conformer au l\u00e9galisme, qui l&rsquo;a d\u00e9j\u00e0 tr\u00e8s fortement affect\u00e9e. La crainte de plaintes possibles de proches de pilotes de F-22 qui seraient affect\u00e9s par des accidents \u00e9ventuels rappelle les embarras de l&rsquo;USAF vis-\u00e0-vis de ses contractants allant en justice dans l&rsquo;affaire du ravitailleur en vol <a href=\"http:\/\/www.dedefensa.org\/article-kc-x_le_contrat_qui_volait_de_ses_propres_ailes_16_11_2010.html\" class=\"gen\">KC-X<\/a> (KC-45). La r\u00e9action de l&rsquo;USAF est, devant ces possibilit\u00e9s, de c\u00e9der autant que faire se peut, au risque d&rsquo;installer dans ses rangs un laxisme qui mine \u00e9videmment l&rsquo;autorit\u00e9 et la hi\u00e9rarchie n\u00e9cessaires dans cette sorte d&rsquo;organisation. A c\u00f4t\u00e9 de cela, les r\u00e8gles de la RP imposent \u00e0 l&rsquo;USAF de continuer \u00e0 soutenir des programmes qu&rsquo;elle a laiss\u00e9s d\u00e9river sans r\u00e9agir et dont elle commence \u00e0 r\u00e9aliser qu&rsquo;ils sont irr\u00e9m\u00e9diablement pourris (cas du JSF) ; cette attitude rigide est pour l&rsquo;essentiel explicable par l&rsquo;affirmation implicite qu&rsquo;il est inconcevable que cette force a\u00e9rienne ne d\u00e9veloppe pas pour son avenir les syst\u00e8mes n\u00e9cessairement et pr\u00e9tendument pr\u00e9sent\u00e9s comme les plus avanc\u00e9s,  et pr\u00e9sent\u00e9s comme tels \u00e0 cause des imp\u00e9ratifs de promotion du syst\u00e8me de la communication, &#8211; nous sommes dans un parfait cercle vicieux et boucl\u00e9 Tous ces \u00e9l\u00e9ments de communication renvoient au r\u00f4le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_les_systemes_antisysteme_ddecrisis_17_01_2011.html\" class=\"gen\">antiSyst\u00e8me<\/a> indirect du syst\u00e8me de la communication, dans son emploi de <a href=\"http:\/\/www.dedefensa.org\/article-dialogues-13_de_la_sublimite_du_systeme_de_la_communication_08_11_2010.html\" class=\"gen\">Janus<\/a>.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est \u00e0 cette lumi\u00e8re qu&rsquo;il faut consid\u00e9rer l&rsquo;avenir de l&rsquo;USAF, qui a d\u00e9j\u00e0 largement <a href=\"http:\/\/www.dedefensa.org\/article-le_declin_catastrophique_de_la_puissance_de_l_usaf_30_07_2008.html\" class=\"gen\">entam\u00e9<\/a> sa <a href=\"http:\/\/www.dedefensa.org\/article-comptabilite_du_trou_noir_06_09_2010.html\" class=\"gen\">chute<\/a> sp\u00e9cifique. L&rsquo;USAF est donc un cas d&rsquo;esp\u00e8ce et un cas d\u00e9monstratif absolument remarquables. De ses d\u00e9boires technologiques qui exp\u00e9rimentent la chute terminale du syst\u00e8me du technologisme, de ses d\u00e9routes juridiques et de communication, \u00e0 ses manifestations pitoyables de d\u00e9monstration de puissance relevant de la bande dessin\u00e9e, \u00e0 ses balades impromptus dans la r\u00e9gion u Golfe, l&rsquo;USAF peut \u00eatre d\u00e9finie comme l&rsquo;application et l&rsquo;illustration les plus remarquables de l&rsquo;\u00e9volution acc\u00e9l\u00e9r\u00e9e du Syst\u00e8me, de sa surpuissance pass\u00e9e \u00e0 son autodestruction pr\u00e9sente.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le F-22 menace l&rsquo;Iran, \u00a0selon l&rsquo;humeur des pilotes&#8230; 2 mai 2012 La semaine derni\u00e8re, la nouvelle filtrait discr\u00e8tement, mais avec une discr\u00e9tion suffisamment ostentatoire pour qu&rsquo;on en soit inform\u00e9 : l&rsquo;USAF a d\u00e9ploy\u00e9 quelques exemplaires de son F-22 Raptor sur une base des Emirats Arabes Unis (EAU). (En g\u00e9n\u00e9ral, la presse-Syst\u00e8me d\u00e9crit le F-22 comme&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[7317,4646,4270,3015,2631,2662,249,5616,10255,2773,10274,2622,11293,11131,3014,4268],"class_list":["post-74684","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-alimentation","tag-antisysteme","tag-autodestruction","tag-communication","tag-de","tag-en","tag-f-22","tag-impuissance","tag-informatique","tag-iran","tag-janus","tag-la","tag-oxygene","tag-surpuissance","tag-systeme","tag-technologisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74684"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74684\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}