{"id":74694,"date":"2012-05-08T17:41:04","date_gmt":"2012-05-08T17:41:04","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/05\/08\/lusaf-et-ses-pilotes-prisonniers-de-la-machine-le-f-22\/"},"modified":"2012-05-08T17:41:04","modified_gmt":"2012-05-08T17:41:04","slug":"lusaf-et-ses-pilotes-prisonniers-de-la-machine-le-f-22","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/05\/08\/lusaf-et-ses-pilotes-prisonniers-de-la-machine-le-f-22\/","title":{"rendered":"L&rsquo;USAF et ses pilotes prisonniers de la machine (le F-22)"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">L&rsquo;USAF et ses pilotes prisonniers de la machine (le F-22)<\/h2>\n<\/p>\n<p><p>Il y eut, ce dimanche, une remarquable \u00e9mission, lors du fameux <em>Sixty Minutes<\/em> de CBS. Deux pilotes de l&rsquo;USAF, le major Jeremy Gordon et le capitaine Josh Wilson, y vinrent parler \u00e0 visages d\u00e9couverts de leur d\u00e9cision de refuser de voler \u00e0 bord de l&rsquo;avion de combat F-22 <em>Raptor<\/em>. Ils avaient pris soin de se faire accompagner par un membre du Congr\u00e8s, le repr\u00e9sentant r\u00e9publicain Adam Kinzinger.<\/p>\n<\/p>\n<p><p>Kinzinger expliqua ainsi sa pr\u00e9sence, en tant que protecteur affich\u00e9 de deux hommes qui pouvaient se pr\u00e9senter comme des <em>whistleblowers<\/em> (litt\u00e9ralement \u00ab\u00a0<a class=\"gen\" href=\"http:\/\/fr.wikipedia.org\/wiki\/Lanceur_d'alerte\">lanceurs d&rsquo;alerte<\/a>\u00ab\u00a0, ou \u00ab\u00a0d\u00e9nonciateurs\u00a0\u00bb dans le bon sens du terme, selon les Qu\u00e9becois : une personne qui d\u00e9cide de d\u00e9noncer publiquement des faits de corruption, d&rsquo;abus de pouvoir, etc., g\u00e9n\u00e9ralement d&rsquo;une administration ou d&rsquo;une entreprise) : &laquo;<em>Congress granted protection to whistleblowers in general and specifically military to say: if you have a concern, you know &ndash; not something obviously little &ndash; but something pretty big and serious&hellip; you have a right to talk to your congressman,\u00a0\u00bb Rep Adam Kinzinger (R-Illinois) tells the network, \u00ab\u00a0because just &#8217;cause you join the military doesn&rsquo;t mean you give up your right to citizenship.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Ainsi l&rsquo;\u00e9mission <em>Sixty Minutes<\/em> ent\u00e9rina-t-elle pour sa tr\u00e8s vaste audience la \u00ab\u00a0mutinerie\u00a0\u00bb sans aucun pr\u00e9c\u00e9dent historique dans ce domaine, qui touche aujourd&rsquo;hui une partie des pilotes de l&rsquo;USAF, affect\u00e9s \u00e0 des unit\u00e9s \u00e9quip\u00e9es du F-22. On a d\u00e9j\u00e0 vu (le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_f-22_menace_l_iran_selon_l_humeur_des_pilotes_02_05_2012.html\">2 mai 2012<\/a>) le cas sans pr\u00e9c\u00e8dent de ces pilotes de F-22 refusant de voler \u00e0 bord de leurs avions. L&rsquo;\u00e9mission de la CBS du <a class=\"gen\" href=\"http:\/\/abcnews.go.com\/Blotter\/fighter-pilots-claim-intimidation-22-raptor-jet-concerns\/story?id=16294011#.T6gzXXj5afI\">6 mai 2012<\/a>, largement comment\u00e9e (voir <em>Danger Room<\/em> du <a class=\"gen\" href=\"http:\/\/www.wired.com\/dangerroom\/2012\/05\/stealth-pilots-mutiny\/\">6 mai 2012<\/a>, <em>Russia Today<\/em> du <a class=\"gen\" href=\"http:\/\/rt.com\/usa\/news\/force-air-f-22-wilson-731\/\">7 mai 2012<\/a>, <em>DoD.Buzz<\/em> du <a class=\"gen\" href=\"http:\/\/www.dodbuzz.com\/2012\/05\/07\/despite-whistle-blowing-pilots-af-is-unmoved-on-f-22\/\">7 mai 2012<\/a>), a surtout mis en \u00e9vidence les conflits que soul\u00e8ve cette situation exceptionnelle et, notamment, l&rsquo;attitude de l&rsquo;USAF vis-\u00e0-vis de ce que <em>Danger Room<\/em> appelle \u00ab\u00a0la mutinerie des pilotes des avions furtifs\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Selon ABC, &laquo;<em>Several current and former F-22 pilots contacted by ABC News for its investigation either did not respond or quickly declined to comment on the plane and two relatives of flyers told ABC News that the pilots had been instructed not to speak to the media on penalty of potentially losing their post with the F-22 &#8212; a coveted position despite the safety concerns. One pilot, when initially contacted by ABC News for comment, agreed to speak on the record but only after he checked with the Air Force public affairs office. Since then, the pilot has not responded to any of ABC News&rsquo; attempts to communicate.<\/em> [&hellip;]<\/p>\n<\/p>\n<p><p>&raquo;<em>Top officials at the Air Force and Lockheed Martin refused to take part in one-on-one interviews with ABC News for its broadcast report, but the Air Force provided a statement last week in which it says the service is committed to &quot;unparalleled dedication to flight safety.\u00a0\u00bb \u00ab\u00a0Flying America&rsquo;s premier fighter aircraft always entails risk but the Air Force has, and always will, take every measure to ensure the safety of our aircrews while delivering air superiority for the nation,\u00a0\u00bb the statement said. The Air Force has also stressed that reports of \u00ab\u00a0hypoxia-like symptoms\u00a0\u00bb are exceedingly rare &ndash; more than two dozen compared to the thousands of flights flown without incident.<\/em><\/p>\n<\/p>\n<p><p>Il y a \u00e0 peu pr\u00e8s, actuellement, 200 pilotes qualifi\u00e9s pour le F-22 ; 36 d&rsquo;entre eux auraient exp\u00e9riment\u00e9 des incidents avec le syst\u00e8me d&rsquo;oxyg\u00e8ne d\u00e9fectueux, avec des s\u00e9quelles notables sinon s\u00e9rieuses. Un pilote est mort dans son avion qui s&rsquo;est \u00e9cras\u00e9 au sol en 2010, dans une occurrence que la famille de la victime et divers intervenants jugent li\u00e9e \u00e0 une d\u00e9fection du syst\u00e8me d&rsquo;alimentation, bien entendu contre l&rsquo;avis de l&rsquo;USAF qui parle d'\u00a0\u00bberreur humaine\u00a0\u00bb. Il est impossible de donner un d\u00e9compte du nombre de pilotes ayant refus\u00e9 ou refusant de voler \u00e0 bord des F-22.<\/p>\n<\/p>\n<p><p><em>Danger Room<\/em> : &laquo;<em>&hellip;Gordon and Wilson say they aren&rsquo;t alone. A \u00ab\u00a0vast, silent majority\u00a0\u00bb of Raptor fliers fears for their lives as their high- and fast-flying jets cause them to black out or become confused in mid-air. Some pilots have taken out extra life-insurance policies. And Air Force doctors \u00ab\u00a0absolutely\u00a0\u00bb have said no one should fly the $400-million-a-copy F-22 until the jet&rsquo;s oxygen woes are resolved, Gordon and Wilson claim.<\/em> [&hellip;]<\/p>\n<\/p>\n<p><p>&laquo;<em>&hellip;In February last year Wilson was at the controls of his F-22 on a training flight when he began feeling disoriented. \u00ab\u00a0I had to really concentrate, immense concentration on just doin&rsquo; simple, simple tasks,\u00a0\u00bb he tells 60 Minutes. \u00ab\u00a0And our training tells you if you suspect something&rsquo;s probably goin&rsquo; on, go ahead and pull your emergency oxygen and come back home. When I did make that decision to pull the emergency oxygen ring, I couldn&rsquo;t find it. I couldn&rsquo;t remember, you know, what part of the aircraft it was in.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Three months later, the Air Force temporarily grounded all of its Raptors so it could study the problem. But that five-month stand-down, and a more limited grounding in October, did not result in any major changes to the F-22&prime;s on-board oxygen-generating system&hellip;<\/em> [&hellip;] <em>The blackouts continued. In October Gordon and his wingman both reported oxygen shortages. In all, Raptor pilots suffered 11 black-outs or near-blackouts between October and May, 60 Minutes reports.<\/em> [&hellip;]<\/p>\n<\/p>\n<p><p>&raquo;[&hellip;T]<em>he cumulative effects of oxygen deprivation are apparent among Raptor fliers, Gordon says. \u00ab\u00a0In a room full of F-22 pilots, the vast majority will be coughing a lot of the times. Other things &mdash; laying down for bed at night after flying and getting just the spinning room feeling, dizziness, tumbling, vertigo kind of stuff.\u00a0\u00bb The whistleblowers anticipate more deaths as the Air Force pushes its Raptor crews to continue flying despite overwhelming evidence of the jet&rsquo;s faultiness. \u00ab\u00a0We are waiting for somethin&rsquo; to happen,\u00a0\u00bb Wilson says. \u00ab\u00a0And if it happens, nobody&rsquo;s going to be surprised. I think it&rsquo;s a matter of time.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>C&rsquo;est une situation sans pr\u00e9c\u00e9dent, certes, et qui para&icirc;t \u00e9galement fig\u00e9e dans une sorte d&rsquo;impuissance g\u00e9n\u00e9rale de l&rsquo;USAF, alors que les pilotes pourraient \u00eatre conduits \u00e0 se manifester publiquement de plus en plus souvent. Il est possible qu&rsquo;\u00e0 la suite de l&rsquo;\u00e9mission de dimanche, une audition au Congr\u00e8s ait lieu sur cette affaire, tandis que les doutes grandissent sur la possibilit\u00e9 que les F-22 aient jamais une r\u00e9elle capacit\u00e9 op\u00e9rationnelle. Il n&rsquo;y a pas encore de lien \u00e9tabli avec les probl\u00e8mes sans nombre du JSF, mais le rapport \u00e9vident entre la complexit\u00e9 de l&rsquo;avion et la panne du syst\u00e8me d&rsquo;alimentation en oxyg\u00e8ne conduit \u00e9videmment \u00e0 se demander si de tels incidents ne menacent pas \u00e9galement la future flotte de JSF, &ndash; s&rsquo;il y a jamais une \u00ab\u00a0future flotte de JSF\u00a0\u00bb, ce qui est une question de plus en plus actuelle.<\/p>\n<\/p>\n<p><p>La gravit\u00e9 du cas est bien entendu au niveau de l&rsquo;impasse constat\u00e9e pour r\u00e9soudre un probl\u00e8me dont il est difficile d&rsquo;envisager qu&rsquo;il puisse accompagner, en l&rsquo;\u00e9tat et sans r\u00e9solution, la \u00ab\u00a0vie op\u00e9rationnelle\u00a0\u00bb de l&rsquo;avion. Il y a d\u00e9j\u00e0 eu une immobilisation de la flotte de F-22 pendant plus de six mois en deux phases (entre 7 et 8% du temps de la \u00ab\u00a0vie op\u00e9rationnelle\u00a0\u00bb totale du F-22 \u00e0 ce jour), et toutes les tentatives de r\u00e9soudre le probl\u00e8me ont \u00e9chou\u00e9 ; \u00e0 cela s&rsquo;ajoutent les restrictions sans nombre de l&rsquo;enveloppe de vol, des performances, etc. Bien entendu, l&rsquo;USAF est d\u00e9sormais de plus en plus tent\u00e9e, pour des raisons de relations publiques, d'\u00a0\u00bbimage\u00a0\u00bb, etc., d&rsquo;\u00e9touffer ce probl\u00e8me en pratiquant une r\u00e9tention d&rsquo;information, voire une censure syst\u00e9matique, tout en affirmant que le probl\u00e8me n&rsquo;est pas grave (ce qui emp\u00eacherait de nouvelles interdictions de vol de longue dur\u00e9e pour tenter de le r\u00e9soudre). Pendant ce temps, la \u00ab\u00a0mutinerie des pilotes\u00a0\u00bb ne peut que s&rsquo;amplifier.<\/p>\n<\/p>\n<p><p>Il ne fait aucun doute, comme on l&rsquo;a d\u00e9j\u00e0 vu, que cette forme de probl\u00e8me est directement li\u00e9e \u00e0 la complexit\u00e9 extraordinaire de ces types d&rsquo;avion (F-22 et JSF). Cette complexit\u00e9 est d\u00e9pendante de l&rsquo;avancement de l&rsquo;avion, dit de \u00ab\u00a0cinqui\u00e8me g\u00e9n\u00e9ration\u00a0\u00bb, autant que du choix de la technologie furtive (des technologies furtives puisque c&rsquo;est un ensemble de technologies formant \u00ab\u00a0la technologie furtive\u00a0\u00bb, ou encore <em>stealth technology<\/em>) ; la technologie furtive impose de tr\u00e8s nombreuses contraintes a\u00e9rodynamiques, de fonctionnement, des mat\u00e9riaux sp\u00e9cifiques, etc., toutes ces conditions nouvelles qui accroissent la complexit\u00e9 et dont on ignore les effets divers, notamment sur l&rsquo;\u00eatre humain dans les conditions de vol et de combat de ce type de syst\u00e8mes. Il est imp\u00e9ratif, pour bien comprendre l&rsquo;ampleur du probl\u00e8me de lier la complexit\u00e9 du syst\u00e8me au choix des technologies furtives, tout en admettant que ce choix renvoie \u00e0 la logique de la modernit\u00e9 elle-m\u00eame, de son d\u00e9veloppement exponentiel, de son choix de technologies de plus en plus complexes et de plus en plus d\u00e9pendantes les unes des autres (constitution de \u00ab\u00a0syst\u00e8mes de syst\u00e8mes\u00a0\u00bb) ; tout cela rendant le contr\u00f4le direct puis indirect de la machine de plus en plus probl\u00e9matique, alors qu&rsquo;en retour l&#8217;emprise de la machine sur l&rsquo;activit\u00e9 humaine consid\u00e9r\u00e9e ne cesse de grandir jusqu&rsquo;\u00e0 devenir exclusive. L&#8217;emprisonnement est alors verrouill\u00e9&hellip;<\/p>\n<\/p>\n<p><p>Ainsi se confirme-t-il de plus en plus que l&rsquo;USAF, \u00e0 l&rsquo;image de la sorte de service op\u00e9rationnel avanc\u00e9 qui peut se comparer \u00e0 elle, est arriv\u00e9e dans un domaine nouveau o&ugrave; les capacit\u00e9s de la machine (les technologies avanc\u00e9es) tendent \u00e0 une contre-productivit\u00e9 puis \u00e0 une inefficacit\u00e9 radicales, tandis que l&rsquo;organisation et sa bureaucratie sont compl\u00e8tement emprisonn\u00e9e \u00e0 cette machine. La chose est aggrav\u00e9e, jusqu&rsquo;au verrouillage le plus complet, par cette \u00e9volution-Syst\u00e8me que nous \u00e9voquons souvent, ici \u00e0 propos du syst\u00e8me du technologisme, passant de la surpuissance \u00e0 l&rsquo;autodestruction. Nous ne sommes plus dans le cycle de temps court ou dans le temporaire, qui permettrait un retour en arri\u00e8re jusqu&rsquo;\u00e0 la bifurcation originelle de la s\u00e9quence, pour prendre une autre orientation. La chronologie est extr\u00eamement longue par rapport \u00e0 la rapidit\u00e9 de d\u00e9veloppement et d&rsquo;int\u00e9gration des technologies, chronologie durant laquelle toute la base technologique de l&rsquo;industrie et les infrastructures de l&rsquo;USAF se sont tourn\u00e9es et conform\u00e9es \u00e0 l&#8217;emploi de la furtivit\u00e9. Celle-ci, la furtivit\u00e9, qui recouvre les technologies furtives mais aussi l&rsquo;esprit qui a concouru \u00e0 leur choix et qui r\u00e9gule leur emploi, est devenue une v\u00e9ritable \u00ab\u00a0philosophie\u00a0\u00bb du technologisme, d&rsquo;un technologisme qu&rsquo;on esp\u00e9rait verrouill\u00e9 dans une supr\u00e9matie et une efficacit\u00e9 sans obstacles. Quelques rappels permettent de situer l&rsquo;enracinement chronologique du probl\u00e8me et de comprendre que l&rsquo;hypoth\u00e8se d&rsquo;une impasse sans retour n&rsquo;est plus \u00e0 repousser, et que cette impasse menace la structure de l&rsquo;USAF dans sa globalit\u00e9, dans une sorte de d\u00e9monstration <em>in vivo<\/em> de la crise terminale du syst\u00e8me du technologisme.<\/p>\n<\/p>\n<p><p>&bull; L&rsquo;apparition et les premiers d\u00e9veloppements de la technologie furtive, avec la mise en place d&rsquo;une bureaucratie qui va avec, favorisant syst\u00e9matiquement son d\u00e9veloppement et des choix allant dans ce sens, date des ann\u00e9es 1970 (deuxi\u00e8me moiti\u00e9 de la d\u00e9cennie). On pourra consulter \u00e0 cet \u00e9gard un historique complet des d\u00e9buts de la technologie de la furtivit\u00e9, ou <em>stealth<\/em>, que nous avons publi\u00e9 en deux textes, successivement le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-retour_sur_la_stealth_technology_premiere_partie_22_07_2005.html\">22 juillet 2007<\/a> et le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-retour_sur_la_stealth_technology_seconde_partie_23_07_2005.html?admin=1\">23 juillet 2007<\/a>.<\/p>\n<\/p>\n<p><p>&bull; La d\u00e9cision d\u00e9cisive de l&rsquo;USAF de passer \u00e0 du \u00ab\u00a0tout-<em>stealth<\/em>\u00ab\u00a0, c&rsquo;est-\u00e0-dire, en termes imag\u00e9s d\u00e9signant les sp\u00e9cificit\u00e9s des mat\u00e9riaux \u00ab\u00a0furtifs\u00a0\u00bb, d&rsquo;abandonner \u00ab\u00a0<em>the aluminium fighter<\/em>\u00ab\u00a0, remonte \u00e0 la fin de la premi\u00e8re guerre du Golfe, c&rsquo;est-\u00e0-dire il y a vingt ans. On rappellera ici un texte que nous avons publi\u00e9 le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_autour_de_l_air_dominance_en_perdition_12_12_2008.html\">12 d\u00e9cembre 2008<\/a>, dans lequel nous citions l&rsquo;experte Rebecca Grant, tr\u00e8s proche de l&rsquo;Air Force Association, qui rappelait les conditions o&ugrave; la d\u00e9cision fut prise. (Ironiquement, le chef d&rsquo;\u00e9tat-major de l&rsquo;USAF qui prit cette d\u00e9cision, le g\u00e9n\u00e9ral McPeak, fut un des conseillers militaires de l&rsquo;\u00e9quipe Obama lors de la campagne \u00e9lectorale de l&rsquo;automne 2008.)<\/p>\n<\/p>\n<p><p>&laquo;<em>Grant nous explique comment l&rsquo;USAF a lanc\u00e9, apr\u00e8s la guerre du Golfe-I de 1991, qui repr\u00e9sente sans aucun doute un sommet dans l&rsquo;histoire de la sup\u00e9riorit\u00e9 et de l&rsquo;efficacit\u00e9 de l&rsquo;aviation militaire dans un conflit de cette importance (\u00ab\u00a0The year 1991 seemed like the dawn of a new age for American airpower\u00a0\u00bb), un vaste plan de refonte de ses structures, et comment ce plan a \u00e9t\u00e9 absolument pulv\u00e9ris\u00e9. Au d\u00e9part (en 1992-92), il y a le choix, sans aucun doute tr\u00e8s audacieux sinon imprudent, de d\u00e9velopper une aviation de combat \u00ab\u00a0tout-stealth\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&laquo;<em>\u00ab\u00a0After Desert Storm, the Air Force decided never again to buy a nonstealthy fighter. According to the then-Chief of Staff of the Air Force, Gen. Merrill A. McPeak, there was no point in buying any more \u00ab\u00a0aluminum\u00a0\u00bb fighters. Stealth was to be the Air Force hallmark from then on. This was a bold decision, given the strong performance of standard fighters &ndash; the F-15s and F-16s in particular &ndash; in the Gulf War. The F-15E was still in production, and it would have been easy indeed for the Air Force to make a case for a big new buy based on combat results&hellip;<\/em> [&hellip;]<\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0A year later<\/em> [1992]<em>, McPeak testified, &lsquo;The F-15 will be able to win any fight that I can think of out<\/em> [<em>to<\/em>] <em>the turn of the century&rsquo; but that its days were numbered after that. &lsquo;The F-15 cannot get to the fight after the turn of the century,&rsquo; by about 2010, McPeak judged. As a result, USAF resisted any temptation to beef up its inventory of F-15Cs, F-15Es, or F-16s, pushing instead its long-term commitment to buy stealth.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Mis en ligne le 8 mai 2012 \u00e0 17H23<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;USAF et ses pilotes prisonniers de la machine (le F-22) Il y eut, ce dimanche, une remarquable \u00e9mission, lors du fameux Sixty Minutes de CBS. Deux pilotes de l&rsquo;USAF, le major Jeremy Gordon et le capitaine Josh Wilson, y vinrent parler \u00e0 visages d\u00e9couverts de leur d\u00e9cision de refuser de voler \u00e0 bord de l&rsquo;avion&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[5553,4270,2651,249,8116,6941,14810,8335,3411,11131,3014,3519,4268,41],"class_list":["post-74694","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-abc","tag-autodestruction","tag-du","tag-f-22","tag-furtive","tag-impasse","tag-mutinerie","tag-pilotes","tag-stealth","tag-surpuissance","tag-systeme","tag-technologie","tag-technologisme","tag-usaf"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74694"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74694\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}