{"id":74699,"date":"2012-05-10T09:05:52","date_gmt":"2012-05-10T09:05:52","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/05\/10\/le-message-de-poutine-a-bho-et-au-bloc-bao\/"},"modified":"2012-05-10T09:05:52","modified_gmt":"2012-05-10T09:05:52","slug":"le-message-de-poutine-a-bho-et-au-bloc-bao","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/05\/10\/le-message-de-poutine-a-bho-et-au-bloc-bao\/","title":{"rendered":"Le \u201cmessage\u201d de Poutine \u00e0 BHO et au bloc BAO\u2026"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Le message de Poutine \u00e0 BHO et au bloc BAO<\/h3>\n<\/p>\n<p><p>\tIl est difficile de ne pas voir, et surtout de ne pas entendre la d\u00e9cision de Poutine de ne pas aller au G8 du 18-19 mai aux USA (\u00e0 Camp David) comme un message indirect au pr\u00e9sident des USA, et au bloc BAO par la m\u00eame occasion. Poutine devait voir BHO en t\u00eate-\u00e0-t\u00eate, en marge du G8, cela \u00e0 l&rsquo;insistance de la partie US. On devra attendre un mois, puisque Poutine a propos\u00e9 que cette rencontre en marge se passe le 18-19 juin \u00e0 Los Carbos, au Mexique, en marge du G20, auquel Poutine assistera bien entendu (acceptation imm\u00e9diate et empress\u00e9e d&rsquo;Obama) Message indirect, avec nombre de significations sp\u00e9culatives, qui se justifient par l&rsquo;intensit\u00e9 g\u00e9n\u00e9rale de la situation, l&rsquo;incertitude des relations USA-Russie et l&rsquo;entame d&rsquo;une nouvelle pr\u00e9sidence Poutine n\u00e9cessitant une nouvelle politique adapt\u00e9e \u00e0 la crise g\u00e9n\u00e9rale que nous connaissons, et qui doit se d\u00e9finir comme une grande politique de crise. <\/p>\n<\/p>\n<p><p>\tL&rsquo;agence Itar-Tass a annonc\u00e9 la nouvelle, relayant le porte-parole de la Maison-Blanche, ce <a href=\"http:\/\/www.itar-tass.com\/en\/c32\/413622.html\" class=\"gen\">10 mai 2012<\/a>, avec quelques d\u00e9tails sur la conversation t\u00e9l\u00e9phonique qu&rsquo;a eue Poutine avec Obama. Tr\u00e8s poliment, bien s\u00fbr, le pr\u00e9sident russe a avis\u00e9 personnellement Obama de sa d\u00e9cision, qu&rsquo;il a justifi\u00e9e par le travail autour de la formation du gouvernement. Assez dr\u00f4lement, il a annonc\u00e9 au pr\u00e9sident US que c&rsquo;est Medvedev, le Premier ministre, qui le remplacera. Il est l\u00e0 aussi difficile de ne pas \u00eatre sollicit\u00e9 par l&rsquo;ironie de l&rsquo;explication que Poutine offre comme raison de son absence au G8 : il ne peut pas venir parce qu&rsquo;il est occup\u00e9 par la formation du gouvernement, mais le chef de ce gouvernement le remplace Si l&rsquo;on consid\u00e8re alors que la raison avanc\u00e9e est de pure forme et \u00e0 peine s\u00e9rieuse, le choix de l&rsquo;explication est entre le peu de cas que fait Poutine du r\u00f4le de Medvedev ou le peu de cas que fait Poutine de sa rencontre avec Obama, pr\u00e9cis\u00e9ment au G8 et \u00e0 Camp David. (Ou bien, il n&rsquo;y a pas de choix, et les deux remarques sont justifi\u00e9es, ce qui est assez acceptable Simplement, l&rsquo;une est plus importante que l&rsquo;autre mais il semble \u00e9galement qu&rsquo;il ne faille pas trop se faire d&rsquo;illusions sur l&rsquo;importance du r\u00f4le de Medvedev dans la Russie du retour de Poutine ; cela, d&rsquo;ailleurs, n&rsquo;aurait rien de surprenant.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Russian President Vladimir Putin told his U.S. counterpart Barack Obama that he could not take part in the G-8 summit to be held in Camp David on May 18-19 due to the formation of a new government in the country. Russia will be represented by Prime Minister Dmitry Medvedev, the White House press service reported on Wednesday, May 9, after the telephone conversation between the leaders of the two countries.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>During the conversation, Putin and Obama agreed to meet on the sidelines of the G-20 summit due to take place in Mexico&rsquo;s Los Cabos on June 18-19. Putin said he had obligations to complete appointments to the new Russian government that is why he could not participate in the G-8 summit in Camp David, the White House press service reported. Obama respected President Putin&rsquo;s decision and lauded Medvedev&rsquo;s participation in the G-8 summit, the press service said.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>The presidents confirmed the commitment to maintaining the dialogue in the spirit of the resetting policy. They noted considerable progress in such issues as nuclear security and the non-proliferation, Afghanistan, the WTO talks, and the expansion of trade cooperation, the press service said.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Earlier, the Kremlin press service stressed that during the conversation, Obama had congratulated Putin on the inauguration. The press service said the presidents exchanged greetings messages on Victory Day and noted the importance of allied relationship that the peoples of both states had established during WWII and conveyed their good wishes to veterans. The heads of state also discussed prospects for the development of Russian-American relations and personal contacts, the press service said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl est vraiment tr\u00e8s difficile de ne pas interpr\u00e9ter la d\u00e9cision de Poutine, mis \u00e0 part les ironies relev\u00e9es ci-dessus, comme une tr\u00e8s s\u00e9rieuse mise au point vis-\u00e0-vis des USA et \u00e0 d&rsquo;Obama. Interpr\u00e9tons donc.<\/p>\n<\/p>\n<p><p>\tPoutine veut bien rencontrer Obama, bien entendu, comme Obama lui-m\u00eame voulait cette rencontre ; mais, \u00e0 la diff\u00e9rence d&rsquo;Obama qui voulait que cela soit fait tr\u00e8s rapidement, Poutine est un peu moins press\u00e9 ; il ne veut pas que cela se passe aux USA o\u00f9 a lieu le G8 et il ne veut pas \u00e0 ce que cela se passe en marge du G8 qui est un groupe dont on peut dire qu&rsquo;il repr\u00e9sente une courroie de transmission du bloc am\u00e9ricaniste-occidentaliste. De telles circonstances interpr\u00e9t\u00e9es conduisent n\u00e9cessairement \u00e0 d&rsquo;autres interpr\u00e9tations, plus g\u00e9n\u00e9rales ; l&rsquo;on peut ajouter, quoi qu&rsquo;en ait voulu Poutine puisqu&rsquo;il s&rsquo;agit d&rsquo;interpr\u00e9tations et nullement d&rsquo;actes pr\u00e9cis\u00e9ment explicit\u00e9s ; et l&rsquo;on peut conclure, alors que Poutine savait que cela serait in\u00e9vitablement interpr\u00e9t\u00e9 dans ce sens Le message serait donc pr\u00e9cis\u00e9ment ce qu&rsquo;il est selon ces interpr\u00e9tations, dans la perception des protagonistes.<\/p>\n<\/p>\n<p><p>\tLa signification de ce message autorise alors des sp\u00e9culations, qui \u00e9clairent ce que pourrait \u00eatre l&rsquo;attitude de Poutine, comme une indication de la politique qu&rsquo;il va suivre (sa grande politique g\u00e9n\u00e9rale de crise). D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, cette attitude et cette politique ne pourraient \u00eatre qualifi\u00e9es que de plus dures par rapport \u00e0 ce qui pr\u00e9c\u00e9da, pour ce qui concerne les relations avec les USA, et, plus g\u00e9n\u00e9ralement, les relations de la Russie avec le bloc BAO en tant que tel. Nous disons bloc BAO en tant que tel, car cela n&#8217;emp\u00eache \u00e9videmment pas des relations d&rsquo;une autre forme, beaucoup plus chaleureuses et constructives, de la Russie avec certains pays du bloc, si ces pays acceptent cette perspective. Cela sera notamment le cas de l&rsquo;Allemagne, dont les liens tr\u00e8s nombreux et tr\u00e8s forts avec la Russie sont un fait majeur ; cela pourrait \u00eatre le cas avec la France, si le nouveau pr\u00e9sident envisage la relation avec la Russie comme un domaine important, et s&rsquo;il infl\u00e9chit la politique fran\u00e7aise actuelle dans un sens un peu moins atlantiste (\u00e0 noter que Poutine a eu un \u00e9change t\u00e9l\u00e9phonique personnel avec Hollande).<\/p>\n<\/p>\n<p><p>\tQuelles peut \u00eatre dans ce contexte la signification g\u00e9n\u00e9rale de ce message de Poutine ? Sp\u00e9culons selon plusieurs orientations<\/p>\n<\/p>\n<p><p>\t D&rsquo;abord, la signification que les relations de la Russie avec les USA, si elles sont tr\u00e8s importantes, ne sont pas (plus) essentielles au point de dominer tout le reste et de bousculer quelques axes fondamentaux de la politique russe. Il s&rsquo;agit dans ce cas d&rsquo;un nouvel axe, c&rsquo;est-\u00e0-dire l&rsquo;axe de r\u00e9sistance de plus en plus active de la direction russe aux pressions am\u00e9ricanistes-occidentalistes, d\u00e9non\u00e7ant la politique du bloc BAO, et, plus sp\u00e9cifiquement, la politique des USA, vis-\u00e0-vis de la Russie. Il s&rsquo;agit, tout \u00e0 fait pr\u00e9cis\u00e9ment, du domaines des <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_l_entr_e_des_antimissiles_dans_la_crise_haute__07_05_2012.html\" class=\"gen\">antimissiles<\/a> autant que du contentieux de ce que les Russes d\u00e9noncent comme l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-l_opposition_russe_chez_elle_l_ambassade_us_09_05_2012.html\" class=\"gen\">agression douce<\/a> des USA contre la Russie, par moyens d&rsquo;influence et de communication, avec son interf\u00e9rence hostile dans les affaires int\u00e9rieures russes et dans la souverainet\u00e9 de la Russie. En d&rsquo;autres mots, Poutine ne sacrifiera rien des int\u00e9r\u00eats russes dans cette sorte d&rsquo;affaire, pour une relation en apparence privil\u00e9gi\u00e9e avec les USA.<\/p>\n<\/p>\n<p><p>\t Subsidiairement, on peut conjecturer que Poutine ne fait gu\u00e8re de cr\u00e9dit au pr\u00e9sident Obama, non pas n\u00e9cessairement sur ses intentions (il ne semble pas y avoir d&rsquo;hostilit\u00e9 personnelle \u00e0 cet \u00e9gard ni une mise en cause de la bonne foi d&rsquo;Obama), mais sur ses capacit\u00e9s par rapport aux pressions du Syst\u00e8me \u00e0 tenir certaines de ses promesses et \u00e0 faire progresser une politique de tr\u00e8s bonnes relations avec la Russie. Il n&rsquo;est pas assur\u00e9 que Poutine ait pris enti\u00e8rement pour du comptant, loin de l\u00e0, la communication discr\u00e8te mais rendue tr\u00e8s publique par un micro inopportun qu&rsquo;Obama avait confi\u00e9e \u00e0 Medvedev pour transmission \u00e0 ce m\u00eame Poutine. (Voir le <a href=\"http:\/\/www.dedefensa.org\/article-_dites_a_vlad_qu_il_patiente__27_03_2012.html\" class=\"gen\">27 mars 2012<\/a>.)<\/p>\n<\/p>\n<p><p>\t D&rsquo;autre part, il y a un symbole dans le fait que la rencontre Poutine-Obama est report\u00e9e de la marge du G8 \u00e0 la marge du G20, comme il y a un symbole dans l&rsquo;absence de d\u00e9placement de Poutine au G8, et dans sa venue, bien entendu, au G20. On doit interpr\u00e9ter cela comme une \u00e9volution objective, r\u00e9alis\u00e9e comme telle ou pas par Poutine peu importe, selon laquelle le G8 perd de plus en plus de son importance au profit du G20. Symboliquement encore plus qu&rsquo;op\u00e9rationnellement, cette \u00e9volution doit \u00eatre per\u00e7ue comme celle d&rsquo;un monde unipolaire qui s&rsquo;efface rapidement, pour un monde multipolaire o\u00f9 les USA et le bloc BAO n&rsquo;exercent plus leur h\u00e9g\u00e9monie et leur magist\u00e8re. Dans le G20, on trouve des repr\u00e9sentations <em>de facto<\/em> de l&rsquo;OTAN, mais aussi du BRICS, et de l&rsquo;OCS (Organisation de Coop\u00e9ration de Shanghai). Il est \u00e9vident que la Russie se trouve d\u00e9sormais bien plus \u00e0 l&rsquo;aise dans le G20 que dans le G8, ce qui est une \u00e9volution remarquable par rapport aux ann\u00e9es 1990 et au d\u00e9but des ann\u00e9es 2000.<\/p>\n<\/p>\n<p><p>\tMais tout cela, finalement, n&rsquo;est que sp\u00e9culations, et peut-\u00eatre le pr\u00e9sident Poutine est-il effectivement tr\u00e8s occup\u00e9 par le choix des ministres du gouvernement dont le Premier ministre le remplacera pour repr\u00e9senter la Russie au G8.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 10 mai 2012 \u00e0 09H06<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le message de Poutine \u00e0 BHO et au bloc BAO Il est difficile de ne pas voir, et surtout de ne pas entendre la d\u00e9cision de Poutine de ne pas aller au G8 du 18-19 mai aux USA (\u00e0 Camp David) comme un message indirect au pr\u00e9sident des USA, et au bloc BAO par la&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[11897,4056,10900,6039,11035,3228,2631,11898,7932,4307,7394,5460,2858,7328,6208,4607,916,2766,14815,14423],"class_list":["post-74699","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-agression","tag-antimissiles","tag-bao","tag-bloc","tag-brics","tag-crise","tag-de","tag-douce","tag-g20","tag-g8","tag-generale","tag-gouvernement","tag-medvedev","tag-multipolaire","tag-obama","tag-politique","tag-poutine","tag-relations","tag-unipolaire","tag-usa-russie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74699"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74699\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}