{"id":74700,"date":"2012-05-10T13:29:11","date_gmt":"2012-05-10T13:29:11","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/05\/10\/cauchemardons-un-peu-sarko-a-lotan\/"},"modified":"2012-05-10T13:29:11","modified_gmt":"2012-05-10T13:29:11","slug":"cauchemardons-un-peu-sarko-a-lotan","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/05\/10\/cauchemardons-un-peu-sarko-a-lotan\/","title":{"rendered":"Cauchemardons un peu\u2026 Sarko \u00e0 l&rsquo;OTAN ?"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Cauchemardons un peu Sarko \u00e0 l&rsquo;OTAN ?<\/h3>\n<\/p>\n<p><p>\tIl faut reconna\u00eetre \u00e0 Richard Cottrell une grande imagination, en plus d&rsquo;une documentation abondante. (Il nous am\u00e8ne des r\u00e9v\u00e9lations diverses dans son livre, qui vient de para\u00eetre ces jours-ci et ne nous est pas encore parvenu : <em>Gladio, NATO&rsquo;s Dagger at the Heart of Europe: The Pentagon-Nazi-Mafia Terror Axis<\/em>. Il y parle des r\u00e9seaux <em>Gladio<\/em>, <a href=\" http:\/\/www.dedefensa.org\/article-gladio_explique-t-il_9_11_interview_du_dr_daniele_ganser_27_12_2005.html\" class=\"gen\">question<\/a> <a href=\"http:\/\/www.dedefensa.org\/article-gladio_explique-t-il_9_11_27_12_2005.html\" class=\"gen\">fascinante<\/a> sans aucun doute, dans le mode de la r\u00e9v\u00e9lation d&rsquo;\u00e9v\u00e8nements int\u00e9ressants, comme celui dont il parle dans le texte que nous citons plus bas, sur le r\u00f4le du g\u00e9n\u00e9ral Lemnitzer par rapport \u00e0 des tentatives contre la vie du g\u00e9n\u00e9ral de Gaulle)<\/p>\n<\/p>\n<p><p>\tCottrell ne suppute pas moins que ceci : pourquoi n&rsquo;offrirait-on pas \u00e0 Nicolas Sarkozy, pour employer son \u00e9nergie extr\u00eame et le remercier de ses services rendus, le poste de secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OTAN, lorsque ce poste se lib\u00e9rera (tout de m\u00eame, dans un an, \u00e0 moins que) ?&#8230; Cottrell pr\u00e9cise, \u00e0 propos d&rsquo;un aspect de son hypoth\u00e8se,  mais cela pourrait \u00eatre pris pour l&rsquo;hypoth\u00e8se dans son enti\u00e8ret\u00e9 : \u00ab<em>I admit that I am entertaining a good deal of speculation here<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tPar cons\u00e9quent, nous sommes en pleine supputation. Pour autant, ce n&rsquo;est pas plus b\u00eate que le d\u00e9ferlement, le <em>tsunami<\/em> de d\u00e9sinformation, de m\u00e9sinformation, de contre-information, etc., que repr\u00e9sente aujourd&rsquo;hui l&rsquo;information officielle, \u00e0 \u00eatre prise pour ce qu&rsquo;elle est, r\u00e9f\u00e9rence absolue du mensonge non moins absolu que dispense le Syst\u00e8me dans sa paradoxale lutte autodestructrice pour sa survie. (Paradoxe, certes) Par cons\u00e9quent, nous nous int\u00e9ressons \u00e0 l&rsquo;hypoth\u00e8se de Cottrell, pr\u00e9sent\u00e9e dans <em>EndtheLie<\/em>, le <a href=\"http:\/\/EndtheLie.com\/2012\/05\/08\/is-sarkozy-eyeing-the-nato-top-job-moreover-is-nato-eyeing-him\/#ixzz1uPIVvyoo\" class=\"gen\">9 mai 2012<\/a>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>What next for Nicolas Sarkozy, the man whose political legacy may best be summed up as a stunning collision of pride and prejudice? We hear from his own lips that in the wake of bitter defeat he will now retire from active politics. He is relatively but not magnificently rich, after two costly divorces. Doubtless a board room seat or two will beckon, in order to put something on the table&rsquo;, as the French like to say.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Will he elect to simply spend more time with his Italian wife, the ex-model and fragrant song thrush Carla Bruni, write his memoirs or other great volumes of historical importance or will he perhaps retire to some philosophical cloister where he will meditate on the future of everything and especially those of his fellow countrymen whose folly is to keep the brie (the ancient president&rsquo;s favorite fromage) in the fridge?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>There aren&rsquo;t many top jobs going begging at the moment. The presidency of the European Council  presently held by the strange wizard-like Belgian Herman von Rompuy  is up for grabs in April next year. But that is really a bureaucratic chore which involves a lot of running around Europe to no evident purpose. Not much job satisfaction there so to speak, still less over-endowed with the limelight that Sarkozy so desperately craves.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>There is however one enticing prospect. NATO&rsquo;s very own Viking, the Great Dane Anders Fogh Rasmussen, is coming to the end of his term of office as Secretary General of the mighty military juggernaut.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Now there&rsquo;s a seat vacant that should appeal to a Frenchman with an unsated determination to leave his mark on world affairs. Nor is it strictly speaking expressly political. It is on the other hand one of the great offices of real power in the western camp. Given NATO&rsquo;s over-arching ambitions to conquer the planet, surely an out-of-work president with time on his hands would find the prospect of playing with real guns and soldiers an alluring prospect? The tonic certainly acted on Anders Fogh Rasmussen, coming as he does from a small country renowned for its inclination to pacifism, like high octane Viagra.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>NATO smiles upon the diminutive ex-tenant of the Elysee Palace. NATO&rsquo;s fortunes in France have certainly gone through rocky spells. In the mid 60&#8242;s President Charles De Gaulle evicted the alliance from its headquarters near Paris on the grounds that persistent attempts on his life could be traced to US-inspired plotting. (See below my new book featuring the leading role in these affairs of top US brasshat General Lyman Lemnitzer).<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>The US, in turn, objected to De Gaulle&rsquo;s stubborn insistence on an independent French nuclear deterrent, the force de frappe (striking force) composed of medium range missiles intended to deter a Russian attack. He considered America&rsquo;s obsession with ICBM&rsquo;s (long range rocketry) not only misplaced but more likely to provoke a nuclear war than prevent it. In my opinion, he was right.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>De Gaulle eventually removed all French military personnel from alliance control. Technically France was still a full member of NATO, but she took no further part in its planning or operations. This stand-off lasted for half a century, until the intensely pro-American Sarkozy became president. In 2009 France resumed full NATO duties and obligations.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>That&rsquo;s a good tick in Sarkozy&rsquo;s box<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tSuit une longue digression sur ce qui serait, selon Cottrell qui prend d\u00e9cid\u00e9ment son hypoth\u00e8se au s\u00e9rieux, le principal obstacle \u00e0 la nomination de Sarkozy : une opposition de la Turquie, \u00e0 cause de l&rsquo;antagonisme de Sarko \u00e0 l&rsquo;\u00e9gard de l&rsquo;entr\u00e9e de la Turquie dans l&rsquo;UE, \u00e0 cause de l&rsquo;affaire de la reconnaissance du g\u00e9nocide arm\u00e9nien par la France, etc. Mais, estime Cottrell, nul doute qu&rsquo;on trouverait une issue, comme on en trouva une dans le cas du Danois Rasmussen, dont la nomination au poste de secr\u00e9taire g\u00e9n\u00e9ral s&rsquo;\u00e9tait \u00e9galement heurt\u00e9e \u00e0 l&rsquo;opposition de la Turquie (ran\u00e7on d&rsquo;une \u00e9pouvantable affaire, qui secoua la civilisation, de publication de caricatures peu am\u00e8nes pour le Proph\u00e8te, dans le chef de la presse d\u00e9mocratique danoise) Ainsi, Cottrell, en bon sp\u00e9cialiste des manigances du type <em>Gladio<\/em>, estime-t-il l&rsquo;affaire quasiment faite et termine-t-il par quelques consid\u00e9rations assez peu flatteuses sur Sarko. (Ce en quoi il n&rsquo;a pas vraiment raison, nous semble-t-il, car Sarko n&rsquo;est ni une cause, ni un fondement de la catastrophe qui frappe la France. Il en est une illustration d&rsquo;occasion, un moyen de fortune, une repr\u00e9sentation quasiment d\u00e9mocratique. Ce serait lui faire un m\u00e9chant proc\u00e8s et le juger plus mauvais homme qu&rsquo;il n&rsquo;est, plus habile et machiav\u00e9lique politique, que faire de lui le responsable central du cataclysme. Bref, ce serait, en un sens, lui faire beaucoup d&rsquo;honneur, alors qu&rsquo;il n&rsquo;est que le figurant de circonstance qui s&rsquo;est charg\u00e9 d&rsquo;allumer la m\u00e8che de la bombe.) <\/p>\n<\/p>\n<p><p>\t\u00ab<em>The pliant globalist Sarkozy needs to be flattered and soothed after his defeat. A French voice at the summit of NATO councils meets a lot of US interests in Europe, at a time where NATO&rsquo;s raison d&rsquo;\u00eatre is questioned in many quarters.<\/em> [] <em>France is a pivotal player in NATO which  as we saw in Chicago  is desperately seeking a reason for its continuing existence. Of course that role is world constable&rsquo; which is always attractive to former colonial powers like the UK and France.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>When some people have the impudence to describe Nicholas Sarkozy as an egregious, attention-seeking chump with an outsize French fry on his shoulder, I am surprised only at the degree of under-statement. Personally, I am always reminded of Richard Nixon when I look at Sarkozy&rsquo;s record and personality.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Nonetheless, NATO&rsquo;s lordly planetary ambitions suggest that offering the crown to the man who returned France to the sovereignty is returning a priceless favor. Tricky  thinking again of Nixon  but not impossible. It all hangs on the quality of the diplomacy. It always does.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tFinalement, comme on le comprend, peu nous importe ici la validit\u00e9 de l&rsquo;hypoth\u00e8se, l&rsquo;argumentation rationnelle, sinon factuelle, sinon \u00e9vidente, qu&rsquo;on pourrait lui opposer. Nous importe essentiellement qu&rsquo;un commentateur la consid\u00e8re comme plausible et la d\u00e9veloppe avec s\u00e9rieux comme une hypoth\u00e8se acceptable, en donnant comme argument p\u00e9remptoire qu&rsquo;apr\u00e8s tout l&rsquo;OTAN doit bien cela \u00e0 celui qui a ramen\u00e9 la France dans son giron, apr\u00e8s le coup du g\u00e9n\u00e9ral de Gaulle d&rsquo;il y a cinquante ans. Peu nous importe \u00e9galement que la th\u00e8se de la responsabilit\u00e9 totale de Sarko dans cette \u00e9volution vis \u00e0 vis de l&rsquo;OTAN ne soit pas tr\u00e8s s\u00e9rieuse, car l&rsquo;argument est ici symbolique et la responsabilit\u00e9 est symboliquement \u00e9vidente. Certes, Sarkozy est celui qui, de ce point de vue, a achev\u00e9 de sacrifier l&rsquo;ind\u00e9pendance nationale fran\u00e7aise, au nom d&rsquo;une non-politique et d&rsquo;une absence totale d&rsquo;arguments qui nous indiquent l&rsquo;inf\u00e9condit\u00e9 et l&rsquo;atrophie compl\u00e8te de sa pens\u00e9e ; mais sa pens\u00e9e, comme on l&rsquo;a sugg\u00e9r\u00e9 plus haut, n&rsquo;appara\u00eet que comme un miroir de la situation des \u00e9lites fran\u00e7aises aujourd&rsquo;hui, pour lesquelles la trahison est un pis-aller, une mani\u00e8re de s&rsquo;\u00e9pargner l&rsquo;effort d&rsquo;une r\u00e9flexion ind\u00e9pendante, une vacance du jugement, une atrophie de la psychologie ; pour lesquelles l&rsquo;ind\u00e9pendance nationale est un concept si vide de sens qu&rsquo;on comprend finalement pourquoi ils ont sacrifi\u00e9 si ais\u00e9ment ce dont ils ne savent quoi faire, jusqu&rsquo;\u00e0 en ignorer le sens, voire l&rsquo;existence<\/p>\n<\/p>\n<p><p>\t<em>In illo tempore<\/em>, il est arriv\u00e9 qu&rsquo;on \u00e9voqu\u00e2t la possibilit\u00e9 d&rsquo;un secr\u00e9taire g\u00e9n\u00e9ral fran\u00e7ais \u00e0 l&rsquo;OTAN. L&rsquo;hypoth\u00e8se rencontrait imm\u00e9diatement l&rsquo;opposition US, et pour cause ; cette nomination ne pouvait \u00eatre con\u00e7ue que comme une fa\u00e7on de r\u00e9\u00e9quilibrer l&rsquo;influence US dans l&rsquo;OTAN, de la contrer, de l&rsquo;abaisser, de la minoriser, etc., et l&rsquo;on retrouvait la France dans son r\u00f4le traditionnel, c&rsquo;est-\u00e0-dire conforme \u00e0 la Tradition et au Principe qui la d\u00e9finit. Cette fois, l&rsquo;hypoth\u00e8se farfelue et grotesque d&rsquo;un Sarko avec une casquette de secr\u00e9taire-en-chef de l&rsquo;OTAN vient tout naturellement au terme du jugement, comme une illustration absolument ad\u00e9quate de l&rsquo;\u00e9volution de la politique fran\u00e7aise et de ceux qui la conduisent, ou sont conduits par elle ; c&rsquo;en est \u00e0 un point o\u00f9, \u00e0 la r\u00e9flexion, s\u00e9duit qu&rsquo;on est par sa coh\u00e9rence dans son temps et dans les murs de son temps, on en vient \u00e0 consid\u00e9rer que l&rsquo;hypoth\u00e8se ne serait plus ni farfelue ni grotesque. C&rsquo;est une bonne mesure du d\u00e9labrement moral de la pens\u00e9e politique fran\u00e7aise, moral au sens o\u00f9 l&rsquo;entendait Renan lorsqu&rsquo;il \u00e9crivait <em>La R\u00e9forme intellectuelle et morale de la France<\/em>,  et d&rsquo;ailleurs, avec une similitude \u00e9clairante, puisque l&rsquo;\u00e9tat de d\u00e9labrement de la France aujourd&rsquo;hui vaut bien celui de 1871, lorsque Renan \u00e9crivit son ouvrage. Le probl\u00e8me, pour la France, en 2012, est qu&rsquo;il n&rsquo;a pas fallu une guerre pour tomber aussi bas ; l&rsquo;entra\u00eenement de la dynamique d&rsquo;autodestruction du Syst\u00e8me, la fascination pour la Chute, l&rsquo;attrait de la bassesse, semblent y avoir suffi amplement.<\/p>\n<\/p>\n<p><p>\tReste donc \u00e0 voir la suite, puisque l&rsquo;on sait que l&rsquo;un des caract\u00e8res les plus intrigants de la France est sa capacit\u00e9 de sans cesse aller du plus bas de la chute au plus vigoureux du redressement. Son histoire est pleine de ces montagnes russes, et l&rsquo;on observera avec int\u00e9r\u00eat la suite des affaires pour savoir si la recette reste d&rsquo;application. Ambiance<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 10 mai 2012 \u00e0 13H28<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cauchemardons un peu Sarko \u00e0 l&rsquo;OTAN ? Il faut reconna\u00eetre \u00e0 Richard Cottrell une grande imagination, en plus d&rsquo;une documentation abondante. (Il nous am\u00e8ne des r\u00e9v\u00e9lations diverses dans son livre, qui vient de para\u00eetre ces jours-ci et ne nous est pas encore parvenu : Gladio, NATO&rsquo;s Dagger at the Heart of Europe: The Pentagon-Nazi-Mafia Terror&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[11996,3283,4413,584,7650,13157,4590,6907],"class_list":["post-74700","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-cottrell","tag-general","tag-gladio","tag-otan","tag-rasmussen","tag-renan","tag-sarkozy","tag-secretaire"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74700"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74700\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}