{"id":74707,"date":"2012-05-14T09:15:37","date_gmt":"2012-05-14T09:15:37","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/05\/14\/frederic-lordon-sur-lavenir-du-fn\/"},"modified":"2012-05-14T09:15:37","modified_gmt":"2012-05-14T09:15:37","slug":"frederic-lordon-sur-lavenir-du-fn","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/05\/14\/frederic-lordon-sur-lavenir-du-fn\/","title":{"rendered":"Fr\u00e9d\u00e9ric Lordon sur l&rsquo;avenir du FN"},"content":{"rendered":"<p><h2 class=\"common-article2\">Fr\u00e9d\u00e9ric Lordon sur l&rsquo;avenir du FN<\/h2>\n<\/p>\n<p><p>\t Dans <em>Le Monde diplomatique<\/em>, le <a href=\"http:\/\/blog.mondediplo.net\/2012-05-02-Front-national-memes-causes-memes-effets\" class=\"gen\">2 mai 2012<\/a>, de Fr\u00e9d\u00e9ric Lordon<\/p>\n<\/p>\n<p><p>\t\u00ab<em>La vie politique fran\u00e7aise est<\/em> [&#8230;] <em>bien moins compliqu\u00e9e que ne voudraient le faire croire les experts \u00e0 tirer dans les coins qui se sont fait une sp\u00e9cialit\u00e9 de l&rsquo;\u00e9vitement des questions de fond, et notamment de celle qui (les) f\u00e2che : la question de la mondialisation, et de son incarnation europ\u00e9enne &#8213; \u00e0 l&rsquo;image de l&rsquo;in\u00e9narrable Bernard Guetta qui, apr\u00e8s les baffes successives du TCE, des scrutins d\u00e9sastreux et de la crise europ\u00e9enne sans fond en est toujours \u00e0 trouver insens\u00e9 qu&rsquo;on puisse faire de l&rsquo;Union europ\u00e9enne le cheval de Troie de la mondialisation. Aussi vont-ils r\u00e9p\u00e9tant que tout projet de transformation de cet ordre social n&rsquo;est que repli sur soi&#8230; Le libre-\u00e9change et la finance d\u00e9r\u00e9glement\u00e9e nous d\u00e9truisent, mais toute tentative d&rsquo;\u00e9chapper \u00e0 la destruction commet la faute morale du repli sur soi. Le corps social devrait donc avoir l&rsquo;heur de se laisser d\u00e9truire avec gr\u00e2ce &#8213; et l&rsquo;on s&rsquo;\u00e9tonne qu&rsquo;une part croissante de l&rsquo;\u00e9lectorat prenne le mors aux dents ! Conform\u00e9ment en effet \u00e0 un encha\u00eenement tr\u00e8s semblable \u00e0 celui que Karl Polanyi avait d\u00e9crit \u00e0 propos des ann\u00e9es 1920-1940, le (n\u00e9o)lib\u00e9ralisme, entre in\u00e9galit\u00e9s, rel\u00e9gation des pauvres et d\u00e9r\u00e9liction individualiste, d\u00e9truit la soci\u00e9t\u00e9 . Tr\u00e8s logiquement, et de la m\u00eame mani\u00e8re qu&rsquo;alors, le corps social lutte pour r\u00e9sister \u00e0 sa propre destruction, quitte \u00e0 s&#8217;emparer des pires moyens, parce que toutes autres solutions \u00e9puis\u00e9es, ce sont les seuls, et qu&rsquo;aux d\u00e9sesp\u00e9r\u00e9s quelque chose vaut toujours mieux que rien.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>On dira cependant que, cette ann\u00e9e, un autre moyen il y en avait un, puisqu&rsquo;il y avait un Front de gauche (FdG), et qu&rsquo;il n&rsquo;a pas emp\u00each\u00e9 les 18 % de Le Pen. Mais c&rsquo;est que le FN est dans le paysage depuis trente ans, et le FdG depuis trois ! &#8213; encore n&rsquo;a-t-il eu probablement pour bon nombre d&rsquo;\u00e9lecteurs d&rsquo;existence r\u00e9elle pour la premi\u00e8re fois que cette ann\u00e9e. Or la pr\u00e9sence p\u00e9renne du FN a eu le temps de produire ces pires effets d&rsquo;incrustation, aussi bien, dans les classes populaires, la conversion partielle des col\u00e8res sociales en haines x\u00e9nophobes, que, dans les classes bourgeoises (petites, et parfois grandes), la lib\u00e9ration d&rsquo;un racisme longtemps tenu \u00e0 l&rsquo;isolement par les conventions sociales et la menace de l&rsquo;indignit\u00e9, mais jouissant de nouvelles licences quand 15 % \u00e0 20 % de la population rejoignent ouvertement l&rsquo;extr\u00eame droite &#8213; et qu&rsquo;il est d\u00e9sormais permis de vivre sa \u00ab foi \u00bb \u00e0 l&rsquo;air libre. C&rsquo;est tout cela qu&rsquo;il appartient \u00e0 un Front de gauche de d\u00e9faire, et d&rsquo;en venir \u00e0 bout d\u00e8s son premier scrutin pr\u00e9sidentiel \u00e9tait \u00e0 l&rsquo;\u00e9vidence trop demander. Ceux qui voyaient Jean-Luc M\u00e9lenchon au second tour se sont enivr\u00e9s tout seuls, aid\u00e9s le cas \u00e9ch\u00e9ant de quelques liqueurs sondagi\u00e8res &#8213; mais ceci n&rsquo;\u00e9tait pas raisonnable. Le FdG a fait 6,5 % pour sa premi\u00e8re sortie \u00e9lectorale nationale (les europ\u00e9ennes de 2009), il fait 11 % \u00e0 sa deuxi\u00e8me, ce sont des r\u00e9sultats plus qu&rsquo;encourageants. Mais qui ne doivent pas faire oublier que la construction d&rsquo;une position \u00e9lectorale est une longue patience.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Une patience d&rsquo;autant plus longue en l&rsquo;occurrence qu&rsquo;\u00e0 propos des \u00e9lecteurs FN qu&rsquo;il lui incombe de reconqu\u00e9rir, m\u00eame la gauche (la vraie gauche) commence \u00e0 donner des signes de fatigue intellectuelle. En t\u00e9moignent les refus exasp\u00e9r\u00e9s d&rsquo;entendre seulement dire la France qui souffre. Assez de la souffrance sociale ! et retour aux explications simples et vraies : ce sont des salauds de racistes. Dans une parfaite sym\u00e9trie formelle avec la droite qui, en mati\u00e8re de d\u00e9linquance, refuse les excuses sociologiques, d&rsquo;ailleurs tristement suivie par la (fausse) gauche depuis un sombre colloque de Villepinte en 1997 (\u00e0 chaque terme socialiste ses abandons), voil\u00e0 qu&rsquo;une partie de la (vraie) gauche, en mati\u00e8re de vote FN, ne veut plus de l&rsquo;alibi de la souffrance sociale. Cette commune erreur, qui consiste \u00e0 ne pas faire la diff\u00e9rence entre deux op\u00e9rations intellectuelles aussi h\u00e9t\u00e9rog\u00e8nes que expliquer et justifier (et par suite excuser), finit in\u00e9vitablement en le m\u00eame catastrophique lieu de l&rsquo;imputation d&rsquo;essence, seul \u00e9nonc\u00e9 demeurant disponible quand on s&rsquo;est priv\u00e9 de toute analyse par les causes. Les d\u00e9linquants seront alors la simple figure du mal, n&rsquo;appelant par cons\u00e9quent d&rsquo;autre r\u00e9ponse que la r\u00e9pression. Quant aux \u00e9lecteurs de l&rsquo;extr\u00eame droite, ils sont donc des salauds, appelant quoi d&rsquo;ailleurs ? La colonie lunaire ? Au d\u00e9plaisir g\u00e9n\u00e9ral sans doute, il faudra pourtant faire avec eux.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Le d\u00e9plaisir, voil\u00e0 pr\u00e9cis\u00e9ment l&rsquo;affect \u00e0 laisser \u00e0 sa place autant que possible quand il est tant soit peu question d&rsquo;analyse politique. Et jamais peut-\u00eatre la d\u00e9grisante maxime spinoziste n&rsquo;aura \u00e9t\u00e9 plus n\u00e9cessaire, qui appelle \u00e0 ne pas rire, ne pas d\u00e9plorer, non plus d\u00e9tester, mais comprendre. Sinon la suspension compl\u00e8te du jugement, du moins sa trempe est en l&rsquo;occurrence d&rsquo;autant plus requise que, d&rsquo;un racisme l&rsquo;autre, la d\u00e9mission \u00e0 comprendre le racisme tout court a le plus souvent pour terminus le racisme social : affreux, sales et m\u00e9chants &#8213; on imagine sans peine les effets politiques qu&rsquo;il est permis d&rsquo;attendre d&rsquo;un viatique intellectuel de pareille minceur, et l&rsquo;on notera au passage la sym\u00e9trie tropologique de ces deux cousins oppos\u00e9s, l&rsquo;un comme l&rsquo;autre d\u00e9marrant du m\u00eame pas : \u00e0 la fin, \u00e7a suffit, il faut bien appeler un chat un chat, soit : les \u00e9lecteurs du FN sont des gros cons exactement comme les arabes sont trop nombreux.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Il est bien certain, pour l&rsquo;heure, qu&rsquo;entre le FN qui rafle la mise, Sarkozy qui court derri\u00e8re, et le Front de Gauche encore \u00e0 sa maturation, l&rsquo;\u00e9tat du rapport de force en question n&rsquo;est pas exactement un motif de r\u00e9jouissance. C&rsquo;est donc le PS de Hollande qui est l&rsquo;ultime recours  nous voil\u00e0 propres Car l&rsquo;ultime recours, devenu depuis vingt ans \u00e9tranger \u00e0 la souffrance sociale et aux classes qui l&rsquo;expriment, d\u00e9n\u00e9gateur des destructions de la mondialisation et de l&rsquo;Europe lib\u00e9rale, liquidateur r\u00e9p\u00e9t\u00e9 de ses propres embryons de promesses progressistes, incarnation jusqu&rsquo;\u00e0 la caricature sociologique de l&rsquo;isolement des gouvernants, ignorant tout des conditions de vie des gouvern\u00e9s, ce recours-l\u00e0 porte \u00e0 part \u00e9gale la coresponsabilit\u00e9 historique du d\u00e9sastre politique pr\u00e9sent.<\/em> []<\/p>\n<\/p>\n<p><p>\t \u00bb<em>Le candidat Hollande a d\u00e9j\u00e0 fait savoir que le dispositif central du TSCG, \u00e0 savoir la r\u00e8gle d&rsquo;or comme m\u00e9canisme aveugle de r\u00e9duction des d\u00e9ficits, n&rsquo;attirait pas de sa part la moindre critique de fond. Et on l&rsquo;a moins encore entendu exprimer la moindre protestation \u00e0 l&rsquo;id\u00e9e de l&#8217;empire des march\u00e9s financiers sur les politiques \u00e9conomiques, ni le premier projet d&rsquo;y rem\u00e9dier s\u00e9rieusement. D\u00e9sormais accoutum\u00e9 \u00e0 la verroterie, on peut compter sur lui pour valider les prodigieuses avanc\u00e9es qui verront, \u00e0 l&rsquo;occasion de l&rsquo;un de ces irr\u00e9parables sommets dont l&rsquo;Europe a pris l&rsquo;habitude, la-croissance rejoindre en mots toutes les dispositions qui la tuent en fait.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>On ne saurait que difficilement reprocher aux \u00e9lecteurs du FN d&rsquo;\u00eatre incapables de rapporter leurs mis\u00e8res sociales \u00e0 l&rsquo;article 63 (libert\u00e9 de mouvements des capitaux) ou aux articles 123 (interdiction du financement des d\u00e9ficits par la Banque centrale europ\u00e9enne) et 126 (d\u00e9ficits excessifs) du Trait\u00e9 de Lisbonne, ou \u00e0 l&rsquo;Organisation mondiale du commerce (OMC) ou au comit\u00e9 de B\u00e2le qui en sont pourtant les causes r\u00e9elles mais abstraites, et surtout lointaines &#8213; \u00e0 d\u00e9faut de quoi, comme on sait, la d\u00e9flection du m\u00e9contentement peut \u00e9lire n&rsquo;importe quel fait comme cause prochaine (et derni\u00e8re) : par exemple des Arabes vus \u00e0 la t\u00e9l\u00e9 C&rsquo;est lorsque ceux \u00e0 qui il appartiendrait d&rsquo;\u00e9tablir les connexions r\u00e9elles des causes et des effets commencent \u00e0 manquer \u00e0 leurs devoirs, par la d\u00e9n\u00e9gation, ou pire encore par la diversion, que le d\u00e9bat politique prend un mauvais tour. Or, tout autour du peuple abandonn\u00e9 il n&rsquo;y a plus que cela : pr\u00e9cepteurs de la raison social-lib\u00e9rale occup\u00e9s \u00e0 nier toute implication de leur monde r\u00eav\u00e9 dans les infortunes populaires et \u00e0 exclure m\u00eame que la question soit pos\u00e9e &#8213; des Bernard Guetta &#8213;, ou bien, forme \u00e9videmment plus pernicieuse, crapules politiques affair\u00e9es \u00e0 conforter ces \u00e9lecteurs dans l&rsquo;id\u00e9e qu&rsquo;en effet les Arabes sont le probl\u00e8me et la police la solution. Spectacle \u00e0 laisser la m\u00e2choire pendante, voil\u00e0 qu&rsquo;au beau milieu de la plus grande crise du capitalisme le d\u00e9bat de second tour roule sur le vote des \u00e9trangers et la pr\u00e9somption de l\u00e9gitime d\u00e9fense des flics sans qu&rsquo;aucun des interrogateurs du candidat de droite ne viennent dire le caract\u00e8re \u00e9hont\u00e9 de sa manuvre &#8213; il est vrai que depuis des d\u00e9cennies les m\u00e9dias n&rsquo;ont eu de cesse d&rsquo;escamoter les vrais probl\u00e8mes et de promouvoir les faux, et eux, ce qui est peut-\u00eatre pire, sans la moindre intention manuvri\u00e8re<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Alors tr\u00e8s bien, prolongeons les tendances : un FN resplendissant, une droite d\u00e9sormais accroch\u00e9e \u00e0 ses basques, un Front de gauche sans doute sorti des limbes mais au d\u00e9but seulement de son parcours, un PS frapp\u00e9 de stupeur \u00e0 l&rsquo;id\u00e9e qu&rsquo;on puisse objecter quoi que ce soit de s\u00e9rieux \u00e0 l&rsquo;Europe lib\u00e9rale et \u00e0 la mondialisation, un chur de pr\u00e9cepteurs \u00e9ditocratiques-experts obstin\u00e9 \u00e0 le conforter dans cette sage restriction (comme en t\u00e9moigne incidemment le d\u00e9lire haineux dont a fait l&rsquo;objet la campagne de M\u00e9lenchon, engag\u00e9 \u00e0 poser les questions qui ne doivent pas \u00eatre pos\u00e9es) On cherche la maxime qui, toutes choses \u00e9gales par ailleurs, permettrait d&rsquo;\u00e9clairer par anticipation la situation politique de 2017. Et facilement on trouve : m\u00eames causes, m\u00eames effets.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<strong><em>Fr\u00e9d\u00e9ric Lordon<\/em><\/strong>\u00bb<\/p>\n<\/p>\n<p><p>\tLordon ne semble pas pouvoir \u00eatre plus directement critique du r\u00f4le de Chevalier anti-FN choisi par M\u00e9lenchon. Ni sa perspective th\u00e9orique ni ses engagements ne le lui permettent. Pourtant la fatigue intellectuelle de la vraie gauche face au FN est massivement pr\u00e9sente dans le FG, et je ne crois pas que ceci soit appel\u00e9 \u00e0 changer. Le plus probable est donc que le FG ne d\u00e9collera  pas de son r\u00f4le de rabatteur d&rsquo;un vote radical \u00e0 l&rsquo;usage du PS, et qu&rsquo;on doit oublier <a href=\"http:\/\/www.marianne2.fr\/Europe-les-traders-siffleront-bientot-la-fin-de-la-recre_a216822.html\" class=\"gen\">le r\u00eave<\/a> de Jacques Sapir :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Pour \u00eatre \u00e0 la hauteur de la situation historique qui est la notre, il devra abandonner ses habits d&rsquo;homme d&rsquo;une gauche trop traditionnelle et accepter de rev\u00eatir ceux du p\u00e8re de la Nation, s&rsquo;il<\/em> [M\u00e9lenchon] <em>veut sauver la R\u00e9publique et nous d\u00e9faire des bastilles que nous pr\u00e9parent tant la droite que les socialistes.<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Pour l&rsquo;instant il h\u00e9site. Qu&rsquo;il le sache : le temps n&rsquo;attend pas.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe duel assommant qui se dessine \u00e0 H\u00e9nin-Beaumont ne va pas dans le sens r\u00eav\u00e9. Enfin on verra. 2017 semble tr\u00e8s tr\u00e8s loin.<\/p>\n<\/p>\n<p>\n<p class=\"signature\"><em>GEO<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fr\u00e9d\u00e9ric Lordon sur l&rsquo;avenir du FN Dans Le Monde diplomatique, le 2 mai 2012, de Fr\u00e9d\u00e9ric Lordon \u00abLa vie politique fran\u00e7aise est [&#8230;] bien moins compliqu\u00e9e que ne voudraient le faire croire les experts \u00e0 tirer dans les coins qui se sont fait une sp\u00e9cialit\u00e9 de l&rsquo;\u00e9vitement des questions de fond, et notamment de celle&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[4646,12536,8809,10306,3572,8315,7823],"class_list":["post-74707","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-antisysteme","tag-fn","tag-geo","tag-lordon","tag-marine","tag-melenchon","tag-sapir"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74707"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74707\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}