{"id":74710,"date":"2012-05-15T15:52:40","date_gmt":"2012-05-15T15:52:40","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/05\/15\/bilderberg-il-faut-sauver-la-grece-et-leuro\/"},"modified":"2012-05-15T15:52:40","modified_gmt":"2012-05-15T15:52:40","slug":"bilderberg-il-faut-sauver-la-grece-et-leuro","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/05\/15\/bilderberg-il-faut-sauver-la-grece-et-leuro\/","title":{"rendered":"Bilderberg : il faut sauver la Gr\u00e8ce (et l&rsquo;euro) !"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Bilderberg : il faut sauver la Gr\u00e8ce (et l&rsquo;euro) !<\/h3>\n<\/p>\n<p><p>\tBilderberg, fameux groupes du complot mondialiste, entre dans la s\u00e9quence actuelle de la crise grecque (et de l&rsquo;euro) par la petite porte,  mais une petite porte assez connue des initi\u00e9s et aga\u00e7ante pour le groupe Bilderberg, pour jouer son r\u00f4le. Il s&rsquo;agit d&rsquo;un article publi\u00e9 par Paul Joseph Watson, complice de Alex Jones sur ses sites <em>Infowards.com<\/em> et <em>PrisonPlanet.com<\/em>. L&rsquo;article \u00ab<em>Bilderberg Scheme To Save The Euro,  Globalists fear Greece could exit single currency and stage a miraculous economic recovery<\/em>\u00bb ne nous apprend rien sur les plans du Bilberberg pour sauver l&rsquo;euro (ni pour sauver la Gr\u00e8ce). Au reste, il n&rsquo;est pas vraiment fait pour \u00e7a, puisqu&rsquo;il s&rsquo;agit surtout de faire en sorte d&rsquo;\u00e9viter que la crise grecque, avec un d\u00e9part de la Gr\u00e8ce qui tournerait au contraire d&rsquo;une catastrophe pour ce pays, montre indirectement que la catastrophe c&rsquo;est l&rsquo;euro (Sur <em>Infowars.com<\/em>, le <a href=\"http:\/\/www.infowars.com\/bilderberg-scheme-to-save-the-euro\/\" class=\"gen\">15 mai 2012<\/a>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Bilderberg is terrified not only that Greece will exit the euro, but that in doing so it will go on to see a massive economic rebound and become an example for other eurozone countries to follow the same course. This fear is exemplified in a piece appearing today in Bilderberg-controlled newspaper the Financial Times entitled Greece&rsquo;s exit may become the euro&rsquo;s envy. Expelled from the eurozone, Greece might prove more dangerous to the system than it ever was inside it  by providing a model of successful recovery, writes Arvind Subramanian.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Subramanian is a Senior Fellow at the Peter G. Peterson Institute for International Economics, which counts amongst its directors numerous influential Bilderberg members, including former Federal Reserve chairman Paul Volcker, former United States Treasury Secretary Lawrence Summers, and Bilderberg kingpin David Rockefeller.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Suppose that by mid-2013 Greece&rsquo;s economy is recovering, while the rest of the eurozone remains in recession. The effect on austerity-addled Spain, Portugal and even Italy would be powerful. Voters there would not fail to notice the improving condition of their hitherto scorned Greek neighbour. They would start to ask why their own governments should not follow the Greek path and voice a preference for leaving the eurozone. In other words, the Greek experience could fundamentally alter the incentives for these countries to remain in the eurozone, especially if economic conditions remained grim, writes Subramanian, adding that Greece&rsquo;s potential exit may prove an infectious model and lead to the demise of the eurozone and perhaps for the European project.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Bilderberg is so desperate to save the euro because it represents the entire foundation of their global financial agenda to create regional currencies and carefully-managed bureaucratic federations on the same model as the European Union. If the euro is proven to be a failure, the prospect of achieving the ultimate goal of a global currency is dead for at least the next 100 years<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe groupe Bilderberg est l&rsquo;une des cibles favorites d&rsquo;Alex Jones, auteur, chroniqueur, acteur, producteur de TV, r\u00e9alisateur de film, fameux complotiste et adepte de la d\u00e9nonciation des complots allant de la menace d&rsquo;un gouvernement mondial au montage interne (<em>Inside Job<\/em>) dans l&rsquo;attaque du 11 septembre 2001 ; enfin, on notera que Jones est de tendance pal\u00e9o-conservatrice et libertarienne (partisan de Ron Paul). Alex Jones ne cesse de traquer les r\u00e9unions et les diverses initiatives de Bilderberg, depuis les ann\u00e9es 1990, et particuli\u00e8rement depuis 2001. Le projet tr\u00e8s r\u00e9cent anti-Bilderberg d&rsquo;Alex Jones est de monter une op\u00e9ration <em>Occupy Bilderberg<\/em>, chose assez ais\u00e9ment r\u00e9alisable puisque la r\u00e9union annuelle du groupe se fait aux USA, \u00e0 Chantilly (eh oui), en Virginie, \u00e0 l&rsquo;h\u00f4tel Marriott Washington Dulles, le 31 mai-3 juin. (Parfaite coordination avec la crise Gr\u00e8ce-euro.)<\/p>\n<\/p>\n<p><p>\tL&rsquo;une des plus r\u00e9centes annonces d&rsquo;Alex Jones doit normalement semer un peu plus le d\u00e9sordre \u00e0 l&rsquo;int\u00e9rieur du groupe. D\u00e9velopp\u00e9e par Paul Joseph Watson le <a href=\"http:\/\/www.infowars.com\/sources-inside-bilderberg-spill-cabals-secret-plans\/\" class=\"gen\">13 mai 2012<\/a>, sur <em>Infowars.com<\/em>, il s&rsquo;agit de l&rsquo;information selon laquelle il (Jones) a r\u00e9ussi \u00e0 \u00e9tablir un contact s\u00fbr avec deux sources \u00e0 l&rsquo;int\u00e9rieur du groupe, pour avoir des informations in\u00e9dites en plus des comptes-rendus qui, en g\u00e9n\u00e9ral, parviennent eux-m\u00eames au public par des voix plus ou moins officieuses. C&rsquo;est une annonce assez inhabituelle pour un journaliste qui, d&rsquo;habitude, dissimule qu&rsquo;il a des sources, ou ne les cite qu&rsquo;apr\u00e8s l&rsquo;\u00e9v\u00e9nement, en r\u00e9v\u00e9lant ce que ses sources lui ont confi\u00e9 (mais en prot\u00e9geant leur anonymat, bien s\u00fbr, comme Jones fait dans ce cas). Cette fois, c&rsquo;est l&rsquo;inverse, et cela ressort finalement d&rsquo;une fa\u00e7on parfaite de la tactique de provocation au d\u00e9sordre de Jones ; il s&rsquo;agit d&rsquo;un message au Bilderberg, qui affecte le plus profond m\u00e9pris pour Jones mais le lit r\u00e9guli\u00e8rement, que le m\u00eame Jones dispose d&rsquo;antennes directes dans le groupe. Cela engagera \u00e9ventuellement \u00e0 certaines prudences et attitudes d&rsquo;autorestriction compromettant le travail du groupe, voire de m\u00e9fiances internes empoisonnant ce travail,  esp\u00e8re Jones (et nous avec, apr\u00e8s tout)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Alex Jones has developed two sources within the Bilderberg Group who have confirmed that the secretive cabal is meeting at the Westfields Marriott Washington Dulles hotel in Chantilly, Virginia from May 31st to June 3rd, with further revelations about Bilderberg&rsquo;s 2012 agenda to follow. Jones said he was contacted by somebody inside Bilderberg two years ago and that he also developed another source intimately connected to the organization within the last week.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The code name for the 2012 Bilderberg meeting is the Palm Tree Conference, the source revealed to Jones. Over the last two days, Bilderberg members have been responding to their invitations and confirming their attendance at the 2012 confab, which will definitely take place at the Westfields Marriott. When calling the hotel, invitees use the code words Palm Tree Conference to signal their attendance and book their room. The hotel is closed to all other guests during the Bilderberg Group meeting and has no rooms available on its website for the duration of the confab<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCet ensemble d&rsquo;informations permet d&rsquo;\u00e9valuer un d\u00e9sordre suppl\u00e9mentaire autour de l&rsquo;affaire grecque. Elle alimente un courant brutal (ou plut\u00f4t contre-courant), apparu ces derni\u00e8res heures, pour affirmer une position des groupes de pression et groupes d&rsquo;influence du pouvoir-Syst\u00e8me europ\u00e9en et globaliste <strong>contre<\/strong> la sortie de la Gr\u00e8ce de l&rsquo;euro. (Il y a eu notamment une intervention du Luxembourgeois Juncker, pr\u00e9sident de l&rsquo;Eurogroupe, contre cette hypoth\u00e8se du d\u00e9part de la Gr\u00e8ce.) Cela vient apr\u00e8s plusieurs jours pendant lesquels le mouvement inverse avait \u00e9t\u00e9 enregistr\u00e9 jusqu&rsquo;au constat, hier, que la sortie de la Gr\u00e8ce de l&rsquo;euro \u00e9tait de plus en plus pr\u00e9sent\u00e9e comme acquise, sinon m\u00eame souhaitable. Cette attitude allait de pair avec le d\u00e9veloppement d&rsquo;un jugement s\u00e9v\u00e8re et quelque peu m\u00e9prisant pour la Gr\u00e8ce, selon une habitude clairement \u00e9tablie dans les groupes de direction europ\u00e9enne, ces derni\u00e8res semaines, et certainement depuis les \u00e9lections du 6 mai. Hier matin, le <em>Guardian<\/em> rapportait que la chose \u00e9tait publiquement comment\u00e9e par des personnages d&rsquo;habitude beaucoup plus stricts et discrets<\/p>\n<\/p>\n<p><p>\t\u00ab<em>This morning&rsquo;s early stock markets losses (see 8.05am) were partly triggered by the news that even members of the European Central Bank&rsquo;s governing council have started discussing the prospect of a Greek eurozone exit.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Luc Coene, the central bank governor of Belgium, told the Financial Times yesterday that I guess an amicable divorce  if that was ever needed  would be possible, adding that he&rsquo;d regret such a break-up. Ireland&rsquo;s central bank governor, Patrick Honohan, also claimed that a Greek exit from the eurozone would be rather destabilising but not disastrous. Honohan told a conference in the Estonian capital Tallinn this weekend that it is not necessarily fatal but it is not attractive.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>It&rsquo;s very unusual for senior members of the ECB to speculate about a member leaving the euro. Arguably it simply reflects the political reality in Greece today, where voters rejected the terms of the country&rsquo;s aid deal. Or is it a signal to Athens that the rest of the eurozone would be prepared to see Greece cut adrift?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCette introduction de nouvelles du groupe Bilderberg (via Alex Jones\/Watson), qui ne figureront certainement pas en une du <em>Financial Times<\/em> mais qui sauront atteindre certaines oreilles (les connexions Jones-Bilderberg sont connues), ajoute \u00e0 l&rsquo;impression de d\u00e9sordre g\u00e9n\u00e9ral, avec l&rsquo;image de tr\u00e8s nombreux groupes de pression et d&rsquo;influence en action, la plupart plus ou moins proches du Syst\u00e8me, et pourtant les uns et les autres avec des positions incertaines ou des positions contradictoires. Cela permet de concevoir que la crise grecque, dans sa ni\u00e8me phase, se d\u00e9veloppe dans une dynamique de perception qui tend \u00e0 nouveau \u00e0 s&rsquo;\u00e9tendre \u00e0 l&rsquo;euro, tout en alimentant un d\u00e9sordre g\u00e9n\u00e9ral d&rsquo;excellente facture A cet \u00e9gard, il faut noter que l&rsquo;on est r\u00e9guli\u00e8rement rappel\u00e9 \u00e0 l&rsquo;ordre,  quoique cette fois, plus que de coutume,  quand la crise grecque se r\u00e9veille pour une ni\u00e8me \u00e9ruption, pour r\u00e9aliser que le crise grecque c&rsquo;est d&rsquo;abord et avant tout la crise de l&rsquo;euro, et qu&rsquo;apr\u00e8s la Gr\u00e8ce d&rsquo;autres pays sont en attente, selon l&rsquo;excellente th\u00e9orie des dominos, pour subir le m\u00eame sort. L&rsquo;impression contraire qui est souvent aliment\u00e9e au d\u00e9but de la s\u00e9quence crisique renvoie \u00e0 l&rsquo;habituelle technique de la psychologie-Syst\u00e8me tendant \u00e0 cloisonner la crise du Syst\u00e8me et \u00e0 pratiquer l&rsquo;art du r\u00e9ductionnisme. Il s&rsquo;av\u00e8re finalement toujours difficile de faire croire que la crise du Syst\u00e8me, dans sa version europ\u00e9enne, se r\u00e9sume simplement \u00e0 la crise grecque. Dans tous les cas, les Bilderberg, gr\u00e2ce \u00e0 Alex Jones et \u00e0 ses complices, s&#8217;emploient eux aussi \u00e0 le rappeler, renfor\u00e7ant un peu plus l&rsquo;impression que l&rsquo;\u00e9valuation de cette s\u00e9quence de crise a \u00e9t\u00e9 sous-\u00e9valu\u00e9e dans sa puissance. L&rsquo;int\u00e9r\u00eat de la dite s\u00e9quence est que l&rsquo;\u00e9volution ne d\u00e9pend pas seulement, ou plus seulement, des habituelles pressions des march\u00e9s ou des r\u00e9gulateurs europ\u00e9ens (qui r\u00e9gulent essentiellement la souverainet\u00e9 nationale au moyen du <em>diktat<\/em>, au d\u00e9savantage du pays concern\u00e9) ; cette fois, il y a une dynamique politique interne d\u00e9pendant du principe, qui reste sacro-saint, de la d\u00e9mocratie. Sans doute est-ce cela qui affole les Bilderberg.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 15 mai 2012 \u00e0 15H42<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bilderberg : il faut sauver la Gr\u00e8ce (et l&rsquo;euro) ! Bilderberg, fameux groupes du complot mondialiste, entre dans la s\u00e9quence actuelle de la crise grecque (et de l&rsquo;euro) par la petite porte, mais une petite porte assez connue des initi\u00e9s et aga\u00e7ante pour le groupe Bilderberg, pour jouer son r\u00f4le. Il s&rsquo;agit d&rsquo;un article publi\u00e9&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[9671,4646,8747,4926,3397,14390,3841,12198,583,8559],"class_list":["post-74710","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-alex","tag-antisysteme","tag-bilderberg","tag-complot","tag-euro","tag-globaliste","tag-grece","tag-infowars-com","tag-jones","tag-watson"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74710"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74710\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}