{"id":74733,"date":"2012-05-26T05:44:28","date_gmt":"2012-05-26T05:44:28","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/05\/26\/jacques-sapir-la-grece-va-quitter-leuro-vite\/"},"modified":"2012-05-26T05:44:28","modified_gmt":"2012-05-26T05:44:28","slug":"jacques-sapir-la-grece-va-quitter-leuro-vite","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/05\/26\/jacques-sapir-la-grece-va-quitter-leuro-vite\/","title":{"rendered":"Jacques Sapir : la Gr\u00e8ce va quitter l&rsquo;euro, vite"},"content":{"rendered":"<p><h2 class=\"common-article2\">Jacques Sapir : la Gr\u00e8ce va quitter l&rsquo;euro, vite<\/h2>\n<\/p>\n<p><p>\tL&rsquo;\u00e9conomiste et historien fran\u00e7ais Jacques Sapir consid\u00e8re comme probable le d\u00e9part de la Gr\u00e8ce de la zone euro, tr\u00e8s rapidement, avant m\u00eame les \u00e9lections du 17 juin prochain. Il expose son analyse et la logique de sa pr\u00e9vision dans <em>Marianne2<\/em>. Sapir trace notamment un parall\u00e8le historique avec les ann\u00e9es 1920 et le refus fran\u00e7ais de ren\u00e9gocier la dette allemande, comme analogie historique pour le refus de l&rsquo;UE (de l&rsquo;Allemagne et de la France) de ren\u00e9gocier le m\u00e9morandum qui lie la Gr\u00e8ce \u00e0 une situation \u00e9conomique et sociale intenable. Bien entendu, la rapidit\u00e9 des \u00e9v\u00e8nements constitue une grande diff\u00e9rence dans cette analogie des ann\u00e9es 1920 avec la situation actuelle, de m\u00eame qu&rsquo;on peut \u00e9galement voir des diff\u00e9rences fondamentales dans le cheminement politique des deux situations (causes de la dette allemande, comportement des pays anglo-saxons vis-\u00e0-vis de la France dans les ann\u00e9es 1920).<\/p>\n<\/p>\n<p><p>\tVoici le texte de Jacques Sapir, dans <em>Marianne2<\/em>, le <a href=\"http:\/\/www.marianne2.fr\/Grece-des-politiques-europeennes-detestables_a218896.html?preaction=nl&#038;id=5912605&#038;idnl=26732&#038;\" class=\"gen\">24 mai 2012<\/a>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Les tensions s&rsquo;accumulent en Gr\u00e8ce. La d\u00e9claration faite hier soir par Lucas Papademos (le Premier ministre sortant) sur une possible sortie de l&rsquo;euro n&rsquo;a fait que confirmer une tendance nette depuis pr\u00e8s de dix jours.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>La Gr\u00e8ce a un besoin urgent d&rsquo;une ren\u00e9gociation du m\u00e9morandum afin d&rsquo;en assouplir les termes et d&rsquo;en allonger le d\u00e9lai. Elle ne peut respecter ses engagements, cela se voit et cela se sait. Mais l&rsquo;Allemagne, et malheureusement la France, s&rsquo;obstinent \u00e0 refuser cette ren\u00e9gociation. On peut comprendre pourquoi ; toute ren\u00e9gociation impliquerait la possibilit\u00e9 d&rsquo;autres ren\u00e9gociations. En termes techniques, c&rsquo;est l&rsquo;introduction d&rsquo;un al\u00e9a moral massif dans les relations entre la Gr\u00e8ce et ses partenaires. Mais, en r\u00e9alit\u00e9, le m\u00e9morandum est en train de tuer le pays, de le conduire au chaos \u00e9conomique, social et demain politique. Nous r\u00e9p\u00e9tons le drame des r\u00e9parations allemandes au lendemain de la Premi\u00e8re Guerre mondiale ou l&rsquo;obstination, l\u00e0 du gouvernement fran\u00e7ais, avait plong\u00e9 l&rsquo;Allemagne dans le chaos. Ce retour aux erreurs des ann\u00e9es 20 et des ann\u00e9es 30 (les politiques de d\u00e9flation) a quelque chose de tragique, comme si les politiciens n&rsquo;avaient rien appris, ou tout oubli\u00e9.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Cette ren\u00e9gociation se heurte \u00e0 l&rsquo;inflexibilit\u00e9 de l&rsquo;Allemagne, suivie sur ce (mauvais) terrain par notre gouvernement qui, obnubil\u00e9 par les euro-obligations, veut croire qu&rsquo;il pourra arracher de substantiels compromis en \u00e9change d&rsquo;un front commun sur la rigueur face \u00e0 la Gr\u00e8ce. Jamais strat\u00e9gie de n\u00e9gociation ne s&rsquo;est av\u00e9r\u00e9e aussi tragiquement fautive. Si un compromis peut \u00eatre arrach\u00e9 \u00e0 l&rsquo;Allemagne, ce ne sera pas avant plusieurs mois, et pour des montants qui s&rsquo;av\u00e8reront tr\u00e8s inf\u00e9rieurs aux espoirs fran\u00e7ais. D&rsquo;ici l\u00e0 nous aurons le drame grec et tr\u00e8s probablement un retour de la crise espagnole (le gouvernement s&rsquo;av\u00e8re incapable de tenir les budgets des r\u00e9gions et doit dans le m\u00eame temps consacrer des sommes immenses \u00e0 la recapitalisation bancaire) et irlandaise. Il faut comprendre que la crise grecque ne peut \u00eatre dissoci\u00e9e de la crise g\u00e9n\u00e9rale de la zone euro, crise dont les manifestations sont \u00e9videntes en Espagne, mais aussi au Portugal et en Irlande, ou encore en Italie.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>La seule strat\u00e9gie possible et jouable consiste \u00e0 mettre l&rsquo;Allemagne devant ses responsabilit\u00e9s, en la mena\u00e7ant de lui faire porter le fardeau d&rsquo;un \u00e9clatement de la zone euro. Croit-on, en effet, que Berlin serait tr\u00e8s heureux d&rsquo;une sortie de la France accompagn\u00e9e d&rsquo;une d\u00e9valuation de 25% ? Croit-on que, politiquement, l&rsquo;Allemagne puisse assumer l&rsquo;\u00e9clatement de l&rsquo;Europe ? On oublie trop souvent que ce n&rsquo;est pas avec des ris et des sourires que l&rsquo;on n\u00e9gocie. Et si jamais l&rsquo;Allemagne s&rsquo;ent\u00eatait, alors la France devrait en tirer les cons\u00e9quences et proposer \u00e0 ses autres partenaires la solution d&rsquo;une dissolution de la zone euro, avec une entente sur les montants des d\u00e9valuations respectives. \u00c0 terme, cela permettrait de reconstituer une zone de coordination mon\u00e9taire en se prot\u00e9geant soigneusement des march\u00e9s financiers, dont l&rsquo;Allemagne et ses alli\u00e9s seraient exclus.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Faute d&rsquo;une ren\u00e9gociation, il est donc probable que la Gr\u00e8ce sortira de l&rsquo;euro avant les \u00e9lections du 17 juin. La dimension d&rsquo;une politique de classe est pr\u00e9sente en Gr\u00e8ce. Les poss\u00e9dants ont d\u00e9j\u00e0 fait sortir le maximum d&rsquo;argent du pays. Ils esp\u00e8rent qu&rsquo;une sortie chaotique leur permettra de renforcer leur pouvoir sur l&rsquo;\u00e9conomie du pays, et d&rsquo;ores et d\u00e9j\u00e0 ils rach\u00e8tent les biens des classes moyennes brutalement appauvries par la politique du m\u00e9morandum. Dans les conditions qui s&rsquo;annoncent, la sortie de l&rsquo;euro sera l&rsquo;occasion d&rsquo;une immense redistribution de la propri\u00e9t\u00e9 aux profits des quelques-uns qui ont d\u00e9j\u00e0 s\u00e9curis\u00e9 depuis plusieurs mois leur fortune.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Le gouvernement issu des \u00e9lections du 17 juin aura donc devant lui la formidable t\u00e2che de faire en sorte que cette sortie de l&rsquo;euro, accompagn\u00e9e d&rsquo;un d\u00e9faut sur la dette publique, puisse se passer du mieux possible. Il devra reprendre la main sur la question du partage des propri\u00e9t\u00e9s et faire en sorte que la croissance attendue profite en premier lieu au plus grand nombre. Il serait logique de l&rsquo;y aider. Mais, on peut craindre que les pays de la zone euro ne pratiquent \u00e0 l&rsquo;\u00e9gard de la Gr\u00e8ce une politique de la terre br\u00fbl\u00e9e, ne serait-ce que pour d\u00e9montrer les co\u00fbts d&rsquo;une sortie. Que notre gouvernement prenne garde. S&rsquo;il devait donner la main \u00e0 une telle politique, ce serait une rupture totale entre lui et la gauche r\u00e9elle. Notre avenir passe par Ath\u00e8nes.<\/em>\u00bb<\/p>\n<\/p>\n<p>\n<p class=\"signature\"><em>dedefensa.oreg<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jacques Sapir : la Gr\u00e8ce va quitter l&rsquo;euro, vite L&rsquo;\u00e9conomiste et historien fran\u00e7ais Jacques Sapir consid\u00e8re comme probable le d\u00e9part de la Gr\u00e8ce de la zone euro, tr\u00e8s rapidement, avant m\u00eame les \u00e9lections du 17 juin prochain. Il expose son analyse et la logique de sa pr\u00e9vision dans Marianne2. Sapir trace notamment un parall\u00e8le historique&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[14850,4043,2748,3484,4141,3397,3841,7627,14849,7823],"class_list":["post-74733","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-14850","tag-4043","tag-allemagne","tag-annees","tag-elections","tag-euro","tag-grece","tag-juin","tag-reparations","tag-sapir"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74733"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74733\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}