{"id":74770,"date":"2012-12-31T12:55:45","date_gmt":"2012-12-31T12:55:45","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/12\/31\/notes-sur-les-cahiers-ddecrisis\/"},"modified":"2012-12-31T12:55:45","modified_gmt":"2012-12-31T12:55:45","slug":"notes-sur-les-cahiers-ddecrisis","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/12\/31\/notes-sur-les-cahiers-ddecrisis\/","title":{"rendered":"Notes sur <em>Les Cahiers<\/em> (<em>dde.crisis<\/em>)"},"content":{"rendered":"<p><h2>Notes sur <em>Les Cahiers<\/em> (<em>dde.crisis<\/em>)<\/h2>\n<\/p>\n<p><p>Avec l&rsquo;immense optimisme qui nous caract\u00e9rise, nous annoncions, le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_l_op_rationnalit_du_mal_et_la_russie_ddecrisis_10_09_2012.html\">10 septembre 2012<\/a>, le num\u00e9ro suivant de <em>dde.crisis<\/em> pour le mois d&rsquo;octobre, &ndash; et le voici en janvier 2013. Mais ce retard n&rsquo;est pas enti\u00e8rement du \u00e0 des circonstances de contrainte puisque, d\u00e8s la fin octobre d\u00e9but novembre nous aurions ou publier ce num\u00e9ro. De cette volont\u00e9 de retarder cette parution, nous nous expliquons pr\u00e9cis\u00e9ment dans notre \u00e9ditorial de ce qui est d\u00e9sormais une \u00ab\u00a0nouvelle collection\u00a0\u00bb de <em>dde.crisis<\/em>, sous le titre de  : <em>Les Cahiers de dde.crisis<\/em>.<\/p>\n<\/p>\n<p><p>Nous reproduisons le texte de cet \u00e9ditorial ci-dessous ; puis, quelques explications compl\u00e9mentaires.<\/p>\n<\/p>\n<p><h3>&Eacute;ditorial, janvier 2013<\/h3>\n<\/p>\n<p><p>&laquo; Bien entendu, ce \u00ab\u00a0num\u00e9ro\u00a0\u00bb de <em>dde.crisis<\/em>, &ndash; qui n&rsquo;en est pas un puisque nous ne parlerons plus de \u00ab\u00a0num\u00e9ro\u00a0\u00bb, &ndash; para&icirc;tra \u00e0 premi\u00e8re vue, \u00e0 nos lecteurs r\u00e9guliers et fid\u00e8les, sans queue ni t\u00eate dans le cours de ce qui \u00e9tait jusqu&rsquo;alors une parution r\u00e9guli\u00e8re. L&rsquo;on sait que la formule a chang\u00e9, depuis le rythme de la parution mensuelle. D\u00e9sormais, le rythme n&rsquo;est plus impos\u00e9, une nouvelle \u00e9volution se fait. En quelque sorte, nous marchons, nous volons au rythme de l&rsquo;Histoire, dans tous les cas pour l&rsquo;\u00e9volution de la formule&hellip;<\/p>\n<\/p>\n<p><p>&raquo; (En plus, disons-le tout de suite au risque de briser le rythme de cet \u00e9ditorial, nous avons, chevill\u00e9e au corps et \u00e0 l&rsquo;\u00e2me, une volont\u00e9 qui tient comme la flamme d&rsquo;une bougie : faire en sorte que <em>dde.crisis<\/em> ne meurt pas&#8230; Ayant mesur\u00e9 notre incapacit\u00e9 \u00e0 poursuivre le rythme de cette parution mensuelle par rapport aux sujets trait\u00e9s, et cela en plus du travail du site, il nous a fallu effectuer une reconversion, nous imposer une lib\u00e9ration de nous-m\u00eames en nous lib\u00e9rant des fers d&rsquo;une parution si contraignante. Cela n&rsquo;alla pas sans souffrances, h\u00e9sitations et incertitudes&hellip;)<\/p>\n<\/p>\n<p><p>&raquo; La Lettre d&rsquo;Analyse <em>dedefensa &#038; eurostrat\u00e9gie<\/em> initiale (publi\u00e9e depuis le 10 septembre 1985, comme le temps passe), sur les questions strat\u00e9giques et politiques, \u00e9tait devenue, le 10 septembre 2009, <em>dde.crisis<\/em> en m\u00eame temps que la formule et le sujet \u00e9voluaient radicalement pour s&rsquo;imposer comme une cha&icirc;ne de r\u00e9flexion m\u00e9tahistorique sur la crise terminale de notre temps et de notre contre-civilisation ; voil\u00e0 que tout cela se poursuit avec cette transformation act\u00e9e par le titre nouveau, <em>Les Cahiers de dde.crisis<\/em>. Il s&rsquo;agit d&rsquo;affirmer par ce nouveau titre de la collection, le caract\u00e8re autonome et int\u00e9gr\u00e9 de chacun des num\u00e9ros, leur compl\u00e8te libert\u00e9 par rapport aux \u00e9v\u00e9nements, leur compl\u00e8te lib\u00e9ration par rapport aux contraintes d&rsquo;une parution r\u00e9guli\u00e8re. Symboliquement, nous attendons la nouvelle ann\u00e9e 2013 pour introduire cette nouvelle collection.<\/p>\n<\/p>\n<p><p>&raquo; (Ce n&rsquo;est pas une observation de circonstance, pour dissimuler un retard par rapport \u00e0 ce que pr\u00e9voyions de faire : il est vrai que ce num\u00e9ro est pr\u00eat depuis au moins deux mois, \u00e0 quelques retouches finales pr\u00e8s, qui auraient pris quelques minutes, une heure ou deux, pas plus&#8230; Mais, comment dire ce sentiment, cette circonstance ? Une sorte d&rsquo;impulsion restrictive nous a retenu, nous a fait repousser la date de publication, pour la faire correspondre \u00e0 un symbole, c&rsquo;est-\u00e0-dire une rupture symbolique, marquant peut-\u00eatre, nous l&rsquo;esp\u00e9rons sans doute, malgr\u00e9 l&rsquo;\u00e2ge v\u00e9n\u00e9rable qui nous caract\u00e9rise, marquant quelque chose comme un nouvel envol&#8230; <em>dedefensa<\/em> est-il une sorte de ph\u00e9nix?)<\/p>\n<\/p>\n<p><p>&raquo; Quoi qu&rsquo;il en soit de ces diverses sornettes, le premier <em>Cahier de dde.crisis<\/em> para&icirc;t ces premiers jours de 2013. Nous avons pass\u00e9 2012, l&rsquo;ann\u00e9e de notre rupture. Nous sommes dans un monde rompu. Cette civilisation qui s&rsquo;\u00e9tait vendue au Diable en devenant contre-civilisation est disloqu\u00e9e, d\u00e9membr\u00e9e, dispers\u00e9e. A nous d&rsquo;observer la venue des temps nouveaux. &raquo;<\/p>\n<\/p>\n<p><h3>Une note personnelle<\/h3>\n<\/p>\n<p><p>S&rsquo;il fallait en trouver une pour d\u00e9finir le moteur de notre tentative de transformation de <em>dde.crisis<\/em> en une formule viable, \u00e9pargn\u00e9e de contraintes insupportables, pourtant dans l&rsquo;esp\u00e9rance de sauver ce qui a fait \u00e0 nos yeux l&rsquo;essentiel de la valeur de cette formule, c&rsquo;est bien cette phrase-l\u00e0 que nous retiendrions&hellip; &laquo; En plus, disons-le tout de suite au risque de briser le rythme de cet \u00e9ditorial, nous avons, chevill\u00e9e au corps et \u00e0 l&rsquo;\u00e2me, une volont\u00e9 qui tient comme la flamme d&rsquo;une bougie : faire en sorte que <em>dde.crisis<\/em> ne meurt pas&#8230; &raquo;<\/p>\n<\/p>\n<p><p>C&rsquo;est cette mission de sauvegarde qui nous donne l&rsquo;\u00e9lan n\u00e9cessaire pour tenter de mettre en marche cette formule des <em>Cahiers<\/em>. L&rsquo;on comprend que notre ambition, c&rsquo;est de remplacer ce que nous perdons en quantit\u00e9, par la qualit\u00e9. Cette ambition, finalement, revient \u00e0 faire de <em>dde.crisis<\/em> des \u00ab\u00a0<em>Cahiers<\/em> de m\u00e9taphysique\u00a0\u00bb accompagnant, du plus haut qu&rsquo;il nous est possible, la marche des \u00e9v\u00e9nements telle qu&rsquo;elle est d\u00e9crite sur le site <em>dedefensa.org<\/em>. C&rsquo;est une entreprise d\u00e9licate, et l&rsquo;ambition est \u00e0 mesure, et le risque, enfin, bien grand de se perdre dans des orientations malheureuses. Nous mesurons tout cela.<\/p>\n<\/p>\n<p><p>&hellip;Fort bien ! La mesure ayant \u00e9t\u00e9 prise, nous allons nous y mettre. Nous ignorons \u00e0 quel rythme de parution nous pouvons arriver. (C&rsquo;est justement l&rsquo;enjeu de la nouvelle formule, ou sa facilit\u00e9 c&rsquo;est selon.) Nous pensons que la chose vaut d&rsquo;\u00eatre tent\u00e9e, non seulement pour faire survivre <em>dde.crisis<\/em>, alias <em>dedefensa &#038; eurostrat\u00e9gie<\/em>, ce qui est un argument par trop sentimental, mais d&rsquo;une fa\u00e7on bien plus fondamentale, parce que cette \u00e9poque et l&rsquo;analyse que nous en faisons constamment m\u00e9ritent sans aucun doute des tentatives de cette sorte. Il s&rsquo;agit d&rsquo;explorer des domaines qu&rsquo;on laisse d&rsquo;habitude bien \u00e9loign\u00e9s des \u00e9v\u00e9nements du monde, pour cause d&rsquo;incompatibilit\u00e9 para&icirc;t-il, de <em>diktat<\/em> des mandarinats universitaires et assimil\u00e9s, d&rsquo;appr\u00e9ciation sourcilleuse de critiques libres plac\u00e9s en embuscade pour emp\u00eacher les autres de l&rsquo;\u00eatre trop, du soin minutieux qu&rsquo;a pris en g\u00e9n\u00e9ral notre Syst\u00e8me de tout compartimenter pour d\u00e9courager toute tentative de synth\u00e8se g\u00e9n\u00e9rale de la situation du monde.<\/p>\n<\/p>\n<p><p>Bref, dans tout cela rien de nouveau. On reconna&icirc;t la d\u00e9marche constante de <em>dedefensa.org<\/em>, depuis les origines et sans jamais s&rsquo;en \u00eatre dissimul\u00e9. Dans les tous prochains jours, premiers jours de 2013, para&icirc;tront le premier <em>dde.crisis<\/em> de la nouvelle collection <em>Les Cahiers<\/em>, et un texte de pr\u00e9sentation normalement publi\u00e9 sur ce site <em>dedefensa.org<\/em>, comme nous avions l&rsquo;habitude de le faire pour <em>dde.crisis<\/em> premi\u00e8re formule, exposant les grands th\u00e8mes du num\u00e9ro.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur Les Cahiers (dde.crisis) Avec l&rsquo;immense optimisme qui nous caract\u00e9rise, nous annoncions, le 10 septembre 2012, le num\u00e9ro suivant de dde.crisis pour le mois d&rsquo;octobre, &ndash; et le voici en janvier 2013. Mais ce retard n&rsquo;est pas enti\u00e8rement du \u00e0 des circonstances de contrainte puisque, d\u00e8s la fin octobre d\u00e9but novembre nous aurions ou&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[16],"tags":[15320,8254,2651,8137,2913,3041,12967],"class_list":["post-74770","post","type-post","status-publish","format-standard","hentry","category-notre-situation","tag-cahiers","tag-dde-crisis","tag-du","tag-editorial","tag-les","tag-mal","tag-proximite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74770"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74770\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}