{"id":74788,"date":"2013-01-10T07:29:44","date_gmt":"2013-01-10T07:29:44","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/01\/10\/la-fausse-vertu-du-fmi\/"},"modified":"2013-01-10T07:29:44","modified_gmt":"2013-01-10T07:29:44","slug":"la-fausse-vertu-du-fmi","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/01\/10\/la-fausse-vertu-du-fmi\/","title":{"rendered":"La fausse vertu du FMI"},"content":{"rendered":"<p><h2 class=\"common-article2\">La fausse vertu du FMI<\/h2>\n<\/p>\n<p><p>\tCela fait des d\u00e9cennies que le FMI a \u00e9t\u00e9 accus\u00e9 par quelques rares \u00e9conomistes latino-am\u00e9ricains puis europ\u00e9ens de contribuer \u00e0 la prise en main des \u00e9conomies des pays pauvres en imposant \u00e0 ceux-ci des programmes dits d&rsquo;ajustement structurel visant \u00e0 r\u00e9aliser diff\u00e9rentes r\u00e9formes politiques en \u00e9change de pr\u00eats dudit FMI. <\/p>\n<\/p>\n<p><p>\tSi certaines de ces r\u00e9formes, telles la lutte contre la corruption, se justifiaient, l&rsquo;essentiel visait \u00e0 privatiser de nombreuses activit\u00e9s jusqu&rsquo;ici exerc\u00e9es par des structures politiques et sociales traditionnelles. L&rsquo;irruption en force des grandes entreprises am\u00e9ricaines dans ces secteurs avait provoqu\u00e9 l&rsquo;apparition de nouvelles classes dirigeantes soumises aux imp\u00e9ratifs de l&rsquo;\u00e9conomie am\u00e9ricaine, sans que la pauvret\u00e9 et le sous-\u00e9quipement en soient s\u00e9rieusement diminu\u00e9s. Les populations avaient fini par s&rsquo;en apercevoir. A la suite de l&rsquo;argentin Nestor Kirchner, un nombre croissant d&rsquo;hommes politiques et d&rsquo;\u00e9conomistes de ces pays avaient fini par contester la vertu pr\u00f4n\u00e9e par le FMI et sa comparse la Banque Mondiale, qui cachaient des app\u00e9tits anglo-saxon autrement plus ambitieux, mais mieux dissimul\u00e9s. <\/p>\n<\/p>\n<p><p>\tLe FMI a-t-il chang\u00e9 depuis ces \u00e9poques? En apparence la duret\u00e9 de son discours contre la mauvaise gestion et la dette s&rsquo;est un peu att\u00e9nu\u00e9. Mais le fonds de sa d\u00e9marche, visant \u00e0 r\u00e9server aux bons \u00e9l\u00e8ves du capitalisme les ressources qu&rsquo;il collecte parmi ses membres n&rsquo;a pas chang\u00e9. Ces bons \u00e9l\u00e8ves sont, plus que jamais, ceux qui lib\u00e9ralisent l&rsquo;acc\u00e8s aux ressources traditionnelles, qui d\u00e9sengagent les Etats de toute politique \u00e9conomique et sociale, qui livrent les pays concern\u00e9s aux grands investisseurs internationaux, investisseurs industriels puis de plus en plus financiers. Certains avaient pens\u00e9 que Dominique Strauss-Kahn, en ouvrant un peu le FMI aux pays \u00e9mergents, aurait pu modifier quelque peu le r\u00f4le de l&rsquo;organisme dans la mondialisation. Mais DSK a chut\u00e9 comme l&rsquo;on sait, \u00e0 la satisfaction sinon \u00e0 l&rsquo;instigation de ceux qu&rsquo;il inqui\u00e9tait \u00e0 Washington. <\/p>\n<\/p>\n<p><p>\tAujourd&rsquo;hui, le FMI, en reprenant sans nuances le discours du d\u00e9sendettement par la rigueur au d\u00e9triment des investissements publics productifs, m\u00e8ne \u00e0 l&rsquo;\u00e9gard de l&rsquo;Europe la m\u00eame politique de d\u00e9structuration qu&rsquo;il menait pr\u00e9c\u00e9demment \u00e0 l&rsquo;\u00e9gard des pays du tiers monde. Tout para\u00eet con\u00e7u pour emp\u00eacher les pays europ\u00e9ens de puiser dans leurs ressources productives potentielles pour s&rsquo;\u00e9manciper de la quasi-colonisation impos\u00e9e par les forces \u00e9conomiques et financi\u00e8res dominant \u00e0 Wall Street et Washington. Bien entendu, cette politique s&rsquo;appuie sur les larges minorit\u00e9s d&rsquo;int\u00e9r\u00eats europ\u00e9ens acquis \u00e0 l&rsquo;atlantisme, qui croient y trouver leur compte. <\/p>\n<\/p>\n<p><p>\tPour conduire une telle d\u00e9marche de d\u00e9c\u00e9r\u00e9bralisation, un langage brutal de conqu\u00eate ne serait pas tr\u00e8s adroit. Il prend au contraire la forme d&rsquo;une pl\u00e9thore de th\u00e9ories \u00e9conomiques et de mod\u00e8les math\u00e9matiques cens\u00e9s incarner une science omnisavante, devant s&rsquo;imposer tant aux peuples qu&rsquo;aux gouvernements. Mais il ne trompe que les na\u00effs et les incomp\u00e9tents r\u00eavant \u00e0 la possibilit\u00e9 d&rsquo;une \u00e9conomie politique scientifique pouvant r\u00e9guler un monde fait de comp\u00e9titions brutales pour les ressources et les pouvoirs. <\/p>\n<\/p>\n<p><p>\tOn s&rsquo;explique mieux dans ces conditions la divine surprise des Europ\u00e9ens d\u00e9couvrant ce jour, gr\u00e2ce \u00e0 la \u00ab confession \u00bb tardive d&rsquo;un expert du FMI (<a href=\"http:\/\/blogs.mediapart.fr\/blog\/hubert-huertas\/090113\/extraordinaire-lausterite-est-une-erreur-mathematique\" class=\"gen\">lien<\/a>) qu&rsquo;il n&rsquo;existait aucune base scientifique s\u00e9rieuse permettant de faire correspondre la r\u00e9duction d&rsquo;un euro dans les budgets publics \u00e0 une r\u00e9duction d&rsquo;un euro dans le produit national du pays concern\u00e9. Tout montre au contraire que joue un effet multiplicateur inverse. Un euro non d\u00e9pens\u00e9 par le budget public entraine plusieurs euro non d\u00e9pens\u00e9s et donc non investies par les acteurs \u00e9conomiques du pays concern\u00e9s. Ainsi les Europ\u00e9ens face \u00e0 des Am\u00e9ricains et Asiatiques qui investissent \u00e0 tour de bras avec l&rsquo;argent vers\u00e9 lib\u00e9ralement par leurs banques centrales, se retrouvent les jambes entrav\u00e9es dans la course qui les oppose \u00e0 leurs rivaux. Le ph\u00e9nom\u00e8ne \u00e9tait depuis longtemps d\u00e9nonc\u00e9 par certaines oppositions socialistes, ou par des \u00e9conomistes atterr\u00e9s. Mais on a pu constater, dans le cas fran\u00e7ais, qu&rsquo;une fois arriv\u00e9s au pouvoir, ces socialistes ont repris \u00e0 leur compte le discours r\u00e9pressif des forces financi\u00e8res internationales. J\u00e9rome Cahuzac, dans sa discussion avec Jean-Luc M\u00e9lanchon le 7 janvier, s&rsquo;en est fait le porte parole jusqu&rsquo;\u00e0 la caricature (voir y compris une vid\u00e9o de l&rsquo;\u00e9mission, \u00e0 ce <a href=\"http:\/\/www.francetvinfo.fr\/face-a-face-cahuzac-melenchon-gauche-realiste-contre-lutte-des-classes_199379.html\" class=\"gen\">lien<\/a>). <\/p>\n<\/p>\n<p><p>\tEst-ce \u00e0 dire que les citoyens europ\u00e9ens vont, d\u00e9couvrant l&rsquo;ineptie des contraintes impos\u00e9es par les gouvernements et le FMI, exiger enfin des changements profonds dans les trait\u00e9s soumettant la Banque centrale europ\u00e9enne \u00e0 la domination du capitalisme international? Probablement pas. Sans penser qu&rsquo;\u00e0 proprement parler un complot organis\u00e9 des oligarchies internationales s&rsquo;exerce pour emp\u00eacher les peuples europ\u00e9ens de r\u00e9agir, on peut cependant faire l&rsquo;hypoth\u00e8se que des forces profondes sont en jeu dans le monde actuel pour maintenir l&rsquo;assujettissement des citoyens de la base aux forces dominantes. On parlera d&rsquo;un Syst\u00e8me, dont l&rsquo;\u00e9tude et la d\u00e9nonciation devrait \u00eatre une priorit\u00e9. Cela fait longtemps que Dedefensa recommande cette d\u00e9marche salutaire. Le terme de Syst\u00e8me sera jug\u00e9 peu scientifique. Mais il l&rsquo;est au moins autant que les mod\u00e8les math\u00e9matiques du FMI.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Jean-Paul Baquiast<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La fausse vertu du FMI Cela fait des d\u00e9cennies que le FMI a \u00e9t\u00e9 accus\u00e9 par quelques rares \u00e9conomistes latino-am\u00e9ricains puis europ\u00e9ens de contribuer \u00e0 la prise en main des \u00e9conomies des pays pauvres en imposant \u00e0 ceux-ci des programmes dits d&rsquo;ajustement structurel visant \u00e0 r\u00e9aliser diff\u00e9rentes r\u00e9formes politiques en \u00e9change de pr\u00eats dudit FMI.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[7895,6837,4965,3014],"class_list":["post-74788","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-baquiast","tag-dsk","tag-fmi","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74788"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74788\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}