{"id":74807,"date":"2013-01-22T14:46:14","date_gmt":"2013-01-22T14:46:14","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/01\/22\/pray-for-me\/"},"modified":"2013-01-22T14:46:14","modified_gmt":"2013-01-22T14:46:14","slug":"pray-for-me","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/01\/22\/pray-for-me\/","title":{"rendered":"\u00ab<em>Pray for me<\/em>\u00bb"},"content":{"rendered":"<p><h3 class=\"titrebloc\">\u00ab<em>Pray for me<\/em>\u00bb<\/h3>\n<\/p>\n<p><p>\t<em>Nostra maxima culpa<\/em> Nous avons souvent fait le portrait de Leon Panetta comme un bon vivant porteur d&rsquo;une liste Secret D\u00e9fense des meilleurs restaurants de Washington, mais le portrait s&rsquo;av\u00e8re incomplet. Certes, le secr\u00e9taire \u00e0 la d\u00e9fense US est un bon vivant mais il est aussi un homme de foi, catholique pratiquant. Sa visite, le 16 janvier 2013, au pape Beno\u00eet XVI n&rsquo;avait rien de diplomatique ni aucun rapport avec les int\u00e9r\u00eats de sa position puisque son successeur (Hagel) est d\u00e9j\u00e0 nomm\u00e9 et le remplacera d\u00e8s que le processus de confirmation du Congr\u00e8s sera parvenu \u00e0 son terme (de toutes les fa\u00e7ons, Hagel confirm\u00e9 ou pas, Panetta, qui a 74 ans, a d\u00e9cid\u00e9 de quitter ses fonctions publiques). Sa visite marquait donc essentiellement le souhait du catholique de rendre compte selon ses convictions,  sinon de se confesser,  \u00e0 propos de ses ann\u00e9es de pouvoir pass\u00e9es \u00e0 la CIA et au Pentagone.<\/p>\n<\/p>\n<p><p>\tIl est vrai qu&rsquo;une telle rencontre, \u00e0 un tel moment de la carri\u00e8re d&rsquo;un secr\u00e9taire \u00e0 la d\u00e9fense, ou pour toute autre personnalit\u00e9 de ce rang dans ces conditions d&rsquo;ailleurs, constitue une occurrence tout \u00e0 fait exceptionnelle. L&rsquo;analyste Ray S. McGovern, lui-m\u00eame ancien analyste de la CIA pass\u00e9 \u00e0 la dissidence de la critique de la politique ext\u00e9rieure de puissance des USA, nous pr\u00e9sente Panetta en visite au Vatican, pour demander la b\u00e9n\u00e9diction du Pape (le <a href=\"http:\/\/consortiumnews.com\/2013\/01\/19\/the-moral-torment-of-leon-panetta\/\" class=\"gen\">19 janvier 2013<\/a>, sur <em>Consortium.News<\/em>).<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Defense Secretary Leon Panetta, a practicing Catholic, sought a blessing on Wednesday from Pope Benedict XVI. Afterward Panetta reported that the Pope said, Thank you for helping to keep the world safe to which Panetta replied, Pray for me. In seeking those prayers, Panetta knows better than the Pope what moral compromises have surrounded him during his four years inside the Obama administration, as CIA director overseeing the covert war against al-Qaeda and as Defense Secretary deploying the largest military on earth.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tMcGovern est, lui aussi, un catholique pratiquant, et il consid\u00e8re cette implication religieuse, marqu\u00e9e pour les deux hommes (Panetta et lui) par une \u00e9ducation commune chez les J\u00e9suites, comme un aspect tr\u00e8s important de la personnalit\u00e9 et de l&rsquo;engagement dans des affaires de s\u00e9curit\u00e9 nationale. A partir de cette conception et de ce qu&rsquo;il savait de Panetta, McGovern avait esp\u00e9r\u00e9, avec ferveur c&rsquo;est le cas de le dire, que la nomination de Panetta \u00e0 la t\u00eate de la CIA par le nouveau pr\u00e9sident Obama d\u00e9but 2009, conduirait \u00e0 une uvre de r\u00e9forme fondamentale des pratiques d\u00e9testables de l&rsquo;agence telles qu&rsquo;elles avaient \u00e9t\u00e9 d\u00e9velopp\u00e9es sous l&rsquo;administration GW Bush. McGovern, qui semble avoir eu des liens personnels avec Panetta, avait clairement \u00e9nonc\u00e9 ses esp\u00e9rances \u00e0 cet \u00e9gard, dans un article, d\u00e9but 2009, dont il donne des extraits cons\u00e9quents dans l&rsquo;article cit\u00e9 ici. Il a \u00e9t\u00e9 profond\u00e9ment d\u00e9\u00e7u par le comportement de Panetta, couvrant \u00e0 la CIA puis au Pentagone, la poursuite voire l&rsquo;accentuation dans certains cas de pratiques telles que les assassinats ill\u00e9gaux, la poursuite de la torture, le soutien actif de cas de violation manifeste de la Constitution par le pr\u00e9sident Obama, etc Ce qui expliquerait, selon McGovern, le besoin o\u00f9 se trouve Panetta d&rsquo;aller recueillir la b\u00e9n\u00e9diction du Pape et de lui demander de prier pour lui. (On observera que le d\u00e9sappointement et l&rsquo;amertume de McGovern s&rsquo;\u00e9tendent par ailleurs \u00e0 Beno\u00eet XVI lui-m\u00eame, et au comportement du Vatican en g\u00e9n\u00e9ral.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>So, while it&rsquo;s possible that historians will discover in decades to come that Panetta gave President Obama sage advice and tried to bend the arc of U.S. military violence downward, I, for one, remain deeply disappointed with Panetta and regretful of my earlier optimism.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>I had the preconceived and, it turns out, misguided notion that Panetta, who a year earlier had denounced torture, and who brought with him a wealth of experience and innumerable contacts on Capitol Hill and in the federal bureaucracy, would be not only determined but also able clean up the mess at the CIA. Moreover, I persuaded myself that I could expect from Panetta, a contemporary with the same education I received at the hands of the Jesuits including moral theology\/ethics, might wear some insulation from power that corrupts. I have learned, though, that no one is immune from the sirens of power, which is an alternative way to explain Panetta&rsquo;s actions over the past four years<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Now, after four years in this swamp of moral and legal relativism, Panetta has turned to Pope Benedict for prayers and blessings, an ironic choice since Benedict himself has shown a high tolerance for sloshing around in this muck. In April 2008, Benedict visited the United States amid sordid disclosures about the Bush administration&rsquo;s practices of torture and worldwide recognition that Bush had ordered the invasion and occupation of Iraq based on false claims about WMD and ties to al-Qaeda.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>On torture, reporting by ABC depicted George W. Bush&rsquo;s most senior aides (Cheney, Powell, Rumsfeld, Ashcroft, Rice and Tenet) meeting multiple times in the White House during 2002-03 to sort out  complete with practical demonstrations  the most efficient mix of torture techniques for captured terrorists. When initially ABC attempted to insulate the President from this sordid activity, Bush responded that he knew all about it and had approved. But Benedict maintained a discreet silence, placing feel-good scenes of happy Catholics cheering his presence over a moral obligation to condemn wrongdoing, a pattern that has recurred far too frequently in the history of the Vatican.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tQuoiqu&rsquo;il s&rsquo;agisse de circonstances bien diff\u00e9rentes, le cas de Panetta, comme ancien directeur de la CIA, pourrait se rapprocher de celui de William Colby, directeur de la CIA par int\u00e9rim entre 1973 et 1975 apr\u00e8s avoir \u00e9t\u00e9 un op\u00e9rationnel impliqu\u00e9 dans des op\u00e9rations aussi cruelles que le <LIEN=http:\/\/en.wikipedia.org\/wiki\/Phoenix_Programprogramme<D>programme <em>Phoenix<\/em> au Vietnam, venant t\u00e9moigner devant la commission Church en 1975 \u00e0 propos des innombrables <em>dirty tricks<\/em> (sales coups) de l&rsquo;Agence. (La commission Church avait \u00e9t\u00e9 \u00e9tablie au S\u00e9nat, sous l&rsquo;impulsion du s\u00e9nateur Church, dans le courant r\u00e9formiste g\u00e9n\u00e9ral qui avait touch\u00e9 les divers centres de pouvoir \u00e0 Washington, au moment du Watergate et de la d\u00e9mission de Nixon, et dans les deux ann\u00e9es qui suivirent.) Les d\u00e9clarations de Colby sur les basses uvres de la CIA furent sensationnelles et scandaleuses, en confirmant publiquement et officiellement les ill\u00e9galit\u00e9s diverses de l&rsquo;Agence (lesquelles p\u00e2lissent compar\u00e9 \u00e0 ce que fait la CIA aujourd&rsquo;hui). Furieux, Kissinger, alors conseiller du pr\u00e9sident Ford et secr\u00e9taire d&rsquo;\u00c9tat, avait dit du comportement du catholique pratiquant qu&rsquo;\u00e9tait Colby qu&rsquo;il se rendait sur la Colline (surnom d\u00e9signant le Congr\u00e8s) comme s&rsquo;il allait \u00e0 confesse, pour tenter d&rsquo;obtenir le pardon de ses p\u00e9ch\u00e9s par l&rsquo;aveu qu&rsquo;il en ferait, et Kissinger finissant par avoir la t\u00eate de Colby qui fut licenci\u00e9 de son poste de directeur le 1er novembre 1975. (Nous devons \u00e0 la saine sp\u00e9culation de rappeler que la mort de Colby, en 1996, \u00e0 la suite d&rsquo;un incident au cours d&rsquo;une sortie de p\u00eache solitaire \u00e0 bord d&rsquo;une embarcation sur une rivi\u00e8re perdue du Maryland, est entour\u00e9e de myst\u00e8re. Certains y voient une liquidation discr\u00e8te, li\u00e9e \u00e0 un manuscrit que Colby se pr\u00e9parait \u00e0 publier et qui aurait disparu corps et bien avec le mort. D&rsquo;autres y voient un suicide, dont son fils Carl Colby [\u00ab<em>Il en avait simplement assez de la vie<\/em>\u00bb]. Officiellement, c&rsquo;\u00e9tait un accident cardiaque, et <em>Amen<\/em>.)<\/p>\n<\/p>\n<p><p>\tLa d\u00e9marche de Panetta aupr\u00e8s du pape Beno\u00eet XVI (Priez pour moi) ressemble dans l&rsquo;esprit \u00e0 cette d\u00e9marche de Colby et rejoint une longue lign\u00e9e de dirigeants de s\u00e9curit\u00e9 nationale aux USA touch\u00e9s par des troubles psychologiques du fait de leurs activit\u00e9s, avec chez certains une forte dimension spirituelle. On commencerait la liste de ces incidents par le suicide du premier secr\u00e9taire \u00e0 la d\u00e9fense de nom, James Forrestal, en mars 1949, suite \u00e0 une grave d\u00e9pression, et l&rsquo;on pourrait poursuivre en se r\u00e9f\u00e9rant aux probl\u00e8mes psychologiques et moraux graves du secr\u00e9taire \u00e0 la d\u00e9fense du temps du Vietnam, Robert McNamara, dont le pr\u00e9sident Johnson ordonna le d\u00e9part au printemps 1968 (McNamara partit \u00e0 la Banque Mondiale), de crainte que son ministre ne se suicid\u00e2t.<\/p>\n<\/p>\n<p><p>\tJames Carroll, auteur remarquable, ancien s\u00e9minariste devenu activiste, fils du g\u00e9n\u00e9ral de l&rsquo;USAF qui mit en place la Defense Intelligence Agency, a longuement parl\u00e9 dans ses diff\u00e9rents \u00e9crits, notamment dans son superbe livre <em>House of War<\/em>, du poids mythique et mystique du Pentagone (<em>Moby Dick<\/em> ou le grand cachalot blanc, selon le secr\u00e9taire \u00e0 la d\u00e9fense et po\u00e8te \u00e0 ses heures William Cohen). Bien entendu, parlant du Pentagone, on peut aussi bien entendre, r\u00e9unis \u00e0 lui, la CIA et tous les organismes du syst\u00e8me de la s\u00e9curit\u00e9 nationale aux USA, l&rsquo;ensemble \u00e9tant effectivement symbolis\u00e9 par le Pentagone, et per\u00e7u comme une entit\u00e9 mal\u00e9fique, proche de la situation ou de la substance d&rsquo;un \u00e9gr\u00e9gore. (C&rsquo;est bien l&rsquo;impression que laisse percer Carroll \u00e0 de nombreuses reprises, ses r\u00e9flexions \u00e0 caract\u00e8re m\u00e9taphysique \u00e9tant alli\u00e9es \u00e0 une exceptionnelle connaissance des personnalit\u00e9s et des \u00e9v\u00e9nements li\u00e9s \u00e0 ce complexe. On a pu voir sur ce site des commentaires et des interventions de James Carroll, le <a href=\"http:\/\/www.dedefensa.org\/article-regarder_le_monstre_dans_les_yeux_james_carroll_et_le_pentagone_20_07_2006.html\" class=\"gen\">20 juillet 2006<\/a> et le <a href=\"http:\/\/www.dedefensa.org\/article-mcnamara_et_le_grand_cachalot_blanc_14_07_2009.html\" class=\"gen\">14 juillet 2009<\/a>).<\/p>\n<\/p>\n<p><p>\tIl y a effectivement quelque chose de singulier dans l&rsquo;ensemble de s\u00e9curit\u00e9 nationale US, une sorte d&rsquo;unicit\u00e9 et d&rsquo;identit\u00e9 sp\u00e9cifiques qu&rsquo;on ne retrouve nulle part ailleurs, dans aucun ensemble de cette sorte, y compris dans ce qui fut le complexe militaro-industriel (CMI) sovi\u00e9tique  dont Carroll disait justement que Gorbatchev avait r\u00e9ussi \u00e0 le terrasser avec la chute de l&rsquo;URSS, et que c&rsquo;\u00e9tait peut-\u00eatre l\u00e0 sa plus grande r\u00e9ussite. (Il y a dans l&rsquo;origine du CMI am\u00e9ricaniste et de toute la n\u00e9buleuse de s\u00e9curit\u00e9 nationale et du syst\u00e8me du technologisme des connexions \u00e9tranges et \u00e0 connotation mystiques et symboliques autant que technologique et scientifique avec le nazisme ou des id\u00e9ologies s&rsquo;en rapprochant,  les origines m\u00eames du milieu des ann\u00e9es 1930 du CMI \u00e9tant fond\u00e9es sur une conception supr\u00e9matiste de la race anglo-saxonne. [Voir notamment le <a href=\"http:\/\/www.dedefensa.org\/article-sur_les_origines_du_complexe_militaro_industriel_cmi_26_01_2003.html\" class=\"gen\">26 janvier 2003<\/a> et le <a href=\"http:\/\/www.dedefensa.org\/article-l_usaf_et_l_evangile_selon_von_braun_01_08_2011.html\" class=\"gen\">1er ao\u00fbt 2011<\/a>.] Nick Cook, enqu\u00eateur et auteur britannique, a d\u00e9taill\u00e9 le fait \u00e0 propos des liens au moins indirects entre le CMI et la n\u00e9buleuse nazie, notamment la SS, notamment avec le d\u00e9veloppement d&rsquo;une conception nazie des sciences fondamentales. Voir le <a href=\"http:\/\/www.dedefensa.org\/article-une_dimension_trange_et_effrayante_du_cmi_am_ricaniste_21_07_2005.html\" class=\"gen\">21 juillet 2005<\/a>.) Ainsi doit-on trouver dans la d\u00e9marche de Panetta,  hors des ricanements et sarcasmes d&rsquo;usage, de type voltairien modernis\u00e9 et esprits forts attenants, et m\u00eame hors de la critique plus factuelle et int\u00e9ressante de McGovern sur les activit\u00e9s de Panetta,  un exemple de plus de l&rsquo;angoisse et du sentiment de culpabilit\u00e9 que fait peser ce monstre sur certains de ceux qui sont plac\u00e9s \u00e0 sa t\u00eate et qui ex\u00e9cutent le plus souvent de fa\u00e7on au moins z\u00e9l\u00e9e la mission de sembler le diriger dans les entreprises de d\u00e9structuration et de dissolution du monde qu&rsquo;il r\u00e9alise syst\u00e9matiquement \u00e0 travers le monde. On trouve dans ces divers occurrences impliquant les diverses personnalit\u00e9s cit\u00e9es un exemple d&rsquo;op\u00e9rationnalit\u00e9 des fonctions mal\u00e9fiques, si ce n&rsquo;est du Mal lui-m\u00eame, par rapport \u00e0 l&rsquo;\u00eatre humain, le <em>sapiens<\/em> : \u00e0 savoir, la proximit\u00e9 extr\u00eame de cette source mal\u00e9fique que peut atteindre le <em>sapiens<\/em> sans pour autant \u00eatre compl\u00e8tement mauvais. (Ce qui retrouve l&rsquo;appr\u00e9ciation de Plotin que nous citons souvent : \u00ab<em> Mais les autres, ceux qui participeraient de lui<\/em> [le mal] <em> et s&rsquo;y assimileraient, deviennent mauvais, n&rsquo;\u00e9tant pas mauvais en soi.<\/em>\u00bb)<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 22 janvier 2013 \u00e0 14H46<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abPray for me\u00bb Nostra maxima culpa Nous avons souvent fait le portrait de Leon Panetta comme un bon vivant porteur d&rsquo;une liste Secret D\u00e9fense des meilleurs restaurants de Washington, mais le portrait s&rsquo;av\u00e8re incomplet. Certes, le secr\u00e9taire \u00e0 la d\u00e9fense US est un bon vivant mais il est aussi un homme de foi, catholique pratiquant.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4796,3369,7921,11056,3966,5286,6521,6197,2660,3194,2661,3918],"class_list":["post-74807","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-benoit","tag-carroll","tag-dick","tag-egregore","tag-james","tag-mcnamara","tag-moby","tag-panetta","tag-pape","tag-pentagone","tag-vatican","tag-xvi"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74807"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74807\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}