{"id":74875,"date":"2013-03-06T06:41:51","date_gmt":"2013-03-06T06:41:51","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/03\/06\/lultime-bataille-de-chavez-un-deuil-mobilisateur\/"},"modified":"2013-03-06T06:41:51","modified_gmt":"2013-03-06T06:41:51","slug":"lultime-bataille-de-chavez-un-deuil-mobilisateur","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/03\/06\/lultime-bataille-de-chavez-un-deuil-mobilisateur\/","title":{"rendered":"L&rsquo;ultime bataille de Chavez : un \u201cdeuil mobilisateur\u201d"},"content":{"rendered":"<p><h3 class=\"titrebloc\">L&rsquo;ultime bataille de Chavez : un deuil mobilisateur<\/h3>\n<\/p>\n<p><p>\tLa mort du pr\u00e9sident v\u00e9n\u00e9zu\u00e9lien Hugo Chavez se place aussit\u00f4t sous les auspices d&rsquo;une crise majeure : non pas seulement une crise int\u00e9rieure du pays, qui va de soi pour un tel \u00e9v\u00e9nement et dans les circonstances g\u00e9n\u00e9rales qu&rsquo;on sait, mais essentiellement une crise \u00e9galement g\u00e9n\u00e9rale opposant le Syst\u00e8me aux forces n\u00e9cessairement antiSyst\u00e8me et se pla\u00e7ant compl\u00e8tement dans un contexte international. Le gouvernement et d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, le groupe Chavez men\u00e9 pour l&rsquo;instant par le vice-pr\u00e9sident Maduro, ont imm\u00e9diatement et exclusivement plac\u00e9 l&rsquo;\u00e9v\u00e9nement dans ce contexte, et avec tous les arguments pour le faire.<\/p>\n<\/p>\n<p><p>\tDeux axes ont aussit\u00f4t \u00e9t\u00e9 choisis pour d\u00e9velopper ce contexte de l&rsquo;agression du Syst\u00e8me, essentiellement repr\u00e9sent\u00e9 par les USA et leur processus imm\u00e9morial d&rsquo;interf\u00e9rences et d&rsquo;intervention ill\u00e9gales dans les pays d&rsquo;Am\u00e9rique latine. D&rsquo;une part, les interf\u00e9rences directes des USA, notamment par le biais de fonctionnaires ou militaires de l&rsquo;ambassade US, avec l&rsquo;expulsion imm\u00e9diate de deux officiers de l&rsquo;USAF travaillant \u00e0 l&rsquo;ambassade et qui sont accus\u00e9s d&rsquo;avoir propos\u00e9 \u00e0 des militaire v\u00e9n\u00e9zu\u00e9liens des actions subversives ; d&rsquo;autre part, des doutes sur les causes du cancer dont Chavez est mort. On trouve des d\u00e9tails de ces deux axes dans l&rsquo;intervention de Maduro, d\u00e9non\u00e7ant un plan de d\u00e9stabilisation, sur <em>Venezuelanalysis.com<\/em>, le <a href=\"http:\/\/venezuelanalysis.com\/news\/8031\" class=\"gen\">5 mars 2013<\/a>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Vice-president Nicolas Maduro today denounced destabilisation plans by the international and Venezuelan right wing, announcing the expulsion of two US officials for threatening military security. He also implied that Chavez&rsquo;s cancer was caused by enemies of Venezuela<\/em> [] <em>Further,<\/em> [Maduro]<em> said, We don&rsquo;t have any doubts that the historical enemies of the country have searched for a way to damage the health of President Chavez&#8230; that he was attacked with this illness, alluding to the possibility of a scientific attack. Just like what happened to Yasser Arafat&#8230; Eventually there will be a scientific investigation into President Chavez&rsquo;s illness, he said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCet aspect d&rsquo;un complot pour susciter le cancer chez Chavez est \u00e9videmment l&rsquo;axe le plus original de cette contre-attaque pr\u00e9ventive du gouvernement v\u00e9n\u00e9zu\u00e9lien compl\u00e8tement dans son r\u00f4le d&rsquo;antiSyst\u00e8me. <em>Russia Today<\/em>, le <a href=\"http:\/\/rt.com\/news\/venezuela-chavez-diplomat-us-873\/\" class=\"gen\">5 mars 2013<\/a>, reprend les deux axes de cette contre-attaque pr\u00e9ventive et d\u00e9veloppe notamment celui qui concerne la sant\u00e9 de Chavez. On y trouve rappel\u00e9 les accusations de Chavez lui-m\u00eame, citant son cas et celui de la pr\u00e9sidente argentine, auxquels il aurait pu ajouter ceux de l&rsquo;ancien pr\u00e9sident br\u00e9silien Lula et de l&rsquo;actuelle pr\u00e9sidente Rousseff, qui ont tous deux d\u00fb \u00eatre trait\u00e9s pour le cancer.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>In December 2011, Chavez speculated that the United States could be infecting the regions leaders with cancer  after Argentine President Cristina Fernandez de Kirchner was diagnosed with thyroid cancer. I don&rsquo;t want to make any reckless accusations, Chavez said in light of something he found to be very, very strange. Would it be strange if [the United States] had developed a technology to induce cancer, and for no one to know it? he asked.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Un autre champ de la bataille de l&rsquo;apr\u00e8s-Chavez concerne l&rsquo;\u00e9conomie. Sur ce point, il s&rsquo;agit, du c\u00f4t\u00e9 du Syst\u00e8me, d&rsquo;une intense op\u00e9ration de communication tournant autour de la r\u00e9cente d\u00e9valuation au Venezuela, et contre elle \u00e9videmment. Il s&rsquo;agit de discr\u00e9diter de toutes les fa\u00e7ons possibles un syst\u00e8me \u00e9conomique qui est en confrontation directe avec l&rsquo;id\u00e9ologie \u00e9conomique du Syst\u00e8me, dont on peut constater partout les caract\u00e8res d\u00e9structurants et dissolvants engendrant des crises successives qui mettent en cause son essence m\u00eame.<\/p>\n<\/p>\n<p><p>\tCes attaques contre le syst\u00e8me \u00e9conomique v\u00e9n\u00e9zu\u00e9lien utilisent toutes les appr\u00e9ciations possibles, parfois extraordinairement hollywoodienne et abracadabrantesques, des r\u00e9alit\u00e9s de cette d\u00e9valuation. On en a une bonne appr\u00e9ciation dans l&rsquo;article de Mark Weisbrot, dans le <em>Guardian<\/em> du <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/2013\/mar\/03\/venezuela-devaluation-doom-mongers\" class=\"gen\">3 mars 2013<\/a>. En voici un court extrait, o\u00f9 Weisbrot semble avoir d\u00e9busqu\u00e9 un \u00e9conomiste-Syst\u00e8me qui pourrait bien avoir confondu, dans sa <em>narrative<\/em>, des faux chiffres du processus de l&rsquo;inflation avec des faux chiffres du processus de la d\u00e9valuation :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Not surprisingly, a lot of what passes for analysis in the press is based on wrong numbers and flawed logic. The award for wrong numbers this time goes to Mois\u00e9s Na\u00edm, who writes in the Financial Times that during Hugo Ch\u00e1vez&rsquo;s presidency, the bolivar has been devalued by 992%. Fans of arithmetic will note immediately that this is impossible. The most that a currency could be devalued is 100%, at which point it would exchange for zero dollars. Apparently, a very wide range of exaggeration is permissible when writing about Venezuela, so long as it is negative<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t L&rsquo;\u00e9conomiste Weisbrot, qui est co-auteur avec Oliver Stone du documentaire pro-Chavez <em>South of the Border<\/em>, travaille aussi avec le site <em>Venezuelanalysis.com<\/em>, qui a un fort soutien de dissidents pro-Chavez aux USA, et qui est une bonne source pour suivre les \u00e9v\u00e9nements au Venezuela. Ce site publie, notamment, ce <a href=\"http:\/\/venezuelanalysis.com\/analysis\/8013\" class=\"gen\">5 mars 2013<\/a>, une analyse int\u00e9ressante du Dr. Francisco Dominguez, secr\u00e9taire pour le Royaume-Uni de <em>Venezuela Solidarity Campaign<\/em>, concernant Ricardo Haussmann, collaborateur \u00e9pisodique du <em>Guardian<\/em> qui prend pour cible la situation \u00e9conomique du Venezuela : Haussmann, homme de l&rsquo;ancien r\u00e9gime d&rsquo;avant-Chavez, puis du FMI, puis de l&rsquo;universit\u00e9 de Harvard C&rsquo;est l&rsquo;arch\u00e9type de l&rsquo;acteur-Syst\u00e8me agissant au niveau \u00e9conomique et organisant le rassemblement des diverses forces \u00e0 dominante \u00e9conomique anti-Chavez et pro-US au Venezuela.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>In the run up to last October&rsquo;s election, won by Hugo Chavez in a landslide victory, it was Haussmann (acting as an advisor to the defeated right-wing candidate Henrique Capriles) who claimed the right-wing opposition would have 200,000 people at polling stations and could then announce their own results before the official ones. Luckily this plan  which was seen by many as the start of a worrying destabilisation aimed at getting the legitimate results not recognised internationally  failed to pick up momentum due to the scale of Hugo Chavez&rsquo;s victory, with Capriles himself recognising the results. But this was not before the Spanish newspaper ABC had published a fake exit poll claiming Hugo Chavez had lost. Surely his role as an advisor to the right-wing political candidate should have featured in the Guardian piece. This would better explain the reasons for the content of the piece.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Likewise sections of the British media have also recently quoted Diego Arria (who denies the 2002 coup in Venezuela was even a coup!) and the 2002 coup-supporting, hard right-wing MP (and friend of George W.Bush) Mar\u00eda Corina Machado. Both are prominent signatories to a recent public petition calling on the Venezuelan military to overturn the country&rsquo;s elected government.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tTout cela d\u00e9finit une situation tr\u00e8s sp\u00e9cifique, qui n&rsquo;est pas inattendue si l&rsquo;on consid\u00e8re la personnalit\u00e9 et l&rsquo;influence du d\u00e9funt autant que la vindicte et la haine dont le poursuivait le Syst\u00e8me, mais une situation qui n&rsquo;en reste pas moins extraordinaire. Cette mort en apparence naturelle (par maladie) est clairement pr\u00e9sent\u00e9e et d\u00e9j\u00e0 per\u00e7ue, et devrait \u00eatre de plus en plus per\u00e7ue comme une mort par agression et attentat du Syst\u00e8me, de fa\u00e7on directe ou indirecte c&rsquo;est selon. Cette pr\u00e9sentation et cette perception font que la mort de Chavez serait beaucoup plus l&rsquo;occasion d&rsquo;une mobilisation que d&rsquo;un deuil, ou, si l&rsquo;on veut,  l&rsquo;occasion d&rsquo;un deuil mobilisateur qui serait l&rsquo;ultime contribution directe de Chavez \u00e0 la bataille antiSyst\u00e8me. Il semble tr\u00e8s probable que les \u00e9lections pr\u00e9sidentielles (dans les 30 jours, selon les d\u00e9clarations du ministre des affaires \u00e9trang\u00e8res du Venezuela) se feront sous le signe de la mobilisation : contre l&rsquo;agression du Syst\u00e8me (USA et \u00e9conomistes-Syst\u00e8me), par ailleurs pr\u00e9cis\u00e9ment ou indistinctement per\u00e7u comme responsable de la mort de Chavez par attentat m\u00e9dico-technologique ou subversion g\u00e9n\u00e9ralis\u00e9e. Le rappel g\u00e9n\u00e9ral des soup\u00e7ons pesant sur les causes du cancer de Chavez devrait jouer un r\u00f4le majeur dans le comportement et la mobilisation de la population pour les \u00e9lections.<\/p>\n<\/p>\n<p><p>\tPar ailleurs et si la situation de l&rsquo;Am\u00e9rique Latine est conforme \u00e0 ce qu&rsquo;on en per\u00e7oit, cette mobilisation devrait d\u00e9passer les fronti\u00e8res du Venezuela parce qu&rsquo;elle concerne logiquement tous les r\u00e9gimes de la nouvelle Am\u00e9rique Latine, de l&rsquo;extr\u00eame gauche de la Bolivie de Morales au centre-gauche du Br\u00e9sil de Lula-Rousseff. (On emploie ces notions de gauche pour la facilit\u00e9, alors qu&rsquo;il faudrait plut\u00f4t situer ces tendances selon la r\u00e9f\u00e9rence antiSyst\u00e8me.) On ne dira pas que tous appr\u00e9ciaient absolument Chavez, mais tous devraient \u00eatre n\u00e9cessairement solidaires, au moins de l&rsquo;imm\u00e9diat apr\u00e8s-Chavez, dans la mesure o\u00f9 les pressions du Syst\u00e8me contre le Venezuela de Chavez impliquent une attaque contre tout le continent, dans son orientation antiSyst\u00e8me actuelle. On peut aller jusqu&rsquo;\u00e0 l&rsquo;hypoth\u00e8se qu&rsquo;il n&rsquo;est nullement impossible que, dans certaines circonstances comme le cas d&rsquo;une tentative brutale de coup contre le r\u00e9gime issu de Chavez, l&rsquo;un ou l&rsquo;autre voisin, y compris le puissant Br\u00e9sil, envisage une intervention militaire qui s&rsquo;appuierait sur une r\u00e9action populaire au Venezuela. Cette sorte d&rsquo;hypoth\u00e8se peut d\u00e9boucher sur des situations de d\u00e9stabilisation majeure o\u00f9 le Syst\u00e8me n&rsquo;est pas gagnant \u00e0 tous les coups,  tant s&rsquo;en faut, parce qu&rsquo;il existe \u00e0 un niveau continental la possibilit\u00e9 d&rsquo;un furieux durcissement antiSyst\u00e8me dans de telles circonstances.<\/p>\n<\/p>\n<p><p>\tMais y aura-t-il tentative directe et brutale de d\u00e9stabilisation ? La doctrine du <a href=\"http:\/\/www.dedefensa.org\/article-kerry_erdogan_le_sionisme_et_le_droit_d_tre_stupide__02_03_2013.html\" class=\"gen\">droit \u00e0 la stupidit\u00e9<\/a> \u00e9nonc\u00e9e par Kerry \u00e9tant d&#8217;emploi universel dans le Syst\u00e8me, ce n&rsquo;est pas impossible. L&rsquo;expulsion des deux officiers de l&rsquo;USAF pourrait en \u00eatre un signe, car tenter de fomenter un coup d&rsquo;\u00c9tat dans les forces arm\u00e9es v\u00e9n\u00e9zu\u00e9liennes dans les conditions actuelles repr\u00e9sente une tactique d&rsquo;une brutalit\u00e9 qui confine effectivement, dans les conditions actuelles (popularit\u00e9 de Chavez, soup\u00e7ons sur les causes de sa mort, solidarit\u00e9 de l&rsquo;Am\u00e9rique Latine), \u00e0 la fameuse stupidit\u00e9. (Que les deux officiers aient ou non effectivement complot\u00e9 est secondaire, le fait essentiel est celui de la perception qu&rsquo;on aurait qu&rsquo;une telle initiative est trop conforme aux pratiques des USA pour qu&rsquo;elle soit cat\u00e9goriquement rejet\u00e9e : dans ce cas, le soup\u00e7on bas\u00e9 sur l&rsquo;exp\u00e9rience historique cr\u00e9e la v\u00e9rit\u00e9 de la chose, par ailleurs quasiment impossible \u00e0 d\u00e9terminer objectivement) L&rsquo;hypoth\u00e8se d&rsquo;une telle tentative active et brutale est donc \u00e0 consid\u00e9rer, ne serait ce que parce que tous les esprits en acceptent la possibilit\u00e9, et qu&rsquo;il ne faut jamais d\u00e9sesp\u00e9rer d&rsquo;un Syst\u00e8me o\u00f9 la multitude de pouvoirs non coordonn\u00e9s entre eux et la passion anti-Chavez largement r\u00e9pandue accentuent la r\u00e9f\u00e9rence \u00e0 la doctrine de la stupidit\u00e9. C&rsquo;est sur ce terrain que le r\u00e9gime Chavez devrait en bonne logique et en juste tactique lancer l&rsquo;apr\u00e8s-Chavez, en allant tr\u00e8s vite \u00e0 de nouvelles \u00e9lections pour capitaliser \u00e0 la fois sur l&rsquo;\u00e9motion, et surtout sur la mobilisation qui devrait accompagner cette \u00e9motion. On ajoutera, comme autre atout des successeurs de Chavez, que l&rsquo;opposition est loin d&rsquo;\u00eatre <a href=\"http:\/\/venezuelanalysis.com\/news\/7875\" class=\"gen\">unie<\/a> autour de l&rsquo;adversaire de Chavez en octobre 2012, Henrique Capriles.<\/p>\n<\/p>\n<p><p>\tLe point le plus remarquable de la situation est donc, une fois de plus, \u00e0 trouver sur le terrain de la communication. L&rsquo;attaque de communication du Syst\u00e8me contre Chavez, et notamment depuis qu&rsquo;il est malade, est telle, elle est d&rsquo;une telle puissance impliquant les apports de la doctrine de la stupidit\u00e9, que l&rsquo;id\u00e9e de l&rsquo;agression s&rsquo;est subrepticement institutionnalis\u00e9e. La mort de Chavez ne serait plus per\u00e7ue comme naturelle, mais comme le r\u00e9sultat de cette agression. La mobilisation en deviendrait alors absolument naturelle, et si cet \u00e9tat d&rsquo;esprit domine, et \u00e9videmment profitable au r\u00e9gime en place, la responsabilit\u00e9 g\u00e9n\u00e9rale de la crise serait per\u00e7ue comme le fait de cette attaque constante et massive contre Chavez. M\u00eame les m\u00e9thodes de communication, d&rsquo;agression douce comme contre la Russie, devraient \u00eatre d\u00e9form\u00e9es dans ce cas parce qu&rsquo;il y a, en Am\u00e9rique Latine, le poids de la brutalit\u00e9 historique du Syst\u00e8me (des USA) dans cette r\u00e9gion, m\u00e9pris\u00e9e et consid\u00e9r\u00e9e comme l&rsquo;arri\u00e8re-cour, voire la basse-cour des USA. On chasse difficilement l&rsquo;atavisme historique de la brutalit\u00e9, surtout lorsqu&rsquo;il se charge de cette stupidit\u00e9-Syst\u00e8me qui semble aller de pair avec l&rsquo;activit\u00e9 surpuissante du Syst\u00e8me, sa haine compl\u00e8te pour tous les principes, de la souverainet\u00e9 \u00e0 la l\u00e9gitimit\u00e9, son go\u00fbt pour l&rsquo;ill\u00e9galit\u00e9 allant jusqu&rsquo;\u00e0 la d\u00e9pendance comme dans le cas d&rsquo;un drogu\u00e9, etc. Tout cela est d\u00e9ploy\u00e9 depuis des ann\u00e9es contre Chavez. Le r\u00e9sultat est que la mort de Chavez, quelle qu&rsquo;en soit la nature, est ais\u00e9ment per\u00e7ue comme un attentat du syst\u00e8me, justifiant toutes les craintes, et donc la mobilisation g\u00e9n\u00e9rale, la contre-attaque pr\u00e9ventive des accusations publiques du gouvernement, l&rsquo;expulsion d&rsquo;officiers de l&rsquo;USAF comme on expulsait des agents du KGB en cas de tension, du temps de la guerre froide, et ainsi de suite.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 6 mars 2013 \u00e0 06H32<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;ultime bataille de Chavez : un deuil mobilisateur La mort du pr\u00e9sident v\u00e9n\u00e9zu\u00e9lien Hugo Chavez se place aussit\u00f4t sous les auspices d&rsquo;une crise majeure : non pas seulement une crise int\u00e9rieure du pays, qui va de soi pour un tel \u00e9v\u00e9nement et dans les circonstances g\u00e9n\u00e9rales qu&rsquo;on sait, mais essentiellement une crise \u00e9galement g\u00e9n\u00e9rale opposant&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2947,4646,3304,11993,3313,11992,3340,3305],"class_list":["post-74875","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-amerique","tag-antisysteme","tag-chavez","tag-expulsion","tag-latine","tag-maduro","tag-presidentielles","tag-venezuela"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74875"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74875\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}