{"id":74878,"date":"2013-03-09T11:09:46","date_gmt":"2013-03-09T11:09:46","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/03\/09\/la-tragedie-de-la-tension\/"},"modified":"2013-03-09T11:09:46","modified_gmt":"2013-03-09T11:09:46","slug":"la-tragedie-de-la-tension","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/03\/09\/la-tragedie-de-la-tension\/","title":{"rendered":"La trag\u00e9die de la tension"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">La trag\u00e9die de la tension<\/h2>\n<\/p>\n<p><p>9 mars 2013 &ndash; Nous allons tenter d&rsquo;analyser les \u00e9v\u00e9nements italiens, essentiellement avec la victoire du <em>Movimento 5 Stelle<\/em> (M5S) et de Beppe Grillo du 25 f\u00e9vrier (voir notamment le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_syst_me_entre_le_clown_et_l_ex-comique_26_02_2013.html\">26 f\u00e9vrier 2013<\/a>), et depuis cet \u00e9v\u00e9nement, selon une approche g\u00e9n\u00e9raliste et antiSyst\u00e8me, en nous pla\u00e7ant singuli\u00e8rement par rapport \u00e0 la position actuelle de l&rsquo;Italie, mais aussi par rapport \u00e0 son \u00e9volution historique, selon la position tr\u00e8s importante de l&rsquo;Italie dans le syst\u00e8me europ\u00e9en tel qu&rsquo;il a \u00e9t\u00e9 install\u00e9 dans les ann\u00e9es 1945-1950. (Par \u00ab\u00a0syst\u00e8me europ\u00e9en\u00a0\u00bb, nous entendons cette esp\u00e8ce d&rsquo;agglom\u00e9r\u00e9 d&rsquo;influences et de pressions directes et indirectes, celle des USA et de l&rsquo;OTAN d&rsquo;abord, celle des f\u00e9d\u00e9ralistes europ\u00e9ens ensuite, avec l&rsquo;alignement de nombre de ces f\u00e9d\u00e9ralistes sur les USA, des institutions europ\u00e9ennes enti\u00e8rement int\u00e9gr\u00e9es dans le Syst\u00e8me g\u00e9n\u00e9ral par l&rsquo;\u00e9conomie, enfin des principales entit\u00e9s nationales.)<\/p>\n<\/p>\n<p><p>L&rsquo;Italie fut en effet, d\u00e8s le d\u00e9part, l&rsquo;un des principaux terrains d&rsquo;intervention de la mise en place de ce syst\u00e8me, notamment \u00e0 cause de son importance strat\u00e9gique, de la puissance de l&rsquo;implantation alli\u00e9e (US) durant la guerre, de son \u00e9quilibre d\u00e9licat entre les forces pro-occidentales d&rsquo;une part (d\u00e9mocrates-chr\u00e9tiens [DC] principalement, avec leurs liens avec la <em>Mafia<\/em>) et un parti communiste tr\u00e8s puissant d&rsquo;autre part. L&rsquo;intervention massive de la CIA dans les \u00e9lections de 1949 pour permettre \u00e0 la DC de l&#8217;emporter, institutionnalisa cette importance italienne qui s&rsquo;est poursuivie depuis, &ndash; de m\u00eame que l&rsquo;intervention de la CIA, d&rsquo;ailleurs, devenue comme \u00ab\u00a0institutionnalis\u00e9e\u00a0\u00bb. Dans les d\u00e9cennies suivantes, l&rsquo;Italie resta un des principaux points de tension de ce syst\u00e8me, notamment au travers des activit\u00e9s des r\u00e9seaux <em>Gladio<\/em> de l&rsquo;OTAN, essentiellement \u00e0 partir des ann\u00e9es 1970. Notre id\u00e9e principale est que cette situation de tension constitue un facteur fondamental pour comprendre et analyser, <strong>y compris et peut-\u00eatre plus que jamais<\/strong> aujourd&rsquo;hui, la situation italienne. (La tension actuelle renvoie \u00e0 l&rsquo;expression \u00ab\u00a0strat\u00e9gie de la tension\u00a0\u00bb, utilis\u00e9e sp\u00e9cifiquement d&rsquo;abord pour l&rsquo;Italie. Cette \u00ab\u00a0strat\u00e9gie de la tension\u00a0\u00bb fut utilis\u00e9e par les forces constituant le pouvoir dans le syst\u00e8me europ\u00e9en pour d\u00e9signer la tactique de provocation et de d\u00e9structuration dans les ann\u00e9es 1970 en Italie, &ndash; <em>anni di piombi<\/em>, ou \u00ab\u00a0ann\u00e9es de plomb\u00a0\u00bb, cumulant avec la mort d&rsquo;Aldo Moro en mai 1978.)<\/p>\n<\/p>\n<p><p>De l\u00e0, l&rsquo;int\u00e9r\u00eat de nous appuyer sur les \u00e9crits et les commentaires de l&rsquo;ex-parlementaire europ\u00e9en et analyste Richard Cottrell, sp\u00e9cifiquement depuis l&rsquo;\u00e9lection du 25 f\u00e9vrier. Ses interventions serviront de base de d\u00e9part de notre analyse. Avec Cottrell, on peut disposer de la vision d&rsquo;un sp\u00e9cialiste d&rsquo;une tendance \u00ab\u00a0dissidente\u00a0\u00bb confirm\u00e9e et pol\u00e9mique, en g\u00e9n\u00e9ral bien inform\u00e9 m\u00eame si parfois un peu trop imaginatif, notamment et pr\u00e9cis\u00e9ment \u00e0 propos des multiples manigances type-<em>Gladio<\/em> en Europe. C&rsquo;est lui que nous allons consulter pour tenter d&rsquo;avoir le cadre g\u00e9n\u00e9ral pour une appr\u00e9ciation de la situation italienne, devenue un nouveau centre fusionnel de la crise du Syst\u00e8me, \u00ab\u00a0section Europe\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>(Nous avons plusieurs fois cit\u00e9 Cottrell, notamment le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_gr_ce_et_l_hypoth_se_l_hypoth_que_gladio_17_05_2012.html\">17 mai 2012<\/a> \u00e0 propos de la Gr\u00e8ce, ou le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_turquie_selon_erdogan_ou_la_trag_die-bouffe_15_10_2012.html\">15 octobre 2012<\/a> \u00e0 propos de la Turquie, chaque fois avec l&rsquo;arri\u00e8re-plan de la probl\u00e9matique des r\u00e9seaux <em>Gladio<\/em>. Dans le dernier texte du 15 octobre 2012, nous identifiions Cottrell et le qualifiions de cette fa\u00e7on  : &laquo;<em>Un autre auteur grand connaisseur des arcanes de l&rsquo;histoire secr\u00e8te, essentiellement europ\u00e9enne dans son cas&hellip; <\/em> [&hellip;] <em>Cet auteur est Richard Cottrell, ancien parlementaire europ\u00e9en (conservateur britannique), sp\u00e9cialiste de la \u00ab\u00a0guerre secr\u00e8te\u00a0\u00bb de l&rsquo;OTAN (les r\u00e9seaux Gladio) et, dans ce cadre, tr\u00e8s bon connaisseur de l&rsquo;histoire secr\u00e8te de la Turquie&hellip;<\/em>&raquo; Cottrell est l&rsquo;auteur notamment du <a class=\"gen\" href=\"http:\/\/www.amazon.com\/gp\/product\/1615776877\/ref=as_li_tf_tl?ie=UTF8&#038;tag=enthli01-20&#038;linkCode=as2&#038;camp=1789&#038;creative=9325&#038;creativeASIN=1615776877\">tr\u00e8s r\u00e9cent<\/a> [juin 2012] <em>Gladio: NATO&rsquo;s Dagger At The Heart Of Europe<\/em>. Il est \u00e9videmment tr\u00e8s probable qu&rsquo;en tant qu&rsquo;ancien parlementaire europ\u00e9en, notamment impliqu\u00e9 dans des commissions d&rsquo;enqu\u00eate du Parlement europ\u00e9en sur <em>Gladio<\/em> et tr\u00e8s vindicatif \u00e0 ce propos, Cottrell se soit constitu\u00e9 un r\u00e9seau de sources qui donnent certainement du cr\u00e9dit \u00e0 nombre de ses informations et, surtout, \u00e0 la base documentaire personnelle de son travail. Cela n&#8217;emp\u00eache ni les exc\u00e8s, ni les erreurs, mais cela structure fortement ses analyses et cela le diff\u00e9rencie de nombre de \u00ab\u00a0complotistes\u00a0\u00bb qui n&rsquo;ont gu\u00e8re de sources directes et une exp\u00e9rience documentaire tr\u00e8s restreinte, sinon nulle.)<\/p>\n<\/p>\n<p><p>L&rsquo;int\u00e9r\u00eat que pr\u00e9sente Cottrell en la circonstance est qu&rsquo;il a publi\u00e9 cinq articles sur l&rsquo;Italie depuis les \u00e9lections du 25 f\u00e9vrier, qui montrent \u00e0 la fois une \u00e9volution, une diversification et un \u00e9largissement de son analyse de la situation. (En tant que sp\u00e9cialiste de <em>Gladio<\/em>, Cottrell est n\u00e9cessairement int\u00e9ress\u00e9 par l&rsquo;Italie qui a \u00e9t\u00e9 un des pays europ\u00e9ens les plus affect\u00e9s par les activit\u00e9s de <em>Gladio<\/em>, et le pays d&rsquo;o&ugrave; est partie, le 24 octobre 1990, la r\u00e9v\u00e9lation publique, par le Premier ministre Giulio Andreotti, de l&rsquo;existence de ces r\u00e9seaux. L&rsquo;Italie, par la voix inattendue du plus coriace mais aussi du plus ambigu des repr\u00e9sentants de son <em>establishment<\/em>, est le pays qui a mis la question des r\u00e9seaux <em>Gladio<\/em> sur la place publique.)<\/p>\n<\/p>\n<p><p>&bull; Dans son premier texte, sur le site <em>EndtheLie.com<\/em> (comme les autres), le <a class=\"gen\" href=\"http:\/\/EndtheLie.com\/2013\/02\/26\/italys-tea-party-makes-the-breakthrough\/#ixzz2MdomSPfE\">26 f\u00e9vrier 2013<\/a>, Cottrell se contente d&rsquo;enregistrer en la commentant la victoire du M5S et des <em>Grillini<\/em>. Son appr\u00e9ciation est r\u00e9sum\u00e9e par le titre, qui se r\u00e9f\u00e8re au ph\u00e9nom\u00e8ne US : &laquo;<em>Italy&rsquo;s Tea Party makes the breakthrough.<\/em>&raquo; (D&rsquo;une fa\u00e7on symbolique bien plus que circonstancielle, il y a une particularit\u00e9 g\u00e9n\u00e9rale tr\u00e8s sp\u00e9cifique qui rapproche <em>Tea Party<\/em> du M5S : l&rsquo;absence institutionnelle d&rsquo;un dirigeant. C&rsquo;\u00e9tait une chose connue pour <em>Tea Party<\/em>. Dans le cas du M5S, une p\u00e9rip\u00e9tie personnelle de Grillo acte la chose. Le M5S refuse, dans sa \u00ab\u00a0charte\u00a0\u00bb, l&rsquo;\u00e9lection parlementaire pour de personne ayant un casier judiciaire ; cela est le cas de Grillo, qui a \u00e9t\u00e9 condamn\u00e9 \u00e0 18 mois de prison en 1980 pour homicides involontaires, &ndash; ses trois passagers tu\u00e9s dans un accident automobile dont il a \u00e9t\u00e9 reconnu responsable ; il ne s&rsquo;est donc pas pr\u00e9sent\u00e9 et il est absent du principal champ de bataille politique qu&rsquo;est le Parlement. Par ailleurs, cette circonstance est pr\u00e9sent\u00e9e comme correspondant \u00e0 la philosophie de M5S, qui refuse la structure des partis traditionnels, &ndash; mais Grillo exerce une influence d\u00e9cisive sur l&rsquo;ensemble.)<\/p>\n<\/p>\n<p><p>Dans cet article du 26 f\u00e9vrier, Cottrell fait plut\u00f4t un tableau du climat g\u00e9n\u00e9ral en Italie apr\u00e8s l&rsquo;\u00e9lection, et rappelle les menaces type-<em>Gladio<\/em>.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>The general mood in Italy is the feeling everywhere that politics are at last exciting, uncertain and unpredictable, a profound sense that Italians themselves have spoken, loud and clear. There is a sense that the giovanni &ndash; the young ones &ndash; are in a mood to Take Back Italy. If they succeed, the consequences may be astonishing: but always remember that terrible tendency of revolutions to ultimately consume their own. The Movimento honeymoon with the Italian people might yet prove tragically brief.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Certainly the forces of counter-attack are already amassing. Italy has a long history of political violence. In my recent work on that subject I have pointed to the famous &lsquo;strategy of tension&rsquo; of the 1970&rsquo;s and 80&rsquo;s, another time of great political crisis. This was a deadly period of bombings, shootings and massacres of perfectly innocent people, invariably blamed on urban guerillas calling themselves the Red Brigades. We know now that much of the violence was orchestrated by the deep state in cahoots with neo-fascists and organized crime, designed to scare Italians back to the arms of safe right wing governments, hence &lsquo;strategy of tension.&rsquo; Those who now feel most aggrieved at Grillo&rsquo;s usurpation will not rest lightly. Grillo himself makes frequent public references to the crimes committed for political aims in times past. He knows full well to look over his shoulders on a constant basis.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Le <a class=\"gen\" href=\"http:\/\/EndtheLie.com\/2013\/02\/27\/shake-rattle-and-roll-in-rome-the-vatican-crumbles-as-the-clown-prince-grabs-the-party-hat\/#ixzz2MdmoXrSr\">27 f\u00e9vrier 2013<\/a>, Cottrell \u00e9largit son sujet. Il passe brusquement \u00e0 la question de la d\u00e9mission du Pape Beno&icirc;t XVI, c&rsquo;est-\u00e0-dire, selon lui, \u00e0 la crise profonde que traverse l&rsquo;&Eacute;glise, &ndash; et ainsi Rome devient-il le th\u00e9\u00e2tre de deux drames parall\u00e8les, &ndash; de plusieurs drames : &laquo;<em>Shake rattle and roll in Rome: the Vatican crumbles as the clown prince<\/em> [Beppe Grillo] <em>grabs the party hat<\/em>&raquo;. Dans ses th\u00e8ses et ses enqu\u00eates, Cottrell a toujours li\u00e9 les scandales du Vatican, notamment de la Banque du Vatican, \u00e0 l&rsquo;affaire de la Loge P2 et, d&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale, aux activit\u00e9s de <em>Gladio<\/em>. Le lien qu&rsquo;il \u00e9tablit entre la crise de l&rsquo;&Eacute;glise, qu&rsquo;il juge presque de nature schismatique, et la crise politique italienne, avec le M5S, devient logique, sinon \u00e9vident, m\u00eame s&rsquo;il est difficilement identifi\u00e9, ou bien indirect et circonstanciel&hellip; Et la crise int\u00e9rieure de l&rsquo;Eglise, r\u00e9percut\u00e9e dans le cadre \u00e9troit de la crise d&rsquo;une religion face \u00e0 l&rsquo;anticl\u00e9ricalisme, s&rsquo;ins\u00e8re brusquement dans le sch\u00e9ma bien plus large de la crise de la civilisation et du sens (donc, la crise du Syst\u00e8me).<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Schism, then, is potentially the order of the day in the Vatican and the Italian Parliament. According some grace to Mr. Grillo, it appears that Rome will, for a time at least, enjoy the privilege of three popes in town at the same time.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>(Plus tard, le <a class=\"gen\" href=\"http:\/\/EndtheLie.com\/2013\/03\/05\/heavens-above-the-sex-bomb-opus-dei-and-why-benedict-is-now-the-prisoner-of-the-vatican\/#ixzz2Mx56nQuR\">5 mars 2013<\/a>, Cottrell compl\u00e8te son dossier sur la crise vaticane en exposant les conditions selon lui de la \u00ab\u00a0d\u00e9mission forc\u00e9e\u00a0\u00bb de Beno&icirc;t XVI, des pressions de l&rsquo;<em>Opus Dei<\/em> sur le Vatican et ainsi de suite.)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Le <a class=\"gen\" href=\"http:\/\/EndtheLie.com\/2013\/02\/28\/taking-down-grillo-italian-spooks-lunge-at-the-castro-of-the-med\/#ixzz2Mx3ZF56b\">28 f\u00e9vrier 2013<\/a>, Cottrell en rajoute sur l&rsquo;alarme g\u00e9n\u00e9rale qu&rsquo;a fait sonner l&rsquo;\u00e9lection du 25 f\u00e9vrier. Pour lui, l&rsquo;analogie avec la dialectique des \u00ab\u00a0ann\u00e9es de plomb\u00a0\u00bb r\u00e9appara&icirc;t dans le chef d&rsquo;un document du service de renseignement italien de l&rsquo;arm\u00e9e, le <em>Servizio Informazioni Difesa<\/em>. Quant \u00e0 Grillo, Cottrell le baptise prestement \u00ab\u00a0le Castro de la M\u00e9diterran\u00e9e\u00a0\u00bb&hellip;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Less than 24 hours later the confirmation came in a report from the &lsquo;Department of Information Security&rsquo; and its national director, Giampiero Massolo, pointing to the outbreak of \u00ab\u00a0potentially massive social unrest, dissent and antagonism in wide areas of Italian society.\u00a0\u00bb<\/em> [&hellip;] <em>Viewed from Brussels, Washington and Frankfurt, Grillo is nothing less than the Castro of the Med.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Le <a class=\"gen\" href=\"http:\/\/EndtheLie.com\/2013\/03\/03\/italys-sans-cullotes-revolution-for-export\/#ixzz2MZ95eBhp\">3 mars 2013<\/a>, Cottrell revient sur Beppe Grillo et le M5S, cette fois dans un mode optimiste. D&rsquo;une part, il analyse M5S comme un mouvement promis \u00e0 un brillant avenir, peut-\u00eatre tr\u00e8s rapidement suffisamment majoritaire pour constituer un gouvernement (en cas de seconde \u00e9lection), et \u00e9galement promis \u00e0 susciter en Europe des mouvements similaires.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Practically unreported in the European and North American media, an extraordinary revolution is under way in Italy. It is nothing short of a peoples&rsquo; revolution which, failing to lose speed and traction as most such forces do after the first bright dawn, seems to be gaining ground in all quarters of Italian society.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>D&rsquo;autre part, il observe que m\u00eame certains segments de l&rsquo;<em>establishment<\/em> commencent \u00e0 consid\u00e9rer Grillo d&rsquo;un &oelig;il plus favorable&hellip;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>One of the country&rsquo;s most conservative newspapers, Corriera della Serra, which is printed in Milan, Italy&rsquo;s very own &lsquo;City of London,&rsquo; has astonished readers by expressing admiration for the &lsquo;quiet revolution,&rsquo; with the caveat of course that &lsquo;it won&rsquo;t last.&rsquo;<\/em> [&hellip;] <em>For the first time this sort of message is resounding in the highly conservative Italian media as an alternative script to enforced austerity. Italians of all classes came to resent the imposition of Mario Monti, an ex-EU Commissioner, as the effective dictator of the country, ruling with a handpicked bunch of cronies.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>L&rsquo;enjeu de l&rsquo;affaire italienne est donc d\u00e9fini dans son cadre le plus large possible par Cottrell dans ses trois articles. D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, on retient dans cette affaire le rapport \u00e0 la situation pr\u00e9sente, &ndash; la politique de l&rsquo;aust\u00e9rit\u00e9, la situation de l&rsquo;euro, la pouss\u00e9e de destruction des souverainet\u00e9s des &Eacute;tats de l&rsquo;Union europ\u00e9enne, et, par logique antagoniste, la pouss\u00e9e d&rsquo;implicite r\u00e9appropriation de cette souverainet\u00e9 qui se trouve au c&oelig;ur des mouvements de contestation antiSyst\u00e8me comme le M5S. Mais en revenant souvent sur la dimension <em>Gladio<\/em>, et dans sa dimension la plus large qui va jusqu&rsquo;\u00e0 impliquer le sort de l&rsquo;&Eacute;glise, Cottrell invite \u00e0 effectivement se pencher sur cette question, ce qui conduit \u00e0 s&rsquo;interroger sur l&rsquo;activisme de <em>Gladio<\/em> aujourd&rsquo;hui, autant qu&rsquo;\u00e0 faire le lien entre la situation actuelle et la p\u00e9riode de pleine activit\u00e9 du m\u00eame <em>Gladio<\/em> (dans le cas italien, les <em>anni di piombi<\/em>). (En compl\u00e9ment, on voit qu&rsquo;un autre incontestable sp\u00e9cialiste de <em>Gladio<\/em>, l&rsquo;universitaire Daniele Ganser, ent\u00e9rine la p\u00e9rennisation de <em>Gladio<\/em> dans notre \u00e9poque, sous une forme ou l&rsquo;autre. Voir deux textes, le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-gladio_explique-t-il_9_11_27_12_2005.html\">27 d\u00e9cembre 2005<\/a> et encore le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-gladio_explique-t-il_9_11_interview_du_dr_daniele_ganser_27_12_2005.html\">27 d\u00e9cembre 2005<\/a>.)<\/p>\n<\/p>\n<p><p>Pour notre compte, nous appr\u00e9cions <em>Gladio<\/em> sous forme de structure et de <strong>concept<\/strong> ; nous tenons donc que <em>Gladio<\/em>, ou son \u00e9manation suivant la fin de la guerre froide qu&rsquo;importe, est rest\u00e9 en activit\u00e9 dans certaines affaires sp\u00e9cifiques de l&rsquo;influence h\u00e9g\u00e9monique des USA en Europe. Ce fut notamment le cas notamment avec la question du \u00ab\u00a0choix\u00a0\u00bb du JSF par la Hollande en 2002, &ndash; ou la \u00ab\u00a0gestion du &lsquo;choix'\u00a0\u00bb devrait-on dire plut\u00f4t. Cette affaire se d\u00e9roula dans une atmosph\u00e8re dramatique, avec l&rsquo;assassinat du <em>leader<\/em> populiste Pim Fortuyn. Nous avions \u00e0 cette \u00e9poque not\u00e9 des aspects extr\u00eamement troubles de cette affaire (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_jsf_de_fortuyn_30_06_2002.html\">30 juin 2002<\/a>), \u00e0 une \u00e9poque o&ugrave; il \u00e9tait peu prudent de le faire. Nous repr&icirc;mes ces \u00e9l\u00e9ments dans des <em>Notes sur une \u00e9volution h\u00e9g\u00e9monique<\/em> qui concernait l&rsquo;implantation \u00ab\u00a0&lsquo;forc\u00e9e\u00a0\u00bb de l&rsquo;avion JSF en Europe, aupr\u00e8s de cinq pays europ\u00e9ens (Danemark, Hollande, Italie, Norv\u00e8ge, Royaume-Uni). Nous notions, dans ce texte du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_une_evolution_hegemonique_18_11_2009.html\">18 novembre 2009<\/a> (dans ce texte, \u00ab\u00a0SB\u00a0\u00bb signifie <em>Stay-Behind<\/em>, autre d\u00e9signation des r\u00e9seaux <em>Gladio<\/em>) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>&hellip;Le r\u00e9sultat de cette implantation fit des march\u00e9s europ\u00e9ens, \u00e0 l&rsquo;exception de la France, un territoire conquis qu&rsquo;il s&rsquo;agissait de g\u00e9rer. L&rsquo;exemple n\u00e9erlandais et le choix du JSF illustrent cette gestion.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>En 1998, une r\u00e9union secr\u00e8te entre des chefs militaires n\u00e9erlandais (sans mandat politique) et leurs correspondants industriels US avait abouti \u00e0 un accord pour le choix du JSF. En mars 2002, le gouvernement prit une d\u00e9cision dans ce sens, que le Parlement devait ratifier. Le 5 mai 2002, le leader populiste Pym Fortuyn, vainqueur probable aux \u00e9lections du 16 mai, rencontra une d\u00e9l\u00e9gation US conduite par l&rsquo;ambassadeur Clifford Sorel, o&ugrave; l&rsquo;on trouvait \u00e9galement des g\u00e9n\u00e9raux hollandais. Fortuyn leur signifia son refus de voter pour le programme JSF, ce qui impliquait une d\u00e9faite du programme au Parlement. Le lendemain, Fortuyn \u00e9tait assassin\u00e9 dans des conditions tr\u00e8s contest\u00e9e. Il fut remplac\u00e9 \u00e0 la t\u00eate des populistes par un inconnu, Mat Herben, dont il s&rsquo;av\u00e9ra qu&rsquo;il avait travaill\u00e9 pendant 22 ans pour les services d&rsquo;information de la d\u00e9fense, qui sont une antenne du SR militaire hollandais. Broos Schnez, de la direction du parti populiste, d\u00e9clara le 28 juin 2002, apr\u00e8s que son parti ait \u00e9t\u00e9 conduit par Herben \u00e0 voter pour le JSF: \u00ab\u00a0We were flabbergasted. The Netherlands needs to know what kind of person he is and he&rsquo;s not honest. He is an old ministry of defence official and perhaps his job was to infiltrate the operation to get the party to vote for the fighter, something which we were always against. I&rsquo;d advise him to go to a good lawyer and clear his name, but nothing is happening, and that&rsquo;s strange.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>L&rsquo;entr\u00e9e dans le programme JSF acquise, Herben donna sa d\u00e9mission de la direction du parti fond\u00e9 par Fortuyn et disparut. L&rsquo;affaire \u00e9tait close. Ce fut une remarquable op\u00e9ration r\u00e9alis\u00e9e dans le plus pur style SB, dont l&rsquo;implantation dans les SR hollandais (dont venait Herben) depuis la fin des ann\u00e9es 1940 est largement document\u00e9e. S&rsquo;il s&rsquo;agit de la manifestation la plus dramatique de l&rsquo;activit\u00e9 de ce r\u00e9seau europ\u00e9en\/OTAN d&rsquo;influence US, elle n&rsquo;en est pas moins exemplaire. On retrouve cette sorte de sch\u00e9ma dans nombre de pays europ\u00e9ens. Son efficacit\u00e9 ne s&rsquo;est jamais d\u00e9mentie.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cette appr\u00e9ciation de lier, notamment, l&rsquo;affaire du JSF \u00e0 l&rsquo;activit\u00e9 des r\u00e9seaux <em>Gladio<\/em> se retrouve pour l&rsquo;Italie. Lors du deuxi\u00e8me gouvernement Prodi de centre-gauche (mai 2006-mai 2008), les suggestions de remettre en question l&rsquo;achat du JSF faites \u00e0 cette \u00e9quipe qui se voulait europ\u00e9enne se heurtaient \u00e0 une fin de non-recevoir terrifi\u00e9e. Il fut toujours sugg\u00e9r\u00e9 par les contacts pris \u00e0 cette \u00e9poque du c\u00f4t\u00e9 de ce gouvernement italien que le retour sur le choix du JSF \u00e9tait impensable, ces d\u00e9clarations impliquant qu&rsquo;il s&rsquo;agissait r\u00e9ellement d&rsquo;une hypoth\u00e8se o&ugrave; des vies \u00e9taient menac\u00e9es. La r\u00e9f\u00e9rence Fortuyn\/Pays-Bas n&rsquo;est donc pas inutile&hellip; Le choix du JSF reste une pierre angulaire de l&rsquo;h\u00e9g\u00e9monie US en Europe, y compris par des moyens terroristes et totalement ill\u00e9gaux ; dans cette optique, le programme JSF, qui a une dimension globale et h\u00e9g\u00e9monique d\u00e9passant largement le seul statut d&rsquo;un programme d&rsquo;armement, a une dimension <strong>tragique<\/strong> du point de vue du destin europ\u00e9en tel que nous le concevons. Sa proximit\u00e9 des affaires <em>Gladio<\/em> rench\u00e9rit sur cet aspect, et d\u00e9signe l&rsquo;Italie comme un pays d&rsquo;une singuli\u00e8re importance, sans doute le plus important dans la trag\u00e9die europ\u00e9enne que constitue la destruction du principe de la souverainet\u00e9 sur ce continent par d\u00e9structuration des nations entra&icirc;nant la dissolution du principe.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">De la \u00ab\u00a0strat\u00e9gie de la tension\u00a0\u00bb \u00e0 la trag\u00e9die de la tension<\/h2>\n<\/p>\n<p><p>Comme le signale Cottrell, Beppe Grillo est parfaitement au courant de \u00ab\u00a0l&rsquo;histoire moderne\u00a0\u00bb de l&rsquo;Italie, et notamment des imbrications des activit\u00e9s de <em>Gladio<\/em> et de ce que cela repr\u00e9sente comme <strong>mal\u00e9diction<\/strong> pour l&rsquo;Italie. On le lit notamment dans une courte chronique de son <em>blog<\/em> \u00e0 laquelle Grillo renvoie dans les textes actuels de ce m\u00eame <em>blog<\/em> ; il s&rsquo;agit d&rsquo;un texte dat\u00e9 du <a class=\"gen\" href=\"http:\/\/www.beppegrillo.it\/2011\/11\/tecniche_di_col.html\">19 novembre 2011<\/a>, intitul\u00e9, par analogie au livre de Malaparte, \u00ab\u00a0Technique du coup d&rsquo;&Eacute;tat\u00a0\u00bb (<em>Tecniche di colpo di Stato<\/em>). (Malaparte est d&rsquo;ailleurs largement cit\u00e9 dans ce texte.) Grillo exprime l&rsquo;opinion que l&rsquo;Italie s&rsquo;est trouv\u00e9e dans une situation de \u00ab\u00a0coup d&rsquo;&Eacute;tat permanent\u00a0\u00bb, essentiellement \u00e0 partir des ann\u00e9es 1970. Il cite bien entendu l&rsquo;enl\u00e8vement et la mort d&rsquo;Aldo Moro comme l&rsquo;un des \u00e9v\u00e9nements marquant ce \u00ab\u00a0coup d&rsquo;&Eacute;tat permanent\u00a0\u00bb, cette affaire qui est l&rsquo;arch\u00e9type <strong>tragique<\/strong> de la p\u00e9riode de \u00ab\u00a0strat\u00e9gie de la tension\u00a0\u00bb, et donc de tous les soup\u00e7ons et intuitions sur l&rsquo;action de <em>Gladio<\/em> en Italie. Renzo Martinelli, r\u00e9alisateur de l&rsquo;excellent film (en 2003), <em>La place des cinq lunes<\/em>, sur le sujet de la mort d&rsquo;Aldo Moro trait\u00e9 en mode \u00e0 peine fictionnel, disait que l&rsquo;\u00e9v\u00e9nement avait eu le m\u00eame effet sur l&rsquo;Italie que l&rsquo;assassinat de Kennedy sur les USA :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>L&rsquo;affaire Moro a influenc\u00e9 l&rsquo;\u00e9volution historique, politique et culturelle de ce pays pour plusieurs d\u00e9cennies<\/em>&raquo;, &ndash; c&rsquo;est-\u00e0-dire, jusqu&rsquo;\u00e0 aujourd&rsquo;hui, et jusqu&rsquo;aux \u00e9lections du 25 f\u00e9vrier&hellip;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ainsi peut-on envisager un sch\u00e9ma historique qui, avec sa dimension tragique, prendrait des allures m\u00e9tahistoriques, pour mieux d\u00e9finir l&rsquo;importance de l&rsquo;\u00e9v\u00e9nement du 25 f\u00e9vrier en Italie. Dans le m\u00eame texte de son <em>blog<\/em> d\u00e9j\u00e0 cit\u00e9, Grillo en vient au c&oelig;ur de son propos en d\u00e9finissant le \u00ab\u00a0coup d&rsquo;&Eacute;tat parfait\u00a0\u00bb auquel sont arriv\u00e9s Monti et ceux qui le soutiennent. (Monti, qui devient Premier ministre le 16 novembre 2011, n&rsquo;est jamais nomm\u00e9 par Grillo dans son texte mais une photo en gros plan de son visage domine le texte et souligne le titre, de fa\u00e7on \u00e0 ne laisser planer aucune incertitude, tout en transformant l&rsquo;accusation en symbole.)<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo; <em>Le coup d&rsquo;&Eacute;tat est la n\u00e9gation de la d\u00e9mocratie. Le coup d&rsquo;&Eacute;tat qui ne dit pas son nom&hellip; est le coup d&rsquo;&Eacute;tat parfait<\/em> &raquo;. (&laquo;<em>Il colpo di Stato \u00e8 la negazione della democrazia. Il colpo di Stato che non si conosce, quello in cui il cittadino esulta per un cambiamento che lo spossessa di ogni partecipazione pubblica, \u00e8 il colpo di Stato perfetto.<\/em>&raquo;)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>D&rsquo;une certaine fa\u00e7on, selon la pens\u00e9e de Grillo, on pourrait juger que le \u00ab\u00a0coup d&rsquo;&Eacute;tat parfait\u00a0\u00bb de Monti achevait, en esp\u00e9rant la verrouiller, une p\u00e9riode de trois ou quatre d\u00e9cennies de \u00ab\u00a0coup d&rsquo;&Eacute;tat permanent\u00a0\u00bb o&ugrave; l&rsquo;agitation, dont on peut supposer qu&rsquo;un art\u00e9fact type-<em>Gladio<\/em> \u00e9tait au pupitre, emp\u00eachait encore la bonne tenue de l&rsquo;application du Syst\u00e8me, &ndash; mais en la pr\u00e9parant, certes. Enfin, Monti vint, et ce fut le \u00ab\u00a0coup d&rsquo;&Eacute;tat parfait\u00a0\u00bb, <strong>sans<\/strong> complot, selon toutes les proc\u00e9dures normales, disons pseudo-d\u00e9mocratiques. Pourtant, cette normalit\u00e9 est si exceptionnelle, et le \u00ab\u00a0coup d&rsquo;&Eacute;tat parfait\u00a0\u00bb tout autant, qu&rsquo;il nous faut bien trouver la raison centrale, et de grand poids, qui a permis cela. Aussit\u00f4t s&rsquo;impose l&rsquo;\u00e9vidence : certes, le \u00ab\u00a0coup d&rsquo;&Eacute;tat parfait\u00a0\u00bb est r\u00e9ussi, &ndash; en un sens mais quel sens lourd de sens ! &ndash; parce qu&rsquo;il n&rsquo;y plus d&rsquo;&Eacute;tat &hellip;<\/p>\n<\/p>\n<p><p>C&rsquo;est justement ce qu&rsquo;a mis \u00e0 d\u00e9couvert le pseudo-complot Monti (pseudo puisque non secret et nullement ill\u00e9gal) : l&rsquo;absence d&rsquo;&Eacute;tat, donc l&rsquo;absence de principe&hellip; C&rsquo;est sa faiblesse mortelle, comme celle du Syst\u00e8me, cette absence de principe. Le \u00ab\u00a0coup parfait\u00a0\u00bb s&rsquo;est exerc\u00e9 sur du quasi-n\u00e9ant (l&rsquo;&Eacute;tat r\u00e9duit \u00e0 ses proc\u00e9dures, vote de l&rsquo;assembl\u00e9e, intervention-Syst\u00e8me des autorit\u00e9s de la r\u00e9publique, etc., et l&rsquo;&Eacute;tat totalement ch\u00e2tr\u00e9 de ses principes, &ndash; l&rsquo;&Eacute;tat devenu &Eacute;tat-eunuque). Le \u00ab\u00a0coup d&rsquo;Etat parfait\u00a0\u00bb a en r\u00e9alit\u00e9 achev\u00e9 une perfection par inversion, en achevant de d\u00e9montrer et de r\u00e9aliser la n\u00e9antisation parfaite de l&rsquo;&Eacute;tat. Cela s&rsquo;est d\u00e9couvert aussit\u00f4t, en pleine lumi\u00e8re, par l&rsquo;application sans vergogne, furieuse, m\u00e9prisante, insultante, d&rsquo;une politique-Syst\u00e8me que ne soutenait \u00e9videmment aucune l\u00e9gitimit\u00e9. Comme les gens de son acabit et de son parti, Monti est parfaitement l&rsquo;exemple de l&rsquo;homme tr\u00e8s-intelligent qui fait des choses tr\u00e8s-stupides : une technique parfaite pour appliquer une politique n\u00e9cessairement inapplicable puisque priv\u00e9e du socle de la l\u00e9gitimit\u00e9 qui seul peut permettre de demander \u00e0 un peuple des efforts h\u00e9ro\u00efques.<\/p>\n<\/p>\n<p><p>D&rsquo;o&ugrave; ceci que Beppe a techniquement raison mais pas tout \u00e0 fait, en renvoyant apr\u00e8s tout \u00e0 l&rsquo;id\u00e9e de Malaparte qu&rsquo;on prendrait trop rapidement pour du comptant, selon laquelle le coup d&rsquo;&Eacute;tat n&rsquo;est qu&rsquo;une \u00ab\u00a0technique\u00a0\u00bb. Laiss\u00e9 effectivement \u00e0 ce rang de technique et parfait dans ce domaine, le coup d&rsquo;&Eacute;tat de Monti est parfait. Mais il est appliqu\u00e9 selon la notion d&rsquo;un autre Italien (l&rsquo;historien et philosophe de l&rsquo;histoire Guglielmo Ferrero) d&rsquo;<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notre_11_novembre_11_11_2008.html\">id\u00e9al de puissance<\/a> qui, par essence, rejette la perfection en ignorant la n\u00e9cessit\u00e9 du principe, et donc va aussit\u00f4t g\u00e2cher la perfection du coup d&rsquo;Etat par sa politique absurde, et qui est absurde justement parce que celui qui l&rsquo;op\u00e9rationnalise n&rsquo;a aucune l\u00e9gitimit\u00e9, vierge de tout principe &hellip; Faut-il s&rsquo;en \u00e9tonner, de sa part \u00e0 lui, Monti, qui vient directement de ces centres de puissance que sont l&rsquo;Union europ\u00e9enne, \u00ab\u00a0la banque\u00a0\u00bb et <em>tutti quanti<\/em>, toutes ces puissances parfaitement priv\u00e9es de l\u00e9gitimit\u00e9, donc investies de l&rsquo;id\u00e9al de puissance seulement, totalement \u00e9trang\u00e8res \u00e0 l&rsquo;<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-genie_latin_et_germanisme_de_guglielmo_ferrero_1917_08_12_2008.html\">id\u00e9al de perfection<\/a> qui, seul, comprend la n\u00e9cessit\u00e9 du socle principiel ? (Les deux notions, de Ferrero certes, explicit\u00e9es dans les deux textes r\u00e9f\u00e9renc\u00e9s.)<\/p>\n<\/p>\n<p><p>Nous dirions m\u00eame que Monti, apr\u00e8s son \u00ab\u00a0coup d&rsquo;&Eacute;tat parfait\u00a0\u00bb, c&rsquo;\u00e9tait la \u00ab\u00a0dictature parfaite\u00a0\u00bb, sans besoin de police, de contrainte brutale, de saluts divers, poings ou mains ouvertes lev\u00e9s, de bottes et de casques ; en ce sens purement \u00ab\u00a0technique\u00a0\u00bb l\u00e0 aussi, bien plus efficace que la vraie-fausse dictature dont nous entretenons nos naus\u00e9es permanentes en d\u00e9fense des droits de l&rsquo;homme. Mais si elle s&rsquo;instaure, cette \u00ab\u00a0dictature parfaite\u00a0\u00bb, c&rsquo;est parce que (bis) il n&rsquo;y a plus d&rsquo;&Eacute;tat, plus de Principe, plus rien du tout. Ainsi le paradoxe supr\u00eame, le \u00ab\u00a0paradoxe parfait\u00a0\u00bb, c&rsquo;est que Monti a mis tout cela en \u00e9vidence ; en instituant toutes ces perfections inverties par l&rsquo;id\u00e9al de puissance mais contraires \u00e0 l&rsquo;id\u00e9al de perfection, il a d\u00e9montr\u00e9 \u00ab\u00a0techniquement\u00a0\u00bb et parfaitement \u00e0 la fois son ill\u00e9gitimit\u00e9 absolue, et l'\u00a0\u00bbimposture parfaite\u00a0\u00bb qu&rsquo;il fut. La racl\u00e9e \u00e9lectorale suivit, sans bavure. C&rsquo;est la perfection m\u00eame de l&rsquo;op\u00e9ration-Monti qui entra&icirc;na n\u00e9cessairement sa chute, &ndash; sans tambour ni trompette, sans \u00e9meutes, sans violence, &ndash; par les urnes, messieurs-dames, comme en belle et bonne d\u00e9mocratie.<\/p>\n<\/p>\n<p><p>Le coup d&rsquo;&Eacute;tat de Monti n&rsquo;\u00e9tait pas id\u00e9ologique, il \u00e9tait du domaine du principe, c&rsquo;est-\u00e0-dire antiPrincipe comme l&rsquo;on dit, inversement pour ses adversaires, antiSyst\u00e8me ; contre le principe de la souverainet\u00e9, et bien entendu, celui de la l\u00e9gitimit\u00e9&hellip; A ce moment appara&icirc;t Beppe. Lui, Beppe, intervenant dans cette situation d&rsquo;ill\u00e9gitimit\u00e9 et d&rsquo;inversion des autorit\u00e9s en place, surgit comme un moteur antiSyst\u00e8me qui peut pr\u00e9tendre apporter avec lui la restauration des principes. C&rsquo;est alors que lui, Grillo et ses <em>Grillini<\/em> r\u00e9alisent ce qu&rsquo;on d\u00e9signerait comme un \u00ab\u00a0contre-coup d&rsquo;&Eacute;tat parfait\u00a0\u00bb, et cette fois perfection totalement assum\u00e9e puisqu&rsquo;activ\u00e9e par l&rsquo;id\u00e9al de perfection qui est principiel par d\u00e9finition, contre l&rsquo;id\u00e9al de puissance ayant d\u00e9montr\u00e9 sa propre \u00ab\u00a0parfaite imposture\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Le fait qui appara&icirc;t alors essentiel est que l&rsquo;\u00e9v\u00e9nement, par l&rsquo;historique m\u00eame de ses acteurs (d\u00e9faite du \u00ab\u00a0coup d&rsquo;&Eacute;tat parfait\u00a0\u00bb verrouillant trois \u00e0 quatre d\u00e9cennies de \u00ab\u00a0coup d&rsquo;&Eacute;tat permanent\u00a0\u00bb), installe dans sa signification cette m\u00eame perspective des 3-4 pr\u00e9c\u00e9dentes d\u00e9cennies. C&rsquo;est l\u00e0 que l&rsquo;histoire <strong>tragique<\/strong> de l&rsquo;Italie que nous avons \u00e9voqu\u00e9e rencontre la situation politique <strong>tragique<\/strong> de l&rsquo;Europe avec cette bataille entre l&rsquo;arbitraire de la politique d&rsquo;aust\u00e9rit\u00e9 (id\u00e9al de puissance) et la r\u00e9sistance antiSyst\u00e8me des peuples (\u00e9lections type-25 f\u00e9vrier, id\u00e9al de perfection). C&rsquo;est l\u00e0 o&ugrave; l&rsquo;on pourrait, au gr\u00e9 des p\u00e9rip\u00e9ties \u00e0 venir tr\u00e8s vite (dont, peut-\u00eatre, de nouvelles \u00e9lections italiennes risquant de placer le M5S en position dirigeante), voir se m\u00ealer \u00e0 la bataille actuelle de l&rsquo;aust\u00e9rit\u00e9, toute l&rsquo;histoire <strong>tragique<\/strong> de l&rsquo;Italie de ces quarante derni\u00e8res ann\u00e9es. Cette \u00e9ventuelle co\u00efncidence des deux choses peut s&rsquo;av\u00e9rer explosive au-del\u00e0 de tout.<\/p>\n<\/p>\n<p><p>&hellip;Voici donc les \u00e9l\u00e9ments de ce qui n&rsquo;est pour l&rsquo;instant, encore, qu&rsquo;un puzzle. La tr\u00e8s in\u00e9dite instabilit\u00e9 que conna&icirc;t l&rsquo;Italie depuis le 25 f\u00e9vrier, avec l&rsquo;\u00e9l\u00e9ment Beppe Grillo, se m\u00e9lange avec des \u00e9l\u00e9ments exceptionnels, comme la crise du Vatican, et des potentialit\u00e9s qui ne le sont pas moins. Bien s&ucirc;r, nous avons insist\u00e9 sur l&rsquo;\u00e9l\u00e9ment <em>Gladio<\/em> en le liant \u00e0 l&rsquo;\u00e9l\u00e9ment du JSF, parce que des circonstances d\u00e9stabilisantes peuvent les faire surgir et les int\u00e9grer, comme acc\u00e9l\u00e9rateur des \u00e9v\u00e9nements, dans ce secteur de la crise g\u00e9n\u00e9rale et d&rsquo;effondrement du Syst\u00e8me que nous sommes en train d&rsquo;observer. Ainsi isolera-t-on trois de ces \u00e9l\u00e9ments autour de la crise italienne :<\/p>\n<\/p>\n<p><p>&bull; La crise du Vatican et de l&rsquo;&Eacute;glise a \u00e9t\u00e9 op\u00e9rationnalis\u00e9e par la d\u00e9mission de Beno&icirc;t XVI. Le plus souvent consid\u00e9r\u00e9e par les commentateurs d&rsquo;un point de vue anticl\u00e9rical, comme l&rsquo;une des querelles \u00e0 l&rsquo;int\u00e9rieur du Syst\u00e8me, dans le cadre g\u00e9n\u00e9ral des pol\u00e9miques dites \u00ab\u00a0soci\u00e9tales\u00a0\u00bb qui dissimulent la crise fondamentale, elle est en train de changer compl\u00e8tement de signification et de s&rsquo;inscrire dans la crise fondamentale. Qu&rsquo;elle ait (qu&rsquo;elle acquiert) ou n&rsquo;ait pas (n&rsquo;acquiert pas) de lien avec la crise italienne, la crise de l&rsquo;&Eacute;glise \u00e9volue d\u00e9sormais vers et comme une manifestation terrible de ce qui constitue la crise g\u00e9n\u00e9rale du sens. Dans ce pays catholique, le symbole a une force consid\u00e9rable, dans le cadre italien en g\u00e9n\u00e9ral et dans le cadre de la crise d&rsquo;effondrement du Syst\u00e8me ; il se concr\u00e9tise par l&rsquo;id\u00e9e de la Chute (cette fois, pour l&rsquo;&Eacute;glise elle-m\u00eame) et s&rsquo;inscrit alors, non plus dans le cadre de la crise des religions, mais comme un \u00e9l\u00e9ment majeur de la crise de civilisation, &ndash; pour nous, crise d&rsquo;effondrement du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>&bull; Le cas de <em>Gladio<\/em> se situe bien entendu dans les menaces de riposte du Syst\u00e8me face \u00e0 la crise italienne. Il peut aussi bien \u00eatre consid\u00e9r\u00e9 du point de vue op\u00e9rationnel que du point de vue du symbole de la <strong>trag\u00e9die<\/strong> italienne. Dans ce dernier cas, qui est celui que nous favorisons, il contribue \u00e0 hausser et \u00e0 a renforcer le sens et la <strong>tension<\/strong> de la crise italienne.<\/p>\n<\/p>\n<p><p>&bull; Le cas de JSF, que nous avons souvent \u00e9voqu\u00e9 comme infiniment plus important qu&rsquo;un simple programme d&rsquo;armement, a les liens qu&rsquo;on sait avec <em>Gladio<\/em> et avec les relations entre les USA et l&rsquo;Europe. (Comme nous \u00e9crivons plus haut : \u00ab\u00a0Le choix du JSF reste une pierre angulaire de l&rsquo;h\u00e9g\u00e9monie US en Europe, y compris par des moyens terroristes et totalement ill\u00e9gaux.\u00a0\u00bb) Le JSF lui-m\u00eame est en crise profonde, la crise de la Chute pour lui aussi, refl\u00e9tant le fondement de la crise de l&rsquo;am\u00e9ricanisme et du technologisme. Dans les circonstances de crise qu&rsquo;on conna&icirc;t en Italie, son cas peut surgir \u00e0 tous moments au premier plan du d\u00e9bat politique, et constituer alors un cas dramatique per\u00e7u comme une volont\u00e9 de rupture de l&rsquo;Italie (de l&rsquo;Europe) avec les USA. Il impliquerait alors, &ndash; cette perspective peut \u00eatre consid\u00e9r\u00e9e, &ndash; comme la mise en cause de l&rsquo;homog\u00e9n\u00e9isation du bloc BAO constitu\u00e9 \u00e0 partir de 2008, tel que nous l&rsquo;avons d\u00e9fini le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_bloc_bao_10_12_2012.html\">10 d\u00e9cembre 2012<\/a>, et la d\u00e9structuration-dissolution de cet ultime regroupement suscit\u00e9 par le Syst\u00e8me dans sa crise de l&rsquo;effondrement.<\/p>\n<\/p>\n<p><p>L&rsquo;un des documents les plus int\u00e9ressants et les plus r\u00e9v\u00e9lateurs sur les r\u00e9seaux <em>Gladio<\/em> fut une s\u00e9rie documentaire de BBC <em>Time Watch<\/em> (<em>Operation Gladio<\/em>, en trois \u00e9pisodes), r\u00e9alis\u00e9e en 1992 mais diffus\u00e9e avec un significatif temps de retard (accessible sur <em>YouTube<\/em>, date de r\u00e9alisation du <a class=\"gen\" href=\"http:\/\/www.youtube.com\/watch?v=yXavNe81XdQ\">10 juin 1992<\/a>). Le documentaire portait essentiellement sur l&rsquo;activit\u00e9 de <em>Gladio<\/em> en Belgique et en Italie, tout en embrassant la totalit\u00e9 du concept. (Nous en avons notamment parl\u00e9, le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-l_hypoth_se_hersh_et_l_cho_des_ann_es_de_plomb__20_01_2005.html\">20 janvier 2005<\/a>.) Il y a un moment caract\u00e9ristique, qui termine la s\u00e9rie, avec quelques derniers mots de Federico Umberto d&rsquo;Amaio, pr\u00e9sent\u00e9 comme \u00ab\u00a0chef de la police politique au minist\u00e8re de l&rsquo;int\u00e9rieur italien, 1972-1974\u00a0\u00bb ; petit bonhomme ricanant et sans doute cynique, qui aurait bien repr\u00e9sent\u00e9 le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_notre_psychologie_28_01_2013.html\">persiflage<\/a> d&rsquo;autres temps. Alors \u00e0 la retraite, il poss\u00e9dait quelques figurines d'\u00a0\u00bbautomates\u00a0\u00bb dont on fit grand usage de la mode, dans les salons du XVIII\u00e8me si\u00e8cle, au temps du persiflage. Les th\u00e8ses m\u00e9canistes de Descartes avaient leurs partisans, et l&rsquo;automate pouvait aussi bien repr\u00e9senter le v\u00e9ritable <em>sapiens<\/em>, &ndash; semblait sugg\u00e9rer en persiflant l&rsquo;ancien policier italien, pr\u00e9sentant l&rsquo;automate \u00ab\u00a0Le jongleur\u00a0\u00bb (en fran\u00e7ais dans sa bouche). Il \u00e9voquait les myst\u00e8res, les manipulations, le double, le triple jeu, et s&rsquo;il semblait laisser croire que <em>Gladio<\/em> les manipulait tous, on finissait par se demander si ceux qui pr\u00e9tendaient agir en toute conscience au nom de <em>Gladio<\/em>, voire en dirigeant <em>Gladio<\/em>, n&rsquo;\u00e9taient pas, dans son esprit, eux-m\u00eames compris dans ce \u00ab\u00a0tous\u00a0\u00bb. <em>Gladio<\/em> prend alors dans le document une dimension mythique et tragique, soudain per\u00e7u comme une entit\u00e9 les manipulant \u00ab\u00a0tous\u00a0\u00bb, y compris cette voix persifleuse&hellip; Ces paroles concluaient la s\u00e9rie, tandis que sonnait \u00e0 nos oreilles, \u00e0 c\u00f4t\u00e9 de la musique aigre et m\u00e9canique de l&rsquo;automate, le leitmotiv du document, les <em>Agnus Dei<\/em> et <em>Hostias<\/em>, solennels, terribles et \u00e9nigmatiques, du <em>Requiem<\/em> Opus 5 de Berlioz, ou \u00ab\u00a0Grande messe des Morts\u00a0\u00bb&hellip; Alors, l&rsquo;on sent qu&rsquo;il est bien question d&rsquo;une <strong>trag\u00e9die<\/strong> d\u00e9passant son \u00e9poque, parce qu&rsquo;elle sugg\u00e8re l&rsquo;id\u00e9e d&rsquo;une perte de contr\u00f4le de son destin par l&rsquo;esp\u00e8ce des <em>sapiens<\/em>, &ndash; ce qui est le cas de la crise d&rsquo;effondrement du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>Nous entendons cet homme, ce persifleur ricanant, dans ces documentaires, comme si le drame effa\u00e7ait le temps, liant et fusionnant la trag\u00e9die pass\u00e9e avec celle que nous connaissons&hellip; Cette trag\u00e9die vient jusqu&rsquo;\u00e0 nous, d&rsquo;une fa\u00e7on tr\u00e8s logique, en s&rsquo;\u00e9largissant \u00e0 la situation italienne, au-del\u00e0 \u00e0 la situation europ\u00e9enne, allant ainsi au c&oelig;ur de la crise d&rsquo;effondrement du Syst\u00e8me en offrant une circonstance diff\u00e9rente qui peut acc\u00e9l\u00e9rer cette crise en portant une attaque d\u00e9structurante et dissolvante au bloc BAO constitu\u00e9 en 2008. Cela constituerait un des prolongements ultimes de la phase finale de l&rsquo;effondrement du Syst\u00e8me.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La trag\u00e9die de la tension 9 mars 2013 &ndash; Nous allons tenter d&rsquo;analyser les \u00e9v\u00e9nements italiens, essentiellement avec la victoire du Movimento 5 Stelle (M5S) et de Beppe Grillo du 25 f\u00e9vrier (voir notamment le 26 f\u00e9vrier 2013), et depuis cet \u00e9v\u00e9nement, selon une approche g\u00e9n\u00e9raliste et antiSyst\u00e8me, en nous pla\u00e7ant singuli\u00e8rement par rapport \u00e0&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[7972,4796,11976,11996,2631,4413,11977,2622,11997,4415,3440,5733,2661,3918],"class_list":["post-74878","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-annee","tag-benoit","tag-beppe","tag-cottrell","tag-de","tag-gladio","tag-grillo","tag-la","tag-p2","tag-plomb","tag-strategie","tag-tension","tag-vatican","tag-xvi"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74878"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74878\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}