{"id":74892,"date":"2013-03-19T07:35:53","date_gmt":"2013-03-19T07:35:53","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/03\/19\/chronique-du-19-courant-harmonie\/"},"modified":"2013-03-19T07:35:53","modified_gmt":"2013-03-19T07:35:53","slug":"chronique-du-19-courant-harmonie","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/03\/19\/chronique-du-19-courant-harmonie\/","title":{"rendered":"Chronique du 19 courant\u2026 Harmonie"},"content":{"rendered":"<p><h2 class=\"common-article2\">Chronique du 19 courant Harmonie<\/h2>\n<\/p>\n<p><p>\t19 mars 2013 Je vais commencer cette chronique par des citations de lecteurs, lesquelles citations ont \u00e0 voir avec le m\u00e9canisme des donations mensuelles, lequel m\u00e9canisme a \u00e0 voir avec l&rsquo;\u00e9tablissement de cette <em>chronique du 19 courant<\/em> (voir le <a href=\"http:\/\/www.dedefensa.org\/article-chronique_du_19_courant_pr_sentation_19_07_2012.html\" class=\"gen\">19 juillet 2012<\/a>). Voyez comme tout s&rsquo;encha\u00eene harmonieusement Harmonie, d&rsquo;ailleurs et justement, tel est le titre de cette chronique, alors qu&rsquo;en une premi\u00e8re version j&rsquo;avais choisi Angoisse &#038; panique ; vous avez d\u00e9j\u00e0 tout en r\u00e9sum\u00e9, par la gr\u00e2ce d&rsquo;une logique que je jugerais admirable parce qu&rsquo;elle m&rsquo;\u00e9tait au d\u00e9part \u00e9trang\u00e8re et qu&rsquo;elle est venue, par la force des choses, guider les choix de ce texte et de ses mots, et la plume qui les \u00e9crit. (Ce qui veut dire \u00e9galement ceci : ne craignez rien et ne vous d\u00e9couragez pas, je ne parlerai des donations que dans l&rsquo;entame ; ensuite la musique changera.)<\/p>\n<\/p>\n<p><p>\tLes lecteurs, d&rsquo;abord. Ils sont deux, et tous deux d&rsquo;excellent conseil, ils ont \u00e9crit dans un esprit chaleureux que je ressens comme la marque d&rsquo;une belle estime pour le site, le travail qui y est fait et <em>tutti quanti<\/em>. Mon esprit \u00e0 moi, en les citant, est \u00e0 mesure. Il y a d&rsquo;abord Jean-Jacques Hector, le <a href=\"http:\/\/www.dedefensa.org\/forum-dedefensaorg_son_alarme_mensuelle_et_son_tat_d_esprit_25_01_2013.html\" class=\"gen\">25 janvier 2013<\/a>, dans le <em>Forum<\/em> du texte correspondant, et son intervention sous le titre Angoisses.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Je comprends que la fr\u00e9quentation quotidienne de l&rsquo;absurde fasse monter chez vous quelque angoisse, comment faire autrement?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Mais quoi? Voil\u00e0 un moments que les donations sont significativement plus importantes en fin de mois.<\/em> [] [A]<em>lors, pourquoi vous inqui\u00e9ter ? Epargnez-vous ce pesant exercice mensuel si vous le pouvez. Bonne chance.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit ensuite de notre lecteur qui s&rsquo;est lui-m\u00eame donn\u00e9 le pseudo de <em>Mumen<\/em>, le <a href=\"http:\/\/www.dedefensa.org\/forum-dedefensaorg_il_y_a_peut-_tre_un_peu_urgence__25_02_2013.html\" class=\"gen\">25 f\u00e9vrier 2013<\/a>, sur le <em>Forum<\/em> du texte attenant. (<em>Mumen<\/em> nous signale par ailleurs des manquements de notre part. Je dis cela en reprenant le nous courant sur <em>dedefensa.org<\/em>, parce que c&rsquo;est dans ce contexte qu&rsquo;il faut r\u00e9pondre, en mettant en \u00e9vidence que nous sommes inexcusables, que nous n&rsquo;avons pour notre cause que les pi\u00e8tres choses habituelles du d\u00e9bordement de l&rsquo;esprit par les circonstances qui s&rsquo;accumulent et qui pressent, du temps trop court, de l&rsquo;attention sans cesse sollicit\u00e9e par les \u00e9v\u00e9nements du monde) <em>Mumen<\/em> met \u00e9galement en cause cette panique mensuelle (qui \u00e9tait angoisse dans le premier courrier) et les textes d&rsquo;alerte des donations qui en seraient le legs.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Et puis votre panique mensuelle du 19 est d\u00e9primante. Je la saute. C&rsquo;est le seul post de votre plume que je zappe par lassitude, duss\u00e9-je perdre une once de votre personne priv\u00e9e, puisqu&rsquo;il s&rsquo;agit la d&rsquo;une de ses rares manifestations. Mr Grasset, je vous aime, mais n&rsquo;ai pas l&rsquo;intention de vous sauver tous les mois.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Votre force tient sans doute en autre chose que QI, culture, outils et talent. Le stress est il votre moyen de toujours rester en \u00e9veil ? D\u00e9sireriez vous r\u00e9ellement le calme et la paix que procurent une tr\u00e9sorerie et des comptes pr\u00e9visionnels sains ?<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>dedefensa mourra-t-elle de ce stress, de cette vie survolt\u00e9e, surdou\u00e9e, ou bien aurons nous la chance et le privil\u00e8ge de vous lire encore des ann\u00e9es (tant que \u00e7a dure, je veux dire, le monde comme on le connait). Qui perdra en dernier, vous ou le syst\u00e8me ?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tSans consid\u00e9rer le fond de l&rsquo;argument, comme promis, il est vrai que ce sentiment d&rsquo;angoisse, voire de panique (ce terme est peut-\u00eatre moins appropri\u00e9), disons d&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale cette humeur d\u00e9pressive est la marque du caract\u00e8re de l&rsquo;auteur de ces lignes. A sa d\u00e9charge, j&rsquo;ajoute, qu&rsquo;outre de n&rsquo;en pas faire myst\u00e8re, il lui arrive d&rsquo;en faire son miel sinon sa bonne fortune. On a vu des textes sur la <a href=\"http:\/\/www.dedefensa.org\/article-chronique_du_19_courant_l_angoisse-melancholia_19_09_2012.html\" class=\"gen\">m\u00e9lancolie<\/a>, sur <a href=\"http:\/\/www.dedefensa.org\/article-chronique_du_19_courant_trag_die_19_10_2012.html\" class=\"gen\">notre trag\u00e9die<\/a>, sur la <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_maniaco-depression_du_monde_ddecrisis_19_01_2012.html\" class=\"gen\">maniaco-d\u00e9pression<\/a> et le bon usage qu&rsquo;on peut en faire, mais surtout sur la <a href=\"http:\/\/www.dedefensa.org\/article-r_silience_pour_r_silience_09_11_2012.html\" class=\"gen\">r\u00e9silience<\/a> o\u00f9 je trouve l&rsquo;argument d\u00e9cisif de l&rsquo;utilit\u00e9 absolument b\u00e9n\u00e9fique, voire essentielle, de ce qui semblerait \u00eatre un c\u00f4t\u00e9 irr\u00e9m\u00e9diablement sombre de la psychologie. Ma conviction plus g\u00e9n\u00e9rale, par exp\u00e9rience certes mais par appr\u00e9hension intellectuelle \u00e9galement, est bien que tout ce qui est d\u00e9pressif dans le caract\u00e8re pr\u00e9sente, dans une mesure importante ou minime c&rsquo;est selon, d&rsquo;une fa\u00e7on \u00e9vidente ou dissimul\u00e9e c&rsquo;est selon encore, le germe d&rsquo;une utilisation contraire, d&rsquo;une capacit\u00e9 d&rsquo;inversion vertueuse de la situation dissolvante et inf\u00e9conde de la d\u00e9pression, d&rsquo;un surgissement d&rsquo;une force constructive et cr\u00e9atrice. De ce point de vue qui met la chimie organique compl\u00e8tement de c\u00f4t\u00e9 en ne la consid\u00e9rant que comme un outil de transmission, ce qui est d\u00e9sign\u00e9 dans le langage courant comme une pathologie serait l&rsquo;occurrence malheureuse o\u00f9 l&rsquo;\u00eatre ne parvient jamais, pour une raison ou l&rsquo;autre, \u00e0 activer cette potentialit\u00e9.<\/p>\n<\/p>\n<p><p>\tCela, c&rsquo;est un aspect du probl\u00e8me que ces remarques m&rsquo;ont amen\u00e9 \u00e0 consid\u00e9rer de nouveau. L&rsquo;autre aspect est la question de la permanence de cet aspect d\u00e9pressif, ou bien sa relativit\u00e9, et par rapport \u00e0 quoi. Ce point de vue est tr\u00e8s important, dans mon chef, car il est le d\u00e9terminant d&rsquo;une conception selon laquelle je consid\u00e8re l&rsquo;\u00eatre en g\u00e9n\u00e9ral, le <em>sapiens<\/em> et sa psychologie dans ce cas mais aussi d&rsquo;autres \u00eatres, comme tr\u00e8s fortement li\u00e9s \u00e0 l&rsquo;activit\u00e9, \u00e0 la dynamique, \u00e0 la puissance du monde,  en d&rsquo;autres mots et pour d&rsquo;autres buts de d\u00e9monstration : li\u00e9s \u00e0 l&rsquo;histoire et \u00e0 la m\u00e9tahistoire, et influenc\u00e9s par elles, directement (par les \u00e9v\u00e9nements eux-m\u00eames), et surtout pour notre propos, indirectement, avec l&rsquo;\u00e9volution et la transformation de l&rsquo;humeur, voire du caract\u00e8re lui-m\u00eame. Je me r\u00e9p\u00e8te pour permettre la transition et g\u00e9n\u00e9raliser le propos : cela est tr\u00e8s important pour une conception des choses que je crois <strong>primordiale<\/strong>, au sens commun et au sens spirituel du mot.<\/p>\n<\/p>\n<p><p>\tEn effet, si cette combinaison de la r\u00e9silience avec sa potentialit\u00e9 cr\u00e9atrice existe heureusement, il n&rsquo;en reste pas moins qu&rsquo;elle t\u00e9moigne d&rsquo;un d\u00e9s\u00e9quilibre, d&rsquo;une <strong>absence d&rsquo;harmonie<\/strong> (on verra plus loin pourquoi j&rsquo;insiste sur ce mot harmonie). Je consid\u00e9rerais alors et dans un premier temps,  bien entendu,  cette r\u00e9silience comme une r\u00e9action urgente et n\u00e9cessaire, un acte de r\u00e9sistance, un acte antiSyst\u00e8me si vous voulez, activ\u00e9 contre cette entreprise funeste de d\u00e9structuration-dissolution qui frappe la psychologie. (C&rsquo;est dire, \u00e0 l&rsquo;\u00e9nonc\u00e9 de cette phrase charg\u00e9e de mots et d&rsquo;expression de l&rsquo;arsenal dialectique courant de <em>dedefensa.org<\/em>, combien j&rsquo;adh\u00e8re \u00e0 l&rsquo;hypoth\u00e8se de l&rsquo;influence directe, et surtout indirecte comme je l&rsquo;ai d\u00e9finie, des \u00e9v\u00e9nements sur la psychologie.) Si elle est cela (r\u00e9action, acte de r\u00e9sistance, acte antiSyst\u00e8me), c&rsquo;est qu&rsquo;il y a agression, et qu&rsquo;il y a bien entendu Syst\u00e8me avec le cort\u00e8ge de pressions d\u00e9structurantes et dissolvantes. Ainsi ai-je toujours eu la conviction, tr\u00e8s longtemps confuse, plus r\u00e9cemment explicit\u00e9e, que cette situation (d\u00e9pression-r\u00e9silience) n&rsquo;est pas une situation absolue, une fatalit\u00e9 de la psychologie humaine. Elle est si forte aujourd&rsquo;hui, si oppressante, avec \u00e9ventuellement mais n\u00e9cessairement une r\u00e9sistance \u00e0 mesure, parce que les \u00e9v\u00e9nements ont l&rsquo;ampleur que l&rsquo;on observe, qu&rsquo;ils sont les \u00e9v\u00e9nements de ce qui est peut-\u00eatre une crise terminale du Syst\u00e8me, d&rsquo;une civilisation devenue contre-civilisation. (L\u00e0 aussi ma conviction fait bon march\u00e9 du peut-\u00eatre pour avancer que c&rsquo;est sans nul doute le cas.)<\/p>\n<\/p>\n<p><p>\t Alors se trouve puissamment et glorieusement activ\u00e9e, comme l&rsquo;indice d&rsquo;une r\u00e9action \u00e0 la fois vitale et sublime, la tendance naturelle \u00e0 se tourner vers le pass\u00e9, pour trouver, ou plut\u00f4t re-trouver des signes de cette harmonie perdue de la psychologie. J&rsquo;y viens parce qu&rsquo;une lecture tr\u00e8s r\u00e9cente m&rsquo;en a donn\u00e9 quelques indications pr\u00e9cises. Il s&rsquo;agit de celle de Lucien Jerphagnon, que j&rsquo;ai d\u00e9couvert sur le tard, comme tant de choses qui tentent de contrebattre mon inculture originelle. (1) Jerphagnon est un ma\u00eetre de la description de la psychologie des anciens, appuy\u00e9e sur une formidable connaissance de la philosophie de ces temps-l\u00e0. (Le favori de Jerphagnon est Plotin, ce qui en a tout de suite fait un de mes amis.) Dans son dernier livre posthume (Jerphagnon est mort en septembre 2011), au titre si parfaitement r\u00e9silient apr\u00e8s tout de <em>L&rsquo;homme qui riait avec les dieux<\/em>, on trouve rassembl\u00e9s divers textes recueillis dans les documents qu&rsquo;il a laiss\u00e9s derri\u00e8re lui. J&rsquo;en retire ici deux extraits du m\u00eame texte (\u00ab<em>Myst\u00e8re et v\u00e9rit\u00e9<\/em>\u00bb) o\u00f9 il nous parle de cette psychologie des anciens dont il situe les derni\u00e8res traces dans notre Moyen \u00c2ge, qui se trouve r\u00e9sum\u00e9e par ce mot d\u00e9j\u00e0 cit\u00e9 plus haut, que je souligne en gras.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Si les sciences et la philosophie \u00e9clairaient la nature d&rsquo;un monde trop longtemps rest\u00e9 opaque, si elles permettaient de s&rsquo;y affirmer et d&rsquo;y mieux vivre, il fallait bien reconna\u00eetre qu&rsquo;aucun savoir n&rsquo;expliquait tout. A commencer par le fait qu&rsquo;il y avait un monde. La croyance r\u00e9pondait au besoin qui subsistait d&rsquo;une pr\u00e9sence tut\u00e9laire, quasi parentale, avec l&rsquo;insondable origine de tout, avec la source \u00e9ternelle d&rsquo;un monde emport\u00e9 par le temps. Avec, finalement, la source de toute esp\u00e9rance.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Ayant si longtemps partag\u00e9 la vie quotidienne des gens de l&rsquo;Antiquit\u00e9 et du Moyen \u00c2ge, j&rsquo;aurais aim\u00e9 restituer aujourd&rsquo;hui quelque chose de l&rsquo;<\/em><strong><em>harmonie<\/em><\/strong> <em>d&rsquo;hier. R\u00e9concilier autant que possible le myst\u00e8re de la v\u00e9rit\u00e9 et la v\u00e9rit\u00e9 du myst\u00e8re. Comme dans tous les divorces, la rupture entre le savoir et le croire a fait des d\u00e9g\u00e2ts, et il me para\u00eet difficilement \u00e9vitable que l&rsquo;homme moderne ne se sente frustr\u00e9 d&rsquo;une dimension essentielle, aussi essentielle que l&rsquo;autre, de son \u00e9quilibre, pour ne point prononcer le mot trop vague de bonheur<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tJe ressens comme la pr\u00e9sence exaltante d&rsquo;une v\u00e9rit\u00e9 grandiose dans cette discr\u00e8te suggestion de la puissance apais\u00e9e qu&rsquo;implique cette harmonie d&rsquo;hier, que je vois principalement s&rsquo;appliquer \u00e0 la psychologie humaine et, par cons\u00e9quent, directement alimenter et aider \u00e0 mettre au jour une pens\u00e9e exprimant aussi pr\u00e9cis\u00e9ment cette m\u00eame harmonie dans la perception du myst\u00e8re du monde et dans la description qu&rsquo;on peut en faire. Admettant cela, on ne peut plus s&rsquo;\u00e9tonner que les Grecs nous ait donn\u00e9 tant de grands esprits, et que les plus grands qui suivirent tant que cette harmonie surv\u00e9cut y fissent constamment r\u00e9f\u00e9rence, en m\u00eame temps qu&rsquo;eux-m\u00eames \u00e9taient de la m\u00eame r\u00e9f\u00e9rence,  au moins, de Platon \u00e0 Plotin si l&rsquo;on veut (Jusqu&rsquo;au moment du commencement du grand changement, selon Jerphagnon, o\u00f9, \u00ab[a]<em>vec Augustin, l&rsquo;autonomie de la philosophie par rapport \u00e0 la religion prend fin<\/em>\u00bb.)<\/p>\n<\/p>\n<p><p>\tComme on devrait la comprendre selon cette appr\u00e9ciation de notre civilisation mise dans la perspective de l&rsquo;\u00e9volution tragique du <em>sapiens<\/em>, l&rsquo;\u00e9volution de sa psychologie est la mesure la plus incontestable de cette trag\u00e9die, et les tourments de cette psychologie confront\u00e9e \u00e0 des conditions du monde insupportables le sont plus encore. Je crois fermement que si l&rsquo;on parvient \u00e0 avoir un comportement, un caract\u00e8re, une pens\u00e9e nourris \u00e0 cette intuition haute de l&rsquo;existence originelle de cette harmonie, comme une lumi\u00e8re qui parvenait \u00e0 transcrire encore le reflet du Principe unique, de l&rsquo;insondable origine de tout, les tourments de la psychologie que l&rsquo;on conna\u00eet n\u00e9cessairement aujourd&rsquo;hui acqui\u00e8rent un sens. Elle ne sont pas en vain ; elles sont absolument le contraire d&rsquo;une pathologie mais source de gu\u00e9rison ; elles sont n\u00e9cessaires, elles sont tout simplement <strong>vitales<\/strong> en ceci qu&rsquo;elles sont la sauvegarde de l&rsquo;esprit si cela est possible, et puisque cela est \u00e9videmment possible<\/p>\n<\/p>\n<p><p>\tAinsi est-ce en revenir \u00e0 la d\u00e9pression, \u00e0 l&rsquo;angoisse, \u00e0 la m\u00e9lancolie qui \u00e9taient au point de d\u00e9part de cette r\u00e9flexion, pourtant \u00e0 partir d&rsquo;une occasion qui pourrait appara\u00eetre anodine ou triviale et qui n&rsquo;en est pas moins r\u00e9v\u00e9latrice comme tout ce qui a trait \u00e0 notre psychologie. Dans ce cas, la r\u00e9silience qui vous fait transmuter une humeur d\u00e9pressive en une dynamique cr\u00e9atrice se nourrit \u00e0 cette conviction que l&rsquo;harmonie a d\u00e9j\u00e0 exist\u00e9, et qu&rsquo;elle pourrait exister \u00e0 nouveau, et ainsi cette terrible agitation qui vous secoue et semble vous martyriser \u00e0 nouveau et constamment prend tout son sens en \u00e9clairant le sens dont elle est porteuse. La r\u00e9silience qui vous fait jaillir d&rsquo;une d\u00e9pression n&rsquo;est pas une revanche, une riposte, ce qui indiquerait que vous \u00eates toujours prisonnier de votre d\u00e9pression, mais justement le contraire, une \u00e9chapp\u00e9e vers la lumi\u00e8re et l&rsquo;harmonie dont cette lumi\u00e8re est l&rsquo;indice. La bataille et le tumulte que nous connaissons sont ce que nous faisons qu&rsquo;ils sont ; ils peuvent parfaitement \u00eatre, ils le sont m\u00eame n\u00e9cessairement au bout de la r\u00e9flexion, une recherche de l&rsquo;harmonie.<\/p>\n<\/p>\n<p><p>\tAinsi n&rsquo;ai-je aucune h\u00e9sitation, lorsqu&rsquo;une de mes r\u00e9flexions y invite presque sous la forme de ce qu&rsquo;on jugerait \u00eatre une confession, \u00e0 exposer ces tourments de mon esprit suscit\u00e9s par les \u00e9carts de ma psychologie. Les lumi\u00e8res du pass\u00e9 m&rsquo;indiquent sans le moindre de ces doutes que l&rsquo;ombre de notre \u00e9poque cr\u00e9pusculaire suscite parfois, qu&rsquo;il y a dans ce trouble profond les signes d&rsquo;une lutte ardente qui a un sens si \u00e9lev\u00e9. Ce n&rsquo;est pas \u00eatre si fou (je ne suis pas si fou) ; c&rsquo;est celui qui en jugerait diff\u00e9remment qui, malheureusement, prendrait ou subirait le risque terrible de l&rsquo;\u00eatre, le fou. <\/p>\n<\/p>\n<p>\n<p class=\"signature\">Philippe Grasset<\/p>\n<\/p>\n<h4>Note<\/h4>\n<p>(1)  Certes, inculte, bien plus inculte qu&rsquo;on croit, l&rsquo;auteur. Aussi, pour r\u00e9pondre \u00e0 une <a href=\"http:\/\/www.dedefensa.org\/forum-le_1914_du_dirigeant_europ_en_type_12_03_2013.html\" class=\"gen\">lectrice<\/a>, j&rsquo;avoue sans fard n&rsquo;avoir pas lu l&rsquo;<em>Homme sans qualit\u00e9<\/em> de Robert Musil. Puisque l&rsquo;occasion s&rsquo;y pr\u00eate, commande de la chose a \u00e9t\u00e9 pass\u00e9e.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chronique du 19 courant Harmonie 19 mars 2013 Je vais commencer cette chronique par des citations de lecteurs, lesquelles citations ont \u00e0 voir avec le m\u00e9canisme des donations mensuelles, lequel m\u00e9canisme a \u00e0 voir avec l&rsquo;\u00e9tablissement de cette chronique du 19 courant (voir le 19 juillet 2012). Voyez comme tout s&rsquo;encha\u00eene harmonieusement Harmonie, d&rsquo;ailleurs et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[18],"tags":[3834,12015,3083,7099,11966,12014,12016,4119,10032,3099,11979,4858],"class_list":["post-74892","post","type-post","status-publish","format-standard","hentry","category-archivesphg","tag-angoisse","tag-croire","tag-depression","tag-donations","tag-hector","tag-jerphagnon","tag-mumen","tag-platon","tag-plotin","tag-psychologie","tag-resilience","tag-savoir"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74892"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74892\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}