{"id":74917,"date":"2013-04-03T04:09:29","date_gmt":"2013-04-03T04:09:29","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/04\/03\/le-mythe-du-glaive\/"},"modified":"2013-04-03T04:09:29","modified_gmt":"2013-04-03T04:09:29","slug":"le-mythe-du-glaive","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/04\/03\/le-mythe-du-glaive\/","title":{"rendered":"Le mythe du glaive"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">Le mythe du glaive<\/h2>\n<\/p>\n<p><p>3 avril 2013 &ndash; Il y a une citation c\u00e9l\u00e8bre du <em>Livre d&rsquo;Isa\u00efe<\/em>, qui doit certainement inspirer nos psychologies enfi\u00e9vr\u00e9es et nos esprits r\u00e9duits \u00e0 l&rsquo;affect&hellip; &laquo;<em>Et Il jugera les nations, et Il convaincra d&rsquo;erreur des peuples nombreux; et ils forgeront de leurs glaives des socs de charrue, et de leurs lances des faux.<\/em>&raquo; Le glaive est donc devenu notre mani\u00e8re de penser la modernit\u00e9, mani\u00e8re post-postmoderniste si l&rsquo;on veut. (Et l&rsquo;on vous jure qu&rsquo;apr\u00e8s, sans aucun doute, le glaive deviendra soc de charrue, &ndash; la chute passe tout, &ndash; et sauve tout&hellip;) La chose, cette mani\u00e8re-l\u00e0 de penser par l&rsquo;id\u00e9e de l&rsquo;arme, a pris, dans ces m\u00eames psychologies conduisant \u00e0 ces m\u00eames esprits, la dimension d&rsquo;un mythe ; tout \u00e9tant inversion lorsqu&rsquo;on parle de ces gens-l\u00e0, il s&rsquo;agit donc d&rsquo;un mythe inverti, qui dit le contraire de ce qu&rsquo;on lui fait pr\u00e9tendre. (Vous n&rsquo;avez pas affaire \u00e0 des Achille-au-pied-l\u00e9ger, press\u00e9s de montrer leur h\u00e9ro\u00efsme, ayant choisi &laquo;<em>une vie courte, mais glorieuse, plut\u00f4t qu&rsquo;une existence longue mais sans \u00e9clat<\/em>&raquo; ; vous avez affaire \u00e0 des bureaucrates et \u00e0 des scribouillards \u00e0 la psychologie captive.)<\/p>\n<\/p>\n<p><p>La Syrie et la question des armes qu&rsquo;il faudrait livrer aux rebelles sont une illustration de cette d\u00e9rive d&rsquo;entropisation de l&rsquo;intelligence, et illustration valant d\u00e9monstration effrayante et catastrophique. La question g\u00e9n\u00e9rale de la crise syrienne s&rsquo;est en effet <strong>contract\u00e9e<\/strong> depuis plusieurs mois et, d&rsquo;une fa\u00e7on agressive sinon hyst\u00e9rique, sinon paroxystique, sur la question des armes, &ndash; des armements que devraient recevoir les rebelles, et qui leur permettrait de l&#8217;emporter en liquidant celui-qui-ne-m\u00e9rite-pas-d&rsquo;exister (<em>dixit<\/em> Fabius, successeur de Vergennes, \u00e0 propos d&rsquo;Assad le Syrien). Ensuite, c&rsquo;est entendu, \u00ab\u00a0ils forgeront de leurs glaives des socs de charrue\u00a0\u00bb, ou des ordinateurs si vous voulez, et ce qui est s&ucirc;r c&rsquo;est que les lendemains chanteront.<\/p>\n<\/p>\n<p><p>On a suffisamment parl\u00e9, ces derniers temps, de livraison d&rsquo;armes aux rebelles syriens et aux d\u00e9bats \u00e0 la fois byzantins et monstrueux qu&rsquo;elles occasionnent, jusqu&rsquo;\u00e0 susciter des pugilats en marge d&rsquo;un sommet, entre princes respectivement saoudiens et qatariens. On peut en voir l\u00e0-dessus le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_un_gaullisme_postmoderne_16_03_2013.html\">16 mars 2013<\/a>, le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_bloc_bao_et_sa_crise_18_03_2013.html\">18 mars 2013<\/a>, le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-qui_commande_ici_kerry_l_ue_ou_le_syst_me__26_03_2013.html\">26 mars 2013<\/a>, le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-les_armes_vers_la_syrie_et_leurs_vertus_inattendues_29_03_2013.html\">29 mars 2013<\/a> (les princes puncheurs). (Nous laissons l\u00e0 aussi de c\u00f4t\u00e9 l&rsquo;aspect, on devrait dire l&rsquo;\u00e9vidence du fait. Discuter sur le fond de la logique de la position du bloc BAO, c&rsquo;est s&rsquo;attaquer avec la raison \u00e0 l&rsquo;explicitation d&rsquo;une position essentiellement r\u00e9gl\u00e9e par l&rsquo;affectivit\u00e9, par une psychologie malade, par la confusion extr\u00eame de l&rsquo;intelligence qui s&rsquo;en d\u00e9duit. Cette discussion n&rsquo;a donc pas lieu d&rsquo;\u00eatre, puisqu&rsquo;il s&rsquo;agit ici de rien moins que d&rsquo;un <strong>diagnostic<\/strong> d&rsquo;ores et d\u00e9j\u00e0 pos\u00e9.)<\/p>\n<\/p>\n<p><p>Le domaine des livraisons d&rsquo;armes aux rebelles a d&rsquo;abord \u00e9t\u00e9 un aspect normal d&rsquo;un ensemble (le bloc BAO) engag\u00e9 dans son soutien aux rebelles. On sait que, pour notre compte, l&rsquo;id\u00e9e du \u00ab\u00a0soutien aux rebelles\u00a0\u00bb croule sous le poids des r\u00e9serves et critiques que nous en faisons (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-de_la_guerre_qui_n_a_pas_eu_lieu_en_syrie_02_04_2012.html\">2 avril 2012<\/a>, le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notre_double_standard_jusqu_la_naus_e_01_06_2012.html\">1er juin 2012<\/a>, le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_notre_tragique_grotesquerie_suite_syrienne_17_12_2012.html\">17 d\u00e9cembre 2013<\/a>, etc.). Mais ce domaine des livraisons d&rsquo;armes \u00e9tait en lui-m\u00eame \u00e0 l&rsquo;abri de ces critiques et ressortait \u00e9videmment du principe de l&rsquo;aide aux rebelles ; le principe est faussaire, stupide, etc., mais ses cons\u00e9quences (livraison d&rsquo;armes) n&rsquo;ont \u00e0 voir qu&rsquo;avec la logique interne de cette position politique. Pourtant et entretemps, la question des livraisons d&rsquo;armes a acquis une sp\u00e9cificit\u00e9 propre, &ndash; et l&rsquo;on voit plus loin pourquoi, qui est l&rsquo;essentiel de notre propos. Elle est devenue fondamentale, et presque le seul centre du d\u00e9bat sur le soutien aux rebelles (notamment parce que l&rsquo;hypoth\u00e8se alternative et radicale d&rsquo;une intervention arm\u00e9e du bloc BAO se heurte \u00e0 des obstacles colossaux, et surtout \u00e0 une impuissance \u00e9vidente de ceux qui l&rsquo;\u00e9voquent avec r\u00e9gularit\u00e9)&hellip; Tr\u00e8s vite, on a \u00ab\u00a0enrichi\u00a0\u00bb ce d\u00e9bat \u00e9videmment faussaire de pr\u00e9cisons significatives : il faut des armes \u00ab\u00a0lourdes\u00a0\u00bb, des armes en g\u00e9n\u00e9ral dites \u00ab\u00a0avanc\u00e9es\u00a0\u00bb, et en g\u00e9n\u00e9ral avec la pr\u00e9cision et l&rsquo;efficacit\u00e9 qu&rsquo;on en attend ; il faut <strong>surtout<\/strong> dans ces armes \u00ab\u00a0avanc\u00e9es\u00a0\u00bb, plus pr\u00e9cis\u00e9ment, des syst\u00e8mes sol-air portables par un seul homme, et maniables par un ou deux servant(s). Ce dernier point est celui qui nous attache pr\u00e9cis\u00e9ment, qui a \u00e9t\u00e9 souvent d\u00e9velopp\u00e9, qui est devenu un <strong>symbole<\/strong> de la \u00ab\u00a0lutte in\u00e9gale\u00a0\u00bb des rebelles vertueux contre un pouvoir tyrannique et usurpateur des vertus de la modernit\u00e9, et disposant notamment de la tra&icirc;tresse et massacreuse puissance a\u00e9rienne contre laquelle les rebelles ne peuvent rien, comme offerts en holocauste, &ndash; ainsi, en effet, se d\u00e9veloppe la <em>narrative<\/em>. Dans cette <em>narrative<\/em>, nous verrions aussi bien, d&rsquo;ailleurs et venu du r\u00e9cit antique, le missile sol-air portable, individuel, tir\u00e9 contre un h\u00e9licopt\u00e8re (surtout) ou un avion, comme la fronde de David qui frappe mortellement le monstrueux Goliath&hellip;<\/p>\n<\/p>\n<p><p>Cela demande \u00e9videmment \u00e0 \u00eatre explicit\u00e9&hellip; Ce <strong>symbole<\/strong> de la technicit\u00e9 op\u00e9rationnelle autant que des vertus des r\u00e9cits les plus antiques et bibliques que repr\u00e9sente l&rsquo;armement sol-air portable et individuel \u00e0 fournir aux rebelles contre la puissance a\u00e9rienne syrienne a une histoire, qui a pris rang, elle aussi, de symbole lib\u00e9rateur, et lib\u00e9ratoire lorsqu&rsquo;il est soumis comme argument puisqu&rsquo;il permet de se dispenser d&rsquo;argumenter r\u00e9ellement en se repliant sur une r\u00e9f\u00e9rence unanimement per\u00e7ue comme vraie. Il s&rsquo;agit de la guerre d&rsquo;Afghanistan des ann\u00e9es 1980, des moudjahidines contre les forces sovi\u00e9tiques principalement, &ndash; ou, comme la psychologie conduit \u00e0 l&rsquo;interpr\u00e9ter, \u00ab\u00a0les combattants de la libert\u00e9 contre la barbarie\u00a0\u00bb&hellip; C&rsquo;est dire si, l\u00e0 aussi, il y a une <em>narrative<\/em>. On ne s&rsquo;\u00e9tonnera pas qu&rsquo;elle m\u00eale, dans ce cas, l&rsquo;h\u00e9ro\u00efsme de l&rsquo;hollywoodisme, la vertu id\u00e9ologique de l&rsquo;am\u00e9ricanisme et celle du dollar. Il s&rsquo;agit de la version de la guerre d&rsquo;Afghanistan selon laquelle c&rsquo;est sp\u00e9cifiquement un syst\u00e8me d&rsquo;arme, bien entendu am\u00e9ricaniste, le syst\u00e8me sol-air portable et individuel <em>Stinger<\/em>, qui a permis \u00e0 la r\u00e9sistance afghane de l&#8217;emporter. Ce point de vue a \u00e9t\u00e9, au fil du temps et de l&rsquo;action du syst\u00e8me de la communication, d\u00e9tach\u00e9 du reste de l&rsquo;histoire tr\u00e8s complexe des arcanes officieuses et\/ou secr\u00e8tes de ce conflit. (La CIA et le financement US y jou\u00e8rent leur r\u00f4le d\u00e8s juillet 1979, comme le montre l&rsquo;interview fameuse de Brzezinski de janvier 1998 au <em>Nouvel Observateur<\/em> [voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-les_origines_du_d_sordre_pr_sent_par_brzezinski_en_janvier_1998_31_07_2005.html\">31 juillet 2005<\/a>], mais aussi l&rsquo;Arabie Saoudite, l&rsquo;&Eacute;gypte, le Pakistan, etc., pour citer quelques-unes des tr\u00e8s nombreuses forces qui apport\u00e8rent des soutiens divers, souvent int\u00e9ress\u00e9s, \u00e0 la r\u00e9sistance afghane.)<\/p>\n<\/p>\n<p><p>La \u00ab\u00a0saga du <em>Stinger<\/em>\u00a0\u00bb est devenue un r\u00e9cit autonome qui induit une sorte de \u00ab\u00a0vertu en soi\u00a0\u00bb, bas\u00e9 sur l&rsquo;action du d\u00e9put\u00e9 r\u00e9publicain du Texas Charles Wilson, de la milliardaire r\u00e9publicaine et anticommuniste Joanne Herring, etc., tout cela \u00e9tant renforc\u00e9 par un livre en 2003, puis couronn\u00e9 par <a class=\"gen\" href=\"http:\/\/fr.wikipedia.org\/wiki\/La_Guerre_selon_Charlie_Wilson\">un film<\/a> en 2007, <em>La Guerre de Charles Wilson<\/em>, avec Tom Hanks et Julia Roberts. Tout le monde y trouvait son compte : l&rsquo;am\u00e9ricanisme et ses int\u00e9r\u00eats autant que sa communication humaniste et moderniste, la r\u00e9putation des USA d\u00e9fenseurs de la libert\u00e9, Hollywood et ses <em>blockbusters<\/em> lib\u00e9raux et maquill\u00e9s en une \u00ab\u00a0histoire\u00a0\u00bb faussaire, l&rsquo;industrie d&rsquo;armement et le technologisme US, etc. Accessoirement, on parlait avec des larmes dans les yeux des \u00ab\u00a0combattants de la libert\u00e9\u00a0\u00bb afghans, mais ce n&rsquo;\u00e9tait manifestement pas le sujet central.<\/p>\n<\/p>\n<p><p>Cette formidable <em>narrative<\/em> soutient principalement, depuis pr\u00e8s de deux ans, toutes les suggestions d&rsquo;armer les rebelles syriens contre Assad, avec d&rsquo;autant plus l&rsquo;argument que ces rebelles sont d\u00e9sarm\u00e9s face \u00e0 l&rsquo;aviation syrienne. (Nous parlons d&rsquo;un \u00ab\u00a0soutien psychologique\u00a0\u00bb \u00e0 ces suggestions, qui n&rsquo;a pas n\u00e9cessairement besoin d&rsquo;\u00eatre explicit\u00e9. La <em>narrative<\/em> concernant la guerre d&rsquo;Afghanistan des ann\u00e9es 1980 constitue l&rsquo;une de ces interventions massives \u00e0 effets psychologiques rationnellement non contr\u00f4l\u00e9s, donc inconscients, auxquelles le syst\u00e8me de la communication nous a habitu\u00e9s ; cette intervention se situe en-de\u00e7\u00e0 de l&rsquo;analyse de la raison, de l&rsquo;exp\u00e9rience qui doit soutenir cette analyse, etc. Cette <em>narrative<\/em> du syst\u00e8me de la communication a une force implicite, non exprim\u00e9e directement et ainsi \u00e0 l&rsquo;abri de la critique historique, sur les psychologies influen\u00e7ant sans le moindre filtre rationnel le jugement des diff\u00e9rents acteurs du bloc BAO dans la crise syrienne.) Outre une exaltation quasi r\u00e9flexive-pavlovienne du r\u00f4le des USA, de l&rsquo;industrie des armements US, etc., la <em>narrative<\/em> <em>Stinger<\/em>\/Afghanistan permet une identification de la r\u00e9bellion syrienne \u00e0 la vertu de la r\u00e9sistance afghane des ann\u00e9es 1980. (On oublie, pour ne pas alourdir le propos, qu&rsquo;une partie non n\u00e9gligeable de cette r\u00e9sistance pr\u00e9parait l&rsquo;expansion islamiste qui a suivi, mais en observant aussi avec une certaine ironie qu&rsquo;on retrouve le cas en Syrie.)<\/p>\n<\/p>\n<p><p>On peut lire par ailleurs un article sur le r\u00f4le des <em>Stinger<\/em> en Afghanistan, que nous mettons en ligne ce m\u00eame <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_narrative_des_stinger_en_afghanistan_03_04_2013.html\">3 avril 2013<\/a>. Il appara&icirc;t que ce syst\u00e8me joua un r\u00f4le important sur la fin du conflit (1986-1987), mais en aucune fa\u00e7on un r\u00f4le d\u00e9cisif et encore moins exclusif ; en 1986-1987, Gorbatchev \u00e9tait d\u00e9j\u00e0 d\u00e9termin\u00e9 \u00e0 un retrait, et l&rsquo;efficacit\u00e9 des missiles sol-air portables \u00e0 cette \u00e9poque fut rendue possible par l&rsquo;extr\u00eame concentration, \u00e0 partir de 1984, des moyens et tactiques d&rsquo;intervention des Sovi\u00e9tiques par la voie a\u00e9rienne. En aucun cas, on ne peut cr\u00e9diter le <em>Stinger<\/em>, et le missile sol-air portable, d&rsquo;une part d\u00e9cisive dans la victoire de la r\u00e9sistance. Certains chefs de la r\u00e9sistance, comme <a class=\"gen\" href=\"http:\/\/fr.wikipedia.org\/wiki\/Ahmed_Chah_Massoud\">Massoud<\/a> (qui ne plaisait que moyennement aux Am\u00e9ricains), pr\u00e9f\u00e9r\u00e8rent s&rsquo;en tenir aux tactiques de la guerre asym\u00e9trique, ou guerre de 4\u00e8me g\u00e9n\u00e9ration (G4G), d&rsquo;ailleurs avec un succ\u00e8s remarquable. (Il semble bien que Massoud n&rsquo;ait jamais dispos\u00e9 de <em>Stinger<\/em>, et, dans la p\u00e9riode 1979-1985 il avait refus\u00e9 d&rsquo;utiliser des SA-7 <em>Strella<\/em> sovi\u00e9tiques, de m\u00eame type que les <em>Stinger<\/em> mais moins performants.)<\/p>\n<\/p>\n<p><p>L&rsquo;\u00e9pisode <em>Stinger<\/em>\/Afghanistan remis dans la perspective de la v\u00e9rit\u00e9 du conflit afghan montre, pour ce qu&rsquo;il en fut de l&rsquo;usage du <em>Stinger<\/em>, que les conditions quasiment <em>sine qua non<\/em> d&#8217;emploi se trouvent dans une base d&rsquo;infrastructure et d&rsquo;organisation solide et stable de la part des utilisateurs, avec un minimum de connaissances technologiques et op\u00e9rationnelles. Bien entendu, cette description vaut exactement autant pour tout autre type d&rsquo;armements \u00ab\u00a0avanc\u00e9s\u00a0\u00bb, de hautes technologies. Il est loin d&rsquo;\u00eatre acquis que la r\u00e9bellion syrienne puisse pr\u00e9senter de tels caract\u00e8res, alors qu&rsquo;on y trouve presqu&rsquo;autant d&rsquo;affrontements entre groupes concurrents, qu&rsquo;entre eux-m\u00eames et le r\u00e9gime Assad. D&rsquo;autre part, bien entendu, l&rsquo;analogie des situations est absolument contestable, notamment dans le fait que les rebelles afghans luttaient contre une force \u00e9trang\u00e8re d&rsquo;invasion tandis que l&rsquo;arm\u00e9e syrienne peut \u00eatre qualifi\u00e9e de beaucoup de choses mais certainement pas de \u00ab\u00a0force \u00e9trang\u00e8re d&rsquo;invasion\u00a0\u00bb. A partir de la r\u00e9f\u00e9rence <em>Stinger<\/em>\/Afghanistan, et la v\u00e9rit\u00e9 que nous avons expos\u00e9e du d\u00e9calage entre la pr\u00e9sentation de communication et de relations publiques, et la r\u00e9alit\u00e9 op\u00e9rationnelle, on peut s&rsquo;interroger sur la r\u00e9elle efficacit\u00e9 qu&rsquo;aurait un afflux d&rsquo;armes avanc\u00e9es vers la r\u00e9bellion anti-Assad. C&rsquo;est l\u00e0 finalement le point op\u00e9rationnel central du d\u00e9bat. Notre appr\u00e9ciation est que l&rsquo;introduction de telles armes, si elle changerait n\u00e9cessairement les conditions du conflit, et notamment la politique de \u00ab\u00a0la guerre syrienne\u00a0\u00bb, n&rsquo;am\u00e8nerait certainement pas ce changement radical en faveur des rebelles qu&rsquo;attendent les acteurs du bloc BAO. Il nous semblerait plut\u00f4t qu&rsquo;elle introduirait un facteur de d\u00e9sordre suppl\u00e9mentaire tr\u00e8s important en renfor\u00e7ant le conflit dans son intensit\u00e9, sans n\u00e9cessairement donner aux rebelles une capacit\u00e9 suppl\u00e9mentaire d\u00e9cisive, peut-\u00eatre m\u00eame en produisant un effet contre-productif en leur faisant abandonner une m\u00e9thode de guerre asym\u00e9trique pour un conflit plus conventionnel pour lequel ils ne seraient ni organis\u00e9s, ni unifi\u00e9s, ni m\u00eame form\u00e9s. Elle conduirait sans nul doute \u00e0 des engagements suppl\u00e9mentaires du c\u00f4t\u00e9 du r\u00e9gime syrien, notamment du c\u00f4t\u00e9 russe, mais aussi irakien et iranien, qui introduiraient un facteur d&rsquo;incertitude de plus en m\u00eame temps qu&rsquo;une extension du conflit.<\/p>\n<\/p>\n<p><p>Toutes ces r\u00e9flexions devraient avoir \u00e9t\u00e9 faites, avec suffisamment de force pour ne plus pr\u00e9senter l&rsquo;argument des armements avanc\u00e9s comme \u00e9vident, et le voir perdurer, presque imp\u00e9ratif, avec une pr\u00e9gnance remarquable. Ce n&rsquo;est pas le cas. L&rsquo;argument n&rsquo;est combattu que par des hypoth\u00e8ses selon lesquelles il pourrait aller vers des mains d\u00e9couvertes impures, &ndash; celles des islamistes parmi les rebelles, &ndash; nullement sur sa valeur propre qui reste intacte, qui continue \u00e0 \u00eatre exalt\u00e9e parfois avec une fi\u00e8vre \u00e9tonnante, sinon suspecte. C&rsquo;est cette situation qui, finalement, nous int\u00e9resse, et qui nous ram\u00e8ne \u00e0 notre exposition du cas au d\u00e9but de ce texte : ce que nous nommons \u00ab\u00a0le mythe du glaive\u00a0\u00bb. Il est alors beaucoup moins question de la \u00ab\u00a0guerre syrienne\u00a0\u00bb, des rebelles, de la r\u00e9f\u00e9rence <em>Stinger<\/em>\/Afghanistan, et beaucoup plus, sinon essentiellement, de la psychologie malade qui r\u00e8gne dans les directions politiques et les \u00e9lites (intellectuelles dans le sens de sa d\u00e9marche m\u00e9diatique) du bloc BAO ; mais cell-ci (la psychologie malade) s&rsquo;exer\u00e7ant sans vergogne \u00e0 propos de ceux-l\u00e0 (\u00ab\u00a0guerre syrienne\u00a0\u00bb, rebelles, r\u00e9f\u00e9rence <em>Stinger<\/em>\/Afghanistan, etc.).<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">L&rsquo;armement comme \u00ab\u00a0cause\u00a0\u00bb politique et morale<\/h2>\n<\/p>\n<p><p><em>Narrative<\/em> diverses, r\u00e9f\u00e9rence implicite \u00e0 l&rsquo;Afghanistan des ann\u00e9es 1980 dans son seul aspect vertueux, aspect de la technologie avanc\u00e9e des armes envisag\u00e9es, dilemme des \u00ab\u00a0bons\u00a0\u00bb rebelles et des islamistes, &ndash; \u00e0 l&rsquo;aide de tous ces \u00ab\u00a0ustensiles\u00a0\u00bb que nous avons rapidement pass\u00e9s en revue, cette question de l&rsquo;armement des rebelles a pris la place centrale dans la psychologie des acteurs-Syst\u00e8me (bloc BAO) dans un processus qui s&rsquo;est d\u00e9velopp\u00e9 en un peu plus d&rsquo;un an. D\u00e8s lors que les Russes et les Chinois s&rsquo;opposaient \u00e0 l&rsquo;ONU \u00e0 une nouvelle op\u00e9ration type-Libye (en f\u00e9vrier 2012), l&rsquo;intervention de cette sorte, qui \u00e9tait pourtant la favorite de la <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_la_politique-syst_me__17_11_2012.html\">politique-Syst\u00e8me<\/a>, devenait un risque consid\u00e9rable et passait au second plan des options envisag\u00e9es ; sa r\u00e9apparitions au premier plan \u00e0 l&rsquo;une et l&rsquo;autre occasions, d&rsquo;une fa\u00e7on \u00e9pisodique, indique qu&rsquo;il s&rsquo;agit d\u00e9sormais d&rsquo;une option \u00ab\u00a0accidentelle\u00a0\u00bb, qui pourrait \u00e0 l&rsquo;extr\u00eame d&rsquo;une situation incontr\u00f4l\u00e9e \u00eatre choisie d&rsquo;une fa\u00e7on inopin\u00e9e ou se d\u00e9velopper d&rsquo;elle-m\u00eame, mais qui resterait comme ayant \u00e9t\u00e9 activ\u00e9e d&rsquo;une fa\u00e7on effectivement accidentelle. En d&rsquo;autres mots, cette option n&rsquo;est plus ma&icirc;tresse de la psychologie des acteurs-Syst\u00e8me (bloc BAO), et c&rsquo;est effectivement l&rsquo;armement qui l&rsquo;a remplac\u00e9. Le processus psychologique a donc cherch\u00e9 \u00e0 faire de la question de l&rsquo;armement des rebelles une \u00ab\u00a0cause\u00a0\u00bb qui correspond&icirc;t aux grandes tendances de cette psychologie, et \u00e0 la politique qui va avec, charg\u00e9e de tous ses principes, de sa morale, etc&hellip; (Ce processus psychologique se d\u00e9cline essentiellement dans le cadre de l&rsquo;<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-l_infraresponsabilit_soumission_psychologique_inconsciente_29_08_2012.html\">infraresponsabilit\u00e9<\/a>, selon la politique de l&rsquo;<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_raison_devenue_idiote_utile_de_l_affectivit__11_06_2012.html\">affectivit\u00e9<\/a>.)<\/p>\n<\/p>\n<p><p>La transmutation de la question technique de l&rsquo;armement des rebelles a d&rsquo;abord subi une transformation par inversion, permettant d&rsquo;\u00e9vacuer la f\u00e2cheuse question : \u00ab\u00a0Pourquoi n&rsquo;intervenez-vous pas en Syrie ?\u00a0\u00bb La r\u00e9ponse vraie impliquerait en effet, selon le jugement des esprits purs qui veillent \u00e0 la dimension morale des exp\u00e9ditions du bloc BAO, 1) un aveu de faiblesse du bloc BAO, en abandonnant le projet \u00ab\u00a0naturel\u00a0\u00bb des principes-Syst\u00e8mes de la modernit\u00e9 avanc\u00e9s comme arguments ; 2) un aveu de soumission par rapport aux positions des r\u00e9gimes russe et chinois, par nature d\u00e9testable et \u00ab\u00a0antimoderne\u00a0\u00bb (en fait antiSyst\u00e8me) ; 3) un aveu de l\u00e2chet\u00e9 puisqu&rsquo;on ne lance pas l&rsquo;attaque en faisant capituler les grands principes devant les r\u00e9alit\u00e9s des rapports de force. L&rsquo;inversion s&rsquo;effectua alors en renversant la raison \u00e9vidente (\u00ab\u00a0Nous livrons des armes parce qu&rsquo;on ne peut envahir la Syrie\u00a0\u00bb) au profit de son contraire (\u00ab\u00a0La livraison d&rsquo;armes fera bien mieux l&rsquo;affaire et sera plus morale qu&rsquo;une invasion en permettant aux seuls Syriens de lib\u00e9rer sans coup f\u00e9rir leur pays du jougs\u00a0\u00bb). Du coup, l&rsquo;armement devenait une \u00ab\u00a0cause\u00a0\u00bb, recevait une sanctification et pouvait devenir le territoire des arguments des psychologies faussaires et malades du bloc BAO ; il devait appara&icirc;tre \u00e0 la fois comme vertueux, comme irr\u00e9sistible, comme repr\u00e9sentatif des \u00ab\u00a0valeurs\u00a0\u00bb du bloc BAO. C&rsquo;est alors que, bien entendu, le symbolisme joue \u00e0 plein et, devenu caricature de symbolisme dans le chef de ceux des pays du bloc BAO qui l&rsquo;instrumentent inconsciemment, devient une sorte de symbolisme inverti, destructeur et paralysant.<\/p>\n<\/p>\n<p><p>D&rsquo;abord, l&rsquo;on en revient aux grandes forces du Syst\u00e8me n\u00e9 du d\u00e9cha&icirc;nement de la Mati\u00e8re, pr\u00e9sent\u00e9es sous forme de mythes incontestables. Dans cette repr\u00e9sentation qui est faite d&rsquo;une importance d\u00e9cisive, sinon presque sacralis\u00e9e, des armes avanc\u00e9es et \u00e0 hautes technologies produites par le bloc BAO, on retrouve l&rsquo;action des deux sous-syst\u00e8mes du Syst\u00e8me. D&rsquo;une part, le syst\u00e8me du technologisme est ici affirm\u00e9 et restaur\u00e9 dans sa pleine puissance, en s&rsquo;exprimant au travers de la vertu et de la puissance d\u00e9vastatrice proclam\u00e9es de ces armes dont on d\u00e9bat de la livraison aux rebelles, jusqu&rsquo;\u00e0 les consid\u00e9rer comme ce facteur de rupture de la situation encore plus efficace qu&rsquo;une intervention en Syrie (selon l&rsquo;interpr\u00e9tation ci-dessus, inversant l&rsquo;appr\u00e9ciation du processus). D&rsquo;autre part, le syst\u00e8me de la communication joue \u00e0 plein, accessoirement sur les appr\u00e9ciations constantes et constamment d\u00e9form\u00e9es de la situation sur le terrain, essentiellement en d\u00e9veloppant dans un arri\u00e8re-plan puissant et essentiel pour la psychologie, des <em>narrative<\/em> telles que cette r\u00e9f\u00e9rence vertueuse au couple <em>Stinger<\/em>\/Afghanistan.<\/p>\n<\/p>\n<p><p>Le r\u00e9sultat \u00e0 ce point est de basculer dans la foi aveugle dans l&rsquo;efficacit\u00e9 des hautes technologies dans l&rsquo;armement, par ailleurs r\u00e9affirm\u00e9e depuis quelques ann\u00e9es avec l&rsquo;usage des drones. (Curieusement, les d\u00e9nonciations et les protestations contre les drone-tueurs sont per\u00e7ues comme confortant cette foi dans l&rsquo;automatisme et l&rsquo;impunit\u00e9 de ces armes, comme signes de leur efficacit\u00e9. C&rsquo;est une r\u00e9action invertie d&rsquo;une psychologie malade, confondant effectivement le bruit et l&rsquo;effet de communication, avec le signe de l&rsquo;efficacit\u00e9 : les d\u00e9nonciations et les protestations contre les drones-tueurs sont au contraire le signe de leur inefficacit\u00e9 et de l&rsquo;\u00e9chec de l&rsquo;automatisme et des valeurs technologiques, puisqu&rsquo;elles sont d\u00e9clench\u00e9es essentiellement par le plus scandaleux, par les \u00ab\u00a0d\u00e9g\u00e2ts collat\u00e9raux\u00a0\u00bb, les identifications rat\u00e9es aboutissant \u00e0 l&rsquo;assassinat de cibles non d\u00e9sign\u00e9es, etc., c&rsquo;est-\u00e0-dire d\u00e9clench\u00e9es par les erreurs de ces machines, donc leur inefficacit\u00e9.) Cette \u00ab\u00a0foi aveugle dans l&rsquo;efficacit\u00e9 des hautes technologies dans l&rsquo;armement\u00a0\u00bb repr\u00e9sente, dans les circonstances qu&rsquo;on consid\u00e8re, et outre l&rsquo;aspect op\u00e9rationnel trompeur, une tentative d&rsquo;affirmer la puissance et la vertu de la modernit\u00e9 du bloc BAO contre des forces per\u00e7ues comme r\u00e9trogrades et vicieuses dans le sens d&rsquo;absence de la vertu de la modernit\u00e9. La puissance et la vertu sont en effet pr\u00e9sentes dans la perception des hautes technologies, qui repr\u00e9sentent aussi bien, dans cette interpr\u00e9tation, le triomphe de la science et du progr\u00e8s et, par cons\u00e9quent, le triomphe de la vertu qui accompagne in\u00e9vitablement la science et le progr\u00e8s. (Les \u00ab\u00a0forces per\u00e7ues comme r\u00e9trogrades et vicieuses\u00a0\u00bb, c&rsquo;est bien s&ucirc;r Assad, mais c&rsquo;est aussi, de plus en plus, les islamistes parmi les rebelles, dont le potentiel de vilenie est en train d&rsquo;acqu\u00e9rir un niveau \u00e9gal \u00e0 celui d&rsquo;Assad.)<\/p>\n<\/p>\n<p><p>Bien entendu, cette foi dans le technologisme, portant sur des armements, porte sur des armements qui rec\u00e8lent par nature, &ndash; directement par la technologie, indirectement par la victoire qu&rsquo;ils sont cens\u00e9s susciter, &ndash; leur transformation en outils de paix par divers processus de transformation une fois l&rsquo;in\u00e9luctable victoire acquise. Il s&rsquo;agit bien de l&rsquo;exhortation d&rsquo;Isa\u00efe (&laquo;<em>Et Il jugera les nations, et Il convaincra d&rsquo;erreur des peuples nombreux; et ils forgeront de leurs glaives des socs de charrue, et de leurs lances des faux<\/em>&raquo;), et l&rsquo;image d&rsquo;autant plus bienvenue qu&rsquo;elle sugg\u00e8re la forme religieuse qui marque ce type d&rsquo;intervention. On notera tout de m\u00eame, accessoirement mais d&rsquo;une fa\u00e7on qui n&rsquo;est pas indiff\u00e9rente, que ces gesticulations autour des armements et dans ce cadre vertueux de la modernit\u00e9 triomphante, permet \u00e9galement de satisfaire avec une \u00e9l\u00e9gante discr\u00e9tion \u00e0 un <em>hubris<\/em> de puissance qui caract\u00e9rise la psychologie du bloc BAO. Cette manifestation de puissance n&rsquo;est pas un facteur politique ni un facteur rationnel ; il s&rsquo;agit d&rsquo;un signe de plus du d\u00e9rangement de la psychologie, et une indication de plus que la politique est bien pass\u00e9e compl\u00e8tement au niveau de l&rsquo;affectivit\u00e9, dans ce cas de la pulsion d&rsquo;affirmation de puissance qui est un des effets de cette psychologie d\u00e9rang\u00e9e.<\/p>\n<\/p>\n<p><p>On doit alors consid\u00e9rer cette fixation devenue d\u00e9sormais obsessionnelle sur la question des armements avanc\u00e9s, non plus comme une simple disposition dans la recherche d&rsquo;un moyen d&rsquo;intervenir en faveur des rebelles, mais comme une v\u00e9ritable exposition de la crise psychologique des directions politiques du bloc BAO, un v\u00e9ritable th\u00e9\u00e2tre si vous voulez des innombrables frustrations, faiblesses et vices de fonctionnement qui accablent nos psychologies. Cela n&rsquo;\u00e9limine pas la rationalisation op\u00e9rationnelle du fait, puisque les conditions de la \u00ab\u00a0guerre syrienne\u00a0\u00bb persistent, mais cela la transforme en figeant la pseudo-politique du bloc BAO sur cet aspect th\u00e9\u00e2tral d&rsquo;exposition de soi-m\u00eame, &ndash; sorte de \u00ab\u00a0spectacle gratuit, il y en aura pour tout le monde\u00a0\u00bb. En tant qu&rsquo;intervention dans la situation politique, cela a pour effet d&rsquo;accentuer jusqu&rsquo;\u00e0 la schizophr\u00e9nie et la paralysie l&rsquo;activit\u00e9 politique du bloc BAO, en interf\u00e9rant jusqu&rsquo;\u00e0 l&rsquo;interdiction sur toutes les possibilit\u00e9s de d\u00e9veloppement, voire de changement politique du bloc BAO, &ndash; ou la politique devenue prisonni\u00e8re de l&rsquo;obsession interpr\u00e9t\u00e9e th\u00e9\u00e2tralement. Litt\u00e9ralement, les dirigeants du bloc BAO ne sont plus capables de raisonner hors de ce sch\u00e9ma de livraison d&rsquo;armes avanc\u00e9es avec le d\u00e9bat qui l&rsquo;accompagne, et la politique syrienne se trouve compl\u00e8tement r\u00e9duite \u00e0 ce d\u00e9bat.<\/p>\n<\/p>\n<p><p>Bien entendu, on n&rsquo;\u00e9chappe pas \u00e0 la conclusion sempiternelle de toutes les actions du bloc BAO, qui sont d&rsquo;\u00eatre d\u00e9velopp\u00e9es selon la crise g\u00e9n\u00e9rale qui affecte le bloc, et d&rsquo;exposer en pleine lumi\u00e8re, d&rsquo;une fa\u00e7on op\u00e9rationnelle, les caract\u00e8res de cette crise. La question des armes ne fait donc que perp\u00e9tuer l&rsquo;\u00e9tat de compl\u00e8te dissolution de la politique du bloc BAO, et sa situation de chose manipul\u00e9e par sa propre crise, et plus que jamais jouet du Syst\u00e8me qui domine et d\u00e9termine toutes les pens\u00e9es (d&rsquo;abord) et toutes les actions du bloc BAO. On observera simplement que la crise syrienne, ou \u00ab\u00a0guerre syrienne\u00a0\u00bb, est en v\u00e9rit\u00e9 un territoire privil\u00e9gi\u00e9 pour cela. Par sa dur\u00e9e, par sa r\u00e9sistance aux pressions du Syst\u00e8me via le bloc BAO, elle expose et ne cesse d&rsquo;aggraver l&rsquo;\u00e9tat de dissolution du bloc et d&rsquo;acc\u00e9l\u00e9rer la r\u00e9duction de sa politique \u00e0 une d\u00e9rive folle soumise d&rsquo;une part, elle-m\u00eame, aux pressions du Syst\u00e8me, d&rsquo;autre part aux cons\u00e9quences chaotiques d&rsquo;une pens\u00e9e r\u00e9duite \u00e0 l&rsquo;affectivit\u00e9, par cons\u00e9quent aux influences de forces ext\u00e9rieures comme le syst\u00e8me du technologisme, autant qu&rsquo;aux illusions dispens\u00e9es par les <em>narrative<\/em> du syst\u00e8me de la communication. Aujourd&rsquo;hui, le front principal de la \u00ab\u00a0guerre syrienne\u00a0\u00bb est donc celui de la poursuite vertigineuse de la dissolution de l&rsquo;intelligence des pays du bloc BAO. C&rsquo;est une guerre-\u00e9clair et sans fin, au moins jusqu&rsquo;\u00e0 plus-soif&#8230;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le mythe du glaive 3 avril 2013 &ndash; Il y a une citation c\u00e9l\u00e8bre du Livre d&rsquo;Isa\u00efe, qui doit certainement inspirer nos psychologies enfi\u00e9vr\u00e9es et nos esprits r\u00e9duits \u00e0 l&rsquo;affect&hellip; &laquo;Et Il jugera les nations, et Il convaincra d&rsquo;erreur des peuples nombreux; et ils forgeront de leurs glaives des socs de charrue, et de leurs&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3236,3124,3015,2631,2622,8296,4321,6767,9863,4429,3867,3014,4268],"class_list":["post-74917","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-afghanistan","tag-armement","tag-communication","tag-de","tag-la","tag-mythe","tag-narrative","tag-obsession","tag-rebellion","tag-stinger","tag-syrie","tag-systeme","tag-technologisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74917"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74917\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}