{"id":74919,"date":"2013-04-04T15:01:41","date_gmt":"2013-04-04T15:01:41","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/04\/04\/legypte-autre-champ-de-lagression-douce-us\/"},"modified":"2013-04-04T15:01:41","modified_gmt":"2013-04-04T15:01:41","slug":"legypte-autre-champ-de-lagression-douce-us","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/04\/04\/legypte-autre-champ-de-lagression-douce-us\/","title":{"rendered":"L&rsquo;\u00c9gypte, autre champ de l&rsquo;\u201cagression douce\u201d US"},"content":{"rendered":"<p><h3 class=\"titrebloc\">L&rsquo;\u00c9gypte, autre champ de l&rsquo;agression douce US<\/h3>\n<\/p>\n<p><p>\tLe sort du comique satirique \u00e9gyptien Youssef \u00e9claire l&rsquo;\u00e9tat des relations entre les USA et l&rsquo;\u00c9gypte, et, surtout, sugg\u00e8re que l&rsquo;\u00c9gypte est devenue, avec la Russie, l&rsquo;un des champs privil\u00e9gi\u00e9s de cette activit\u00e9 que nous d\u00e9signons comme l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-l_lection_de_poutine_en_perspective_12_03_2012.html\" class=\"gen\">agression<\/a> <a href=\"http:\/\/www.dedefensa.org\/article-la_guerre_nouvelle_est_d_clar_e_et_elle_est_totale_14_03_2012.html\" class=\"gen\">douce<\/a> de la part des USA. (Dans ce cas, on pourrait dire que, toutes proportions gard\u00e9es, notamment pour l&rsquo;\u00e9cho du syst\u00e8mle de la communication, Youssef tient, pour l&rsquo;\u00c9gypte vis-\u00e0-vis des USA, le r\u00f4le des <em>Pussy Riot<\/em> pour la Russie vis-\u00e0-vis des USA.) <\/p>\n<\/p>\n<p><p>\t<em>Antiwar.com<\/em> donne le <a href=\"\/%E2%80%AAhttp:\/\/news.antiwar.com\/2013\/04\/02\/egypt-govt-slams-us-meddling-in-internal-affairs\/%E2%80%AC\" class=\"gen\">3 avril 2013<\/a>, un rapide compte-rendu, avec quelques liens utiles, sur l&rsquo;\u00e9tat de cette tension entre les deux pays, c&rsquo;est-\u00e0-dire entre le pouvoir des Fr\u00e8res Musulmans (Morsi) et la strat\u00e9gie de communication des USA : \u00ab<em>Tensions between the Obama Administration and Egypt&rsquo;s ruling Freedom and Justice Party (FJP) seem to be on the rise today, after the FJP issued a statement condemning the US State Department, accusing them of meddling in internal matters by criticizing the Youssef case.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t <em>Russia Today<\/em> d\u00e9veloppe plus en d\u00e9tails le cas, le <a href=\"http:\/\/rt.com\/news\/islamists-egypt-us-interference-247\/\" class=\"gen\">3 avril 2013<\/a>. Il d\u00e9crit notamment l&rsquo;attitude des USA dans cette affaire et la r\u00e9action des Fr\u00e8res Musulmans parlant en leur nom, ce qui permet d&rsquo;interpr\u00e9ter cela comme une r\u00e9action officieuse de Morsi sans que le pr\u00e9sident \u00e9gyptien soit personnellement et explicitement impliqu\u00e9 dans cette passe d&rsquo;armes. (A noter que le seul \u00e0 garder son calme et \u00e0 prendre la chose avec philosophie est Youssef lui-m\u00eame : \u00ab<em>Going to jail is a risk that we have to go through, he told CNN. But you know, with big shows and big programs comes creative responsibility and maybe bigger risks. So I think we just have to accept that this could happen any time.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Bassem Youssef, who is known as Egypt&rsquo;s Jon Stewart, was detained and grilled in court for five hours on Sunday. He was released on a $2,200 bail. The comic was arrested after Egypt&rsquo;s investment authority received complaints about Youssef&rsquo;s show, including mockery of state symbols and prominent personalities and sexually suggestive language, state-run Ahram Gate reported.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The move prompted the US Department of State spokeswoman Victoria Nuland, to criticize the decision saying it raised concerns about the Egyptian government&rsquo;s commitment to basic freedoms. This coupled with recent arrest warrants issued for other political activists is evidence of a disturbing trend of growing restrictions on the freedom of expression, she said at the State Department&rsquo;s daily press briefing on Monday. So there does not seem to be an evenhanded application of justice here. Nuland added that Egyptian authorities seemed selective in their prosecution, accusing them of cracking down on offenders such as Youssef, while ignoring or playing down attacks on anti-government protesters and cases of extreme police brutality.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t\u00bb<em>The Justice and Freedom Party, the political wing of the Muslim Brotherhood, condemned the comments and said the government was committed to freedom of expression. Nuland&rsquo;s statements are&#8230;blatantly interfering in Egypt&rsquo;s internal affairs, a party statement said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit d&rsquo;une nouvelle passe d&rsquo;armes entre les USA et l&rsquo;\u00c9gypte, la premi\u00e8re de cette sorte ayant eu lieu \u00e0 la fin 2011-d\u00e9but 2012 avec l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-les_militaires_gyptiens_contre_washington_pour_leur_sauvegarde__08_02_2012.html\" class=\"gen\">affaire des ONG<\/a> pseudo-\u00e9gyptiennes qui opposa les USA et le pouvoir militaire. D\u00e9j\u00e0, il s&rsquo;agissait d&rsquo;ing\u00e9rence US au nom des habituels refrains (d\u00e9mocratie, droits de l&rsquo;homme, libert\u00e9 de parole, etc., dont les USA constituent une r\u00e9f\u00e9rence in\u00e9galable), avec financement US de certaines ONG \u00e9gyptiennes dont l&rsquo;activisme pouvait \u00eatre jug\u00e9 d\u00e9stabilisant par le pouvoir. Les militaires avaient r\u00e9agi en d\u00e9non\u00e7ant l&rsquo;ing\u00e9rence US et l&rsquo;affaire avait largement interf\u00e9r\u00e9 sur les relations entre les deux pays (m\u00eame si les militaires avaient c\u00e9d\u00e9 du terrain, finalement). Cette fois, il s&rsquo;agit de Morsi et des Fr\u00e8res Musulmans, que BHO a choisi de soutenir malgr\u00e9 divers avatars. Pourtant, il y a cette interf\u00e9rence, semblable \u00e0 quelques autres, mais celle-l\u00e0 particuli\u00e8rement stridente et sonore. La protestation de Fr\u00e8res Musulmans refl\u00e8te nettement le sentiment de Morsi et est prise effectivement comme une r\u00e9action du pr\u00e9sident.<\/p>\n<\/p>\n<p><p>\tCe qui est tr\u00e8s remarquable, c&rsquo;est que les USA agissent de cette fa\u00e7on alors qu&rsquo;ils ont choisi de soutenir Morsi, malgr\u00e9 ce qu&rsquo;ils peuvent lui reprocher, et malgr\u00e9 sa situation tr\u00e8s faible, comme un pis-aller certes mais essentiel parce qu&rsquo;il y a la n\u00e9cessit\u00e9 strat\u00e9gique de garder des liens avec l&rsquo;\u00c9gypte et d&rsquo;\u00e9viter que ce pays sombre dans le d\u00e9sordre. Le r\u00e9sultat net est que, dans cette circonstance, ils affaiblissent Morsi, non au profit de quelque opposition organis\u00e9e qu&rsquo;ils pourraient choisi de soutenir, mais simplement un profit d&rsquo;un d\u00e9sordre plus grand encore. Une autre cons\u00e9quence est que cette intervention devrait nourrir les sentiments antiam\u00e9ricanistes ici et l\u00e0, qui sont prompts \u00e0 s&rsquo;enflammer dans des situations de faiblesse du pouvoir et de d\u00e9sordre. Mais, comme l&rsquo;on sait, cet \u00e9trange agissement politique, qui refl\u00e8te d&rsquo;ailleurs assez bien l&rsquo;ind\u00e9cision d\u00e9sormais proverbiale d&rsquo;Obama, est de toutes les fa\u00e7ons le produit d&rsquo;un processus bureaucratique, notamment au d\u00e9partement d&rsquo;\u00c9tat ; c&rsquo;est aussi la production d&rsquo;un ph\u00e9nom\u00e8ne que nous d\u00e9signons l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-l_infraresponsabilit_soumission_psychologique_inconsciente_29_08_2012.html\" class=\"gen\">infraresponsabilit\u00e9<\/a> (1), dont certains des attendus sont souvent \u00e9nonc\u00e9s, d&rsquo;une fa\u00e7on peu consciente sinon inconsciente quant aux implications, par les acteurs eux-m\u00eames (voir le <a href=\"http:\/\/www.dedefensa.org\/article-mcfaul_ambassadeur-syst_me_moscou_15_06_2012.html\" class=\"gen\">15 juin 2012<\/a>, sur l&rsquo;ambassadeur des USA \u00e0 Moscou, McFaul).<\/p>\n<\/p>\n<p><p>\tLe point le plus \u00e9tonnant de ces circonstances est que le processus ainsi d\u00e9crit affecte essentiellement deux des pays (la Russie et l&rsquo;\u00c9gypte) qui devraient \u00eatre les plus importants pour les USA, et dont les relations avec les USA sont les plus d\u00e9licates et souvent proches d&rsquo;un r\u00e9el antagonisme. En ce sens, on pourrait ais\u00e9ment conclure que l&rsquo;agression douce, qui fait \u00e9videmment partie des impulsions o\u00f9 le Syst\u00e8me joue un r\u00f4le particuli\u00e8rement important, participe d&rsquo;une fa\u00e7on affirm\u00e9e \u00e0 la phase d&rsquo;autodestruction du Syst\u00e8me puisque le r\u00e9sultat net est de compromettre des relations tr\u00e8s importantes pour la politique am\u00e9ricaniste, qui n&rsquo;est \u00e9videmment qu&rsquo;un succ\u00e9dan\u00e9 de la <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_la_politique-syst_me__17_11_2012.html\" class=\"gen\">politique-Syst\u00e8me<\/a>. Il y a dans tout cela une grande logique qui renvoie aux agitations et aux d\u00e9veloppements du Syst\u00e8me<\/p>\n<\/p>\n<p><p>\t On observera, selon un lien certes indirect mais ressortant du m\u00eame domaine qui nous importe, que le Qatar, autre pays de la m\u00eame bande accoquin\u00e9e au bloc BAO et m\u00eame le plus extr\u00e9miste d&rsquo;entre tous, se trouve confront\u00e9 \u00e0 des difficult\u00e9s en \u00c9gypte tenant \u00e9galement \u00e0 des interf\u00e9rences dans la situation du pays, sous une autre forme. L\u00e0 aussi, on retrouve un m\u00e9lange paradoxal renvoyant \u00e0 la situation de l&rsquo;\u00e9quation surpuissance-autodestruction du Syst\u00e8me, les avatars du Qatar \u00e9tant dus \u00e0 sa puissance m\u00eame, \u00e0 sa politique tr\u00e8s active (sinon activiste, dans tous les cas pour ce qui est de l&rsquo;Egypte), mais bien entendu men\u00e9e \u00e0 coups de $milliards et faisant fi d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale des principes structurants de la l\u00e9gitimit\u00e9 et de la souverainet\u00e9,  situation assez normale m\u00eame si paradoxale, apr\u00e8s tout, puisque le Qatar est aussi ignorant de tels principes dans leur manifestation chez les autres comme chez lui que le sont les USA Voici donc comment Roula Khalaf, dans le <em>Financial Times<\/em>, nous pr\u00e9sente la chose, le <a href=\"http:\/\/www.ft.com\/intl\/cms\/s\/0\/5235ca36-9adf-11e2-b982-00144feabdc0.html#axzz2PE0INSBM\" class=\"gen\">1er avril 2013<\/a>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Qatar&rsquo;s Hamad bin Jassim al-Thani was visibly frustrated when asked about the Gulf state&rsquo;s involvement in Egypt at the concluding press conference of the Arab League summit. No, Doha is not buying the Suez Canal, he declared. Nor is it leasing the Pyramids, he added, dismissing rumours of Qatari intentions swirling in Cairo&rsquo;s media. And no, Qatar is not taking sides between Islamists and liberals, the prime minister claimed, pointing out that his country gave $2bn in aid to Egypt when the military ruled and before the election of Mohamed Morsi, the Muslim Brotherhood leader.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>That the Qatari prime minister had to answer last week for his backing for Egypt is just one of the signs of the massive backlash against the Gulf state. As Sheikh Hamad recognised: We are now blamed for anything that happens in Egypt.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Riding the Islamist wave in the region makes political sense for a small country with huge ambitions and the need to secure its future. But as Qatar is discovering, becoming a party in domestic political struggles is a risky business, more hazardous than Doha had bargained for<\/em>\u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 4 avril 2013 \u00e0 15H02<\/p>\n<h4>Addendum<\/h4>\n<p>(1) Voir aussi notre texte mis en ligne apr\u00e8s la parution de cet article, le <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_infraresponsabilit__06_04_2013.html\" class=\"gen\">6 avril 2013<\/a>.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00c9gypte, autre champ de l&rsquo;agression douce US Le sort du comique satirique \u00e9gyptien Youssef \u00e9claire l&rsquo;\u00e9tat des relations entre les USA et l&rsquo;\u00c9gypte, et, surtout, sugg\u00e8re que l&rsquo;\u00c9gypte est devenue, avec la Russie, l&rsquo;un des champs privil\u00e9gi\u00e9s de cette activit\u00e9 que nous d\u00e9signons comme l&rsquo;agression douce de la part des USA. (Dans ce cas, on&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[11897,11898,9550,11025,8480,11981,7611,4859,2730,12055,12054],"class_list":["post-74919","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-agression","tag-douce","tag-egypte","tag-freres","tag-mcfaul","tag-morsi","tag-musulman","tag-qatar","tag-russie","tag-surpuissance-autodestruction","tag-youssef"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74919"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74919\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}