{"id":74949,"date":"2013-04-25T06:12:27","date_gmt":"2013-04-25T06:12:27","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/04\/25\/une-affaire-qui-marche-le-goulag-us\/"},"modified":"2013-04-25T06:12:27","modified_gmt":"2013-04-25T06:12:27","slug":"une-affaire-qui-marche-le-goulag-us","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/04\/25\/une-affaire-qui-marche-le-goulag-us\/","title":{"rendered":"Une affaire qui marche : le <em>Goulag<\/em> US"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Une affaire qui marche : le <em>Goulag<\/em> US<\/h3>\n<\/p>\n<p><p>\tL&rsquo;ensemble p\u00e9nitentiaire US s&rsquo;est lentement transform\u00e9, depuis le d\u00e9but des ann\u00e9es 1970, en un <em>Prison Industrial Complex<\/em> (PIC) qui s&rsquo;av\u00e8re \u00eatre une des plus \u00e9tonnantes trouvailles du Syst\u00e8me dans la recherche d&rsquo;une activit\u00e9 <strong>\u00e0 la fois<\/strong> industrielle et g\u00e9nocidaire,  faisant passer au second plan les probl\u00e9matiques de la justice et de la d\u00e9linquance qui, d&rsquo;ordinaire, d\u00e9finissent la question des prisons. L&rsquo;\u00e9tablissement du <a href=\"http:\/\/en.wikipedia.org\/wiki\/Prisonindustrial_complex\" class=\"gen\">PIC<\/a> est en g\u00e9n\u00e9ral dat\u00e9 de 1973, avec une loi de l&rsquo;Etat de New York pass\u00e9e par le gouverneur Nelson Rockefeller, rendant passible de prison tout d\u00e9tenteur et utilisateur de drogue. Depuis, les peines pour ces d\u00e9lits, jusqu&rsquo;aux plus ridiculement mineurs, n&rsquo;ont cess\u00e9 de s&rsquo;alourdir, mettant en \u00e9vidence la participation active \u00e0 l&rsquo;entreprise du syst\u00e8me l\u00e9gislatif et du syst\u00e8me judiciaire US.<\/p>\n<\/p>\n<p><p>\tL&rsquo;analyste politique et photographe Nile Bowie, collaborateur de <em>Russia Today<\/em>, publie ce <a href=\"http:\/\/rt.com\/op-edge\/moral-monstrosity-american-gulag-258\/\" class=\"gen\">23 avril 2013<\/a> un article sur \u00ab[A] <em>Moral monstruosity : America&rsquo;s for profit Gulag system<\/em>\u00bb Il y d\u00e9crit les conditions de d\u00e9veloppement, de fonctionnement et d&rsquo;existence du PIC, dont la population a augment\u00e9 de 772% entre 1970 et 2009, et dont la part du priv\u00e9 a \u00e9t\u00e9 multipli\u00e9e par 17 durant les deux derni\u00e8res d\u00e9cades. Le PIC est effectivement devenu une part int\u00e9grante du Syst\u00e8me, notamment dans sa division \u00e9conomique, comme un effet presque naturel et \u00e9vident de la doctrine capitaliste d\u00e9velopp\u00e9e dans les conditions du Syst\u00e8me. Actuellement, la population carc\u00e9rale aux USA approche les 25% de la population carc\u00e9rale mondiale, alors que la population US se situe entre 4% et 5% de la population mondiale. (D&rsquo;une fa\u00e7on qu&rsquo;on devrait juger assez significative de l&rsquo;implication du syst\u00e8me capitaliste, et dans tous les cas certainement symbolique, ce rapport 4%\/5% <em>versus<\/em> pr\u00e8s de 25% est \u00e9galement celui du pourcentage de la population US par rapport au pourcentage d&rsquo;\u00e9mission de CO2 pour l&rsquo;activit\u00e9 industrielle par les USA.)<\/p>\n<\/p>\n<p><p>\tL&#8217;emploi du terme <em>Goulag<\/em> (ou GOULAG, puisqu&rsquo;il s&rsquo;agit d&rsquo;un acronyme russe) pour qualifier le syst\u00e8me p\u00e9nitentiaire US appara\u00eet en g\u00e9n\u00e9ral assez d\u00e9licat. Pourtant, la description du PIC tel qu&rsquo;il est aujourd&rsquo;hui \u00e9carte les derni\u00e8res r\u00e9ticences : il s&rsquo;agit bien d&rsquo;un syst\u00e8me de <em>Goulag<\/em>, puisque son op\u00e9rationnalit\u00e9 permet l&rsquo;usage d&rsquo;une main d&rsquo;uvre \u00e0 si bon march\u00e9 qu&rsquo;on peut la consid\u00e9rer comme quasiment gratuite, tandis qu&rsquo;elle neutralise et \u00e9limine des cat\u00e9gories tr\u00e8s pr\u00e9cises d&rsquo;individus dont le Syst\u00e8me se m\u00e9fie.<\/p>\n<\/p>\n<p><p>\tDurant ces ces quelques d\u00e9cennies depuis l&rsquo;institution du PIC, la population carc\u00e9rale a \u00e9t\u00e9 de plus en plus aliment\u00e9e par trois grands courants sociaux et ethniques : la population d\u00e9pendante de la drogue sous tous ses aspects, jusqu&rsquo;aux cas les plus mineurs ; la population des immigrants clandestins captur\u00e9s essentiellement \u00e0 la fronti\u00e8re entre les USA et le Mexique ; la population des minorit\u00e9s ethniques, essentiellement les Africains Am\u00e9ricains. (Bien entendu, les diverses cat\u00e9gories de d\u00e9viants du Syst\u00e8me, comme les prisonniers politiques sous la forme de contestataires divers, sont inclus dans ces courants.) L&rsquo;auteur compare le syst\u00e8me actuel des prisons au syst\u00e8me de prisons, \u00e9galement priv\u00e9, qui fut mis en place aux USA apr\u00e8s l&rsquo;abolition de l&rsquo;esclavage, de la Guerre de S\u00e9cession jusqu&rsquo;au d\u00e9but du XX\u00e8me si\u00e8cle, et d&rsquo;ailleurs nullement cantonn\u00e9 \u00e0 une seule r\u00e9gion du pays, pour regrouper des populations fournissant de la main d&rsquo;uvre \u00e0 bon march\u00e9, sinon \u00e0 co\u00fbt quasiment nul, pour le travail traditionnel de la cueillette de coton, mais aussi pour les travaux d&rsquo;infrastructure de modernisation (routes, chemins de fer, etc.). Ce syst\u00e8me est ainsi reproduit aujourd&rsquo;hui, avec la privatisation maximale, les travailleurs-esclaves recevant des sommes ridicules sinon symboliques et les entreprises priv\u00e9es g\u00e9rant les prisons (il y en a trois principalement, CCA, GEO Group, Cornell) sous-traitant des travaux divers pour l&rsquo;ext\u00e9rieur. Ce syst\u00e8me rassemble tous les attributs habituels du capitalisme am\u00e9ricaniste, notamment une organisation de corruption maximale du monde politique avec une organisation tr\u00e8s puissante de lobbying, pour obtenir certaines lois favorisant les activit\u00e9s rentables du complexe, aussi bien que des lois qui favorisent directement (s\u00e9v\u00e9rit\u00e9 des peines) et indirectement le recrutement des populations carc\u00e9rales. Dans ce dernier cas, par exemple, les lobbies du complexe luttent avec acharnement contre la d\u00e9p\u00e9nalisation de la marijuana, la consommation de cette drogue mineure fournissant un nombre appr\u00e9ciable de travailleurs-esclaves.<\/p>\n<\/p>\n<p><p>\tDans tous les cas envisag\u00e9s, les peines sont extr\u00eamement lourdes, de fa\u00e7on \u00e0 obtenir une stabilit\u00e9 de la main d&rsquo;uvre. Les prisonniers vivent dans des conditions de plus en plus d\u00e9grad\u00e9es, parfois dans des conditions stup\u00e9fiantes de promiscuit\u00e9 dans des immenses hangars organis\u00e9s en dortoir, puisque les entreprises priv\u00e9es ne cessent de restreindre les budgets d&rsquo;entretien et que les quelques interventions publiques sont restreintes \u00e0 cause de la crise. Bien entendu, tout cela se passe dans un climat de contrainte et de violence internes constant, qui favorise indirectement la soumission des prisonniers. Lorsqu&rsquo;ils sont lib\u00e9r\u00e9s, puisque la chose arrive, les prisonniers sont le plus souvent priv\u00e9s de leurs droits civiques et d&rsquo;acc\u00e8s aux services sociaux et au march\u00e9 du travail, ce qui fait que le complexe esp\u00e8re les r\u00e9cup\u00e9rer rapidement sous la forme de l&rsquo;un ou l&rsquo;autre d\u00e9lit de survie aussit\u00f4t transform\u00e9 en une peine de prison maximale (r\u00e9cidive). Ainsi le syst\u00e8me est-il complet, avec comme premier incitatif le profit. Enfin, toutes ces conditions excluent toute vie sociale et familiale des d\u00e9tenus ; elles suscitent une d\u00e9gradation rapide de leur \u00e9tat de sant\u00e9 au sens le plus large avec des soins m\u00e9dicaux r\u00e9duits au minimum, si bien qu&rsquo;on peut consid\u00e9rer qu&rsquo;il s&rsquo;agit \u00e9galement d&rsquo;une entreprise d&rsquo;\u00e9limination douce (!) de type g\u00e9nocidaire, portant sur des populations dont le Syst\u00e8me en g\u00e9n\u00e9ral ne veut pas. Le circuit est ainsi boucl\u00e9 et la capitalisme, parvenant \u00e0 son essence la plus intime, rejoint compl\u00e8tement les caract\u00e8res g\u00e9n\u00e9raux du <em>Goulag<\/em> stalinien.<\/p>\n<\/p>\n<p><p>\tVoici un extrait important du texte de Nile Bowie, de ce <a href=\"http:\/\/rt.com\/op-edge\/moral-monstrosity-american-gulag-258\/\" class=\"gen\">23 avril 2013<\/a>, dont l&rsquo;int\u00e9r\u00eat est de d\u00e9velopper la description des conditions de l&rsquo;action du complexe pour assurer sa position de puissance au sein du Syst\u00e8me, notamment dans le monde politique US.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The number of people imprisoned under state and federal custody increased 772% percent between 1970 and 2009, largely due to the incredible influence that private corrections corporations wield against the American legal system. The argument is that by subjecting correctional services to market pressures, efficiencies will be increased and prison facilities can be run at a lower cost due to market competition. What these privatizations produce in turn is a system that destroys families by incentivizing the mass long-term detention of non-violent criminals, a system that is increasingly difficult to deconstruct and reform due to millions paid out to state and federal policymakers. According to reports issued by advocacy group Public Campaign, the three major corrections firms Corrections Corporation of America (CCA), the GEO Group, and Cornell, have spent over $22 million lobbying Congress since 2001.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>As a means of influencing policymaking at the federal level, at least $3.3 million have been given to political parties, candidates, and their political action committees, while more than $7.3 million has been given to state candidates and political parties since 2001, including $1.9 million in 2010, the highest amount in the past decade. Senators like Lindsay Graham and John McCain have received significant sums from the private prison corporations while Chuck Schumer, Chair of the Rules Committee on Immigration and Border Enforcement, received at least $64,000 from lobbyists. The prison lobby thrives off of laws that criminalize migrants and submit them to mandatory detention prior to being deported, sometimes up to 10 months or more; private firms have consistently pushed for the classification of immigration violations as felonies to justify throwing more and more immigrants behind bars. The number of illegal immigrants being incarcerated inside the United States has risen exponentially under Immigration and Customs Enforcement, an agency responsible for annually overseeing the imprisonment of 400,000 foreign nationals at the cost of over $1.9 billion on custody-related operations.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The private prison industry has become increasingly dependent on immigration-detention contracts, and the huge contributions of the prison lobby towards drafting Arizona&rsquo;s controversial immigration law SB 1070 are all but unexpected. Arizona&rsquo;s SB 1070 requires police to determine the immigration status of someone arrested or detained when there is reasonable suspicion that they&rsquo;ve illegally entered the US, which many view as an invitation for rampant racial profiling against non-whites. While the administration of Arizona&rsquo;s Governor Jan Brewer is lined with former private prison lobbyists, its Department of Corrections budget has been raised by $10 million in 2012, while all other Arizona state agencies were subject to budget cuts during that fiscal year. The concept of privatizing prisons to reduce expenses comes at great cost to the inmates detained, who are subjected to living in increasingly squalid conditions in jail cells across America. In 2007, the Texas Youth Commission (TYC), a state agency that overseas juvenile corrections facilities, was sent to a West Texas juvenile prison run by GEO Group for the purpose of monitoring its quality standards.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The monitors sent by the TYC were subsequently fired for failing to report the sordid conditions they witnessed in the facility while they awarded the GEO Group with an overall compliance score of nearly 100% &#8211; it was later discovered that the TYC monitors were employed by the GEO Group. Independent auditors later visited the facility and discovered that inmates were forced to urinate or defecate in small containers due to a lack of toilets in some of the cells. The independent commission also noted in their list of reported findings that the facility racially segregated prisoners and denied inmates access to lawyers and medical treatment. The ACLU and Southern Poverty Law Center have also highlighted several cases where GEO Group facility administrators turned a blind eye to brutal cases of rape and torture within their facilities, in addition to cases of its staff engaging in violence against inmates. According to the Justice Department data, nearly 210,000 prisoners are abused annually (prison personnel are found responsible half the time), while 4.5 percent of all inmates reported sexual assaults and rape.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>It&rsquo;s not possible to conceive how such institutionalized repression can be rolled back when the Obama administration shows only complicity with the status quo  a staggering $18 billion was spent by his administration on immigration enforcement, including detention, more than all other federal law enforcement agencies combined. Under Obama&rsquo;s watch, today&rsquo;s private prison population is over 17 times larger than the figure two decades earlier. Accordingly, Obama&rsquo;s drug czar, Gil Kerlikowske, has condemned the recently passed state laws in Colorado and Washington that legalize the possession of marijuana in small amounts. The Obama administration is bent on keeping in place the current federal legislation, where a first-time offender caught with marijuana can be thrown in prison for a year. It&rsquo;s easy to see why common-sense decriminalization is stifled &#8211; an annual report released by the CCA in 2010 reiterates the importance of keeping in place harsh sentencing standards, The demand for our facilities and services could be adversely affected by the relaxation of enforcement efforts, leniency in conviction or parole standards and sentencing practices or through the decriminalization of certain activities that are currently proscribed by our criminal laws. For instance, any changes with respect to drugs and controlled substances or illegal immigration could affect the number of persons arrested, convicted, and sentenced, thereby potentially reducing demand for correctional facilities to house them.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Such is the nature of a perverted brand of capitalism, and today&rsquo;s model bares little difference to the first private prisons introduced following the abolishment of slavery in the late 1800s, where expansive prison farms replaced slave plantations where predominately African-American inmates were made to pick cotton and construct railroads in states such as Alabama, Georgia and Mississippi. Today, African-Americans make up 40% of the prison population and are incarcerated seven times more often than whites, despite the fact that African-Americans make up only 12% of the population. Inmates are barred from voting in elections after their release and are denied educational and job opportunities. The disproportionate levels of black people in prisons is undeniably linked to law enforcement&rsquo;s targeting of intercity black communities through anti-drug stipulations that command maximum sentencing for possession of minute amounts of rock cocaine, a substance that floods poor black neighborhoods.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Perhaps these social ills are byproducts of a system that places predatory profits before human dignity. Compounding the illogic is that state spending on prisons has risen at six times the rate of spending on higher education over the past two decades. Mumia Abu-Jamal, America&rsquo;s most famous political prisoner, has spent over three decades on death row; he was convicted in 1981 for the murder of a white police officer, while forensic experts say critical evidence vindicating Jamal was withheld from the trial. In an interview with RT, Jamal relates his youth activism with the Black Panthers party against political imprisonment in contrast to the present day situation, We could not perceive back then of what it would become you can literally talk about millions of people incarcerated by the prisoner-industrial complex today: men, women and children. And that level of mass incarceration, really mass repression, has to have an immense impact in effect on the other communities, not just among families, but in a social and communal consciousness way, and in inculcation of fear among generations. The fear and immortality the system perpetuates shows no sign of abating. Being one of the few growth industries the United States has left, one can only imagine how many people will be living in cages in the decades to come.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCe qui est remarquable dans cette description du complexe, c&rsquo;est la fa\u00e7on structurelle d\u00e9crite d&rsquo;une organisation syst\u00e9matique, tr\u00e8s rentabilis\u00e9e, tr\u00e8s bien contr\u00f4l\u00e9e, qui d\u00e9passe tr\u00e8s largement en efficacit\u00e9 et en rentabilit\u00e9 le syst\u00e8me stalinien (<em>Goulag<\/em>). On rejoint alors des consid\u00e9rations beaucoup plus larges, qui doivent alimenter la r\u00e9flexion sur la nature profonde d&rsquo;un Syst\u00e8me qui g\u00e9n\u00e8re, presque naturellement, presque de lui-m\u00eame, de tels ensembles dont les moyens de fonctionnement sont l&rsquo;esclavagisme (dans des conditions pires que l&rsquo;esclavage originel), la d\u00e9shumanisation et la destruction psychologique, l&rsquo;extermination organis\u00e9e, collectivis\u00e9e d&rsquo;une fa\u00e7on rampante et indirecte. Gr\u00e2ce aux conditions de communication du Syst\u00e8me, ces ensembles ont la caract\u00e9ristique d&rsquo;\u00eatre pr\u00e9sent\u00e9es et per\u00e7ues (sup\u00e9riorit\u00e9 indiscutable sur les dictatures d&rsquo;extermination) comme de bien public et de participation efficace \u00e0 la protection normale de la loi et de l&rsquo;ordre d\u00e9mocratiques. L&rsquo;effet de ces ph\u00e9nom\u00e8nes rejoint la production naturelle du Syst\u00e8me comme \u00e9l\u00e9ment repr\u00e9sentant le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_source_de_tous_les_maux_ddecrisis_10_09_2010.html\" class=\"gen\">pire de tous les maux<\/a>, ou le Mal parvenu \u00e0 un \u00e9tat de fonctionnement maximal et exclusif ; il s&rsquo;agit de la production maximale de d\u00e9structuration, de dissolution et d&rsquo;entropisation, dans ce cas de la soci\u00e9t\u00e9 et de populations diverses.<\/p>\n<\/p>\n<p><p>\tIl faut noter que certains auteurs ont \u00e9galement rapproch\u00e9 le fonctionnement du syst\u00e8me nazi g\u00e9rant, organisant et d\u00e9veloppant le syst\u00e8me d&rsquo;extermination (Holocauste), de la r\u00e9f\u00e9rence du capitalisme am\u00e9ricaniste (pour nous, produit du Syst\u00e8me), avec sa branche bureaucratique et sa branche de productivit\u00e9 et de rentabilit\u00e9. Ainsi en ont-ils fait un produit direct de la modernit\u00e9, ce qui correspond assez justement au jugement naturel qui nous vient sous la plume. Le <a href=\"http:\/\/www.dedefensa.org\/article-peut-on_dire_cia_s_gulag__07_12_2005.htmlW\" class=\"gen\">7 d\u00e9cembre 2005<\/a>, parlant alors du seul syst\u00e8me de prisonniers de la CIA dans la Guerre contre la Terreur, nous \u00e9crivions ceci, qui citait un de ces principaux auteurs, le professeur Richard L. Rubenstein :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Pour ce qui concerne le syst\u00e8me nazi, qui pr\u00e9sente un autre cas, il faut lire La perfidie de l&rsquo;Histoire, de Richard L. Rubenstein (n\u00e9 en 1924, professeur d&rsquo;histoire et de philosophie des religions \u00e0 l&rsquo;universit\u00e9 de Bridgeport, dans le Connecticut). Ce livre, publi\u00e9 en 2005 (\u00e9ditions Le Cerf), comprend le texte original de Rubenstein, datant de 1975 (avec un ajout de circonstances, datant de 2004, traitant du terrorisme islamique). L&rsquo;originalit\u00e9 de l&rsquo;approche de Rubenstein est qu&rsquo;il fait porter l&rsquo;essentiel de la responsabilit\u00e9 de l&rsquo;Holocauste dans son ampleur et dans la r\u00e9alisation de son aspect syst\u00e9matique non sur l&rsquo;id\u00e9ologie, qui est l&rsquo;\u00e9l\u00e9ment d\u00e9clencheur, mais sur la bureaucratisation et les m\u00e9thodes industrielles modernes de gestion et de production. C&rsquo;est introduire comme principal accus\u00e9 de l&rsquo;ampleur et de la substance du crime les m\u00e9thodes et les contraintes modernistes au travers de l&rsquo;expansion et de la gestion industrielles, et de la bureaucratisation syst\u00e9mique.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>La caract\u00e9ristique finale est un montage syst\u00e9mique s&rsquo;apparentant moins \u00e0 un complot qu&rsquo;\u00e0 l&rsquo;\u00e9volution naturelle (c&rsquo;est-\u00e0-dire logique dans ce cas, de la logique interne du syst\u00e8me) d&rsquo;un syst\u00e8me de conception moderniste \u00e0 la fois de cloisonnement et de dilution de la perception des responsabilit\u00e9s. L&rsquo;effet m\u00e9canique du montage est de cacher l&rsquo;ampleur et le motif du crime aux ex\u00e9cutants, et d&rsquo;assurer son efficacit\u00e9 compl\u00e8te sans prendre le risque de l&rsquo;ill\u00e9galit\u00e9 qui constitue une transgression des lois difficilement supportable pour un esprit conformiste (la bureaucratie implique un complet conformisme de l&rsquo;esprit ;  il faut donc m\u00e9nager leur conformisme). Rubenstein observe qu&rsquo;\u00e0 cause de diverses dispositions et situations, l&rsquo;Holocauste ne peut \u00eatre tenu pour ill\u00e9gal selon les lois allemandes en vigueur \u00e0 l&rsquo;\u00e9poque. Rubenstein laisse clairement voir qu&rsquo;il consid\u00e8re la bureaucratisation de la puissance am\u00e9ricaine comme une \u00e9volution de m\u00eame substance que les structures qui permirent l&rsquo;Holocauste&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 25 avril 2013 \u00e0 06H10<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une affaire qui marche : le Goulag US L&rsquo;ensemble p\u00e9nitentiaire US s&rsquo;est lentement transform\u00e9, depuis le d\u00e9but des ann\u00e9es 1970, en un Prison Industrial Complex (PIC) qui s&rsquo;av\u00e8re \u00eatre une des plus \u00e9tonnantes trouvailles du Syst\u00e8me dans la recherche d&rsquo;une activit\u00e9 \u00e0 la fois industrielle et g\u00e9nocidaire, faisant passer au second plan les probl\u00e9matiques de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-74949","post","type-post","status-publish","format-standard","hentry","category-bloc-notes"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74949"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74949\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}