{"id":74971,"date":"2013-05-08T05:53:24","date_gmt":"2013-05-08T05:53:24","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/05\/08\/poutine-netanyahou-les-s-300-et-les-ss-26\/"},"modified":"2013-05-08T05:53:24","modified_gmt":"2013-05-08T05:53:24","slug":"poutine-netanyahou-les-s-300-et-les-ss-26","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/05\/08\/poutine-netanyahou-les-s-300-et-les-ss-26\/","title":{"rendered":"Poutine-Netanyahou , les S-300 et les SS-26"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Poutine-Netanyahou , les S-300 et les SS-26<\/h3>\n<\/p>\n<p><p>\tComme on l&rsquo;a d\u00e9j\u00e0 observ\u00e9 plusieurs fois, le site <em>DEBKAFiles<\/em> demande \u00e0 \u00eatre d\u00e9crypt\u00e9, entre ses analyses orient\u00e9es, sinon fabriqu\u00e9es, et ses observations fond\u00e9es et inform\u00e9es r\u00e9percutant certaines pr\u00e9occupations r\u00e9elles de la communaut\u00e9 de s\u00e9curit\u00e9 nationale isra\u00e9lienne. On placera la nouvelle du <a href=\"http:\/\/www.debka.com\/article\/22957\/US-to-arm-Syrian-rebels-Putin's-rebuke-Chinese-peace-plan-mar-Netanyahu's-Chinese-trip\" class=\"gen\">7 mai 2013<\/a> dans la seconde cat\u00e9gorie. Il s&rsquo;agit d&rsquo;un texte tr\u00e8s s\u00e9v\u00e8re pour le comportement et la strat\u00e9gie de Netanyahou durant la s\u00e9quence des attaques isra\u00e9liennes en Syrie. Le texte se termine par cette conclusion effectivement tr\u00e8s s\u00e9v\u00e8re, o\u00f9 il est jug\u00e9 que le fin manuvrier qu&rsquo;est pr\u00e9tendument Netanyahou s&rsquo;est trouv\u00e9 lui-m\u00eame pi\u00e9g\u00e9 par le voyage en Chine (d\u00e9part le 5 mai, jusqu&rsquo;au 10 mai) qu&rsquo;il a d\u00e9cid\u00e9 de maintenir dans la situation d&rsquo;urgence entre Isra\u00ebl et la Syrie&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>&#8230;Clearly, Prime Minister Netanyahu would have been wiser to postpone his Chinese visit instead of taking off while Israeli air force blasts will still reverberating in Damascus. By staying at home, he would have displayed a firmer and steadier hand at the helm.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>And after taking off, he would have done well not to linger for two days in Shanghai first. This gave the Russian leader the chance to catch him wrong-footed and administer a strong, publicized rebuke, so bearing down on the agenda of Netanyahu&rsquo;s forthcoming talks with Chinese leaders.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl faut noter que cette appr\u00e9ciation tr\u00e8s d\u00e9favorable du comportement de Netanyahou est partag\u00e9 par divers analystes, et m\u00eame par des dirigeants politiques intervenant publiquement. La plus int\u00e9ressante de ces interventions est celle d&rsquo;Erdogan, en la circonstance alli\u00e9 d&rsquo;Isra\u00ebl contre la Syrie d&rsquo;Assad mais qui entretient une tr\u00e8s forte antipathie pour Netanyahou et une m\u00e9fiance g\u00e9n\u00e9rale pour Isra\u00ebl qui font de cette alliance une circonstance bien fragile sinon rocambolesque.  Novosti rapporte le <a href=\"http:\/\/fr.rian.ru\/world\/20130507\/198246100.html<\/p>\n<\/p>\n<p><p>\t17:49 07\/05\/2013&Prime; class=\u00a0\u00bbgen\u00a0\u00bb>7 mai 2013<\/a> la r\u00e9action d&rsquo;Erdogan<\/p>\n<\/p>\n<p><p>\t\u00ab<em>La frappe isra\u00e9lienne contre Damas est absolument inacceptable et ne peut avoir aucune justification. Pour le r\u00e9gime ill\u00e9gitime d&rsquo;Assad, cette attaque est un beau cadeau et un atout pr\u00e9cieux, a d\u00e9clar\u00e9 M. Erdogan devant le groupe parlementaire de son Parti pour la justice et le d\u00e9veloppement (AKP). Et d&rsquo;expliquer qu&rsquo;Assad pourrait exploiter cette frappe a\u00e9rienne pour d\u00e9tourner l&rsquo;attention de l&rsquo;opinion mondiale du conflit sanglant en Syrie.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDans son analyse, <em>DEBKAFiles<\/em> fait allusion \u00e0 une conversation t\u00e9l\u00e9phonique entre Poutine et le Premier ministre isra\u00e9lien le <a href=\"http:\/\/fr.rian.ru\/world\/20130506\/198237215.html\" class=\"gen\">6 mai 2013<\/a>, alors que le second se trouvait \u00e0 Shanghai. Les circonstances \u00e9taient effectivement tr\u00e8s d\u00e9favorables \u00e0 Netanyahou, isol\u00e9 \u00e0 Shanghai, engag\u00e9 dans une visite de type commercial, tandis que Poutine, lui, semble lui avoir parl\u00e9 de choses infiniment plus graves. Si la r\u00e9f\u00e9rence ci-dessus (Novosti) ne donne aucune pr\u00e9cision, <em>DEBKAFiles<\/em> n&rsquo;en est au contraire nullement avare, en se r\u00e9f\u00e9rant \u00e0 ses propres sources dont on peut juger qu&rsquo;elles constituent un relais quasi-direct des dirigeants de s\u00e9curit\u00e9 nationale isra\u00e9liens&#8230; On conna\u00eet la m\u00e9fiance de cette communaut\u00e9, sinon l&rsquo;hostilit\u00e9 pour les directions politiques isra\u00e9liennes en g\u00e9n\u00e9ral, et particuli\u00e8rement Netanyahou. <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Putin did not say how, but he did announce he had ordered the acceleration of highly advanced Russian weapons supplies to Syria. DEBKAfile&rsquo;s military sources disclose that the Russian leader was referring to S-300 anti-air systems and the nuclear-capable 9K720 Iskander (NATO named SS-26 Stone) surface missiles, which are precise enough to hit a target within a 5-7 meter radius at a distance of 280 kilometers.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In his phone call to Netanyahu, the Russian leader made no bones about his determination not to permit the US, Israel or any other regional force (e.g. Turkey and Qatar) overthrow President Bashar Assad. He advised the prime minister to make sure to keep this in mind.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Our sources add: Since Syrian air defense teams have already trained in Russia on the handling of the S-300 interceptor batteries, they can go into service as soon as they are landed by one of Russia&rsquo;s daily airlifts to Syria. Russian air defense officials will supervise their deployment and prepare them for operation. Moscow is retaliating not just for Israel&rsquo;s air operations against Syria but in anticipation of the Obama administration&rsquo;s impending decision to send the first US arms shipments to the Syrian rebels&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLes pr\u00e9cisions concernant l&rsquo;armement russe sont importantes. Elles concernent deux syst\u00e8mes d&rsquo;arme dont les Isra\u00e9liens ont d\u00e9j\u00e0 montr\u00e9 qu&rsquo;ils en ont une grande crainte. Ils sont d\u00e9j\u00e0 intervenus au plus haut niveau (Premier ministre) pour demander aux Russes, \u00e0 plusieurs reprises depuis 2007, de ne pas livrer des S-300 aux Iraniens et des SS-26 aux Syriens. On a d\u00e9j\u00e0 relev\u00e9 de nombreuses indications de la possibilit\u00e9 que les Russes livrent des SS-26 aux Syriens (le <a href=\"http:\/\/www.dedefensa.org\/article-du_roi_abdallah_de_jordanie_au_ss-26_l_arme_secr_te_des_russes_28_08_2008.html\" class=\"gen\">28 ao\u00fbt 2008<\/a>, les <a href=\"http:\/\/www.dedefensa.org\/article-regard_sur_le_flou_syrien_et_explosif_11_12_2012.html\" class=\"gen\">11 d\u00e9cembre 2012<\/a> et <a href=\"http:\/\/www.dedefensa.org\/article-du_patriot_l_iskander_20_12_2012.html\" class=\"gen\">20 d\u00e9cembre 2012<\/a>). Pour le S-300, il n&rsquo;en a pas \u00e9t\u00e9 vraiment question pour le Syrie jusqu&rsquo;ici mais il en est d\u00e9sormais question pr\u00e9cis\u00e9ment. Les deux cas sont th\u00e9oriquement tr\u00e8s inqui\u00e9tants pour Isra\u00ebl :<\/p>\n<\/p>\n<p><p>\t Le SS-26 est une arme offensive \u00e0 port\u00e9e suffisante pour menacer profond\u00e9ment Isra\u00ebl \u00e0 partir des pays voisins. Elle est tr\u00e8s pr\u00e9cise, tr\u00e8s difficilement d\u00e9tectable et extr\u00eamement difficile \u00e0 intercepter. Encore plus du point de vue de la communication et du symbole (on ne parle \u00e9videmment pas d&rsquo;une potentialit\u00e9 effective), il y a le fait que le SS-26 est un armement \u00e0 double capacit\u00e9 (conventionnelle <strong>et nucl\u00e9aire<\/strong>).<\/p>\n<\/p>\n<p><p>\t Le S-300, \u00e0 cause de sa port\u00e9e, supprime l&rsquo;avantage essentiel de l&rsquo;arm\u00e9e de l&rsquo;air isra\u00e9lienne qui intervient plus souvent contre la Syrie en <em>stand-off<\/em>, c&rsquo;est-\u00e0-dire \u00e0 partir d&rsquo;une position lointaine (souvent l&rsquo;espace a\u00e9rien du Liban) en tirant des missiles guid\u00e9s \u00e0 grande port\u00e9e,  mais cette port\u00e9e \u00e9quivalant en gros, justement, \u00e0 celle du S-300. La grande port\u00e9e du S-300 est donc une grave menace, \u00e0 partir de la Syrie, contre l&rsquo;aviation militaire isra\u00e9lienne.<\/p>\n<\/p>\n<p><p>\tOn ne d\u00e9battra pas ici du fait de savoir s&rsquo;il y a eu des livraisons effectives&#8230; L&rsquo;annonce m\u00eame de ces livraisons, ou de ces possibles livraisons, est en soi une arme terrible de communication. Elle signifie que la Russie, si elle en a eu, ne se tient plus tenue \u00e0 un quelconque engagement pass\u00e9 avec Isra\u00ebl de ne pas livrer de telles armes,  cela dans l&rsquo;extr\u00eame de l&rsquo;hypoth\u00e8se o\u00f9 il y aurait eu une telle d\u00e9cision. Les liens, ou les rapports, entre Isra\u00ebl et la Russie au niveau de la s\u00e9curit\u00e9 sont complexes et parfois surprenants. La Russie peut avoir vis-\u00e0-vis d&rsquo;Isra\u00ebl une attitude compr\u00e9hensive. Au contraire, si les \u00e9v\u00e9nements le commandent, la Russie peut avoir une attitude extr\u00eamement ferme, et les Isra\u00e9liens, qui connaissent et respectent les Russes, savent que la d\u00e9termination russe est dans ce cas un facteur primordial, qui n&rsquo;a rien \u00e0 voir avec les atermoiements et la politique caoutchouteuse des USA dans ce domaine. Tout cela montre indirectement qu&rsquo;en cette circonstance comme en d&rsquo;autres, mais peut-\u00eatre plus encore dans ce cas, la critique de ses chefs de la s\u00e9curit\u00e9 nationale contre Netanyahou est fond\u00e9e, et rappelle au reste celle que nous rappelions de notre c\u00f4t\u00e9 dans notre texte du <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_une_guerre-_clair_en_coup_de_vent_07_05_2013.html\" class=\"gen\">7 mai 2013<\/a>, qui vaudrait tr\u00e8s directement pour Netanyahou : \u00ab[S]<em>elon les chefs du Shin Bet : Alors aux commandes, Yaakov Peri estime n&rsquo;avoir re\u00e7u durant les six ans de son mandat aucune consigne des gouvernements successifs. Ou bien il a cette formule, dont les termes sont partag\u00e9s par ses coll\u00e8gues : Isra\u00ebl remporte la plupart des batailles, sans gagner la guerre. Nous ne savions pas dans quelle direction aller, r\u00e9sume Peri. C&rsquo;\u00e9tait toujours de la tactique, jamais de vision strat\u00e9gique&rsquo;.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tSi Poutine a r\u00e9ellement dit \u00e0 Netanyahou ce que <em>DEBKAFiles<\/em> en dit, ou m\u00eame la moiti\u00e9 de ce que <em>DEBKAFiles<\/em> en dit, la situation est s\u00e9rieuse pour Netanyahou&#8230; Erdogan a alors raison de parler d&rsquo;un cadeau qu&rsquo;on qualifiera alors de stupide, fait par Netanyahou \u00e0 la Syrie. Le v\u00e9ritable cadeau fait \u00e0 la Syrie, c&rsquo;est d&rsquo;avoir ouvert une avenue \u00e0 la Russie&#8230; Jusqu&rsquo;ici, la Russie livrait des armements \u00e0 la Syrie selon un argument qui ne cessait de s&rsquo;affaiblir, selon lequel elle ex\u00e9cutait des contrats anciens et\/ou livrait essentiellement des \u00e9quipements n&rsquo;ayant aucun r\u00f4le dans la guerre syrienne en cours. Valable il y a un an, cet argument est aujourd&rsquo;hui tr\u00e8s vuln\u00e9rable et bancal en raison de l&rsquo;extension, de l&rsquo;approfondissement du conflit, et il pla\u00e7ait la Russie dans une position plus vuln\u00e9rable vis-\u00e0-vis de ses partenaires du bloc BAO. Mais voil\u00e0 soudain qu&rsquo;Isra\u00ebl institue une dimension nouvelle, d&rsquo;agression ext\u00e9rieure contre la souverainet\u00e9 de la Syrie qui est un argument irr\u00e9sistible par ce qu&rsquo;il implique d&rsquo;ill\u00e9galit\u00e9, de menace d&rsquo;extension du conflit faisant courir un risque terrible \u00e0 la s\u00e9curit\u00e9 de la r\u00e9gion, etc., toutes choses qui constituent des arguments tr\u00e8s puissants en faveur de l&rsquo;attitude russe dans les n\u00e9gociations comme dans la crise en g\u00e9n\u00e9ral. Du coup, la Russie peut dire qu&rsquo;elle livre des armes \u00e0 Assad dans le but de prot\u00e9ger la souverainet\u00e9 d&rsquo;un pays, de contrecarrer l&rsquo;extension de la guerre, de r\u00e9pondre \u00e0 un comportement qu&rsquo;elle peut qualifier, non seulement d&rsquo;ill\u00e9gal mais d&rsquo;irresponsable et de catastrophique,  tout cela, aux frais Isra\u00ebl. La Russie se trouve \u00e0 nouveau dans une position de tr\u00e8s grande force, jusqu&rsquo;\u00e0 faire savoir discr\u00e8tement qu&rsquo;elle pourrait elle-m\u00eame intervenir, qu&rsquo;elle le ferait d&rsquo;ailleurs <em>de facto<\/em> si tel ou tel armement avanc\u00e9 \u00e9tait livr\u00e9 et \u00e9tait servi par des \u00e9quipes russes.<\/p>\n<\/p>\n<p><p>\tOn voit que, S-300 et SS-26 livr\u00e9s ou pas, ces armes ont d&rsquo;abord une tr\u00e8s forte puissance de communication. Leur \u00e9vocation, dans une situation o\u00f9 il devient acceptable, voire presque l\u00e9gal par logique indirecte de livrer de tels syst\u00e8mes, instaure une terrible menace pour Isra\u00ebl qui n&rsquo;a jamais cach\u00e9 sa crainte de ses armements. Isra\u00ebl perd des atouts qui le servait beaucoup jusqu&rsquo;ici : une position de pseudo-neutralit\u00e9 tr\u00e8s affirm\u00e9e, appuy\u00e9e sur une menace militaire (a\u00e9rienne) contre laquelle personne dans la r\u00e9gion ne pouvait grand&rsquo;chose. Depuis la semaine derni\u00e8re et la coup de t\u00e9l\u00e9phone de Poutine \u00e0 Netanyahou avant hier, <strong>cette perception<\/strong> a vol\u00e9 en \u00e9clat. Isra\u00ebl est d\u00e9sormais <strong>per\u00e7u<\/strong> comme strat\u00e9giquement tr\u00e8s vuln\u00e9rable, pour un avantage bien improbable et purement tactique. La Syrie a re\u00e7u  un cadeau royal, la Russie est plus que jamais ma\u00eetresse du jeu. SS-26 ou pas, S-300 ou non, avec la possibilit\u00e9 que ces choses inqui\u00e9tantes soient r\u00e9ellement introduites en Syrie&#8230;<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 8 mai 2013 \u00e0 05H56<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poutine-Netanyahou , les S-300 et les SS-26 Comme on l&rsquo;a d\u00e9j\u00e0 observ\u00e9 plusieurs fois, le site DEBKAFiles demande \u00e0 \u00eatre d\u00e9crypt\u00e9, entre ses analyses orient\u00e9es, sinon fabriqu\u00e9es, et ses observations fond\u00e9es et inform\u00e9es r\u00e9percutant certaines pr\u00e9occupations r\u00e9elles de la communaut\u00e9 de s\u00e9curit\u00e9 nationale isra\u00e9lienne. On placera la nouvelle du 7 mai 2013 dans la seconde&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3977,11461,6582,2774,8446,8070,3867],"class_list":["post-74971","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-chine","tag-debka","tag-iskander","tag-israel","tag-s-300","tag-ss26","tag-syrie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74971"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74971\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}