{"id":74976,"date":"2013-05-10T14:50:16","date_gmt":"2013-05-10T14:50:16","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/05\/10\/notes-sur-la-danse-de-saint-guy-du-bloc-bao\/"},"modified":"2013-05-10T14:50:16","modified_gmt":"2013-05-10T14:50:16","slug":"notes-sur-la-danse-de-saint-guy-du-bloc-bao","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/05\/10\/notes-sur-la-danse-de-saint-guy-du-bloc-bao\/","title":{"rendered":"Notes sur la danse de Saint-Guy du bloc BAO"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Notes sur la danse de Saint-Guy du bloc BAO<\/h3>\n<\/p>\n<p><p>\t10 mai 2013 \u00a0La rencontre de Moscou (Kerry-Lavrov), essentiellement sur la Syrie, a donc \u00e9t\u00e9 un succ\u00e8s incontestable pour la Russie. Mais, comme nous le pr\u00e9cisions le <a href=\"http:\/\/www.dedefensa.org\/article-sourires_de_lavrov_kerry_in_the_pocket_08_05_2013.html\" class=\"gen\">8 mai 2013<\/a>, ce fut essentiellement un succ\u00e8s de communication, ce qui est d&rsquo;ailleurs l&rsquo;<strong>essentiel<\/strong> et la seule <strong>affirmation certaine<\/strong> qu&rsquo;on puisse envisager dans une telle \u00e9poque : \u00ab<em>En attendant, une rencontre comme celle de Moscou, o\u00f9 un Kerry suit \u00e0 fond les Russes sur la question de la conformation \u00e0 l&rsquo;accord de Gen\u00e8ve, est un incontestable succ\u00e8s de communication pour la Russie, et un point marqu\u00e9 vis-\u00e0-vis des extr\u00e9mistes divers du bloc BAO, autant que des rebelles&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tPour autant, nous retenions \u00e9videmment notre optimisme, inexistant en fait puisque sans raison d&rsquo;\u00eatre, par rapport aux suites de cette initiative. Pour cette raison, nous parlons d&rsquo;un succ\u00e8s de communication de Moscou, qui n&rsquo;engage rien de l&rsquo;avenir, selon l&rsquo;exp\u00e9rience qu&rsquo;on a des pratiques diplomatiques actuelles et de l&rsquo;extraordinaire inconsistance, caoutchouteuse ou molle c&rsquo;est selon, de la diplomatie US. Nous concluions donc : \u00ab<em>Alors qu&rsquo;on \u00e9tait au bord de la Troisi\u00e8me Guerre mondiale il y a quatre jours, on se trouve aujourd&rsquo;hui sur la voie d&rsquo;une grande conf\u00e9rence internationale d&rsquo;o\u00f9 certains esp\u00e8rent voir sortir un accord au moins de cessez-le-feu&#8230; Bien, nous ne parierions ni sur l&rsquo;un ni sur l&rsquo;autre, ni sur la Troisi\u00e8me Guerre mondiale, ni sur un accord de cessez-le-feu ; par contre nous parions sur la toute puissance de la communication et, en un sens, sur la puissance d&rsquo;influence et l&rsquo;habilet\u00e9 manuvri\u00e8re des Russes.<\/em>\u00bb Cette r\u00e9serve n&rsquo;\u00e9tait pas de trop&#8230;<\/p>\n<\/p>\n<p><p>\tEffectivement, la rencontre de Moscou a \u00e9t\u00e9 per\u00e7ue, par ce que nous jugeons \u00eatre des observateurs s\u00e9rieux, comme un succ\u00e8s (pour les Russes) et comme une perc\u00e9e diplomatique en faveur de la th\u00e8se russe, qui est par ailleurs celle du bon sens et de la seule issue diplomatique pour la crise syrienne qu&rsquo;on puisse explorer. Nous allons citer plusieurs de ces sources s\u00e9rieuses. (Il se trouve que ces sources s\u00e9rieuses sont \u00e9galement des sources non align\u00e9es sur la ligne, ou <em>narrative<\/em> du bloc BAO, sinon des sources dissidentes. Non seulement ceci explique cela, mais ceci est la condition <em>sine qua non<\/em> de cela : on ne <strong>peut \u00eatre<\/strong> s\u00e9rieux que si l&rsquo;on ne suit pas la ligne\/la <em>narrative<\/em> du bloc BAO.)<\/p>\n<h3>Espoir et scepticisme&#8230;<\/h3>\n<\/p>\n<p><p>\tD&rsquo;abord, Jim Lobe, de IPS, le <a href=\"http:\/\/www.ipsnews.net\/2013\/05\/hope-scepticism-over-u-s-russian-accord-on-syria-conference\/\" class=\"gen\">9 mai 2013<\/a>. Lobe parle \u00e0 la fois d&rsquo;un espoir devant l&rsquo;aspect s\u00e9rieux de l&rsquo;accord de Moscou, du moins pour la communication qui en a \u00e9t\u00e9 faite ; et de scepticisme, parce que l&rsquo;exp\u00e9rience montre qu&rsquo;un succ\u00e8s de communication, \u00e9ventuellement sanctionn\u00e9 par un engagement public et donc solennel d&rsquo;un secr\u00e9taire d&rsquo;\u00c9tat, n&rsquo;est le garant de rien du tout. Lobe constate ce qui est l&rsquo;\u00e9vidence : l&rsquo;administration Obama,  dans la mesure o\u00f9 Kerry-\u00e0-Moscou repr\u00e9sente l&rsquo;administration Obama, dans la mesure o\u00f9 l&rsquo;administration Obama est suffisamment un artefact coh\u00e9rent pour \u00eatre repr\u00e9sent\u00e9,  s&rsquo;est nettement rapproch\u00e9e des th\u00e8ses de Moscou, notamment sur la participation du r\u00e9gime Assad \u00e0 la conf\u00e9rence pr\u00e9vue, et \u00e0 la formation d&rsquo;une gouvernement de transition. (Nous mettons en gras les d\u00e9clarations de Kerry concernant le cas Assad dans cette occurrence. Cela nous servira plus loin comme rappel.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The surprise accord reached by the U.S. and Russia in Moscow Tuesday to try to convene an international conference to resolve the two-year-old civil war in Syria as soon as the end of this month has been greeted with equal measures of hope and scepticism.<\/em>[&#8230;] <em>The joint decision to revive the long-dormant Geneva Communique, which laid out the core elements of a political solution to the conflict war after a meeting of the U.N.-sponsored Action Group for Syria last June, was reached after deliberations between Secretary of State John Kerry and Russian Foreign Minister Sergei Lavrov.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb[&#8230;T]<em>he administration of President Barack Obama appears to have narrowed its difference on that score with Moscow. At the time, many U.S. analysts, particularly those on the hawkish side of the spectrum, believed that the balance of power on the ground was moving in the opposition&rsquo;s direction, and that it was simply a matter of time  months, if not weeks  until the regime crumbled. But after months of bloody stalemate, it appears that the government&rsquo;s forces have recently regained the initiative by systematically retaking control of strategically located towns and cities&#8230;<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<MI>Indeed, Kerry appears to have accepted Moscow&rsquo;s position that Assad does not have to step down in order for negotiations to get underway. <D<[<strong>I<\/strong>]<strong><em>t&rsquo;s impossible for me as an individual to understand how Syria could possibly be governed in the future by the man who has committed the things we know that have taken place<\/em><\/strong><em>, he said during a press conference with Lavrov after the meeting. <\/em><strong><em>ButI&rsquo;m not going to decide that tonight, and I&rsquo;m not going to decide that in the end, because the Geneva Communique says that the transitional government has to be chosen by mutual consent by the parties the current regime and the opposition.<\/em><\/strong> <em>For his part, Lavrov, without mentioning Assad by name, said he was not interested in the fate of certain persons.<\/em>\u00bb<\/p>\n<h3>Optimisme prudent&#8230;<\/h3>\n<\/p>\n<p><p>\tParmi les d\u00e9clarations de rares personnalit\u00e9s et experts s\u00e9rieux cit\u00e9es par Lobe, on en rel\u00e8vera deux.<\/p>\n<\/p>\n<p><p>\t D&rsquo;abord celle de l&rsquo;envoy\u00e9 sp\u00e9cial de l&rsquo;ONU Lakhdar Brahimi, dont on dit qu&rsquo;il est sur le point de d\u00e9missionner (le second apr\u00e8s Kofi Annan) et qui semblerait devoir retenir cette d\u00e9cision apr\u00e8s l&rsquo;accord de Moscou : \u00ab<em>This is the first hopeful news concerning that unhappy country in a very long time&#8230; The statements made in Moscow constitute a very significant first step forward. It is nevertheless only a first step.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t On rel\u00e8ve aussi cet avis de Paul Pilar, ancien officier de la CIA, qui fut National Intelligence Officer pour le Proche-Orient et l&rsquo;Asie du Sud : \u00ab<em>The chance of a diplomatic breakthrough coming out of the projected conference is at best modest. But it represents a more realistic hope for bringing a modicum of peace and stability to Syria in the foreseeable future than does stoking the civil war with more outside involvement in the military conflict. The fact that the United States and Russia could agree on any of this is a breakthrough of sorts&#8230;<\/em>\u00bb<\/p>\n<h3>Sont-ils devenu des adultes ?<\/h3>\n<\/p>\n<p><p>\tOn s&rsquo;arr\u00eatera encore \u00e0 l&rsquo;avis de P\u00e9p\u00e9 Escobar, sur <em>Russia Today<\/em> le <a href=\"http:\/\/rt.com\/op-edge\/syria-global-dance-of-diplomacy-046\/\" class=\"gen\">9 mai 2013<\/a>. On conna\u00eet Escobar, ses commentaires en forme d&rsquo;envol\u00e9es, appuy\u00e9s sur de nombreux contacts, souvent avis\u00e9s, courageux, extr\u00eamement document\u00e9s, mais \u00e9galement souvent inclin\u00e9s au pessimisme quant au comportement du bloc BAO dont il estime qu&rsquo;il est plus puissant et plus manuvrier qu&rsquo;il ne para\u00eet \u00e0 certains (nous parlons pour nous-m\u00eames dans ce cas). Pour cette fois, Escobar, dans une analyse plus g\u00e9n\u00e9rale de la situation, commence par une rapide revue de la conf\u00e9rence de Moscou o\u00f9 il juge effectivement que les USA se sont rendus aux arguments des Russes. (C&rsquo;est-\u00e0-dire qu&rsquo;ils auraient enfin consenti \u00e0 agir comme des adultes, ce qui est parfaitement situer le domaine o\u00f9 l&rsquo;on \u00e9volue, entre l&rsquo;infantilisme g\u00e9n\u00e9ral du bloc BAO, et les \u00e9clairs de maturit\u00e9 lorsqu&rsquo;il s&rsquo;agit des Russes.)&#8230; L\u00e0 aussi, quelques soulign\u00e9s en gras de notre part.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>It&rsquo;s tempting to assume Israel&rsquo;s bombing of Syria may have led geopolitical players to start behaving as adults.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>US Secretary of State John Kerry met Turkish Foreign Minister Ahmet Davutoglu before landing in Moscow to meet President Putin. Iranian Foreign Minister Ali Akbar Salehi was in Amman  and then forward to Damascus. British Prime Minister David of Arabia&rsquo; Cameron will also meet Putin in Sochi. Next week, Qatar&rsquo;s Foreign Minister will be in Tehran.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>What does this diplomatic dance mean? From an Obama administration point of view, it&rsquo;s still the same game: Assad must go, as the President himself stressed many times, and Moscow must give way.<\/em> <strong><em>Wishful thinking, of course; even Kerry, after meeting Russian Foreign Minister Sergei Lavrov, seems to have realized which way the (desert) wind is blowing.<\/em><\/strong><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Here I interpreted the choices Obama had before the Israeli bombing. It&rsquo;s (relatively) safe to assume that the Obama administration may have abandoned the no-fly zone option, at least for now. The notion that Obama  or Cameron, or Israel <\/em> <strong><em>would be able to intimidate Putin comes straight from Alice in Wonderland.<\/em><\/strong>\u00bb<\/p>\n<h3>Est-ce une diplomatie s\u00e9rieuse ?<\/h3>\n<\/p>\n<p><p>\tCommentaire de <em>The Moon of Alabama<\/em> (MoA), maintenant. Une autre source s\u00e9rieuse, sans nul doute, qui s&rsquo;attache surtout aux cons\u00e9quences de ce qu&rsquo;il juge acquis,  et il est fond\u00e9 de le faire, si l&rsquo;on s&rsquo;en tient \u00e0 une diplomatie s\u00e9rieuse. Puisque le processus de Gen\u00e8ve est r\u00e9activ\u00e9 avec une conf\u00e9rence importante pour la fin du mois, selon l&rsquo;accord Russie-USA&#8230; (Le <a href=\"http:\/\/www.moonofalabama.org\/2013\/05\/syria-the-us-has-no-leverage.html\" class=\"gen\">7 mai 2013<\/a>, avec un soulign\u00e9 de gras \u00e0 nouveau de notre part.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Secretary of State Kerry&rsquo;s talk with Putin and Lavrov yesterday brought back the Geneva consensus from last June which then Secretary of State Clinton<\/em> <strong><em>had thrown out of the window immediately after she had agreed to it<\/em><\/strong><em>. According to the Geneva plan the United States and Russia will convene a conference with the aim to find  some consensual new Syrian government with each side promising to bring its supported party to the table.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>For Russia that will be easy to do. The Syrian government has always agreed to such talks and is willing to send a delegation that will be able to discuss the various issues and to compromise.<\/em>\u00bb<\/p>\n<h3>Poutine pensait \u00e0 autre chose&#8230;<\/h3>\n<\/p>\n<p><p>\tMention \u00e9galement de la conclusion d&rsquo;un article de <em>WSWS.org<\/em> sur les p\u00e9rip\u00e9ties de Carla Del Ponte et de ses d\u00e9clarations sur les responsabilit\u00e9s des rebelles dans l&rsquo;utilisation de l&rsquo;armement chimique. Cette conclusion concerne la visite de Kerry \u00e0 Moscou et ce qui est int\u00e9ressant, c&rsquo;est l&rsquo;accent mis sur le climat de l&rsquo;accueil fait par les Russes \u00e0 Kerry, dans tous les cas par Poutine,  ce qui nous permettra d&rsquo;encha\u00eener sur la suite en revenant sur l&rsquo;attitude de Kerry. Cet accueil est singuli\u00e8rement marqu\u00e9 par un certain m\u00e9pris et une pi\u00e8tre consid\u00e9ration de Kerry, en tant que repr\u00e9sentant de la diplomatie du bloc BAO\/des USA. Cela revient \u00e0 la transcription de cet avis des Russes donn\u00e9 aux diplomates du bloc BAO qui leur demandent leur aide (le <a href=\"http:\/\/www.dedefensa.org\/article-sourires_de_lavrov_kerry_in_the_pocket_08_05_2013.html\" class=\"gen\">8 mai 2013<\/a>)  : \u00ab<em>Nous voulons bien mais nous n&rsquo;avons pas confiance en vous. C&rsquo;est \u00e0 peu pr\u00e8s ce que les Russes pensent lorsqu&rsquo;ils re\u00e7oivent, tous sourires, John Kerry \u00e0 Moscou&#8230;<\/em>\u00bb (Le texte de <em>WSWS.org<\/em> du <a href=\"http:\/\/www.wsws.org\/en\/articles\/2013\/05\/08\/syri-m08.html\" class=\"gen\">9 mai 2013<\/a>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Secretary of State John Kerry traveled to Moscow on Tuesday, attempting to gain Russian support for US regime-change efforts in Syria. Together with China, Russia has vetoed three separate UN resolutions condemning Assad for his government&rsquo;s crackdown on the US-backed rebel groups. The United States believes that we share some very significant common interests with respect to Syriastability in the region, not having extremists creating problems throughout the region and elsewhere, Kerry declared. The United States and Russia reportedly agreed to organize a conference on the war that both the Assad regime and the opposition would attend.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Nevertheless, Kerry received<\/em> <strong><em>a chilly welcome from Putin, who kept him waiting for hours and reportedly fiddled with his pen distractedly while Kerry spoke<\/em><\/strong><em>. The Russian Foreign Ministry released a statement, implicitly critical of US policy, that declared: The further escalation of armed confrontation sharply increases the risk of creating new areas of tension and the destabilization of the so-far relatively calm atmosphere on the Lebanese-Israeli border.<\/em>\u00bb<\/p>\n<h3>Kerry historien<\/h3>\n<\/p>\n<p><p>\tCela \u00e9tant rapport\u00e9, qui concerne donc ce que la situation diplomatique a de s\u00e9rieusement consid\u00e9r\u00e9e, venons-en \u00e0 la danse de Saint-Guy. (La danse de Saint-Guy n&rsquo;est pas seulement une expression, c&rsquo;est aussi une maladie r\u00e9elle. Cela va bien pour notre sujet. Cela va encore mieux quand on d\u00e9couvre le nom scientifique de cette maladie pour les adultes, qui fait vraiment partie de notre sujet&#8230; \u00ab<em>Et si les expressions fran\u00e7aises peuvent souvent donner lieu \u00e0 des d\u00e9rives humoristiques, ce n&rsquo;est pas le cas de celle-ci qui correspond \u00e0 une maladie nerveuse touchant les enfants (chor\u00e9e de Sydenham) ou les adultes (chor\u00e9e<\/em> <strong><em>de Huntington<\/em><\/strong><em>) et qui se manifeste, entre autres, par des mouvements brusques, d\u00e9sordonn\u00e9s et incontr\u00f4lables, surtout dans les membres.<\/em>\u00bb (<a href=\"http:\/\/www.expressio.fr\/expressions\/la-danse-de-saint-guy.php\" class=\"gen\">D\u00e9finition<\/a> dans <em>Expressio<\/em>.)<\/p>\n<\/p>\n<p><p>\tEn l&rsquo;occurrence, la danse de Saint-Guy est celle de John Kerry&#8230; Le d\u00e9tail de ses d\u00e9clarations \u00e0 Moscou (o\u00f9 l&rsquo;on retrouve la citation de Lobe) m\u00e9rite d&rsquo;\u00eatre retranscrit. Ce n&rsquo;est pas notre habitude de reprendre des parties importantes de textes officiels, mais dans ce cas nous d\u00e9rogeons \u00e0 cette habitude. Le ton emphatique, enthousiaste de Kerry pour la Russie, pour Poutine, pour Lavrov (Serguei), mais aussi, ce qui est encore plus remarquable, pour le r\u00f4le de la Russie (URSS) pendant la Deuxi\u00e8me Guerre mondiale (on \u00e9tait la veille de l&rsquo;anniversaire de la capitulation allemande), dans un sens qui est syst\u00e9matiquement ignor\u00e9 par l&rsquo;historiographie US et du bloc BAO, avec le chiffre vbdes morts russes de 27 millions, ou proche de 30 millions, plut\u00f4t que la version BAO de pr\u00e8s de 20 millions  tout cela \u00e9tait remarquable d&rsquo;un enthousiasme pro-russe, que des esprits mal intentionn\u00e9s pourrait juger \u00eatre de l&rsquo;obs\u00e9quiosit\u00e9. A ce point de la lecture de cette d\u00e9claration de Kerry, on en d\u00e9duira que la diplomatie US est, devant la Russie, dans un \u00e9tat d&rsquo;affolement consid\u00e9rable, que l&rsquo;administration Obama veut \u00e0 tout prix \u00e9viter de se faire entra\u00eener dans un conflit, que les USA cherchent \u00e0 tout prix un soutien  de la Russie.<\/p>\n<\/p>\n<p><p>\tOn comprend les sourires de Lavrov, qui peuvent aussi bien exprimer satisfaction, d\u00e9rision, voire un peu de m\u00e9pris, et m\u00eame de compassion apr\u00e8s tout (quoique cela soit fort peu du genre de Lavrov)&#8230;<\/p>\n<h3>La feuille de route de Kerry<\/h3>\n<\/p>\n<p><p>\tNous reproduisons donc par ailleurs (ce <a href=\"http:\/\/www.dedefensa.org\/article-kerry_la_gloire_de_la_russie_et_de_serguei__10_05_2013.html\" class=\"gen\">10 mai 2013<\/a>), comme dit plus haut, l&rsquo;essentiel de cette d\u00e9claration de Kerry, qui vaut la lecture sans aucun doute. Ici, nous nous contentons de citer le passage qui concerne sp\u00e9cifiquement la situation des n\u00e9gociations sur la Syrie par rapport au sort du pr\u00e9sident Assad, suite \u00e0 une question. On y retrouve les citations de Lobe. On remarque l&rsquo;extr\u00eame prudence des termes de Kerry qui ne d\u00e9clare jamais une politique sp\u00e9cifique, mais qui donne des avis personnels, qui pr\u00e9cise que le temps n&rsquo;est pas venu de se prononcer sp\u00e9cifiquement, qui indique que ce n&rsquo;est pas \u00e0 lui de d\u00e9cider du sort d&rsquo;Assad, que les deux parties (dont le r\u00e9gime, c&rsquo;est-\u00e0-dire le r\u00e9gime d&rsquo;Assad) doivent \u00eatre les parties de la n\u00e9gociation, etc. (Soulign\u00e9 en gras, le passage concernant Assad.)<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Now, up until now, I think there has been a perception that Russia and the United States haven&rsquo;t been particularly on the same page of cooperating in this effort. So what I think is significant is that we are here to say that we are going to cooperate in trying to implement the Geneva communique, and I think our understanding of that communique is very similar, and there&rsquo;s actually more agreement<\/em> <strong><em>even though our position has been that it&rsquo;s impossible for me as an individual to understand how Syria could possibly be governed in the future by the man who has committed the things that we know have taken place. But that&rsquo;s not  I&rsquo;m not going to decide that tonight. And I&rsquo;m not going to decide that in the end. Because the Geneva communique says that the transitional government has to be chosen by mutual consent by the parties. Who are the parties? The parties are the current regime and the opposition.<\/em><\/strong> <em>So what we&rsquo;re going to undertake to do is to try to get them in a position where they, representing the people they represent  Syria and the interests they represent  put people into a transitional government by mutual consent&#8230;<\/em>\u00bb<\/p>\n<h3>Danse de Saint-Guy \u00e0 Rome<\/h3>\n<\/p>\n<p><p>\tApr\u00e8s Moscou, Kerry a fait une escale \u00e0 Rome o\u00f9 il a rencontr\u00e9 la ministre italienne des affaires \u00e9trang\u00e8res Bonino, mais aussi le ministre des affaires \u00e9trang\u00e8res jordanien et la ministre isra\u00e9lienne de la justice, de passage dans la capitale italienne. Cela a permis une \u00e9volution de la position de Kerry sur le point de la pr\u00e9sence, voire de l&rsquo;existence m\u00eame du pr\u00e9sident syrien Assad selon l&rsquo;interpr\u00e9tation du ministre Fabius. Donnons deux interpr\u00e9tations dans une occurrence absolument confuse comme c&rsquo;est la r\u00e8gle sur ce sujet.<\/p>\n<\/p>\n<p><p>\t De <em>Russia Today<\/em>, ce <a href=\"http:\/\/rt.com\/news\/cameron-proof-rebels-chemical-weapons-050\/\" class=\"gen\">9 mai 2013<\/a>&#8230; Il s&rsquo;agit donc d&rsquo;une voix qu&rsquo;on ne peut raisonnablement consid\u00e9rer comme acquise au Syst\u00e8me et au bloc BAO&#8230; Pourtant, m\u00eame son interpr\u00e9tation reste probl\u00e9matique car il n&rsquo;a jamais \u00e9t\u00e9 question, d&rsquo;aucun c\u00f4t\u00e9 que ce soit, qu&rsquo;Assad fasse partie du gouvernement de transition,  ce qui est bien en cause ici, comme facteur de d\u00e9saccord entre Russie et USA &#8230; <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Despite the US now pushing with Russia for an international conference to be called on Syria, US Secretary of State John Kerry said once again that Syrian President Bashar Assad cannot be part of the transitional process. The foreign minister will work with us, as they have, to try to bring all the parties to the table so that we can effect a transition government by mutual consent of both sides, Kerry told reporters during his visit to Rome on Thursday. President Assad will not be a component of that transitional government, he added.<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>\t\u00bb<em>The statements came after Kerry&rsquo;s trip to Moscow where he discussed the Syrian issue with his Russian counterpart Lavrov. The US and Russia have been at odds over the fate of Assad: while Washington insists he must step down, Moscow maintains that only the Syrian people should decide on the matter. The two powers failed to iron out this difference in approach during the Moscow talks. However, both reiterated their commitment to the Syria peace plan  known as the Geneva Communiqu\u00e9  agreed by the Action Group for Syria in June 2012 and called for a follow-up meeting on the conference by the end of May&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t De la <em>BBC.news<\/em>, ce <a href=\"http:\/\/www.bbc.co.uk\/news\/world-middle-east-22465918?print=true\" class=\"gen\">9 mai 2013<\/a>. Avec ce m\u00e9dia, on est en plein dans le Syst\u00e8me, ce qui se sent d\u00e8s le titre et le sous-titre o\u00f9 il est affirm\u00e9 successivement \u00ab<em>Syria conflict: US says Assad can have no post-war role  US Secretary of State John Kerry has said Syrian President Bashar al-Assad would have no role in a political settlement to Syria&rsquo;s conflict.<\/em>\u00bb Il y a une diff\u00e9rence entre <em>no post-war role<\/em> (aucun r\u00f4le pour l&rsquo;apr\u00e8s-guerre), qui indique une situation politique structurelle en th\u00e9orie ind\u00e9finie, et  <em> no role in a political settlement to Syria&rsquo;s conflict<\/em> (aucun r\u00f4le dans l&rsquo;arrangement politique du conflit syrien) qui indique une situation politique conjoncturelle n\u00e9cessairement limit\u00e9e (dans ce cas au gouvernement de transition). Le texte lui-m\u00eame prend encore quelques distance de cette interpr\u00e9tation en escalier de <em>BBC.News<\/em> puisqu&rsquo;on passe du aucun r\u00f4le dans l&rsquo;arrangement politique du conflit syrien au d\u00e9part pur et simple d&rsquo;Assad comme une pr\u00e9-condition alors que Kerry parle de <em>our judgement<\/em> selon lequel <em>Assad will not be a component of that transitional government<\/em><\/p>\n<\/p>\n<p><p>\tSuivant donc son titre et son sous-titre qui indique l&rsquo;agitation courante dans la chor\u00e9e de Huntington, le texte d\u00e9marre de cette fa\u00e7on : \u00ab<em>The comments followed reports that the US was softening its insistence on Mr Assad&rsquo;s departure as a precondition for any deal &#8211; as demanded by rebels. That had been opposed by Russia, which this week backed a conference to seek a political solution to the Syrian war.<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Speaking to reporters in Rome, Mr Kerry said Mr Judeh would work with the US on a transition government by mutual consent of both sides, which clearly means that in our judgement President Assad will not be a component of that transitional government. Later, Mr Kerry said it was very significant that Russian Foreign Minister Sergei Lavrov had said Moscow was not tied to any one person and had backed the idea of transitional government. There is no way that anybody here believes that the opposition is ever going to give consent to President Assad to be running that government.<\/em>\u00bb<\/p>\n<h3>Danse de Saint-Guy \u00e0 Washington<\/h3>\n<\/p>\n<p><p>\tPour parfaire la naus\u00e9e qui agr\u00e9mente en g\u00e9n\u00e9ral le suivi d&rsquo;un commentaire sur l&rsquo;\u00e9volution de la politique US\/BAO, type-chor\u00e9e de Huntington, on se reportera \u00e0 quelques textes de <em>Antiwar.com<\/em>, de leur habituelle et excellents synth\u00e8ses express, montrant comment, successivement, Washington a soutenu \u00e0 100% le tournant de Kerry acceptant compl\u00e8tement le processus de la conf\u00e9rence de Gen\u00e8ve qu&rsquo;avait recrach\u00e9 Hillary Clinton apr\u00e8s l&rsquo;avoir accept\u00e9 (en <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_une_conf_rence_perdue_corps_et_biens_03_07_2012.html\" class=\"gen\">juin 2012<\/a>), qui ne pr\u00e9voit aucune pr\u00e9-condition d&rsquo;aucune sorte, puis le tournant en sens inverse. Kerry, effectivement mol et mall\u00e9able \u00e0 souhait, n&rsquo;a qu&rsquo;\u00e0 s&rsquo;adapter&#8230;<\/p>\n<\/p>\n<p><p>\t Le <a href=\"http:\/\/news.antiwar.com\/2013\/05\/07\/obama-moral-obligation-to-end-syrian-civil-war\/&#8236;\" class=\"gen\">8 mai 2013<\/a> : \u00ab<em>Previous efforts at a negotiated settlement in Syria stalled over US (and by extension pro-US rebel) demands that President Assad unconditionally resign before the talks begin. President Obama is suggesting that the policy may be changing however. Citing a moral obligation to end the ongoing Syrian Civil War, the Obama Administration has now announced a deal with the Russian government to jointly back a negotiated settlement.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Le <a href=\"http:\/\/news.antiwar.com\/2013\/05\/09\/us-no-syria-peace-deal-without-assad-ouster\/&#8236;\" class=\"gen\">10 mai 2013<\/a> : \u00ab<em>The Obama Administration announced two days ago that it was making a dramatic shift, supporting negotiations to end the Syrian Civil War. Today, they appear to have backtracked entirely, insisting that any talks are preconditioned on President Bashar Assad resigning. The 360 degree path that ended with them taking the same failed position they&rsquo;ve held for over a year appears to have come entirely from Syria&rsquo;s rebels loudly rejecting the US-Russia pact yesterday, saying they are holding out for the government to give in to all their demands unilaterally.<\/em>\u00bb<\/p>\n<h3>Prisonnier de la politique-Syst\u00e8me<\/h3>\n<\/p>\n<p><p>\tAinsi semblerait-il que le r\u00e9sultat de cette \u00e9tonnante manuvre, autour de la rencontre de Moscou, avec semblerait-il (bis) deux fois 180\u00b0 en deux jours de la part des USA, serait une situation aussi complexe et aussi bloqu\u00e9e qu&rsquo;elle l&rsquo;\u00e9tait dimanche, avant l&rsquo;arriv\u00e9e de Kerry \u00e0 Moscou, puisque rien de fondamental n&rsquo;aurait finalement chang\u00e9. La seule nouvelle (?) est que la diplomatie US (du bloc BAO) aurait montr\u00e9 et d\u00e9montr\u00e9 une fois de plus, non pas ses limites, mais sa compl\u00e8te, totale et absolue inexistence, sa compl\u00e8te d\u00e9pendance (au sens de l&rsquo;addiction \u00e0 une drogue) aux pressions de la <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_la_politique-syst_me__17_11_2012.html\" class=\"gen\">politique-Syst\u00e8me<\/a> engendr\u00e9e par un m\u00e9canisme et des forces \u00e9chappant \u00e0 <strong>tout contr\u00f4le humain<\/strong>.<\/p>\n<\/p>\n<p><p>\tEn fait de diplomatie, on est conduit \u00e0 observer qu&rsquo;il s&rsquo;agit d&rsquo;une pi\u00e8tre manuvre de communication redondante o\u00f9 il s&rsquo;agit de dire que la Russie s&rsquo;est ralli\u00e9e \u00e0 la politique du bloc BAO apr\u00e8s qu&rsquo;on se soit ralli\u00e9 \u00e0 la politique de la Russie, o\u00f9 les USA ne parviennent pas \u00e0 donner le change plus de 48 heures. Dans l&rsquo;aventure pr\u00e9c\u00e9dente, <strong>exactement similaire<\/strong>, la prise de position de Kerry (\u00e0 Oslo le 12 mars, voir le <a href=\"http:\/\/www.dedefensa.org\/article-qui_commande_ici_kerry_l_ue_ou_le_syst_me__26_03_2013.html \" class=\"gen\">26 mars 2013<\/a>) avait au moins tenu plus d&rsquo;une semaine (mais comment\u00e9e par un silence de plomb), avant que le secr\u00e9taire d&rsquo;\u00c9tat commence \u00e0 virer comme il a commenc\u00e9 \u00e0 le faire \u00e0 Rome apr\u00e8s Moscou, sans doute pour se r\u00e9aligner sur la politique-Syst\u00e8me. Aujourd&rsquo;hui, il semble qu&rsquo;il faille 48 heures pour que la mascarade soit pli\u00e9e, en carr\u00e9, et le faux-nez rouge du clown prestement \u00f4t\u00e9.<\/p>\n<\/p>\n<p><p>\tAinsi en jugerait-on, si l&rsquo;on s&rsquo;en tient aux \u00e9tonnantes circonvolutions des 7-9 mai, et aux d\u00e9clarations possibles (qui peut en \u00eatre assur\u00e9 ?) de Washington. Les commentaires de la presse-Syst\u00e8me, eux, ont imperturbablement suivi l&rsquo;habituelle feuille de route, comme le montre <em>BBC.News<\/em> : Assad doit partir avant toutes choses, et s&rsquo;il y a accord \u00e0 Moscou c&rsquo;est bien que les Russes se sont enfin align\u00e9s sur la politique du bloc BAO et son immense sagesse.<\/p>\n<\/p>\n<p><p>\tLe pauvre Kerry en est r\u00e9duit \u00e0 juger comme une avanc\u00e9e extraordinaire que Lavrov ait comment\u00e9 sobrement que la politique russe n&rsquo;\u00e9tait li\u00e9e au sort d&rsquo;aucune personne (<em>Kerry said it was very significant&rsquo; that Russian Foreign Minister Sergei Lavrov had said Moscow was not tied to any one person&rsquo; and had backed the idea of transitional government.<\/em>). Les Russes n&rsquo;ont jamais dit autre chose, n&rsquo;ayant jamais affirm\u00e9 qu&rsquo;ils voulaient ou pas le maintien d&rsquo;Assad au pouvoir, puisque pour eux une politique vis-\u00e0-vis d&rsquo;un \u00c9tat souverain ne saurait d\u00e9pendre d&rsquo;un avis sur le sort d&rsquo;un dirigeant, qui est un mati\u00e8re souveraine int\u00e9rieure. Les Russes ne cessent de r\u00e9p\u00e9ter qu&rsquo;ils ne veulent qu&rsquo;une chose, le respect du principe de non-ing\u00e9rence dans les affaires int\u00e9rieures d&rsquo;un \u00c9tat souverain, le sort d&rsquo;Assad devant \u00eatre le fait du peuple syrien lui-m\u00eame, au cours d&rsquo;\u00e9lections \u00e0 organiser.<\/p>\n<h3>La confusion comme art diplomatique<\/h3>\n<\/p>\n<p><p>\tIl est donc pour l&rsquo;instant impossible de fixer une situation qui s&rsquo;ab\u00eeme dans la confusion la plus compl\u00e8te. On voit mal comment une grande conf\u00e9rence pourrait se tenir d&rsquo;ici la fin du mois pour parvenir \u00e0 un r\u00e8glement temporaire (cessation des combats et gouvernement int\u00e9rimaire) si le climat et les vagues impressions et interpr\u00e9tations diverses qui se pr\u00e9cipitent depuis mardi ne sont pas clarifi\u00e9es. Il devrait donc y avoir \u00e0 nouveau de franches conversations entre la Russie et les USA, pour fixer ces conditions pr\u00e9liminaires \u00e0 la conf\u00e9rence ; pour autant, il n&rsquo;est pas assur\u00e9 qu&rsquo;elles aient lieu, ni surtout qu&rsquo;elles puissent \u00eatre franches, ces conversations ; pour autant, dirions-nous en sens inverse et pour la beaut\u00e9 de l&rsquo;\u00e9quilibre des pr\u00e9cisions, il n&rsquo;est pas assur\u00e9 qu&rsquo;on n&rsquo;assiste pas \u00e0 un nouveau tournant des USA&#8230; Mais, sur le fond, les USA s&rsquo;appuyant sur les rebelles dont ils ont \u00e9pous\u00e9 la cause et dont ils sont plus les prisonniers qu&rsquo;ils ne les contr\u00f4lent, des rebelles qui sont divis\u00e9s en autant de factions qui ne vivent que par la surench\u00e8re maximaliste dont le but est la t\u00eate d&rsquo;Assad, sur le fond il nous para\u00eet infiniment improbable qu&rsquo;on puisse arriver \u00e0 cette grande conf\u00e9rence avec deux parties stabilis\u00e9es et assur\u00e9es dans des positions conciliables&#8230; Sur le fond, il nous para\u00eet tout aussi infiniment improbable qu&rsquo;on y parvienne jamais, avec une politique du bloc BAO aussi peu contr\u00f4lable par lui-m\u00eame, aussi soumise \u00e0 des forces ext\u00e9rieures, aussi compl\u00e8tement emport\u00e9e par la temp\u00eate qu&rsquo;elle a presque exclusivement contribu\u00e9 \u00e0 d\u00e9clencher.<\/p>\n<\/p>\n<p><p>\tLa Russie, elle, ne peut que tenir sur sa position intangible du respect de la souverainet\u00e9 (pour la Syrie), donc sans aucun pr\u00e9-condition sur la situation d&rsquo;Assad. C&rsquo;est l\u00e0, pour la Russie, une question de principe qui tient toute la politique de ce pays, et la moindre concession faite <strong>en principe<\/strong> sur le sort d&rsquo;Assad aurait justement comme effet de d\u00e9truire compl\u00e8tement ce principe essentiel de la souverainet\u00e9. Les Russes savent parfaitement qu&rsquo;une telle orientation constituerait une acceptation tacite de la politique dite du <em>regime change<\/em>, soit l&rsquo;acceptation de la dynamique de la politique-Syst\u00e8me qui s\u00e8me le d\u00e9sordre dans les relations internationales, et qui, d&rsquo;ailleurs, pourrait un jour se retourner contre eux-m\u00eames. Dans une telle occurrence et par une belle journ\u00e9e, l&rsquo;ambassadeur US \u00e0 Moscou McFaul ne demanderait-il pas un gouvernement de transition en Russie avec \u00e9limination de Poutine de tout r\u00f4le politique ? La prolif\u00e9ration d&rsquo;une telle politique accouch\u00e9e de la politique-Syst\u00e8me est, pour les Russes comme pour tout le monde, bien aussi dangereuse que la prolif\u00e9ration du terrorisme&#8230;<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur la danse de Saint-Guy du bloc BAO 10 mai 2013 \u00a0La rencontre de Moscou (Kerry-Lavrov), essentiellement sur la Syrie, a donc \u00e9t\u00e9 un succ\u00e8s incontestable pour la Russie. Mais, comme nous le pr\u00e9cisions le 8 mai 2013, ce fut essentiellement un succ\u00e8s de communication, ce qui est d&rsquo;ailleurs l&rsquo;essentiel et la seule affirmation&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[4202,2998,855,2830,2707,4102,2726,9966,2730],"class_list":["post-74976","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-assad","tag-change","tag-kerry","tag-lavrov","tag-moscou","tag-politique-systeme","tag-regime","tag-rome","tag-russie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74976"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74976\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}