{"id":74978,"date":"2013-05-11T12:04:27","date_gmt":"2013-05-11T12:04:27","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/05\/11\/les-usa-et-la-syrie-phase-depressive\/"},"modified":"2013-05-11T12:04:27","modified_gmt":"2013-05-11T12:04:27","slug":"les-usa-et-la-syrie-phase-depressive","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/05\/11\/les-usa-et-la-syrie-phase-depressive\/","title":{"rendered":"Les USA et la Syrie  : phase d\u00e9pressive&#8230;"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Les USA et la Syrie  : phase d\u00e9pressive&#8230;<\/h3>\n<\/p>\n<p><p>\tLa situation du bloc BAO, surtout des USA, vis-\u00e0-vis de la Syrie suit l&rsquo;habituel rythme qu&rsquo;on pourrait qualifier de <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_maniaco-depression_du_monde_ddecrisis_19_01_2012.html\" class=\"gen\">maniaco-d\u00e9pressif<\/a> tant cette posture psychologique caract\u00e9rise bien les perceptions humaines et le rythme des \u00e9v\u00e9nements dans cette \u00e9poque totalement d\u00e9pendante d&rsquo;une communication \u00e9crasante et incontr\u00f4lable. L&rsquo;attitude g\u00e9n\u00e9rale des USA vis-\u00e0-vis de la Syrie est entr\u00e9e en phase d\u00e9pressive apr\u00e8s une phase hypomaniaque de quelques jours suivant l&rsquo;intervention isra\u00e9lienne de communication (<a href=\"http:\/\/www.dedefensa.org\/article-intronisation_du_facteur_falseflag_04_05_2013.html\" class=\"gen\">peut-\u00eatre<\/a> type <em>falseflag<\/em>) des 22-23 avril pour faire accepter l&rsquo;id\u00e9e de l&rsquo;utilisation de l&rsquo;armement chimique par le r\u00e9gime Assad et faire progresser l&rsquo;id\u00e9e d&rsquo;une intervention.<\/p>\n<\/p>\n<p><p>\tLe dernier commentaire en date de l&rsquo;administration Obama concernant l&rsquo;utilisation d&rsquo;armement chimique en Syrie (si possible par les gens d&rsquo;Assad) vient du vice-pr\u00e9sident Biden. Il s&rsquo;agit d&rsquo;un aveu complet d&rsquo;ignorance (plut\u00f4t que d&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-de_l_inconnaissance_du_systeme_13_07_2011.html\" class=\"gen\">inconnaissance<\/a>) \u00e0 propos de cet \u00e9v\u00e9nement, ou de ce non-\u00e9v\u00e9nement, de l&rsquo;utilisation de l&rsquo;armement chimique. C&rsquo;est le commentaire le plus \u00e9labor\u00e9 \u00e0 ce jour dans la mesure o\u00f9 il expose la strat\u00e9gie de communication de l&rsquo;administration dans cette mati\u00e8re, qui est de ne pas renouveler les erreurs des guerres en Irak et en Afghanistan, le plus souvent engag\u00e9es sur la foi de renseignements qui se sont r\u00e9v\u00e9l\u00e9s faux, ou \u00eatre tout simplement des montages de groupes int\u00e9ress\u00e9s.<\/p>\n<\/p>\n<p><p>\tLe commentaire de Biden est contenu dans une interview au magazine <em>Rolling Stone<\/em>, dont <em>Russia Today<\/em> reprend les \u00e9l\u00e9ments essentiels sur la question envisag\u00e9e. Il s&rsquo;agit d&rsquo;une intervention de communication prudente bien qu&rsquo;officielle du plus haut niveau. <em>Rolling Stone<\/em>, qui a parfois des positions contestatrices du Syst\u00e8me, n&rsquo;est pas une source souvent consult\u00e9e ou cit\u00e9e dans le r\u00e9seau de la communication-Syst\u00e8me. Par contre, le fait qu&rsquo;il s&rsquo;agisse d&rsquo;une intervention d&rsquo;une personnalit\u00e9 du niveau de Biden montre que l&rsquo;administration Obama veut donner \u00e0 ces informations, quoique avec une diffusion limit\u00e9e, un tr\u00e8s haut degr\u00e9 de cr\u00e9dit pour informer de sa position sur le probl\u00e8me. C&rsquo;est une attitude bien dans la mani\u00e8re de cette administration : faire passer avec une certaine discr\u00e9tion un message important,  puisque cette d\u00e9claration de Biden est certainement le message le plus \u00e9labor\u00e9 de l&rsquo;administration Obama vis-\u00e0-vis de l&#8217;emploi du chimique dans la s\u00e9quence actuelle commenc\u00e9e fin avril ; et message qui signifie : Nous ne faisons aucune confiance aux renseignements dont nous disposons, donc nous ne savons rien et il est hors de question que nous agissions pour le moment, et il est bien peu probable que nous sachions jamais quelque chose de pr\u00e9cis.<\/p>\n<\/p>\n<p><p>\t<em>Russia Today<\/em>, le <a href=\"http:\/\/rt.com\/news\/washington-syrian-chemical-weapons-079\/\" class=\"gen\">10 mai 2013<\/a> : \u00ab<em>Due to the foggy intelligence emanating out of Syria, it is unclear whether president Assad authorized the use of chemical weapons if the rebels had used them, US vice president Joe Biden said stepping back from the unanimous rhetoric of the recent days. His comments, delivered in an interview with Rolling Stone magazine, were a step back from a recent report speculating that Obama administration officials were preparing to arm Syrian rebel forces. It has been widely reported that top US government officials believe Assad responsible for the choking clouds.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>We don&rsquo;t have a chain of ownership, Biden said. We don&rsquo;t know for certain whether they were used by some of the opposition, including the radicals who have aligned themselves with Al-Qaeda. It&rsquo;s probable, but we don&rsquo;t know for certain, that they were used by the regime.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>The vice president admitted that the country&rsquo;s recent &#8211; and disastrous  wars in Iraq and Afghanistan have made White House officials nervous about entering into open combat in Syria, despite vocal criticism from Congressional leaders that the American military should get involved.  With all the credibility we&rsquo;ve gained in the world, we don&rsquo;t want to blow it like the last administration did in Iraq, saying weapons of mass destruction,&rsquo; he continued. We know that there have been traces found of what are probably chemical weapons. What we don&rsquo;t know yet  and we&rsquo;re drilling down on it as hard as we can  is whether they were accidentally released in an exchange of gunfire or artillery fire, or blown up or something.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe constat ci-dessus concerne l&rsquo;armement chimique mais il refl\u00e8te en r\u00e9alit\u00e9 une phase d\u00e9pressive qui affecte toute la politique US vis-\u00e0-vis de la Syrie. Mais, pour suivre la logique choisie, nous devrions plut\u00f4t parler de la psychologie de la direction am\u00e9ricaniste vis-\u00e0-vis de cette question syrienne, qui est \u00e0 nouveau incorpor\u00e9e dans la perception du d\u00e9sordre complet caract\u00e9risant la situation des relations internationales. C&rsquo;est l\u00e0 un caract\u00e8re int\u00e9ressant de ces phases activistes (celle du 22-23 avril) qui semblent lanc\u00e9es, d&rsquo;ailleurs souvent d&rsquo;une fa\u00e7on qui ne r\u00e9pond pas \u00e0 une logique ou \u00e0 une planification humaines, pour tenter de pr\u00e9cipiter la crise \u00e0 un niveau sup\u00e9rieur de gravit\u00e9 et d&rsquo;intervention (et en parlant de la guerre syrienne, on pourrait aussi bien parler de toute autre crise). Ces phases, effectivement hypomaniaques, se transforment tr\u00e8s vite en phases d\u00e9pressives devant l&rsquo;extr\u00eame difficult\u00e9 de pouvoir distinguer dans la pression de la communication les \u00e9l\u00e9ments d&rsquo;une situation claire et contr\u00f4lable. Assez rapidement \u00e9merge l&rsquo;argument de l&rsquo;attentisme, que m\u00eame les partisans hypomaniaques de l&rsquo;intervention (dans le cas de Washington, les parlementaires hyper bellicistes type Graham-McCain), eux-m\u00eames touch\u00e9s par l&rsquo;humeur d\u00e9pressive, n&rsquo;ont plus la force de contrarier. Ce rythme maniaco-d\u00e9pressif, avec la pr\u00e9pond\u00e9rance incontestable pour la phase d\u00e9pressive d\u00e9pourvu de la moindre capacit\u00e9 de <a href=\"http:\/\/www.dedefensa.org\/article-r_silience_pour_r_silience_09_11_2012.html\" class=\"gen\">r\u00e9silience<\/a> \u00e0 cause de son emprisonnement aux lubies de la phase hypomaniaque lorsqu&rsquo;il s&rsquo;agit d&rsquo;agir, convient parfaitement au ph\u00e9nom\u00e8ne d&#8217;embourbement crisique qui t\u00e9moigne de la vigueur extraordinaire de l&rsquo;infrastructure crisique (voir notre <em>Glossaire.dde<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_facteur_crisique__30_04_2013.html\" class=\"gen\">30 avril 2013<\/a> sur le facteur crisique&rsquo;).<\/p>\n<\/p>\n<p><p>\tDans cette sorte de phase d\u00e9pressive apparaissent des textes qui r\u00e9sument la logique de l&rsquo;attentisme sugg\u00e9r\u00e9 par l&rsquo;humeur d\u00e9pressive. Aucun ne l&rsquo;exprime mieux, pour ce cas, que ce texte tr\u00e8s court de Zbigniew Brzezinski, qui ressemble plus \u00e0 une fiche tr\u00e8s condens\u00e9e, type-feuille de route, destin\u00e9e \u00e0 un Obama qu&rsquo;\u00e0 un article. (Ce pourrait \u00eatre le cas, Brzezinski jouant le r\u00f4le \u00e9pisodique de conseiller ext\u00e9rieur d&rsquo;Obama dans certains cas critiques). Dans l&rsquo;hebdomadaire <em>Time<\/em> du <a href=\"http:\/\/swampland.time.com\/2013\/05\/08\/syria-intervention-will-only-make-it-worse\/\" class=\"gen\">8 mai 2013<\/a>, Brzezinski d\u00e9taille d&rsquo;une fa\u00e7on tr\u00e8s br\u00e8ve, tr\u00e8s concentr\u00e9e et imp\u00e9rative, les raisons pour lesquelles les USA ne doivent <strong>rien faire<\/strong> en Syrie. On notera ce constat implicite, assez inattendu chez cet adversaire visc\u00e9ral de la Russie, que seuls les Russes sont capables de faire quelque chose et qu&rsquo;il faut les laisser faire. Brzezinski avance l&rsquo;espoir que l&rsquo;issue soit des \u00e9lections contr\u00f4l\u00e9es par l&rsquo;ONU (ce que veulent effectivement les Russes) o\u00f9 l&rsquo;on pourrait esp\u00e9rer qu&rsquo;Assad soit persuad\u00e9 de n&rsquo;y pas participer,  sans doute parce qu&rsquo;il aurait de fortes chances de les remporter ? (Brezinski ajoute, presque ironiquement par r\u00e9f\u00e9rence \u00e0 l&rsquo;incoh\u00e9rence de la politique du bloc BAO, l&rsquo;expression par chance,  \u00ab<em>The only solution is to seek Russia&rsquo;s and China&rsquo;s support for U.N.-sponsored elections in which,<\/em> <strong><em>with luck<\/em><\/strong><em>, Assad might be persuaded not to participate.<\/em>\u00bb) Implicitement, le constat nous conduit \u00e0 observer la situation de paralysie (embourbement crisique, certes) o\u00f9 se trouvent les USA. Si les Russes y \u00e9chappent en partie, c&rsquo;est bien entendu parce que leur politique est fond\u00e9e sur le respect de principes structurants, ce qui leur permet effectivement d&rsquo;\u00e9chapper \u00e0 l&rsquo;\u00e9touffement des pressions de la communication qui mordent essentiellement sur les positions affaiblies par la d\u00e9structuration.<\/p>\n<\/p>\n<p><p>\tBrzezinski pr\u00e9sente donc la guerre syrienne comme une guerre de sectes dans une r\u00e9gion volatile et explosive , guerre au potentiel d&rsquo;expansion vertigineux, dans laquelle les int\u00e9r\u00eats US d\u00e9j\u00e0 menac\u00e9s ne pourraient l&rsquo;\u00eatre que davantage si les USA intervenaient. Tous les sch\u00e9mas d&rsquo;interventions qu&rsquo;on a \u00e9voqu\u00e9s ne peuvent que faire empirer la situation, en la rendant plus complexe, plus mena\u00e7ante encore pour la position strat\u00e9gique des USA, estime-t-il. On ne peut que prier pour que les Russes et les Chinois, qui d\u00e9tiennent la clef de la crise, participent \u00e0 un effort pour permettre \u00e0 l&rsquo;ONU d&rsquo;obtenir une cessation des combats et l&rsquo;organisation d&rsquo;\u00e9lections, et prier encore un peu plus qu&rsquo;Assad soit convaincu de n&rsquo;y pas participer&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>&#8230;The struggle is between forces funded and armed by outside sponsors, notably Saudi Arabia, Qatar and Iran. Also participating are foreign religious groups not directly controlled by the sponsors, namely the Sunni Salafists and Iranian-aligned militias, not to mention intensely anti-Western al-Qaeda fighters. American involvement would simply mobilize the most extreme elements of these factions against the U.S. and pose the danger that the conflict would spill over into the neighborhood and set Jordan, Iraq and Lebanon on fire.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>That risk has been compounded by the recent Israeli bombing of weapons sites inside Syria. Whatever their justification, the attacks convey to some Arabs the sense that there is an external plot against them. That impression would be solidified if the U.S. were now to enter the fight, suggesting a de facto American-Israeli-Saudi alliance, which would play into the hands of the extremists.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Broader regional fighting could bring the U.S. and Iran into direct conflict, a potentially major military undertaking for the U.S. A U.S.-Iran confrontation linked to the Syrian crisis could spread the area of conflict even to Afghanistan. Russia would benefit from America&rsquo;s being bogged down again in the Middle East. China would resent U.S. destabilization of the region because Beijing needs stable access to energy from the Middle East.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>To minimize these potential consequences, U.S. military intervention would have to achieve a decisive outcome relatively quickly through the application of overwhelming force. That would require direct Turkish involvement, which seems unlikely given Turkey&rsquo;s internal difficulties, particularly its tenuous relations with its substantial Kurdish minority&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe Docteur Zbigniew Brzezinski semble \u00e9prouver une satisfaction presque sadique \u00e0 d\u00e9crire tous les verrous du d\u00e9sordre syrien garantissant cette situation de d\u00e9sordre du conflit, en ajoutant que la superpuissance US ne ferait qu&rsquo;ajouter quelques verrous de plus \u00e0 ce d\u00e9sordre en intervenant. Le vieux routier cynique et r\u00e9aliste de la politique ext\u00e9rieure US ne fait l\u00e0 que d\u00e9velopper sa condamnation constante de cette caricature absolue de l&rsquo;ordre international qu&rsquo;est devenue la politiquer ext\u00e9rieure, notamment et principalement celle des USA. Il le fait de concert avec son vieil ennemi, <em>alter ego<\/em> en, crapulerie, <a href=\"http:\/\/www.dedefensa.org\/article-la_syrie_fait_sortir_kissinger_de_ses_gonds_05_04_2012.html\" class=\"gen\">Henry Kissinger<\/a>, les deux hommes d\u00e9non\u00e7ant et ha\u00efssant l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-la_raison_devenue_idiote_utile_de_l_affectivit__11_06_2012.html\" class=\"gen\">affectivit\u00e9<\/a> et l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_infraresponsabilit__06_04_2013.html\" class=\"gen\">infraresponsabilit\u00e9<\/a> qui sont la r\u00e9f\u00e9rence constante de cette anti-politique d\u00e9velopp\u00e9e comme l&rsquo;un des facteurs principaux de la <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_la_politique-syst_me__17_11_2012.html\" class=\"gen\">politique-Syst\u00e8me<\/a> engendrant le d\u00e9sordre. Bien entendu, cela n&rsquo;\u00e9lude en rien leurs responsabilit\u00e9s pass\u00e9es (celles de Brzezinski et celle de Kissinger) dans l&rsquo;\u00e9tablissement des conditions qui ont conduit \u00e0 la situation actuelle,  par exemple et exemple d&rsquo;actualit\u00e9, Brzezinski comme <a href=\"http:\/\/www.dedefensa.org\/article-les_origines_du_d_sordre_pr_sent_par_brzezinski_en_janvier_1998_31_07_2005.html\" class=\"gen\">principal architecte<\/a> de la formation de cet artefact de la modernit\u00e9 naufrag\u00e9e qu&rsquo;est la <em>narrative<\/em> de l&rsquo;islamisme extr\u00e9miste ; mais cela leur donne une position critique, de connaisseur en quelque sorte, qui, dans les \u00e9pisodes d\u00e9pressifs comme celui qui se pr\u00e9cipite ces derniers jours, permet de mieux \u00e9clairer le champ de ruines et de mesurer l&rsquo;\u00e9tat de la psychologie.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 11 mai 2013 \u00e0 12H06<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les USA et la Syrie : phase d\u00e9pressive&#8230; La situation du bloc BAO, surtout des USA, vis-\u00e0-vis de la Syrie suit l&rsquo;habituel rythme qu&rsquo;on pourrait qualifier de maniaco-d\u00e9pressif tant cette posture psychologique caract\u00e9rise bien les perceptions humaines et le rythme des \u00e9v\u00e9nements dans cette \u00e9poque totalement d\u00e9pendante d&rsquo;une communication \u00e9crasante et incontr\u00f4lable. L&rsquo;attitude g\u00e9n\u00e9rale des&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[1235,1006,3903,12120,855,3736,2995,3867,11129],"class_list":["post-74978","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-biden","tag-brzezinski","tag-chimique","tag-embourbement","tag-kerry","tag-kissinger","tag-maniaco-depression","tag-syrie","tag-verrous"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74978"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74978\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}