{"id":74996,"date":"2013-05-22T04:21:24","date_gmt":"2013-05-22T04:21:24","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/05\/22\/les-tristes-records-de-dedefensaorg\/"},"modified":"2013-05-22T04:21:24","modified_gmt":"2013-05-22T04:21:24","slug":"les-tristes-records-de-dedefensaorg","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/05\/22\/les-tristes-records-de-dedefensaorg\/","title":{"rendered":"Les tristes records de <em>dedefensa.org<\/em>"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Les tristes records de <em>dedefensa.org<\/em><\/h3>\n<\/p>\n<p><p>\tLe <a href=\"http:\/\/www.dedefensa.org\/article-dedefensaorg_et_votre_solidarit__22_02_2013.html\" class=\"gen\">22 f\u00e9vrier 2013<\/a>, tr\u00e8s t\u00f4t le matin, nous publiions un message de <em>dedefensa.org<\/em> faisant \u00e9tat, d&rsquo;abord du message du mois pr\u00e9c\u00e9dent d&rsquo;un lecteur qui se voulait rassurant pour ce qui concernait la question de nos donation, qui nous conseillait \u00e9galement de nous \u00e9pargner ce pesant exercice mensuel (celui d&rsquo;\u00e9crire des messages comme celui que vous lisez en ce moment,  si vous le lisez). Nous poursuivions malheureusement ce pesant exercice mensuel en observant :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Nous ne demanderions que cela, sans aucun doute, de nous \u00e9pargner ce pesant exercice mensuel. Mais l\u00e0, pour l&rsquo;imm\u00e9diat qu&rsquo;est la situation de ce mois de f\u00e9vrier, les dieux n&rsquo;ont pas l&rsquo;air tr\u00e8s vraiment pr\u00e9occup\u00e9s de notre sort Pour faire bref : nous ne sommes jamais partis d&rsquo;aussi bas pour un 19 courant (365) ; nous n&rsquo;avons jamais aussi peu attir\u00e9 l&rsquo;attention des donateurs dans les trois jours suivant l&rsquo;affichage de la barre de donation, et il s&rsquo;en faut de beaucoup (de 365 le 18 f\u00e9vrier \u00e0 405 ce 22 f\u00e9vrier au matin)&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tNous parlions \u00e0 ce propos du \u00ab<em>seul et<\/em> [&#8230;] <em>froid argument comptable<\/em>\u00bb. C&rsquo;est toujours lui qui nous fait observer que notre record de f\u00e9vrier est battu en ce joli mois de mai puisque nous ne sommes jamais parti d&rsquo;aussi bas&rsquo;&#8230;, bla bla bla : 220 le 18 mai 2013, 309 le 22 mai 2013 au petit matin. Rien ne nous emp\u00eachera de remercier chaleureusement ceux qui sont intervenus dans cette donation du mois de mai. Pour les autres, pour le reste (la comptabilit\u00e9),  faites-vous vous-m\u00eames votre religion et pratiquez-la comme il vous plaira.<\/p>\n<\/p>\n<p><p>\tCette rubrique des diff\u00e9rents messages pour la donation mensuelle n&rsquo;est pas la plus roborative ni la plus excitante intellectuellement qu&rsquo;on puisse trouver sur le site. Elle n&rsquo;est pas \u00e9crite d&rsquo;une plume \u00e9clair\u00e9e par l&rsquo;intuition haute (dans tous les cas, au d\u00e9but des messages puisqu&rsquo;il nous arrive de trouver un peu d&rsquo;inspiration, chemin faisant). Elle ne suscite pas (ou plus, d&rsquo;ailleurs, car la chose a chang\u00e9) beaucoup de r\u00e9actions \u00e9crites, sinon des r\u00e9actions restrictives mais tr\u00e8s bien intentionn\u00e9es \u00e0 notre \u00e9gard ; pour nous dire que ces messages sont inutiles, qu&rsquo;on lit peu ces messages, ou qu&rsquo;on les zappe tout simplement, ou qu&rsquo;ils devraient \u00eatre plus saupoudr\u00e9s d&rsquo;humour (comme le fut, semble-t-il pour la perception de certains, celui du <a href=\"http:\/\/www.dedefensa.org\/article-de_la_crise_dedefensaorg_et_retour_22_04_2013.html\" class=\"gen\">22 avril 2013<\/a>). Bref, \u00e0 toutes ces occasions, <em>dedefensa.org<\/em> est jug\u00e9 et jaug\u00e9, dans son aspect le plus inint\u00e9ressant ; c&rsquo;est le privil\u00e8ge du lecteur, jusqu&rsquo;\u00e0 dire que c&rsquo;est notre propre privil\u00e8ge lorsque nous lisons nous-m\u00eames, \u00e0 diverses occasions de lecture, et nous n&rsquo;avons \u00e0 cet \u00e9gard, pour notre compte, aucun jugement \u00e0 signifier. (Quant \u00e0 en avoir un intimement, c&rsquo;est une autre affaire, qui est n\u00f4tre et que nous gardons pour nous-m\u00eames. Il n&rsquo;est d&rsquo;ailleurs aucunement assur\u00e9 que nous soyons nous-m\u00eames assur\u00e9s de ce jugement qui est, le plus souvent, trop d\u00e9pendant de l&rsquo;humeur.)<\/p>\n<\/p>\n<p><p>\tIl n&rsquo;est par contre pas sans int\u00e9r\u00eat de s&rsquo;int\u00e9resser \u00e0 l&rsquo;histoire de <em>dedefensa.org<\/em>, parce que nous pr\u00e9tendons avoir notre sp\u00e9cificit\u00e9, notre ambition, notre conception du monde, et que, par cons\u00e9quent, nous avons notre histoire. Le site fourmille de textes qui vous donnent des indications \u00e0 ce sujet, et la derni\u00e8re chronique du 19 courant&#8230;, ce <a href=\"http:\/\/www.dedefensa.org\/article-chronique_du_19_courant_journaliste_lui__19_05_2013.html\" class=\"gen\">19 mai 2013<\/a>, est pleine d&rsquo;indication \u00e0 cet \u00e9gard&#8230; Ainsi cette question, dont chacun devinera le sens \u00e0 sa fa\u00e7on : nos lecteurs veulent-ils \u00eatre simplement spectateurs de cette histoire, ou bien acteurs ? (Nous ne parlons pas des indiff\u00e9rents, des sans opinion et des ne sait pas, \u00e0 qui effectivement il serait d\u00e9plac\u00e9 d&rsquo;adresser de telles questions.) La r\u00e9ponse \u00e0 cette question se trouve dans la solidarit\u00e9 qu&rsquo;il leur importe peu d&rsquo;exprimer ou qu&rsquo;ils veulent au contraire exprimer. Dans ce cas, le mot solidarit\u00e9, qui r\u00e8gle selon ce qu&rsquo;on en fait le choix d&rsquo;\u00eatre spectateur ou acteur, a le don magique de changer l&rsquo;or vil dont nous avons besoin en un sentiment actif qui a peut-\u00eatre sa grandeur et qui nous est infiniment pr\u00e9cieux.<\/p>\n<\/p>\n<p><p>\tNous savons que ces temps sont \u00e0 la fois extr\u00eamement durs, cruels, si d\u00e9structurants qu&rsquo;ils touchent affreusement nos \u00e9quilibres psychologiques. Nous sommes m\u00eame persuad\u00e9s qu&rsquo;il y a un rapport entre ce que nous nommons la crise d&rsquo;effondrement du Syst\u00e8me et le comportement, disons presqu&rsquo;inconscient, de nos lecteurs (qui restent constants en nombre) vis-\u00e0-vis de causes publiques et d&rsquo;actes d&rsquo;engagement comme le soutien \u00e0 <em>dedefensa.org<\/em> est \u00e0 sa fa\u00e7on. Nous pensons que cette crise d&rsquo;effondrement est entr\u00e9e dans une phase psychologique nouvelle, aigue, depuis quelques mois, et que cela se refl\u00e8te de fa\u00e7on assez remarquable dans l&rsquo;aspect statistique de notre affaire de donation,  avec des interventions (financi\u00e8res, donc de solidarit\u00e9) de nos lecteurs beaucoup moins nombreuses, beaucoup plus contenues, beaucoup plus retenues,  essentiellement et <strong>soudainement<\/strong> depuis d\u00e9cembre 2012, o\u00f9 il nous est devenu tr\u00e8s difficile, comme l&rsquo;on dit d&rsquo;une fa\u00e7on peu engageante, de boucler nos fins de mois. (Nous parlons aussi bien du r\u00e9sultat final que de l&rsquo;\u00e9volution de la donation \u00e0 partir du 19 courant&#8230; et de nos messages d&rsquo;appel et de rappel.)<\/p>\n<\/p>\n<p><p>\tCe sentiment d&rsquo;un changement de tonalit\u00e9 de la crise ne concerne pas seulement le corps de ce message, il implique un jugement g\u00e9n\u00e9ral de notre part et il devrait faire l&rsquo;objet de l&rsquo;un ou l&rsquo;autre texte \u00e0 cet \u00e9gard, sur ce site. Il s&rsquo;agit de l&rsquo;observation que notre crise d&rsquo;effondrement, crise g\u00e9n\u00e9rale par d\u00e9finition, est effectivement entr\u00e9e dans une phase nouvelle, non pas sp\u00e9cifiquement d&rsquo;elle-m\u00eame mais dans la perception que nous en avons. (Le rapport entre les deux, rythme de la crise et notre perception, n&rsquo;est pas direct ni proportionn\u00e9 parce que la dynamique de la premi\u00e8re est constante mais dissimul\u00e9e [<a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_les_termites__10_04_2013.html\" class=\"gen\">les termites<\/a>] et que la seconde n&rsquo;y r\u00e9agit que par saccades.) Nous pensons que les psychologies, la psychologie collective touch\u00e9e par les effets des \u00e9v\u00e9nements et les impressions des grands courants m\u00e9tahistoriques, et par cons\u00e9quent les psychologies individuelles qui en recueillent elles-m\u00eames les effets secondaires par le biais du collectif, ont incub\u00e9 un fait nouveau. Il s&rsquo;agit bien entendu d&rsquo;un fait m\u00e9ritant des guillemets par rapport au sens commun subverti par le Syst\u00e8me et qui lui est hostile, puisque fait non exprim\u00e9 consciemment, et encore moins r\u00e9pandu dans le syst\u00e8me de la communication o\u00f9 les forces du Syst\u00e8me ont leurs positions et leurs <em>diktat<\/em>. Il s&rsquo;agit, \u00e0 notre estime qui est de l&rsquo;ordre de l&rsquo;intuitif, du fait de l&rsquo;in\u00e9luctabilit\u00e9 de cette crise, c&rsquo;est-\u00e0-dire le fait que cette crise est in\u00e9luctablement celle de l&rsquo;effondrement  effondrement du Syst\u00e8me, certes, mais effondrement tout court finalement, ou disons de fa\u00e7on plus symbolique la crise de la Chute.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit bien entendu d&rsquo;une analyse largement intuitive, mais qui implique une analyse sp\u00e9cifique de nombreux faits av\u00e9r\u00e9s. Son exposition ici extr\u00eamement rapide (nous en reprendrons le fil dans un autre cadre) est au moins la d\u00e9monstration contraire du sentiment que nous avions en commen\u00e7ant ce message ; avec la suggestion qu&rsquo;un tel message peut, effectivement, avoir un autre int\u00e9r\u00eat que celui assez pi\u00e8tre de la sollicitation ; peut-\u00eatre, m\u00eame, qu&rsquo;il peut contribuer \u00e0 transformer l&rsquo;or vil en un sentiment d&rsquo;une solidarit\u00e9 enrichissante au haut sens du mot&#8230;<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 22 mai 2013 \u00e0 04H15<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les tristes records de dedefensa.org Le 22 f\u00e9vrier 2013, tr\u00e8s t\u00f4t le matin, nous publiions un message de dedefensa.org faisant \u00e9tat, d&rsquo;abord du message du mois pr\u00e9c\u00e9dent d&rsquo;un lecteur qui se voulait rassurant pour ce qui concernait la question de nos donation, qui nous conseillait \u00e9galement de nous \u00e9pargner ce pesant exercice mensuel (celui d&rsquo;\u00e9crire&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[16],"tags":[3228,2981,7099,2651,2803,11966,7897,3014],"class_list":["post-74996","post","type-post","status-publish","format-standard","hentry","category-notre-situation","tag-crise","tag-dedefensa-org","tag-donations","tag-du","tag-effondrement","tag-hector","tag-solidarite","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74996"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74996\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}