{"id":75008,"date":"2013-05-28T05:25:55","date_gmt":"2013-05-28T05:25:55","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/05\/28\/une-loi-sur-la-transparence-bien-opaque\/"},"modified":"2013-05-28T05:25:55","modified_gmt":"2013-05-28T05:25:55","slug":"une-loi-sur-la-transparence-bien-opaque","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/05\/28\/une-loi-sur-la-transparence-bien-opaque\/","title":{"rendered":"Une loi sur la transparence bien opaque"},"content":{"rendered":"<p><h2 class=\"common-article2\">Une loi sur la transparence bien opaque<\/h2>\n<\/p>\n<p><p>\tL&rsquo;\u00e9pisode Cahuzac date de quelques semaines, il est quasiment oubli\u00e9 c&rsquo;est pourquoi il devient opportun de le consid\u00e9rer.<\/p>\n<\/p>\n<p><p>\tCe ne sera pas \u00e0 la mani\u00e8re subtile et gramscienne de <a href=\"http:\/\/www.monde-diplomatique.fr\/2013\/05\/KEUCHEYAN\/49087\" class=\"gen\">Razmig Keucheyan<\/a> quand il analyse la subversivisme&rsquo; de l \u00e9nonce journalistique qui aboutit \u00e0 une impasse politique.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit donc d&rsquo;un personnage public, en charge d&rsquo;une fonction minist\u00e9rielle.<\/p>\n<\/p>\n<p><p>\tIl dissimule des revenus qu&rsquo;il place dans un havre fiscal.<\/p>\n<\/p>\n<p><p>\tIl y a l\u00e0 d\u00e9j\u00e0 une double atteinte \u00e0 l&rsquo;int\u00e9r\u00eat public. Il prive la collectivit\u00e9 d&rsquo;une contribution et fait fructifier cette somme non d\u00e9clar\u00e9e par des fonds helv\u00e9tiques. Les banques suisses emploient une bonne part de ce que l&rsquo;on confie dans des pr\u00eats qu&rsquo;ils accordent aux \u00c9tats auxquels  manquent ces sommes \u00e0 leurs revenus fiscaux. Le contribuable fran\u00e7ais paie alors par l&rsquo; imp\u00f4t les int\u00e9r\u00eats sur ce dont la collectivit\u00e9 a \u00e9t\u00e9 priv\u00e9e.<\/p>\n<\/p>\n<p><p>\tL&rsquo;entorse \u00e0 la morale que constitue la d\u00e9n\u00e9gation du personnage confort\u00e9e par la passivit\u00e9 ou la connivence de ses coll\u00e8gues si elle a \u00e9t\u00e9 le motif majeur de l&rsquo;indignation publique serait presque anecdotique si elle ne venait pas recouvrir un fait majeur.<\/p>\n<\/p>\n<p><p>\tCe p\u00e9cule provient de r\u00e9mun\u00e9rations par des laboratoires pharmaceutiques pour services rendus par un ancien membre de cabinet d&rsquo;un Ministre de la sant\u00e9. Cette activit\u00e9 de conseil a g\u00e9n\u00e9r\u00e9 des honoraires suffisamment cons\u00e9quents au point qu&rsquo;un exc\u00e9dent \u00e9chappe au fisc.<\/p>\n<\/p>\n<p><p>\tUn chirurgien qui se consacre ensuite \u00e0 des implants capillaires n&rsquo;est pas un pharmacologue. Son assistance technique ne peut que relever de la facilitation des AMM, autorisations de mise sur le march\u00e9, et d&rsquo;aide \u00e0 obtenir l&rsquo;agr\u00e9ment du bon prix de vente de la mol\u00e9cule ou du dispositif m\u00e9dical.<\/p>\n<\/p>\n<p><p>\tL&rsquo;int\u00e9r\u00eat public s&rsquo;en trouve l\u00e9s\u00e9 une troisi\u00e8me fois, un arrangement sur le prix implique bien des d\u00e9bours plus importants pour les syst\u00e8mes de s\u00e9curit\u00e9 sociale, voire une quatri\u00e8me fois si l&rsquo;autorisation de mise sur le march\u00e9 est abusive.<\/p>\n<\/p>\n<p><p>\tEn 2009, \u00e0 l&rsquo;occasion d&rsquo;une \u00e9pid\u00e9mie de la grippe A H1N1, un Ministre de la Sant\u00e9 s&rsquo;est laiss\u00e9 berner.  Des fabricants de vaccins avaient assur\u00e9, appuy\u00e9s dans leurs pr\u00e9dictions par une pr\u00e9sidente de l&rsquo;OMS nullement ind\u00e9pendante, qu&rsquo;elle d\u00e9cimerait l&rsquo;humanit\u00e9. Le syst\u00e8me de sant\u00e9 fran\u00e7ais a d\u00e9pens\u00e9 quelques 400 millions d&rsquo;euros pour un vaccin dont ni l&rsquo;efficacit\u00e9 ni l&rsquo;inocuit\u00e9 n&rsquo;avait \u00e9t\u00e9 prouv\u00e9e. Le public avait alors per\u00e7u m\u00eame imparfaitement la l\u00e9g\u00e8ret\u00e9 des d\u00e9cideurs en mati\u00e8re de sant\u00e9 face \u00e0 la puissance des firmes pharmaceutiques. Quand elles ne corrompent pas, elles ont des moyens tr\u00e8s puissants de persuasion.<\/p>\n<\/p>\n<p><p>\tLe communiqu\u00e9 de l&rsquo;Acad\u00e9mie de m\u00e9decine de septembre 2004 qui concluait \u00e0 l&rsquo;absence de preuves validant l&rsquo;int\u00e9r\u00eat th\u00e9rapeutique des m\u00e9dicaments hom\u00e9opathiques, il recommandait leur d\u00e9remboursement. <\/p>\n<\/p>\n<p><p>\tLe Ministre d&rsquo;alors a refus\u00e9 de mettre en application cet avis fond\u00e9. Le syndicat des m\u00e9decins hom\u00e9opathes et  le laboratoire d&rsquo;importance mondiale sp\u00e9cialis\u00e9 dans cette branche avaient obtenu gain de cause. Face \u00e0 la v\u00e9rit\u00e9 certes relative de la science, les int\u00e9r\u00eats d&rsquo;une corporation et d&rsquo;une industrie qui vend de au mieux de l&rsquo;amidon et de l&rsquo;eau l&rsquo;ont emport\u00e9. Le principe de la prise en charge des patients par cette technique repose sur l&rsquo;hypoth\u00e8se qu&rsquo;une substance dilu\u00e9e un nombre tr\u00e8s important de fois est active. Les tenants de cette pratique se fondent encore sur une exp\u00e9rience publi\u00e9e par Nature en 1988 d\u00e9crite par une \u00e9quipe d&rsquo;immunologistes fran\u00e7ais. Des cellules immunitaires qui r\u00e9pondent normalement \u00e0 des signaux d\u00e9livr\u00e9s par des anticorps en solution r\u00e9agissent \u00e0 des concentrations ind\u00e9tectables de ces anticorps. \u00c9tait n\u00e9e la th\u00e9orie magique de la m\u00e9moire de l&rsquo;eau. Aucune \u00e9quipe n&rsquo;a pu la reproduire, ce qui laisse penser \u00e0 un artefact dans la proc\u00e9dure exp\u00e9rimentale. <\/p>\n<\/p>\n<p><p>\tL&rsquo;enseignement payant de la pratique hom\u00e9opathique, doctrine \u00e9rig\u00e9e en sp\u00e9cialit\u00e9 est assur\u00e9, par cet important laboratoire.<\/p>\n<\/p>\n<p><p>\tL&rsquo;exigence de la science qui devrait se baser sur des preuves est affaiblie, ramen\u00e9e au rang d&rsquo;une croyance. Un principe qui ne dit pas son m\u00e9canisme d&rsquo;action et qui n&rsquo;administre pas la preuve de son action n&rsquo;est pas un m\u00e9dicament, il peut au mieux \u00eatre consid\u00e9r\u00e9 comme un produit avec des vertus all\u00e9gu\u00e9es et ne devrait pas \u00eatre vendu en pharmacie.(selon la loi)<\/p>\n<\/p>\n<p><p>\tOn pouvait esp\u00e9rer un effet secondaire salvateur d&rsquo;abord du scandale en 2005 de l&rsquo;anti-inflammatoire Vioxx\u00ae du laboratoire Merk vendu comme non gastro-toxique et qui a \u00e9t\u00e9 responsable de plus de 100 000 d\u00e9c\u00e8s par atteinte des coronaires. \u00c9taient en cause l&rsquo;effacement frauduleux des effets secondaires lors de la pr\u00e9sentation des \u00e9tudes cliniques devant la commission de la FDA et surtout une absence de rigueur dans le contr\u00f4le des tests cliniques par des m\u00e9decins qui sont souvent consultants de ces firmes.<\/p>\n<\/p>\n<p><p>\tUne discipline accrue pouvait aussi \u00eatre exig\u00e9e de la part des pouvoirs publics aux laboratoires dans l&rsquo;\u00e9laboration de leurs protocoles apr\u00e8s la mise au jour en 2010 des effets de cette amph\u00e9tamine (le benfluorex) donn\u00e9e comme m\u00e9dicament amaigrissant des r\u00e9gimes antidiab\u00e9tiques.<\/p>\n<\/p>\n<p><p>\tIl pr\u00e9vaut une opacit\u00e9 totale dans les relations entre les firmes et les professionnels de sant\u00e9 qui de par leur rang universitaire et hospitalier influencent leurs confr\u00e8res dans leurs prescriptions.<\/p>\n<\/p>\n<p><p>\tLe d\u00e9cret relatif \u00e0  la loi sur la \u00ab s\u00e9curit\u00e9 du m\u00e9dicament \u00bb transparence en sant\u00e9 vient d&rsquo;\u00eatre publi\u00e9 le <a href=\"http:\/\/www.legifrance.gouv.fr\/affichTexte.do?cidTexte=JORFTEXT000027434029&#038;dateTexte=&#038;categorieLien=id\" class=\"gen\">22 mai 2013<\/a>.<\/p>\n<\/p>\n<p><p>\tIl ne permet pas de rendre publics les contrats pass\u00e9s entre les laboratoires et les acteurs de sant\u00e9 prestataires de service. Les conventions de ce type continuent d&rsquo;\u00eatre prot\u00e9g\u00e9es par le secret industriel et commercial. Leur existence n&rsquo;a pas \u00e0 \u00eatre signal\u00e9e par la firme qui r\u00e9mun\u00e8re un acteur de sant\u00e9 qui facture ses services. <\/p>\n<\/p>\n<p><p>\tIl est devenu banal de lire sur la premi\u00e8re page powerpoint d&rsquo;un expos\u00e9 scientifique la liste des liens d&rsquo;int\u00e9r\u00eat entre le conf\u00e9rencier et ceux qui le paient sans que les auditeurs s&rsquo;en offusquent ou \u00e9mettent des r\u00e9serves sur l&rsquo;objectivit\u00e9 du travail pr\u00e9sent\u00e9. Tous les grands et parfois plus petits communicateurs, les experts&rsquo; dans n&rsquo;importe quel congr\u00e8s m\u00e9dical  re\u00e7oivent des appointements des firmes.<\/p>\n<\/p>\n<p><p>\tEn revanche, et c&rsquo;est un bon acquis, les cadeaux faits aux m\u00e9decins et aux \u00e9tudiants dont il est d\u00e9montr\u00e9 qu&rsquo;ils influencent le porteur de stylo sont  rendus publics d\u00e8s le premier euro.<\/p>\n<\/p>\n<p><p>\tUne mani\u00e8re simple d&rsquo;exprimer le manque de substance de cette loi, c&rsquo;est de dire le cadeau est interdit mais pas l&#8217;emploi fictif.<\/p>\n<\/p>\n<p><p>\tPourquoi s&rsquo;insurger contre cette ambiance de corruption passive et active qui semble impr\u00e9gner tout le syst\u00e8me et devenue notre milieu ambiant ?<\/p>\n<\/p>\n<p><p>\tLe centre du contr\u00f4le et de pr\u00e9vention des maladies d&rsquo;Atlanta vient de publier une enqu\u00eate men\u00e9e sur la sant\u00e9 mentale des enfants entre 2005 et 2011. Un enfant sur cinq serait atteint de troubles des fonctions cognitives, sociales ou \u00e9motionnelles. C&rsquo;est une perturbation de l&rsquo;attention qui saurait \u00e9t\u00e9 le plus souvent d\u00e9couverte, devant l&rsquo;anxi\u00e9t\u00e9, la d\u00e9pression ou l&rsquo;autisme.<\/p>\n<\/p>\n<p><p>\tCette difficult\u00e9 de maintenir son attention est justiciable de traitement psychotrope, une amph\u00e9tamine-like,  qui sera administr\u00e9 \u00e0 vie, selon le code de bonnes pratiques en psychiatrie le fameux DSM, <em>Diagnostic and Statistical Manuel of Mental Disorders<\/em>.<\/p>\n<\/p>\n<p><p>\tQuelle sp\u00e9cificit\u00e9 ont les enfants des US(a) pour que se soit produite une telle \u00e9pid\u00e9mie ?<\/p>\n<\/p>\n<p><p>\tEst-ce g\u00e9n\u00e9ralisable \u00e0 la plan\u00e8te ?<\/p>\n<\/p>\n<p><p>\tQuelle est validit\u00e9 des \u00e9valuations psychologiques eu \u00e9gard \u00e0 l&rsquo;\u00e9normit\u00e9 du march\u00e9 potentiel et cette promesse d&rsquo;une camisole chimique pour tous?<\/p>\n<\/p>\n<p><p>\tTant que n&rsquo;est pas assur\u00e9e de fa\u00e7on au moins relative une ind\u00e9pendance entre les prescripteurs et les fabricants des m\u00e9dicaments, le soup\u00e7on et la vigilance sont  permis.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Badia Benjelloun<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une loi sur la transparence bien opaque L&rsquo;\u00e9pisode Cahuzac date de quelques semaines, il est quasiment oubli\u00e9 c&rsquo;est pourquoi il devient opportun de le consid\u00e9rer. Ce ne sera pas \u00e0 la mani\u00e8re subtile et gramscienne de Razmig Keucheyan quand il analyse la subversivisme&rsquo; de l \u00e9nonce journalistique qui aboutit \u00e0 une impasse politique. Il s&rsquo;agit&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3953,12058,12187],"class_list":["post-75008","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-benjelloun","tag-cahuzac","tag-medicaments"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75008"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75008\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}