{"id":75013,"date":"2013-05-30T04:52:29","date_gmt":"2013-05-30T04:52:29","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/05\/30\/lim-monde\/"},"modified":"2013-05-30T04:52:29","modified_gmt":"2013-05-30T04:52:29","slug":"lim-monde","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/05\/30\/lim-monde\/","title":{"rendered":"L&rsquo;im-monde"},"content":{"rendered":"<p><h2 class=\"common-article2\">L&rsquo;im-monde<\/h2>\n<\/p>\n<p><p>\tUn correspondant du quotidien vesp\u00e9ral fran\u00e7ais aurait \u00e9t\u00e9 t\u00e9moin de l&#8217;emploi d&rsquo;armes chimiques par l&rsquo;arm\u00e9e gouvernementale syrienne.<\/p>\n<\/p>\n<p><p>\tLa description des sympt\u00f4mes endur\u00e9s par les miliciens \u00ab rebelles \u00bb \u00e9voquent ceux produits par des gaz neurotoxiques.<\/p>\n<\/p>\n<p><p>\tSignes ophtalmologiques avec troubles visuels et une pupille r\u00e9tract\u00e9e&rsquo;, signes digestifs, vomissements et signes respiratoires d\u00e9crits comme raclements et suffocation.<\/p>\n<\/p>\n<p><p>\tLe r\u00e9cit, esp\u00e9r\u00e9 digeste gr\u00e2ce la petite touche litt\u00e9raire avec le petit bruit de la canette non pas sur le comptoir d&rsquo;\u00e9tain mais un certain cliquetis \u00e0 peine audible, produit des t\u00e9moignages de ces combattants et d&rsquo;un m\u00e9decin.<\/p>\n<\/p>\n<p><p>\tLe photographe du journal le Monde (en lettres gothiques) aurait souffert de troubles visuels et respiratoires durant plusieurs jours. Premi\u00e8re invraisemblance du r\u00e9cit : les gaz neurotoxiques utilis\u00e9s comme armes de guerre sont certes inodores et incolores, mais les signes digestifs sont sur le m\u00eame plan que les signes respiratoires. L&rsquo;antidote doit \u00eatre imm\u00e9diatement administr\u00e9 pour lever le blocage des terminaisons nerveuses sans quoi la paralysie est rapidement mortelle.<\/p>\n<\/p>\n<p><p>\tDeuxi\u00e8me incongruit\u00e9. L&rsquo;iconographie cens\u00e9e illustrer le texte montre un homme qui tente avec une seringue de prodiguer des instillations oculaires. Les effets des gaz neurotoxiques \u00e0 p\u00e9n\u00e9tration cutan\u00e9e et respiratoire n&rsquo;ont aucune chance d&rsquo;\u00eatre lev\u00e9s par des lavages oculaires. Ceux-ci ne peuvent soulager qu&rsquo;en cas de gaz irritants des muqueuses.<\/p>\n<\/p>\n<p><p>\tTroisi\u00e8me aberration. Le m\u00e9decin rebelle rapporte le cas d&rsquo;un combattant qui lui a \u00e9t\u00e9 confi\u00e9 avec un rythme cardiaque fou. Le blocage enzymatique qui conduit \u00e0 l&rsquo;accumulation du neurotransmetteur l&rsquo;ac\u00e9tylcholine induit surtout une bradycardie, et l&rsquo;hypotension majeure par absence du tonus vasculaire est l&rsquo;urgence absolue. On restitue une tension art\u00e9rielle inexistante avant de vouloir contr\u00f4ler un rythme cardiaque, m\u00eame aberrant, m\u00eame anarchique. Pour \u00eatre rigoureux une phase d&rsquo;hypertension avec tachycardie peut \u00eatre observ\u00e9e dans les premi\u00e8res minutes de l&rsquo;intoxication. Le d\u00e9lai n\u00e9cessaire pour transporter un patient jusqu&rsquo;\u00e0 un centre de secours \u00e0 travers le d\u00e9dale impos\u00e9 par une zone de guerre en milieu urbain exclut cette hypoth\u00e8se. Quatri\u00e8me anomalie. La consultation de n&rsquo;importe encyclop\u00e9die en ligne indique comme sympt\u00f4me cardinal des effets neurotoxiques les convulsions. Le sujet mortellement atteint suffoque dans un contexte de crises cloniques spectaculaires. Ce type de manifestations est si impressionnant que leur absence dans le roman permet de qualifier le r\u00e9cit de faux t\u00e9moignage.<\/p>\n<\/p>\n<p><p>\tL&rsquo;auteur \u00e0 la fin de son article prend une pr\u00e9caution rh\u00e9torique. Il \u00e9met la possibilit\u00e9 de l&rsquo;usage de plusieurs vari\u00e9t\u00e9s de gaz toxiques par l&rsquo;arm\u00e9e gouvernementale, solution \u00e9l\u00e9gante pour brouiller les pistes de l&rsquo;usage d&rsquo;un gaz mortel prohib\u00e9 qu&rsquo;il sugg\u00e8re fortement tout au long de son histoire tr\u00e8s arrang\u00e9e.<\/p>\n<\/p>\n<p><p>\tCependant, sensation de br\u00fblure oculaire et toux irritatives se rencontrent lors de l&rsquo;exposition \u00e0 des gaz lacrymog\u00e8nes. \u00c0 chaque dispersion de foules ou de manifestations par les CRS en France ou aux USA o\u00f9 l&rsquo;usage des gaz poivr\u00e9s conna\u00eet un regain, il faudra mobiliser la Cour europ\u00e9enne des Droits de l&rsquo;Homme.<\/p>\n<\/p>\n<p><p>\tLa publication de cet \u00e9pisode survient au moment o\u00f9 les pays incarc\u00e9r\u00e9s dans l&rsquo;Union Europ\u00e9enne ont d\u00e9cid\u00e9 de suspendre officiellement l&#8217;embargo sur la livraison des armes \u00e0 la r\u00e9bellion en Syrie.<\/p>\n<\/p>\n<p><p>\tElle est contemporaine \u00e9galement de la pr\u00e9paration des pourparlers en faveur d&rsquo;un Gen\u00e8ve II o\u00f9 devraient si\u00e9ger les \u00ab bellig\u00e9rants \u00bb et les pays qui les arment et sans lesquels cette confrontation du bloc occidental avec les int\u00e9r\u00eats de puissances dites \u00e9mergentes sur les d\u00e9combres de la souverainet\u00e9 de la Syrie n&rsquo;aurait pas lieu.<\/p>\n<\/p>\n<p><p>\tLe r\u00e9gime syrien est explicitement accus\u00e9 de crimes de guerre ou contre l&rsquo;humanit\u00e9 au moment o\u00f9 plus de 15 000 soldats des arm\u00e9es imp\u00e9riales occidentales et de leurs vassaux subissent un entra\u00eenement intense en Jordanie. Cette pr\u00e9paration anormale sur le plan num\u00e9rique indiquerait l&rsquo;imminence d&rsquo;une attaque type coalition contre l&rsquo;Irak.<\/p>\n<\/p>\n<p><p>\tD\u00e9j\u00e0, les effets d&rsquo;une diss\u00e9mination du conflit au Liban se font ressentir.<\/p>\n<\/p>\n<p><p>\tLes escarmouches autour plateau occup\u00e9 du Golan entre Isra\u00ebl et des combattants du c\u00f4t\u00e9 syrien signalent la possibilit\u00e9 d&rsquo;un autre front. Un char d&rsquo;assaut isra\u00e9lien y a \u00e9t\u00e9 r\u00e9cemment d\u00e9truit.<\/p>\n<\/p>\n<p><p>\tCe que redoutent le plus les rares strat\u00e8ges sionistes, c&rsquo;est l&rsquo;extension du chaos \u00e0 la Jordanie. La version officielle de la neutralit\u00e9 isra\u00e9lienne est une l\u00e9gende de fa\u00e7ade. Le soutien \u00e0 la r\u00e9bellion syrienne a pris de nombreuses formes, y compris sous celle d&rsquo;une assistance logistique et m\u00e9dicale. Au-del\u00e0 de leur crainte que des missiles russes S 300 soient op\u00e9rationnels aux mains de la d\u00e9fense de la souverainet\u00e9 syrienne, l&#8217;embrasement de la r\u00e9gion aura un impact civil non n\u00e9gligeable sur une population isra\u00e9lienne pr\u00eate \u00e0 \u00e9migrer en cas de danger. En cas de conflit militaire g\u00e9n\u00e9ralis\u00e9, l&rsquo;\u00c9tat-major sioniste n&rsquo;oublie pas que les discours de Sayed Hassan Nasrallah ne sont pas des rodomontades. Le Hezbollah doit disposer d&rsquo;un arsenal et d&rsquo;un entra\u00eenement convaincants.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Badia Benjelloun<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;im-monde Un correspondant du quotidien vesp\u00e9ral fran\u00e7ais aurait \u00e9t\u00e9 t\u00e9moin de l&#8217;emploi d&rsquo;armes chimiques par l&rsquo;arm\u00e9e gouvernementale syrienne. La description des sympt\u00f4mes endur\u00e9s par les miliciens \u00ab rebelles \u00bb \u00e9voquent ceux produits par des gaz neurotoxiques. Signes ophtalmologiques avec troubles visuels et une pupille r\u00e9tract\u00e9e&rsquo;, signes digestifs, vomissements et signes respiratoires d\u00e9crits comme raclements et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3953,3903,2711,2878,3867],"class_list":["post-75013","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-benjelloun","tag-chimique","tag-le","tag-monde","tag-syrie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75013"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75013\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}