{"id":75039,"date":"2013-06-13T11:34:55","date_gmt":"2013-06-13T11:34:55","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/06\/13\/leffondrement-systeme-de-sa-psychologie\/"},"modified":"2013-06-13T11:34:55","modified_gmt":"2013-06-13T11:34:55","slug":"leffondrement-systeme-de-sa-psychologie","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/06\/13\/leffondrement-systeme-de-sa-psychologie\/","title":{"rendered":"L&rsquo;effondrement-Syst\u00e8me de sa psychologie"},"content":{"rendered":"<p><h3 class=\"titrebloc\">L&rsquo;effondrement-Syst\u00e8me de sa psychologie<\/h3>\n<\/p>\n<p><p>\tVoici un document qui, \u00e0 la seule perception, \u00e0 la simple audition du ton, du rythme, du son enfin, m\u00eame sans qu&rsquo;il soit n\u00e9cessaire de comprendre le sens du discours (il est bien s\u00fbr en anglo-am\u00e9ricain), nous en dit plus que dix bouquins de psychologie politique, sur la d\u00e9ch\u00e9ance d&rsquo;un homme par l&rsquo;attaque contre sa psychologie, sur la destruction-Syst\u00e8me d&rsquo;un candidat brillant devenu un pr\u00e9sident \u00e9puis\u00e9, presque b\u00e9gayant. C&rsquo;est le site <em>LewRockwell.com<\/em>, de tendance libertarienne (pro-Ron Paul), qui a eu l&rsquo;id\u00e9e de faire ce montage. On met en parall\u00e8le, avec alternativement un extrait de chaque discours, un discours du candidat Obama le 7 ao\u00fbt 2007, sur le n\u00e9cessaire respect des lois et de la Constitution m\u00eame, et surtout dans la lutte contre le terrorisme, et le discours du pr\u00e9sident Obama du 7 juin 2013, tentant de justifier le programme PRISM qui vient d&rsquo;\u00eatre mis \u00e0 jour par Snowden, par l&rsquo;interm\u00e9diaire du <em>Guardian<\/em>, et qui fait bien entendu bon march\u00e9 des diverses lois et de la Constitution, dans le chef de son quatri\u00e8me amendement. Bien entendu, entre les deux discours, pour ce qui est du sens de la chose, on trouve sans grand \u00e9tonnement la plus compl\u00e8te contradiction.<\/p>\n<\/p>\n<p><p>\tVoici le texte de pr\u00e9sentation du montage, de Michael S. Rozeff, le <a href=\"http:\/\/www.lewrockwell.com\/blog\/lewrw\/archives\/139347.html\" class=\"gen\">12 juin 2013<\/a>, sur une vid\u00e9o \u00e9galement dat\u00e9e du <a href=\"http:\/\/www.lewrockwell.com\/blog\/lewrw\/archives\/139364.html\" class=\"gen\">12 juin 2013<\/a>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The video of Obama vs. Obama is extremely interesting. As a candidate, Obama spoke fluidly and quickly as if he were inspired and believed what he was saying, although this could have been inspired by attacking the opposition. As president, he is tired, terribly deliberate, holding back, speaking with more pauses (a long one right before he says One has to make a choice), choosing his words carefully, as if he is an aged and infirm man.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>As candidate, he praised constitutional guidelines and criticized false tradeoffs. As president, he embraces tradeoffs, explains them and says he has to make a choice, and he mentions it&rsquo;s also his team&rsquo;s choice. He now views himself, not as upholding the law, but as maximizing the social utility of the nation by choosing the best tradeoff between safety and the Constitution. This is an impossible task. It is equally impossible to control the economy, produce social welfare, and alleviate other ills through power politics.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The American system (and other systems of government worldwide) reflect impossible goals and impossible tasks required of political powers. In becoming president, the true beliefs of Obama surfaced, which were utilitarian. This is one reason why he sought the presidency and it&rsquo;s one reason why those who seek the presidency and attain it never keep their promises. Once in the office, they listen to the powers and advisors around them in order to implement their utilitarianism. They give in to the temptation to do good for the nation<\/em> <strong><em>as they see it<\/em><\/strong> <em>and in fact they&rsquo;ve been elected to do exactly that, and that&rsquo;s what&rsquo;s wrong to begin with. There is no way in the world that one man or a small body of them can promote the General welfare using power politics, not in the ways that it is construed in this day and age.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tNous laisserons de c\u00f4t\u00e9 l&rsquo;argumentation id\u00e9ologique qu&rsquo;on trouve dans les deux derniers paragraphes, qui sont d\u00e9velopp\u00e9s conform\u00e9ment \u00e0 l&rsquo;orientation du site (libertarien, adversaire d&rsquo;un \u00c9tat puissant, de l&rsquo;interventionnisme public, d\u00e9fenseur inconditionnel de la Constitution, etc.). Implicitement, c&rsquo;est, selon l&rsquo;argument id\u00e9ologique toujours, cette impossibilit\u00e9 de parvenir \u00e0 r\u00e9aliser ces ambitions \u00e9tatiques, ou ces ambitions par le biais de la puissance publique, qui expliquent l&rsquo;esp\u00e8ce d&rsquo;effondrement psychologique d&rsquo;Obama qu&rsquo;on per\u00e7oit au travers des diff\u00e9rences fulgurantes entre les deux discours ; et cette impossibilit\u00e9, du fait de t\u00e2ches impossibles \u00e0 accomplir parce qu&rsquo;une part trop grande est donn\u00e9e \u00e0 l&rsquo;\u00c9tat, qu&rsquo;on attend trop de l&rsquo;\u00c9tat, etc.<\/p>\n<\/p>\n<p><p>\tMais ces diff\u00e9rences sont fulgurantes et int\u00e9ressantes, pour nous, dans un premier temps non pas tant sur le fond du discours que dans le ton bien entendu, avec ici la conviction et l\u00e0 l&rsquo;absence totale de conviction ; avec ici l&rsquo;accent de la sinc\u00e9rit\u00e9 pleine d&rsquo;entrain (quels que soient les arguments, jusqu&rsquo;\u00e0 l&rsquo;int\u00e9r\u00eat politique, qui fondent cette sinc\u00e9rit\u00e9, la sinc\u00e9rit\u00e9 est l\u00e0), avec l\u00e0 le d\u00e9sint\u00e9r\u00eat complet pour ce qui pourrait \u00eatre consid\u00e9r\u00e9 comme de la sinc\u00e9rit\u00e9, voire m\u00eame le simulacre de la sinc\u00e9rit\u00e9 ; avec ici le parler clair et tranchant et l\u00e0 le parler embarrass\u00e9, h\u00e9sitant, parfois m\u00eame compl\u00e8tement absent avec des trous de 3 \u00e0 4 secondes. Si le second discours nous montre un Obama psychologiquement \u00e9puis\u00e9, ce n&rsquo;est pas tant parce qu&rsquo;il plaide le contraire de ce qu&rsquo;il plaidait 2007, mais parce qu&rsquo;il le plaide \u00e0 l&rsquo;aide de mensonges et d&rsquo;arguments compl\u00e8tement inconsistants que lui impose le Syst\u00e8me,  dans tous les cas, rien qui ne sorte de son propre jugement (pour \u00e9ventuellement alimenter ce qui serait alors sa propre conviction).<\/p>\n<\/p>\n<p><p>\tNous ne disons certainement pas qu&rsquo;Obama s&rsquo;aper\u00e7oit n\u00e9cessairement qu&rsquo;il y a mensonges, donc qu&rsquo;il ment consciemment et que cela serait la cause de sa fatigue psychologique ; nous irions m\u00eame jusqu&rsquo;\u00e0 penser que justement ce n&rsquo;est pas le cas, et que cela ne doit pas \u00eatre le cas. Notre appr\u00e9ciation est qu&rsquo;Obama porte inconsciemment le poids des mensonges et des inconsistances qui, in\u00e9vitablement, habillent et <strong>chargent de tout leur poids<\/strong> la <em>narrative<\/em> qu&rsquo;il est <strong>oblig\u00e9<\/strong> de d\u00e9velopper&#8230; Et s&rsquo;il est oblig\u00e9 de le faire, c&rsquo;est que la pression du Syst\u00e8me est irr\u00e9sistible pour lui, parce qu&rsquo;il ne s&rsquo;est pas mis en position de pouvoir lui r\u00e9sister, voire de la balayer, en adoptant une position que nous qualifierions de principielle, en s&rsquo;appuyant sur les principes qui fondent une l\u00e9gitimit\u00e9 et qui, seuls, donnent la force de r\u00e9sister aux pressions du Syst\u00e8me et de conserver une psychologie dynamique. (Obama n&rsquo;a pas \u00e9t\u00e9 l&rsquo;<em>American<\/em> <a href=\"http:\/\/www.dedefensa.org\/article-american_gorbatchev_29_10_2008.html\" class=\"gen\">Gorbatchev<\/a> qu&rsquo;on pouvait esp\u00e9rer qu&rsquo;il serait ; il n&rsquo;est pas non plus, \u00e9videmment, de la trempe d&rsquo;un de Gaulle, qui d\u00e9veloppe sa politique en s&rsquo;appuyant effectivement sur des principes et conforte sa conviction par la solidit\u00e9 in\u00e9branlable de ces principes : sauf en de rares occasions d&rsquo;erreurs tactiques, de Gaulle, \u00e0 70 ans pass\u00e9s, n&rsquo;a jamais l&rsquo;air de parler selon cet \u00e2ge, et son discours est effectivement d\u00e9tach\u00e9 des contraintes temporelles et physiques.)<\/p>\n<\/p>\n<p><p>\tAvec la comparaison de ces deux discours, aux dates o\u00f9 ils sont faits, Obama nous appara\u00eet \u00eatre comme un exemple impeccable d&rsquo;une psychologie victime du Syst\u00e8me, avec la paralysie que cela suppose pour les fonctions actives et cr\u00e9atrices de l&rsquo;esprit. Dans <em>La gr\u00e2ce de l&rsquo;Histoire<\/em>, nous d\u00e9veloppons l&rsquo;id\u00e9e que l&rsquo;action du Syst\u00e8me, notamment par son interm\u00e9diaire de la communication (syst\u00e8me de la communication), agit aujourd&rsquo;hui sur la psychologie de ceux qui sont proches de lui (le Syst\u00e8me) et sous son empire, exactement de la m\u00eame fa\u00e7on que le <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_notre_psychologie_28_01_2013.html\" class=\"gen\">persiflage<\/a> a fonctionn\u00e9 au XVIII\u00e8me si\u00e8cle aupr\u00e8s des psychologies des m\u00eames \u00e9lites, conduisant \u00e0 un affaiblissement extraordinaire de ces psychologie.<\/p>\n<\/p>\n<p><p>\tDans le cas d&rsquo;Obama illustr\u00e9 par les deux discours, on peut r\u00e9ellement parler d&rsquo;un effondrement de la psychologie, qui implique bien entendu comme effets induits la dissolution de toute conviction, l&rsquo;entropisation du parler refl\u00e9tant l&rsquo;absence compl\u00e8te de pens\u00e9e derri\u00e8re le propos par acceptation d&rsquo;un discours ext\u00e9rieur pour justifier des \u00e9v\u00e9nements (ici le r\u00e9seau PRISM, l&rsquo;architecture de surveillance et d&rsquo;oppression type <em>Stasi<\/em>-USA constitu\u00e9e avec la NSA, etc.). Les mots sont effectivement <strong>vid\u00e9s de leur sens<\/strong> parce que la psychologie est \u00e9puis\u00e9e et ne r\u00e9agit plus devant cette situation. (La fonction d&rsquo;une psychologie normale, alimentant une pens\u00e9e ainsi alert\u00e9e et agissant par cons\u00e9quent dans ce sens, \u00e9tant d&rsquo;ailleurs de rejeter un tel discours que celui que prononce Obama, ou plut\u00f4t qu&rsquo;il m\u00e2chonne en cherchant d\u00e9sesp\u00e9r\u00e9ment \u00e0 lui ins\u00e9rer quelque coh\u00e9rence.) Bien entendu, le discours est dict\u00e9 par le Syst\u00e8me,  que ce soit <em>my team<\/em> comme il dit, ou n&rsquo;importe quel scribouillard, ou sp\u00e9cialiste de la communication, \u00e0 partir d&rsquo;une fiche de la NSA vaguement tamponn\u00e9e et m\u00eame pas relue par un Alexander (directeur de la NSA) ou un Clapper (DNI) qui ont bien assez affaire \u00e0 se d\u00e9battre avec leurs propres divers mensonges prof\u00e9r\u00e9s depuis des mois, devant le Congr\u00e8s et sous serment, et dont les parlementaires commencent \u00e0 prendre ombrage. Tous ces personnages et toutes ces fonctions assurent un relais des impulsions du Syst\u00e8me vers le porte-voix qu&rsquo;est le pr\u00e9sident, et chacun, dans cette cha\u00eene, agissant par automatisme et sans vraiment r\u00e9aliser l&rsquo;importance, les causes et les effets de ce qui est fait. Au bout de la cha\u00eene, comme on le constate, le porte-voix est \u00e9puis\u00e9&#8230;<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 13 juin 2013 \u00e0 11H34<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;effondrement-Syst\u00e8me de sa psychologie Voici un document qui, \u00e0 la seule perception, \u00e0 la simple audition du ton, du rythme, du son enfin, m\u00eame sans qu&rsquo;il soit n\u00e9cessaire de comprendre le sens du discours (il est bien s\u00fbr en anglo-am\u00e9ricain), nous en dit plus que dix bouquins de psychologie politique, sur la d\u00e9ch\u00e9ance d&rsquo;un homme&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[7911,2631,9580,2685,3483,4369,4321,3871,6208,9839,12212,3099,12224],"class_list":["post-75039","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-conviction","tag-de","tag-epuisement","tag-gaulle","tag-gorbatchev","tag-mensonges","tag-narrative","tag-nsa","tag-obama","tag-persiflage","tag-prism","tag-psychologie","tag-snowden"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75039"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75039\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}