{"id":75040,"date":"2013-06-13T16:54:51","date_gmt":"2013-06-13T16:54:51","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/06\/13\/notes-sur-le-mensonge-le-moins-mensonger-possible\/"},"modified":"2013-06-13T16:54:51","modified_gmt":"2013-06-13T16:54:51","slug":"notes-sur-le-mensonge-le-moins-mensonger-possible","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/06\/13\/notes-sur-le-mensonge-le-moins-mensonger-possible\/","title":{"rendered":"Notes sur le mensonge \u201cle moins mensonger possible\u201d"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Notes sur le mensonge le moins mensonger possible<\/h3>\n<\/p>\n<p><p>\t13 juin 2013  Admirons, tout en ressentant les effets d&rsquo;un certain \u00e9puisement (mais d&rsquo;une saine fatigue, certes), le potentiel impressionnant de situations nouvelles qu&rsquo;engendre cette affaire NSA\/PRISM devenue NSA\/PRISM\/Snowden. Quand l&rsquo;on pense qu&rsquo;elle a \u00e9clat\u00e9 le 6 juin (date fatidique), on est confondu par la rapidit\u00e9 des choses, donc la vuln\u00e9rabilit\u00e9 extr\u00eame des composants du Syst\u00e8me \u00e0 toute pouss\u00e9e antiSyst\u00e8me de r\u00e9sistance.<\/p>\n<\/p>\n<p><p>\tEncore une fois, car nous ne cessons de le proclamer, la sortie publique de Snowden a compl\u00e8tement boulevers\u00e9 la s\u00e9quence. Elle a diversifi\u00e9 les centres d&rsquo;int\u00e9r\u00eats et de tension de l&rsquo;affaire. Elle a polaris\u00e9 l&rsquo;attention vers d&rsquo;autres points que le seul objet de la fuite.<\/p>\n<\/p>\n<p><p>\t&#8230; Disons, en avan\u00e7ant \u00e9ventuellement un n\u00e9ologisme contestable, que la sortie publique de Snowden, avec ses effets, a multipolaris\u00e9 une attention qui, au d\u00e9part, pouvait s&rsquo;av\u00e9rer manipulatrice, notamment dans le chef du Syst\u00e8me et de ses relais direction politique et presse-Syst\u00e8me, en appr\u00e9hendant et en att\u00e9nuant l&rsquo;effet obtenu, comme on a pu le craindre entre la publication des documents et l&rsquo;apparition publique de Snowden. Cette multipolarisation a d\u00e9structur\u00e9 et dissous cette attention \u00e0 potentialit\u00e9 contre-offensive du Syst\u00e8me dans le d\u00e9sordre des centres d&rsquo;int\u00e9r\u00eat et l&rsquo;a transform\u00e9e, en la mettant sur la d\u00e9fensive, en une perception d&rsquo;un \u00e9v\u00e9nement multiple impliquant tous les domaines et exer\u00e7ant une force d\u00e9stabilisantes contre les structures du Syst\u00e8me. <\/p>\n<\/p>\n<p><p>\tL&rsquo;humanisation de l&rsquo;affaire, par Snowden interpos\u00e9, a sollicit\u00e9 cet \u00e9clatement des centres d&rsquo;int\u00e9r\u00eat, et par cons\u00e9quent a transform\u00e9 un cas assez clair que le Syst\u00e8me pouvait ais\u00e9ment ma\u00eetriser en une confusion consid\u00e9rable. Cette confusion est bien entendu multipli\u00e9e par la formidable caisse de r\u00e9sonnance qu&rsquo;est le syst\u00e8me de la communication, puisque personne ne peut songer \u00e0 mettre frein \u00e0 cette pouss\u00e9e de la communication.<\/p>\n<h3>L&rsquo;effet Snowden au Congr\u00e8s<\/h3>\n<\/p>\n<p><p>\tAinsi constate-t-on la remarquable succession de phases diff\u00e9rentes, depuis l&rsquo;humanisation de l&rsquo;affaire. Il y a d\u00e9j\u00e0 trois phases depuis que l&rsquo;affaire PRISM\/NSA est devenue PRISM\/NSA\/Snowden.<\/p>\n<\/p>\n<p><p>\tCe week-end, c&rsquo;\u00e9tait la mobilisation contre le tra\u00eetre Snowden et pour l&rsquo;h\u00e9ro\u00efque <em>whistleblower<\/em>, selon ce qu&rsquo;on en a, qu&rsquo;on soit brave et appoint\u00e9 d\u00e9fenseur du Syst\u00e8me, qu&rsquo;on ait pour irr\u00e9sistible vocation d&rsquo;\u00eatre antiSyst\u00e8me comme l&rsquo;on respire. En d\u00e9but de semaine c&rsquo;\u00e9tait le constat de la politisation et de l&rsquo;internationalisation du cas Snowden, donnant aux pratiques de la NSA une nouvelle dimension qui concerne aussi bien la Russie (offrant l&rsquo;asile politique \u00e0 Snowden) que l&rsquo;Europe (protestant contre l&rsquo;espionnage et l&rsquo;\u00e9coute ill\u00e9gale \u00e9tendus \u00e0 la dimension transatlantique). Depuis hier, c&rsquo;est la col\u00e8re qui s&#8217;empare du Washington, particuli\u00e8rement au Congr\u00e8s.<\/p>\n<\/p>\n<p><p>\tCantonn\u00e9 dimanche dans le r\u00f4le du molosse furieux demandant la t\u00eate de Snowden, le Congr\u00e8s s&rsquo;est avis\u00e9 du contenu des r\u00e9v\u00e9lations publi\u00e9es par le <em>Guardian<\/em>, et venues de Snowden. Il s&rsquo;est soudain interrog\u00e9 sur elles. (On notera qu&rsquo;il ne semblait pas y songer, ou d&rsquo;une fa\u00e7on beaucoup moins urgente, par cons\u00e9quent beaucoup moins agressive, entre le 6 et le 9 juin, jour de l&rsquo;apparition de Snowden&#8230; Toujours l&rsquo;effet-Snowden.)<\/p>\n<h3>Vari\u00e9t\u00e9s exotiques du langage<\/h3>\n<\/p>\n<p><p>\t&#8230; Donc, le Congr\u00e8s s&rsquo;est ru\u00e9 sur les auditions urgentes et sous serment des responsables du renseignement et de la NSA, et d\u00e9couvre des vari\u00e9t\u00e9s exotiques du langage humain, cat\u00e9gorie-Syst\u00e8me ; les mensonges semi-mensongers, ou bien les moins mensongers possibles, les v\u00e9rit\u00e9s pas tout \u00e0 fait vraies mais tout de m\u00eame, etc. Ces dirigeants sont contraints d&rsquo;\u00e9mettre ces diverses fantaisies parce qu&rsquo;eux-m\u00eames sont totalement d\u00e9pass\u00e9s par les activit\u00e9s du monstre qu&rsquo;ils sont cens\u00e9s diriger, qui en fait les manipule et les soumet \u00e0 des contraintes dialectiques extraordinaires.<\/p>\n<\/p>\n<p><p>\tLes gens du Congr\u00e8s, eux, d\u00e9couvrent des ab\u00eemes nouveaux sous la forme des organisations qu&rsquo;ils sont cens\u00e9es contr\u00f4ler et dont ils ne connaissent rien,  soit pour cause de somnolence durant les auditions, soit parce qu&rsquo;ils furent victimes de r\u00e9tentions d&rsquo;informations. D&rsquo;o\u00f9 des explosions de fureur vertueuse, l&rsquo;objet de leur col\u00e8re passant d&rsquo;un Snowden qui r\u00e9v\u00e8le les turpitudes du Syst\u00e8me, aux Clapper et Cie, responsables de la mise en place de ces turpitudes. Ils sont tous coinc\u00e9s entre la pompe et le d\u00e9corum de l&rsquo;apparence du Syst\u00e8me (d\u00e9clarations dithyrambiques, serments devant le Congr\u00e8s, etc.) et l&rsquo;impossibilit\u00e9 ontologique de r\u00e9concilier les effrayantes activit\u00e9s du monstre (NSA &#038; Cie) dont il importe de dire quelques v\u00e9rit\u00e9s qui ne soient pas trop mensong\u00e8res. Qui en sait le moins et qui ment le plus, qui comprend et qui cherche \u00e0 comprendre ? Partout, les mains dans le sac&#8230;<\/p>\n<h3>Le quatre v\u00e9rit\u00e9s du d\u00e9put\u00e9 Pascrell<\/h3>\n<\/p>\n<p><p>\tOn trouve bien r\u00e9sum\u00e9e l&rsquo;atmosph\u00e8re washingtoniennes, avec relais vers le Congr\u00e8s, dans ces d\u00e9clarations path\u00e9tiques et furieuses \u00e0 la fois du d\u00e9put\u00e9 d\u00e9mocrate (le parti du pr\u00e9sident) Bill Pascrell, du New Jersey, sortant d&rsquo;une audition de James Clapper, du directeur du renseignement (Director, National Intelligence, ou DNI), qui supervise toutes les agences de renseignement. (Voir le <em>Guardian<\/em> du <a href=\"http:\/\/www.guardian.co.uk\/world\/2013\/jun\/12\/anger-mounts-congress-telephone-surveillance-programmes\" class=\"gen\">12 juin 2013<\/a>.) <\/p>\n<\/p>\n<p><p>\tPascrell nous dit que, selon le DNI, nombre d&rsquo;informations (sur NSA\/PRISM) se trouvent dans une lettre de la NSA envoy\u00e9e au Congr\u00e8s en 2011. Ni ses coll\u00e8gues ni lui-m\u00eame ne l&rsquo;ont jamais lue parce qu&rsquo;il semble bien qu&rsquo;on ne le leur a jamais communiqu\u00e9e ; tout le reste \u00e0 l&rsquo;avenant&#8230; D&rsquo;o\u00f9 sa conclusion : Il est juste que les citoyens soient inform\u00e9s, mais on devrait commencer par nous informer, nous, au Congr\u00e8s<\/p>\n<\/p>\n<p><p>\t\u00ab<em>There was a letter that we were supposed to have received in 2011 but I can&rsquo;t find it and most of my friends in Congress did not receive this either, said New Jersey Democrat Bill Pascrell, who claimed the widespread collection of phone data amounted to spying on Americans  This is one of the first briefings I have been to where I actually learned something. People should know what&rsquo;s going on in their name but we need to start with Congress knowing what the heck is going on.<\/em>\u00bb<\/p>\n<h3>Clapper, virtuose du mensonge le moins mensonger possible<\/h3>\n<\/p>\n<p><p>\tIl faut dire que les performances des malheureux chefs du renseignement US sont r\u00e9v\u00e9latrices du d\u00e9sordre extraordinaire o\u00f9 ils se trouvent plac\u00e9s. Ils sont les repr\u00e9sentants d&rsquo;un monstre insatiable, prog\u00e9niture directe du Syst\u00e8me, qui d\u00e9vore tout sous ses exigences et ne peut avoir par d\u00e9finition la moindre limite,  le monstre veut <strong>tout<\/strong>, pour <strong>toujours<\/strong> Selon Gus Hunt, directeur des programmes technologiques \u00e0 la CIA : \u00ab<em>We fundamentally try to collect everything and hang onto it forever.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe directeur national du renseignement (DNI), James Clapper, est en premi\u00e8re ligne. C&rsquo;est le virtuose de plus en plus \u00e9puis\u00e9 et accabl\u00e9 du demi-mensonge \u00e0 moiti\u00e9 vrai, du mensonge le moins mensonger possible, de la r\u00e9ponse sous serment la moins mensong\u00e8re possible et ainsi de suite,  tout cela pour qualifier ses diverses d\u00e9positions pr\u00e9c\u00e9dentes que s\u00e9nateurs et d\u00e9put\u00e9s lui mettent \u00e0 pr\u00e9sent sous le nez, \u00e0 la lumi\u00e8re des r\u00e9v\u00e9lations de Snowden. Le <em>Guardian<\/em> du <a href=\"http:\/\/www.guardian.co.uk\/world\/2013\/jun\/12\/james-clapper-intelligence-chief-criticism\" class=\"gen\">12 juin 2013<\/a> nous informe de cela, de Clapper qui r\u00e9pond souvent non aux demandes d&rsquo;information parce que c&rsquo;est \u00ab<em>the most truthful, or least untruthful manner<\/em> [<em>to answer<\/em>]\u00bb.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>It now appears clear that the director of national intelligence, James Clapper, lied under oath to Congress and the American people, <\/em>[<em>Justin Amash a House&rsquo; Michigan Republican<\/em>] <em>posted on Wednesday morning. Members of Congress can&rsquo;t make informed decisions on intelligence issues when the head of the intelligence community wilfully makes false statements. Perjury is a serious crime. Mr Clapper should resign immediately.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>At a hearing of the Senate intelligence committee on 12 March, Oregon Democrat Ron Wyden grew frustrated that he could not get a direct answer from Clapper about a question Wyden said he had been posing to the intelligence agencies in a series of letters for a year: when do US spies need a warrant to surveil Americans&rsquo; communications? What I wanted to see is if you could give me a yes or no answer to the question: does the NSA collect any type of data at all on millions or hundreds of millions of Americans? Wyden asked Clapper. No, sir, Clapper said. Not wittingly. There are cases where they could inadvertently, perhaps, collect, but not wittingly.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Clapper&rsquo;s claim to Congress was undermined by an April order of the secretive Fisa court instructing Verizon to turn over phone records on millions of Americans to the National Security Agency. Published by the Guardian, the order explicitly authorized the NSA to collect so-called metadata between the United States and abroad; or wholly within the United States, including local telephone calls. An NSA data-mining program, called Boundless Informant and also revealed by the Guardian, further allows the NSA to sort its collected communications by country of origin. Clapper defended himself in a surprising way. He told NBC&rsquo;s Andrea Mitchell this week that the question was unfair, akin to asking him when he was going to stop beating his wife. So I responded in what I thought was the most truthful, or least untruthful manner by saying no, Clapper said.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Clapper is in danger of becoming a meme signifying government deception about surveillance. The hashtag Clapper on Twitter is filled with acerbic tweets mocking the least untruthful line. On Tuesday, Fred Kaplan of Slate said Obama needed to fire Clapper for untruthfulness, a conclusion echoed by James Fallows of the Atlantic. Wyden, the senator who posed the question to Clapper, all but called the director of national intelligence a liar&#8230;<\/em>\u00bb<\/p>\n<h3>Le g\u00e9n\u00e9ral Alexander, ou la vertu de la NSA<\/h3>\n<\/p>\n<p><p>\tPassons \u00e0 une autre vedette du <em>show<\/em>, un virtuose du non. Le chef de la NSA, le g\u00e9n\u00e9ral Alexander, a, en bon militaire, adopt\u00e9 une tactique d\u00e9fensive h\u00e9rit\u00e9e du football italien d&rsquo;antant  : on b\u00e9tonne C&rsquo;est non partout ! Snowden ment, les documents mentent, le <em>Guardian<\/em> ment, la NSA ne peut pas mentir <\/p>\n<\/p>\n<p><p>\tTiens, mieux encore : la NSA d\u00e9fend les libert\u00e9s civiles et la vie priv\u00e9e des citoyens, oui-oui, mais on ne peut malheureusement en donner la preuve flagrante parce que, \u00f4 malheur, c&rsquo;est <em>classified<\/em>, class\u00e9 <em>top secret<\/em>, <em>cosmic<\/em>, etc. Justement ! C&rsquo;est en gardant tout cela <em>top secret<\/em>&#8211;<em>cosmic<\/em> que la NSA d\u00e9fend les libert\u00e9s civiles et la vie priv\u00e9e des citoyens, alors on ne peut rien d\u00e9classifier de tout cela pour d\u00e9-montrer la vertu de la NSA car ce serait mettre cette vertu en p\u00e9ril, et par cons\u00e9quent mettre en p\u00e9ril les libert\u00e9s civiles et la vie priv\u00e9es des gens&#8230; Alexander a r\u00e9invent\u00e9 le mouvement perp\u00e9tuel dans la boucle boucl\u00e9e, mont\u00e9 sur une sc\u00e8ne class\u00e9e <em>top secret<\/em>&#8211;<em>cosmic<\/em>, dans un th\u00e9\u00e2tre de l&rsquo;absurde sans d\u00e9but ni fin, avec acc\u00e8s par une galerie de miroirs d\u00e9formants garnie de prismes, ou PRISM. (Dans <em>Russia Today<\/em>, le <a href=\"http:\/\/rt.com\/usa\/nsa-terror-attack-prevented-597\/\" class=\"gen\">12 juin 2013<\/a>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Wednesday&rsquo;s hearing on the Hill was scheduled to focus heavily on Alexander&rsquo;s role with protecting the US cyber infrastructure, but the NSA scandal exposed less than a week earlier took center stage shortly after the general finished reading his opening remarks and Sen. Leahy began grilling him over a leaked program called PRISM and another surveillance operation that intercepts the online communications of US citizens. Soon other lawmakers joined in, using the opportunity to speak with the Obama administration cyber czar about PRISM and other claims made by 29-year-old NSA leaker Edward Snowden, including that he could wiretap anyone, from you or your account to a federal judge to even the president from the NSA&rsquo;s systems. False, Alexander answered Congress of the allegation. I know of no way to do that.<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Later in the hearing, Sen. Mark Udall (D-Oregon) asked Alexander if he could ensure the NSA cooperates with any investigation into possible civil liberties or privacy violations caused by the surveillance programs, a request of which the general answered in the affirmative  but not before rejecting allegations of abuse. I think you bring up a very important point here, because I do think what we&rsquo;re doing protects Americans&rsquo; civil liberties and privacy, Alexander said. To date, we have not been able to explain it because it&rsquo;s classified. How do we explain this and still keep this nation secure? That&rsquo;s the issue that we have in front of us.<\/em>\u00bb<\/p>\n<h3>La NSA contre la Terreur : tout \u00e7a pour \u00e7a ?<\/h3>\n<\/p>\n<p><p>\tQuelle \u00e9norme affaire ! dirait-on. Et pourtant&#8230; Et pour quoi, finalement ? On veut dire : tout \u00e7a pour \u00e7a ? En effet, le <em>Guardian<\/em>, toujours lui, nous entretient des r\u00e9sultats obtenus par les voies et moyens du monstre am\u00e9ricaniste, NSA-CIA et le reste, et leur super technologies. Apr\u00e8s tout, la premi\u00e8re cause fondamentale de ce d\u00e9veloppement monstrueux des moyens de surveillance, l&rsquo;a \u00e9t\u00e9 pour stopper et an\u00e9antir le terrorisme. Certains contesteront ce sch\u00e9ma, mais cela n&rsquo;importe pas ici. D&rsquo;abord, nous parlons de ce qui doit \u00eatre, de la <em>narrative<\/em> officielle, de ce qui importe au Congr\u00e8s ; ensuite, nous croyons que, m\u00eame s&rsquo;il y a des arri\u00e8re-pens\u00e9es, le but de tout le processus de renforcement de la <em>Stasi-of-America<\/em> fut bien, d&rsquo;abord, et reste malgr\u00e9 tout, de lutter contre le terrorisme, contre la Terreur&#8230; Et le r\u00e9sultat est simple dans sa nettet\u00e9, presque la nettet\u00e9 du rien.<\/p>\n<\/p>\n<p><p>\tLe <em>Guardian<\/em>, donc, d\u00e9taille cela, ce <a href=\"http:\/\/www.guardian.co.uk\/world\/2013\/jun\/12\/nsa-surveillance-data-terror-attack\" class=\"gen\">12 juin 2013<\/a>. Il appara\u00eet que les quelques r\u00e9sultats obtenus, dans telle ou telle affaire de complot terroriste d\u00e9jou\u00e9, le furent, non pas du fait, pour l&rsquo;essentiel, de la NSA &#038; Cie avec leurs super-technologies de surveillance mais par l&rsquo;action d&rsquo;\u00e9quipes des SR US et britanniques op\u00e9rant selon les bonnes vieilles recettes du renseignement Par renseignement humain (<em>HumInt<\/em>), infiltration, etc.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Lawyers and intelligence experts with direct knowledge of two intercepted terrorist plots that the Obama administration says confirm the value of the NSA&rsquo;s vast data-mining activities have questioned whether the surveillance sweeps played a significant role, if any, in foiling the attacks.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The defence of the controversial data collection operations, highlighted in a series of Guardian disclosures over the past week, has been led by Dianne Feinstein, chairwoman of the Senate intelligence committee, and her equivalent in the House, Mike Rogers. The two politicians have attempted to justify the NSA&rsquo;s use of vast data sweeps such as Prism and Boundless Informant by pointing to the arrests and convictions of would-be New York subway bomber Najibullah Zazi in 2009 and David Headley, who is serving a 35-year prison sentence for his role in the 2008 Mumbai attacks.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Rogers told ABC&rsquo;s This Week that the NSA&rsquo;s bulk monitoring of phone calls and internet contacts was central to intercepting the plotters. I can tell you, in the Zazi case in New York, it&rsquo;s exactly the programme that was used, he said. A similar point was made in anonymous briefings by administration officials to the New York Times and Reuters.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But court documents lodged in the US and UK, as well as interviews with involved parties, suggest that data-mining through Prism and other NSA programmes played a relatively minor role in the interception of the two plots. Conventional surveillance techniques, in both cases including old-fashioned tip-offs from intelligence services in Britain, appear to have initiated the investigations&#8230;<\/em>\u00bb<\/p>\n<h3>Tiens, que pense le citoyen ordinaire ?<\/h3>\n<\/p>\n<p><p>\tLe d\u00e9sordre n&rsquo;\u00e9pargne pas les sondages qui semblent ne plus rien vouloir dire dans les r\u00e9sultats qu&rsquo;ils donnent,  contradictoires et confus. Mais tout cela est logique, quoi qu&rsquo;il en soit. Ils donnent, ces sondages, par ces contradictions et cette confusion, une parfaite image du d\u00e9sordre washingtonien qui se retrouve \u00e9videmment dans le sentiment de celui que les sondeurs d\u00e9signent comme l&rsquo;Am\u00e9ricain ordinaire (<em>ordinary Americans<\/em>).<\/p>\n<\/p>\n<p><p>\t Ainsi, le <a href=\"http:\/\/www.rasmussenreports.com\/public_content\/politics\/general_politics\/june_2013\/59_oppose_government_s_secret_collecting_of_phone_records\" class=\"gen\">9 juin 2013<\/a>, un sondage de l&rsquo;institut Rasmussen, honorablement connu, nous dit que 59% des citoyens s&rsquo;opposent aux pratiques gouvernementales de la collecte secr\u00e8te des conversations t\u00e9l\u00e9phoniques, contre 26% qui s&rsquo;en satisfont.<\/p>\n<\/p>\n<p><p>\t Le <a href=\"http:\/\/www.people-press.org\/2013\/06\/10\/majority-views-nsa-phone-tracking-as-acceptable-anti-terror-tactic\/\" class=\"gen\">10 juin 2013<\/a>, une enqu\u00eate du non moins honorable institut <em>PEW Research<\/em> (diffus\u00e9e par le Washington <em>Post<\/em>), nous dit que 56% des Am\u00e9ricains jugent le programme de la NSA d&rsquo;\u00e9coute des conversations t\u00e9l\u00e9phoniques acceptable s&rsquo;il\/puisqu&rsquo;il s&rsquo;agit d&rsquo;enqu\u00eater sur des terroristes, contre 41% qui le jugent inacceptable. (A noter que, plus loin dans cette enqu\u00eate fouill\u00e9e, on trouve 45% pour approuver la m\u00eame pratique de surveillance et d&rsquo;espionnage de l&rsquo;internet, mais 52% qui la condamnent, soit un r\u00e9sultat contradictoire du pr\u00e9c\u00e9dent.) <\/p>\n<\/p>\n<p><p>\t Le <a href=\"http:\/\/www.cbsnews.com\/8301-250_162-57588748\/most-disapprove-of-govt-phone-snooping-of-ordinary-americans\/\" class=\"gen\">11 juin 2013<\/a>, voil\u00e0 un sondage CBS.<em>News<\/em>, bien connu et sans doute honorable, pour nous dire que 58% des gens interrog\u00e9s d\u00e9sapprouvent ces pratiques d&rsquo;\u00e9coute et de surveillance des Am\u00e9ricains ordinaires, contre 30% qui approuvent. Pourtant l&rsquo;on apprend du m\u00eame sondage que 75% des personnes interrog\u00e9es approuvent ces pratiques si elles s&rsquo;exercent contre des personnes suspectes d&rsquo;activit\u00e9s terroristes&#8230; Voil\u00e0 qui est int\u00e9ressant et \u00e9claire notre lanterne. Le probl\u00e8me devient alors de savoir ce que l&rsquo;on en juge ; et si la NSA, elle, juge que tout Am\u00e9ricain ordinaire est, d&rsquo;une mani\u00e8re potentielle, une personne suspecte d&rsquo;activit\u00e9s terroristes. Les instituts de sondages vont donc d\u00e9sormais s&rsquo;attacher \u00e0 demander aux Am\u00e9ricains ordinaires combien d&rsquo;Am\u00e9ricains exactement sont ordinaires, pour mieux d\u00e9terminer la signification des r\u00e9sultats de ce dernier sondage qui pr\u00e9tendrait nous \u00e9clairer en mettant de l&rsquo;ordre dans le d\u00e9sordre des esprits.<\/p>\n<\/p>\n<p><p>\t&#8230;Tout cela se fait et se dit sous le regard de pierre d&rsquo;Abraham Lincoln.<\/p>\n<h3>Une v\u00e9rit\u00e9 de situation<\/h3>\n<\/p>\n<p><p>\tQu&rsquo;on pardonne cette remarque impromptue, qui se comprendra mieux plus loin, mais il nous semble fixer l&rsquo;enjeu des choses en nous pla\u00e7ant sous le patronage de la pierre imm\u00e9moriale de l&rsquo;immense sculpture du grand pr\u00e9sident qu&rsquo;on trouve \u00e0 son M\u00e9morial, comme dans certaines de ses paroles pr\u00e9monitoires. Le spectacle de Washington, depuis deux jours, sous le silence assourdissant du premier pr\u00e9sident Africain-Am\u00e9ricain qui ne sait que dire pour porter l&rsquo;anath\u00e8me contre un gamin de 29 ans r\u00e9fugi\u00e9 \u00e0 Hong Kong, est celui d&rsquo;une capitale d&rsquo;un empire immense totalement prisonnier de lui-m\u00eame, c&rsquo;est-\u00e0-dire du Syst\u00e8me. L&rsquo;angoisse d\u00e9pressive de Lincoln qui est un fait historique important, r\u00e9pond \u00e0 leur hyst\u00e9rie hypomaniaque, restituant ainsi symboliquement la <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_maniaco-depression_du_monde_ddecrisis_19_01_2012.html\" class=\"gen\">maniaco-d\u00e9pression<\/a> caract\u00e9ristique du <em>sapiens<\/em> soumis aux exigences monstrueuses du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tLes agitations qu&rsquo;on d\u00e9crit plus haut, qui semblent \u00eatre celles de la vertu outrag\u00e9e des pompeux membres du Congr\u00e8s, qui feraient sourire en un premier mouvement o\u00f9 l&rsquo;on songe \u00e0 cet empilement de cynisme, de corruption, d&rsquo;asservissement au Syst\u00e8me qu&rsquo;ils constituent, n&rsquo;en restituent pas moins, jug\u00e9es en un second mouvement de la pens\u00e9e, une <strong>v\u00e9rit\u00e9<\/strong> indubitable. Il est vrai que l&rsquo;apparat du Syst\u00e8me, le d\u00e9corum et la pompe, impliquent une apparence de vertu qui est leur sentiment de sauvegarde pour supporter le poids \u00e9crasant des turpitudes de leur asservissement. Ainsi se comprend-il que la fureur initiale, cruelle et vengeresse, contre le jeune <em>whistleblower<\/em>, se mue soudain en une col\u00e8re \u00e9pouvantable contre les soi-disant chefs de la structure oppressive, ou <em>Stasi-of-America<\/em>, que Snowden d\u00e9nonce.<\/p>\n<\/p>\n<p><p>\tEn un sens, litt\u00e9ralement, ils la <strong>d\u00e9couvrent<\/strong>, et l&rsquo;on finirait par croire que l&rsquo;\u00e9norme fuite de Snowden leur est d&rsquo;abord destin\u00e9s, \u00e0 eux les membres du Congr\u00e8s. \u00ab<em>There was a letter that we were supposed to have received in 2011 but I can&rsquo;t find it and most of my friends in Congress did not receive this either !<\/em>\u00bb : de qui se moque-t-on ? s&rsquo;exclame le d\u00e9put\u00e9 Pascrell. Et tout cela, alors que ces chefs de cette <em>Stasi-of-America<\/em> pr\u00eatent serment chaque fois qu&rsquo;ils t\u00e9moignent devant le Congr\u00e8s ! Et ceux-l\u00e0 ont install\u00e9, ou plut\u00f4t laiss\u00e9 s&rsquo;installer, cette <em>Stasi-of-America<\/em> qui menace la libert\u00e9 et la Constitution ! Aussi invraisemblable que cela pourrait para\u00eetre, nous croirions volontiers que cette col\u00e8re n&rsquo;est pas feinte, et que leur horreur devant la <em>Stasi-of-America<\/em> ne l&rsquo;est pas moins.<\/p>\n<h3>Une Am\u00e9rique immens\u00e9ment fragile<\/h3>\n<\/p>\n<p><p>\tPar cons\u00e9quent, nous sommes conduits \u00e0 envisager une nouvelle dimension,  une de plus,  \u00e0 cette extraordinaire affaire PRISM\/NSA\/Snowden, qui se r\u00e9pand comme une train\u00e9e de poudre, dans toutes les directions. Aujourd&rsquo;hui, on la voit toucher le Congr\u00e8s, avec le cas \u00e9ventuellement consid\u00e9rable,  selon ce qu&rsquo;on en fera,  des affaires de parjure et de mensonges sous serment dans le chef de hauts fonctionnaires civils ou militaires, en plus de la mise \u00e0 jour de cette <em>Stasi-of-America<\/em> pour laquelle ils votent consciencieusement depuis 2002, en toute connaissance de cause mais sans savoir vraiment de quoi il s&rsquo;agit.<\/p>\n<\/p>\n<p><p>\tCe qu&rsquo;on d\u00e9crit n&rsquo;est par cons\u00e9quent qu&rsquo;incoh\u00e9rence, d\u00e9sordre de l&rsquo;esprit, cloisonnement des psychologies malades, irresponsabilit\u00e9 sinon <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_infraresponsabilit__06_04_2013.html\" class=\"gen\">infraresponsabilit\u00e9<\/a>,  et il s&rsquo;agit exactement de cela. Il n&rsquo;y a finalement aucune surprise dans cette foire consid\u00e9rable et pompeuse, o\u00f9 s&rsquo;entrechoquent toutes les contradictions et tous les paradoxes du monde. Nous atteignons un point de d\u00e9sordre et de confusion o\u00f9 il faudrait envisager, pour qu&rsquo;ils se sortent de cette nasse o\u00f9 ils s&rsquo;agitent, pour reprendre le contr\u00f4le et para\u00eetre \u00e0 nouveau ce qu&rsquo;ils croient qu&rsquo;ils sont, une grande op\u00e9ration de cette sorte d&rsquo;\u00e9norme nettoyage apparent \u00e9pisodique, une sorte de super-Watergate o\u00f9 des t\u00eates doivent tomber, et m\u00e9chamment&#8230; <\/p>\n<\/p>\n<p><p>\tMais dans cette situation d&rsquo;impuissance compl\u00e8te, de paralysie du pouvoir, o\u00f9 d\u00e9j\u00e0 rodent d&rsquo;autres scandales non r\u00e9solus, une telle issue est extr\u00eamement dangereuse. Premi\u00e8rement, d&rsquo;ailleurs, ce n&rsquo;est pas une issue. M\u00eame un super-Watergate de cette sorte ne permettrait pas de reprendre le contr\u00f4le des choses, et de satisfaire leur besoin de vertu. Le risque est \u00e9norme d&rsquo;un d\u00e9rapage vers des voies encore plus radicales, \u00e9ventuellement vers la mise en cause du pr\u00e9sident lui-m\u00eame, coinc\u00e9 dans son obligation-Syst\u00e8me de soutenir les ex\u00e9cutants type-Clapper et le reste. Si le pr\u00e9sident est vis\u00e9, s&rsquo;il est touch\u00e9, c&rsquo;est alors tout le syst\u00e8me de l&rsquo;am\u00e9ricanisme, comme courroie de transmission du Syst\u00e8me, qui est \u00e9branl\u00e9 jusque dans ses tr\u00e9fonds. Aujourd&rsquo;hui, bien entendu, ce pays, les USA, est <strong>immens\u00e9ment fragile<\/strong>, bien plus qu&rsquo;il ne l&rsquo;\u00e9tait en 1973-74. La chute d&rsquo;un pr\u00e9sident en 2013 ou 2014 n&rsquo;a rien \u00e0 voir avec la chute d&rsquo;un pr\u00e9sident en 1973 ou 1974, quarante ans plus t\u00f4t. Une telle crise ne serait pas un \u00e9v\u00e9nement soudain \u00e0 potentialit\u00e9 catastrophique qui resterait d&rsquo;une possibilit\u00e9 assez restreinte, ce serait la pouss\u00e9e ultime vers le processus de dissolution du syst\u00e8me de l&rsquo;am\u00e9ricanisme, du centre, des structures du pouvoir aux USA, mang\u00e9es par <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_les_termites__10_04_2013.html\" class=\"gen\">les termites<\/a> depuis des ann\u00e9es et des d\u00e9cennies.<\/p>\n<h3>Anatomie de la <em>Stasi-of-America<\/em><\/h3>\n<\/p>\n<p><p>\tEn attendant, plus ou moins longtemps, il est temps de se pencher s\u00e9rieusement sur l&rsquo;artefact qu&rsquo;est le syst\u00e8me de l&rsquo;am\u00e9ricanisme comme principal \u00e9l\u00e9ment du Syst\u00e8me. Ces auditions au Congr\u00e8s, ces fureurs, ces \u00e9changes, les d\u00e9clarations des chefs impliqu\u00e9s, montrent combien il s&rsquo;agit effectivement,  dans le chef de la NSA et de la <em>Stasi-of-America<\/em>, l&rsquo;une dans l&rsquo;autre certes,  d&rsquo;une structure autonome fonctionnant selon sa propre dynamique et circulant sur son aire sans souci des remous et des d\u00e9g\u00e2ts qu&rsquo;elle occasionne&#8230;<\/p>\n<\/p>\n<p><p>\tCette fois est une fois exceptionnelle, sans que nous sachions si c&rsquo;est la fois d\u00e9cisive Nous parlons de la rapidit\u00e9, la v\u00e9locit\u00e9, la s\u00fbret\u00e9 avec laquelle une affaire qui partait pour \u00eatre une de ces occurrences classiques o\u00f9 le Syst\u00e8me se rassemble pour vouer aux g\u00e9monies un <em>whistleblower<\/em> h\u00e9ro\u00efque et partir \u00e0 sa chasse pour avoir sa peau, se transforme, se retourne comme un chaussette en un drame washingtonien \u00e9galement classique mais si dangereux d\u00e9sormais, o\u00f9 les uns et les autres se d\u00e9chirent, o\u00f9 les parlementaire se jouent la grande sc\u00e8ne de la vertu offens\u00e9e, o\u00f9 les ex\u00e9cutants adoub\u00e9s par ces m\u00eames parlementaires se retrouvent comme des adolescents piteux, maladroits, sournois et menteurs, devant les d\u00e9clamations et les serments sur fond d&rsquo;inviolable Constitution.<\/p>\n<\/p>\n<p><p>\tBien, nul ne sait ce que tout cela durera. Il n&#8217;emp\u00eache qu&rsquo;il s&rsquo;agit d&rsquo;une de ces occasions o\u00f9 l&#8217;emportement pourrait faire passer le tout dans un mode incontr\u00f4lable, et mettre en danger l&rsquo;\u00e9quilibre du Syst\u00e8me Il n&#8217;emp\u00eache que le tohu-bohu est consid\u00e9rable, qu&rsquo;on prend langue pour de nouveaux interrogatoires-torture au Congr\u00e8s, qu&rsquo;on demande la t\u00eate au moins d&rsquo;un Clapper, et ainsi de suite. Rien ne pla\u00eet plus au parlementaire basique de Washington, corrompu jusqu&rsquo;\u00e0 l&rsquo;os et votant comme un automate, d&rsquo;appara\u00eetre soudain dans sa toge de s\u00e9nateur romain, ne jurant son all\u00e9geance qu&rsquo;\u00e0 la Constitution, d\u00e9clamant sur les m\u00e2nes disponibles,  au moins de Lincoln, sinon de la Grande R\u00e9publique.<\/p>\n<\/p>\n<p><p>\t&#8230;Tout cela se fait et se dit sous le regard de pierre d&rsquo;Abraham Lincoln, disions-nous plus haut.<\/p>\n<h3>Lincoln sous le regard des barbares<\/h3>\n<\/p>\n<p><p>\tEffectivement, le regard de pierre de Lincoln, \u00e0 la fois furieux, m\u00e9prisant, \u00e9nigmatique, et sans doute secr\u00e8tement las&#8230; Que pense-t-il, ce Lincoln \u00e9crasant, install\u00e9 sur son gigantesque fauteuil de pierre qui n&rsquo;est pas un tr\u00f4ne,  surtout pas ! Que pense-t-il, install\u00e9 dans son <a href=\"http:\/\/en.wikipedia.org\/wiki\/Lincoln_Memorial\" class=\"gen\">M\u00e9morial<\/a>, de la fr\u00e9n\u00e9sie de ces fourmis hyst\u00e9riques qui peuplent les couloirs du Congr\u00e8s de la Grande R\u00e9publique, comme si elles s&rsquo;agitaient au rythme glorieux de <em>The Battle Hymn of the Republic<\/em> ? <\/p>\n<\/p>\n<p><p>\tIl n&rsquo;y a pas un moment d\u00e9cisif, une circonstance tragique ou d&rsquo;une gloire fard\u00e9e de la Grande R\u00e9publique&#8230; Il n&rsquo;y a pas une sc\u00e8ne d&rsquo;un film hollywoodien sur la politique washingtonienne o\u00f9 le r\u00e9alisateur pr\u00e9tend exprimer la v\u00e9rit\u00e9 d&rsquo;une situation ou la v\u00e9rit\u00e9 d&rsquo;un personnage, de <em>Mister Smith Goes to Washington<\/em> de Capra au <em>Nixon<\/em> de Stone, qui ne se passe au pied de cette immense et \u00e9crasante sculpture du grand pr\u00e9sident.<\/p>\n<\/p>\n<p><p>\tLincoln, l&#8217;embl\u00e8me d&rsquo;Obama pour son \u00e9lection, Lincoln le plus grand pr\u00e9sident de l&rsquo;histoire des \u00c9tats-Unis, l&rsquo;homme par qui les USA furent tordus par le fer et par le feu pour para\u00eetre la nation qui importait, et qui ne le furent jamais, cette nation&#8230; Lincoln, le plus grand pr\u00e9sident, c&rsquo;est-\u00e0-dire le plus autoritaire, le plus tyrannique, le plus producteur de forfaitures diverses, le plus faussaire en un sens et l&rsquo;installateur du Syst\u00e8me au cur de la R\u00e9publique, et sans doute \u00e9galement, le plus angoiss\u00e9 et <a href=\"http:\/\/www.dedefensa.org\/article-obama_et_lincoln_et_lyautey_24_11_2008.html\" class=\"gen\">le plus d\u00e9pressif<\/a>. Le <a href=\"http:\/\/www.lewrockwell.com\/blog\/lewrw\/archives\/139190.html\" class=\"gen\">9 juin 2013<\/a>, Thomas di Lorenzo, sp\u00e9cialiste de Lincoln de la sorte que Spielberg s&rsquo;est bien gard\u00e9 de consulter pour tourner <a href=\"http:\/\/lewrockwell.com\/dilorenzo\/dilorenzo242.html\" class=\"gen\">son sucre d&rsquo;orge<\/a> du m\u00eame nom, \u00e9crivait, \u00e0 propos d&rsquo;un obscur mais h\u00e9ro\u00efque parlementaire, ce qu&rsquo;il faut savoir du grand pr\u00e9sident :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>&#8230;.all of these heroes stand on the shoulders of Democratic Congressman Clement L. Vallandigham of Dayton, Ohio, who was deported by the Lincoln administration in 1863.  He was treated in this way for saying such things as how any British sovereign over the past 300 years would have lost his head for doing things Lincoln was doing (illegal suspension of Habeas Corpus, mass imprisonment of tens of thousands of political dissenters, shutting down more than 300 opposition newspapers, committing treason by levying war upon the [Southern] states, the exact definition of treason under Article 3, Section 3 of the Constitution, confiscating firearms, intimidating federal judges, rigging Northern elections, waging war without congressional approval, and worse).  He also condemned the Lincoln administration on the floor of Congress for waging total war on his own country for the purpose of institutionalizing corporate welfare, protectionist tariffs, and nationalized banks and currency to pay for it all.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAinsi \u00e9tait Lincoln, et c&rsquo;est pr\u00e9cis\u00e9ment pour cela que cette figure malgr\u00e9 tout tragique est effectivement le plus grand pr\u00e9sident des Etats-Unis. Sa victoire, \u00e0 la veille de son assassinat, vit son grand g\u00e9n\u00e9ral, Grant, recevoir la capitulation de Lee en mettant presque le genou en terre d&rsquo;\u00e9motion et de respect devant le grand g\u00e9n\u00e9ral sudiste, \u00e0 <a href=\"http:\/\/www.dedefensa.org\/article-archivesphg-2_le_paradoxe_d_appomattox_06_01_2012.html\" class=\"gen\">Appomatox<\/a>, en avril 1865, r\u00e9sumant ainsi involontairement, par ce comportement, la forfaiture de cette fausse <em>Civil War<\/em>. Les d\u00e9buts en politique du grand Lincoln, en 1838, avaient \u00e9t\u00e9 marqu\u00e9s par un discours, dans sa ville de Springfield, dans l&rsquo;Illinois. Il disait ceci :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>A quel moment, donc, faut-il s&rsquo;attendre \u00e0 voir surgir le danger<\/em> [pour l&rsquo;Am\u00e9rique]<em>? Je r\u00e9ponds que, s&rsquo;il doit nous atteindre un jour, il devra surgir de nous-m\u00eames.<\/em> [&#8230;] <em>Si la destruction devait un jour nous atteindre, nous devrions en \u00eatre nous-m\u00eames les premiers et les ultimes artisans. En tant que nation d&rsquo;hommes libres, nous devons \u00e9ternellement survivre, ou mourir en nous suicidant.<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\tAinsi soit-il ?<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur le mensonge le moins mensonger possible 13 juin 2013 Admirons, tout en ressentant les effets d&rsquo;un certain \u00e9puisement (mais d&rsquo;une saine fatigue, certes), le potentiel impressionnant de situations nouvelles qu&rsquo;engendre cette affaire NSA\/PRISM devenue NSA\/PRISM\/Snowden. Quand l&rsquo;on pense qu&rsquo;elle a \u00e9clat\u00e9 le 6 juin (date fatidique), on est confondu par la rapidit\u00e9 des&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[12231,3285,10437,3896,3871,12232,12224,4999,3744,2626],"class_list":["post-75040","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-clapper","tag-congres","tag-espionnage","tag-lincoln","tag-nsa","tag-prims","tag-snowden","tag-surveillance","tag-terreur","tag-watergate"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75040"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75040\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}