{"id":75077,"date":"2013-07-03T16:06:12","date_gmt":"2013-07-03T16:06:12","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/07\/03\/destin-dun-whistleblower\/"},"modified":"2013-07-03T16:06:12","modified_gmt":"2013-07-03T16:06:12","slug":"destin-dun-whistleblower","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/07\/03\/destin-dun-whistleblower\/","title":{"rendered":"Destin d&rsquo;un <em>whistleblower<\/em>"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Destin d&rsquo;un <em>whistleblower<\/em><\/h3>\n<\/p>\n<p><p>\tIl appara\u00eet de plus en plus \u00e9vident que Edward Snowden n&rsquo;a gu\u00e8re de chance de trouver un pays qui voudra lui accorder l&rsquo;asile politique, ce qui est une d\u00e9monstration de ce que nous nommons l&#8217;empire de la terreur. (Ce qui est d\u00e9sign\u00e9 en g\u00e9n\u00e9ral comme la crainte de tous les pays concern\u00e9s de compromettre leurs relations avec les USA [voir <em>WSWS.org<\/em> du <a href=\"http:\/\/www.wsws.org\/en\/articles\/2013\/07\/03\/pers-j03.html\" class=\"gen\">3 juillet 2013<\/a>] ; mais, \u00e0 notre sens, il s&rsquo;agit d&rsquo;une crainte beaucoup plus large et diffuse des dirigeants-Syst\u00e8me et m\u00eame de ceux qui en d\u00e9pendent moins face \u00e0 une exigence d&rsquo;une structure essentielle du Syst\u00e8me.) Snowden fait de plus en plus figure d&rsquo;isol\u00e9 face au Syst\u00e8me, voire de martyre si l&rsquo;on veut un terme plus tragique (on reviendra sur ce point). Il est \u00e0 noter que son p\u00e8re, qui avait d&rsquo;abord pris une position assez r\u00e9serv\u00e9e face \u00e0 son action, jugeant qu&rsquo;il \u00e9tait manipul\u00e9 par Assange et <em>Wikileaks<\/em> et lui recommandant de cesser ses fuites, de rentrer aux USA et d&rsquo;affronter la justice, a \u00e9volu\u00e9 et le consid\u00e8re d\u00e9sormais comme un h\u00e9ros, dans sa derni\u00e8re lettre rendue publique par son avocat. Lon Snowden compare son fils au h\u00e9ros de la R\u00e9volution am\u00e9ricaine, le d\u00e9signant comme un <a href=\"http:\/\/en.wikipedia.org\/wiki\/Paul_Revere\" class=\"gen\">Paul Revere<\/a> moderne.  (Sur <em>Yahoo.com<\/em>, le <a href=\"http:\/\/news.yahoo.com\/edward-snowdens-dad-calls-him-modern-day-paul-171620928--abc-news-topstories.html\" class=\"gen\">2 juillet 2013<\/a>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>As alleged NSA leaker Edward Snowden&rsquo;s options for political asylum appear to dwindle, Snowden&rsquo;s father sent a letter to his son today, calling him a modern day Paul Revere who helped awaken Congressional oversight of U.S. intelligence from a deep slumber. In the letter, written by attorney Bruce Fein in collaboration with Lonnie Snowden, the two say that by leaking information on the National Security Agency&rsquo;s vast domestic and international surveillance programs, the younger Snowden has forced onto the national agenda the question of whether the American people prefer the right to be left alone from government snooping&#8230; You are a modern day Paul Revere summoning the American people to confront the growing danger of tyranny and one branch government, the letter says.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>It also references the Director of National Intelligence James Clapper&rsquo;s comments before a Senate committee in which he denied the NSA purposefully collects, as Sen. Ron Wyden put it, any type of data at all on millions or hundreds of millions of Americans  a denial apparently disputed by reports based on Snowden&rsquo;s information. The letter asks whether Clapper or Snowden is the superior patriot.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The letter, in which the elder Snowden only requests that his 30-year-old son to engage us in regular exchanges of ideas or thoughts&#8230; about curing or mitigating the hugely suboptimal political culture of the United States, is a departure from Lon Snowden&rsquo;s previous requests that his son stop the leaks and come home.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe cas Snowden prend une dimension humaine qui m\u00e9rite qu&rsquo;on s&rsquo;y attache, notamment en fonction de son refus de l&rsquo;asile politique en Russie \u00e0 condition de cesser ses attaques contre les USA, c&rsquo;est-\u00e0-dire la diffusion des documents de la NSA. Il est quasiment acquis que Snowden n&rsquo;a plus grand&rsquo;chose \u00e0 diffuser, sinon rien du tout, puisqu&rsquo;il a distribu\u00e9 tous les documents qu&rsquo;ils poss\u00e8dent \u00e0 divers journaux et personnes. Glenn Greenwald l&rsquo;a encore confirm\u00e9 le <a href=\"http:\/\/dyn.politico.com\/printstory.cfm?uuid=C24F066F-EE83-497A-8004-DD72EC332D77\" class=\"gen\">2 juillet 2013<\/a>, sur <em>Politico.com<\/em>, parlant en ces termes des intentions des autorit\u00e9s US : \u00ab<em>They don&rsquo;t care about Edward Snowden at this point; he can no longer do anything that he hasn&rsquo;t already done; what they care about is making an extremely negative example out of him to intimidate future whistleblowers from coming forward because they&rsquo;ll think that they&rsquo;ll end up like him&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIllustrant la chose, Greenwald annonce une prochaine publication de documents qu&rsquo;il promet explosifs&#8230; \u00ab<em>Just wait a little bit, you&rsquo;ll have it, The Guardian journalist who broke the NSA surveillance story said on Fox &#038; Friends. Although Greenwald wouldn&rsquo;t reveal exactly what the new revelations are, he said the world will be shocked. I will say that there are vast programs, both domestic and international spying, that the world will be shocked to learn about, that the NSA is engaged in with no democratic accountability and that&rsquo;s what driving our reporting, Greenwald said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCette r\u00e9alit\u00e9 fait s&rsquo;interroger sur le refus de Snowden de l&rsquo;offre conditionnelle d&rsquo;asile politique de la Russie. Il y a l&rsquo;argument g\u00e9n\u00e9ral de la poursuite de sa mission de diffusion des documents NSA, par exemple comme le signale <em>WSWS.org<\/em> (dans le texte d\u00e9j\u00e0 cit\u00e9) : \u00ab<em>Snowden swiftly rejected Putin&rsquo;s offer, which would have made him a political prisoner of the Kremlin oligarchy, and withdrew his asylum application. His action made clear his determination to continue exposing the illegal operations of the US government and at the same time underscored the fraud of the espionage charges brought against him.<\/em>\u00bb Cet argument de la poursuite de la diffusion des documents NSA n&rsquo;a plus gu\u00e8re de sens, comme on l&rsquo;a vu plus haut. D\u00e8s lors, le jugement selon lequel Snowden deviendrait un prisonnier politique en Russie n&rsquo;est pas plus d&rsquo;une signification convaincante et nous para\u00eet ressortir pour beaucoup de l&rsquo;hostilit\u00e9 visc\u00e9rale des trotskistes pour un gouvernement qu&rsquo;ils consid\u00e8rent comme successeur lointain de Staline en m\u00eame temps que complice capitaliste des USA (\u00ab<em>Whatever the geopolitical conflicts between Moscow and Washington, however, both governments represent rapacious capitalist ruling strata and are united in their fear of state crimes being exposed to their respective working populations.<\/em>\u00bb). On peut m\u00eame avancer que, selon l&rsquo;\u00e9volution de la situation des relations USA-Russie qu&rsquo;on peut sans grand risque appr\u00e9cier comme promises \u00e0 s&rsquo;aggraver, un Snowden install\u00e9 en Russie pourrait retrouver un r\u00f4le politique public. Cela est d&rsquo;autant plus \u00e0 consid\u00e9rer qu&rsquo;il dispose dans le pays de nombreux alli\u00e9s, dans des positions d&rsquo;influence non n\u00e9gligeables, et que la pression sur Poutine pour une politique plus antiam\u00e9ricaniste est une constante de la situation russe.<\/p>\n<\/p>\n<p><p>\tComme le dit Greenwald, le gouvernement US entend faire un exemple pour emp\u00eacher que surgissent d&rsquo;autres <em>whistleblower<\/em>. Cet avis est g\u00e9n\u00e9ralement confirm\u00e9 par des voix dissidentes autoris\u00e9es. Par exemple, <a href=\"http:\/\/en.wikipedia.org\/wiki\/Norman_Solomon\" class=\"gen\">Norman Solomon<\/a>, parlant \u00e0 <em>Russia Today<\/em> le <a href=\"http:\/\/rt.com\/op-edge\/us-snowden-nsa-leaks-539\/\" class=\"gen\">2 juillet 2013<\/a> : \u00ab<em>There is an element of panic in US policy towards Edward Snowden and this entire issue, and the effort is of the big global giant trying to crush any ongoing voice in this case from Edward Snowden who could authoritatively, with great information, continue to inform the world.<\/em> [&#8230;] <em> The US government wants to discourage whistleblowing from those in agencies like the NSA.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl faut aussit\u00f4t rappeler que Snowden pr\u00e9parait son affaire depuis quatre ans, qu&rsquo;il a eu sous les yeux les exemples des pers\u00e9cutions contre Assange et contre Bradley Manning, qu&rsquo;il savait parfaitement le sort qui l&rsquo;attendait, comme il ne l&rsquo;a jamais cach\u00e9. On est alors conduit \u00e0 observer que l&rsquo;attitude du gouvernement US (du Syst\u00e8me), si m\u00eame l&rsquo;entreprise d&rsquo;\u00e9limination de Snowden r\u00e9ussit, n&rsquo;est pas n\u00e9cessairement promise \u00e0 \u00eatre d&rsquo;une compl\u00e8te efficacit\u00e9 dissuasive. La psychologie de Snowden, comme en un sens celle de Manning (moins celle d&rsquo;Assange), n&rsquo;est pas celle du calcul, de la manuvre, de la survie politique, etc., mais bien plut\u00f4t celle du martyre. La psychologie du martyre est un caract\u00e8re particulier, tr\u00e8s sp\u00e9cifique, qui existe sans aucun doute d&rsquo;une fa\u00e7on psychologique structur\u00e9e et n&rsquo;est certainement pas une simple image symbolique. Dans ce cas, les difficult\u00e9s jusqu&rsquo;au danger supr\u00eame de l&rsquo;oppression et du martyre impos\u00e9es par une entit\u00e9 qu&rsquo;on identifie au Mal deviennent plus un argument pour agir, une \u00e9preuve de la destin\u00e9e voire de la providence si l&rsquo;on veut, qu&rsquo;on envisage et qu&rsquo;on accepte pour soi-m\u00eame comme une mesure de sa propre valeur. (Certaines confidences de son avocat montrent que Manning vit son calvaire de cette fa\u00e7on.)<\/p>\n<\/p>\n<p><p>\tDans ce cas, la politique US devient compl\u00e8tement improductive parce qu&rsquo;elle confirme la situation de son producteur (le Syst\u00e8me, via les USA), dans le chef d&rsquo;une entit\u00e9 mal\u00e9fique, oppressive, contre laquelle Manning et Snowden et tout autre <em>whistleblower<\/em> de cette trempe se sont r\u00e9volt\u00e9s, et donc ajoute une raison suppl\u00e9mentaire de r\u00e9volte pour une psychologie de martyre comme il semble en exister encore et qui attendrait son tour pour se manifester. (On pourrait m\u00eame se demander, certes, si la situation actuelle, dans sa monstruosit\u00e9, n&rsquo;est pas propice \u00e0 susciter l&rsquo;action antiSyst\u00e8me de telles psychologies.) Mais la politique US, en fait <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_la_politique-syst_me__17_11_2012.html\" class=\"gen\">politique-Syst\u00e8me<\/a> et rien d&rsquo;autre, n&rsquo;en a cure parce qu&rsquo;elle ob\u00e9it \u00e0 des principes de force. Le Syst\u00e8me n&rsquo;a aucune id\u00e9e des formes inattendues ou radicales que peut prendre l&rsquo;h\u00e9ro\u00efsme, puisqu&rsquo;il ignore d&rsquo;ailleurs ce que c&rsquo;est que l&rsquo;h\u00e9ro\u00efsme.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 3 juillet 2013 \u00e0 16H03<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Destin d&rsquo;un whistleblower Il appara\u00eet de plus en plus \u00e9vident que Edward Snowden n&rsquo;a gu\u00e8re de chance de trouver un pays qui voudra lui accorder l&rsquo;asile politique, ce qui est une d\u00e9monstration de ce que nous nommons l&#8217;empire de la terreur. (Ce qui est d\u00e9sign\u00e9 en g\u00e9n\u00e9ral comme la crainte de tous les pays concern\u00e9s&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[6841,6944,6615,9933,12266,3099,12224],"class_list":["post-75077","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-calvaire","tag-greenwald","tag-manning","tag-martyre","tag-oppression","tag-psychologie","tag-snowden"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75077"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75077\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}