{"id":75094,"date":"2013-07-13T10:58:14","date_gmt":"2013-07-13T10:58:14","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/07\/13\/la-servilite-des-satellites\/"},"modified":"2013-07-13T10:58:14","modified_gmt":"2013-07-13T10:58:14","slug":"la-servilite-des-satellites","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/07\/13\/la-servilite-des-satellites\/","title":{"rendered":"La servilit\u00e9 des satellites"},"content":{"rendered":"<p><h2 class=\"common-article2\">La servilit\u00e9 des satellites<\/h2>\n<\/p>\n<p><p>\tL&rsquo;affaire Snowden a \u00e9t\u00e9 encore plus r\u00e9v\u00e9latrice sur l&rsquo;Europe que sur les \u00c9tats-Unis.<\/p>\n<\/p>\n<p><p>\tCertes, les faits d&rsquo;espionnage de la NSA sont importants. Mais beaucoup de gens se doutaient de quelque chose dans ce genre. Le refus de la France, de l&rsquo;Italie et du Portugal d&rsquo;autoriser l&rsquo;avion priv\u00e9 du pr\u00e9sident de la Bolivie de traverser leur espace a\u00e9rien sur le simple soup\u00e7on que Edward Snowden pouvait se trouver \u00e0 bord est un peu plus \u00e9tonnant.<\/p>\n<\/p>\n<p><p>\tEnsemble, toutes ces r\u00e9v\u00e9lations confirment l&rsquo;ach\u00e8vement de la transformation des \u00ab\u00a0d\u00e9mocraties occidentales\u00a0\u00bb en quelque chose d&rsquo;autre, une entit\u00e9 qui n&rsquo;a pas encore re\u00e7u de nom.<\/p>\n<\/p>\n<p><p>\tL&rsquo;outrage fait au pr\u00e9sident bolivien a confirm\u00e9 que cette entit\u00e9 transatlantique n&rsquo;a absolument aucun respect pour le droit international, m\u00eame si ses dirigeants s&rsquo;y r\u00e9f\u00e9rent lorsque cela leur convient. Mais respecter ce droit ou se laisser entraver par lui d&rsquo;une mani\u00e8re quelconque ? Certainement pas.<\/p>\n<\/p>\n<p><p>\tEt ce m\u00e9pris de la loi est li\u00e9 \u00e0 un changement institutionnel plus fondamental : la destruction de la d\u00e9mocratie r\u00e9elle au niveau national. Aux Etats-Unis, cela a \u00e9t\u00e9 accompli par le pouvoir de l&rsquo;argent, o\u00f9 les candidats sont comparables aux chevaux de course appartenant \u00e0 des milliardaires. En Europe, ce fut l&rsquo;oeuvre de l&rsquo;Union europ\u00e9enne, dont la bureaucratie a progressivement repris les fonctions \u00e9conomiques essentielles des Etats ind\u00e9pendants, d\u00e9l\u00e9gant aux gouvernements nationaux la t\u00e2che de concocter d&rsquo;\u00e9normes controverses autour des questions de vie priv\u00e9e, telles que le mariage, tandis que la politique socio-\u00e9conomique se voit dict\u00e9e par la Commission europ\u00e9enne \u00e0 Bruxelles.<\/p>\n<\/p>\n<p><p>\tMais derri\u00e8re cette Commission, et derri\u00e8re le jeu \u00e9lectoral am\u00e9ricain, se trouve le pouvoir anonyme identique qui dicte ses volont\u00e9s \u00e0 cette entit\u00e9 transatlantique : le capital financier.<\/p>\n<\/p>\n<p><p>\tCe pouvoir devrait \u00eatre officiellement \u00e9tendu dans un proche avenir par la cr\u00e9ation d&rsquo;une zone de libre-\u00e9change entre l&rsquo;Union europ\u00e9enne et les \u00c9tats-Unis. Cette \u00e9volution est le r\u00e9sultat de la soi-disant \u00ab construction europ\u00e9enne \u00bb qui depuis plusieurs d\u00e9cennies a transf\u00e9r\u00e9 des comp\u00e9tences des Etats europ\u00e9ens souverains \u00e0 l&rsquo;UE, qui \u00e0 son tour va transf\u00e9rer ses pouvoirs \u00e0 des institutions transatlantiques, le tout sous le contr\u00f4le d\u00e9cisif des \u00ab March\u00e9s \u00bb &#8211; euph\u00e9misme pour d\u00e9signer le capital financier.<\/p>\n<\/p>\n<p><p>\tLes citoyens ne sont inform\u00e9s de la derni\u00e8re \u00e9tape de ce processus de d\u00e9-d\u00e9mocratisation en cours que lorsque cette derni\u00e8re est d\u00e9j\u00e0 bien engag\u00e9e. Le r\u00e9sultat est un foss\u00e9 toujours plus large entre d&rsquo;un c\u00f4t\u00e9 \u00ab\u00a0la classe politique\u00a0\u00bb, qui comprend \u00e0 la fois les hommes politiques et les m\u00e9dias de masse, et de l&rsquo;autre c\u00f4t\u00e9 la population en g\u00e9n\u00e9ral. La principale t\u00e2che encore d\u00e9volue \u00e0 la classe politique est de divertir la population avec l&rsquo;illusion qu&rsquo;elle vit toujours dans une d\u00e9mocratie, et que les repr\u00e9sentants qu&rsquo;elle \u00e9lit agissent dans ses int\u00e9r\u00eats.<\/p>\n<\/p>\n<p><p>\tLorsqu&rsquo;un \u00e9v\u00e9nement tel que l&rsquo;affaire grotesque de l&rsquo;avion pr\u00e9sidentiel bolivien survient et expose la servilit\u00e9 des fonctionnaires du pays, on peut compter sur les grands m\u00e9dias pour le balayer sous le tapis. La t\u00e9l\u00e9vision fran\u00e7aise a largement ignor\u00e9 l&rsquo;\u00e9v\u00e9nement &#8211; une n\u00e9gligence facilit\u00e9e par le r\u00e9cent soul\u00e8vement en Egypte. Un seul grand \u00e9v\u00e9nement international par jour est consid\u00e9r\u00e9 suffisant pour un public dont le r\u00e9gime \u00ab informationnel \u00bb de base est centr\u00e9 sur la m\u00e9t\u00e9o, les sports et les crimes sexuels.<\/p>\n<\/p>\n<p><p>\tPour mesurer l&rsquo;ampleur de la reddition de l&rsquo;ind\u00e9pendance fran\u00e7aise au cours des derni\u00e8res d\u00e9cennies, on peut rappeler que dans les ann\u00e9es 1970, le gouvernement de centre droit du Pr\u00e9sident Val\u00e9ry Giscard d&rsquo;Estaing avait facilement accord\u00e9 l&rsquo;asile aux Black Panthers fuyant les \u00c9tats-Unis. Aujourd&rsquo;hui, le ministre de l&rsquo;Int\u00e9rieur d&rsquo;un gouvernement soi-disant de \u00ab centre gauche \u00bb exclut d&rsquo;accorder l&rsquo;asile \u00e0 tout citoyen des \u00c9tats-Unis, au motif que les \u00c9tats-Unis sont un pays \u00ab ami \u00bb, une \u00ab d\u00e9mocratie \u00bb avec un syst\u00e8me judiciaire ind\u00e9pendant.<\/p>\n<\/p>\n<p><p>\tEn Allemagne, la propagande anticommuniste ayant eu recours aux d\u00e9nonciations constantes des indiscr\u00e9tions de la Stasi pour enterrer tout souvenir des avantages perdus du r\u00e9gime est-allemand, comme le plein emploi, la garde des enfants et l&rsquo;\u00e9galit\u00e9 sociale pour les femmes, les r\u00e9v\u00e9lations sur l&rsquo;espionnage de la NSA ne pouvaient \u00eatre ignor\u00e9es. M\u00eame les dirigeants politiques en Allemagne semblaient sinc\u00e8rement indign\u00e9s.<\/p>\n<\/p>\n<p><p>\tEn France, les dirigeants politiques ont murmur\u00e9 quelques vagues d\u00e9sapprobations et rapidement chang\u00e9 de sujet. Et dans le cas o\u00f9 on daignait mentionner cet incident, la ligne officielle \u00e9tait qu&rsquo;il n&rsquo;y avait pas lieu de faire un grand tapage \u00e0 propos de pratiques que nous, les grandes puissances sophistiqu\u00e9es, connaissons de toute fa\u00e7on et pratiquons nous-m\u00eames.<\/p>\n<\/p>\n<p><p>\tL&rsquo;auto-incrimination b\u00e9ate \u00ab\u00a0nous aussi, nous le faisons\u00a0\u00bb est une fa\u00e7on d&rsquo;affirmer que la France est toujours une grande puissance malfaisante, et non un simple satellite des \u00c9tats-Unis.<\/p>\n<\/p>\n<p><p>\tLors d&rsquo;une interview t\u00e9l\u00e9vis\u00e9e hier, on a montr\u00e9 au ministre des Affaires \u00e9trang\u00e8res fran\u00e7ais Laurent Fabius une vid\u00e9o du pr\u00e9sident Obama se r\u00e9f\u00e9rant \u00e0 plusieurs reprises au pr\u00e9sident fran\u00e7ais Fran\u00e7ois Hollande comme \u00ab\u00a0pr\u00e9sident Houlon\u00a0\u00bb. Fabius a rapidement chang\u00e9 de sujet pour louer le r\u00f4le important de la France dans la promotion de la guerre en Syrie. Le fait que le pr\u00e9sident fran\u00e7ais est consid\u00e9r\u00e9 comme tellement insignifiant qu&rsquo;Obama n&rsquo;a pas besoin de s&#8217;emb\u00eater \u00e0 apprendre son nom ne m\u00e9ritait pas d&rsquo;\u00eatre relev\u00e9.<\/p>\n<\/p>\n<p><p>\tLe m\u00e9pris d&rsquo;Obama pour Hollande, le m\u00e9pris de Hollande pour le Pr\u00e9sident de la Bolivie, illustrent bien ce nouvel ordre mondial gouvern\u00e9 non par des pr\u00e9occupations humaines, mais par \u00ab les march\u00e9s \u00bb. Ce n&rsquo;est pas que les march\u00e9s donnent des ordres directs sur ces sujets. Mais la r\u00e9duction du gouvernement \u00e0 la \u00ab\u00a0gouvernance\u00a0\u00bb dont la fonction principale est de faire taire la populace pendant que les institutions, les lois et les forces arm\u00e9es poursuivent la t\u00e2che de rendre le monde plus s\u00fbr pour les capitaux d&rsquo;investissement afin de r\u00e9colter le maximum de profits, rend l&rsquo;humain hors jeu et la politique devient un exercice vide dans la conformit\u00e9.<\/p>\n<\/p>\n<p><p>\tL&rsquo;explication d&rsquo;une telle reddition r\u00e9side dans l&rsquo;id\u00e9ologie qui a domin\u00e9 l&rsquo;Europe, et peut-\u00eatre surtout la France, au cours du dernier demi-si\u00e8cle. Une interpr\u00e9tation particuli\u00e8re de l&rsquo;histoire du milieu du XXe si\u00e8cle a sap\u00e9 la confiance dans la souverainet\u00e9 populaire, accus\u00e9e (\u00e0 tort) de conduire au \u00ab totalitarisme \u00bb. Cette id\u00e9ologie a pr\u00e9par\u00e9 les \u00e9lites \u00e0 abdiquer en faveur des institutions techniques et des \u00ab march\u00e9s \u00bb qui semblent innocents de tout p\u00e9ch\u00e9 politique. La puissance du capital financier et de son champion am\u00e9ricain est moins la cause que le r\u00e9sultat de cette abdication politique.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est la seule chose qui puisse expliquer la ru\u00e9e extraordinaire des gouvernements europ\u00e9ens \u00e0 ob\u00e9ir au moindre caprice du ma\u00eetre am\u00e9ricain, \u00e0 la veille des n\u00e9gociations pour une zone de libre-\u00e9change transatlantique que les dirigeants europ\u00e9ens vont pr\u00e9senter \u00e0 leurs populations comme une compensation pour la destruction continue du mod\u00e8le de protection sociale europ\u00e9enne. Les principes, la d\u00e9cence diplomatique, Edward Snowden, doivent tous \u00eatre sacrifi\u00e9s \u00e0 cette derni\u00e8re tentative d\u00e9sesp\u00e9r\u00e9e de mettre l&rsquo;Europe hors de la port\u00e9e de l&rsquo;influence de son peuple.<\/p>\n<\/p>\n<p><p>\tQuelques commentateurs sont all\u00e9s jusqu&rsquo;\u00e0 sugg\u00e9rer qu&rsquo;Edward Snowden serait une sorte de coup mont\u00e9, soi-disant pour montrer aux gens que le gouvernement am\u00e9ricain est tout-puissant. L&rsquo;affront fait au pr\u00e9sident bolivien en est une illustration m\u00eame plus frappante. Mais \u00e0 long terme, la prise de conscience de la port\u00e9e de ce pouvoir est la premi\u00e8re \u00e9tape vers la lib\u00e9ration.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Diana Johnstone<\/p>\n<\/p>\n<h4>Note<\/h4>\n<p>L&rsquo;original en anglais de cet article a paru dans <em>CounterPunch<\/em> le <a href=\"http:\/\/www.counterpunch.org\/2013\/07\/05\/the-servility-of-the-satellites\/\" class=\"gen\">5 juillet 2013<\/a>.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La servilit\u00e9 des satellites L&rsquo;affaire Snowden a \u00e9t\u00e9 encore plus r\u00e9v\u00e9latrice sur l&rsquo;Europe que sur les \u00c9tats-Unis. Certes, les faits d&rsquo;espionnage de la NSA sont importants. Mais beaucoup de gens se doutaient de quelque chose dans ce genre. Le refus de la France, de l&rsquo;Italie et du Portugal d&rsquo;autoriser l&rsquo;avion priv\u00e9 du pr\u00e9sident de la&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[12229,4860,2687,3203,4901,4607,12224],"class_list":["post-75094","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-asile","tag-autriche","tag-france","tag-hollande","tag-morales","tag-politique","tag-snowden"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75094"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75094\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}