{"id":75124,"date":"2013-07-29T05:22:41","date_gmt":"2013-07-29T05:22:41","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/07\/29\/le-systeme-face-a-la-presse-antisysteme\/"},"modified":"2013-07-29T05:22:41","modified_gmt":"2013-07-29T05:22:41","slug":"le-systeme-face-a-la-presse-antisysteme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/07\/29\/le-systeme-face-a-la-presse-antisysteme\/","title":{"rendered":"Le Syst\u00e8me face \u00e0 la presse antiSyst\u00e8me"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Le Syst\u00e8me face \u00e0 la presse antiSyst\u00e8me<\/h3>\n<\/p>\n<p><p>\tNous avons \u00e9t\u00e9 alert\u00e9s par un article de <em>Infowars.com<\/em> en pleine jubilation, ce <a href=\"http:\/\/www.infowars.com\/government-promises-to-stop-lying-under-drudge-report-spotlight\/&#8236;\" class=\"gen\">28 juillet 2013<\/a>. Sign\u00e9 Adan Salazar et Alex Jones (et suivi d&rsquo;une chronique TV de Jones le soir du m\u00eame jour), la nouvelle exploite une conf\u00e9rence de George Little, assistant du secr\u00e9taire \u00e0 la d\u00e9fense pour affaires publiques (ou relations publiques). (La communication de Little, retransmise par le r\u00e9seau <em>American Forces Press Service<\/em> [AFPS], est du <a href=\"http:\/\/www.defense.gov\/News\/NewsArticle.aspx?ID=120522\" class=\"gen\">25 juillet 2013<\/a>.)<\/p>\n<\/p>\n<p><p>\tLittle est donc aussi bien le porte-parole du Pentagone que son directeur de la communication. Il fait un bilan de la situation de communication du Pentagone et offre des perspectives. Surtout,  et c&rsquo;est ce que soulignent justement Salazar-Jones,  il jette un cri d&rsquo;alarme, il panique, devant l&rsquo;incursion des nouveaux m\u00e9dias, ou m\u00e9dias alternatifs, tout ce qui est en-dehors de la presse-Syst\u00e8me et se trouve assimilable plus ou moins \u00e0 une presse antiSyst\u00e8me (voir plus bas). C&rsquo;est une indication incontestable que cette presse antiSyst\u00e8me est en train, d&rsquo;une part de r\u00e9aliser un travail d&rsquo;information remarquable et incontr\u00f4lable par le Pentagone, d&rsquo;autre part de gagner gr\u00e2ce \u00e0 cela une influence consid\u00e9rable avec des effets dommageables pour le Pentagone (<em>dito<\/em>, le Syst\u00e8me). Selon AFPS :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Little pointed out that the widespread embedding of reporters in Iraq and Afghanistan forged close bonds between military members and the Fourth Estate. As deployments wind down and the services return to a more garrison-centered public affairs environment, he said, we must look for new ways to enhance these bonds.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Little said new approaches should include engaging more with nontraditional journalists such as bloggers and tweeters, who sometimes break news but also may report gossip and rumor. We must be constantly listening for new voices on defense issues, he said, and develop those relationships as well.  We must engage with anyone and everyone who is interested in what the department is doing.  In order to effectively communicate our message, we must be communicating across all platforms, new and old. By creating richer, more interesting content, we can create a deeper connection with the American public, and nourish the growing news appetite, on our terms.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLittle prend alors une orientation inattendue mais finalement sans surprise en fonction du constat qu&rsquo;il fait. Il conseille aux forces arm\u00e9es, aux officiers de relations publics, aux chefs militaires qui ont des contacts ext\u00e9rieurs de devenir des professionnels de la communication et d&rsquo;entretenir des contacts de confiance avec la presse,  et notamment, et essentiellement, avec la presse alternative, la nouvelle presse que le Pentagone semble particuli\u00e8rement anxieux de rassembler de son c\u00f4t\u00e9,  y compris par le moyen de la v\u00e9rit\u00e9 qui serait bien entendu am\u00e9nag\u00e9e pour correspondre \u00e0 la substance m\u00eame du Pentagone et \u00e0 la sauvegarde les int\u00e9r\u00eats&#8230; \u00ab<em>Little said commanders must be open and honest with the media. The department can&rsquo;t hide bad news stories, he noted. When bad things happen, the American people should hear it from us, not as a scoop on the Drudge Report, he said. This requires all commanders to be open and honest with the press and to rely on their public affairs officer&rsquo;s strategic advice in developing communication strategies, Little said&#8230;<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\t Alex Jones a saut\u00e9 sur l&rsquo;occasion, et notamment sur la mention de <em>Drudge Report<\/em> par Little, comme r\u00e9f\u00e9rence d&rsquo;un m\u00e9dia alternatif qui diffuse souvent des informations exclusives sur le d\u00e9partement de la d\u00e9fense, et met souvent celui-ci en mauvaise posture. Pour Jones, cela signifie que le gouvernement (le Pentagone) a reconnu la puissance de la presse alternative et qu&rsquo;il va tout faire pour la subvertir comme il est arriv\u00e9 \u00e0 le faire pour la presse-Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>In essence, this is a signal of defeat to the power that is independent media, and shows just how large of an effect it is having. Alex Jones lends his analysis: Just as the term Google&rsquo; became synonymous with search engine,&rsquo; DrudgeReport.com has become the catchword for all independent forms of journalism alive on the web today. Jones believes Drudge&rsquo;s mention in the DoD speech is a testament to how legit and credible Drudge really is. This is the reason why the news aggregator has so frequently been the target of naysayer critics ranging from exiting-DHS secretary Janet Napolitano to White House Press Secretary Jay Carney to White House Senior Advisor Dan Pfeiffer, who said that Drudge&rsquo;s stories actively hurt the White House&rsquo;s message on a daily basis.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>On one hand, the government has revealed it is not invincible to the onslaught of curious, honest and hard-working journalists eager to obtain and report the truth. It shows just how vulnerable the man behind the curtain really is; in all his power, he&rsquo;s upset over the few forms of media he can&rsquo;t control. With Drudge continually pouring out their contradictions, the federal government is finding it harder to keep their stories straight and consistently gets caught off-guard.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>On the other hand, the DoD&rsquo;s announcement that it will become more engaged with journalists is even more unsettling in light of the fact that just two weeks ago the CIA was given a green light to flood America with even more government propaganda. The fact that they&rsquo;re openly announcing their intent to infiltrate the media means they&rsquo;re ready to move forward with plans to squelch the First Amendment. This is the opening salvo public announcement of open war on the power of the press.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>This is a completely cynical move by the Pentagon, Alex says. They&rsquo;ve been engaged forever in domestic psy-op operations, but now that they&rsquo;ve been blown wide open by alternative media we&rsquo;re seeing the psy-op of cognitive infiltration. They say they&rsquo;re going to reach out to the media (that means persuading members of the alternative media with money as well) basically setting up operations against it, but they&rsquo;re announcing this is not an assault. We&rsquo;re your friends! We come in peace! We promise we&rsquo;ll be truthful and we&rsquo;re gonna communicate! Listen to us!&rsquo; It&rsquo;s actually the opposite. This is the Pentagon, psy-warfare and cyber-security all declaring war on the First Amendment. The only huge website out there that you can call mainstream but also alternative that is really challenging the establishment is the Drudge Report, which should be considered a world treasure, along with all other alternative media. We shouldn&rsquo;t be demoralized by this development, we should be excited, because this shows we&rsquo;re having an effect in keeping freedom alive and spreading it worldwide.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLa r\u00e9action de Jones est bien dans sa mani\u00e8re, agressive, avantageuse, truculente, \u00e0-la-retape, etc. La r\u00e9f\u00e9rence <em>Infowars<\/em>, tout comme celle de <em>Drudge Report<\/em> d&rsquo;ailleurs, restent \u00e0 consid\u00e9rer avec certaines r\u00e9serves, tout en reconnaissant leurs qualit\u00e9s \u00e9parses et diss\u00e9min\u00e9es et, surtout, leur participation effective \u00e0 la construction d&rsquo;une force puissante, constituant techniquement et politiquement ce qu&rsquo;on nomme presse alternative, qui occupe d\u00e9sormais une place pr\u00e9pond\u00e9rante dans le syst\u00e8me de la communication, certainement plus puissante et plus dangereuse que la presse-Syst\u00e8me dans la perception qu&rsquo;en ont les repr\u00e9sentants du Syst\u00e8me. En raison de cette perception, et malgr\u00e9 toutes les r\u00e9serves qu&rsquo;on peut \u00e9mettre en fonction de la multitude d&rsquo;orientations, de m\u00e9thodes, de diff\u00e9rences de qualit\u00e9 dans cette presse alternative, il nous semble qu&rsquo;on peut d\u00e8s lors qualifier cette force, selon l&rsquo;ensemble des effets qu&rsquo;elle obtient, de presse antiSyst\u00e8me. Pour l&rsquo;ensemble de la presse antiSyst\u00e8me, c&rsquo;est une avanc\u00e9e extraordinaire, dont il y a tout lieu de croire qu&rsquo;elle sera poursuivie, essentiellement \u00e0 cause de l&rsquo;inefficacit\u00e9 et des erreurs colossales du Syst\u00e8me en mati\u00e8re de communication.<\/p>\n<\/p>\n<p><p>\tNous rappelons que l&rsquo;intervention de Little concernant la faiblesse de communication du Syst\u00e8me n&rsquo;est pas la premi\u00e8re dans le chef du Pentagone (les autres d\u00e9partements, notamment le d\u00e9partement d&rsquo;\u00c9tat, sont moins prompts \u00e0 reconna\u00eetre leurs faiblesses, voire m\u00eame \u00e0 les identifier). Il y a quelques ann\u00e9es, l&rsquo;effort du Syst\u00e8me (du Pentagone) \u00e9tait enti\u00e8rement orient\u00e9 sur la mission de gagner les curs et les esprits des populations des pays investis par ses forces militaires, notamment en Afghanistan et en Irak. Il le faisait avec l&rsquo;aide agr\u00e9\u00e9e et reconnue de la presse-Syst\u00e8me, r\u00e9percutant ses initiatives et incursions diverses sur les terres indig\u00e8nes comme autant d&rsquo;exploits \u00e0 la gloire de la civilisation, et en plus, pour assurer cette emprise, avec un r\u00e9seau puissant de p\u00e9n\u00e9tration de cette m\u00eame presse-Syst\u00e8me, notamment \u00e0 l&rsquo;aide de milliers d&rsquo;articles r\u00e9dig\u00e9s par les services du Pentagone et r\u00e9pandus dans cette m\u00eame presse-Syst\u00e8me comme provenant de sources ind\u00e9pendantes. Parfois, le Syst\u00e8me devait s&rsquo;arr\u00eater, faire le constat des choses et reconna\u00eetre ses \u00e9checs et ses impuissances pour tenter de les rectifier, comme Little fait aujourd&rsquo;hui \u00e0 l&rsquo;\u00e9gard de la presse antiSyst\u00e8me. Nous avions publi\u00e9 \u00e0 deux reprises, des interventions tr\u00e8s significatives de groupes ou de dirigeants du Syst\u00e8me actant l&rsquo;\u00e9chec que constituait l&rsquo;action du gouvernement US dans ce domaine de la communication.<\/p>\n<\/p>\n<p><p>\t Le <a href=\"http:\/\/www.dedefensa.org\/article-la_crise_de_l_am_ricanisme_engag_dans_la_guerre_28_11_2004.html\" class=\"gen\">28 novembre 2004<\/a>, il s&rsquo;agissait de la divulgation d&rsquo;un rapport de 111 pages du <em>Defense Science Board<\/em> \u00e9crit \u00e0 la demande du secr\u00e9taire \u00e0 la d\u00e9fense Donald Rumsfeld \u00ab<em>pour donner une \u00e9valuation g\u00e9n\u00e9rale de la politique US dans la guerre contre la Terreur, particuli\u00e8rement dans le domaine de la communication (Strategic Communication)<\/em>\u00bb. C&rsquo;\u00e9tait Jim Lobe, de <em>Antiwar.com<\/em>, qui avait eu communication de ce document.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Ce document est stup\u00e9fiant pour la mani\u00e8re dont il dresse un r\u00e9quisitoire implacable des erreurs fondamentales,  diverses strategic mistakes, sur tous les aspects de la guerre contre la Terreur que m\u00e8ne Washington. Il aurait \u00e9t\u00e9 \u00e9crit par Noam Chomsky ou ce m\u00eame Jim Lobe, ou encore par William S. Lind, qu&rsquo;il para\u00eetrait compl\u00e8tement normal. Non, il s&rsquo;agit d&rsquo;un travail officiel qui place l&rsquo;administration GW Bush et Washington en g\u00e9n\u00e9ral devant ses extraordinaires erreurs.<\/em> [&#8230;] <em>La description que ce rapport donne \u00e9galement, dans sa premi\u00e8re partie, du d\u00e9tail des dysfonctionnements, de la paralysie, des guerres internes, des erreurs, de la scl\u00e9rose de la bureaucratie am\u00e9ricaine dans cette guerre est \u00e9galement confondante. Le rapport va jusqu&rsquo;\u00e0 des analyses psychologiques am\u00e9ricaines d&rsquo;une finesse remarquable. Un exemple avec ce passage, dont on gardera les derniers mots comme un chef d&rsquo;oeuvre d&rsquo;observation : Finally, Muslims see Americans as strangely narcissistic  namely, that the war is all about us. As the Muslims see it, everything about the war is  for Americans  really no more than an extension of American domestic politics and its great game. This perception is of course necessarily heightened by election-year atmospherics, but nonetheless sustains their impression that when Americans talk to Muslims they are really just talking to themselves.<\/em> \u00bb<\/p>\n<\/p>\n<p><p>\t Le <a href=\"http:\/\/www.dedefensa.org\/article-un_nouveau_9_10_pour_rumsfeld_20_02_2006.html\" class=\"gen\">20 f\u00e9vrier 2006<\/a>, c&rsquo;\u00e9tait Donald Rumsfeld lui-m\u00eame qui prenait la parole. Cela se passait lors d&rsquo;une conf\u00e9rence qu&rsquo;il donnait devant le <em>Council of Foreign Relations<\/em> (CFR) de Washington, entre amis et comp\u00e8res par cons\u00e9quent. Quelques mois avant sa d\u00e9mission, le secr\u00e9taire \u00e0 la d\u00e9fense actait d\u00e9j\u00e0 l&rsquo;\u00e9chec de sa direction des affaires strat\u00e9giques et militaires, et nous sugg\u00e9rions (titre de l&rsquo;article  : \u00ab<em>Un nouveau 9\/10 pour Rumsfeld?<\/em>\u00bb) que cette intervention constituait un pendant \u00e9trange \u00e0 la premi\u00e8re qu&rsquo;il avait faite, le <a href=\"http:\/\/www.dedefensa.org\/article-le_courage_de_rumsfeld_et_un_discours_qui_m_rite_de_faire_date_11_09_2001.html\" class=\"gen\">10 septembre 2001<\/a>, comme s&rsquo;il actait deux \u00e9checs successifs. Le premier \u00e9chec (9\/10) \u00e9tait de lui-m\u00eame face au Syst\u00e8me apr\u00e8s quelques mois de tentative de r\u00e9forme du Pentagone, le second de lui-m\u00eame incorpor\u00e9 dans le Syst\u00e8me et reconnaissant l&rsquo;\u00e9chec du Syst\u00e8me&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Le plus extraordinaire est certainement la peinture d&rsquo;une r\u00e9alit\u00e9 (car tout cela est bel et bien r\u00e9el) o\u00f9 la puissance moderniste, progressiste, reine de la communication et ainsi de suite, appara\u00eet en pleine lumi\u00e8re pour ce qu&rsquo;elle est,  un g\u00e9ant poussif, scl\u00e9ros\u00e9 et sans imagination, paralys\u00e9 et archa\u00efque. Ce n&rsquo;est pas le fait de n&rsquo;en rien savoir : depuis des ann\u00e9es, des d\u00e9cennies,  oserons-nous ajouter : depuis la naissance de la R\u00e9publique?  l&rsquo;Am\u00e9rique affirme l&rsquo;importance de la communication comme une v\u00e9ritable r\u00e9volution permanente et affirme d&rsquo;un m\u00eame souffle \u00eatre la matrice, la porteuse et la dispensatrice de cette r\u00e9volution. Le r\u00e9sultat, au bout des si\u00e8cles, est significatif pour ceux qui savent voir.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Face \u00e0 cela, depuis 9\/11, il y a un d\u00e9luge de communication pour affirmer la v\u00e9tust\u00e9 d&rsquo;esprit, l&rsquo;archa\u00efsme, l&rsquo;inadaptation des islamistes, des musulmans, des terroristes, et du reste d&rsquo;ailleurs, y compris la old Europe,  tous ces gens d\u00e9pass\u00e9s qui n&rsquo;ont rien compris au credo du modernisme am\u00e9ricaniste passant par la communication. Et voil\u00e0 que Rumsfeld, dans un tour de passe-passe dont il a le secret, nous ass\u00e8ne ces v\u00e9rit\u00e9s qui sont l&rsquo;exact contraire de ce qu&rsquo;on nous r\u00e9p\u00e8te. And I suggest that some humility is in order&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;imposture du Syst\u00e8me est r\u00e9ellement sa marque de fabrique, avec la constance sinon la quasi-p\u00e9rennit\u00e9 de son \u00e9chec dans le domaine o\u00f9 il a toujours affirm\u00e9 son triomphe in\u00e9luctable. Il semble effectivement incapable de bien communiquer, c&rsquo;est-\u00e0-dire d&rsquo;englober les personnes vis\u00e9es, hors de son propre univers justement, dans son propre univers de communication. Cet extrait du rapport de 2004 est \u00e9tonnant, effectivement, de justesse d&rsquo;identification du mal : \u00ab<em>Finally, Muslims see Americans as<\/em> <strong><em>strangely narcissistic  namely, that the war is all about us<\/em><\/strong><em>. As the Muslims see it, everything about the war is  for Americans  really<\/em> <strong><em>no more than an extension of American domestic politics and its great game<\/em><\/strong><em>. This perception is of course necessarily heightened by election-year atmospherics, but nonetheless sustains their impression that<\/em> <strong><em>when Americans talk to Muslims they are really just talking to themselves.<\/em><\/strong>\u00bb L&rsquo;int\u00e9r\u00eat de l&rsquo;\u00e9volution de la situation, c&rsquo;est bien qu&rsquo;il semble de plus que ce que les musulmans pensaient des Am\u00e9ricains \u00e0 cette \u00e9poque (et qu&rsquo;ils pensent plus que jamais, certes), aujourd&rsquo;hui les Am\u00e9ricains (les citoyens des USA) le pensent de plus en plus du Syst\u00e8me qui les dirige, \u00e0 Washington, et des serviteurs de ce Syst\u00e8me, puisqu&rsquo;ils s&rsquo;av\u00e8rent \u00eatre de plus en plus attentifs \u00e0 la presse antiSyst\u00e8me et de plus en plus influenc\u00e9s par elle. Il s&rsquo;agit d&rsquo;une heureuse \u00e9volution, qui identifie de plus en plus le Syst\u00e8me en tant que lui-m\u00eame, et tendant \u00e0 le s\u00e9parer des USA dans le chef de sa population de plus en plus hostile au Syst\u00e8me,  les citoyens US devenant les musulmans des USA, dissidents de l&rsquo;information officielle, sous surveillance constante (NSA et le reste), etc.<\/p>\n<\/p>\n<p><p>\tComme effet principal pour notre compte, nous avons l&rsquo;heureuse bonne nouvelle de voir notre domaine de l&rsquo;internet conduit \u00e0 une sorte d&rsquo;intronisation. Effectivement, cela situe l&rsquo;importance, en un sens, de l&rsquo;intervention de Little. D\u00e9sormais, pour le Pentagone, le domaine que nous d\u00e9signons comme presse antiSyst\u00e8me est plus important du point de vue de l&rsquo;information et de l&rsquo;influence que la presse-Syst\u00e8me. (Cela vaut pour les USA. Nous serions peut-\u00eatre moins affirmatifs pour les pays europ\u00e9ens mais la tendance va certainement dans ce sens \u00e0 cause du discr\u00e9dit extraordinaire que sa soumission au Syst\u00e8me ne cesse d&rsquo;alimenter dans le chef de la presse-Syst\u00e8me. Ils n&rsquo;ont donc de meilleurs ennemis qu&rsquo;eux-m\u00eames, pratiquant avec z\u00e8le leur religion de la surpuissance accouchant de l&rsquo;autodestruction.) Bienvenue dans l&rsquo;univers de la dissidence&#8230;<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 29 juillet 2013 \u00e0 05H24<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Syst\u00e8me face \u00e0 la presse antiSyst\u00e8me Nous avons \u00e9t\u00e9 alert\u00e9s par un article de Infowars.com en pleine jubilation, ce 28 juillet 2013. Sign\u00e9 Adan Salazar et Alex Jones (et suivi d&rsquo;une chronique TV de Jones le soir du m\u00eame jour), la nouvelle exploite une conf\u00e9rence de George Little, assistant du secr\u00e9taire \u00e0 la d\u00e9fense&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[7849,4646,7867,3019,12321,12097,60,12320,3758,3364,4741,569,4392],"class_list":["post-75124","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-alternative","tag-antisysteme","tag-board","tag-defense","tag-dsb","tag-infowars","tag-internet","tag-little","tag-musulmans","tag-presse","tag-presse-systeme","tag-rumsfeld","tag-science"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75124"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75124\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}