{"id":75126,"date":"2013-07-30T03:39:47","date_gmt":"2013-07-30T03:39:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/07\/30\/la-nsa-ou-la-providence-sur-ecoutes\/"},"modified":"2013-07-30T03:39:47","modified_gmt":"2013-07-30T03:39:47","slug":"la-nsa-ou-la-providence-sur-ecoutes","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/07\/30\/la-nsa-ou-la-providence-sur-ecoutes\/","title":{"rendered":"La NSA, ou la Providence sur \u00e9coutes"},"content":{"rendered":"<p><h2 class=\"common-article\">La NSA, ou la Providence sur \u00e9coutes<\/h2>\n<\/p>\n<p><p>\t30 juillet 2013  Nous d\u00e9veloppons un aspect de notre <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-choisir_sa_crise_22_07_2013.html\" class=\"gen\">22 juillet 2013<\/a>, pr\u00e9cis\u00e9ment lorsque nous \u00e9crivions : \u00ab<em>A partir de l\u00e0, et parall\u00e8lement \u00e0 la r\u00e9flexion th\u00e9orique et m\u00e9thodologique que nous poursuivons, il serait logique de proposer une autre r\u00e9flexion, plus conjoncturelle, expliquant et justifiant beaucoup plus en d\u00e9tails et selon la nature de certains composants de la crise ce choix de l&rsquo;int\u00e9r\u00eat pour telle crise plut\u00f4t que pour telle autre. Nous aurions l\u00e0 un compl\u00e9ment absolument<\/em> <strong><em>n\u00e9cessaire<\/em><\/strong> <em>\u00e0 notre d\u00e9marche, avec l&rsquo;explication fondamentale et essentielle de ce en quoi cette crise choisie par nous apporte effectivement de suppl\u00e9ment d&rsquo;exploration et de compr\u00e9hension de la crise g\u00e9n\u00e9rale d&rsquo;effondrement du Syst\u00e8me. Ce sujet divergeant notablement de la r\u00e9flexion d\u00e9velopp\u00e9e ici, sera trait\u00e9 ind\u00e9pendamment, et certainement tr\u00e8s rapidement, par un second F&#038;C<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDans ce propos, nous voulions signifier qu&rsquo;il nous para\u00eet important de comprendre <strong>\u00e9galement<\/strong> un aspect de l&rsquo;essence m\u00eame de la crise Snowden\/NSA, c&rsquo;est-\u00e0-dire l&rsquo;objet de cette crise. Nous parlons de la NSA, mais aussi, avec \u00e0 l&rsquo;esprit le compagnonnage de la NSA notamment avec Google, dont l&rsquo;on conna\u00eet les projets eschatologiques (voir le <a href=\"http:\/\/www.dedefensa.org\/article-notre_intelligence_et_la_chute_07_06_2013.html\" class=\"gen\">7 juin 2013<\/a> et le <a href=\"http:\/\/www.dedefensa.org\/article-ecce_homo-google_22_07_2013.html\" class=\"gen\">22 juillet 2013<\/a>), c&rsquo;est-\u00e0-dire comme si le <em>sapiens-corporate<\/em> (<em>dito<\/em>, tr\u00e8s pr\u00e9cis\u00e9ment les dirigeants de Google) \u00e9tait sorti du lot commun de l&rsquo;humaine nature et r\u00e9glait les \u00e9v\u00e9nements au-del\u00e0 des bornes que nous connaissons, pour cette humaine nature. (En un sens, Google, qui appara\u00eet comme \u00e9mergeant du lot du <em>Big Business<\/em> US, est <strong>\u00e0 la fois<\/strong> M\u00e9phistoph\u00e9l\u00e8s et Faust : il se propose \u00e0 lui-m\u00eame le march\u00e9 de la disposition d&rsquo;une puissance contre son \u00e2me, et, passant \u00e0 son enveloppe faustienne, il accepte \u00e9videmment et se donne \u00e0 lui-m\u00eame \u00e0 la fois cette puissance et son \u00e2me. Reste \u00e0 voir les p\u00e9rip\u00e9ties que l&rsquo;affaire Snowden\/NSA vont faire conna\u00eetre \u00e0 la cotation en bourse de cette puissance et de l&rsquo;\u00e2me de Google-Faust donn\u00e9e \u00e0 Google-M\u00e9phistoph\u00e9l\u00e8s.)<\/p>\n<\/p>\n<p><p>\tLa situation telle qu&rsquo;elle est au point actuel d&rsquo;une \u00e9volution extr\u00eamement rapide acquiert une singuli\u00e8re importance dans le chef de cette quasi-fusion des ambitions de la NSA et de Google, ambitions disons postm\u00e9taphysiques (comme l&rsquo;on dit postmoderniste,  c&rsquo;est-\u00e0-dire au-del\u00e0 de la modernit\u00e9 selon notre interpr\u00e9tation,  donc au-del\u00e0 de la m\u00e9taphysique pour Google-NSA, d&rsquo;une m\u00e9taphysique qui, par ailleurs, n&rsquo;existe plus selon la pens\u00e9e-Syst\u00e8me courante). Cela sert d&rsquo;introduction \u00e0 la fois utile et p\u00e9remptoire \u00e0 l&rsquo;appr\u00e9ciation qu&rsquo;on va donner de la NSA, cette appr\u00e9ciation permettant de compl\u00e9ter l&rsquo;importance que nous donnons \u00e0 la crise Snowden\/NSA. Pour conduire \u00e0 bien cette appr\u00e9ciation, il faut commencer par l&rsquo;origine.<\/p>\n<\/p>\n<p><p>\tEn 1949 fut cr\u00e9\u00e9e l&rsquo;AFSA (Armed Forces Security Agency), qui s&rsquo;av\u00e9ra selon la formule initiale beaucoup trop restreinte dans ses capacit\u00e9s pour les ambitions am\u00e9ricanistes. En 1951, une r\u00e9forme fut ordonn\u00e9e et, \u00e0 la suite d&rsquo;un rapport circonstanci\u00e9e, l&rsquo;AFSA devint en octobre 1952 la NSA (National Security Agency), aux pr\u00e9rogatives largement \u00e9tendues au-del\u00e0 du seul cercle des forces arm\u00e9es. (Voir l&rsquo;article <a href=\"http:\/\/en.wikipedia.org\/wiki\/National_Security_Agency\" class=\"gen\">NSA<\/a> dans le <em>Wikip\u00e9dia<\/em>, tr\u00e8s fortement document\u00e9.) Ainsi la NSA occupe-t-elle une place singuli\u00e8re :<\/p>\n<\/p>\n<p><p>\t Parmi les agences et services des forces arm\u00e9es, elle est fortement \u00e9largie aux domaines non-militaires dans son propre domaine d&rsquo;action. Cet \u00e9largissement permet \u00e0 la NSA de jouer compl\u00e8tement son r\u00f4le dans le r\u00e9seau <em>Echelon<\/em>, ou <a href=\"http:\/\/en.wikipedia.org\/wiki\/AUSCANNZUKUS \" class=\"gen\">AUSCANNZUKUS<\/a>, form\u00e9 en plusieurs \u00e9tapes \u00e0 partir d&rsquo;un accord USA-UK de 1946 d&rsquo;\u00e9coute et de surveillance conjointes (tout de m\u00eame, avec les USA dirigeant et dispatchant le tout). <em>Echelon<\/em> rassemble tous les pays <strong>anglo-saxons<\/strong> (Australie, Canada, Nouvelle-Z\u00e9lande, UK, USA). Ce point est essentiel.<\/p>\n<\/p>\n<p><p>\t  Ce point est essentiel, en effet, parce que l&rsquo;AFSA devenue NSA est tout de m\u00eame, bien entendu, partie prenante du Complexe Militaro-Industriel (CMI). Cette immense n\u00e9buleuse, cette entit\u00e9, ce syst\u00e8me anthropotechnocratique, cette \u00e9gr\u00e9gore d\u00e9finie par la m\u00e9taphore <em>Moby Dick<\/em> ou la m\u00e9taphore Achab selon le sentiment qu&rsquo;on en a (voir le <a href=\"http:\/\/www.dedefensa.org\/article-achab_sait-il_encore_rationnaliser_sa_folie__17_07_2013.html\" class=\"gen\">17 juillet 2013<\/a>), est aussi, <em>in fine<\/em> un projet qu&rsquo;on pourrait qualifier de prom\u00e9th\u00e9en ; et il l&rsquo;est d&rsquo;une fa\u00e7on qui l&rsquo;apparente plus \u00e0 des forces sup\u00e9rieures qu&rsquo;\u00e0 des volont\u00e9s humaines pleinement et consciemment assum\u00e9es, lorsqu&rsquo;on conna\u00eet le poids n\u00e9gligeable des cr\u00e9atures humaines plac\u00e9es \u00e0 sa t\u00eate et n&rsquo;ayant aucune stabilit\u00e9 de l&rsquo;exercice du pouvoir ; lorsqu&rsquo;\u00e9galement l&rsquo;on sait que des cr\u00e9atures humaines du CMI montr\u00e8rent des vell\u00e9it\u00e9s fameuses de r\u00e9volte contre son empire, notamment parmi les plus fameuses le pr\u00e9sident Eisenhower le <a href=\"http:\/\/www.dedefensa.org\/article-un_general-president_nous_parle_du_complexe_militaro-industriel_10_08_2005.html\" class=\"gen\">16 janvier 1961<\/a> et le secr\u00e9taire \u00e0 la d\u00e9fense Rumsfeld le <a href=\"http:\/\/www.dedefensa.org\/article-le_courage_de_rumsfeld_et_un_discours_qui_m_rite_de_faire_date_11_09_2001.html\" class=\"gen\">10 septembre 2001<\/a>.<\/p>\n<\/p>\n<p><p>\tDeux \u00e9v\u00e9nements au sens tr\u00e8s large du mot \u00e9clairent d&rsquo;une lumi\u00e8re singuli\u00e8re les origines du CMI, et son orientation et son organisation <strong>id\u00e9ologiques<\/strong> d\u00e8s ces origines, et par cons\u00e9quent leurs effets n\u00e9cessaires sur la NSA. Nous allons les rappeler \u00e0 partir de deux extraits de la <a href=\"http:\/\/www.dedefensa.org\/article-la_grace_de_l_histoire_cinquieme_partie_02_12_2010.html\" class=\"gen\">Cinqui\u00e8me Partie<\/a> du premier tome de <em>La gr\u00e2ce de l&rsquo;Histoire<\/em> (\u00ab<em>La transversale du technologisme<\/em>\u00bb).<\/p>\n<\/p>\n<p><p>\t Sur les origines m\u00eames du CMI, quand le M (Militaro) n&rsquo;avait pas encore de raison d&rsquo;\u00eatre (ces origines se situent entre 1935 et 1937, avec l&rsquo;\u00e9tablissement d&rsquo;un tripode scientifique,  l&rsquo;observatoire de Pasadena, la biblioth\u00e8que Huntington et le California Institute of Technology, ou CaltTech). Ce dernier point tend \u00e0 renforcer l&rsquo;interpr\u00e9tation du r\u00f4le fondamental de la NSA tel qu&rsquo;on peut le distinguer aujourd&rsquo;hui. L&rsquo;\u00e9l\u00e9ment militaire est pr\u00e9sent mais il n&rsquo;en est en rien restrictif de rien du tout et s&rsquo;il est central pour l&rsquo;administration et la direction de la gestion, il n&rsquo;en est pas moins qu&rsquo;un \u00e9l\u00e9ment parmi d&rsquo;autres. Les ambitions de la NSA sont globales, dans tout le sens du mot, donc embrassant tous les domaines de la puissance, au-del\u00e0 de la seule composante militaire. (Voir aussi, parmi nos tr\u00e8s nombreux articles sur le CMI, celui qui d\u00e9crit en d\u00e9tails les p\u00e9rip\u00e9ties les plus lointaines des origines du CMI, le <a href=\"http:\/\/www.dedefensa.org\/article-aux_sources_du_cmi_rubrique_analyse_de_defensa_volume_21_n_09_du_25_janvier_2005_02_02_2006.html\" class=\"gen\">2 f\u00e9vrier 2006<\/a>.) Voici l&rsquo;extrait de <em>La gr\u00e2ce de l&rsquo;Histoire<\/em> :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>&#8230;Il s&rsquo;agit alors, encore dans les remous de la Grande D\u00e9pression o\u00f9 l&rsquo;on d\u00e9nonce les agissements de la racaille socialiste rassembl\u00e9e autour de lui par Roosevelt, de cr\u00e9er un p\u00f4le de puissance utilisant le g\u00e9nie scientifique et l&rsquo;habilet\u00e9 financi\u00e8re, rassembl\u00e9s dans la dynamique sans \u00e9gale qu&rsquo;est le d\u00e9veloppement technologique. Il y a effectivement, sous-jacente, une dimension s&rsquo;exprimant par l&rsquo;espoir fi\u00e9vreux que cette dynamique est grosse d&rsquo;une transmutation, effectivement de caract\u00e8re m\u00e9tahistorique comme nous l&rsquo;avons signal\u00e9 plus haut, qui serait capable d&rsquo;imposer une transformation d\u00e9cisive extrayant l&rsquo;Am\u00e9rique des scories de la Grande D\u00e9pression pour l&rsquo;installer au plus haut dans l&rsquo;humanit\u00e9, dans une sorte d&rsquo;envol\u00e9e supra-humaine. La Californie du Sud et Los Angeles ont \u00e9t\u00e9 choisis par ce rassemblement de personnalit\u00e9s de renom, parce que les \u00e9migrants, les non-WASP (White Anglo-Saxon Protestant), y sont encore peu nombreux, parce qu&rsquo;il y r\u00e8gne effectivement cette atmosph\u00e8re \u00e9trange de mysticisme et d&rsquo;\u00e9sot\u00e9risme, o\u00f9 les avanc\u00e9es scientifiques sont consid\u00e9r\u00e9es selon leurs rapports \u00e9vidents avec la religion et avec la race nordique. Dans son livre City of Quartz  Excavating the future of Los Angeles, le sociologue, urbaniste et historien de Los Angeles Mike Davies caract\u00e9rise de la sorte l&rsquo;orientation de ce mouvement, dont l&rsquo;une des chevilles ouvri\u00e8res est le physicien Robert Millikan, venu de la direction de l&rsquo;universit\u00e9 de Chicago pour prendre celle du fameux Institut Technologique de Californie (CalTech) :<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Dans son r\u00f4le d&rsquo;entra\u00eeneur du mouvement dans la position qu&rsquo;il occupait de directeur de Cal Tech, Millikan se transforma de plus en plus en un id\u00e9ologue d&rsquo;une vision tr\u00e8s sp\u00e9cifique de la science pour la Californie du Sud. Parlant lors d&rsquo;occasion tr\u00e8s exemplaire devant l&rsquo;\u00e9litiste California Club de Los Angeles, ou \u00e0 un banquet pour cette association au manoir de Huntington, Millikan insistait particuli\u00e8rement sur deux point fondamentaux. Le premier \u00e9tait que la Californie du Sud constituait une extension scientifique unique o\u00f9 la recherch\u00e9 acad\u00e9mique et industrielle s&rsquo;assemblaient pour r\u00e9soudre des d\u00e9fis scientifiques aussi fondamentaux que la transmission \u00e0 distance de la puissance et la cr\u00e9ation d&rsquo;\u00e9nergie \u00e0 partir de la lumi\u00e8re solaire. Le second, encore plus important, \u00e9tait qu&rsquo;aujourd&rsquo;hui, comme le fut l&rsquo;Angleterre il y a deux si\u00e8cles, la Californie est le poste avanc\u00e9 le plus occidental de la civilisation nordique&rsquo;, avec l&rsquo;exceptionnelle opportunit\u00e9 d&rsquo;avoir une population qui comprend le double d&rsquo;Anglo-Saxons que dans les autres grandes r\u00e9gions et villes de ce pays, comme New York ou Chicago.&rsquo;<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Ainsi Davies d\u00e9finit l&rsquo;interpr\u00e9tation que donne Millikan de la science et du business, comme les voies et moyens recr\u00e9ant la sup\u00e9riorit\u00e9 aryenne (reproducing Aryan supremacy) dans le Sud de la Californie. L\u00e0 est le cur fervent et bouillonnant du Complexe, avec son foyer scientifique de CalTech s&rsquo;exprimant dans la puissance technologique de l&rsquo;a\u00e9ronautique plong\u00e9e dans sa dynamique d&rsquo;affirmation de sa puissance industrielle  et ce cur qui bat est anglo-saxon, c&rsquo;est-\u00e0-dire aryen selon ces th\u00e9oriciens et id\u00e9ologues audacieux (Certes, quelques Juifs s&rsquo;\u00e9taient gliss\u00e9s dans cette vaste entreprise, \u00e0 CalTech, comme Albert Einstein par exemple, mais passons outre ces d\u00e9tails.)<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Sur la forme que prit l&rsquo;activit\u00e9 scientifique du CMI \u00e0 partir des rapports qui s&rsquo;\u00e9tablirent par le simple courant des saisies et des appropriations de l&rsquo;un sur l&rsquo;autre, entre le CMI et l&rsquo;ensemble de d\u00e9veloppement de la science mis en place par les nazis. C&rsquo;est au sein d&rsquo;organisations sp\u00e9cifiques, renvoyant aux domaines les plus id\u00e9ologis\u00e9s et les plus fanatis\u00e9s, comme la SS, que les nazis d\u00e9velopp\u00e8rent cette approche qui portaient sur des orientations tr\u00e8s sp\u00e9cifiques, tr\u00e8s diff\u00e9rents de ceux de la science traditionnelle, notamment avec des \u00e9l\u00e9ments mythiques, voire magiques y \u00e9tant incorpor\u00e9s. Tout cela sculpta un syst\u00e8me tr\u00e8s sp\u00e9cifique qui eut son influence sur le CMI, \u00e0 partir de 1944-1945 comme on le pr\u00e9cise ci-dessous. (Voir aussi, pour plus de pr\u00e9cision sur la citation de Nick Cook, notre texte du <a href=\"http:\/\/www.dedefensa.org\/article-une_dimension_trange_et_effrayante_du_cmi_am_ricaniste_21_07_2005.html\" class=\"gen\">21 juillet 2005<\/a>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Dans son d\u00e9veloppement, d\u00e8s ses origines, cette entit\u00e9 massive qu&rsquo;est le Pentagone ne dissimula pas, \u00e0 plus d&rsquo;une occasion, sa fascination pour l&rsquo;orientation de la science nazie, et notamment pour ses m\u00e9thodologies, principalement \u00e0 l&rsquo;occasion de l&rsquo;incorporation dans son vaste domaine de scientifiques et chercheurs allemands en 1945-1947 (Operation PaperClip), qui avaient travaill\u00e9 durant plus d&rsquo;une d\u00e9cennie dans des structures et selon des orientations contr\u00f4l\u00e9es et d\u00e9termin\u00e9es par le parti national-socialiste, et, pr\u00e9cis\u00e9ment, la SS. L&rsquo;historien et journaliste militaire, Nick Cook, sp\u00e9cialis\u00e9 dans des recherches sur les programmes secrets du Pentagone (black programs), expliquait dans une interview \u00e0 The Atlantic Monthly, le 5 septembre 2002,  et le propos, d\u00e9barrass\u00e9 des prudences de rigueur, est lumineux :<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Comment avaient-ils d\u00e9velopp\u00e9 cela? Sur quel mod\u00e8le s&rsquo;\u00e9taient-ils bas\u00e9s? Leur mod\u00e8le est remarquablement similaire au syst\u00e8me qui \u00e9tait utilis\u00e9 par les Allemands,  sp\u00e9cialement, la SS,  pour leurs programmes de syst\u00e8mes d&rsquo;arme ultrasecrets durant la Deuxi\u00e8me Guerre mondiale. Alors, est-ce que quelqu&rsquo;un, disons un Hans Kammler ou quelqu&rsquo;un d&rsquo;autre, avait fourni un mod\u00e8le, on dirait clef sur porte&rsquo;, au gouvernement des USA \u00e0 la fin de la guerre? Je ne connais pas la r\u00e9ponse \u00e0 cette question mais si l&rsquo;on consid\u00e8re le recrutement massif<\/em> [de personnels allemands] <em>durant l&rsquo;op\u00e9ration Paperclip, et selon ce qu&rsquo;on sait du black world des programmes militaires US, il ne semble nullement d\u00e9plac\u00e9 de se poser de telles questions.<\/em> [] <em>Ce que je veux dire, c&rsquo;est que si vous suivez les tendances des scientifiques et des ing\u00e9nieurs Nazis qui furent recrut\u00e9s par les USA \u00e0 la fin de la Seconde Guerre mondiale, le malheureux et in\u00e9vitable corollaire auquel vous parvenez est qu&rsquo;en vous appropriant leur science, vous h\u00e9ritez \u00e9galement, m\u00eame si involontairement, d&rsquo;un peu de leur id\u00e9ologie. La science qui en sort est n\u00e9cessairement  teint\u00e9e de quelque chose d&rsquo;autre. Et il s&rsquo;agit de quelque chose avec laquelle vous devez \u00eatre tr\u00e8s prudent. Il s&rsquo;agit d&rsquo;un effet collat\u00e9ral extr\u00eamement d\u00e9plaisant et dangereux et, si vous n&rsquo;\u00eates pas tr\u00e8s attentif, vous perdez de vue l&rsquo;essence m\u00eame de ce que vous \u00eates cens\u00e9 prot\u00e9ger.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDepuis 1952, le d\u00e9veloppement de la NSA s&rsquo;est fait d&rsquo;une fa\u00e7on exponentielle suivant deux courbes qui n&rsquo;ont fait que se renforcer l&rsquo;une l&rsquo;autre : d&rsquo;une part le d\u00e9veloppement du CMI lui-m\u00eame, d&rsquo;autre part le d\u00e9veloppement des communications avec l&rsquo;apparition des technologies du domaine, une des branche les plus sp\u00e9cifiques et novatrices de l&rsquo;\u00e9lectronique. (Il faut signaler que l&rsquo;\u00e9lectronique s&rsquo;est d\u00e9velopp\u00e9e aux USA, notamment et essentiellement sur financement de l&rsquo;USAAF devenue USAF en 1947, \u00e0 partir d&rsquo;un \u00e9norme rapport r\u00e9alis\u00e9 en 1944-1945 sous la direction de Theodore von Karman [de CalTech], <em>Toward the Horizon<\/em>, \u00e0 la demande du g\u00e9n\u00e9ral Arnold, commandant en chef de l&rsquo;USAAF-USAF, et portant sur le d\u00e9veloppement des technologies \u00e0 venir dans les 25 ans \u00e0 partir de 1945.) Le d\u00e9veloppement de la NSA s&rsquo;effectua \u00e9galement d&rsquo;une mani\u00e8re subreptice, sans aspect v\u00e9ritablement spectaculaire, au contraire par exemple de la CIA, de la DIA du Pentagone, des divers services arm\u00e9es du Pentagone, de l&rsquo;industrie de l&rsquo;armement, etc. (L&rsquo;argument du secret pour expliquer cette discr\u00e9tion ne tient gu\u00e8re dans la mesure o\u00f9 il affecte les autres agences soumises aux m\u00eames r\u00e8gles, comme celles que nous avons cit\u00e9es ; on verra plus loin notre argument \u00e0 cet \u00e9gard.)  C&rsquo;est dans les ann\u00e9es 1960 que la NSA prit v\u00e9ritablement son essor, sans \u00eatre pour autant plus connue, avec le d\u00e9but de l&rsquo;introduction massives des technologies de la communication (l&rsquo;\u00e9lectronique, l&rsquo;informatique, etc.).<\/p>\n<\/p>\n<p><p>\tIl nous importe d&rsquo;insister sur une autre dimension de ces ann\u00e9es 1960, marqu\u00e9es par diverses trag\u00e9dies (l&rsquo;assassinat de Kennedy apr\u00e8s la crise de Cuba, les r\u00e9voltes noire et \u00e9tudiante, le Vi\u00eat-Nam, etc.). Le CMI se trouva plac\u00e9 devant une perspective qui apparut soudainement comme ambigu\u00eb et explosive. Cette perspective \u00e9tait op\u00e9rationnalis\u00e9e par la doctrine MAD (Destruction Mutuelle Assur\u00e9e, qui s&rsquo;appuie sur une perspective d&rsquo;armement de destruction plan\u00e9taire d&rsquo;une part, une impossibilit\u00e9 de faire la guerre en raison des capacit\u00e9s de ces armements d&rsquo;autre part). Les dimensions mythiques et symboliques de cette situation sont \u00e9videntes. Elles furent symbolis\u00e9es par un \u00e9v\u00e9nement relevant \u00e0 la fois du monde m\u00e9diatique, du monde secret et du monde de l&rsquo;imposture, qui est le fameux document <em>Report from the Iron Mountain<\/em>. (Voir notamment l&rsquo;<a href=\"http:\/\/en.wikipedia.org\/wiki\/The_Report_from_Iron_Mountain\" class=\"gen\">article<\/a> de <em>Wikileaks<\/em> et un <a href=\"http:\/\/www.museumofhoaxes.com\/hoax\/archive\/permalink\/report_from_iron_mountain\" class=\"gen\">article<\/a> non dat\u00e9 de <em>The Museum of Hoax<\/em>.) Dans un article sur une livraison de <em>dde.crisis<\/em>, le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_le_complexe_ddecrisis_21_02_2011.html\" class=\"gen\">21 f\u00e9vrier 2011<\/a>, nous \u00e9crivions :<\/p>\n<\/p>\n<p><p>\t\u00ab[Dans les ann\u00e9es 1960, le] <em>Complexe devient donc syst\u00e8me, soit technocratique, soit mystique (\u00e9gr\u00e9gore), ou les deux \u00e0 la fois, et il \u00e9tablit aussit\u00f4t son empire. Divers signes nous informent de cette transformation radicale. Le plus \u00e9trange et le plus caract\u00e9ristique est un livre pr\u00e9sentant un soi-disant rapport officiel r\u00e9dig\u00e9 par un rassemblement d&rsquo;experts, qui est un faux caricatural \u00e9crit par les adversaires du Complexe, mais qui rencontre involontairement les ambitions du Complexe. Report From Iron Mountain,  le bien nomm\u00e9 avec cette r\u00e9f\u00e9rence \u00e0 une montagne de fer,  \u00e9tablit la n\u00e9cessit\u00e9 d&rsquo;une guerre perp\u00e9tuelle pour l&rsquo;accomplissement de la destin\u00e9e manifeste du Complexe. Ce faux rapport r\u00e9sonne \u00e9trangement, comme s&rsquo;il \u00e9tait vrai, \u00e0 l&rsquo;heure de la guerre sans fin contre la Terreur.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDurant ces ann\u00e9es, la NSA eut, du point de vue de la notori\u00e9t\u00e9 et de l&rsquo;influence, une existence assez courante d&rsquo;une grande agence du gouvernement, loin de la notori\u00e9t\u00e9 de la CIA ou d&rsquo;autres grands crus du Pentagone. Les repr\u00e9sentants de la NSA \u00e9taient auditionn\u00e9s au Congr\u00e8s, parfois s\u00e9v\u00e8rement, des hommes de la NSA entreprenaient des missions dangereuse (sur le USS <em>Liberty<\/em> coul\u00e9 par erreur par les Isra\u00e9liens en 1967, sur le USS <em>Pueblo<\/em>, arraisonn\u00e9 en toute connaissance de cause en 1968 par les Nord-Cor\u00e9ens). Aucun nom n&rsquo;\u00e9mergeait de la NSA pour imposer une certaine notori\u00e9t\u00e9. C&rsquo;est pourtant durant ces ann\u00e9es-l\u00e0 que se situe un \u00e9v\u00e9nement symbolique et \u00e9trange, avec la cr\u00e9ation du blason de la NSA, ou du sceau c&rsquo;est selon, pr\u00e9sent\u00e9 d\u00e9finitivement en 1965. Il est ainsi <a href=\"http:\/\/www.nsa.gov\/about\/faqs\/about_nsa.shtml#about9\" class=\"gen\">d\u00e9crit<\/a> sur le site de l&rsquo;Agence, dans les <em>Frequently Asked Questions<\/em>&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The NSA seal was designed in 1965 by direction of NSA Director LTG Marshall S. Carter, United States Army. The seal shows an eagle within a circle, holding a key. The eagle  a symbol of courage, supreme power, and authority  represents the national scope of NSA&rsquo;s mission. The shield on the eagle&rsquo;s breast is drawn from the Great Seal of the United States, and represents the states drawn together under a single chief that unites them and represents Congress. The key in the eagle&rsquo;s talons represents security. It evolved from the emblem of St. Peter the Apostle, and his power \u00ab\u00a0to loose and to bind.\u00a0\u00bb The circular shape of the seal is a symbol of eternity.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDans le cas de la NSA et dans la perspective de ce qu&rsquo;elle est devenue et de ce qu&rsquo;on d\u00e9couvre d&rsquo;elle, nous sommes particuli\u00e8rement attentifs \u00e0 l&rsquo;aspect symbolique dans la mesure o\u00f9 il s&rsquo;agit d&rsquo;une entit\u00e9 d&rsquo;une immense puissance, d\u00e9velopp\u00e9e exponentiellement et sans la moindre entrave, qui dispose donc de tous les moyens n\u00e9cessaires pour un \u00e9ventuel dessein, et qui, par cons\u00e9quent, n&rsquo;a besoin <strong>que d&rsquo;un sens<\/strong> pour d\u00e9terminer ce dessein. Ce sens ne peut \u00eatre indiqu\u00e9, bien entendu, que par les symboles dont elle se pare. Ces symboles, apparus dans son sceau, d\u00e9couvrent des ambitions extraordinaires,  mais logiques, si on les place dans le bric-\u00e0-brac du mysticisme am\u00e9ricaniste, et particuli\u00e8rement du CMI, dont on a fait quelques rappels plus haut.<\/p>\n<\/p>\n<p><p>\t Les cl\u00e9s de Saint-Pierre, qui constituent la porte des cieux (Dans l&rsquo;<em>Evangile selon Jean<\/em>, ceci, o\u00f9 les verbes <em>to loose<\/em> et <em>to bind<\/em> signifient lier et d\u00e9lier : \u00ab<em>Et moi je te dis que tu es Pierre, et sur cette pierre je b\u00e2tirai mon \u00c9glise. Je te donnerai les clefs du royaume des cieux. Ce que tu lieras sur la terre sera li\u00e9 dans les cieux, et ce que tu d\u00e9lieras sur la terre sera d\u00e9li\u00e9 dans les cieux.<\/em>\u00bb) Voici donc la NSA pr\u00e9sent\u00e9e symboliquement comme ma\u00eetresse de l&rsquo;acc\u00e8s des cieux aussi bien que des espaces terrestres&#8230;<\/p>\n<\/p>\n<p><p>\t Le cercle repr\u00e9sente l&rsquo;\u00e9ternit\u00e9&#8230; Cela n&rsquo;a pas besoin de longues explications, mais induit le constat qu&rsquo;il y a une r\u00e9elle logique qui s&rsquo;exerce entre cette r\u00e9f\u00e9rence et la place offerte \u00e0 Saint-Pierre. Pour la NSA, la perspective de son d\u00e9veloppement et de ses ambitions n&rsquo;a pas de limites et s&rsquo;exerce dans le champ m\u00e9taphysique et selon les normes de la religion dans ses implications les plus hautes.<\/p>\n<\/p>\n<p><p>\tAinsi en arrive-t-on au constat d&rsquo;une carri\u00e8re \u00e9trange de la NSA, avant d&rsquo;arriver \u00e0 la situation pr\u00e9sente. <strong>D&rsquo;une part<\/strong>, il existe une certaine discr\u00e9tion dans le chef de cette agence, non pas tant \u00e0 cause du secret (il est valable pour toutes les agences de cette sorte) qu&rsquo;\u00e0 cause du manque d&rsquo;attrait de communication d&rsquo;une telle entit\u00e9 ; c&rsquo;est, \u00e0 notre sens, \u00e9galement beaucoup moins \u00e0 cause du secret et essentiellement \u00e0 cause du manque d&rsquo;attrait, paradoxalement en mati\u00e8re de communication (du point de vue m\u00e9diatique), que la NSA fut longtemps surnomm\u00e9e <em>No Such Agency<\/em>,  comme si elle n&rsquo;existait pas. En un mot un peu enlev\u00e9, pendant longtemps la NSA n&rsquo;a pas \u00e9t\u00e9 tr\u00e8s <em>sexy<\/em> par rapport, par exemple, \u00e0 la CIA. (Le premier livre s\u00e9rieux et d\u00e9taill\u00e9 sur la NSA date de 1982,  c&rsquo;est <em>Puzzle Palace<\/em> de John Bramont, qui s&rsquo;adresse surtout \u00e0 des sp\u00e9cialistes de la communication technique. A comparer avec la profusion d&rsquo;ouvrages sur la CIA, d\u00e8s les ann\u00e9es 1950.) <strong>D&rsquo;autre part<\/strong>, et ceci d\u00e9cisivement pour notre propos, il existe le d\u00e9veloppement d&rsquo;une sorte de conscience-Syst\u00e8me de la NSA, qui n&rsquo;\u00e9mane d&rsquo;aucune entit\u00e9 humaine, aucune pens\u00e9e rationnelle, aucun groupe ou l&rsquo;autre, et qui est pourtant r\u00e9sum\u00e9 symboliquement par son sceau, qui m\u00e9riterait dans ce cas d&rsquo;\u00eatre per\u00e7u vraiment comme un blason ; il s&rsquo;agit de la sorte de conscience-Syst\u00e8me d&rsquo;\u00eatre une force \u00e9chappant au standard et aux conceptions communes, pour se projeter parmi les dieux. Cette conception est appuy\u00e9e sur un courant, dissimul\u00e9 mais puissant, du legs du CMI, d&rsquo;une sorte de supr\u00e9matisme mystique, ou bien plut\u00f4t magique et d&rsquo;un \u00e9sot\u00e9risme \u00e0 mesure, allant jusqu&rsquo;\u00e0 p\u00eacher dans les eaux troubles et agit\u00e9es des grandiloquences du nazisme. (Dans un article du <a href=\"http:\/\/www.admiroutes.asso.fr\/larevue\/2013\/137\/scaringella.htm\" class=\"gen\">3 juillet 2013<\/a> sur <em>Automates Intelligents<\/em>, site de Jean-Paul Baquiast, qu&rsquo;on retrouve souvent sur <em>dedefensa.org<\/em>, Bernard Scaringella, qui intervient \u00e9galement parfois sur notre Forum, met en \u00e9vidence combien la politique dans tous les cas d&rsquo;absolu dans l&rsquo;accumulation de la mati\u00e8re de la NSA, politique dite des <em>big data<\/em>, fait s&rsquo;interroger pour savoir si l&rsquo;on n&rsquo;est pas plut\u00f4t du c\u00f4t\u00e9 de la magie que du c\u00f4t\u00e9 de lza science.) <\/p>\n<h3>Transmutation de la NSA<\/h3>\n<\/p>\n<p><p>\tCe qui nous importe ici est de d\u00e9terminer l&rsquo;essence m\u00eame de la NSA, comme s&rsquo;il s&rsquo;agissait d&rsquo;une entit\u00e9 pouvant \u00eatre envisag\u00e9e comme telle, et m\u00eame plut\u00f4t une \u00e9gr\u00e9gore en plus d&rsquo;\u00eatre syst\u00e8me anthropotechnocratique. Il s&rsquo;agit de comprendre comment cette agence parvient finalement \u00e0 \u00eatre, comme elle l&rsquo;est aujourd&rsquo;hui, l&rsquo;objet de toutes les attentions, de toutes les fascinations secr\u00e8tes, de toutes les falsifications, de toutes les craintes et terreurs les plus justifi\u00e9es ; comment, du point de vue op\u00e9rationnel qui marque bien l&rsquo;\u00e9volution, elle est devenue la source du plus grand nombre de <em>whistleblower<\/em> ces derni\u00e8res ann\u00e9es. (Snowden est \u00e9videmment spectaculaire parce qu&rsquo;il a avec lui des montagnes de documents, mais il a \u00e9t\u00e9 pr\u00e9c\u00e9d\u00e9 de plusieurs <em>whistleblower<\/em> de la NSA durant les douze derni\u00e8res ann\u00e9es. Depuis 9\/11, les dissidents viennent beaucoup plus de la NSA que, disons, de la CIA.)<\/p>\n<\/p>\n<p><p>\tL&rsquo;attention port\u00e9e \u00e0 la NSA a commenc\u00e9 \u00e0 se manifester d&rsquo;une mani\u00e8re tangible dans le syst\u00e8me de la communication dans sa dimension publique et m\u00e9diatique, \u00e0 partir de l&rsquo;affaire du r\u00e9seau <em>Echelon<\/em>, au milieu des ann\u00e9es 1990. Mais encore, il ne s&rsquo;agissait que de communication nous dirions d&rsquo;un point de vue technique. D&rsquo;autre part, <em>Echelon<\/em> ne concernait que l&rsquo;ext\u00e9rieur des USA (et des anglo-saxons). L&rsquo;Europe habitu\u00e9e par de longues ann\u00e9es de servilit\u00e9 \u00e0 de telles incursions US, et d&rsquo;ailleurs par sa complicit\u00e9 \u00e0 cet \u00e9gard, n&rsquo;insista pas vraiment, sauf le Parlement europ\u00e9en qui sait, dans cette sorte d&rsquo;occasion, montrer une certaine alacrit\u00e9. Bref, \u00e0 peine horrifi\u00e9s par le spectacle de la chose, on referma la plaie et l&rsquo;on n&rsquo;en parla plus.<\/p>\n<\/p>\n<p><p>\tAvec 9\/11, tout changea. Techniquement, la Guerre contre la Terreur \u00e9tait, du point de vue am\u00e9ricaniste, un fantastique argument pour la NSA. Le terrorisme organis\u00e9 \u00e9tant, par sa nature m\u00eame, \u00e0 la fois insaisissable op\u00e9rationnellement et dans l&rsquo;obligation pourtant de communiquer, le r\u00f4le th\u00e9orique de la NSA trouva un domaine d&rsquo;expansion consid\u00e9rable. En m\u00eame temps, l&rsquo;explosion des technologies de communication et de l&rsquo;internet fournissait un argument suppl\u00e9mentaire, \u00e9galement d&rsquo;un poids consid\u00e9rable. La NSA devint ainsi un acteur central du dispositif de s\u00e9curit\u00e9 nationale (et internationale) des USA et du CMI,  et par acteur, il faut entendre le mot aussi bien du point de vue technique que du point de vue symbolique que quasiment m\u00e9taphysique \u00e0 la sauce postmoderniste. Elle l&rsquo;est aujourd&rsquo;hui, d&rsquo;une mani\u00e8re \u00e9crasante Techniquement toujours, mais au sens large et conceptuel du terme et en englobant l&rsquo;histoire de la NSA jusqu&rsquo;\u00e0 nos jours pr\u00e9cis\u00e9ment, jusqu&rsquo;\u00e0 la crise Snowden\/NSA dans sa dimension actuelle et sa dynamique exponentielle, nous pourrions nous contenter, pour mesurer le statut de communication \u00e9crasant de la NSA, de l&rsquo;appr\u00e9ciation, que nous soutenons depuis ses d\u00e9buts, que cette crise s&rsquo;est effectivement transform\u00e9e en un \u00e9v\u00e9nement fondamental qui secoue tout le syst\u00e8me de la communication,  et le Syst\u00e8me lui-m\u00eame, certes. Deux appr\u00e9ciations parmi tant d&rsquo;autres, dans des domaines diff\u00e9rents, fixent cette \u00e9volution.<\/p>\n<\/p>\n<p><p>\t Celle de Jacob Heilbrunn, de <em>The National Interest<\/em>, le <a href=\"http:\/\/nationalinterest.org\/blog\/jacob-heilbrunn\/congress-challenges-the-nsa-8778\" class=\"gen\">26 juillet 2013<\/a> : \u00ab<em>The sense one derives<\/em> [&#8230;]  <em>is that one computer programPRISM, UPSTREAM, and so onis leading to the next, that the desire to obtain information, in whatever form, has become an end in itself, which is what is leading to the construction of a massive electronic records holding facility in the desert in Utah, one that will likely become a monument to future generations of<\/em> <strong><em>the folly of the current one.<\/em><\/strong>\u00bb<\/p>\n<\/p>\n<p><p>\t Celle de Boris Kazantsev, dans <em>Strategic-Culture.org<\/em>, le <a href=\"http:\/\/www.strategic-culture.org\/news\/2013\/07\/27\/the-time-for-serious-discussion-the-future-global-cyberspace-has-come.html\" class=\"gen\">27 juillet 2013<\/a> : \u00ab<em>The Snowden affair, as expected, is snowballing, gathering more and more new details and revelations. This has already led to several international scandals (including the egregious example of what happened with Bolivian President Evo Morales&rsquo; plane) and most likely will lead to more. However, this entire situation poses another, more global question: does current international law measure up to the existing realities of the development of the information sphere, and is it able to give countries the tools they need to maintain their informational sovereignty?<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\tMais, selon nous, la sc\u00e8ne est pos\u00e9e pour une autre d\u00e9marche que ces consid\u00e9rations fort terrestres. (On notera cependant que les deux consid\u00e9rations techniques au sens large et conceptuel d\u00e9j\u00e0 signal\u00e9, exemples parmi des centaines d&rsquo;autres faites r\u00e9guli\u00e8rement aujourd&rsquo;hui en marge de la crise Snowden\/NSA telle qu&rsquo;elle a litt\u00e9ralement explos\u00e9e, impliquent des consid\u00e9rations qui ne limitent  rien de la r\u00e9flexion que nous offrons, et m\u00eame l&rsquo;encouragent,  par exemple avec le jugement de Heillbrun sur <em>the folly of the current<\/em> [<em>generation<\/em>]\u00bb.) Cette autre d\u00e9marche est ce par quoi nous allons pouvoir d\u00e9velopper notre hypoth\u00e8se, substantiv\u00e9e au d\u00e9part par le sentiment diluvien de mysticisme qui s&#8217;empara des dirigeants am\u00e9ricanistes pour d\u00e9finir la Guerre contre la Terreur comme une sorte de conflit sans fin, une guerre \u00e9ternelle. On conviendra que ce sentiment n\u00e9 d&rsquo;une psychologie am\u00e9ricaniste boulevers\u00e9e par l&rsquo;\u00e9v\u00e9nement 9\/11 convient \u00e0 ravir au composant sur l&rsquo;\u00e9ternit\u00e9 du sceau\/blason de la NSA. On croirait que ce sceau\/blason, compos\u00e9 en 1965, anticipait 9\/11&#8230;<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit donc de consid\u00e9rer la NSA comme une entit\u00e9, voire une \u00e9gr\u00e9gore. Cela est d&rsquo;autant plus concevable qu&rsquo;on a vu combien cette agence s&rsquo;est transform\u00e9e en un artefact technique et humain colossal du point de vue quantitatif, mais avec un \u00e9l\u00e9ment humain particuli\u00e8rement anonyme, bureaucratique, sans personnalit\u00e9s marquantes qui \u00e9mergeraient de son histoire, et avec une singuli\u00e8re banalit\u00e9 du point de vue de l&rsquo;\u00e9clat m\u00e9diatique dans le syst\u00e8me de la communication pendant des d\u00e9cennies. (Tout cela, encore, au contraire d&rsquo;une agence telle que la CIA.) La NSA appara\u00eet donc comme singuli\u00e8rement <strong>anonyme<\/strong>, \u00e0 la fois du point de vue de sa repr\u00e9sentation (ou de sa direction) humaine, \u00e0 la fois du point de vue des activit\u00e9s humaines avec les cons\u00e9quences de son absence du point de vue de la communication m\u00e9diatique et de l&rsquo;influence sur la psychologie et donc la repr\u00e9sentation que nous nous f\u00eemes d&rsquo;elle. On comprend alors que rien n&rsquo;interdit de poser le m\u00eame constat du point de vue de la pens\u00e9e humaine, dont on peut faire l&rsquo;hypoth\u00e8se qu&rsquo;elle est absente dans sa dimension cr\u00e9atrice dans le dessein fondamental de la NSA, et r\u00e9duite simplement \u00e0 l&rsquo;acquisition et au fonctionnement du comment ? de l&rsquo;expansion de l&rsquo;activit\u00e9 de la NSA. Les \u00e9v\u00e9nements ext\u00e9rieurs (9\/11 et sa mystique clinquante) fournissent un cadre indirect mais \u00f4 combien puissant pour favoriser ce qui serait le dessein de l&rsquo;expansion de la NSA, mais l\u00e0 aussi sans intervention humaine directe. Envisageant la question sous cet angle, on constate combien l&rsquo;on <strong>retrouve<\/strong> d&rsquo;une fa\u00e7on irr\u00e9sistible les grands courants fondateurs, profonds et dissimul\u00e9s du CMI, tels qu&rsquo;on les a d\u00e9taill\u00e9s ci-dessus,  le courant supr\u00e9matiste et mystique anglo-saxon de l&rsquo;origine (ann\u00e9es 1935-1937), les emprunts faits par le CMI \u00e0 la science nazie \u00e0 la fin de la guerre, jusqu&rsquo;\u00e0 l&#8217;emprunt des m\u00e9thodes et certaines recherches relevant plus d&rsquo;une approche magique de la science que de l&rsquo;approche rationnelle classique en Occident. La dimension m\u00e9taphysique,  m\u00eame s&rsquo;il s&rsquo;agit d&rsquo;une m\u00e9taphysique de bazar,  s&rsquo;impose d&rsquo;elle-m\u00eame et l&rsquo;on comprend qu&rsquo;elle n&rsquo;attendait qu&rsquo;une occasion pour se manifester, et que 9\/11 et la suite furent cette occasion.<\/p>\n<\/p>\n<p><p>\tDivers portraits ont \u00e9t\u00e9 trac\u00e9s du principal des employ\u00e9s de la NSA, conduisant son dessein quasiment m\u00e9taphysique, notamment le g\u00e9n\u00e9ral Alexander qui est \u00e0 la t\u00eate de l&rsquo;Agence jusqu&rsquo;en 2014. Ce sont des personnalit\u00e9s ternes, sans trait marquant qui rencontr\u00e2t la perception m\u00e9taphysique de l&rsquo;\u00e9gr\u00e9gore NSA. (Rien \u00e0 voir, par exemple, avec certains directeurs et dirigeants de la CIA, ceux de la fin des ann\u00e9es 1940 et des ann\u00e9es 1950 qui assignaient \u00e0 la CIA une mission de sauvegarde de la haute culture et de la civilisation occidentales face au communisme [voir le <a href=\"http:\/\/www.dedefensa.org\/article-frances_stonor_saunders_who_paid_the_piper_30_12_2001.html\" class=\"gen\">30 d\u00e9cembre 2001<\/a> et le <a href=\"http:\/\/www.dedefensa.org\/article-_qui_m_ne_la_danse_ou_la_guerre_froide_sous_un_autre_clairage_12_07_2003.html\" class=\"gen\">2 juillet 2007<\/a>], ou un Allen Dulles fr\u00e8re de Foster parmi les directeurs, ou un William Colby, fervent catholique, allant t\u00e9moigner devant la commission Church en 1975 comme s&rsquo;il allait \u00e0 confesse pour obtenir la r\u00e9mission de ses p\u00e9ch\u00e9s.) Au contraire, Alexander est une sorte de g\u00e9n\u00e9ral-bureaucrate, obs\u00e9d\u00e9 par l&rsquo;aspect quantitatif, qui d\u00e9veloppe une politique d&rsquo;\u00e9ternit\u00e9 par simple automatisme d&rsquo;une accumulation de la surveillance et de l&rsquo;\u00e9coute jusqu&rsquo;\u00e0 <strong>l&rsquo;absolu<\/strong>. Greenwald a publi\u00e9, le <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/2013\/jul\/15\/crux-nsa-collect-it-all\" class=\"gen\">15 juillet 2013<\/a>, un commentaire, notamment d&rsquo;un article du Washington <em>Post<\/em> sur Alexander (\u00ab<em>The crux of the NSA story in one phrase: collect it all. The actual story that matters is not hard to see: the NSA is attempting to collect, monitor and store all forms of human communication.<\/em>\u00bb) :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>In his eight years at the helm of the country&rsquo;s electronic surveillance agency, Alexander, 61, has quietly presided over a revolution in the government&rsquo;s ability to scoop up information in the name of national security.<\/em> <strong><em>And, as he did in Iraq, Alexander has pushed hard for everything he can get<\/em><\/strong><em>: tools, resources and the legal authority to collect and store vast quantities of raw information on American and foreign communications.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tOn comprend que nous ne parlons ni d&rsquo;un visionnaire, ni d&rsquo;un proph\u00e8te, ni du Diable poursuivant son projet de se substituer \u00e0 un Dieu inattentif. Il s&rsquo;agit de la pauvret\u00e9 d&rsquo;une psychologie moderniste transform\u00e9e en postmoderniste comme s&rsquo;il y avait transmutation, versant dans la boulimie du quantitatif jusqu&rsquo;au but de l&rsquo;absolu de tout, pour l&rsquo;\u00e9ternit\u00e9&#8230; L&rsquo;absolu et l&rsquo;\u00e9ternit\u00e9 par la machinerie bureaucratique et l&rsquo;aveuglement de l&rsquo;<em>hybris<\/em> m\u00e9caniste. C&rsquo;est cette m\u00eame sorte de psychologie qu&rsquo;on retrouve chez un Eric Schmidt, patron de Google, ou chez tout autre dirigeant de cette firme, nous assommant de d\u00e9clarations de type publicitaire sur le changement de <em>sapiens<\/em> en <em>sapiens<\/em>-Google pour un prix modique, par diverses manipulations, pour enfin ajuster l&rsquo;homme aux exigences des bilans annuels de Google. (Voir le <a href=\"http:\/\/www.dedefensa.org\/article-notre_intelligence_et_la_chute_07_06_2013.html\" class=\"gen\">7 juin 2013<\/a> et le <a href=\"http:\/\/www.dedefensa.org\/article-ecce_homo-google_22_07_2013.html\" class=\"gen\">22 juillet 2013<\/a>.) Sans aucun doute, leurs divers projets sont monstrueux, et leurs commentaires \u00e0 pr\u00e9tention m\u00e9taphysique, mais tout cela restant au niveau du bazar, du quantitatif, de la pub-Syst\u00e8me de l&rsquo;am\u00e9ricanisme. Ils nous m\u00e8nent <strong>en v\u00e9rit\u00e9<\/strong> au meilleur des mondes avec une pauvret\u00e9 conceptuelle, une m\u00e9diocrit\u00e9 intellectuelle, un \u00e9puisement psychologique qui t\u00e9moignent de l&rsquo;absence compl\u00e8te de la r\u00e9alisation de l&rsquo;importance m\u00e9tahistorique de l&rsquo;enjeu. Ces pauvres gens sont des instruments, des sous-idiots utiles (avant les idiots utiles \u00e9taient au moins des intellectuels) d&rsquo;une force de d\u00e9structuration, de dissolution et d&rsquo;entropisation (dd&#038;e) qui les emporte comme des f\u00e9tus de paille. Cette pauvret\u00e9 syst\u00e9matique qui les nimbe v\u00e9ritablement et les retient tout en bas de l&rsquo;\u00e9chelle, le plus bas possible, justifierait \u00e0 elle seule la sorte d&rsquo;hypoth\u00e8se que nous \u00e9voquons,  bref et si l&rsquo;on veut bien nous pardonner cette insolence de langage de pure circonstance,  vraiment trop cons pour les clefs de Saint-Pierre et l&rsquo;\u00e9ternit\u00e9&#8230;<\/p>\n<\/p>\n<p><p>\tLa Bonne Nouvelle (dans le sens religieux, pour ceux qui y tiennent) est que ces faibles esprits sont d\u00e9voil\u00e9s par la crise Snowden\/NSA comme on l&rsquo;a d\u00e9j\u00e0 observ\u00e9. Ils sont sortis de leur carapace de secret qui paraissait \u00e0 ceux qui s&rsquo;en avisaient l&rsquo;indice d&rsquo;une puissance complotiste consid\u00e9rable, et qui s&rsquo;av\u00e8re n&rsquo;avoir \u00e9t\u00e9 que de l&rsquo;anonymat par incapacit\u00e9 d&rsquo;\u00eatre <em>sexy<\/em> pour le syst\u00e8me de la communication. (Voir notamment le <a href=\"http:\/\/www.dedefensa.org\/article-l_inconnaissance_perdue_de_la_nsa_27_06_2013.html\" class=\"gen\">27 juin 2013<\/a>, repris du <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_hyper-big_brother_snowden_et_row_25_06_2013.html\" class=\"gen\">25 juin 2013<\/a> : \u00ab<em>La puissance de la surveillance secr\u00e8te, c&rsquo;est le secret, pas la surveillance, parce que le secret c&rsquo;est le mythe et que le mythe domine tout dans nos esprits, et notamment la raison. La puissance d&rsquo;hyper-Big Brother r\u00e9sidait dans l&rsquo;ignorance technique pr\u00e9cise qu&rsquo;on avait de son existence, bien que tout le monde se doutait<\/em> <strong><em>\u00e9videmment<\/em><\/strong> <em>de son existence. Si vous savez d&rsquo;un point de vue technique, et technologique, qu&rsquo;hyper-Big Brother existe, vous le d\u00e9mythifiez et sa puissance de surveillance n&rsquo;est plus mythique mais technique, ou technologique, et \u00e9galement humaine, avec toute la relativisation que cela suppose&#8230;<\/em>\u00bb) Ces remarques qui concernent la NSA valent aussi, \u00e0 notre sens, pour Google et ses projets de transmutation de <em>sapiens<\/em>, \u00e9normes dans leurs cons\u00e9quences mais \u00e0 deux balles dans leur conceptualisation originelle, du type <em>collect it all<\/em> (ou encore <em>to collect, monitor and store all forms of human&#8230; <\/em>[<em>being<\/em> ?]). L\u00e0-dessus, l&rsquo;on n&rsquo;a pas le droit d&rsquo;ignorer que la NSA et Google (et quelques autres), c&rsquo;est blanc bonnet et bonnet blanc, interchangeables \u00e0 tous \u00e9gards et aussi unis que l&rsquo;<em>American Dream<\/em> et la faillite de Detroit,  et aussi vuln\u00e9rables dans leur pauvret\u00e9 intellectuelle et culturelle, et leur faiblesse psychologique<\/p>\n<\/p>\n<p><p>\tLa crise Snowden\/NSA, dans ses cons\u00e9quences type-le roi est nu, a lanc\u00e9 le processus paradoxal de d\u00e9construction de la NSA,  bataille engag\u00e9e au cur du Syst\u00e8me en pleine d\u00e9composition, comme l&rsquo;a <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_une_d_faite_du_syst_me_26_07_2013.html\" class=\"gen\">montr\u00e9<\/a> le vote de la Chambre des Repr\u00e9sentants. D\u00e9sormais, leurs capacit\u00e9s et leurs ambitions sont limit\u00e9es, peut-\u00eatre d\u00e9cisivement, par ce contrecoup (<em>blowback<\/em>) dont on voit partout les manifestations et les effets. Les cons\u00e9quences possibles sont \u00e0 mesure, car autant l&rsquo;\u00e9difice issu de l&rsquo;esprit de la CMI et r\u00e9alis\u00e9 pour notre propos est formidable de surpuissance, autant son \u00e9branlement peut toucher tout l&rsquo;\u00e9difice du Syst\u00e8me dans un processus d&rsquo;autodestruction&#8230; L&rsquo;entreprise lanc\u00e9e par Google et quelques autres est \u00e9galement d\u00e9sormais soumise \u00e0 cet al\u00e9a fondamental. Ainsi la situation est-elle d\u00e9sormais plus ouverte qu&rsquo;elle ne fut jamais, au cur du Syst\u00e8me qui se d\u00e9chire dans sa crise d&rsquo;effondrement.<\/p>\n<\/p>\n<p><p>\tAyant d\u00e9velopp\u00e9 tout cela et mis la NSA (et la NSA\/Google) \u00e0 sa vraie place conceptuelle d&rsquo;une monstrueuse et banale m\u00e9diocrit\u00e9 de la postmodernit\u00e9, ayant d\u00e9mystifi\u00e9 ce qui n&rsquo;est qu&rsquo;un mythe de relations publiques comme tout ce qui pr\u00e9tend au mythe dans l&rsquo;am\u00e9ricanisme, il reste le constat que le dessein poursuivi \u00e9tait (et reste) celui d&rsquo;une transmutation d\u00e9cisive de la civilisation, de l&rsquo;ultime effort pour susciter sa Chute dans l&rsquo;entropisation. Il reste donc le Myst\u00e8re d\u00e9cisif de savoir ce qu&rsquo;est r\u00e9ellement la NSA (et ses satellites divers),  et l\u00e0, nous qui ne faisons gu\u00e8re confiance au hasard pour expliquer les choses, nous retrouvons notre hypoth\u00e8se supr\u00eame de la NSA-\u00e9gr\u00e9gore, c&rsquo;est-\u00e0-dire d&rsquo;une force supra-humaine dans la puissance et absolument entropique dans le dessein. C&rsquo;est de cette fa\u00e7on que nous envisageons cette excroissance monstrueuse qui s&rsquo;est d\u00e9velopp\u00e9e quasiment sans intervention humaine et a engendr\u00e9 naturellement un dessein, et le dessin de son sceau o\u00f9 figurent clefs de Saint-Pierre et cercle ferm\u00e9 de l&rsquo;\u00e9ternit\u00e9. L&rsquo;avatar peut-\u00eatre d\u00e9cisif qui se manifeste au travers de l&rsquo;infrastructure crisique qui s&rsquo;est \u00e9tablie, et de son dernier joyau qu&rsquo;est la crise Snowden\/NSA, concerne donc quelque chose qui nous d\u00e9passe, nous surpasse et fait des <em>sapiens<\/em>-Syst\u00e8me de bien pi\u00e8tres figurants. (Auraient-ils vraiment besoin d&rsquo;\u00eatre transmut\u00e9s par Google et orient\u00e9s par la NSA ?) Il est effectivement logique d&rsquo;avancer que cet avatar, ou ce contrecoup, ou ce coup d&rsquo;arr\u00eat, se manifestera, s&rsquo;il va aux termes, dans un domaine \u00e0 mesure,  au cur du  <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_syst_me_08_07_2013.html\" class=\"gen\">Syst\u00e8me<\/a> vu comme expression op\u00e9rationnelle du <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_d_cha_nement_de_la_mati_re__05_11_2012.html\" class=\"gen\">d\u00e9cha\u00eenement de la Mati\u00e8re<\/a>. La crise Snowden\/NSA est <strong>vraiment<\/strong> une opportunit\u00e9 de passer \u00e0 la phase finale de la crise d&rsquo;effondrement du Syst\u00e8me. Opportunit\u00e9 ne signifie pas r\u00e9alisation de la chose, mais au moins la bataille respire et l&rsquo;on per\u00e7oit joyeusement les feux de son ultimit\u00e9. M\u00eame si Snowden \u00e9tait le pauvre h\u00e8re manipul\u00e9 par des puissances obscures que certains en ont fait, un peu vite quoi, il reste qu&rsquo;il produit des effets int\u00e9ressants qui prennent tout le monde de vitesse.<\/p>\n<\/p>\n<p><p>\tAffaire \u00e0 suivre, comme dirait Saint-Pierre, \u00e9ventuellement pour l&rsquo;\u00e9ternit\u00e9&#8230;<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La NSA, ou la Providence sur \u00e9coutes 30 juillet 2013 Nous d\u00e9veloppons un aspect de notre F&#038;C du 22 juillet 2013, pr\u00e9cis\u00e9ment lorsque nous \u00e9crivions : \u00abA partir de l\u00e0, et parall\u00e8lement \u00e0 la r\u00e9flexion th\u00e9orique et m\u00e9thodologique que nous poursuivons, il serait logique de proposer une autre r\u00e9flexion, plus conjoncturelle, expliquant et justifiant beaucoup&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2857,4270,12325,5055,12323,3012,3466,12322,10091,6944,10846,2673,3123,10847,3809,11675,12324,12326,4392,12224,11131],"class_list":["post-75126","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-alexander","tag-autodestruction","tag-blason","tag-caltech","tag-clefs","tag-complexe","tag-dieu","tag-eternite","tag-google","tag-greenwald","tag-iron","tag-metaphysique","tag-militaro-industriel","tag-mountain","tag-nazi","tag-providence","tag-saint-pierre","tag-sceau","tag-science","tag-snowden","tag-surpuissance"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75126"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75126\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}