{"id":75186,"date":"2013-09-02T05:45:18","date_gmt":"2013-09-02T05:45:18","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/09\/02\/sen-laver-les-mains-en-criant-victoire\/"},"modified":"2013-09-02T05:45:18","modified_gmt":"2013-09-02T05:45:18","slug":"sen-laver-les-mains-en-criant-victoire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/09\/02\/sen-laver-les-mains-en-criant-victoire\/","title":{"rendered":"S&rsquo;en laver les mains en criant \u201cvictoire!\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">S&rsquo;en laver les mains en criant \u00ab\u00a0victoire!\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>2 septembre 2013 &ndash; Pour le titre de ce commentaire g\u00e9n\u00e9ral \u00e0 partir d&rsquo;un fait \u00e9videmment stup\u00e9fiant, nous avons beaucoup h\u00e9sit\u00e9 avant de nous replier derri\u00e8re la r\u00e9f\u00e9rence c\u00e9l\u00e8bre mais anecdotique du Pr\u00e9fet Pontius Pilatus \u00e0 propos du sort de J\u00e9sus de Nazareth. Cela aurait pu \u00eatre \u00ab\u00a0Transmission de la patate chaude\u00a0\u00bb, ou bien simplement un \u00ab\u00a0On ferme\u00a0\u00bb qui aurait aussi bien concern\u00e9 le r\u00f4le du pr\u00e9sident que, plus largement, l&rsquo;exercice de la puissance faussaire de l&rsquo;Empire en plein processus de d\u00e9tricotage. Pour le reste, il s&rsquo;agit, comme cela a \u00e9t\u00e9 pr\u00e9cis\u00e9, d&rsquo;une id\u00e9e du seul Obama jaillie vendredi et aussit\u00f4t concr\u00e9tis\u00e9e en d\u00e9cision. (Aucun de ces conseillers ne lui avait pr\u00e9sent\u00e9 cette option, la jugeant sans doute hors de propos, non conforme au comportement du pr\u00e9sident ou simplement indigne dans l&rsquo;atmosph\u00e8re totalement irr\u00e9elle d&rsquo;<em>hybris<\/em> qui continue \u00e0 r\u00e9gner \u00e0 la Maison-Blanche. Le National Security Council de l&rsquo;ultra-faucon-<em>neocon<\/em> Susan Rice n&rsquo;avait pas cette possibilit\u00e9 dans ses cartons rafra&icirc;chis, <a class=\"gen\" href=\"http:\/\/firstread.nbcnews.com\/_news\/2013\/08\/31\/20273128-the-white-house-walk-and-talk-that-changed-obamas-mind-on-syria?lite\">selon NBC<\/a>.) Cette option compl\u00e8tement impr\u00e9vue, venue \u00e0 l&rsquo;esprit d&rsquo;Obama \u00e0 partir du spectacle de la d\u00e9confiture de Cameron, illumine effectivement, et le caract\u00e8re d&rsquo;Obama, et sa position r\u00e9elle sur la crise syrienne.<\/p>\n<\/p>\n<p><p>&bull; Un caract\u00e8re tortueux, d\u00e9sinvolte, ennemi des responsabilit\u00e9s et des positions tranch\u00e9es, pr\u00e9occup\u00e9 de prot\u00e9ger la r\u00e9putation et l&rsquo;image qu&rsquo;il croit flatteuses, pour caract\u00e9riser ses actes de gouvernement. Il se sort peut-\u00eatre, temporairement, du gu\u00eapier qu&rsquo;il a lui-m\u00eame confectionn\u00e9 (son absurde obligation de \u00ab\u00a0<em>red line<\/em>\u00ab\u00a0) et dans lequel il s&rsquo;est lui-m\u00eame fourr\u00e9, mais il n&rsquo;en sort grandi en rien, et m\u00eame plut\u00f4t diminu\u00e9 \u00e0 un niveau de politicien washingtonien. Cela, pr\u00e9cisons-le, pour la premi\u00e8re impression.<\/p>\n<\/p>\n<p><p>&bull; Sur la crise syrienne, notre jugement de toujours est qu&rsquo;Obama \u00e9tait et reste visc\u00e9ralement oppos\u00e9 \u00e0 une intervention, et cette id\u00e9e de transf\u00e9rer \u00ab\u00a0la pate chaude\u00a0\u00bb au Congr\u00e8s lui permet d&rsquo;\u00e9viter une d\u00e9cision. Pour autant, elle ne r\u00e8gle rien : si le Congr\u00e8s (essentiellement la Chambre des Repr\u00e9sentants) le soutient, la d\u00e9cision lui revient \u00e0 nouveau, dans des conditions qui, malgr\u00e9 l&rsquo;apparence imm\u00e9diate, n&rsquo;ont gu\u00e8re de chances d&rsquo;\u00eatre meilleures qu&rsquo;elle n&rsquo;\u00e9taient avant sa d\u00e9cision, simplement du fait que la s\u00e9quence aura montr\u00e9 <a class=\"gen\" href=\"http:\/\/www.bostonglobe.com\/news\/world\/2013\/08\/30\/little-international-support-for-military-action-syria\/pzFRglyeRnTzUnaB5odC0H\/story.html\">sa solitude<\/a> initiale le poussant \u00e0 forcer des appuis ext\u00e9rieurs au prix d&rsquo;une r\u00e9duction accept\u00e9e de ses pr\u00e9rogatives. Si le Congr\u00e8s censure le projet d&rsquo;attaque, alors il se trouve consid\u00e9rablement affaibli au niveau int\u00e9rieur, jusqu&rsquo;\u00e0 une crise possible de sa direction, sans parler de la menace de l&rsquo;effondrement d\u00e9cisif du statut d'\u00a0\u00bbhyperpuissance\u00a0\u00bb des USA vers une d\u00e9route inf\u00e2me &#8230; Mais peut-\u00eatre le psychiatre ou un confesseur habile trouverait-il au fond de son \u00e2me incertaine et dissimul\u00e9e le secret d\u00e9sir d&rsquo;un vote n\u00e9gatif qui le d\u00e9barrasserait du fardeau \u00e0 l&rsquo;avantage de la vertu constitutionnelle, et \u00e0 l&rsquo;avantage de sa propre <em>hybris<\/em>. Il pourrait toujours arguer pour lui-m\u00eame que sa \u00ab\u00a0stature\u00a0\u00bb d&rsquo;homme d&rsquo;&Eacute;tat, cette pr\u00e9occupation d\u00e9risoire, est confirm\u00e9e <em>a contrario<\/em> par son respect de l&rsquo;esprit de la Constitution, &ndash; cette honorable pr\u00e9occupation pour cet ex-professeur de loi constitutionnel qui ne cesse de la violer (la Constitution). \u00ab\u00a0C&rsquo;est la faute \u00e0 la Constitution, pas \u00e0 moi\u00a0\u00bb, dirait-il pour justifier cette impuissance voulue, alors qu&rsquo;il proclame toujours et inconstitutionnellement qu&rsquo;il n&rsquo;a pas besoin de l&rsquo;accord du Congr\u00e8s pour agir. Quel esprit tortueux, le contraire d&rsquo;un homme d&rsquo;&Eacute;tat &#8230;<\/p>\n<\/p>\n<p><p>&bull; Un <em>post-scriptum<\/em> qui n&rsquo;est pas sans importance concernerait une attaque malgr\u00e9 un vote n\u00e9gatif du Congr\u00e8s (ce qui est \u00ab\u00a0l\u00e9galement\u00a0\u00bb possible \u00e0 la lumi\u00e8re de la \u00ab\u00a0l\u00e9galit\u00e9-selon-Obama\u00a0\u00bb puisque c&rsquo;est le pr\u00e9sident qui, en ce moment, semble \u00ab\u00a0faire la loi\u00a0\u00bb selon les besoins de sa politique). La situation serait totalement in\u00e9dite puisque l&rsquo;\u00e9pisode n&rsquo;aurait fait que confirmer la solitude d&rsquo;Obama dans l&rsquo;aventure, sa r\u00e9ticence pour attaquer et, malgr\u00e9 tout, sa volont\u00e9 d&rsquo;attaquer pour ne pas voir le statut de sa position diminu\u00e9e, pour prot\u00e9ger sa \u00ab\u00a0cr\u00e9dibilit\u00e9\u00a0\u00bb. Il s&rsquo;agit toujours de l&rsquo;encha&icirc;nement de n\u00e9cessit\u00e9s impos\u00e9es par une position arbitraire et risqu\u00e9e de communication (la \u00ab\u00a0<em>red line<\/em>\u00ab\u00a0), rendu encore plus compliqu\u00e9 par son extension dans le nombre de cha&icirc;nons impliqu\u00e9s et le temps \u00e9coul\u00e9.<\/p>\n<\/p>\n<p><p>On donnera ici quelques commentaires de divers experts et autres, qui ne pr\u00e9tendent pas repr\u00e9senter toute la palette de cette riche communaut\u00e9 mais qui rassemblent \u00e0 peu pr\u00e8s l&rsquo;esprit des diverses r\u00e9actions qui ont imm\u00e9diatement suivi la d\u00e9cision d&rsquo;Obama. L&rsquo;ensemble de ces r\u00e9actions a \u00e9t\u00e9 rassembl\u00e9 par le bureau de Washington de McClatchy, imm\u00e9diatement apr\u00e8s la d\u00e9claration du pr\u00e9sident US, apr\u00e8s le commentaire selon lequel Obama prend un gros risque en consultant le Congr\u00e8s, dont l&rsquo;avantage pourrait \u00eatre pourtant &laquo;<em>a broad popular support, giving him a stronger hand in facing Syrian President Bashar Assad and perhaps other dictators later in such regimes as Iran&#8230;<\/em>&raquo; N\u00e9anmoins, le titre met l&rsquo;accent sur l&rsquo;aspect n\u00e9gatif du risque, &ndash; &laquo;<em>Obama risks embarrassing loss in Congress.<\/em>&raquo; (Voir McClatchy, le <a class=\"gen\" href=\"http:\/\/www.mcclatchydc.com\/2013\/08\/31\/200963\/obama-risks-embarrassing-loss.html#.UiMSHI432ew\">31 ao&ucirc;t 2013<\/a>.)<\/p>\n<\/p>\n<p><p>&laquo;<em>But there are military and political risks in the process. Militarily, a desperate Assad could use the time while Obama waits for a Congressional debate to launch another chemical weapon attack, either in his own country or elsewhere in the Middle East, turning a civil war into a regional conflict. Politically, Obama could emerge as a weakened leader, finding it even more difficult to push his proposals through Congress, including his top priorities of passing a budget and rewriting the nation&rsquo;s immigration laws.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0Ultimately, I think he felt he was going to be a target from both the left and the right if he did it alone, and with few significant allies overseas, I don&rsquo;t think he wanted to be isolated,\u00a0\u00bb said Lee Miringoff, director of the Marist Institute for Public Opinion at Marist College in New York. \u00ab\u00a0This puts the ball in Congress&rsquo;s court and they either join and he gets policy and political cover or they oppose.\u00a0\u00bb<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo;<em>Foreign policy experts questioned the wisdom of waiting at least another week for Congress to return before the U.S. could act. Michael Singh, a former director for Middle East affairs at the National Security Council under President George W. Bush who&rsquo;s now with the Washington Institute for Near East Policy, a research center, said there could be repercussions. \u00ab\u00a0You risk losing the momentum toward an effective military operation with a decision to go to Congress,\u00a0\u00bb he said, adding it also gives opponents like Russia and Iran more time to protest, and for the Syrians to mount a counter offensive and make certain their air forces are better protected. \u00ab\u00a0Anytime you lose the element of surprise you&rsquo;re reducing the efficacy of your military strike,\u00a0\u00bb he added.<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo;<em>If Congress does approve the authorization, Obama could emerge stronger than before. Anthony H. Cordesman, a military analyst with the Center for Strategic and International Studies, said a successful military operation could boost Obama&rsquo;s domestic agenda. \u00ab\u00a0It will be harder on the budget issues to come up against a president who is strong and successful,\u00a0\u00bb he said. \u00ab\u00a0A president who is strong and failed is a different story, and the president considers that.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, on s&rsquo;est aussit\u00f4t pr\u00e9cipit\u00e9 sur plusieurs aspects de la situation concernant les \u00e9v\u00e9nements \u00e0 venir, &ndash; oubliant souvent de tirer les enseignements de la d\u00e9cision d&rsquo;Obama &#8230; Si Obama a pris cette d\u00e9cision, c&rsquo;est qu&rsquo;il \u00e9tait dramatiquement isol\u00e9, ce qui implique une dramatique d\u00e9gradation de la situation \u00e0 son d\u00e9savantage apr\u00e8s une semaine de lobbying intense en faveur d&rsquo;une op\u00e9ration tr\u00e8s vite cantonn\u00e9e \u00e0 une \u00ab\u00a0punition\u00a0\u00bb du r\u00e9gime Assad sans autre intention strat\u00e9gique. Si Obama \u00e9tait dramatiquement isol\u00e9, c&rsquo;est justement par son absence compl\u00e8te de strat\u00e9gie pour poser un acte au potentiel d\u00e9stabilisant consid\u00e9rable, en application d&rsquo;une mesure pr\u00e9sent\u00e9e comme universellement \u00e9vidente et qui n&rsquo;a pourtant aucun support l\u00e9gal, et dont la cause fondamentale n&rsquo;est absolument pas prouv\u00e9e ni av\u00e9r\u00e9e. (Pour une analyse d\u00e9taill\u00e9e sur les \u00ab\u00a0preuves\u00a0\u00bb de la culpabilit\u00e9, voir l&rsquo;excellent texte de Virginia Tilley sur <em>Antiwar.com<\/em>, le <a class=\"gen\" href=\"http:\/\/original.antiwar.com\/virginia-tilley\/2013\/08\/30\/syria-dossier-another-failed-argument\/\">31 mars 2013<\/a>.)<\/p>\n<\/p>\n<p><p>Bien entendu, l&rsquo;\u00e9v\u00e9nement imm\u00e9diat, &ndash; ou, justement, qui ne l&rsquo;est pas vraiment, alors que le Congr\u00e8s aurait pu \u00eatre convoqu\u00e9 en session extraordinaire d\u00e8s ce lundi, &ndash; est le d\u00e9bat et le vote au Congr\u00e8s sur la question de l&rsquo;attaque contre la Syrie. Bien entendu, on trouve des versions prospectives compl\u00e8tement oppos\u00e9es. Ce qui est souvent remarquable, ou bien est-ce conforme au r\u00e9flexe qui se g\u00e9n\u00e9ralise de parer l&rsquo;adversaire ou l&rsquo;adversit\u00e9 de vertus plus grandes dont l&rsquo;un ou l&rsquo;autre dispose, c&rsquo;est de trouver dans les deux camps des prospectives privil\u00e9giant l&rsquo;autre camp&#8230; Plus pr\u00e9cis\u00e9ment, cela s&rsquo;explique par ceci que les \u00ab\u00a0optimistes\u00a0\u00bb (vote favorable) sont de vieux adversaires de la politique bushiste recycl\u00e9e-BHO o&ugrave; l&rsquo;agression ext\u00e9rieure dominait et provoquait le r\u00e9flexe \u00e0 mesure des parlementaires ; tandis que les \u00ab\u00a0pessimistes\u00a0\u00bb (vote ind\u00e9cis ou d\u00e9favorable) sont des commentateurs-Syst\u00e8me qui ont constat\u00e9 que la politique d&rsquo;affrontement int\u00e9rieur, de crise du pouvoir, a (re)pris le dessus.<\/p>\n<\/p>\n<p><p>&bull; Ainsi en est-il de Afshin Rattansi, journaliste ind\u00e9pendant qui collabore avec <em>Russia Today<\/em>, qui est interview\u00e9 par la cha&icirc;ne de TV russe le <a class=\"gen\" href=\"http:\/\/rt.com\/op-edge\/congressional-approval-obama-democracy-265\/\">1er septembre 2013<\/a>. Il est manifestement adversaire de la politique US et n&rsquo;envisage gu\u00e8re que cette politique puisse \u00eatre contest\u00e9e \u00e0 Washington.<\/p>\n<\/p>\n<p><p><strong><em>Russia Today<\/em><\/strong>: &laquo;<em>Will the US Congress do to Obama what the UK parliament did to Prime Minister Cameron &#8211; or is he assured of their support in advance?<\/em>&raquo;<\/p>\n<\/p>\n<p><p><strong><em>Afshin Rattansi<\/em><\/strong>: &laquo;<em>A lot of sources are saying that a memo entitled \u00ab\u00a0Surgical Strikes\u00a0\u00bb was sent to all congressional offices on August 26. President Obama is pretty comfortable getting that approval from the members of Congress, so no real chance of that<\/em> [<em>Congress do to Obama what the UK parliament did to Prime Minister Cameron<\/em>]<em>. On the other hand, he has made it explicitly clear and he has been briefing since he gave a speech in the Rose Garden that action can take place within 24 hours, if necessary. Congressional approval is merely an add-on to show how democratic it is&#8230;.<\/em>&raquo; [&#8230;]<\/p>\n<\/p>\n<p><p><strong><em>Russia Today<\/em><\/strong>: &laquo;<em>According to poll results we&rsquo;ve seen, the American public is largely against an intervention in Syria &#8211; how will it react to Obama&rsquo;s announcement?<\/em>&raquo;<\/p>\n<\/p>\n<p><p><strong><em>Afshin Rattansi<\/em><\/strong>: &laquo;<em>One should not underestimate the power of TV news propaganda. One can argue that television news is looking more and more like al Qaeda propaganda videos. After all, news bulletins are made up from these YouTube videos, that they call open-source intelligence here in London, as far as MI6 and Joint Intelligence Committee is concerned. The power of that propaganda to persuade the American people that this would be a short and simple and surgical pin-point and all these absurd words&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Il faut signaler que Rattansi introduit une nuance int\u00e9ressante dans ses appr\u00e9ciations, en citant des sources qui ont laiss\u00e9 entendre que la direction du Pentagone, &ndash; essentiellement le secr\u00e9taire \u00e0 la d\u00e9fense Hagel et le g\u00e9n\u00e9ral (pr\u00e9sident du comit\u00e9 des chefs d&rsquo;\u00e9tat-major) Dempsey auraient mis leurs d\u00e9missions sur la table si l&rsquo;op\u00e9ration contre la Syrie \u00e9tait d\u00e9clench\u00e9e sans aucun soutien l\u00e9gal, et notamment sans l&rsquo;accord du Congr\u00e8s &#8230; Cette affirmation est remarquable par son importance \u00e0 propos d&rsquo;une situation av\u00e9r\u00e9e (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-discr_tement_mais_r_solument_le_pentagone_rechigne_31_08_2013.html\">31 ao&ucirc;t 2013<\/a>) et, si elle s&rsquo;av\u00e9rait fond\u00e9e, par ce qu&rsquo;elle nous dirait de la tension extraordinaire r\u00e9gnant \u00e0 Washington, et m\u00eame au sein de l&rsquo;administration elle-m\u00eame. Deux d\u00e9missions de cette sorte de deux personnalit\u00e9s si compl\u00e8tement au c&oelig;ur de l&rsquo;action militaire, &ndash; si elles avaient eu lieu, si elles avaient lieu dans le cours de la crise actuelle, &ndash;pourraient \u00eatre ressenties, selon les coutumes am\u00e9ricanistes, comme une pression proche d&rsquo;une sorte de <em>putsch<\/em> (voir notamment le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-appel_un_putsch_postmoderne_des_g_n_raux_us_27_12_2006.html\">27 d\u00e9cembre 2007<\/a>).<\/p>\n<\/p>\n<p><p>&bull; Par contre, un m\u00e9dia si compl\u00e8tement proche du Syst\u00e8me qu&rsquo;est le site <em>Politico.com<\/em> offre une approche extr\u00eamement circonspecte de l&rsquo;attitude du Congr\u00e8s. Le texte va jusqu&rsquo;\u00e0 mettre indirectement en cause Obama, selon l&rsquo;id\u00e9e exprim\u00e9e plus haut qu&rsquo;il d\u00e9sirerait au fond, pour \u00e9chapper \u00e0 sa propre responsabilit\u00e9, <strong>\u00eatre emp\u00each\u00e9<\/strong> par le Congr\u00e8s de faire ce que sa propre imprudence (la fameuse \u00ab\u00a0ligne rouge\u00a0\u00bb) lui impose de faire et qu&rsquo;il ne voudrait pas faire &#8230; (Ce qui impliquerait que sa position selon laquelle il peut agir sans l&rsquo;accord du Congr\u00e8s est une simple figure de rh\u00e9torique, ou de basse communication et rien d&rsquo;autre.) Cela en dit long, dans tous les cas, sur le climat de m\u00e9fiance r\u00e9ciproque et de \u00ab\u00a0d\u00e9sunion nationale\u00a0\u00bb qui r\u00e8gne \u00e0 Washington ; ce climat dont ce pr\u00e9sident, \u00e0 force de man&oelig;uvres, d&rsquo;h\u00e9sitations, de poses de communication, d&rsquo;habilet\u00e9s de circonstances et d&rsquo;absence d&rsquo;engagement principiel, porte une part importante de la responsabilit\u00e9.<\/p>\n<\/p>\n<p><p>&laquo;<em>Sen. Ron Johnson (R-Wis.) &mdash; who received a classified briefing in the White House Situation Room on Thursday and is convinced Assad used chemical weapons &mdash; said if a vote were held today, it would fail. I don&rsquo;t think it passes,\u00a0\u00bb Johnson told Politico. \u00ab\u00a0Right now there are far too many questions unanswered.\u00a0\u00bb \u00ab\u00a0If all this is about because President Obama drew a red line and he&rsquo;s concerned about his credibility and restoring his credibility, that&rsquo;s not enough justification for me,\u00a0\u00bb Johnson said.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>To some of his critics, it looks like Obama wants Congress to stop him. Even if Saturday&rsquo;s surprise move is in line with Obama&rsquo;s personal feelings, it smacks of a base and poor political calculation, they say. By not demanding Congress return from its vacation early, it gives Assad a window to repeat a chemical weapons attack should he so choose.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0It&rsquo;s like watching a bad episode of &lsquo;The West Wing.&rsquo; You cannot be president and go back and forth like this and try to communicate strength and confidence to your enemies and your allies,\u00a0\u00bb said one veteran Democratic strategist. \u00ab\u00a0It&rsquo;s a fundamental misunderstanding of what presidential power is. It&rsquo;s clear that he doesn&rsquo;t want to do this. Now they&rsquo;re trying to find any way possible to get away from that outcome.\u00a0\u00bb<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo;<em>There is also as much opposition to striking Syria from anti-war Democrats as there is from libertarian Republicans. And that&rsquo;s before getting into the hawkish caucus who have been calling for Obama to strike without congressional approval.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Rep. Peter King (R-N.Y.) presented the view of national security hawks who have sought action against Syria long before the Aug. 21 chemical weapons incident that finally prompted the Obama administration to make its case for attacking Assad&rsquo;s regime. \u00ab\u00a0President Obama is abdicating his responsibility as commander-in-chief and undermining the authority of future presidents. The president does not need Congress to authorize a strike on Syria,\u00a0\u00bb King said. \u00ab\u00a0The president doesn&rsquo;t need 535 members of Congress to enforce his own redline.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>&#8230; Bref, et pour l&rsquo;instant, on peut observer qu&rsquo;Obama ne s&rsquo;est pas fait beaucoup d&rsquo;amis avec sa d\u00e9cision-surprise de samedi. Si le soup\u00e7on d&rsquo;\u00e9chapper \u00e0 sa propre responsabilit\u00e9 est partag\u00e9, &ndash; et il a tout lieu de l&rsquo;\u00eatre, &ndash; on comprendra que les parlementaires n&rsquo;appr\u00e9cient gu\u00e8re d&rsquo;\u00eatre convoqu\u00e9s par le Pr\u00e9sident pour faire le sale boulot, c&rsquo;est-\u00e0-dire porter la responsabilit\u00e9 d&rsquo;un \u00e9ventuel \u00e9chec final de toute cette farce tragi-comique, &ndash; \u00e0 certains moments plus comique que tragique que comique, \u00e0 d&rsquo;autres plus tragique que comique.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Un \u00e9pisode chaotique<\/h2>\n<\/p>\n<p><p>Il y a deux choses \u00e0 consid\u00e9rer dans cette d\u00e9cision. L&rsquo;une est le fait m\u00eame du d\u00e9bat \u00e0 venir et du vote du Congr\u00e8s. L&rsquo;autre est le d\u00e9lai ainsi impos\u00e9 \u00e0 la possibilit\u00e9 de l&rsquo;attaque, avec l&rsquo;effet sur les \u00e9v\u00e9nements et selon ce qu&rsquo;en d\u00e9cideront les \u00e9v\u00e9nements. Pour ce qui est du Congr\u00e8s, on l&rsquo;a vu, pour certains le vote favorable est acquis. On se gardera de tout pronostic mais on observera que la partie est bien plus complexe &#8230;.<\/p>\n<\/p>\n<p><p>Il y a \u00e9videmment, pour caract\u00e9riser la fonction du Congr\u00e8s, un ph\u00e9nom\u00e8ne politique extr\u00eamement bien fait et compl\u00e8tement faussaire par rapport au concept auquel il pr\u00e9tend se r\u00e9f\u00e9rer, qu&rsquo;on devrait nommer le \u00ab\u00a0syst\u00e8me de la d\u00e9mocratie anglosaxoniste\u00a0\u00bb, o&ugrave; \u00ab\u00a0d\u00e9mocratie\u00a0\u00bb n&rsquo;est qu&rsquo;un terme utile type \u00ab\u00a0concept utile\u00a0\u00bb comme on dit \u00ab\u00a0idiot utile\u00a0\u00bb appliqu\u00e9 \u00e0 un syst\u00e8me imposant une discipline de fer \u00e0 ses repr\u00e9sentants pour soutenir ce qu&rsquo;on appelait \u00ab\u00a0la ligne du Parti\u00a0\u00bb et qu&rsquo;on devrait nommer d\u00e9sormais la ligne-Syst\u00e8me. Ce ph\u00e9nom\u00e8ne politique est cadenass\u00e9 par un conformisme \u00e9galement de fer et un apparat \u00e0 la fois patriotique et humanitariste ; il permet les d\u00e9bats internes pour la r\u00e9partition des avantages du Syst\u00e8me et impose un rassemblement (nomm\u00e9 \u00ab\u00a0bipartisan\u00a0\u00bb aux USA) sur les orientations fondamentales du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>Mais ce ph\u00e9nom\u00e8ne est vici\u00e9, \u00ab\u00a0gauchi\u00a0\u00bb, aujourd&rsquo;hui, \u00e0 l&rsquo;image du destin du Syst\u00e8me transformant sa dynamique de surpuissance en dynamique d&rsquo;autodestruction. Il y a d\u00e9sormais des r\u00e9voltes, des rebellions, des explosions impr\u00e9visibles, en un mot le virus d&rsquo;irr\u00e9sistibles pouss\u00e9es antiSyst\u00e8me qui troublent gravement, et \u00e0 notre sens irr\u00e9m\u00e9diablement, la bonne marche de la chose. C&rsquo;est \u00e9videmment aux USA que se manifeste <strong>structurellement<\/strong> ce ph\u00e9nom\u00e8ne depuis sans aucun doute juillet-ao&ucirc;t 2011 et le d\u00e9bat sur la dette publique (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-tea_party_est-il_leur_american_gorbatchev__03_08_2011.html\">3 ao&ucirc;t 2011<\/a>) qui a compl\u00e8tement chang\u00e9 la marche du Syst\u00e8me dans ce pays, pr\u00e9c\u00e9d\u00e9 de quelques coups de semonce pr\u00e9monitoires mais alors sans cons\u00e9quence (le vote de la Chambre des Repr\u00e9sentants du 29 septembre 2008 [voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_desordre_et_la_chambre_30_09_2008.html\">30 septembre 2008<\/a>], refusant le plan Paulson pour sauver les banques). On a encore vu une manifestation de cette perte de contr\u00f4le le 24 juillet (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_une_d_faite_du_syst_me_26_07_2013.html\">26 juillet 2013<\/a>), sur la question de la NSA. Au Royaume-Uni, le vote sur l&rsquo;engagement en Syrie (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_fant_me_de_tony_blair_ricane_jaune_29_08_2013.html\">29 ao&ucirc;t 2013<\/a> et le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_une_vacillation_spasmodique_30_08_2013.html\">30 ao&ucirc;t 2013<\/a>) nous indique que la branche anglaise du \u00ab\u00a0syst\u00e8me de la d\u00e9mocratie anglosaxoniste\u00a0\u00bb est touch\u00e9e du m\u00eame mal, et qu&rsquo;elle l&rsquo;est gravement.<\/p>\n<\/p>\n<p><p>On observera que ces spasmes antiSyst\u00e8me ne sont pas d\u00e9clench\u00e9s par des domaines pr\u00e9cis sur lesquels s&rsquo;exerce le vote, mais selon une logique antiSyst\u00e8me justement, tendant \u00e0 mettre en cause d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale la \u00ab\u00a0ligne-Syst\u00e8me\u00a0\u00bb parce que l&rsquo;\u00e9volution de cette ligne est de plus en plus autodestructrice et que cette \u00e9volution suscite confusion, d\u00e9sordre et r\u00e9actions violentes. En l&rsquo;\u00e9tat de complication o&ugrave; l&rsquo;a port\u00e9e Obama et au stade d&rsquo;avancement contradictoire des \u00e9v\u00e9nements, cette crise syrienne exasp\u00e8re tout le monde \u00e0 Washington, et d&rsquo;ailleurs selon des lignes de force radicalement oppos\u00e9es, &ndash; entre les antiguerres libertariens qui ne veulent plus d&rsquo;intervention et la faction psychiatrique des \u00ab\u00a0fous de guerre\u00a0\u00bb type McCain-Graham qui veut beaucoup plus qu&rsquo;une \u00ab\u00a0<em>softened strike<\/em>\u00a0\u00bb ; du point de vue des m\u00e9canismes antiSyst\u00e8me, on observera qu&rsquo;elle est \u00e9ventuellement, \u00e0 ce stade, un bon champ d&rsquo;exercice pour cette attitude. \u00ab\u00a0Cette crise syrienne exasp\u00e8re tout le monde\u00a0\u00bb parce que BHO lui-m\u00eame, avec ses man&oelig;uvres, ses nuances labyrinthiques, ses voltefaces accompagn\u00e9es de promesses de lignes droites, ses sinuosit\u00e9s byzantines, sa nonchalance derri\u00e8re la pompe du discours, finit par devenir un des facteurs de cet agacement g\u00e9n\u00e9ral. Derri\u00e8re la crise syrienne, Obama lui-m\u00eame tend \u00e0 \u00ab\u00a0exasp\u00e9rer tout le monde\u00a0\u00bb, et l&rsquo;on retrouve l\u00e0 encore un terrain connu o&ugrave; la logique antiSyst\u00e8me peut trouver des aliments.<\/p>\n<\/p>\n<p><p>Au reste, l&rsquo;id\u00e9e de donner jusqu&rsquo;au 9 septembre pour lancer le d\u00e9bat du Congr\u00e8s, ce qui supposerait une intense campagne de lobbying d&rsquo;ici l\u00e0 avec le pr\u00e9sident au charbon appelant le maximum d&rsquo;\u00e9lus \u00e0 partir de son bureau ovale, alors que justement le pr\u00e9sident quitte Washington pour \u00e9ventuellement se faire sermonner par Poutine au G20 de Saint-Petersbourg, cette id\u00e9e-l\u00e0 finalement ne semble gu\u00e8re en \u00eatre une, mais plut\u00f4t une nonchalance coupable et peut-\u00eatre bien maladroite. (Diable ! Si l&rsquo;affaire est si s\u00e9rieuse, pourquoi BHO n&rsquo;a-t-il pas annonc\u00e9 dans la foul\u00e9e, samedi 31 ao&ucirc;t, qu&rsquo;il n&rsquo;allait pas au G20, &ndash; bonne occasion de sur-punir Poutine \u00e0 la fois pour l&rsquo;affaire Snowden et l&rsquo;attitude russe vis-\u00e0-vis de la Syrie, &ndash; pour rester \u00e0 Washington et presser les parlementaires de regagner vite fait la ligne-Syst\u00e8me  ? A moins qu&rsquo;il s&rsquo;en fiche, BHO, et qu&rsquo;il s&rsquo;arrangerait bien de se voir priv\u00e9 de son <em>show<\/em> anti-Assad ? Ainsi cette affaire ne cesse-t-elle, \u00e0 chaque avanc\u00e9e du constat et du raisonnement, de faire resurgir tous les soup\u00e7ons.)<\/p>\n<\/p>\n<p><p>Bref, nul ne peut dire ce que sera l&rsquo;attitude du Congr\u00e8s. On sait bien que plus d&rsquo;un parlementaire, d\u00e9sormais, attend que se confirme et se renforce la coalition qui s&rsquo;est affirm\u00e9e le 24 juillet 2013. On comprend alors que l&rsquo;enjeu d\u00e9passe l&rsquo;affaire syrienne et concerne une restructuration fondamentale en cours de la r\u00e9partition des forces du pouvoir am\u00e9ricaniste. On a vu que l&rsquo;affaire syrienne, dans le cadre de la question g\u00e9n\u00e9rale d&rsquo;une politique de s\u00e9curit\u00e9 nationale \u00e0 pr\u00e9tention h\u00e9g\u00e9monique globale et \u00e0 bout de souffle tout uniment, devient un bon argument de politique int\u00e9rieure, sinon de perspective \u00e9lectorale. (Voir un <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_une_vacillation_spasmodique_30_08_2013.html\">Rand Paul<\/a>, qui ne demanderait pas mieux d&rsquo;enfourcher la cause n\u00e9o-isolationniste de l&rsquo;anti-interventionniste.) Ainsi avons-nous, au lieu d&rsquo;un de ces mot d&rsquo;ordre d'\u00a0\u00bbunion nationale\u00a0\u00bb qui, en g\u00e9n\u00e9ral, et surtout depuis 9\/11, mobilisait les parlementaires au nom de l&rsquo;asservissement \u00e0 la <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_la_politique-syst_me__17_11_2012.html\">politique Syst\u00e8me<\/a>, l&rsquo;ouverture possible sinon probable vers un de ces d\u00e9bats de \u00ab\u00a0d\u00e9sunion nationale\u00a0\u00bb comme Washington est devenu la sp\u00e9cialiste depuis au moins trois ans. Cette d\u00e9sunion-l\u00e0, si elle se confirme \u00e0 propos de l&rsquo;affaire syrienne, pourrait nous mener bien plus loin que le seul vote qu&rsquo;attend Obama pour se couvrir.<\/p>\n<\/p>\n<p><p>Au reste, que feront BHO et le Congr\u00e8s d&rsquo;un vote favorable \u00e0 une attaque ? Est-ce vraiment un cadeau ? C&rsquo;est qu&rsquo;entretemps, les \u00e9v\u00e9nements n&rsquo;attendent pas &#8230; Il y a ce Michael Singh qui nous dit \u00e0 peu pr\u00e8s \u00ab\u00a0Vous risquez de perdre le rythme conduisant \u00e0 l&rsquo;in\u00e9luctabilit\u00e9 d&rsquo;une op\u00e9ration militaire avec la d\u00e9cision d&rsquo;aller devant le Congr\u00e8s &#8230; Quand vous perdez l&rsquo;\u00e9l\u00e9ment de surprise, vous r\u00e9duisez l&rsquo;efficacit\u00e9 de votre op\u00e9ration militaire\u00a0\u00bb (&laquo;<em>\u00ab\u00a0You risk losing the momentum toward an effective military operation with a decision to go to Congress,\u00a0\u00bb he said, adding it also gives opponents like Russia and Iran more time to protest, and for the Syrians to mount a counter offensive and make certain their air forces are better protected. \u00ab\u00a0Anytime you lose the element of surprise you&rsquo;re reducing the efficacy of your military strike\u00a0\u00bb<\/em>&raquo;) Disons que nous trouvons cette remarque bien trop \u00ab\u00a0op\u00e9rationnelle\u00a0\u00bb, compl\u00e8tement insuffisante mais pourtant l&rsquo;esprit de la chose est bien l\u00e0 : dans le mot \u00ab\u00a0rythme\u00a0\u00bb (\u00ab\u00a0<em>momentum<\/em>\u00ab\u00a0), bien plus que dans celui de la surprise ou de l&rsquo;efficacit\u00e9.<\/p>\n<\/p>\n<p><p>&#8230; Le rythme, c&rsquo;est celui de la crise elle-m\u00eame, non seulement celle de la Syrie mais celle du pouvoir, de la psychologie de nos dirigeants, de nos <em>narrative<\/em>, bref la crise g\u00e9n\u00e9rale d&rsquo;effondrement du Syst\u00e8me. Ce rythme, c&rsquo;est la pression constante de la communication, avec son effet sur la psychologie ; c&rsquo;est la n\u00e9cessit\u00e9, chez celui qui a lanc\u00e9 une dynamique de la conduire sans reprendre son souffle, et d&rsquo;en perdre la conduite si le rythme varie et ne tient plus &#8230; Nous entrons alors dans le domaine sup\u00e9rieur des \u00e9v\u00e9nements eux-m\u00eames, de ceux qui nous conduisent et imposent leurs conditions aux pi\u00e8tres figurants de la pi\u00e8ce. En effet, au-dessus de tout cela, et compl\u00e9tant les deux \u00e9l\u00e9ments consid\u00e9r\u00e9s, on trouve le constat \u00e9vident de la puissance et de l&rsquo;autonomie des \u00e9v\u00e9nements tels qu&rsquo;ils se manifestent d\u00e9sormais. &laquo;<em>Comme dans les situations crisiques paroxystiques d\u00e9sormais, les \u00e9v\u00e9nements ont une fois de plus pris le commandement de leur propres destins, et une fois de plus avec une d\u00e9cision encore plus affirm\u00e9e et des effets \u00e0 mesure. Rien ne peut \u00eatre dit de particuli\u00e8rement int\u00e9ressant dans le d\u00e9tail sur leur \u00ab\u00a0politique\u00a0\u00bb, sinon ce constat, qui n&rsquo;est pas rien, du d\u00e9tricotage actif de tous les actes du Syst\u00e8me, y compris de la narrative centrale qui est d&rsquo;une pauvret\u00e9 remarquable et suscite une mobilisation \u00e0 mesure, &ndash; massive bien entendu, parce que les troupes, sinon les troupeaux-Syst\u00e8me sont l\u00e0, mais appuy\u00e9e sur une conviction aussi mince qu&rsquo;une couche de glace dans la d\u00e9b\u00e2cle du printemps<\/em>&raquo; (Notre texte du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-hyst_ricisme_syriana_29_08_2013.html\">29 ao&ucirc;t 2013<\/a> .)<\/p>\n<\/p>\n<p><p>Ce qui est remarquable depuis le d\u00e9clenchement de cette s\u00e9quence paroxystique, c&rsquo;est l&rsquo;orientation de la courbe, ou plut\u00f4t dirait-on, de la pente dynamique de cette crise. Partie de tr\u00e8s haut, de cette impression d&rsquo;in\u00e9luctabilit\u00e9 et de ce besoin de paroxysme (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-l_in_luctable_et_le_besoin_de_paroxysme_25_08_2013.html\">25 ao&ucirc;t 2013<\/a>), de cette hyst\u00e9rie semblant d&rsquo;abord irr\u00e9sistible (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-les_incertitudes_dubitatives_de_l_hyst_rie_27_08_2013.html\">27 ao&ucirc;t 2013<\/a>), \u00e0 un moment o&ugrave; il semblait que rien ni personne ne r\u00e9sisterait \u00e0 la chose, o&ugrave; l&rsquo;on pourrait rassembler des coalitions historiques et assurer les frappes qui importeraient, la dynamique n&rsquo;a cess\u00e9 de s&rsquo;incurver vers le bas, la crise de revenir de Syrie pour s&rsquo;\u00e9panouir, destructrice, dans les pays du bloc BAO eux-m\u00eames (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-hyst_ricisme_syriana_29_08_2013.html\">29 ao&ucirc;t 2013<\/a>). On ne voit pas pourquoi cette tendance qui n&rsquo;a fait que s&rsquo;acc\u00e9l\u00e9rer se renverserait, voire m\u00eame ralentirait. Au contraire, puisque ce sont toujours les m\u00eames artistes \u00e0 la barre, les m\u00eames <em>narrative<\/em>, les m\u00eames pauvres psychologies encha&icirc;n\u00e9es, les m\u00eames retraites badigeonn\u00e9es en rodomontades de rassemblement national.<\/p>\n<\/p>\n<p><p>(Quelle diff\u00e9rence compl\u00e8te avec, par exemple, 2002-2003 et la pr\u00e9paration de l&rsquo;attaque contre l&rsquo;Irak, o&ugrave; pourtant les foules manifestaient par millions dans les rues. Au contraire, la tendance \u00e9tait alors, comme on dit \u00e0 Wall Street, compl\u00e8tement \u00ab\u00a0haussi\u00e8re\u00a0\u00bb&#8230; Glenn Greenwald se rappelait, dans un article qu&rsquo;il publie ce <a class=\"gen\" href=\"http:\/\/www.theguardian.com\/commentisfree\/2013\/sep\/01\/obama-congress-syria-authorization\">1er septembre 2013<\/a>, le spectacle pitoyable de Joe Biden, actuel vice-pr\u00e9sident, allant supplier GW de permettre au Congr\u00e8s de voter sur la guerre, pour faire savoir qu&rsquo;il existait, le Congr\u00e8s, &ndash; le vote \u00e9tant, lui, acquis d&rsquo;avance &#8230; &laquo;<em>I vividly remember watching then-Senate Foreign Relations Chairman Joe Biden practically begging the Bush White House to \u00ab\u00a0allow\u00a0\u00bb Congress to vote on the attack while promising in advance that they would approve for it.<\/em>&raquo;)<\/p>\n<\/p>\n<p><p>La question est alors moins de savoir tr\u00e8s pr\u00e9cis\u00e9ment si BHO l&#8217;emportera au Congr\u00e8s et ce qui se passera ensuite, m\u00eame si les p\u00e9rip\u00e9ties d&rsquo;ici l\u00e0 et tout du long s&rsquo;annoncent du plus grand int\u00e9r\u00eat. La question devient : dans cette courbe descendante apr\u00e8s le sommet in\u00e9luctable et hyst\u00e9rique originel, vers la tendance constante de la dissolution autodestructrice de la dynamique du bloc BAO, s&rsquo;arr\u00eatera-t-on seulement \u00e0 la situation du <em>statu quo ante<\/em> (d&rsquo;avant la d\u00e9cision d&rsquo;attaquer) du bloc BAO, ou bien ira-t-on encore plus loin, c&rsquo;est-\u00e0-dire plus bas dans la dissolution, vers une crise qui ne se contenterait pas de \u00ab\u00a0faire <em>blowback<\/em>\u00a0\u00bb comme \u00e0 l&rsquo;accoutum\u00e9, mais qui commencerait <strong>r\u00e9ellement<\/strong> \u00e0 d\u00e9vorer le c&oelig;ur du bloc BAO et du Syst\u00e8me. De ce point de vue, il ne faut pas craindre de compter comme un \u00e9l\u00e9ment de poids la d\u00e9termination de ces hommes-Syst\u00e8me de poursuivre avec un ent\u00eatement presque grandiose dans cette voie de l&rsquo;aveuglement, c&rsquo;est-\u00e0-dire de poursuivre leurs plans d&rsquo;intervention&#8230;<\/p>\n<\/p>\n<p><p>Finalement et au-del\u00e0 de toute prospective rationnelle, on irait jusqu&rsquo;\u00e0 envisager qu&rsquo;un BHO, qui aimerait tant qu&rsquo;un Congr\u00e8s le dispense de l&rsquo;exercice, serait contraint effectivement \u00e0 le poursuivre d&rsquo;une fa\u00e7on ou l&rsquo;autre. Il y sera aid\u00e9 par la vigilante sentinelle-poire, Hollande-Fabius, qui semble presque dans l&rsquo;extase dans la r\u00e9affirmation constante de ce nihilisme de notaire et de province, qu&rsquo;on croirait presque d&rsquo;une texture sublime tant cette insistance nous rapproche de leur instant fatal. (Tout le monde est de cet avis, dans les salons&#8230; Un auditeur-voyeur normal devrait en perdre son dentier en s&rsquo;effarant lui-m\u00eame lorsqu&rsquo;il entend, dans la brillante \u00e9quipe de France-24, l&rsquo;un des commentateurs du discours d&rsquo;Obama du 31 ao&ucirc;t, meubler notre attente des paroles d\u00e9cisives du POTUS du commentaire qui s&rsquo;av\u00e8re un constat qui va de soi qu&rsquo;avec la fermet\u00e9 qu&rsquo;il d\u00e9ploie dans l&rsquo;effort vers l&rsquo;accomplissement de sa politique syrienne et guerri\u00e8re, &laquo;<em>apr\u00e8s tout le pr\u00e9sident Hollande est tout simplement gaulliste<\/em>&raquo;. Vive la poire&#8230;)<\/p>\n<\/p>\n<p><p>&#8230; Eh bien, il semble que BHO ait trouv\u00e9 un r\u00f4le \u00e0 sa mesure, du type \u00ab\u00a0<em>Yes, I can<\/em>\u00ab\u00a0. Fossoyeur de l'\u00a0\u00bbEmpire\u00a0\u00bb, selon la technique de la constante r\u00e9affirmation jusqu&rsquo;\u00e0 l&rsquo;exposition fortement risqu\u00e9e d&rsquo;une surpuissance forc\u00e9e qui basculerait dans l&rsquo;autodestruction ? Sa gestion de cet \u00e9pisode paroxystique de la crise syrienne qu&rsquo;il a lui-m\u00eame provoqu\u00e9 (sa \u00ab\u00a0ligne rouge\u00a0\u00bb) est \u00e0 la fois tordue, insaisissable, fuyante, d\u00e9routante, parfois presque efficace dans le fait assez curieux et paradoxal d'\u00a0\u00bbacheter du temps\u00a0\u00bb, &ndash; celui qui a besoin d&rsquo;agir tr\u00e8s, tr\u00e8s vite, pour imposer aux h\u00e9sitants le fait accompli, qui fait durer la chose, choisissant la tactique tordue au d\u00e9triment de la strat\u00e9gie conqu\u00e9rante &#8230; Et, \u00e0 c\u00f4t\u00e9 de cela et \u00e0 cause de cela, objectivement consid\u00e9r\u00e9, du point de vue du Syst\u00e8me, gestion absolument catastrophique, avec des reculs successifs ponctu\u00e9s de rodomontades extraordinaires pr\u00e9sentant ces reculs comme offensifs et irr\u00e9sistibles. A moins que BHO ait le projet secret d&rsquo;exp\u00e9dier l'\u00a0\u00bbEmpire\u00a0\u00bb <em>ad patres<\/em> (sorte d'\u00a0\u00bb<em>American<\/em> <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-american_gorbatchev_29_10_2008.html\">Gorbatchev<\/a>\u00a0\u00bb dissimul\u00e9, camoufl\u00e9 sous son double apparemment contradictoire pour mieux l&#8217;emporter, inversion totale enfin r\u00e9alis\u00e9e) ?<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S&rsquo;en laver les mains en criant \u00ab\u00a0victoire!\u00a0\u00bb 2 septembre 2013 &ndash; Pour le titre de ce commentaire g\u00e9n\u00e9ral \u00e0 partir d&rsquo;un fait \u00e9videmment stup\u00e9fiant, nous avons beaucoup h\u00e9sit\u00e9 avant de nous replier derri\u00e8re la r\u00e9f\u00e9rence c\u00e9l\u00e8bre mais anecdotique du Pr\u00e9fet Pontius Pilatus \u00e0 propos du sort de J\u00e9sus de Nazareth. Cela aurait pu \u00eatre \u00ab\u00a0Transmission&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[6968,4270,3359,3903,3285,2687,7932,6170,3203,6427,3867],"class_list":["post-75186","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-6968","tag-autodestruction","tag-chambre","tag-chimique","tag-congres","tag-france","tag-g20","tag-gaulliste","tag-hollande","tag-preuves","tag-syrie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75186"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75186\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}