{"id":75189,"date":"2013-09-04T04:19:23","date_gmt":"2013-09-04T04:19:23","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/09\/04\/le-cur-du-sujet-suite\/"},"modified":"2013-09-04T04:19:23","modified_gmt":"2013-09-04T04:19:23","slug":"le-cur-du-sujet-suite","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/09\/04\/le-cur-du-sujet-suite\/","title":{"rendered":"Le c\u0153ur du sujet (suite)"},"content":{"rendered":"<p><h2 class=\"common-article\">Le cur du sujet (suite)<\/h2>\n<\/p>\n<p><p>\t4 septembre 2013  A cet instant de cette phase paroxystique de la crise syrienne, il nous importe de fixer les grands arguments et les consid\u00e9rations essentielles du d\u00e9bat, selon notre point de vue et d&rsquo;ailleurs pour nous-m\u00eames, pour notre d\u00e9marche d&rsquo;analyse. Il est donc question de la Syrie comme arch\u00e9type pr\u00e9sent d&rsquo;une politique g\u00e9n\u00e9rale que nous avons d\u00e9finie d&rsquo;un point de vue g\u00e9n\u00e9ral, selon notre classement, comme la politique-Syst\u00e8me selon notre jargon (voir notre <em>Glossaire.dde<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_la_politique-syst_me__17_11_2012.html\" class=\"gen\">17 novembre 2012<\/a>). Cela indique bien qu&rsquo;il s&rsquo;agit d&rsquo;une forme fondamentale de politique, exerc\u00e9e hors de toute consid\u00e9rations de circonstances, d&rsquo;implications de la v\u00e9rit\u00e9 de la situation, comme un mod\u00e8le dont l&rsquo;application doit \u00eatre absolue, imp\u00e9rative, jusqu&rsquo;\u00e0 servir d&rsquo;une sorte de dogme appr\u00e9ci\u00e9 hors de toute contingence, appliqu\u00e9, voire <strong>impos\u00e9<\/strong> \u00e0 tous ces pays qui se trouvent directement sous la coupe du Syst\u00e8me. Nous avions d\u00e9j\u00e0 identifi\u00e9, sous des d\u00e9nominations pr\u00e9cises offertes par Harlan K. Ullman impliquant une d\u00e9finition approximative, cette politique telle qu&rsquo;elle \u00e9tait d\u00e9j\u00e0 suivie,  alors sans l&rsquo;avoir conceptualis\u00e9e sous l&rsquo;expression politique-Syst\u00e8me, c&rsquo;est-\u00e0-dire sans cherche encore \u00e0 comprendre ses fondements m\u00eame. Il s&rsquo;agissait de la politique de l&rsquo;id\u00e9ologie et de l&rsquo;instinct de type bushiste (voir le texte du <a href=\"http:\/\/www.dedefensa.org\/article-le_c_ur_du_sujet_29_05_2009.html\" class=\"gen\">29 mai 2009<\/a>, sous le titre \u00ab<em>Le cur du sujet<\/em>\u00bb que nous reprenons dans son extension pour ce texte), puis de type BHO clairement en nette am\u00e9lioration dans le sens de la d\u00e9structuration et de la dissolution (voir le <a href=\"http:\/\/www.dedefensa.org\/article-bho_c_est_gw-turbo_16_02_2012.html\" class=\"gen\">16 f\u00e9vrier 2012<\/a>, o\u00f9 nous offrions la qualification suivante de la politique d&rsquo;Obama : \u00ab<em>BHO, c&rsquo;est GW-turbo<\/em>\u00bb). Voil\u00e0 pour le pr\u00e9liminaire.<\/p>\n<\/p>\n<p><p>\tPassons \u00e0 la Syrie, d&rsquo;abord pour dire ce dont nous ne parlerons pas, dont nous parlons gu\u00e8re en g\u00e9n\u00e9ral. Il s&rsquo;agit de la question ardemment controvers\u00e9e de l&rsquo;attaque chimique, de ses responsabilit\u00e9s, de ses auteurs. C&rsquo;est un d\u00e9bat pol\u00e9mique, sans fin, qui n&rsquo;a aucune chance d&rsquo;\u00eatre tranch\u00e9 dans la fi\u00e8vre actuelle. Nous nous demandons m\u00eame, dans des circonstances o\u00f9 la communication est un fait totalement subjectif, manipulable, etc., et cela <strong>dans tous les sens<\/strong>, si la v\u00e9rit\u00e9 sera jamais connue ; les guillemets dans ce cas montrent bien combien cette question de la v\u00e9rit\u00e9 dans ce cas nous para\u00eet \u00e0 la fois al\u00e9atoire, insaisissable, et finalement accessoire. La justification fondamentale pour notre d\u00e9sint\u00e9r\u00eat est que cette question du chimique est la cons\u00e9quence d&rsquo;un encha\u00eenement de faits qui sont autant de tromperies, de simulacres, etc., \u00e9ventuellement l\u00e0 aussi <strong>dans tous les sens<\/strong>, qui nous interdisent d\u00e9finitivement d&rsquo;en venir au cur du sujet. C&rsquo;est l\u00e0 que l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-de_l_inconnaissance_du_systeme_13_07_2011.html\" class=\"gen\">inconnaissance<\/a> nous sert d&rsquo;argument p\u00e9remptoire. Il ne nous a jamais paru int\u00e9ressant de distinguer les responsabilit\u00e9s des uns et des autres en Syrie (et le r\u00e9gime Assad ne peut \u00eatre, par d\u00e9finition et exp\u00e9rience \u00e9vidente de cette sorte de situation, exon\u00e9r\u00e9 de crimes et horreurs, de la m\u00eame fa\u00e7on que les rebelles, parce que justement l&rsquo;encha\u00eenement dont nous parlons rend la chose,  les horreurs de tous les cot\u00e9s,  absolument in\u00e9luctable). S&rsquo;attarder \u00e0 cette question, c&rsquo;est \u00eatre emprisonn\u00e9 dans une pol\u00e9mique qui ne peut qu&rsquo;abaisser sinon interdire la r\u00e9flexion, et enfermer l&rsquo;esprit dans la poigne terrible du jugement emprisonn\u00e9,  alors que c&rsquo;est le fait de la politique-Syst\u00e8me <em>as a whole<\/em>, avec ses causes sup\u00e9rieures qui, seul, a de l&rsquo;int\u00e9r\u00eat pour nous.<\/p>\n<\/p>\n<p><p>\tDe toutes les fa\u00e7ons, on doit montrer l&rsquo;inanit\u00e9 de la cause en elle-m\u00eame, par l&rsquo;historique de la chose (l&rsquo;usage du chimique), par l&rsquo;hypocrisie \u00e9vidente des accusateurs et ainsi de suite. Cela n&rsquo;exon\u00e8re personne, y compris Assad, de quelque responsabilit\u00e9 que ce soit si c&rsquo;est le cas, mais fait pr\u00e9cis\u00e9ment du proc\u00e8s de la Syrie et de la punition morale qui va avec, au degr\u00e9 d&rsquo;intensit\u00e9 et d&rsquo;hyst\u00e9rie qui l&rsquo;affecte, une infection et une perversit\u00e9 intellectuelle, une inversion de l&rsquo;esprit qui sont la marque de cette \u00e9poque et du bloc BAO,  sans surprise aucune, puisque le bloc c&rsquo;est le Syst\u00e8me, qui repr\u00e9sente toutes les manifestations d\u00e9structurantes et dissolvantes possibles.<\/p>\n<\/p>\n<p><p>\tPour clore une fois pour toutes ce faux-d\u00e9bat des vrais-d\u00e9vots, mesurant la bassesse affreuse de cette \u00e9poque, nous allons signaler l&rsquo;une ou l&rsquo;autre citation d&rsquo;un article de <M>WSWS.org<D> du <a href=\"http:\/\/www.wsws.org\/en\/articles\/2013\/08\/31\/syri-a31.html\" class=\"gen\">31 ao\u00fbt 2013<\/a>. Nous avons des r\u00e9serves sur l&rsquo;orientation de <em>WSWS.org<\/em>, dont nous partageons ni les buts, ni les m\u00e9thodes de r\u00e9flexion politique. Mais nous reconnaissons \u00e0 ces gens, de par leur formation et la forme de l&rsquo;esprit trotskiste, une rigueur certaine du raisonnement, et une r\u00e9elle honn\u00eatet\u00e9 du propos lorsqu&rsquo;il s&rsquo;agit des faits. (Nous prenons un risque car nous avons d&rsquo;exp\u00e9rience que les Dupont-Dupond locaux de tel ou tel organe de s\u00e9curit\u00e9 officiel, lorsque vous citez ceci ou cela,  <em>WSWS.org<\/em> pour le cas, justement,  sautent sur l&rsquo;occasion, je dirais m\u00eame plus, et s&rsquo;exclament triomphalement  : Ne serait-ce pas un site trotskiste ? Nous ne plaisantons pas, cela nous est arriv\u00e9 car c&rsquo;est \u00e0 ce niveau que ces gens-l\u00e0 trouvent leurs preuves. On mesure l&rsquo;esprit.)<\/p>\n<\/p>\n<p><p>\tA propos des preuves psalmodi\u00e9es avec une \u00e9motion de mormon qui vous tire les larmes par un Kerry d\u00e9guis\u00e9 en crois\u00e9, voici ce qu&rsquo;en dit <em>WSWS.org<\/em> (mais d&rsquo;innombrables sources peuvent \u00eatre consult\u00e9es, certes) &#8230; \u00ab<em>However, anyone who reads this report, which surfaced on the Internet shortly after Kerry&rsquo;s speech, will find not one shred of probative evidence. The document, barely three pages long, includes a series of unsubstantiated assertions that are tailored to the US policy aim of manufacturing a pretext for direct intervention in a US-provoked civil war aimed at toppling the Syrian regime of Bashar al-Assad.<\/em> [&#8230;] <em>The document consists of a series of assertions that begin with the words, The United States government assesses with high confidence and then indict the Syrian government for the alleged August 21 attack.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tPour l&rsquo;autre citation, c&rsquo;est l&rsquo;occurrence qui envisage l&rsquo;hypoth\u00e8se extr\u00eame : Assad effectivement utilisateur de chimique &#8230; Assad ne serait donc pas un saint, ce qui est par ailleurs l&rsquo;\u00e9vidence, mais aussi et surtout car c&rsquo;est bien le cur du sujet l\u00e0 aussi, qui sont-ils, ces gens-l\u00e0, pour le juger, en g\u00e9n\u00e9ral dans leurs <em>talk-shows<\/em> arros\u00e9s de pub, dans une position d&rsquo;irresponsabilit\u00e9 et d&rsquo;ignorance compl\u00e8tes de la v\u00e9rit\u00e9 des situations ? Les voici &#8230; <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Who is he<\/em> [Kerry] <em>kidding? US imperialism has the least right to preach morality in the Middle East or anywhere else on the planet. Over the past decade of war it directly killed tens of thousands Iraqis, including through the use of depleted uranium munitions and white phosphorus shells, while creating the catastrophic conditions that claimed the lives of hundreds of thousands more. What were napalm and Agent Orange, massively deployed during the war in Vietnam that claimed over 3 million lives, if not chemical weapons? And it is US imperialism alone that has employed the most horrific of weapons, the atomic bomb, killing nearly a quarter of a million Japanese civilians in Hiroshima and Nagasaki.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Every war it has waged over the past period has been based on lies, from the fabricated Gulf of Tonkin incident in Vietnam to the nonexistent weapons of mass destruction in Iraq. The impending war on Syria is no exception.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCertes on pourrait ajouter des monceaux de <strong>faits<\/strong> sur les horreurs sans fin, en Irak (on peut rappeler <a href=\"http:\/\/www.dedefensa.org\/article-souvenir_de_falloujah_pire_qu_hiroshima_26_07_2010.html\" class=\"gen\">Falloujah<\/a> et ce qu&rsquo;il resta), en Afghanistan et ailleurs, ainsi que d&rsquo;autres occurrences plus anciennes (voir le <a href=\"http:\/\/www.dedefensa.org\/article-du_temps_o_le_chimique_a_allait_27_08_2013.html\" class=\"gen\">27 ao\u00fbt 2013<\/a>). Tout le monde le sait, parce que tout le monde qui juge Assad a le <strong>devoir de savoir<\/strong>,  ou bien tout le monde se tait &#8230; Telle est l&rsquo;alternative, qui r\u00e9duit la revendication morale qui est l&rsquo;ossature de communication de la politique du bloc BAO \u00e0 la vanit\u00e9 de l&rsquo;\u00e9cume des jours &#8230;  Point final sur ce point du d\u00e9bat pour notre cas, et nous passons \u00e0 l&rsquo;essentiel qui est une toute autre fa\u00e7on d&rsquo;appr\u00e9cier ces caract\u00e8res irresponsables et inacceptables de cette m\u00eame politique du bloc.<\/p>\n<\/p>\n<p><p>\tUn texte du Russe F\u00e9dor Loukianov, \u00e9diteur de <em>Global Affairs<\/em>, pr\u00e9sident du Conseil de Politique Etrang\u00e8re et de D\u00e9fense et membre du Conseil Russe pour les affaires Internationales, est d&rsquo;un particulier int\u00e9r\u00eat. (Nos lecteur d\u00e9j\u00e0 pu lire diverses r\u00e9f\u00e9rences \u00e0 Loukianov : voir, par exemple, le <a href=\"http:\/\/www.dedefensa.org\/article-au_hasard_le_pouvoir_24_12_2012.html\" class=\"gen\">24 d\u00e9cembre 2012<\/a>.) Dans cet article du <a href=\"http:\/\/www.al-monitor.com\/pulse\/originals\/2013\/08\/us-syria-russia-military-action.html#ixzz2dYBdHizC\" class=\"gen\">27 ao\u00fbt 2013<\/a> sur <em>Al Monitor.com<\/em>, Loukianov prend comme th\u00e8me g\u00e9n\u00e9ral la possibilit\u00e9 que l&rsquo;actuelle phase paroxystique de la crise syrienne peut gravement compromettre la perspective de Gen\u00e8ve-II et consid\u00e9rablement aggraver les relations d\u00e9j\u00e0 tr\u00e8s tendues entre les USA et la Russie. (Cette perspective s&rsquo;est largement renforc\u00e9e et aggrav\u00e9e avec les \u00e9v\u00e9nements de ces derniers jours.) Loukianov met en cause la doctrine d&rsquo;intervention du bloc BAO, la fameuse R2P (<em>Right To Protect<\/em> en intervenant chez les autres lorsqu&rsquo;on juge <em>ex cathedra<\/em> et pour soi-m\u00eame qu&rsquo;on en a le devoir moral, donc le droit absolu), d\u00e9j\u00e0 manifest\u00e9e dans les ann\u00e9es 1990 (ex-Yougoslavie jusqu&rsquo;au Kosovo de 1999). Il rappelle, \u00e0 l&rsquo;adresse du bloc BAO, que dans deux circonstances vitales,  les accords de Dayton de 1995 et la capitulation de Milosevic en juin 1999,  c&rsquo;est l&rsquo;intervention des Russes aupr\u00e8s du m\u00eame Milosevic qui permit d&rsquo;une fa\u00e7on d\u00e9cisive que ces deux occurrences se terminassent \u00e0 l&rsquo;avantage du bloc BAO. Si l&rsquo;envoy\u00e9 d&rsquo;Eltsine, Viktor Tchernomyrdine, n&rsquo;avait pas annonc\u00e9 le 3 juin 1999 \u00e0 Milosevic que la Russie ne le soutenait plus, provoquant sa d\u00e9cision de cesser toute r\u00e9sistance, l&rsquo;OTAN aurait d\u00fb proc\u00e9der \u00e0 une invasion terrestre, avec cons\u00e9quences&#8230; (Les perspectives \u00e9taient tr\u00e8s difficiles, sinon pire pour l&rsquo;OTAN, l&rsquo;\u00e9poque.) Cette fois, observe Loukianov, le bloc BAO, s&rsquo;il attaque la Syrie, n&rsquo;aura aucune aide de la Russie dans ce sens, avec cons\u00e9quences&#8230; Chacun en tirera sa conclusion.<\/p>\n<\/p>\n<p><p>\tMais le passage le plus int\u00e9ressant pour notre propos est la derni\u00e8re partie de l&rsquo;article de Loukianov. Il y a d&rsquo;abord une analyse prospective op\u00e9rationnelle, qui contient l&rsquo;indication int\u00e9ressante que l&rsquo;arriv\u00e9e du nouveau pr\u00e9sident iranien provoque un rapprochement entre l&rsquo;Iran et la Russie alors que tout \u00e9tait braqu\u00e9 sur un rapprochement entre l&rsquo;Iran et le Bloc BAO. Cette derni\u00e8re possibilit\u00e9 nous para\u00eet bien improbable, vu l&rsquo;\u00e9tat d&rsquo;esprit et le <em>modus operandi<\/em> du bloc BAO &#8230; C&rsquo;est sur ce cas pr\u00e9cis d&rsquo;un int\u00e9r\u00eat particulier pour nous que Loukianov termine justement, ce cas qui est le principal sujet de pr\u00e9occupation de la direction russe qui en a d\u00e9j\u00e0 identifi\u00e9 clairement la d\u00e9raison et l&rsquo;irrationalit\u00e9 : pourquoi le bloc BAO agit-il comme il le fait ? (Nous soulignons de gras les passages qui nous semblent les plus \u00e9clairants.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>&#8230; In general, the attacks from the US Navy aircraft carriers on targets in Syria will have an inflaming effect on public opinion in Russia, akin to the scene of the NATO missiles setting Belgrade on fire in 1999. Syria is perceived as somewhat more familiar and dear than a distant and strange Libya. The common perception is that Americans are<\/em> <strong><em>totally out of control<\/em><\/strong> <em>and they bomb anybody they want to.<\/em> <strong><em>If nobody stops them, one day they will make a landing in our own backyard. This is a very common opinion in Russia<\/em><\/strong><em>, and it appeared right after the Cold War when the use of force by NATO became routine.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Exacerbation of the conflict in Syria will cast a shadow on the meeting of the G-20 nations in St. Petersburg. Yet more fun should be had at the informal summit of the BRIC countries at the beginning of September and the meeting of the Shanghai Cooperation Organization (SCO) in mid-September. The latter meeting will be joined by Iran (the observing country), as well as China, where Vladimir Putin will have his first meeting with the new president, Hassan Rouhani. Russia will, most likely, try to bring together as many representatives of influential countries that strongly object to interference, especially by force, into somebody&rsquo;s internal affairs. And the BRIC countries, SCO in particular, may as well support the enthusiasm.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The direct military assistance to the Assad regime, in the event the conflict expands, won&rsquo;t be easy simply due to the limitations of physical delivery of weapons. However, closer cooperation with Iran which, no doubt, is going to support Assad to the end, may help create additional opportunities. Since Mahmoud Ahmadinejad has left, Tehran is leaning toward Moscow, which was rather harshly addressed by the former president. Iran and Russia will do their best to straighten out the power balance in Syria, which is definitely not going to benefit from the interference of NATO leading to a rapid activation of the weapons supply to the revolutionaries.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The direct involvement of foreign states in the Syrian crisis will take it to an essentially different level. One thing is the most upsetting:<\/em> <strong><em>Something must have happened to democracy in the 21st century.<\/em><\/strong> <em>Back in the day, the cunning diplomats representing the leading powers kept themselves busy with intrigues, under-the-table dealings and intense negotiations. War was legitimate, but considered as a last resort (excluding, of course, the classic aggressors focusing on military expansion).<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Today, step by step, starting with Yugoslavia, a story with a poor script repeats itself. An internal conflict appeared in the country within the zone of the attention of the international community. The countries with most leverage immediately make<\/em> <strong><em>their decisions as to who is the bad guy and who is the good guy<\/em><\/strong><em>. Thereafter, they begin to engage in fruitless diplomacy, not for the sake of mediation and peace-making, or to achieve a mutually acceptable resolution, but rather to make the bad guys surrender to the good guys. Then the international community heaves a heavy sigh in despair. As a rule, this is exactly the time when some ugly incident, akin to genocide, arises and leaves no room for the last hope. And here it comes, in a blink of an eye, a full scale war of the most powerful alliances in the history of mankind against the bad guys (almost always the regimes), in order to let the good guys win.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Let&rsquo;s set aside the moral principles of justice; they do not rule in politics. Though it does look miserable. It all begins with some acute problems, usually arising from deep historical animosities between the nations and religions, which end up in a simplified black-and-white paradigm. In the end, the almighty ones make vain attempts to figure out what went wrong and why the good guys turned out to be so ungrateful.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>And, finally, the worst news is such actions could have been explained if there were some sort of strategy behind it, some clearly defined purpose.<\/em> <BI>Apparently, nothing even close to that exists. Politics has been reduced to ideological reflexes and natural instincts.<D< <strong><em>The reflexes help finding the right side of history to find yourself in, i.e., to bend to the ever-changing circumstances and events. And instincts<\/em><\/strong> <strong><em>tell your gut to take up arms and go to war if you don&rsquo;t know what else to do<\/em><\/strong><em>. A little too unpretentious for the increasingly complex and<\/em> <strong><em>incomprehensible<\/em><\/strong> <em>world of the 21st century.<\/em>\u00bb <\/p>\n<h3>Le chaos contr\u00f4l\u00e9-devenant-incontr\u00f4l\u00e9<\/h3>\n<\/p>\n<p><p>\tLe sujet de l&rsquo;analyse de Loukianov est \u00e9videmment une probl\u00e9matique que nous suivons de notre c\u00f4t\u00e9 depuis longtemps. Dans notre article du <a href=\"http:\/\/www.dedefensa.org\/article-au_hasard_le_pouvoir_24_12_2012.html\" class=\"gen\">24 d\u00e9cembre 2012<\/a>, nous nous r\u00e9f\u00e9rions d\u00e9j\u00e0 \u00e0 une de ses analyses dans le m\u00eame sens pour d\u00e9velopper la n\u00f4tre, toujours sur ce m\u00eame sujet mais selon un d\u00e9veloppement plus pouss\u00e9 en employant des param\u00e8tres s\u00e9picifiques. D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, nous avions conclu qu&rsquo;il y avait dans la politique du bloc BAO une suppression compl\u00e8te de toute approche rationnelle, notamment pour la cause d&rsquo;une raison totalement subvertie et d&rsquo;une psychologie compl\u00e8tement appauvrie par la proximit\u00e9 et l&rsquo;influence \u00e9crasante du Syst\u00e8me. Cela se traduit par une affectivit\u00e9 dominante et d\u00e9vastatrice, qui soumet ce qu&rsquo;on n&rsquo;ose plus gu\u00e8re nommer politique, et les d\u00e9cisions qui vont avec, \u00e0 des facteurs divers relevant de l&rsquo;id\u00e9ologie la plus sommaire et la plus terrorisante, ainsi qu&rsquo;\u00e0 des consid\u00e9rations nombreuses de communication.<\/p>\n<\/p>\n<p><p>\tIl existe effectivement, dans ce contexte, une v\u00e9ritable terrorisation de la psychologie (voir le <a href=\"http:\/\/www.dedefensa.org\/article-leur_psychologie_terroris_e_16_04_2012.html\" class=\"gen\">16 avril 2012<\/a> et le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_terrorisation_de_la_psychologie_ddecrisis_18_06_2012.html\" class=\"gen\">18 juin 2012<\/a>) qui infecte l&rsquo;intelligence, l&rsquo;esprit, et au bout du compte pour ce qui concerne l&rsquo;action dite politique, le jugement. Les causes op\u00e9rationnelles d\u00e9clenchant cette attitude sont conceptualis\u00e9es sous la forme de <em>narrative<\/em>, instrument\u00e9es \u00e0 partir de diverses manipulations de communication, si nombreuses et de plus en plus impudentes dans le conflit syrien depuis largement plus d&rsquo;un an (voir le <a href=\"http:\/\/www.dedefensa.org\/article-de_la_guerre_qui_n_a_pas_eu_lieu_en_syrie_02_04_2012.html\" class=\"gen\">2 avril 2012<\/a>), dont le but est de fabriquer une r\u00e9alit\u00e9 r\u00e9pondant aux imp\u00e9ratifs de l&rsquo;affectivit\u00e9. Dans notre texte du <a href=\"http:\/\/www.dedefensa.org\/article-la_raison_devenue_idiote_utile_de_l_affectivit__11_06_2012.html\" class=\"gen\">11 juin 2012<\/a>, nous \u00e9crivions :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Le constat est effectivement que l&rsquo;effacement d&rsquo;une<\/em> <strong><em>raison efficace<\/em><\/strong><em>, une raison loyale \u00e0 la perception de la r\u00e9alit\u00e9, ouvre la porte au d\u00e9ferlement de l&rsquo;affect en termes psychologiques, ou pure affectivit\u00e9, dans les r\u00e9actions \u00e0 la situation de Syrie. Cet affect n&rsquo;est \u00e9videmment pas suscit\u00e9 par un plan de manipulation puisqu&rsquo;on a vu que la raison, qui seule peut produire humainement de tels plans, est absente dans son r\u00f4le habituel de rangement des ambitions et des projets humains. L&rsquo;affect pr\u00e9pond\u00e9rant dans ces r\u00e9actions est donc la cause autant que le produit des manipulations innombrables qui caract\u00e9risent le compte-rendu de la v\u00e9rit\u00e9 de la situation syrienne, qui est bien entendu une v\u00e9rit\u00e9 compl\u00e8tement fabriqu\u00e9e,  litt\u00e9ralement, selon notre jargon, une narrative. Il s&rsquo;agit d&rsquo;une auto-manipulation, ou techniquement d&rsquo;une auto-m\u00e9sinformation, suscit\u00e9es par une affectivit\u00e9 qui a compl\u00e8tement pris le dessus dans l&rsquo;attitude psychologique, et qui affecte l&rsquo;observation des faits et le jugement selon des normes id\u00e9ologiques de type hyst\u00e9rique elles-m\u00eames v\u00e9hicul\u00e9es dans la psychologie avant d&rsquo;\u00eatre transcrites en id\u00e9es de type-standard et homog\u00e9n\u00e9is\u00e9es (droits de l&rsquo;homme, humanitarisme, etc.).<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tNous avons recherch\u00e9 et continuons \u00e0 d\u00e9velopper cette recherche sur les causes fondamentales de cette situation, qui touchent principalement les pays de ce que nous nommons le bloc BAO (voir notre <em>Glossaire.dde<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_bloc_bao_10_12_2012.html\" class=\"gen\">10 d\u00e9cembre 2012<\/a>), c&rsquo;est-\u00e0-dire de ce qu&rsquo;on a coutume de nommer les d\u00e9mocraties occidentales dont le d\u00e9veloppement, l&rsquo;id\u00e9ologie et les valeurs sont directement issues du Si\u00e8cle des Lumi\u00e8res et des stades r\u00e9volutionnaires qui ont conclu ce si\u00e8cle, qui sont toutes absolument repr\u00e9sentatives des fondements de ce qu&rsquo;on nomme selon l&rsquo;entendement g\u00e9n\u00e9ral mais lui-m\u00eame fortement id\u00e9ologis\u00e9, la modernit\u00e9. Dans notre rangement propre, bien entendu, nous retrouvons ces entit\u00e9s du bloc BAO comme directement h\u00e9riti\u00e8res, et int\u00e9gr\u00e9es dans le ph\u00e9nom\u00e8ne, de cette sorte de trin\u00f4me m\u00e9tahistorique repr\u00e9sent\u00e9 chronologiquement par le <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_d_cha_nement_de_la_mati_re__05_11_2012.html\" class=\"gen\">d\u00e9cha\u00eenement de la Mati\u00e8re<\/a> marquant la rupture terrible de la fin du XVIII\u00e8me si\u00e8cle, le <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_syst_me_08_07_2013.html\" class=\"gen\">Syst\u00e8me<\/a> qui en est la cr\u00e9ation op\u00e9rationnelle, et l&rsquo;\u00e9quation surpuissance-autodestruction repr\u00e9sentant la courbe dynamique de fonctionnement du Syst\u00e8me. <\/p>\n<\/p>\n<p><p>\tDans les effets op\u00e9rationnels, la politique g\u00e9n\u00e9rale engendr\u00e9e par cet ensemble est caract\u00e9ris\u00e9e par des effets chronologiques de d\u00e9structuration, de dissolution, avec le but ultime de l&rsquo;entropisation qui est l&rsquo;homog\u00e9n\u00e9isation totale de toute structure et de toute \u00e9laboration dans une sorte de n\u00e9antisation, un rien qui ne manifeste plus aucun caract\u00e8re sp\u00e9cifique. (Dans notre jargon, il s&rsquo;agit de la formule dd&#038;e.) Lavrov parle dans le chef du but du bloc BAO de la recherche d&rsquo;un chaos contr\u00f4l\u00e9 en Syrie (<em>Russia Today<\/em>, le <a href=\"http:\/\/rt.com\/news\/lavrov-chemicals-syria-secret-295\/\" class=\"gen\">3 septembre 2013<\/a> : \u00ab<em>However, it appeared that Russia&rsquo;s partners in the matter  especially those who back the rebels  were less interested in the conference<\/em>[Gen\u00e8ve-II] <em>than in creating controlled chaos, as Lavrov put it<\/em>\u00bb). Notre perception est que Lavrov d\u00e9crit la recherche de ce que le bloc BAO croit \u00eatre, ou fait semblant de croire pour justifier son entra\u00eenement, une tactique finalement constructive (r\u00e9f\u00e9rence au concept extr\u00eamement pauvre et cosm\u00e9tique, puisque n&rsquo;ayant jamais fonctionn\u00e9 en tant que v\u00e9ritable chaos, de chaos cr\u00e9ateur) ; notre appr\u00e9ciation est que cette tactique constructive est en fait une \u00e9tape d&rsquo;une dynamique \u00e0 un stade situ\u00e9e quelque part entre dissolution et entropisation. (Il faut observer que cette remarque de Lavrov, en plus de nombreuses autres de dirigeants russes autant que du texte du Loukianov, montrent combien les Russes sont de loin les plus avanc\u00e9s dans la recherche d&rsquo;une explication acceptable du comportement du bloc BAO et des USA.)<\/p>\n<\/p>\n<p><p>\tLa cause fondamentale \u00e0 laquelle conduisent ces diff\u00e9rentes observations ne peut, selon notre conviction, que renvoyer \u00e0 ce que nous nommons m\u00e9taHistoire, ou m\u00e9taphysique de l&rsquo;Histoire, ou encore Histoire devenue m\u00e9taphysique. Les facteurs intervenant sont \u00e9videmment du type qu&rsquo;on identifie \u00e0 la notion tr\u00e8s large de Mal, et qu&rsquo;on doit rechercher dans des domaines que seule la m\u00e9taphysique peut d\u00e9finir. Nos lecteurs peuvent consulter les textes divers, sur ce site, qui traitent de cette question, notamment ceux du <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_proximit_du_mal_ddecrisis_04_01_2013.html\" class=\"gen\">4 janvier 2013<\/a> et, surtout, du <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_mal_i_14_02_2013.html\" class=\"gen\">14 f\u00e9vrier 2013<\/a>.<\/p>\n<\/p>\n<p><p>\tA partir de ces remarques, on comprendra que nous nous trouvons, avec l&rsquo;actuel \u00e9pisode paroxystique de la crise syrienne, dans un cas contradictoire,  un peu comme une sorte de contradiction entre tactique et strat\u00e9gie, comme si la tactique risquait de conduire au contraire du but strat\u00e9gique recherch\u00e9. Ce que nous avons d\u00e9crit plus haut fait ais\u00e9ment comprendre que nous tenons le Syst\u00e8me et la politique qu&rsquo;il produit comme des ph\u00e9nom\u00e8nes absolument destructeurs, dont on ne peut que souhaiter la destruction avant d&rsquo;envisager quoi que ce soit, quelque r\u00e9forme que ce soit. (Une r\u00e9forme du Syst\u00e8me avec le Syst\u00e8me existant toujours ne pourrait \u00eatre qu&rsquo;un pi\u00e8ge, la puissance du Syst\u00e8me absorbant cette r\u00e9forme, \u00e9ventuellement \u00e0 son avantage, ce qui en retournerait l&rsquo;usage contre ses initiateurs sinc\u00e8rement antiSyst\u00e8me \u00e0 l&rsquo;origine.) Pourtant, nous-m\u00eames (y compris nous-m\u00eames \u00e0 <em>dedefensa.org<\/em>)  n&rsquo;\u00e9chappons pas \u00e0 ce r\u00e9flexe, \u00e0 partir de notre critique constante du Syst\u00e8me, de souhaiter l&rsquo;\u00e9chec de ses initiatives, et de travailler dans ce sens. Mais l&rsquo;on comprend bien que nous sommes dans le domaine tactique, puisque le Syst\u00e8me n&rsquo;est pas d\u00e9truit et que nous ne sommes <strong>en rien<\/strong> assur\u00e9s d&rsquo;obtenir un r\u00e9sultat globalement positif,  et que c&rsquo;est m\u00eame le contraire qui est probable. Ainsi, lorsqu&rsquo;on critique l&rsquo;action actuelle du Syst\u00e8me dans l&rsquo;affaire syrienne, en faveur de la guerre, et si l&rsquo;on voit cette action confront\u00e9e \u00e0 un \u00e9chec, peut-on dire que ce succ\u00e8s tactique est \u00e9galement strat\u00e9gique ? Cela n&rsquo;est nullement assur\u00e9, puisque le Syst\u00e8me reste en place. Au contraire, si on le voit progresser dans sa dynamique de surpuissance (vers la guerre), on peut avancer l&rsquo;argument d\u00e9cisif tenant \u00e0 notre analyse g\u00e9n\u00e9rale que cette dynamique de surpuissance va se transformer par sa propre action en dynamique d&rsquo;autodestruction.<\/p>\n<\/p>\n<p><p>\tSelon cette logique, on pourrait avancer comme argument le d\u00e9veloppement de l&rsquo;extr\u00eame de cette logique elle-m\u00eame, qui serait de dire que l&rsquo;entr\u00e9e en guerre voulue par le Syst\u00e8me serait une issue souhaitable dans la mesure o\u00f9 la situation aurait toutes les chances de verser dans un chaos qui, tr\u00e8s rapidement, gr\u00e2ce aux capacit\u00e9s largement d\u00e9montr\u00e9es du Syst\u00e8me de son incapacit\u00e9 de produire et de d\u00e9velopper quoi que ce soit dans un sens structurant et contr\u00f4lable, passerait de l&rsquo;illusion du chaos contr\u00f4lable au chaos incontr\u00f4lable qui est la nature m\u00eame, et nature irr\u00e9sistible, du chaos. Le Syst\u00e8me, engag\u00e9 dans le chaos, se trouverait alors engag\u00e9 dans sa phase d&rsquo;autodestruction. Bien entendu, cette perspective semble terriblement destructrice et \u00e9pouvantable, sauf qu&rsquo;on peut se demander si la situation actuelle dans la s\u00e9quence depuis 9\/11, ne fournit pas bien autant de destructions \u00e9pouvantables sans que le Syst\u00e8me ait engag\u00e9 son existence. Car le fait est qu&rsquo;aujourd&rsquo;hui, dans les conditions de tension qu&rsquo;il conna\u00eet et qu&rsquo;il a cr\u00e9\u00e9es et constamment aggrav\u00e9es d&rsquo;ailleurs, accabl\u00e9 de crises, rong\u00e9 de l&rsquo;int\u00e9rieur par ses <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_les_termites__10_04_2013.html\" class=\"gen\">termites<\/a>, le Syst\u00e8me engagerait son existence dans une telle aventure syrienne aussit\u00f4t \u00e9largie g\u00e9ographiquement et op\u00e9rationnellement.<\/p>\n<\/p>\n<p><p>\tCette hypoth\u00e8se n&rsquo;est pas unique dans son aspect op\u00e9rationnel. Elle peut \u00eatre pond\u00e9r\u00e9e par la chronologie de l&rsquo;effet-<em>blowback<\/em>, impliquant que le chaos engendr\u00e9 par une guerre aurait <strong>tr\u00e8s probablement<\/strong> et <strong>tr\u00e8s rapidement<\/strong> des effets de d\u00e9sordre profond dans les pays du bloc BAO, qui reviendraient finalement \u00e0 ce que le chaos s&rsquo;installe <strong>\u00e9galement<\/strong> au sein m\u00eame des directions politiques-Syst\u00e8me et au sein du cur de l&rsquo;appareil du Syst\u00e8me bien autant, et peut-\u00eatre plus rapidement que sur le th\u00e9\u00e2tre d&rsquo;op\u00e9ration consid\u00e9r\u00e9. Cette issue est favoris\u00e9e par le nombre tr\u00e8s grand de crises tr\u00e8s pressantes de toutes natures existant actuellement au sein des pays du bloc BAO, dans divers domaines, et notamment dans le domaine clef des pouvoirs en place. Cela nous conduit \u00e0 une autre hypoth\u00e8se op\u00e9rationnelle, qui peut \u00eatre consid\u00e9r\u00e9e comme alternative ou compl\u00e9mentaire. Il s&rsquo;agit de consid\u00e9rer que les \u00e9v\u00e9nements, rebondissements, voltefaces, incertitudes, etc., qui d\u00e9filent depuis une d\u00e9cade \u00e0 peu pr\u00e8s, et \u00e0 quelle vitesse, contribueraient avec une rapidit\u00e9 \u00e0 mesure, \u00e0 \u00e9roder consid\u00e9rablement les pouvoirs en place au service du Syst\u00e8me. Ces \u00e9v\u00e9nements sont dus aux conditions incertaines et cr\u00e9atrices de d\u00e9sordre et d&rsquo;inorganisation, dues essentiellement \u00e0 la puissance du syst\u00e8me de communication obligeant \u00e0 des positions et \u00e0 des \u00e9volutions chaotiques, emp\u00eachant \u00e0 la fois le regroupement et l&rsquo;organisation des forces du Syst\u00e8me, alors que pourtant le but (faire la guerre \u00e0 la Syrie) est extr\u00eamement bien identifi\u00e9. Du coup, les tensions suscit\u00e9es par ce but extr\u00eamement dangereux et si bien identifi\u00e9 suscitent des pressions qui contribuent au contraire du regroupement et de l&rsquo;organisation des forces du syst\u00e8me, produisant alors un effet-<em>blowback<\/em> avant m\u00eame que l&rsquo;\u00e9v\u00e9nement supr\u00eame (la guerre et le chaos) ait \u00e9t\u00e9 accompli,  un effet-<em>blowback<\/em> d&rsquo;un \u00e9v\u00e9nement avant que cet \u00e9v\u00e9nement ait eu lieu compl\u00e8tement ou m\u00eame soit largement entam\u00e9, si l&rsquo;on veut&#8230;<\/p>\n<\/p>\n<p><p>\tDans ce cas, on rencontre l&rsquo;occurrence o\u00f9 la tactique incertaine exerc\u00e9e contre l&rsquo;action du Syst\u00e8me, se transforme en une strat\u00e9gie dont le but devient clair : rechercher la d\u00e9structuration et la dissolution du Syst\u00e8me, qui peuvent d&rsquo;ailleurs \u00e9voluer d&rsquo;une mani\u00e8re cach\u00e9e, sans que nous nous en apercevions directement, avant m\u00eame que le Syst\u00e8me ait pu parvenir \u00e0 une attitude offensive coh\u00e9rente. La dynamique d&rsquo;autodestruction aurait pris le pas sur la dynamique de surpuissance d&rsquo;une fa\u00e7on autoritaire, sans avoir \u00e0 attendre le d\u00e9roulement de l&rsquo;\u00e9quation de transformation dynamique de surpuissance-dynamique d&rsquo;autodestruction. Vu les circonstances actuelles, et notamment la d\u00e9cision d&rsquo;Obama de faire intervenir le Congr\u00e8s, ce qui implique un d\u00e9lai inattendu qui accentue un d\u00e9sordre d\u00e9j\u00e0 consid\u00e9rable,  pourrait-on voir un chaos contr\u00f4l\u00e9 existant peut-\u00eatre d\u00e9j\u00e0 dans le bloc BAO, devenir un chaos incontr\u00f4l\u00e9, prenant bien entendu et n\u00e9cessairement une autre forme que ce qui se passe en Syrie et dans la r\u00e9gion ? &#8230; Et, dans ce cas, intervenant avant qu&rsquo;il ne se passe quoi que ce soit de fondamentalement nouveau en Syrie et dans la r\u00e9gion dans la phase actuelle de pressions et d&rsquo;attaques venues de l&rsquo;ext\u00e9rieur et du fait du bloc BAO ?<\/p>\n<\/p>\n<p><p>\t&#8230; Quoi qu&rsquo;il en soit de l&rsquo;hypoth\u00e8se (des hypoth\u00e8ses) envisag\u00e9es, l&rsquo;id\u00e9e consid\u00e9r\u00e9e ici est qu&rsquo;il existe une concurrence potentielle entre deux chaos contr\u00f4l\u00e9s-devenant-incontr\u00f4l\u00e9s,  entre la situation syrienne sous la menace du bloc BAO, et la situation \u00e0 l&rsquo;int\u00e9rieur du bloc BAO mena\u00e7ant la Syrie. Le plus rapide \u00e0 se d\u00e9velopper ne serait pas n\u00e9cessairement celui auquel, nous Occidentaux si habitu\u00e9s \u00e0 notre propre sup\u00e9riorit\u00e9, nous serions en g\u00e9n\u00e9ral conduits \u00e0 penser. Nous sommes \u00e0 un moment o\u00f9 l&rsquo;Histoire devenant m\u00e9taHistoire a son mot \u00e0 dire, qui supplanterait tous les autres. Si elle consentait \u00e0 le dire, les \u00e9v\u00e9nements nous r\u00e9serveraient n\u00e9cessairement des surprises.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le cur du sujet (suite) 4 septembre 2013 A cet instant de cette phase paroxystique de la crise syrienne, il nous importe de fixer les grands arguments et les consid\u00e9rations essentielles du d\u00e9bat, selon notre point de vue et d&rsquo;ailleurs pour nous-m\u00eames, pour notre d\u00e9marche d&rsquo;analyse. Il est donc question de la Syrie comme arch\u00e9type&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[12393,2870,4270,5264,3934,6384,3162,10119,11929,7932,8333,2773,3085,7746,3041,8844,2673,3193,3099,12406,5535,12407,11131,3867,12116],"class_list":["post-75189","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-affectivite","tag-attaque","tag-autodestruction","tag-blowback","tag-chaos","tag-controle","tag-dde","tag-dissolution","tag-entropisation","tag-g20","tag-incontrole","tag-iran","tag-kosovo","tag-loukianov","tag-mal","tag-metahistoire","tag-metaphysique","tag-milosevic","tag-psychologie","tag-r2p","tag-raison","tag-subvertie","tag-surpuissance","tag-syrie","tag-terrorisation"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75189"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75189\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}