{"id":75218,"date":"2013-09-21T13:28:28","date_gmt":"2013-09-21T13:28:28","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/09\/21\/snowdennsa-en-mode-turbo\/"},"modified":"2013-09-21T13:28:28","modified_gmt":"2013-09-21T13:28:28","slug":"snowdennsa-en-mode-turbo","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/09\/21\/snowdennsa-en-mode-turbo\/","title":{"rendered":"Snowden\/NSA en mode <em>turbo<\/em>"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Snowden\/NSA en mode <em>turbo<\/em><\/h3>\n<\/p>\n<p><p>\tOn a vu par ailleurs, ce m\u00eame <a href=\"http:\/\/www.dedefensa.org\/article-nsa_et_cie_ou_la_guerre_contre_l_am_rique_latine_21_09_2013.html\" class=\"gen\">21 septembre 2013<\/a>, la dimension consid\u00e9rable que la crise Snowden\/NSA a acquise dans sa dimension ext\u00e9rieure, accouchant d&rsquo;une crise secondaire chronologiquement mais essentielle par ailleurs, avec l&rsquo;installation des relations entre les USA et l&rsquo;Am\u00e9rique latine dans une situation de confrontation ouverte,  Br\u00e9sil en t\u00eate, ce qui n&rsquo;est pas rien. On veut compl\u00e9ter cette \u00e9volution chronologiquement en temps r\u00e9el par une observation g\u00e9n\u00e9rale de ce que nous d\u00e9signerions comme la maturit\u00e9 de cette crise Snowden\/NSA. Cette crise a r\u00e9ussi \u00e0 franchir l&rsquo;obstacle de la d\u00e9sorientation de l&rsquo;attention du syst\u00e8me de la communication vers l&rsquo;\u00e9pisode paroxystique de la crise syrienne, pour retrouver le devant de la sc\u00e8ne. Plus encore, sa diversification est remarquable, et aussi la perception de plus en plus large qu&rsquo;en ont les commentateurs.<\/p>\n<\/p>\n<p><p>\t&#8230; Par exemple, Simon Jenkins, du <em>Guardian<\/em>, le <a href=\"http:\/\/www.theguardian.com\/commentisfree\/2013\/sep\/19\/gchq-we-monster-we-cant-control\" class=\"gen\">19 septembre 2013<\/a>, avec son titre rendant toute justice \u00e0 Snowden :\u00ab<em>Edward Snowden has started a global debate&#8230;<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\t\u00ab<em>The Brazilian president cancels a state visit to Washington. The German justice minister talks of a Hollywood nightmare. His chancellor, Angela Merkel, ponders offering Edward Snowden asylum. The EU may even end the safe harbour directive which would force US-based computer servers to relocate to European regulation. Russians and Chinese, so often accused of cyber-espionage, hop with glee. In response, an embarrassed Barack Obama pleads for debate and a review of the Patriot Acts. Al Gore refers to the Snowden revelations as obscenely outrageous. The rightwing John McCain declares a review entirely appropriate. The Senate holds public hearings and summons security chiefs, who squirm like mafia bosses on the run. America&rsquo;s once dominant internet giants, with 80% of the globe under their sway, now face Balkanised regulation round the world as nation states seek to repatriate digital sovereignty.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl est vrai que Snowden est devenu un personnage plus que fr\u00e9quentable, y compris dans de vastes segments de la presse-Syst\u00e8me, y compris dans les consid\u00e9rations officielles les plus affirm\u00e9es. Ainsi en est-il, pour ce dernier cas, de la visite officielle et publiquement annonc\u00e9e qu&rsquo;une d\u00e9l\u00e9gation de parlementaires br\u00e9siliens de la commission des affaires \u00e9trang\u00e8res du Parlement a pr\u00e9vu de faire \u00e0 Moscou, pour s&rsquo;informer aupr\u00e8s de Snowden de l&rsquo;ampleur du programme US de surveillance et d&rsquo;espionnage de la NSA au Br\u00e9sil. Snowden est en passe d&rsquo;acqu\u00e9rir un statut quasi-officiel de consultant strat\u00e9gique aupr\u00e8s de vastes entit\u00e9s, soit des \u00c9tats, soit des entreprises, etc., qui sont l&rsquo;objet d&rsquo;actions intrusives de la part de la NSA, tout en consolidant sa position h\u00e9ro\u00efque de d\u00e9nonciateur du Syst\u00e8me, et certainement le d\u00e9nonciateur le plus efficace et le plus formidable de toutes les annales. (Daniel Ellsberg, l&rsquo;homme des <em>Pentagon Papers<\/em> et grand anc\u00eatre de tous les <em>whistleblower<\/em>, parlant la semaine derni\u00e8re \u00e0 l&rsquo;acteur John Cusack [voir plus loin] : \u00ab<em>I&rsquo;ve been waiting 40 years for Edward Snowden, and his revelations are the most important in US history, including the Pentagon Papers.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tPar contraste, toujours selon Jenkins, les directions politiques du bloc BAO sont de plus en plus compar\u00e9es aux pires r\u00e9f\u00e9rences, comme Jenkins l&rsquo;observe, s&rsquo;en prenant au gouvernement britannique qui est sa cible favorite dans le commentaire cit\u00e9 : \u00ab<em>While Washington has been tearing itself apart, dismissive remarks by William Hague in the Commons and Lady Warsi in the Lords could have passed muster in Andropov&rsquo;s supreme soviet&#8230;<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\t On citait plus haut l&rsquo;acteur John Cusack, qui signe un commentaire dans <em>The Guardian<\/em> le <a href=\"http:\/\/www.theguardian.com\/commentisfree\/2013\/sep\/18\/eric-holder-guarantee-nsa-reporters-rights?CMP=twt_gu\" class=\"gen\">18 septembre 2013<\/a>, au titre de membre actif de la direction de l&rsquo;association <em>Freedom Press Foundation<\/em> (FPF), o\u00f9 il si\u00e8ge \u00e0 c\u00f4t\u00e9 de Greenwald et de Poitras. Il s&rsquo;agit donc d&rsquo;une intervention politique en faveur de la protection des journalistes qui sont l&rsquo;objet de harc\u00e8lement des autorit\u00e9s officielles. Il n&#8217;emp\u00eache que Cusack est un acteur confirm\u00e9 \u00e0 Hollywood et que sa sortie repr\u00e9sente \u00e9galement un signe de la possible implication de Hollywood dans la crise Snowden\/NSA et la pol\u00e9mique qui l&rsquo;accompagne. Son commentaire concerne essentiellement la NSA et Snowden lui-m\u00eame&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Another week and another wave of stories on the NSA and the unconstitutional out-of-control surveillance state hit the digital newsstands, showing once again why the tide is turning. Some revelations are so surreal, it&rsquo;s hard not to assume they&rsquo;re satire. NSA chief Keith Alexander seems to be modeling his ambitions and visions for international spying after General Curtis LeMay&rsquo;s views on nuclear war. Meanwhile, despite the massive smear campaign against Edward Snowden, opinion polls stand clearly with the truth-tellers. People know they have a right to know what the government is doing in their names. State secrecy is on the run, while American privacy, long rumored dead, is alive and kicking and wants the fight out in the open  in the sunlight and in the public square.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCet int\u00e9r\u00eat d&rsquo;Hollywood pour la crise Snowden\/NSA est confirm\u00e9 par l&rsquo;intervention d&rsquo;un acteur de grand poids dans le cin\u00e9ma US et international, Matt Damon. La prise de position de Damon, directement en faveur de Snowden qu&rsquo;il juge h\u00e9ro\u00efque, est d&rsquo;un grand poids dans la mesure o\u00f9 il est politiquement tr\u00e8s actif, qu&rsquo;il a \u00e9t\u00e9 un des plus fervents soutiens d&rsquo;Obama, qu&rsquo;il a depuis rompu avec lui \u00e0 cause de sa politique ill\u00e9gale et destructrice de s\u00e9curit\u00e9 nationale, ce qu&rsquo;il a d&rsquo;ailleurs signifi\u00e9 au pr\u00e9sident au cours d&rsquo;un entretien. Damon illustre ainsi parfaitement une position courante \u00e0 Hollywood, lib\u00e9rale et de soutien initial \u00e0 Obama, mais en la portant courageusement \u00e0 son terme logique qui est de rejeter Obama \u00e0 cause de la trahison compl\u00e8te de ses engagements \u00e9lectoraux. Jusqu&rsquo;ici, Hollywood restait fig\u00e9 dans son soutien \u00e0 Obama, aussi bien par conformisme lib\u00e9ral que par crainte de tomber sous l&rsquo;accusation de racisme qui rel\u00e8ve du sacril\u00e8ge terroriste ; les prises de position de Damon et de Cusack rompent avec cet immobilisme couard. Si l&rsquo;on signale cette \u00e9volution, c&rsquo;est \u00e0 cause de l&rsquo;importance massive au niveau de l&rsquo;influence de Hollywood dans le d\u00e9bat politique, dans le syst\u00e8me de la communication. La position de Damon \u00e9tait pr\u00e9sent\u00e9e par <em>WSWS.org<\/em> le <a href=\"http:\/\/www.wsws.org\/en\/articles\/2013\/08\/30\/damo-a30.html\" class=\"gen\">31 ao\u00fbt 2013<\/a>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Matt Damon, one of the most popular film actors currently working, told a BBC television host last week that he supported the actions of Edward Snowden, the whistle-blower who has lifted the lid on the criminal activities of the National Security Agency (NSA). Damon, who has received three Academy Award nominations, five Golden Globe nominations and five Screen Actors Guild Awards nominations, told Husam Asi, host of the BBC Arabic television show Alternative Cinema [Cinema Badila], that Snowden had done a great thing. The clip was posted on YouTube August 22, and the entire interview aired on Alternative Cinema two days later.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Asi asked Damon, Would you do what Snowden did? Damon replied, I don&rsquo;t know, I haven&rsquo;t read everything that he&rsquo;s leaked. But he certainly seems like a very conscientious guythese revelations are pretty incredible and pretty shocking, and kind of fly in the face of the public statements that all these officials have made. On balance, the actor continued, I think it&rsquo;s a great thing that he did. If we&rsquo;re going to trade our civil liberties for our security, then that should be a decision that we collectively make. It shouldn&rsquo;t be made for us.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Damon&rsquo;s statement of support for Snowden, now living in Russia, takes a certain amount of courage, considering the large-scale government and media campaign to discredit the whistle-blower, along with others who have exposed US government crimes, such as Julian Assange and Bradley Manning.<\/em><\/p>\n<\/p>\n<p><p>\t Un autre domaine o\u00f9 la crise Snowden\/NSA fait des ravages est celui du monopole des grands groupes de gestion et de contr\u00f4le d&rsquo;internet, quasi-exclusivement US. Comme on l&rsquo;a vu, notamment au travers de l&rsquo;exemple latino-am\u00e9ricain (Br\u00e9sil-Argentine, notamment), il y a une dynamique de balkanisation de cette infrastructure, selon le mot de Jenkins, ce qui active d&rsquo;une fa\u00e7on significative une dynamique exactement contraire \u00e0 la globalisation que pr\u00e9tendrait pr\u00e9senter l&rsquo;internet, mais simplement parce que cette globalisation est un  faux-nez pour la domination des USA, c&rsquo;est-\u00e0-dire du Syst\u00e8me. La r\u00e9action en cours peut signifier effectivement une fragmentation d\u00e9fensive dans certains domaines, tout comme elle peut repr\u00e9senter une r\u00e9action antiSyst\u00e8me dans d&rsquo;autres cas et se manifester comme telle ; dans ce domaine de l&rsquo;internet, notre jugement serait plus favorable \u00e0 une dynamique antiSyst\u00e8me qu&rsquo;\u00e0 une posture de fragmentation d\u00e9fensive.<\/p>\n<\/p>\n<p><p>\tDe toutes les fa\u00e7ons, il s&rsquo;agit d&rsquo;une tendance que le march\u00e9 lui-m\u00eame, essentiellement les consommateurs pour ce cas, initie de par l&rsquo;attitude massive qu&rsquo;on constate. Le groupe Facebook du jeune Zuckerberg l&rsquo;exp\u00e9rimente d&rsquo;une fa\u00e7on douloureuse. Le <a href=\"http:\/\/thehill.com\/blogs\/hillicon-valley\/technology\/323185-zuckerberg-trust-in-facebook-other-internet-firms-went-down-after-nsa-spying-news#ixzz2fJtDWu51\" class=\"gen\">18 septembre 2013<\/a>, le site <em>The Hill<\/em> rapportait l&rsquo;humeur assez sombre de Zuckerberg, de plus en plus irrit\u00e9 par l&rsquo;attitude des autorit\u00e9s US qui refusent de prendre en compte les imp\u00e9ratifs \u00e9thico-commerciaux (curieux assemblage) permettant aux groupes de sa cat\u00e9gorie de fonctionner, au cours d&rsquo;une conf\u00e9rence organis\u00e9e par <em>The Atlantic<\/em>. Zuckerberg n&rsquo;a \u00e9videmment pas cach\u00e9 que ses plaintes et ses inqui\u00e9tudes pouvaient \u00eatre reprises aussi bien par les autres grands groupes du domaine, notamment Google, qui essuient des pertes consid\u00e9rables.<\/p>\n<\/p>\n<p><p>\tPeu avant cette conf\u00e9rence, le <em>Daily Mail<\/em> annon\u00e7ait, le <a href=\" http:\/\/www.dailymail.co.uk\/sciencetech\/article-2423713\/Facebook-users-committing-virtual-identity-suicide-quitting-site-droves-privacy-addiction-fears.html\" class=\"gen\">17 septembre 2013<\/a>, relay\u00e9 par <em>Infowars.com<\/em> ce m\u00eame <a href=\"\/%E2%80%AAhttp:\/\/www.infowars.com\/11-million-users-abandon-facebook\/\" class=\"gen\">17 d\u00e9cembre 2013<\/a>, que des chercheurs de l&rsquo;universit\u00e9 de Vienne montrent que les consommateurs abandonnent Facebook \u00e0 un rythme sans pr\u00e9c\u00e9dent depuis la crise Snowden\/NSA : 11 millions d&rsquo;abonn\u00e9s, dont neuf millions aux USA, et les deux millions restants au Royaume-Uni (l&rsquo;\u00e9tude porte sur ces deux seuls pays), dont 48,3% ont pris cette d\u00e9cision pour des raisons de vie priv\u00e9e qui est la formule d\u00e9signant directement une r\u00e9action \u00e0 l&rsquo;action de la NSA.<\/p>\n<\/p>\n<p><p>\t On voit combien, l&rsquo;ensemble de la crise Snowden\/NSA, arriv\u00e9e \u00e0 maturit\u00e9 gr\u00e2ce \u00e0 sa r\u00e9silience, et donc avec son inclusion d\u00e9finitive dans l&rsquo; <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_notre_kosmos_crisique__27_03_2013.html\" class=\"gen\">infrastructure<\/a> <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_facteur_crisique__30_04_2013.html\" class=\"gen\">crisique<\/a>, est conduite \u00e0 interf\u00e9rer dans tous les domaines de la crise du Syst\u00e8me, et de la crise de la modernit\u00e9 <em>per se<\/em>. On le voit avec la crise politique entre l&rsquo;Am\u00e9rique latine et les USA, on le voit aussi avec la fa\u00e7on dont en sont impr\u00e9gn\u00e9s les milieux les plus courants et les plus sp\u00e9cifiques de la soci\u00e9t\u00e9 du bloc BAO comme l&rsquo;activit\u00e9 des utilisateurs de l&rsquo;internet, la vie priv\u00e9e des citoyens, la position d&rsquo;Hollywood, etc. (Tout cela avec une mont\u00e9e de l&rsquo;organisation de l&rsquo;opposition aux USA, avec la formation du groupe <a href=\"https:\/\/rally.stopwatching.us\/\" class=\"gen\">StopWatchingUs<\/a>, qui regroupe de nombreuses associations anti-NSA et organise un rassemblement massif d&rsquo;opposition \u00e0 la surveillance de masse, le 26 octobre 2013 \u00e0 Washington, D.C.)<\/p>\n<\/p>\n<p><p>\tA l&rsquo;image de ce qu&rsquo;\u00e9crit Jenkins (\u00ab<em>Edward Snowden has started a global debate&#8230;<\/em>\u00bb), la crise Snowden a d\u00e9sormais une dimension globale, aussi bien quantitative que qualitative. C&rsquo;est d&rsquo;ailleurs le m\u00eame Jenkins qui le met en \u00e9vidence, \u00e9galement au niveau qualitatif, lorsqu&rsquo;il \u00e9crit en conclusion de son article qui est d\u00e9velopp\u00e9 pour critiquer l&rsquo;absence compl\u00e8te de d\u00e9bat sur le sujet de la responsabilit\u00e9 des autorit\u00e9s publique au Royaume-Uni, par contraste avec les USA (le Royaume-Uni est aussi coupable, avec son GCHQ que les USA avec leur NSA) :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The reality is that Britons generally have little trouble with the authority of the state.<\/em> [&#8230;] <em>A few people still hold to the futurist ideology that all things digital are benign. Since I see the digital revolution as one of means not ends, I am less convinced. A huge industry has shrunk the globe and vastly increased transparency, but it is poised to corrupt the very freedoms it professes to advance. The market is no guard against it, only democratic oversight. If that fails, as it has, everything is at risk.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAinsi Jenkins nous sugg\u00e8re-t-il l&rsquo;essentiel, s&rsquo;il y a lui-m\u00eame pens\u00e9, qui est la fin de la l\u00e9gitimit\u00e9 de l&rsquo;\u00c9tat \u00e0 cause de l&rsquo;action de dissolution du Syst\u00e8me \u00e0 laquelle se pr\u00eatent la plupart des \u00c9tats, et certainement tous les \u00c9tats du bloc BAO, et par cons\u00e9quent la transformation de l&rsquo;autorit\u00e9 en autoritarisme. Cet autoritarisme se r\u00e9pand d&rsquo;ailleurs hors des structures pulv\u00e9ris\u00e9es des Etats. Ainsi des activit\u00e9s telles que celles des GCHQ\/NSA deviennent-elles des monstruosit\u00e9s irresponsables, dont l&rsquo;orientation menace l&rsquo;essence m\u00eame de la civilisation, ou plut\u00f4t du tr\u00e8s peu qu&rsquo;il reste de civilisation dans notre contre-civilisation. La rencontre avec la logique dissolvante de la puissance du technologisme, tel que nous l&rsquo;avons encore identifi\u00e9 par rapport \u00e0 son \u00e9volution le <a href=\"http:\/\/www.dedefensa.org\/article-_leur_monde_menace_le_monde_16_09_2013.html\" class=\"gen\">16 septembre 2013<\/a>, est de ce point de vue compl\u00e8tement in\u00e9vitable. Le pouvoir priv\u00e9 de l\u00e9gitimit\u00e9 devient un instrument des puissances autoritaristes qui, elles, n&rsquo;ont aucune obligation de l\u00e9gitimit\u00e9, et de telles puissances qui sont de plus en plus m\u00e9caniques et priv\u00e9es du moindre contr\u00f4le principiel (humain, lorsque l&rsquo;\u00e9l\u00e9ment humain a encore une conscience quelconque de ce qu&rsquo;est la l\u00e9gitimit\u00e9 principielle). Par cons\u00e9quent, la crise Snowden\/NSA se rapproche de plus en plus, si elle ne fusionne enti\u00e8rement avec la crise de la technologie intelligente identifi\u00e9e par le groupe du CSER (dans le texte r\u00e9f\u00e9renc\u00e9 <a href=\"http:\/\/www.dedefensa.org\/article-_leur_monde_menace_le_monde_16_09_2013.html\" class=\"gen\">ci-dessus<\/a>). On se doute que, dans notre propos, nous fassions place au plus grand doute quant \u00e0 la capacit\u00e9 de la d\u00e9mocratie \u00e0 contenir cette tendance de puissance brute,  comme Jenkins l&rsquo;esp\u00e8re, lui, mais sans trop y croire pourrait-on deviner &#8230; Nous aurions, nous, beaucoup plus confiance dans la fascination irr\u00e9sistible du syst\u00e8me, retrouv\u00e9e dans toutes ses cr\u00e9atures, pour l&rsquo;autodestruction. <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 21 septembre 2013 \u00e0 13H29<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Snowden\/NSA en mode turbo On a vu par ailleurs, ce m\u00eame 21 septembre 2013, la dimension consid\u00e9rable que la crise Snowden\/NSA a acquise dans sa dimension ext\u00e9rieure, accouchant d&rsquo;une crise secondaire chronologiquement mais essentielle par ailleurs, avec l&rsquo;installation des relations entre les USA et l&rsquo;Am\u00e9rique latine dans une situation de confrontation ouverte, Br\u00e9sil en t\u00eate,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3677,12426,12440,10233,8715,4229,3371,4008,4954,12224,5712,12439],"class_list":["post-75218","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bresil","tag-cser","tag-cusack","tag-damon","tag-facebook","tag-gchq","tag-hollywood","tag-intelligence","tag-jenkins","tag-snowden","tag-technologique","tag-zuckenberg"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75218"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75218\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}