{"id":75229,"date":"2013-09-28T11:50:24","date_gmt":"2013-09-28T11:50:24","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/09\/28\/une-resolution-qui-en-dit-si-long\/"},"modified":"2013-09-28T11:50:24","modified_gmt":"2013-09-28T11:50:24","slug":"une-resolution-qui-en-dit-si-long","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/09\/28\/une-resolution-qui-en-dit-si-long\/","title":{"rendered":"Une r\u00e9solution qui en dit si long&#8230;"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Une r\u00e9solution qui en dit si long&#8230;<\/h3>\n<\/p>\n<p><p>\tEn termes de tactique,  signifiant \u00e9videmment que la situation strat\u00e9gique n&rsquo;est <strong>en rien boucl\u00e9e<\/strong>,  la r\u00e9solution de l&rsquo;ONU vot\u00e9e vendredi pulv\u00e9rise tout l&rsquo;argumentaire de la politique du bloc BAO depuis deux ans \u00e0 l&rsquo;encontre du gouvernement de la Syrie. C&rsquo;est une avanc\u00e9e tactique significative, dans une crise qui se poursuit, qui est loin d&rsquo;\u00eatre finie, qui peut m\u00eame s&rsquo;aggraver encore,  mais qui s&rsquo;aggraverait, dans ce cas, dans des conditions de communication notablement plus d\u00e9favorables pour le bloc BAO, et cette fois avec le risque majeur d&rsquo;une confrontation au plus haut niveau (voir le <a href=\"http:\/\/www.dedefensa.org\/article-onu_syrie_russie_usa_et_la_guerre_dans_tout_a__27_09_2013.html\" class=\"gen\">27 septembre 2013<\/a>). Ce risque-l\u00e0, il faut bien le pr\u00e9ciser, est d&rsquo;abord un risque <strong>pour le bloc BAO<\/strong>.<\/p>\n<\/p>\n<p><p>\tLe 27 septembre 2013 fut donc un de ces jours qu&rsquo;on qualifie d&rsquo;historique, avec en plus la conversation t\u00e9l\u00e9phonique d&rsquo;Obama \u00e0 Rouhani (dans ce sens, Obama ayant pris l&rsquo;initiative d&rsquo;appeler Rouhani), dans le meilleur climat du monde, apr\u00e8s la performance de communication du nouveau pr\u00e9sident iranien \u00e0 l&rsquo;ONU, ponctu\u00e9e par sa rencontre avec Kerry et la Haute Repr\u00e9sentante de l&rsquo;UE Ashton que l&rsquo;on entendit rire presque aux \u00e9clats \u00e0 plus d&rsquo;une occasion. Rouhani se sert parfaitement de son allure bon enfant et conciliante. Pour l&rsquo;instant, n\u00e9anmoins, c&rsquo;est l&rsquo;affaire syrienne qui est la plus importante parce qu&rsquo;elle implique des actes (le r\u00e9solution de l&rsquo;ONU), tandis que la conversation BHO-Rouhani et le reste ne constituent que des mises en place de pr\u00e9paration, une mise en forme enjou\u00e9e du climat de la communication entre l&rsquo;Iran et le Bloc BAO. La Russie, notamment avec le regard per\u00e7ant de Lavrov qui la repr\u00e9sentait \u00e0 l&rsquo;ONU, observe tout cela non sans une certaine satisfaction,  mais, sans doute, sans tenir rien pour acquis.<\/p>\n<\/p>\n<p><p>\tNous passons rapidement sur les effusions entre l&rsquo;Iran et le bloc BAO sous ses divers aspects (voir l&rsquo;offensive de charme de Rouhani, sur <em>Al Monitor<\/em> le <a href=\"http:\/\/www.al-monitor.com\/pulse\/originals\/2013\/09\/rouhani-un-visit-reception-message.html#ixzz2g9xLvbp1\" class=\"gen\">27 septembre 2013<\/a>), y compris la conversation Obama-Rouhani qui a contribu\u00e9 d\u00e9cisivement au climat bon enfant et aux intentions bienveillantes,  rien de plus mais rien de moins,  ponctu\u00e9e des pr\u00e9cisions qui fournissent le <em>corpus<\/em> anecdotique indispensable pour toute bonne copie \u00e0 publier. (Voir encore <em>Al Monitor<\/em>, dans sa rubrique <em>Back Channel<\/em>, le <a href=\"http:\/\/backchannel.al-monitor.com\/index.php\/2013\/09\/6402\/obama-speaks-with-irans-rouhani\/#ixzz2g9yI3u00\" class=\"gen\">27 septembre 2013<\/a> : \u00ab<em>Obama signed off on the call with a Persian goodbye, after Rouhani wished him farewell in English, the White House said. Rouhani&rsquo;s Twitter account, in a tweet that was later deleted, said Rouhani told Obama in English, Have a Nice Day!&rsquo; and Obama responded with, Thank you. Khodahafez.&rsquo;<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tPour ce qui concerne le plat de r\u00e9sistance, qui est la r\u00e9solution de l&rsquo;ONU sur la Syrie, McClatchy.<em>News<\/em> donne une bonne interpr\u00e9tation de l&rsquo;\u00e9v\u00e9nement, le <a href=\"http:\/\/www.mcclatchydc.com\/2013\/09\/27\/v-print\/203520\/despite-lacking-a-military-threat.html\" class=\"gen\">27 septembre 2013<\/a>. Il faut tout de m\u00eame noter que cette interpr\u00e9tation est comment\u00e9e par des experts qui sont manifestement l\u00e0 pour tenter de mettre en \u00e9vidence tout ce qu&rsquo;il y a de <strong>pas tout \u00e0 fait catastrophique<\/strong> dans cette r\u00e9solution, pour la politique am\u00e9ricaniste depuis deux ans, jusqu&rsquo;\u00e0 la plus r\u00e9cente s\u00e9quence.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The U.N. Security Council late Friday approved a U.S.-Russian resolution that mandates the expedited removal of Syrian President Bashar Assad&rsquo;s chemical weapons arsenal but stops short of threatening military action for noncompliance&#8230;<\/em> [..] <em>In other words, if Assad is accused of another chemical attack, Russia could still use its veto power to drag out the Security Council&rsquo;s determination of noncompliance, and then could block the harshest measures under the U.N. Charter&rsquo;s Chapter 7. Of course, President Barack Obama already has argued that he doesn&rsquo;t need Security Council approval to carry out military strikes against regime targets, though that threat of unilateral military force is much dimmer now that the U.S. has signed on to the international route.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The worst-case scenario from the administration&rsquo;s perspective would be if Assad does violate the resolution in some way and then the Russians stonewall at the Security Council. Then the administration is sort of back to square one in terms of what it does, said Peter Spiro, who teaches international law at Temple University in Philadelphia and who testified before the Senate Foreign Relations Committee on the NATO intervention in Libya. Still, that doesn&rsquo;t mean the resolution is insignificant, Spiro and other international law experts said. It would be hard for Russia to argue against findings of noncompliance as wrong or politically motivated because the resolution is written so that any violations would be confirmed first by experts from the Organization for the Prohibition of Chemical Weapons, the world body that monitors the chemical weapons ban.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Gregory Fox, who teaches international law at Wayne State University in Michigan and has written extensively about the Security Council&rsquo;s role in promoting democracy, said that the lack of an automatic trigger for military action isn&rsquo;t necessarily a failing in the resolution because such automatic triggers are extremely rare. The only case he could think of was Resolution 678 against Iraq in 1990, after Saddam Hussein&rsquo;s forces invaded Kuwait. Fox said the resolution&rsquo;s use of must and shall to outline what Syria is to do is consistent with a Chapter 7 resolution. He noted that sanctions as a punitive tool can work, arguing that Iran wouldn&rsquo;t have made the landmark overtures seen this week at the United Nations without the toll sanctions have taken on the Islamic Republic&rsquo;s economy&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe rapport McClatchy s&rsquo;attache \u00e9galement aux r\u00e9actions de l&rsquo;opposition syrienne. Il y est essentiellement question de l&rsquo;opposition convenable, soutenue par le bloc BAO, c&rsquo;est-\u00e0-dire l&rsquo;opposition type-peau de chagrin puisqu&rsquo;elle laisse dans une ombre ind\u00e9cise et mena\u00e7ante l&rsquo;essentiel de la r\u00e9bellion sur le terrain en termes de capacit\u00e9s op\u00e9rationnelles, savoir les groupes djihadistes et islamistes. D&rsquo;une fa\u00e7on assez int\u00e9ressante, le chef de cette opposition convenable,, Ahmed Jarba, a d\u00e9clar\u00e9 que l&rsquo;un de ses buts s&rsquo;il allait \u00e0 la conf\u00e9rence Gen\u00e8ve-II,  ce qu&rsquo;il semble vouloir faire conform\u00e9ment aux consignes,  serait l&rsquo;expulsion de Syrie de tous les combattants \u00e9trangers. Cela signifie bien entendu les Iraniens et les combattants du Hezbollah qui s&rsquo;y trouvent, <strong>mais aussi<\/strong> les djihadistes\/islamistes de la r\u00e9bellion, qui sont tous des non-Syriens. (Et McClatchy de conclure justement : \u00ab<em>Any close observer of the conflict understands that the Islamist extremist fighters comprise the rebels&rsquo; most effective fighting force, and it is difficult to see who would expel them.<\/em>\u00bb) La m\u00eame logique pr\u00e9vaut dans le chef des Russes, qui disent que l&rsquo;\u00e9limination des armes chimiques signifie la destruction des stocks d&rsquo;Assad mais aussi des armements chimiques que poss\u00e8de la r\u00e9bellion (voir <em>Russia Today<\/em> le <a href=\"http:\/\/rt.com\/news\/syria-chemical-weapons-lavrov-kerry-298\/\" class=\"gen\">25 septembre 2013<\/a>) ; l\u00e0 aussi, un territoire min\u00e9 propre \u00e0 bien des querelles.<\/p>\n<\/p>\n<p><p>\tMcClatchy : \u00ab<em>&#8230;To the Syrian opposition&rsquo;s chagrin, the deal also would appear to protect against the risk of an abrupt regime change, which the administration wants to avoid given the lack of a viable, moderate opposition authority waiting in the wings. That gives the Assad government every incentive to comply fully with the resolution, gambling that the time and expenditure associated with the undertaking would dull the West&rsquo;s political will to remove him from office. Assad still has an overwhelming tactical advantage, Fox said. He&rsquo;s giving up his chemical weapons, but is not giving up his ability to fight this civil war, brutally.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Syrian opposition leaders have criticized the U.S.-Russian deal, complaining of feeling sold out by the Obama administration&rsquo;s narrowing of its strategic interests to the chemical weapons issue. More than 100,000 people have died and millions have been displaced, the opposition notes, and yet the U.S. entered into a deal with Russia that all but guarantees Assad job security for at least the next several months.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Ahmed Jarba, head of the Syrian Opposition Coalition, the opposition faction recognized by the U.S. and Britain as the legitimate representative of the Syrian people, adopted a slightly softer stance toward the resolution in remarks to reporters Friday in New York. He said the opposition would&rsquo;ve preferred to have seen tougher language on consequences but that, overall, the group was happy with the resolution because it removes at least one tool from Assad&rsquo;s vast arsenal. However, Jarba added, there must be a parallel track to support the opposition&rsquo;s fighting side, which was dealt a huge blow this week when five brigades that had been part of the U.S.-backed Supreme Military Command joined an Islamist bloc spearheaded by the al Qaida-allied Nusra Front&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCette r\u00e9solution de l&rsquo;ONU est particuli\u00e8rement int\u00e9ressante parce qu&rsquo;elle permet de rassembler tous les grands enseignements de la s\u00e9quence paroxystique de la crise syrienne que nous venons de vivre, de remettre certaines affirmations dans une lumi\u00e8re bien contradictoire, d&rsquo;envisager des perspectives <strong>extr\u00eamement contrast\u00e9es<\/strong>. Elle fixe \u00e9galement ce qui est moins le triomphe de la diplomatie russe en tant que telle (repr\u00e9sentante des int\u00e9r\u00eats russes) que le triomphe d&rsquo;une diplomatie essentiellement principielle que repr\u00e9sente la Russie, aux d\u00e9pens d&rsquo;une anti-diplomatie spasmodique appuy\u00e9e sur des valeurs d\u00e9termin\u00e9es pour permettre de d\u00e9velopper arbitrairement cette anti-diplomatie.<\/p>\n<\/p>\n<p><p>\t Puisque cette r\u00e9solution marque un  triomphe de la diplomatie principielle, donc de la diplomatie russe qui en est l&rsquo;expression la plus proche aujourd&rsquo;hui, elle est certainement, de fa\u00e7on encore plus affirm\u00e9e, une d\u00e9b\u00e2cle de la politique des valeurs, du bloc BAO. Les USA (et les suppl\u00e9tifs avec eux) ont c\u00e9d\u00e9 sur l&rsquo;essentiel : pas de menace militaire (chapitre VII), la pol\u00e9mique autour de la responsabilit\u00e9 de l&rsquo;attaque du 21 ao\u00fbt laiss\u00e9e de c\u00f4t\u00e9. Tout le montage concernant une exp\u00e9dition punitive conforme \u00e0 la <em>narrative<\/em> du pr\u00e9sum\u00e9 coupable mis au ban de l&rsquo;humanit\u00e9 apr\u00e8s avoir \u00e9t\u00e9 jug\u00e9 dans ce sens avant m\u00eame l&rsquo;examen du d\u00e9lit, ce montage s&rsquo;effondre d&rsquo;un seul mouvement. Cela ne signifie pas qu&rsquo;on n&rsquo;y reviendra pas, cela signifie qu&rsquo;il n&rsquo;a pour l&rsquo;instant plus aucune pertinence.<\/p>\n<\/p>\n<p><p>\t La principale cons\u00e9quence de cette situation est une sorte de re-l\u00e9g\u00e9timation d&rsquo;Assad, puisqu&rsquo;il est n\u00e9cessairement impliqu\u00e9 comme tel (pr\u00e9sident de la Syrie) dans une r\u00e9solution qui porte sur l&rsquo;armement chimique qu&rsquo;il contr\u00f4le, puisque son existence l\u00e9gitime est act\u00e9e pour toutes les op\u00e9rations concernant cet armement chimique, puisque sa pr\u00e9sence l\u00e9gitime (de ses repr\u00e9sentants) \u00e0 Gen\u00e8ve-II qui doit suivre est \u00e9galement act\u00e9e. Pour ces pays qui, il y a dix-huit mois ne pouvaient concevoir n&rsquo;importe quelle d\u00e9marche officielle sur la Syrie qu&rsquo;apr\u00e8s la liquidation (au moins politique, sinon pire) d&rsquo;Assad, il n&rsquo;y a pas pire situation. Pour tous les pays du bloc BAO, l&rsquo;existence du  chimique n&rsquo;a jamais \u00e9t\u00e9 officiellement un sujet de pr\u00e9occupation, sinon pour pouvoir exiger le d\u00e9part d&rsquo;Assad d\u00e8s qu&rsquo;un usage de chimique permettait de monter une d\u00e9nonciation contre lui. La situation est compl\u00e8tement renvers\u00e9e : le chimique est l&rsquo;objet officiel sinon exclusif de la pr\u00e9occupation, et l&rsquo;existence d&rsquo;Assad comme pr\u00e9sident, pass\u00e9e au second plan, est n\u00e9cessairement ent\u00e9rin\u00e9e par toute l&rsquo;op\u00e9ration. <\/p>\n<\/p>\n<p><p>\t Le mythe du th\u00e8me la menace de la force paye, employ\u00e9 par les divers commentateurs du bloc BAO pour couvrir de la vertu du r\u00e9alisme la d\u00e9b\u00e2cle \u00e0 l&rsquo;ONU, ne r\u00e9siste pas une seconde \u00e0 l&rsquo;analyse. Assad, le 10 septembre, n&rsquo;a pas c\u00e9d\u00e9 \u00e0 la force en acceptant le plan des Russes. La menace de la force n&rsquo;existait plus essentiellement contre lui depuis le 31 ao\u00fbt, jour o\u00f9 Obama a d\u00e9cid\u00e9 de consulter le Congr\u00e8s sur l&rsquo;usage de cette force. Depuis ce jour, la menace de la force s&rsquo;exer\u00e7ait directement contre le pr\u00e9sident des USA, devant la perspective d&rsquo;un vote n\u00e9gatif in\u00e9vitable du Congr\u00e8s : soit Obama obtemp\u00e9rait \u00e0 ce vote n\u00e9gatif et il n&rsquo;\u00e9tait plus question de force, mais de la faiblesse, voire de la marginalisation d&rsquo;un ex\u00e9cutif ridiculis\u00e9 ; soit il passait outre et se trouvait devant une autre menace, bien plus s\u00e9rieuse, celle d&rsquo;une proc\u00e9dure de destitution ouvrant une tr\u00e8s grave crise institutionnelle en pleine crise ext\u00e9rieure aigu. Si quelqu&rsquo;un a \u00e9t\u00e9 sauv\u00e9 en l&rsquo;occurrence par le plan russe connect\u00e9 \u00e0 la menace de la force, c&rsquo;est Obama, pas Assad, et les Russes le savent bien : outre l&rsquo;int\u00e9r\u00eat du plan lui-m\u00eame, ils sont intervenus pour sauver Obama, pas Assad, parce qu&rsquo;ils ont besoin d&rsquo;un gouvernement stable aux USA pour tenter de stabiliser la situation en Syrie. (Voir le <a href=\"http:\/\/www.dedefensa.org\/article-une_am_rique_antiguerre_une_am_rique_en_r_volte__10_09_2013.html\" class=\"gen\">10 septembre 2013<\/a> : \u00ab<em>Quant \u00e0 la Russie, elle a manuvr\u00e9 classiquement, selon sa politique ferme et principielle qui est de rechercher la stabilisation, si n\u00e9cessaire en venant \u00e0 l&rsquo;aide d&rsquo;un pr\u00e9sident US en difficult\u00e9,  ce qui va aussi dans le sens d&rsquo;un but de stabilisation. (C&rsquo;est une habitude h\u00e9rit\u00e9e du temps de l&rsquo;URSS : le meilleur et le plus fid\u00e8le soutien de Nixon pendant la crise du Watergate fut certainement le Premier Secr\u00e9taire du PC de l&rsquo;URSS Brejnev&#8230;)<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\t D&rsquo;une certaine fa\u00e7on, la crise syrienne est donc internationalis\u00e9e, mais pas du tout comme le voulaient les pays du bloc BAO. Cette internationalisation se fait dans le cadre de l&rsquo;ONU dans le sens inverse voulu par les pays du bloc BAO : position centrale de la Russie, renforcement de la l\u00e9gitimit\u00e9 d&rsquo;Assad et, autre \u00e9l\u00e9ment que nous relierions \u00e0 cette m\u00eame s\u00e9quence paroxystique, <a href=\"http:\/\/www.dedefensa.org\/article-le_grand_schisme__26_09_2013.html\" class=\"gen\">Grand Schisme<\/a> \u00e0 l&rsquo;int\u00e9rieur du camp rebelle pr\u00e9cipit\u00e9 par les \u00e9v\u00e9nements depuis le plan russe. Une autre cons\u00e9quence adverse pour le camp BAO, c&rsquo;est l&rsquo;isolement d&rsquo;Isra\u00ebl, qui s&rsquo;est imprudemment impliqu\u00e9 dans la crise syrienne contre Assad depuis plusieurs mois (alors qu&rsquo;une bonne partie de l&rsquo;<em>establishment<\/em> de s\u00e9curit\u00e9 nationale isra\u00e9lien \u00e9tait contre cette implication), et qui paye cet engagement \u00e9videmment dans le sens d&rsquo;un maximalisme interventionniste par l&rsquo;isolement que nous signalons puisque la solution de force n&rsquo;a pas eu lieu et qu&rsquo;Assad est en meilleure position aujourd&rsquo;hui. Triste cerise pour le g\u00e2teau que Netanyahou a essuy\u00e9 en pleine face, le r\u00e9chauffement des relations de l&rsquo;Iran avec le bloc BAO. La position int\u00e9rieure de Netanyahou risque de devenir tr\u00e8s rapidement tr\u00e8s pr\u00e9caire, devant l&rsquo;\u00e9chec g\u00e9n\u00e9ralis\u00e9 de sa politique.<\/p>\n<\/p>\n<p><p>\tTous ces constats concernent des situations qui, selon nous, sont av\u00e9r\u00e9es. Nous le r\u00e9p\u00e9tons, nous sommes dans le domaine tactique, et la situation strat\u00e9gique n&rsquo;est pas tranch\u00e9e, et loin de l&rsquo;\u00eatre. Nous ne pensons aucunement que ces diverses circonstances stabilisent la situation d&rsquo;une fa\u00e7on d\u00e9cisive, parce que la crise syrienne est une crise arch\u00e9typique par sa fragilit\u00e9 de situation, avec notamment la tendance g\u00e9n\u00e9rale du bloc BAO \u00e0 l&rsquo;extr\u00e9misme, y compris et surtout lorsque sa politique subit des revers. La crise syrienne est dans un risque constant de basculement, m\u00eame lorsqu&rsquo;un tel bouleversement tactique a lieu. Le seul enseignement est de constater que, dans de telles conditions si fortement \u00e9largies et dramatis\u00e9es, tout basculement est n\u00e9cessairement plus risqu\u00e9 et porteur de potentialit\u00e9s plus graves. Ainsi, l&rsquo;hypoth\u00e8se maximale d\u00e9battue le <a href=\"http:\/\/www.dedefensa.org\/article-onu_syrie_russie_usa_et_la_guerre_dans_tout_a__27_09_2013.html\" class=\"gen\">27 septembre 2013<\/a> n&rsquo;est absolument pas obsol\u00e8te, au contraire elle est install\u00e9e comme un risque structurel tr\u00e8s s\u00e9rieux. La seule remarque optimiste qu&rsquo;on peut faire est que cette hypoth\u00e8se, justement, pourrait faire r\u00e9fl\u00e9chir un peu plus, du c\u00f4t\u00e9 du bloc BAO, que l&rsquo;on n&rsquo;a fait jusqu&rsquo;ici ; optimisme pas loin du vu pieux, mais enfin&#8230;<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 28 septembre 2013 \u00e0 11H46<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une r\u00e9solution qui en dit si long&#8230; En termes de tactique, signifiant \u00e9videmment que la situation strat\u00e9gique n&rsquo;est en rien boucl\u00e9e, la r\u00e9solution de l&rsquo;ONU vot\u00e9e vendredi pulv\u00e9rise tout l&rsquo;argumentaire de la politique du bloc BAO depuis deux ans \u00e0 l&rsquo;encontre du gouvernement de la Syrie. C&rsquo;est une avanc\u00e9e tactique significative, dans une crise qui&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4202,12453,3903,3318,2773,2830,3555,3679,2790,3478,4607,12268,12241,3867,5600,12454],"class_list":["post-75229","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-assad","tag-chapitre","tag-chimique","tag-force","tag-iran","tag-lavrov","tag-legitimite","tag-menace","tag-netanyahou","tag-onu","tag-politique","tag-principielle","tag-rouhani","tag-syrie","tag-tactique","tag-vii"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75229"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75229\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}