{"id":75237,"date":"2013-10-03T09:04:47","date_gmt":"2013-10-03T09:04:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/10\/03\/snowden-nomine-pour-le-prix-sakharov\/"},"modified":"2013-10-03T09:04:47","modified_gmt":"2013-10-03T09:04:47","slug":"snowden-nomine-pour-le-prix-sakharov","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/10\/03\/snowden-nomine-pour-le-prix-sakharov\/","title":{"rendered":"Snowden \u201cnomin\u00e9\u201d pour le Prix Sakharov"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Snowden nomin\u00e9 pour le Prix Sakharov<\/h3>\n<\/p>\n<p><p>\tLundi, le Parlement europ\u00e9en a donn\u00e9 la liste des trois ultimes s\u00e9lectionn\u00e9s pour le Prix Sakharov, sans doute la plus importante distinction institu\u00e9e dans le bloc BAO, section europ\u00e9enne, pour r\u00e9compenser des activit\u00e9s de d\u00e9fense des droits civiques et autres droits de l&rsquo;homme (selon les termes officiels des statuts, Prix destin\u00e9 \u00e0 \u00ab<em>r\u00e9compenser la libert\u00e9 d&rsquo;esprit et les personnalit\u00e9s qui s&rsquo;efforcent de d\u00e9fendre les droits de l&rsquo;Homme et les libert\u00e9s fondamentales<\/em>\u00bb). <em>France 24<\/em> pr\u00e9sentait ainsi, le <a href=\"http:\/\/www.france24.com\/fr\/20131001-edward-snowden-prix-sakharov-liberte-expression-parlement-europeen-scandale-prism-espionnage-etats-unis\" class=\"gen\">1er octobre 2013<\/a> les conditions de cette s\u00e9lection, ou nomination, qui repr\u00e9sente d\u00e9j\u00e0, en soi, un acte officiel int\u00e9ressant, sinon important, de la part du Parlement Europ\u00e9en (PE).<\/p>\n<\/p>\n<p><p>\t\u00ab<em>&#8230; C&rsquo;est sur le nom de cet ancien consultant pour la National Security Agency (NSA), une agence de renseignement am\u00e9ricaine, que la Gauche unitaire europ\u00e9enne et les \u00e9cologistes ont jet\u00e9 leur d\u00e9volu pour concourir au prix, remis par le Parlement europ\u00e9en pour r\u00e9compenser la libert\u00e9 d&rsquo;esprit et les personnalit\u00e9s qui s&rsquo;efforcent de d\u00e9fendre les droits de l&rsquo;Homme et les libert\u00e9s fondamentales.<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>\t\u00bb<em>La Gauche unitaire europ\u00e9enne et les \u00e9cologistes ont souhait\u00e9, en choisissant Edward Snowden, lui rendre hommage pour l&rsquo;\u00e9norme service qu&rsquo;il a rendu aux droits de l&rsquo;Homme et aux citoyens europ\u00e9ens. Dans un communiqu\u00e9 lu devant le Parlement europ\u00e9en, Edward Snowden a remerci\u00e9 les  d\u00e9put\u00e9s de relever le d\u00e9fi soulev\u00e9 par la question de la surveillance de masse. La surveillance de populations enti\u00e8res, plut\u00f4t que de cibler des individus pr\u00e9cis, devient la plus grande menace contre les droits de l&rsquo;Homme de notre temps, a-t-il \u00e9galement \u00e9crit. Il a risqu\u00e9 sa libert\u00e9 pour nous aider \u00e0 prot\u00e9ger la n\u00f4tre. Il est le symbole du rejet de l&rsquo;intrusion dans la vie priv\u00e9e des citoyens. Il faut lui reconna\u00eetre un r\u00f4le contre cette forme d&rsquo;oppression insidieuse, estime l&rsquo;eurod\u00e9put\u00e9e \u00e9cologiste Karima Delli, cit\u00e9e par l&rsquo;Humanit\u00e9&rsquo;.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Le nom du laur\u00e9at doit \u00eatre choisi le 10 octobre par les chefs de groupes politiques du Parlement europ\u00e9en. Le prix sera remis le 20 novembre prochain \u00e0 Strasbourg. Parmi les candidats, figurent \u00e9galement la jeune pakistanaise Malala Youzafsa\u00ef, cibl\u00e9e par les Taliban pour son combat sur la scolarisation des filles, et les militants b\u00e9larusses emprisonn\u00e9s Ales Bialiatski, Eduard Lobau et Mykola Statkevich.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;appr\u00e9ciation g\u00e9n\u00e9rale, dans les milieux europ\u00e9ens, est que Snowden a de grandes chances de remporter le Prix, selon la logique du processus r\u00e9alis\u00e9 jusqu&rsquo;ici. Les deux autres pr\u00e9s\u00e9lectionn\u00e9s (ou groupe de pr\u00e9s\u00e9lectionn\u00e9s), quelles que soient les situations et les comportements qui ont abouti \u00e0 leur s\u00e9lection, ont une notori\u00e9t\u00e9 beaucoup moins grande que celle de Snowden et, surtout, sont dans un contexte politique compl\u00e8tement diff\u00e9rent. L&rsquo;argument ainsi d\u00e9velopp\u00e9 dans les milieux cit\u00e9s est que la pr\u00e9s\u00e9lection de Snowden ent\u00e9rine officiellement une volont\u00e9 claire du PE de marquer sa propre position politique, tr\u00e8s diff\u00e9rente de celle des diverses autorit\u00e9s officielles europ\u00e9ennes soucieuses de ne pas interf\u00e9rer sur leurs propres relations avec les USA, que l&rsquo;on sait extr\u00eamement respectueuses de la susceptibilit\u00e9, et de la puissance de ce pays. \u00ab<em>Il serait politiquement illogique qu&rsquo;apr\u00e8s une telle affirmation officielle, le PE n&rsquo;aille pas au terme de sa d\u00e9marche<\/em>, observe une de ces sources. <em>Le seul argument contraire, qui est loin d&rsquo;\u00eatre n\u00e9gligeable et qui p\u00e8se son poids, peut venir de pressions des autorit\u00e9s europ\u00e9ennes contre la d\u00e9signation de Snowden le 10 octobre, voire de pressions US indirectes et directes, qui doivent d&rsquo;ores et d\u00e9j\u00e0 \u00eatre en pleine action.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLa pr\u00e9s\u00e9lection de Snowden a attir\u00e9 assez peu d&rsquo;attention aux USA, o\u00f9 la presse-Syst\u00e8me est compl\u00e8tement absorb\u00e9e par le <em>government shutdown<\/em> ; de toutes les fa\u00e7ons, le r\u00e9flexe basique et pavlovien de cette presse-Syst\u00e8me dans cette affaire pr\u00e9cis\u00e9ment, et dans un domaine symbolique aussi sensible, est d&rsquo;accorder le moins de publicit\u00e9 possible au processus officiel tant qu&rsquo;il n&rsquo;est pas arriv\u00e9 \u00e0 son terme. McClatchy.<em>News<\/em> publie un texte essentiellement factuel, le <a href=\"http:\/\/www.mcclatchydc.com\/2013\/10\/01\/203815\/nsa-leaker-snowden-among-finalists.html#storylink=cpy\" class=\"gen\">2 octobre 2013<\/a>, mentionnant tout de m\u00eame l&rsquo;avis d&rsquo;un expert fran\u00e7ais de l&rsquo;IFRI, Dominique Mo\u00efsi, connu depuis longtemps, sinon depuis toujours, pour ses positions atlantistes et proam\u00e9ricanistes,  mais pratiquant dans ce cas, par r\u00e9flexe du respect courant chez lui pour les institutions europ\u00e9ennes officielles et par prudence de pronostic, une dialectique de type mi-figue mi-raisin&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Dominique Moisi, an expert on European-American relations at the French Institute for International Relations, cautioned that the nomination says more about the nominating parties than about a broader European view. But even he acknowledged that the inclusion of Snowden in the final three underscores a major difference between the United States and Europe. Perhaps it says that with the NSA scandal, the United States has isolated itself among democratic countries, he said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<em>France 24<\/em> mentionne dans son texte cette observation d&rsquo;\u00e9vidence d&rsquo;une situation du comble de l&rsquo;ironie : \u00ab<em>Comble de l&rsquo;ironie, alors qu&rsquo;il figure aujourd&rsquo;hui parmi les candidats au prix du Parlement europ\u00e9en, aucun pays de l&rsquo;Union europ\u00e9enne n&rsquo;a souhait\u00e9 lui accorder l&rsquo;asile au moment de la r\u00e9v\u00e9lation du scandale.<\/em>\u00bb C&rsquo;est surtout reconna\u00eetre la position qu&rsquo;a prise le PE depuis l&rsquo;origine de la crise Snowden\/NSA sur le cas Snowden, \u00e0 partir de l&rsquo;\u00e9motion consid\u00e9rable soulev\u00e9e dans les milieux parlementaires europ\u00e9ens par les r\u00e9v\u00e9lations-Snowden sur les structures d&rsquo;\u00e9coute et de surveillance de la NSA en Europe, et notamment dans les institutions europ\u00e9ennes. (Structures qui, jusqu&rsquo;\u00e0 nouvel ordre, sont toujours en place et toujours au travail.) On reconna\u00eet l\u00e0 le comportement assez courant du PE, dans certaines affaires pol\u00e9miques, de prendre le contrepied des positions officielles europ\u00e9ennes de pusillanimit\u00e9 et de prudence. On sait que c&rsquo;est un caract\u00e8re constant de l&rsquo;activit\u00e9 de la repr\u00e9sentation parlementaire, qui estime ne pas avoir assez de pouvoir, et qui cherche \u00e0 interf\u00e9rer sur les institutions ex\u00e9cutives et les gouvernements des pays membres dans leurs actions europ\u00e9ennes, en g\u00e9n\u00e9ral dans un sens maximalistes, pour faire pression sur ces ex\u00e9cutifs, affirmer son existence, r\u00e9clamer plus de pouvoir, etc. D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, et surtout dans cette affaire Snowden \u00e0 cause de sa tr\u00e8s haute signification politique, on observe ainsi une grande diff\u00e9rence entre l&rsquo;activisme des repr\u00e9sentations europ\u00e9ennes des partis impliqu\u00e9s, et leurs repr\u00e9sentations nationales beaucoup plus prudentes et timides \u00e0 cause de leur proximit\u00e9, voire de leurs implications dans les affaires gouvernementales. Il s&rsquo;agit d&rsquo;un jeu assez classique, qui est en g\u00e9n\u00e9ral d&rsquo;une importance politique assez pauvre et d&rsquo;un effet \u00e0 mesure, sauf pour certaines exceptions d&rsquo;affaires particuli\u00e8rement pol\u00e9miques et politiques. Le cas du r\u00e9seau <em>Echelon<\/em> au milieu des ann\u00e9es 1990 en est un exemple, et le cas Snowden aujourd&rsquo;hui, qui poursuit cette veine en quelque sorte, en est un autre.<\/p>\n<\/p>\n<p><p>\tBien entendu, le cas Snowden est incomparablement plus important et plus significatif dans le chef d&rsquo;une \u00e9ventuelle attribution du Prix Sakharov au <em>whistleblower<\/em>, que tout ce que le PE a pu faire dans l&rsquo;affaire <em>Echelon<\/em>. Dans l&rsquo;apparat du Syst\u00e8me, le Prix Sakharov est extr\u00eamement prestigieux et d&rsquo;une valeur symbolique qu&rsquo;aucune autorit\u00e9 du Syst\u00e8me ne peut ignorer dans le cadre du syst\u00e8me de la communication. C&rsquo;est assez dire que, si Snowden re\u00e7oit le Prix, l&rsquo;effet public et de communication sera consid\u00e9rable, sans commune mesure avec les r\u00e9actions pour sa pr\u00e9s\u00e9lection, et cet effet sera sans aucun doute un fait politique de grande importance. La direction washingtonienne et le reste \u00e0 Washington (la presse-Syst\u00e8me) ne pourront pas, et ne voudront pas d&rsquo;ailleurs passer la chose sous silence. Il s&rsquo;agira in\u00e9vitablement, du point de vue officiel US, d&rsquo;un acte de d\u00e9fiance et d&rsquo;hostilit\u00e9 <strong>de l&rsquo;Europe<\/strong> en tant que telle vis-\u00e0-vis des USA. Les autorit\u00e9s am\u00e9ricanistes n&rsquo;ont pas l&rsquo;habitude de sacrifier \u00e0 la subtilit\u00e9 consistant \u00e0 d\u00e9m\u00ealer les diff\u00e9rences, les antagonismes, etc., entre les diff\u00e9rentes institutions europ\u00e9ennes, et l&rsquo;acte du PE serait alors consid\u00e9r\u00e9 comme un acte europ\u00e9en, m\u00eame si les ex\u00e9cutifs europ\u00e9ens n&rsquo;en sont manifestement pas partisanes. Les autorit\u00e9s am\u00e9ricanistes consid\u00e9reront in\u00e9vitablement ce choix comme un d\u00e9fi \u00e0 la suppos\u00e9e bonne r\u00e9putation des USA dans une affaire o\u00f9 on a pu mesurer d\u00e9j\u00e0 l&rsquo;extraordinaire sensibilit\u00e9 US \u00e0 l&rsquo;\u00e9gard de l&rsquo;apparat officiel, des positions formelles, .<\/p>\n<\/p>\n<p><p>\tAttendons donc le 10 octobre puisque, cette ann\u00e9e, le Prix Sakharov, du nom de l&rsquo;acad\u00e9micien sovi\u00e9tique dissident et Prix Nobel de la Paix 1975, aura sans aucun doute, certainement dans le d\u00e9bat pour son attribution, un r\u00e9el int\u00e9r\u00eat politique ; et si Snowden est choisi, nous attendrons alors le 20 novembre, pour constater s&rsquo;il vient ou non \u00e0 Strasbourg, en personne, recevoir le Prix, et dans quelles conditions, peut-\u00eatre dans un avion de la CIA affr\u00e9t\u00e9 par la NSA, en pleine campagne de redorure de son blason tristement terni dans l&rsquo;esprit public. Pour nous faire patienter dans ces diverses occurrences, on peut m\u00e9diter sur l&rsquo;int\u00e9ressante nouvelle, et signe que les antiSyst\u00e8me entendent tenter d&rsquo;utiliser \u00e0 leur avantage tous les r\u00e9seaux et connections-Syst\u00e8me, de la demande officielle d&rsquo;un groupe de personnalit\u00e9s russes pour l&rsquo;inscription de Vladimir Poutine pour la nomination comme Prix Nobel de la Paix. Sans pr\u00e9juger une seconde de son r\u00e9sultat bien entendu, la d\u00e9marche en soi vaut d&rsquo;\u00eatre relev\u00e9e, d&rsquo;autant qu&rsquo;elle est pr\u00e9sent\u00e9e joliment comme un pendant au Prix Nobel de la Paix usurp\u00e9 par Obama en 2009. (Selon <em>Russia Today<\/em>, le <a href=\"http:\/\/rt.com\/politics\/putin-nobel-peace-prize-587\/\" class=\"gen\">1er octobre 2013<\/a>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>President Putin should get the Nobel Peace Prize for his moves to resolve the Syrian crisis, according to a group of Russian activists and political scientists who have indicated that they are officially proposing the president&rsquo;s nomination.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>One of the main sponsors of the move, State Duma MP Iosif Kobzon, told reporters that in his view Putin deserved the prize much more than the 2009 laureate, US President Barack Obama. Barack Obama is the man who has initiated and approved the United States&rsquo; aggressive actions in Iraq and Afghanistan, now he is preparing for an invasion into Syria. He bears this title nevertheless. Our president, who tries to stop the bloodshed and who tries to help the conflict situation with political dialogue, is in my view more worthy of this high title, the Interfax news agency quoted Kobzon as saying.<\/em>\u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 3 octobre 2013 \u00e0 09H04<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Snowden nomin\u00e9 pour le Prix Sakharov Lundi, le Parlement europ\u00e9en a donn\u00e9 la liste des trois ultimes s\u00e9lectionn\u00e9s pour le Prix Sakharov, sans doute la plus importante distinction institu\u00e9e dans le bloc BAO, section europ\u00e9enne, pour r\u00e9compenser des activit\u00e9s de d\u00e9fense des droits civiques et autres droits de l&rsquo;homme (selon les termes officiels des statuts,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[12213,2824,3186,3644,3871,5006,916,4999,12466],"class_list":["post-75237","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-ecoute","tag-europeen","tag-gauche","tag-nobel","tag-nsa","tag-parlement","tag-poutine","tag-surveillance","tag-verts"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75237"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75237\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}