{"id":75244,"date":"2013-10-08T06:11:10","date_gmt":"2013-10-08T06:11:10","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/10\/08\/finalement-ce-bachar-est-un-type-tres-bien\/"},"modified":"2013-10-08T06:11:10","modified_gmt":"2013-10-08T06:11:10","slug":"finalement-ce-bachar-est-un-type-tres-bien","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/10\/08\/finalement-ce-bachar-est-un-type-tres-bien\/","title":{"rendered":"\u201cFinalement, ce Bachar est un type tr\u00e8s bien&#8230;\u201d"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Finalement, ce Bachar est un type tr\u00e8s bien&#8230;<\/h3>\n<\/p>\n<p><p>\tFaut-il prendre au s\u00e9rieux les \u00e9v\u00e9nements du monde tels qu&rsquo;ils nous sont restitu\u00e9s par le syst\u00e8me de la communication ? La question se pose, bien qu&rsquo;en g\u00e9n\u00e9ral on l&rsquo;ignore, ou si on la devine on l&rsquo;\u00e9vacue, comme on glisse la cendre de cigarette sous le tapis &#8230; Notre appr\u00e9ciation est que les \u00e9v\u00e9nements du monde sont \u00e0 la fois un constant travail d&rsquo;interpr\u00e9tation, d&rsquo;appr\u00e9ciation, d&rsquo;intuition, enfin un constant travail de reconstruction, de <strong>restructuration<\/strong> \u00e0 partir de mille et mille morceaux souvent \u00e9pars et souvent sans le moindre sens selon la logique rationnelle courante ; et, bien entendu, un travail dans lequel la communication tient, pour la perception n\u00e9cessaire, une place essentielle.<\/p>\n<\/p>\n<p><p>\tConsid\u00e9rez la rencontre Kerry-Lavrov \u00e0 Bali, en Indon\u00e9sie, en marge du sommet de l&rsquo;APEC o\u00f9 Sa Majest\u00e9 Barack Obama n&rsquo;a pu se rendre puisqu&rsquo;il doit rester \u00e0 Washington pour surtout <strong>ne pas n\u00e9gocier<\/strong> la fin du <em>government shutdown<\/em>,  c&rsquo;est-\u00e0-dire, rester \u00e0 Washington, surtout pour ne rien faire, et nous prouver ainsi que le commandant en chef est <em>in charge<\/em>. Songez qu&rsquo;il y a un mois nous nous trouvions bien plus proche de la guerre que du <em>statu quo<\/em> de la crise, le pr\u00e9sident US pr\u00eat \u00e0 passer outre au probable vote n\u00e9gatif du Congr\u00e8s pour une attaque de punition contre la Syrie ; que le risque \u00e9tait bien que cette attaque puisse d\u00e9boucher sur un encha\u00eenement d&rsquo;\u00e9v\u00e9nements militaires o\u00f9 Russes et Am\u00e9ricains pouvaient se retrouver face \u00e0 face, c&rsquo;est-\u00e0-dire avec l&rsquo;hypoth\u00e8se de ce qu&rsquo;on nomme une guerre mondiale. Songez qu&rsquo;il y a quinze jours, apr\u00e8s que Poutine ait sauv\u00e9 Obama du pi\u00e8ge o\u00f9 il s&rsquo;\u00e9tait enferm\u00e9 d&rsquo;avoir \u00e0 d\u00e9cider d&rsquo;une attaque invraisemblable, l&rsquo;on travaillait d&rsquo;arrache-pied \u00e0 une r\u00e9solution de l&rsquo;ONU sur l&rsquo;armement chimique syrien que les parties am\u00e9ricaniste et fran\u00e7aise s&rsquo;acharnaient \u00e0 tenter de saboter en y introduisant une clause de punition militaire au cas o\u00f9 Bachar el-Assad ne tiendrait pas ses engagements ; songez que, durant tout ce laps de temps, les insultes continuaient \u00e0 pleuvoir sur Assad, l&rsquo;homme qui ne m\u00e9rite pas d&rsquo;exister (Fabius <em>texto<\/em>), le nouveau nouvel Hitler, dont ils r\u00e9clamaient tous la t\u00eate depuis dix-huit mois.<\/p>\n<\/p>\n<p><p>\t&#8230; Songez \u00e0 tout cela et \u00e9coutez cette petite musique enivrante qui nous vient de John Kerry donnant, suite \u00e0 sa rencontre avec son ami Sergue\u00ef, des appr\u00e9ciations \u00f4 combien \u00e9logieuses sur le comportement du pr\u00e9sident Assad, et bien entendu des amis russes &#8230; \u00ab<em>The process has begun in record time and we are appreciative for the Russian co-operation and obviously for the Syrian compliance&#8230;<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\tVoici ce que <em>Russia Today<\/em> nous dit, le <a href=\"http:\/\/rt.com\/news\/lavrov-kerry-apec-syria-818\/\" class=\"gen\">7 octobre 2013<\/a>, de cette rencontre. \u00ab<em>The Assad regime in Syria deserves credit for complying with the chemical weapons deal, US Secretary of State John Kerry said after the first high-level meeting with his Russian counterpart since Moscow and Washington agreed on the deal.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Kerry and Russian Foreign Minster Sergey Lavrov met on the sidelines of the APEC summit in Bali, Indonesia on Monday morning. The process has begun in record time and we are appreciative for the Russian co-operation and obviously for the Syrian compliance, Kerry said. The Secretary of State also said that the US has agreed with Russia to move towards Syria peace talks as soon as possible.<\/em> [&#8230;] <em>I think it&rsquo;s extremely significant that yesterday, Sunday, within a week of the (UN) resolution being passed, some chemical weapons were being destroyed, Kerry stressed. I think it&rsquo;s a credit to the Assad regime, frankly. It&rsquo;s a good beginning and we welcome a good beginning.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe <em>Guardian<\/em> du <a href=\"http:\/\/www.theguardian.com\/world\/2013\/oct\/07\/syrias-chemical-weapons-destruction-on-track-us-and-russia-agree\" class=\"gen\">7 octobre 2013<\/a> a rapport\u00e9 de son c\u00f4t\u00e9 cette r\u00e9action du secr\u00e9taire d&rsquo;\u00c9tat US, en la qualifiant de \u00ab<em>some rare, if qualified, US praise for Syrian president Bashar al-Assad<\/em>\u00bb. Il est int\u00e9ressant de rapporter la r\u00e9action du <em>Guardian<\/em> (m\u00eame s&rsquo;il s&rsquo;agit d&rsquo;une d\u00e9p\u00eache AP,  que l&rsquo;on peut nuancer, en, l&rsquo;endossant, selon la ligne du journal). Contrairement \u00e0 <em>Russia Today<\/em>, le <em>Guardian<\/em> a toujours \u00e9t\u00e9 extr\u00eamement d\u00e9favorable au pr\u00e9sident syrien, suivant la ligne d&rsquo;une condamnation morale compl\u00e8te, de la sorte qui implique son d\u00e9part sans conditions pour parvenir \u00e0 une possibilit\u00e9 de r\u00e8glement du conflit,  selon l&rsquo;attitude standard des conceptions des lib\u00e9raux interventionnistes.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The United States and Russia are very pleased with progress in destroying Syria&rsquo;s chemical weapons stocks, US secretary of state John Kerry said on Monday. He offered some rare, if qualified, US praise for Syrian president Bashar al-Assad. Kerry, speaking at a press conference with Russian foreign minister Sergei Lavrov, said the Assad regime deserved credit for its speedy compliance thus far with the UN security council resolution calling for the elimination of the weapons. But Kerry stressed Assad was not yet off the hook.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Let me be crystal clear, Kerry said, we&rsquo;re very pleased with the pace of what has happened with respect to chemical weapons.<\/em> [&#8230;]  <em>I think that was a terrific example of global co-operation, of multilateral efforts to accomplish an accepted goal and they have moved with equal speed to get on the ground in Syria and begin the operations, he said. I think it is also credit to the Assad regime for complying rapidly as they are supposed to, Kerry said. We hope that will continue. Now, I am not going to vouch today for what happens months down the road. But it is a good beginning and we should welcome a good beginning.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tNotre consid\u00e9ration n&rsquo;est pas ici de type politique et ne porte certainement pas sur l&rsquo;avancement du processus de d\u00e9sarmement chimique, ou sur la coop\u00e9ration Russie-USA qui est un fait av\u00e9r\u00e9 depuis plusieurs mois. Il est sur ce changement de ton <strong>extraordinaire<\/strong> de la partie US, qui a laiss\u00e9 la partie russe certes satisfaire, mais aussi passablement surprise sinon stup\u00e9faite, justement, du ton employ\u00e9 et de l&rsquo;enthousiasme montr\u00e9. Bien que la chose ait re\u00e7u assez peu de publicit\u00e9, il s&rsquo;agit d&rsquo;un acte diplomatique qui constitue une sorte de rel\u00e9gitimation officielle et proclam\u00e9e (et non <em>de facto<\/em>) d&rsquo;Assad dans le chef des USA pour cette s\u00e9quence, quoi qu&rsquo;il en soit des faits eux-m\u00eames et de l&rsquo;avenir de ce processus. (Nous insistons : rel\u00e9gitimation pour cette s\u00e9quence et quel que soit l&rsquo;avenir du processus, ce qui implique que la dynamique peut changer compl\u00e8tement d&rsquo;orientation dans trois jours. Nous nous en tenons \u00e0 l&rsquo;\u00e9v\u00e9nement indiscutable du 7 octobre 2013, \u00e0 Bali.)<\/p>\n<\/p>\n<p><p>\tIl faut d&rsquo;abord noter qu&rsquo;on a assist\u00e9 avec les derniers \u00e9v\u00e9nements \u00e0 une compl\u00e8te contraction de l&rsquo;essence m\u00eame du cas syrien vu du c\u00f4t\u00e9 US (bloc BAO), par rapport \u00e0 la constitution du dossier et la perception de la crise. Au d\u00e9part, et pendant l&rsquo;essentiel de la crise, jusqu&rsquo;au mois d&rsquo;ao\u00fbt, le facteur de l&rsquo;armement chimique en tant que tel a \u00e9t\u00e9 secondaire sinon accessoire dans la ligne de communication du bloc BAO. Cette ligne de communication \u00e9tait fond\u00e9e sur un seul point : <strong>l&rsquo;intol\u00e9rabilit\u00e9 du r\u00e9gime Assad<\/strong>, et particuli\u00e8rement avec le pr\u00e9alable de l&rsquo;\u00e9limination, politique voire physique, d&rsquo;Assad, cela selon le verdict sans appel de son comportement <strong>intol\u00e9rable<\/strong> dans les troubles touchant le pays depuis dix-huit mois. Cette ligne lui faisait porter l&rsquo;exclusivit\u00e9 de la responsabilit\u00e9, donc le consid\u00e9rait comme condamn\u00e9 sans appel. (Tout cela, quoi qu&rsquo;on puisse penser bien entendu de ces positions,  nous parlons d&rsquo;une <strong>logique interne<\/strong> d&rsquo;une politique, ou plut\u00f4t d&rsquo;une ligne de communication qui fait effectivement office de politique, qui a donc la m\u00eame importance.) L&rsquo;\u00e9l\u00e9ment chimique n&rsquo;a jou\u00e9 que dans la mesure o\u00f9 il causait, toujours selon cette ligne de communication, des pertes en vies humaines innocentes, toujours du fait de la responsabilit\u00e9 exclusive d&rsquo;Assad. Tout \u00e9tait consid\u00e9r\u00e9, arrang\u00e9, manipul\u00e9, etc., pour aller dans ce sens. Officiellement, l&rsquo;armement chimique et son d\u00e9mant\u00e8lement n&rsquo;ont jamais constitu\u00e9 un probl\u00e8me central, quelles qu&rsquo;aient \u00e9t\u00e9 les arri\u00e8re-pens\u00e9es. De m\u00eame, le v\u00e9ritable nud de la crie du 21 ao\u00fbt n&rsquo;est pas l&rsquo;armement chimique <em>per se<\/em> mais l&rsquo;attaque du 21 ao\u00fbt, consid\u00e9r\u00e9e absolument comme \u00e9tant du fait d&rsquo;Assad, ayant caus\u00e9 plus de 1.400 morts. (L\u00e0 aussi, tout cela selon la version US, et quelles que soient les innombrables manuvres de manipulation, de montage, etc., selon ce que nous savons des pratiques du bloc BAO \/des USA dans ce domaine  nous importe ici ce que nous nommons ligne de communication.)<\/p>\n<\/p>\n<p><p>\tPar cons\u00e9quent, la r\u00e9solution du point de vue th\u00e9orique du statut de l&rsquo;armement chimique et du point de vue pratique de sa d\u00e9molition avec un accord sans h\u00e9sitation d&rsquo;Assad, ou un bon d\u00e9but de r\u00e9solution, ne pouvaient constituer en soi un \u00e9l\u00e9ment central conduisant \u00e0 des appr\u00e9ciations si \u00e9logieuses de Kerry qu&rsquo;elles forment, dans leur esprit justement, une <strong>rel\u00e9gitimation d&rsquo;Assad<\/strong>. C&rsquo;est bien sur ce point que cette intervention est extr\u00eamement surprenante, particuli\u00e8rement sinon exclusivement dans son esprit et dans sa forme. Nous laissons volontairement de c\u00f4t\u00e9 les arri\u00e8re-pens\u00e9es, les calculs dits de <em>realpolitik<\/em>, la position difficiles de l&rsquo;administration US, etc. M\u00eame ces consid\u00e9rations ne justifient en rien le ton remploy\u00e9, justement cette sorte de rel\u00e9gitimation d&rsquo;Assad, <strong>y compris<\/strong> si l&rsquo;on accepte le fait qu&rsquo;il sera partie prenante \u00e0 une conf\u00e9rence \u00e0 venir, dite Gen\u00e8ve-II. Selon la <em>realpolitik<\/em> justement, tout cela peut \u00eatre admis, on dirait <em>de facto<\/em>, sans que de telles paroles de rel\u00e9gitimation soient prononc\u00e9es. <\/p>\n<\/p>\n<p><p>\tCe que nous voulons alors mettre en \u00e9vidence c&rsquo;est une hypoth\u00e8se hors du domaine de la politique rationnellement conduite et exerc\u00e9e, d&rsquo;autant que nous jugeons extr\u00eamement faible, sinon inexistante, la rationalit\u00e9 dans ce cas, du c\u00f4t\u00e9 du bloc BAO et des USA. Cette brutale \u00e9volution s\u00e9mantique de Kerry, inutilement brutale (m\u00eame si dans un sens souhaitable) selon une consid\u00e9ration politique rationnelle, permet d&rsquo;impliquer justement que nous ne sommes pas n\u00e9cessairement dans le domaine de la politique rationnelle. Tout se passe comme si, \u00e0 cause d&rsquo;un processus psychologique donn\u00e9 et selon des pressions non \u00e9labor\u00e9es humainement mais proc\u00e9dant plut\u00f4t de forces \u00e9v\u00e9nementielles non identifiables, ces interventions ressortaient d&rsquo;une autre sc\u00e8ne politique, voire d&rsquo;un monde politique diff\u00e9rent au sens fort et concret de ces termes.<\/p>\n<\/p>\n<p><p>\tNous pourrions simplement nous en tenir \u00e0 l&rsquo;ironie qu&rsquo;attire, voire que justifie un tel changement complet de ton et de substance (puisque ce comportement implique des engagements politiques concrets). Nous pr\u00e9f\u00e9rons aller un peu plus loin, puisque plac\u00e9s devant un v\u00e9ritable \u00e9v\u00e9nement public, circonstanci\u00e9, document\u00e9 et si frappant par son caract\u00e8re. (Nous pr\u00e9f\u00e9rons cela malgr\u00e9 que cette \u00e9volution brutale et extraordinaire n&rsquo;ait gu\u00e8re \u00e9t\u00e9 relev\u00e9e, ou bien mentionn\u00e9e avec une g\u00eane palpable, comme dans le cas du <em>Guardian<\/em>, et une r\u00e9elle incompr\u00e9hension. D&rsquo;abord, la presse-Syst\u00e8me ne trouve dans ce fait, on s&rsquo;en doute, rien d&rsquo;excitant du point de vue de ses crit\u00e8res. Ensuite, la Syrie n&rsquo;est plus dans ses pr\u00e9occupations : alors que certains \u00e9voquaient la Troisi\u00e8me Guerre mondiale il y a seulement trois semaines, aujourd&rsquo;hui, la crise est \u00e0 peine mentionn\u00e9e. D&rsquo;ailleurs, ce constat lui-m\u00eame participe d&rsquo;une certaine fa\u00e7on du climat de bizarrerie de l&rsquo;\u00e9v\u00e9nement observ\u00e9, sans d&rsquo;ailleurs que cette bizarrerie soit exceptionnelle,  ce qui est d&rsquo;autant plus marquant pour l&rsquo;appr\u00e9ciation d\u00e9velopp\u00e9e.) Ces diff\u00e9rents aspects, y compris les remarques entre parenth\u00e8ses, nous conduisent \u00e0 nouveau \u00e0 estimer qu&rsquo;il s&rsquo;agit l\u00e0, effectivement, d&rsquo;une situation extraordinaire, o\u00f9 l&rsquo;aspect psychologique et l&rsquo;effet d&rsquo;interf\u00e9rences de formes peu courantes l&#8217;emportent largement sur les explications rationnelles (y compris celles qui concerneraient des manuvres tortueuses des USA, dont on ne voit ici aucun signe et aucune justification). Cela nous confirme dans le jugement que nous vivons une p\u00e9riode m\u00e9tahistorique qui sort de l&rsquo;ordinaire, o\u00f9 l&rsquo;on doit consid\u00e9rer qu&rsquo;il existe plusieurs plans politiques et historiques d&rsquo;activit\u00e9 sans liens logiques et rationnels entre eux, y compris dans un m\u00eame dossier, dans une m\u00eame crise, pouvant conduire \u00e0 des changements de lignes de communication refl\u00e9tant des situations sans aucun lien entre elles puisque passant psychologiquement d&rsquo;un monde \u00e0 l&rsquo;autre.<\/p>\n<\/p>\n<p><p>\tEn d&rsquo;autres mots, la question est de savoir si le Kerry de lundi, \u00e0 Bali, est le m\u00eame homme, ou le m\u00eame Kerry que celui qui, dix jours avant encore, animaient tout son raisonnement autour de l&rsquo;axe de r\u00e9flexion de la possibilit\u00e9 de l&rsquo;organisation d&rsquo;une attaque contre la Syrie, c&rsquo;est-\u00e0-dire selon la logique compr\u00e9hensible (m\u00eame si hautement critiquable) de la ligne de communication d&rsquo;une agression arm\u00e9e et de l&rsquo;hostilit\u00e9 anti-Assad qui est la constante US depuis l&rsquo;origine du conflit. Le constat important est l&rsquo;absence comp\u00e8te de stade de d\u00e9compression, la rupture entre cette phase et les d\u00e9clarations de lundi, ainsi que l&rsquo;absence d&rsquo;int\u00e9r\u00eat politique de passer \u00e0 une telle position de soutien d&rsquo;Assad jusqu&rsquo;\u00e0 la rel\u00e9gitimation de la part d&rsquo;une administration qui n&rsquo;a jamais brill\u00e9 par l&#8217;emportement pour l&rsquo;enthousiasme, y compris pour ce qui serait une soudaine r\u00e9v\u00e9lation de la v\u00e9rit\u00e9, d&rsquo;autant que cette v\u00e9rit\u00e9 est si souvent contraire \u00e0 ses int\u00e9r\u00eats. Tout cela fait songer \u00e0 une sorte de rupture d&rsquo;un type compl\u00e8tement inhabituel, une rupture psychologique de type spatio-temporel, avec le surgissement d&rsquo;une perception compl\u00e8tement diff\u00e9rente impos\u00e9e par des facteurs non-identifi\u00e9es et non-identifiables et conduisant \u00e0 un espace et \u00e0 un temps politiques et historiques compl\u00e8tement diff\u00e9rents, plut\u00f4t qu&rsquo;\u00e0 un acte de type politique normal, m\u00eame si audacieux (ce dernier cas \u00e9tait en g\u00e9n\u00e9ral compl\u00e8tement \u00e9tranger \u00e0 un processus bureaucratique normal de cette administration, donc compl\u00e8tement improbable). Cette hypoth\u00e8se fait partie des facteurs rationnellement inexplicables qui foisonnent actuellement dans les comportements politiques, qui sont la marque de l&rsquo;exceptionnalit\u00e9 de la p\u00e9riode,  la crise syrienne \u00e9tant d&rsquo;ailleurs un des \u00e9v\u00e9nements-phare de cette exceptionnalit\u00e9 de l&rsquo;\u00e9poque, et cela renfor\u00e7ant l&rsquo;hypoth\u00e8se.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 8 octobre 2013 \u00e0 05H59<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finalement, ce Bachar est un type tr\u00e8s bien&#8230; Faut-il prendre au s\u00e9rieux les \u00e9v\u00e9nements du monde tels qu&rsquo;ils nous sont restitu\u00e9s par le syst\u00e8me de la communication ? La question se pose, bien qu&rsquo;en g\u00e9n\u00e9ral on l&rsquo;ignore, ou si on la devine on l&rsquo;\u00e9vacue, comme on glisse la cendre de cigarette sous le tapis &#8230;&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4202,8424,12476,3903,855,2830,2878,12475,2789,12474,3867],"class_list":["post-75244","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-assad","tag-autre","tag-bali","tag-chimique","tag-kerry","tag-lavrov","tag-monde","tag-relegitimation","tag-rupture","tag-spati-temporelle","tag-syrie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75244"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75244\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}