{"id":75275,"date":"2013-10-28T05:34:20","date_gmt":"2013-10-28T05:34:20","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/10\/28\/notes-sur-les-pathologies-de-la-modernite\/"},"modified":"2013-10-28T05:34:20","modified_gmt":"2013-10-28T05:34:20","slug":"notes-sur-les-pathologies-de-la-modernite","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/10\/28\/notes-sur-les-pathologies-de-la-modernite\/","title":{"rendered":"Notes sur les pathologies de la modernit\u00e9"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">Notes sur les pathologies de la modernit\u00e9<\/h2>\n<\/p>\n<p><p>28 octobre 2013 &ndash; La semaine derni\u00e8re fut singuli\u00e8re, comme on le sait, avec l&rsquo;implication <strong>forc\u00e9e mais imp\u00e9rative<\/strong> de l&rsquo;Europe dans la crise Snowden\/NSA, du c\u00f4t\u00e9 des accusateurs r\u00e9ticents. \u00ab\u00a0Forc\u00e9e\u00a0\u00bb pour l&rsquo;implication europ\u00e9enne, \u00ab\u00a0r\u00e9ticents\u00a0\u00bb pour les accusateurs europ\u00e9ens, parce que l&rsquo;Europe et les USA sont absolument rang\u00e9s sur la m\u00eame ligne au sein du bloc BAO, tout cela sous l&#8217;empire du Syst\u00e8me qui est en r\u00e9alit\u00e9 l&rsquo;expression ultime et compl\u00e8tement autonome de la modernit\u00e9 parvenue au bout de son voyage, affirmant sa surpuissance mais sombrant n\u00e9cessairement dans l&rsquo;autodestruction.<\/p>\n<\/p>\n<p><p>Les r\u00e9actions de nombre de commentateurs-Syst\u00e8me aux r\u00e9v\u00e9lations-Snowden (\u00e9coutes de divers chefs d&rsquo;&Eacute;tat notamment), en Europe, et <strong>particuli\u00e8rement<\/strong> en France, a \u00e9t\u00e9 une sorte de bouillie pour les chats dont le but est d&rsquo;exon\u00e9rer les USA, mais le Syst\u00e8me et la modernit\u00e9 en v\u00e9rit\u00e9, de toute responsabilit\u00e9 sp\u00e9cifique et exceptionnaliste qui pourrait exprimer un \u00e9tat psychologique singulier, &mdash; une <strong>pathologie<\/strong>, en un mot. La ligne des arguments extraits de cette bouillie a donc r\u00e9pondu \u00e0 deux lieux communs qui rel\u00e8vent du cynisme lorsqu&rsquo;il se fait d\u00e9guisement de la pauvret\u00e9 de l&rsquo;esprit et faux-nez du r\u00e9alisme, et qui se r\u00e9v\u00e8le comme une sorte de na\u00efvet\u00e9 invertie (par irr\u00e9flexion et inexp\u00e9rience) : \u00ab\u00a0Tout le monde espionne (a toujours espionn\u00e9) tout le monde\u00a0\u00bb, et \u00ab\u00a0Ces gens (les chefs d&rsquo;&Eacute;tat) savent tr\u00e8s bien qu&rsquo;ils sont espionn\u00e9s, leur indignation est forc\u00e9e\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Le cas fondamental n&rsquo;est pas de ce domaine, ces r\u00e9actions de banalisation de la crise Snowden\/NSA n&rsquo;\u00e9tant qu&rsquo;une sorte de r\u00e9flexe de d\u00e9flexion dont nous verrons plus loin ce que nous jugeons en \u00eatre les causes profondes. Le cas fondamental qui se manifeste est beaucoup plus simple ; il est celui de la signification <strong>profonde<\/strong> des actes de surveillance, d&rsquo;\u00e9coute et d&rsquo;espionnage de la NSA tels qu&rsquo;ils sont r\u00e9v\u00e9l\u00e9s \u00e0 une cadence diluvienne depuis le 6 juin 2013.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Le cas de la pathologie de la surveillance<\/h3>\n<\/p>\n<p><p>Il y a un excellent \u00e9ditorial de Paul Woodward, dans <em>War In Context<\/em>, ce <a class=\"gen\" href=\"http:\/\/warincontext.org\/2013\/10\/26\/the-american-pathology\/\">26 octobre 2013<\/a>. Woodward a bien vu que l&rsquo;acte en g\u00e9n\u00e9ral de la NSA n&rsquo;a rien \u00e0 voir avec la surveillance, l&rsquo;espionnage, la s\u00e9curit\u00e9 nationale en tant que domaines techniques et politiques courants. C&rsquo;est une pathologie de l&rsquo;am\u00e9ricanisme, et l&rsquo;on verra bien, dans ce texte, combien les termes psychologiques abondent et nullement les termes techniques inh\u00e9rents \u00e0 l&rsquo;activit\u00e9 du renseignement \u00e9lectronique. L&rsquo;\u00e9vidence est d&rsquo;ailleurs clairement exprim\u00e9e : ce fait m\u00eame, mis en avant par le syst\u00e8me de la communication parce qu&rsquo;\u00e0 la fois sensationnel (du mot \u00ab\u00a0sensation\u00a0\u00bb) et symbolique, des \u00e9coutes directes d&rsquo;une Merkel et de divers autres chefs d&rsquo;Etat n&rsquo;a rien \u00e0 voir avec l&rsquo;efficacit\u00e9. Le r\u00e9sultat de ces \u00e9coutes est sans aucun doute d&rsquo;un pi\u00e8tre int\u00e9r\u00eat du point de vue du renseignement ; mais la cause en est une obsession, un d\u00e9s\u00e9quilibre psychologique, &ndash; bref, les marques de la pathologie dont on parle.<\/p>\n<\/p>\n<p><p>&laquo;<em>Matthew Aid, an intelligence historian and expert on the NSA, says: \u00ab\u00a0I think most of us who have studied U.S. intelligence over the years naturally assume that there is no country on the face of the planet who does not receive some level of attention from the U.S. intelligence community. We have to because we are one of the few global superpowers left on the planet.\u00a0\u00bb Aid says this in conjunction with a hint of incredulity about the current expressions of shock and indignation being expressed by America&rsquo;s allies who object to being spied upon.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>While the expressions of shock coming from Europe and elsewhere may indeed be contrived, the indignation is not, and this distinction is one that many Americans fail to grasp. Once again, American exceptionalism rears its ugly head and once again Americans fail to recognize its ugliness.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>America<\/em> <strong><em>has to<\/em><\/strong> <em>spy on its allies. Why? Because the prevailing attitude in this country &mdash; the American outlook &mdash; is that on a fundamental level, American interests differ from the interests of everyone else on the planet. This is a form of insanity, but insanity is difficult to recognize when it gets expressed collectively. When virtually everyone suffers from similar delusions, then crazy becomes normal.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>In order to plausibly justify bugging the mobile phone of German Chancellor Angela Merkel or that of any of the U.S.&rsquo;s other close allies, one would have to show how the benefits of doing so, outweigh the potential costs. In reality, the benefits are negligible to non-existent while the costs may prove enormous. The argument that \u00ab\u00a0everyone does it\u00a0\u00bb simply doesn&rsquo;t wash. Who has bugged President Obama&rsquo;s Blackberry? Let&rsquo;s suppose that France succeeded in doing so. What&rsquo;s America&rsquo;s response going to be? \u00ab\u00a0Fair game. Everyone does it.\u00a0\u00bb I don&rsquo;t think so.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>But returning to the idea that the diplomatic crisis in which the U.S. is now embroiled is symptomatic of an American disease, the primary symptom which finds countless expressions is the idea that \u00ab\u00a0because we are Americans\u00a0\u00bb is a coherent and rational explanation for anything. The idea that Americans are in some way intrinsically different from everyone else is baseless yet functions as a presupposition guiding so many of America&rsquo;s actions.<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo;<em>The ultimate irony is this: America&rsquo;s \u00ab\u00a0need\u00a0\u00bb to spy on the world is a byproduct of a lack of curiosity about the rest of the world. Americans fear what they don&rsquo;t understand&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Le cas de la pathologie de la surveillance (suite)<\/h3>\n<\/p>\n<p><p>Cette pathologie de la surveillance doit \u00eatre consid\u00e9r\u00e9e \u00e9galement dans sa totalit\u00e9, aussi bien vis-\u00e0-vis de l&rsquo;ext\u00e9rieur que les USA \u00ab\u00a0craignent parce qu&rsquo;ils ne le comprennent pas\u00a0\u00bb, que vis-\u00e0-vis de l&rsquo;int\u00e9rieur (les citoyens) que l&rsquo;am\u00e9ricanisme \u00ab\u00a0craint parce qu&rsquo;il ne les comprend pas\u00a0\u00bb. La surveillance, on le sait, est largement d\u00e9velopp\u00e9e au niveau int\u00e9rieur, et objet d&rsquo;un d\u00e9bat tr\u00e8s vif, et d&rsquo;une crise en v\u00e9rit\u00e9, un des nombreux produits de la crise Snowden\/NSA. Cet aspect (la surveillance) est compl\u00e9t\u00e9 par le volet de l&#8217;emprisonnement, qui est une forme maximale de surveillance allant jusqu&rsquo;\u00e0 la liquidation.<\/p>\n<\/p>\n<p><p>L\u00e0-dessus, on peut, on <strong>doit parler<\/strong> de ce <em>goulag<\/em> am\u00e9ricaniste qui d\u00e9passe, en efficacit\u00e9, en continuit\u00e9, en structuration et en banalisation (jusqu&rsquo;\u00e0 l&rsquo;int\u00e9grer dans la vie courante sans n\u00e9cessit\u00e9 de terreur polici\u00e8re), le <em>goulag<\/em> Stalinien. Un rappel n&rsquo;est pas d\u00e9plac\u00e9, de notre texte du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-les_prisons_us_en_2012_pire_que_le_goulag_et_l_esclavage_26_01_2012.html\">26 janvier 2012<\/a>, qui reprenait des extraits du texte de Adam Gopnik, dans le <em>New Yorker<\/em> pr\u00e9-dat\u00e9 du <a class=\"gen\" href=\"http:\/\/www.newyorker.com\/arts\/critics\/atlarge\/2012\/01\/30\/120130crat_atlarge_gopnik?printable=true%A4tPage=all#ixzz1kUfhE92i\">30 janvier 2012<\/a>. On peut relire ces extraits en ayant \u00e0 l&rsquo;esprit l&rsquo;interpr\u00e9tation que nous donnons ici d&rsquo;une manifestation de cette pathologie de l&rsquo;am\u00e9ricanisme, \u00e0 la fois de la m\u00e9connaissance, de la peur et de la haine \u00ab\u00a0de l&rsquo;autre\u00a0\u00bb pouss\u00e9e jusqu&rsquo;\u00e0 l&rsquo;absurde de ses propres citoyens, &ndash; donc de leur n\u00e9cessaire surveillance, <strong>par tous les moyens possibles<\/strong>, des plus <em>soft<\/em> et <em>stealthy<\/em> jusqu&rsquo;aux plus brutaux et barbares.<\/p>\n<\/p>\n<p><p>&laquo;<em>For most privileged, professional people, the experience of confinement is a mere brush, encountered after a kid&rsquo;s arrest, say. For a great many poor people in America, particularly poor black men, prison is a destination that braids through an ordinary life, much as high school and college do for rich white ones. More than half of all black men without a high-school diploma go to prison at some time in their lives. Mass incarceration on a scale almost unexampled in human history is a fundamental fact of our country today&mdash;perhaps<\/em> <strong><em>the<\/em><\/strong> <em>fundamental fact, as slavery was the fundamental fact of 1850. In truth, there are more black men in the grip of the criminal-justice system&mdash;in prison, on probation, or on parole&mdash;than were in slavery then. Over all, there are now more people under \u00ab\u00a0correctional supervision\u00a0\u00bb in America&mdash;more than six million&mdash;than were in the Gulag Archipelago under Stalin at its height. That city of the confined and the controlled, Lockuptown, is now the second largest in the United States.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>The accelerating rate of incarceration over the past few decades is just as startling as the number of people jailed: in 1980, there were about two hundred and twenty people incarcerated for every hundred thousand Americans; by 2010, the number had more than tripled, to seven hundred and thirty-one. No other country even approaches that. In the past two decades, the money that states spend on prisons has risen at six times the rate of spending on higher education. Ours is, bottom to top, a \u00ab\u00a0carceral state,\u00a0\u00bb in the flat verdict of Conrad Black, the former conservative press lord and newly minted reformer, who right now finds himself imprisoned in Florida, thereby adding a new twist to an old joke: A conservative is a liberal who&rsquo;s been mugged; a liberal is a conservative who&rsquo;s been indicted; and a passionate prison reformer is a conservative who&rsquo;s in one.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>The scale and the brutality of our prisons are the moral scandal of American life&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Le cas de Tocqueville \u00e0 la d\u00e9couverte de l&rsquo;Am\u00e9rique<\/h3>\n<\/p>\n<p><p>Ces constats ne sont pas nouveaux. Ils pars\u00e8ment les r\u00e9flexions de Tocqueville visitant l&rsquo;Am\u00e9rique en 1831, et rassemblant son mat\u00e9riel d&rsquo;information et de commentaire qui nourrirait son &oelig;uvre-maitresse <em>De la d\u00e9mocratie en Am\u00e9rique<\/em>. Pendant ce long s\u00e9jour de plusieurs mois, Tocqueville s&rsquo;int\u00e9ressa particuli\u00e8rement au syst\u00e8me carc\u00e9ral US, qui constituait d&rsquo;ailleurs l&rsquo;objet officiel de sa visite. Il nota l&rsquo;organisation remarquable de ce syst\u00e8me, jusqu&rsquo;\u00e0 des exp\u00e9riences de \u00ab\u00a0prisons sans barreaux\u00a0\u00bb, o&ugrave; la d\u00e9lation, la surveillance y compris entre d\u00e9tenus, tenaient lieu de barreaux plus solides que des vrais. Cela resta au niveau de l&rsquo;exp\u00e9rience parce que, par atavisme et v\u00e9n\u00e9ration de la puissance, le Syst\u00e8me fait tout de m\u00eame plus confiance au <em>knout<\/em> qu&rsquo;\u00e0 la subtilit\u00e9 des man&oelig;uvres habiles.<\/p>\n<\/p>\n<p><p>Par ailleurs, il y eut, dans des notes prises de sa d\u00e9couverte de l&rsquo;Am\u00e9rique, celui de <em>Voyage en Am\u00e9rique<\/em>, lors de ce p\u00e9riple de 1831, des observations int\u00e9ressantes d&rsquo;une facture plus g\u00e9n\u00e9rale du m\u00eame Tocqueville. Elles marquaient ce que nommions le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_fragilite_extreme_de_l_amerique_05_02_2009.html\">5 f\u00e9vrier 2009<\/a>, &laquo;<em>La fragilit\u00e9 extr\u00eame de l&rsquo;Am\u00e9rique<\/em>&raquo;. Il s&rsquo;agit de deux citations extraites des <em>&OElig;uvres<\/em> (I) de Tocqueville, dans la Pl\u00e9iade. (Les mots soulign\u00e9s en gras le sont par l&rsquo;auteur lui-m\u00eame.)<\/p>\n<\/p>\n<p><p>&bull; Sing Sing, 29 mai 1831. &laquo;<em>Le principe des r\u00e9publiques anciennes \u00e9tait le sacrifice de l&rsquo;int\u00e9r\u00eat particulier au bien g\u00e9n\u00e9ral, dans ce sens on peut dire qu&rsquo;elles \u00e9taient<\/em> <strong><em>vertueuses<\/em><\/strong>. <em>Le principe de celle-ci me para&icirc;t \u00eatre de faire rentrer l&rsquo;int\u00e9r\u00eat particulier dans l&rsquo;int\u00e9r\u00eat g\u00e9n\u00e9ral. Une sorte d&rsquo;\u00e9go\u00efsme raffin\u00e9 et intelligent semble le pivot sur lequel roule toute la machine. Ces gens-ci ne s&#8217;embarrassent pas \u00e0 rechercher si la vertu publique est bonne, mais ils pr\u00e9tendent prouver qu&rsquo;elle est utile. Si ce dernier point est vrai, comme je le pense en partie, cette soci\u00e9t\u00e9 peut passer pour \u00e9clair\u00e9e mais non vertueuse. Mais jusqu&rsquo;\u00e0 quel degr\u00e9 les deux principes du bien individuel et du bien g\u00e9n\u00e9ral peuvent-ils en effet se confondre? Jusqu&rsquo;\u00e0 quel point une conscience qu&rsquo;on pourrait appeler de r\u00e9flexion et de calcul pourra-t-elle ma&icirc;triser les passions politiques qui ne sont pas encore n\u00e9es, mais qui ne manqueront pas de na&icirc;tre? C&rsquo;est ce que l&rsquo;avenir seul nous montrera.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>&bull; Sing Sing, 1er juin 1831. &laquo;<em>Quand on r\u00e9fl\u00e9chit \u00e0 la nature de cette soci\u00e9t\u00e9-ci, on voit jusqu&rsquo;\u00e0 un certain point l&rsquo;explication de ce qui pr\u00e9c\u00e8de: la soci\u00e9t\u00e9 am\u00e9ricaine est compos\u00e9e de mille \u00e9l\u00e9ments divers nouvellement rassembl\u00e9s. Les hommes qui vivent sous ses lois sont encore anglais, fran\u00e7ais, allemands, hollandais. Ils n&rsquo;ont ni religion, ni m&oelig;urs, ni id\u00e9es communes; jusqu&rsquo;\u00e0 pr\u00e9sent on ne peut dire qu&rsquo;il y ait un caract\u00e8re am\u00e9ricain \u00e0 moins que ce soit celui de n&rsquo;en point avoir. Il n&rsquo;existe point ici de souvenirs communs, d&rsquo;attachements nationaux. Quel peut donc \u00eatre le seul lien qui unisse les diff\u00e9rentes parties de ce vaste corps?<\/em> <strong><em>L&rsquo;int\u00e9r\u00eat.<\/em><\/strong>&raquo;<\/p>\n<\/p>\n<p><p>Ces notes permettent de dresser un \u00e9tat des lieux de l&rsquo;Am\u00e9rique qui, contrairement aux supputations logiques de l&rsquo;auteur, n&rsquo;a pas chang\u00e9. Il s&rsquo;agit d&rsquo;un immense pays sans &Eacute;tat au sens r\u00e9galien du terme, o&ugrave; effectivement le bien public n&rsquo;est qu&rsquo;un arrangement commun pour favoriser le bien priv\u00e9 et rien d&rsquo;autre, o&ugrave; le principal r\u00e9sultat de la grande guerre lib\u00e9ratrice et \u00e9mancipatrice (la Guerre de S\u00e9cession) fut principalement de pulv\u00e9riser les derniers obstacles pour le d\u00e9cha&icirc;nement d&rsquo;un \u00ab\u00a0capitalisme sauvage\u00a0\u00bb sans exemple (le <em>Gilded Age<\/em>, ou \u00ab\u00a0&Acirc;ge du toc\u00a0\u00bb, entre 1865 et 1890)&#8230; Ce cadre-l\u00e0, extr\u00eamement puissant pour les fortunes, mais extr\u00eamement fragile pour la coh\u00e9sion nationale, n\u00e9cessita toujours, d&rsquo;une part une formidable action de communication dans la cr\u00e9ation et la promotion forcen\u00e9e de symboles fictifs et de <em>narrative<\/em> (les USA, <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-l_empire_de_la_communication_25_11_1999.html\">empire de la communication<\/a>), d&rsquo;autre part une obsession effectivement devenue pathologique de la surveillance selon les r\u00e9f\u00e9rences d&rsquo;un conformisme de fer, d\u00e9bouchant sur une recherche pathologique de toutes les d\u00e9viance imaginables, y compris et prioritairement celles des dissidents et, en g\u00e9n\u00e9ral, des libres esprits.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Le cas de la France-poire face \u00e0 l&rsquo;Am\u00e9rique<\/h3>\n<\/p>\n<p><p>Tocqueville vivait \u00e0 l&rsquo;\u00e9poque du roi-poire (Louis-Philippe), comme nous vivons \u00e0 l&rsquo;\u00e9poque du pr\u00e9sident-poire. (Il y a une troublante co\u00efncidence-poire entre cette partie du XIX\u00e8me et notre partie actuelle du XXI\u00e8me.) Cette \u00e9poque louis-philipparde marquait parfaitement les deux extr\u00eames de l&rsquo;attitude de la France vis-\u00e0-vis des USA : \u00e0 la fois un proam\u00e9ricanisme jusqu&rsquo;\u00e0 l&rsquo;identification, des exclamations de madame <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-ullman-diog_ne_cherche_un_leadership_26_10_2013.html\">de Sta\u00ebl<\/a> \u00e0 la popularit\u00e9 de Fenimore Cooper ou de Benjamin Franklin en France, au d\u00e9veloppement du <em>business<\/em> \u00e0 l&rsquo;am\u00e9ricaine ; \u00e0 la fois un antiam\u00e9ricanisme radical dont la France fut la pionni\u00e8re, de Stendhal \u00e0 Baudelaire et \u00e0 tant d&rsquo;autres. (Pour une documentation et une r\u00e9flexion sur ces \u00e9tranges et fascinants rapports entre la France et les USA, voir les deuxi\u00e8me et troisi\u00e8me Parties du premier tome de <em>La Gr\u00e2ce de l&rsquo;Histoire<\/em>, le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-deuxieme_partie_le_reve_americain_et_vice-versa_03_04_2010.html\">3 avril 2010<\/a> [&laquo;<em>Le r\u00eave am\u00e9ricain et vice-versa<\/em>&raquo;] et le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-troisieme_partie_1919-1933_du_reve_americain_a_l_american_dream_16_05_2010.html\">16 mai 2010<\/a> [&laquo;<em>1919-1933, du r\u00eave am\u00e9ricain \u00e0 l&rsquo;American Dream<\/em>&raquo;].)<\/p>\n<\/p>\n<p><p>Aujourd&rsquo;hui, on retrouve ces m\u00eames attitudes, transmut\u00e9es selon les facteurs du temps. Comme il n&rsquo;y a pas d&rsquo;antiam\u00e9ricanisme plus virulent en France (m\u00eame si inexprim\u00e9 en tant que tel), de De Gaulle \u00e0 de Villepin, \u00e0 Le Pen-M\u00e9lanchon (m\u00eame combat de ce point de vue, quoi qu&rsquo;ils en veuillent !), il n&rsquo;y a pas de proam\u00e9ricanisme plus fort que l&rsquo;actuel soutien-Syst\u00e8me de la direction fran\u00e7aise et du parti des salonards parisien aux USA, avec pour le cas qui nous occupe un r\u00e9flexe pavlovien de banalisation des actes de la NSA (\u00ab\u00a0tout le monde espionne&#8230;\u00a0\u00bb, bla bla bla), la coop\u00e9ration militaire avec les USA, l&rsquo;<em>obamania<\/em> courante (BHO, &laquo;<em>la \u00ab\u00a0cooltitude\u00a0\u00bb absolue<\/em>&raquo;, selon le philosophe-pr\u00e9sentateur du <em>Grand Journal<\/em>, et parfaitement innocent et brave gar\u00e7on, Antoine de Caunes).<\/p>\n<\/p>\n<p><p>Cette attitude vient du fait que, pour la France, et cela d\u00e8s 1775-1776, avant m\u00eame qu&rsquo;elle existe, l&rsquo;Am\u00e9rique-en-devenir <strong>a \u00e9t\u00e9<\/strong> la modernit\u00e9 m\u00eame que la France pr\u00e9parait par ailleurs avec les Lumi\u00e8res, et cela malgr\u00e9 tous les signes contraires. (Voir <em>From Dawn to Decadence &mdash; 500 Years of Western Cultural Life<\/em>, de <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-jacques_barzun_le_vrai_american_dream_l_american_dream_destine_a_etre_fracasse_03_04_2006.html\">Jacques Barzun<\/a> : &laquo;<em>If anything, the aim of the american War of Independance was reactionary : \u00ab\u00a0back to the good old days!\u00a0\u00bb Taxpayers, assemblymen, traders, and householders wanted a return to the conditions before the latter-day English policies. The appeal was to the immemorial rights of Englishmen: self governments through representatives and taxation granted by local assemblies, not set arbitrarily by the king. No new Idea entailing a shift in forms of power &mdash; the marks of revolutions &mdash; was proclaimed. The 28 offenses that King George was accused of had long been familiar in England. The language of the Declaration is that of a protest against abuses of power, not of proposals for recasting the government on new principles.<\/em>&raquo;)<\/p>\n<\/p>\n<p><p>Face \u00e0 l&rsquo;Am\u00e9rique-qui-est-la modernit\u00e9, la France entretient donc son attitude originelle, absolument contradictoire et extr\u00e9miste dans les deux sens, qu&rsquo;elle a vis-\u00e0-vis de la modernit\u00e9 : \u00e0 la fois cr\u00e9atrice de la modernit\u00e9 (Les Lumi\u00e8res, la R\u00e9volution, l&rsquo;universalisme moderniste), \u00e0 la fois d\u00e9nonciatrice de la modernit\u00e9 (les antimodernes, la structuration de la Tradition gr\u00e2ce \u00e0 ses politiques principielles, ses principes de souverainet\u00e9 et de l\u00e9gitimit\u00e9, la d\u00e9nonciation du nivellement dissolvant de la d\u00e9mocratie, etc.) ; \u00e0 la fois matrice en partie du \u00ab\u00a0<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_d_cha_nement_de_la_mati_re__05_11_2012.html\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a>\u00a0\u00bb (la R\u00e9volution) et adversaire la plus acharn\u00e9e des cons\u00e9quences de ce d\u00e9cha&icirc;nement. Ce parcours chaotique d&rsquo;une France cr\u00e9atrice de la modernit\u00e9 et adversaire f\u00e9roce de la modernit\u00e9 se ressent n\u00e9cessairement par des attitudes extr\u00eames, aujourd&rsquo;hui dans une phase de proam\u00e9ricanisme qui institue une sorte de \u00ab\u00a0plus am\u00e9ricaniste que l&rsquo;am\u00e9ricanisme\u00a0\u00bb. Par ailleurs, il faut d\u00e9fendre les \u00ab\u00a0valeurs\u00a0\u00bb qui sous-tendent ce \u00ab\u00a0plus am\u00e9ricaniste que l&rsquo;am\u00e9ricanisme\u00a0\u00bb, et cela au risque, dans une \u00e9poque extr\u00eame o&ugrave; les masques tombent plus qu&rsquo;ils ne dissimulent, de devoir d\u00e9noncer l&rsquo;am\u00e9ricanisme qui est le simulacre d\u00e8s l&rsquo;origine que d\u00e9finit Barzun cit\u00e9 plus haut.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Le cas de la crise NSA\/Snowden devenue \u00ab\u00a0crise premi\u00e8re\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>Tout cela mesure l&rsquo;importance <strong>fondamentale<\/strong> de la crise Snowden\/NSA qui n&rsquo;a rien \u00e0 voir avec une crise type-journalisme-Syst\u00e8me (\u00ab\u00a0tout le monde espionne&#8230;\u00a0\u00bb, bla bla bla). Comme on le sait \u00e0 la lecture de divers commentaires et analyses sur ce site, nous investissons la crise Snowden\/NSA d&rsquo;une importance sp\u00e9cifique exceptionnelle. Nous la consid\u00e9rons comme investie du qualificatif de \u00ab\u00a0<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-choisir_sa_crise_22_07_2013.html\">crise premi\u00e8re<\/a>\u00a0\u00bb dans l&rsquo;ordre d&rsquo;importance des crises et certainement devenue la plus motrice et la plus centrale de la crise g\u00e9n\u00e9rale d&rsquo;effondrement du Syst\u00e8me, ou <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_crise_haute_ddecrisis_20_02_2012.html\">crise haute<\/a>. Nous avons act\u00e9 cette \u00e9volution, en diverses \u00e9tapes, notamment&#8230;<\/p>\n<\/p>\n<p><p>&bull; Le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_au_moins_trois_crises_et_leurs_intimes_connexions_17_06_2013.html\">17 juin 2013<\/a> : &laquo;<em>Il reste le fait, relativement nouveau mais de plus en plus av\u00e9r\u00e9, que PRISM\/NSA\/Snowdon se divise en deux pour ses effets, &ndash; donc devient<\/em> <strong><em>au moins deux crises<\/em><\/strong>. <em>D&rsquo;une part, un effet int\u00e9rieur direct&#8230;<\/em> [&#8230;] <em>D&rsquo;autre part, un effet ext\u00e9rieur presque direct&#8230;<\/em> [&#8230;] <em>avec ce que pourrait, ce que devrait \u00eatre la r\u00e9action chinoise, puis accompagn\u00e9e de la r\u00e9action russe, avec leurs effets directs de tension avec le bloc BAO.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>C&rsquo;est une situation tourbillonnante, \u00e0 la fois dans la manufacture et le d\u00e9veloppement de la crise PRISM\/NSA\/Snowdon, \u00e0 la fois dans les rapports et les connexions de cette crise avec les crises existantes, ou avec de nouvelles crises en formation. D&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale dans la s\u00e9quence actuelle, on voit qu&rsquo;un lien de plus en plus ferme est \u00e9tabli entre les diverses crises, actives ou en gestation. Cela tend \u00e0 offrir la perspective d&rsquo;un \u00e9largissement de la notion de crise haute&#8230; <\/em><\/p>\n<\/p>\n<p><p>&bull; Le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-choisir_sa_crise_22_07_2013.html\">22 juillet 2013<\/a>, nous observions la transformation de la crise en \u00ab\u00a0crise premi\u00e8re\u00a0\u00bb. La crise Snowden\/NSA &laquo;<em>se suffit \u00e0 elle-m\u00eame, \u00e0 partir d&rsquo;\u00e9l\u00e9ments existants a priori stables avant que la crise n&rsquo;\u00e9clate (existence de Snowden, existence de Greenwald, existence de la NSA, existence des programmes de la NSA, etc.) ; elle porte en elle-m\u00eame les conditions de son \u00e9ruption, de son d\u00e9veloppement, de son imbrication dans l&rsquo;infrastructure crisique ; elle suscite par elle-m\u00eame, par effets directs et indirects, une multitude de d\u00e9stabilisations qui n&rsquo;ont aucun besoin de manipulations externes mais d\u00e9pendent simplement d&rsquo;encha&icirc;nements \u00e9v\u00e9nementiels et psychologiques. Il s&rsquo;agit donc d&rsquo;une crise \u00ab\u00a0pure au premier degr\u00e9\u00a0\u00bb (\u00ab\u00a0crise premi\u00e8re\u00a0\u00bb).<\/em> [&#8230;] <em>La crise Snowden, en tant que \u00ab\u00a0crise premi\u00e8re\u00a0\u00bb, est un choix \u00e9vident, &ndash; et l\u00e0, on se moque bien de savoir s&rsquo;il y a montage, manipulation, etc., toutes choses qui doivent \u00eatre \u00e9limin\u00e9es, \u00e9galement par la tactique-strat\u00e9gie de l&rsquo;inconnaissance, comme autant d&rsquo;obstacles de diversion et d&rsquo;atomisation par cloisonnement de l&rsquo;essentiel dress\u00e9s par le Syst\u00e8me.<\/em> [&#8230;] <em>Il s&rsquo;agit de laisser l&rsquo;accessoire de l&rsquo;enqu\u00eate sur la v\u00e9racit\u00e9 d\u00e9risoire des faits accessoires, pour embrasser l&rsquo;essentiel du destin que produit cette crise.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Ce classement est bien entendu d&ucirc; \u00e0 l&rsquo;exceptionnelle \u00ab\u00a0op\u00e9rationnalit\u00e9\u00a0\u00bb de cette crise, qui fait 1) qu&rsquo;elle touche tous les domaines essentiels, int\u00e9rieur aux USA, ext\u00e9rieur aux USA, au c&oelig;ur de bloc BAO, 2) qu&rsquo;elle produit constamment d&rsquo;autres crises, 3) qu&rsquo;elle est quasiment sans fin et compl\u00e8tement impr\u00e9visible \u00e0 cause de la forme d&rsquo;intervention de ses animateurs Snowden-Greenwald, 4) qu&rsquo;elle touche le c&oelig;ur du Syst\u00e8me dans le chef d&rsquo;une des organisations essentielles de ce Syst\u00e8me. Mais il est d&ucirc; aussi, ce classement, \u00e0 ce que nous d\u00e9taillons en priorit\u00e9, qui est les pathologies de l&rsquo;am\u00e9ricanisme et, par cons\u00e9quent, les pathologies de la modernit\u00e9. Sa position au c&oelig;ur de la crise d&rsquo;effondrement du Syst\u00e8me n&rsquo;est en rien usurp\u00e9e. La crise Snowden\/USA est aujourd&rsquo;hui tr\u00e8s largement plus importante que la crise de l&rsquo;effondrement du syst\u00e8me financier de l&rsquo;automne 2008, elle lui est <strong>d&rsquo;une nature sup\u00e9rieure<\/strong>.<\/p>\n<\/p>\n<p><p>&#8230; Enfin, elle <strong>s&rsquo;est constitu\u00e9e<\/strong> d&rsquo;autorit\u00e9 comme la manifestation principale de la crise d&rsquo;effondrement du Syst\u00e8me, puisqu&rsquo;elle se manifeste au c&oelig;ur du Syst\u00e8me.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Le cas des \u00e9coutes t\u00e9l\u00e9phoniques de Merkel<\/h3>\n<\/p>\n<p><p>Effectivement, Snowden\/NSA comme crise du Syst\u00e8me, d\u00e9couvrant combien la NSA, organisation arch\u00e9typique du Syst\u00e8me, est un artefact, une entit\u00e9, voire une \u00e9gr\u00e9gore, compl\u00e8tement insaisissable et hors de tout contr\u00f4le possible, dot\u00e9 de capacit\u00e9s autonomes d&rsquo;action, mettant les <em>sapiens<\/em>, y compris le <em>sapiens<\/em>-POTUS et sa &laquo;<em>\u00ab\u00a0cooltitude\u00a0\u00bb absolue<\/em>&raquo;, devant des faits tr\u00e8s largement accomplis, et depuis des lustres&#8230; On revient ici au texte de Woodward, vu en t\u00eate de cette analyse, qui nous donne quelques indications de plus permettant de consolider ce th\u00e8me largement substantiv\u00e9.<\/p>\n<\/p>\n<p><p>&laquo;<em>In an op-ed at USA Today, Lisa Monaco, President Obama&rsquo;s assistant for homeland security and counterterrorism, notes that the administration is currently reviewing U.S. surveillance capabilities, including with respect to foreign partners. \u00ab\u00a0We want to ensure we are collecting information because we need it and not just because we can.\u00a0\u00bb The New York Times reports that the tapping of Merkel&rsquo;s phone began a decade ago but that during his five years as president, Obama had no knowledge of this. The same report also says: \u00ab\u00a0In Washington, the reaction<\/em> [<em>from Europe<\/em>] <em>has set off a debate over whether it is time to put the brakes on the NSA, whose capabilities, Mr. Obama has hinted, have expanded faster than its judgment.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>A much more pointed response is reported coming from Germany: So fierce was the anger in Berlin over suspicions that American intelligence had tapped into Ms. Merkel&rsquo;s cellphone that Elmar Brok of Germany, the chairman of the European Parliament&rsquo;s foreign affairs committee and a pillar of trans-Atlantic exchanges since 1984, spoke Friday of America&rsquo;s security establishment as a creepy \u00ab\u00a0state within a state.\u00a0\u00bb<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo;<em>&#8230;But the real issue is not technological; it is political. For the NSA to be spying on the German chancellor while the U.S. president knows nothing about it, shows that the NSA has become a rogue operation.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>(Hier, le quotidien allemand <em>Bild<\/em> publiait des \u00ab\u00a0r\u00e9v\u00e9lations\u00a0\u00bb selon lesquelles Obama avait \u00e9t\u00e9 mis au courant par la NSA des \u00e9coutes de Merkel depuis 2010. [Voir le <em>Guardian<\/em> du <a class=\"gen\" href=\"http:\/\/www.theguardian.com\/world\/2013\/oct\/27\/barack-obama-nsa-angela-merkel-germany\">27 octobre 2013<\/a>.] La source est un \u00ab\u00a0officiel de la NSA\u00a0\u00bb, ce qui nous fait sortir du domaine Snowden et devrait nous appara&icirc;tre comme une indication bien significative d&rsquo;un affrontement en train de prendre forme entre la NSA et la Maison-Blanche. Bob Woodward notait le m\u00eame <a class=\"gen\" href=\"http:\/\/warincontext.org\/2013\/10\/27\/obama-lied-to-merkel-when-claiming-to-know-nothing-about-nsa-bugging-her-phone-says-new-report\/\">27 octobre 2013<\/a> : &laquo;<em>Bild is a tabloid that does not have a reputation for journalistic excellence. Even so, if a conflict between the NSA and the White House is escalating, then an NSA source might turn to this type of publication as a way of making a veiled threat. The report has the effect of sowing doubt about Obama&rsquo;s statements even if NSA officials now make dismissive responses, pointing out the unreliability of the press.<\/em>&raquo;)<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Le cas de l&rsquo;acte du Syst\u00e8me seul<\/h3>\n<\/p>\n<p><p>Le constat \u00e0 ce point est qu&rsquo;il appara&icirc;t de plus en plus difficile que les USA continuent \u00e0 assurer l&rsquo;activit\u00e9 de la NSA comme ils l&rsquo;ont fait jusqu&rsquo;ici, au constat des d\u00e9g\u00e2ts diplomatiques et d&rsquo;influence extraordinaires d\u00e9j\u00e0 caus\u00e9s et qui ne vont faire que s&rsquo;amplifier. C&rsquo;est l&rsquo;observation du directeur de l&rsquo;<em>Open Technology Institute<\/em>, Sascha Meinrath (le <a class=\"gen\" href=\"http:\/\/rt.com\/op-edge\/us-lost-internet-credibility-580\/\">23 octobre 2013<\/a>, interview de <em>Russia Today<\/em>) : &laquo;<em>It is clear that what the US has been doing is not sustainable over time. This has created a massive reputational crisis for the US&#8230;<\/em>&raquo; La question \u00e0 ce point devient alors, en fonction de ce que Woodward remarquait ci-dessus, et que nous ne cessons d&rsquo;observer, celle de la NSA comme entit\u00e9 quasiment autonome.<\/p>\n<\/p>\n<p><p>Dans le <em>Guardian<\/em> du <a class=\"gen\" href=\"http:\/\/www.theguardian.com\/commentisfree\/2013\/oct\/21\/general-alexander-obama-split-nsa\">22 octobre 2013<\/a>, Marcy Wheeler \u00e9crivait que le d\u00e9part d&rsquo;Alexander en avril 2014 cr\u00e9ait une opportunit\u00e9 d&rsquo;une r\u00e9forme structurelle de la NSA (&laquo;<em>But now, with the need to replace Alexander, Obama has an opportunity to consider defense over \u00ab\u00a0big data\u00a0\u00bb. At the very least, Obama should consider breaking out the NSA&rsquo;s defensive and offensive functions to create competing champions, one fighting to create holes, and one fighting to plug them&#8230;<\/em>&raquo;, &ndash; encore, cette recommandation prend-elle en compte le seul concept de l&rsquo;efficacit\u00e9). Des lois de r\u00e9forme structurelle sont en cours d&rsquo;\u00e9laboration au Congr\u00e8s \u00e9galement (Voir <em>End of The Lie<\/em> du <a class=\"gen\" href=\"http:\/\/EndtheLie.com\/2013\/09\/26\/bipartisan-group-of-senators-introduces-new-intelligence-reform-bill-to-limit-nsa-surveillance-powers\/#axzz2iwjciBKn\">26 septembre 2013<\/a>)&#8230;<\/p>\n<\/p>\n<p><p>Pour autant, la question reste enti\u00e8rement pos\u00e9e de savoir si de telles actions sont possibles, si la p\u00e9n\u00e9tration de l&rsquo;ext\u00e9rieur et la d\u00e9structuration du monstre-NSA est possible. Dans <em>JFK &#038; l&rsquo;Indicible<\/em>, qui vient de para&icirc;tre (Demi-Lune, septembre 2013), James W. Douglass rappelle qu&rsquo;apr\u00e8s avoir \u00e9t\u00e9 inform\u00e9 du d\u00e9sastre de la Baie des Cochons d&rsquo;avril 1961, Kennedy confia \u00e0 un de ses conseillers &laquo;<em>Il faut r\u00e9duire la CIA en miettes et les disperser aux quatre vents<\/em>&raquo;, observation qu&rsquo;il poursuivit apr\u00e8s la crise des missiles de Cuba en octobre 1962, confiant \u00e0 Arthur Schlesinger : &laquo;<em>C&rsquo;est la croix et la banni\u00e8re pour savoir ce qui se trame mais j&rsquo;ai retenu une chose de cette affaire, c&rsquo;est que nous allons devoir nous occuper de la CIA.<\/em> [&#8230;] <em>Personne ne s&rsquo;en est jamais occup\u00e9.<\/em>&raquo; On conna&icirc;t la suite (et encore ne voulons-nous parler ici que du destin de la CIA, sans autre sp\u00e9culation).<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Le cas de la continuit\u00e9 de la crise<\/h3>\n<\/p>\n<p><p>Mais il se fait que nous ne sommes plus en 1961-1963&#8230; L&rsquo;\u00e9poque est <strong>totalement diff\u00e9rente<\/strong>, quasiment un nouveau monde et une \u00ab\u00a0\u00e9poque maistrienne\u00a0\u00bb o&ugrave; les \u00e9v\u00e9nements eux-m\u00eames ont pris le pas sur les impulsions d\u00e9sormais insignifiantes et <em>irrelevent<\/em> des directions-<em>sapiens<\/em>, fussent-elles acquises au Syst\u00e8me comme c&rsquo;est le cas en g\u00e9n\u00e9ral.<\/p>\n<\/p>\n<p><p>Un projet plus ou moins ficel\u00e9 au sommet de l&rsquo;UE est donc d&rsquo;\u00e9tablir une commission USA-Europe, pour r\u00e9diger une sorte de <em>modus vivendi<\/em> de non-espionnage r\u00e9ciproque, \u00ab\u00a0pour r\u00e9tablir la confiance dans les relations transatlantiques et m\u00eame les am\u00e9liorer\u00a0\u00bb comme dit \u00e0 peu pr\u00e8s le pr\u00e9sident-poire avec sa pens\u00e9e fulgurante. Cette sorte de v&oelig;u conforme \u00e0 la bienpensance-Syst\u00e8me est touchant par le vide qui l&rsquo;habite, et par sa langue de bois presque \u00e9mouvante \u00e0 force de na\u00efvet\u00e9. Les esprits forts, eux, ceux qui pensent que \u00ab\u00a0tout le monde espionne tout le monde\u00a0\u00bb selon une pens\u00e9e qui est une variation sur le m\u00eame th\u00e8me de la bienpensance-Syst\u00e8me, songent aussit\u00f4t \u00e0 l'\u00a0\u00bbencommisionnement\u00a0\u00bb ; une commission qui ne d\u00e9cidera rien en laissant croire qu&rsquo;on d\u00e9cide quelque chose, et en neutralisant la pol\u00e9mique. Ce cynisme na\u00eff passe \u00e0 c\u00f4t\u00e9 de la v\u00e9rit\u00e9 de la situation.<\/p>\n<\/p>\n<p><p>Ce soi-disant \u00ab\u00a0encommisionnement\u00a0\u00bb, si la commission se constitue, va se faire sous la menace de l&rsquo;\u00e9p\u00e9e de Damocl\u00e8s du rythme infernal des r\u00e9v\u00e9lations. Malgr\u00e9 ce projet de n\u00e9gociation et un sommet bruxellois de l&rsquo;UE qui pourrait para&icirc;tre \u00e0 certains avoir \u00ab\u00a0vid\u00e9 l&rsquo;abc\u00e8s\u00a0\u00bb avec ce qu&rsquo;ils jugeraient \u00eatre les d\u00e9nonciations formelles n\u00e9cessaires et suffisantes des dirigeants europ\u00e9ens, au contraire la tension continue de monter, notamment autour des \u00e9coutes de Merkel. La bande Snowden-Greenwald-Poitras constitu\u00e9e en un magistral dispositif antiSyst\u00e8me s&rsquo;y entend pour distiller ses r\u00e9v\u00e9lations selon l&rsquo;opportunit\u00e9 des \u00e9v\u00e9nements, et les derniers avatars montrant les relations USA-UE \u00e0 la lumi\u00e8re de la NSA constituent une occasion de taille. Le classique \u00e9touffoir transatlantique des deux bureaucraties alli\u00e9s (US et UE) pour \u00e9carter toute menace d&rsquo;affichage des antagonismes et disparit\u00e9s r\u00e9elles entre les deux partenaires du bloc BAO, aura bien des difficult\u00e9s \u00e0 fonctionner. M\u00eame hors de l&rsquo;hypoth\u00e8se de cette commission, la m\u00eame situation pr\u00e9vaut d&rsquo;une tension transatlantique que les arrangements humains habituels, \u00ab\u00a0entre amis\u00a0\u00bb, auront infiniment de mal \u00e0 disperser sous les coups de boutoir des antiSyst\u00e8me.<\/p>\n<\/p>\n<p><p>La crise Snowden\/NSA est indomptable et incontr\u00f4lable \u00e0 cause de ce qu&rsquo;elle rec\u00e8le d&rsquo;elle-m\u00eame, affectant absolument tous les domaines et territoires politiques, des USA aux relations internationales, et faisant peser sur les psychologies cette tension permanente de l&rsquo;inattendu et de la surprise. Elle est indomptable et incontr\u00f4lable parce qu&rsquo;elle est l&rsquo;expression la plus achev\u00e9e des pathologies de la modernit\u00e9 qui, d\u00e9sormais, tourmentent ouvertement les directions politiques du bloc BAO et du Syst\u00e8me. Elle est indomptable et incontr\u00f4lable parce qu&rsquo;elle ne s&rsquo;op\u00e9rationnalise que par le biais du syst\u00e8me de la communication, lequel a d\u00e9sormais une fonction antiSyst\u00e8me manifeste et extr\u00eamement puissante.<\/p>\n<\/p>\n<p><p>Ces attaques constantes du dispositif antiSyst\u00e8me, et cette fois aussi bien dans la situation \u00e9voqu\u00e9e des relations transatlantiques que dans la situation int\u00e9rieure US, poussent \u00e9galement \u00e0 la n\u00e9cessit\u00e9 de changements selon un processus classique selon l&rsquo;observation minimale que les USA (les NSA) ne peuvent continuer \u00e0 op\u00e9rer de la sorte. La \u00ab\u00a0n\u00e9cessit\u00e9 de changements\u00a0\u00bb, on y revient, c&rsquo;est quelque chose qui ressemble \u00e0 une r\u00e9forme radicale de la NSA passant par son investissement et sa prise de contr\u00f4le par le pouvoir washingtonien. Si l&rsquo;on veut vraiment obtenir un r\u00e9sultat dont d\u00e9pend la reprise en mains de ses capacit\u00e9s d&rsquo;influence et de contr\u00f4le qui font la puissance fondamentale du washingtonien, il va falloir que le <em>sapiens<\/em>-POTUS se coltine avec la NSA, qui est \u00e0 la fois &laquo;<em>a state within a state<\/em>&raquo; et &laquo;<em>a rogue operation<\/em>&raquo;, &ndash; c&rsquo;est-\u00e0-dire un \u00ab\u00a0&Eacute;tat-voyou\u00a0\u00bb au c&oelig;ur d&rsquo;un syst\u00e8me (de l&rsquo;am\u00e9ricanisme) dont la t\u00eate (le gouvernement) n&rsquo;est m\u00eame pas un &Eacute;tat, puisque sans la dimension r\u00e9galienne, et qui a toujours suivi sa propre pathologie obsessionnelle de la surveillance. Il y a l\u00e0 une situation qui se situe g\u00e9ographiquement entre Charybde et Scylla, et politiquement entre marteau et enclume.<\/p>\n<\/p>\n<p><p>&#8230; Il y a l\u00e0 le cas d&rsquo;un affrontement potentiel, peut-\u00eatre d\u00e9cisif, sans aucun doute fratricide, entre divers \u00e9l\u00e9ments du Syst\u00e8me. Le moins int\u00e9ressant n&rsquo;est pas celui qui se dessine, \u00e0 Washington m\u00eame, entre la pr\u00e9sidence et la NSA elle-m\u00eame.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur les pathologies de la modernit\u00e9 28 octobre 2013 &ndash; La semaine derni\u00e8re fut singuli\u00e8re, comme on le sait, avec l&rsquo;implication forc\u00e9e mais imp\u00e9rative de l&rsquo;Europe dans la crise Snowden\/NSA, du c\u00f4t\u00e9 des accusateurs r\u00e9ticents. \u00ab\u00a0Forc\u00e9e\u00a0\u00bb pour l&rsquo;implication europ\u00e9enne, \u00ab\u00a0r\u00e9ticents\u00a0\u00bb pour les accusateurs europ\u00e9ens, parce que l&rsquo;Europe et les USA sont absolument rang\u00e9s sur&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[2769,15373,9704,4852,6944,3203,4633,3871,6208,4280,5499,9436,12224,4999,3098,4847],"class_list":["post-75275","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-americain","tag-bild","tag-fratricide","tag-goulag","tag-greenwald","tag-hollande","tag-merkel","tag-nsa","tag-obama","tag-pathologie","tag-potus","tag-reve","tag-snowden","tag-surveillance","tag-tocqueville","tag-woodward"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75275"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75275\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}