{"id":75280,"date":"2013-10-30T04:26:47","date_gmt":"2013-10-30T04:26:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/10\/30\/terrible-crise-fratricide\/"},"modified":"2013-10-30T04:26:47","modified_gmt":"2013-10-30T04:26:47","slug":"terrible-crise-fratricide","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/10\/30\/terrible-crise-fratricide\/","title":{"rendered":"Terrible crise fratricide"},"content":{"rendered":"<p><h2 class=\"common-article\">Terrible crise fratricide<\/h2>\n<\/p>\n<p><p>\t30 octobre 2013  C&rsquo;est l&rsquo;avis de Glenn Greenwald que la semaine derni\u00e8re, avec les r\u00e9v\u00e9lations des \u00e9coutes plus ou moins av\u00e9r\u00e9es de dirigeants europ\u00e9ens du calibre de G\u00e9ants Historiques que sont Hollande et Merkel, avec le sommet de l&rsquo;UE kidnapp\u00e9 en bonne part par rapport \u00e0 son calendrier original par ces affaires du type NSA, avec la panique et le d\u00e9sordre qui se sont signal\u00e9s \u00e0 Washington \u00e0 ce propos, la crise Snowden\/NSA a pris un tour nouveau en for\u00e7ant l&rsquo;attention sur son aspect ext\u00e9rieur (<em>dito<\/em>, l&rsquo;espionnage-surveillance de la NSA sur le vaste domaine de ROW [<em>rest Of the World<\/em>], particuli\u00e8rement et tr\u00e8s sp\u00e9cifiquement les amis du bloc BAO). On lit cela dans son commentaire du <a href=\"http:\/\/www.theguardian.com\/commentisfree\/2013\/oct\/25\/europe-erupts-nsa-spying-chief-government\" class=\"gen\">25 octobre 2013<\/a> dans le <em>Guardian<\/em> (et l&rsquo;on y notera le principal argument, mis \u00e0 mal par Greenwald au nom d&rsquo;une d\u00e9nonciation avis\u00e9e de l&rsquo;activisme de l&rsquo;anglosaxonisme, du d\u00e9bat entre les robots-Syst\u00e8me tentant d&rsquo;arr\u00eater la vague antiSyst\u00e8me : \u00ab<em>everyone spies!<\/em>\u00bb) :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The most under-discussed aspect of the NSA story has long been its international scope. That all changed this week as both Germany and France exploded with anger over new revelations about pervasive NSA surveillance on their population and democratically elected leaders.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>As was true for Brazil previously, reports about surveillance aimed at leaders are receiving most of the media attention, but what really originally drove the story there were revelations that the NSA is bulk-spying on millions and millions of innocent citizens in all of those nations. The favorite cry of US government apologists -everyone spies!  falls impotent in the face of this sort of ubiquitous, suspicionless spying that is the sole province of the US and its four English-speaking surveillance allies (the UK, Canada, Australia and New Zealand).<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl est remarquable que cette d\u00e9stabilisation des relations transatlantiques,  c&rsquo;en est une, sans nul doute,  se r\u00e9alise apr\u00e8s une premi\u00e8re vague de r\u00e9v\u00e9lations concernant l&rsquo;Europe, courant juin dernier, dont les effets ont \u00e9t\u00e9 mineurs. Cela montre la r\u00e9silience antiSyst\u00e8me de la crise Snowden\/NSA qui est une crise multi-cibles, qui n&rsquo;oublie rien et repart \u00e0 l&rsquo;attaque quand une premi\u00e8re pouss\u00e9e a \u00e9chou\u00e9. La s\u00e9quence actuelle par rapport \u00e0 ce qui a pr\u00e9c\u00e9d\u00e9 est ainsi comment\u00e9e par Greenwald : \u00ab<em>First, note how leaders such as Chancellor Angela Merkel reacted with basic indifference when it was revealed months ago that the NSA was bulk-spying on all German citizens, but suddenly found her indignation only when it turned out that she personally was also targeted. That reaction gives potent insight into the true mindset of many western leaders.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tOn donne ici deux autres r\u00e9actions qui envisagent le probl\u00e8me du point de vue plus g\u00e9n\u00e9ral des effets sur l&rsquo;influence et le statut moral des USA,  le deuxi\u00e8me point \u00e9tant un moyen tr\u00e8s puissant de renforcement du premier dans la politique am\u00e9ricaniste. Les deux points de vue ne consid\u00e8rent pas le facteur de l&rsquo;exceptionnalisme des USA, tant dans la pratique de la NSA que dans la politique g\u00e9n\u00e9rale des USA (ce facteur de l&rsquo;exceptionnalisme \u00e9tant \u00e9galement un facteur de renforcement de l&rsquo;influence dans la psychologie de l&rsquo;am\u00e9ricanisme).<\/p>\n<\/p>\n<p><p>\t Extrait de l&rsquo;interview par <em>Russia Today<\/em> le <a href=\"http:\/\/rt.com\/op-edge\/world-spying-america-denial-698\/\" class=\"gen\">25 octobre 2013<\/a>, de Gevin MacFayden, directeur du <em> Centre of Investigative Journalism<\/em> \u00e0 Londres.<\/p>\n<\/p>\n<p><p>\t<strong><em>Russia Today<\/em><\/strong> : \u00ab<em>Are you surprised so many world leaders are allegedly being monitored?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<strong><em>Gavin MacFadyen<\/em><\/strong> : \u00ab<em>No, I wasn&rsquo;t. I was surprised that there were so few. I think the truth is that the Americans have the capacity  as other countries do, but particularly the United States  to spy on almost anybody they want to. It&rsquo;s an abuse of power on a very large scale.<\/em> [&#8230;] <em>However, the principle of interfering with other leaders is an astonishing presumption and damaging to relations. It&rsquo;s also known, of course, here in Britain where I&rsquo;m based, that it&rsquo;s very common, much of this kind of thing. But to cover it up, there&rsquo;s a kind of outrage. Oh, this is a terrible thing. Of course it is terrible on one level, but at the same time they all do it. So it&rsquo;s not quite as awful as it appears, however that doesn&rsquo;t make it any less worse for the Americans. I think they were caught out doing something they denied. They lied about it. And now we find out it&rsquo;s much bigger than anybody thought.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Extrait de l&rsquo;interview du directeur de l&rsquo;<em>Open Technology Institute<\/em>, Sascha Meinrath, le <a href=\"http:\/\/rt.com\/op-edge\/us-lost-internet-credibility-580\/\" class=\"gen\">23 octobre 2013<\/a>, \u00e9galement par <em>Russia Today<\/em>.<\/p>\n<\/p>\n<p><p>\t<strong><em>Russia Today<\/em><\/strong>: \u00ab<em>Do you believe the fallout from the scandal might actually lead to Washington reviewing, or curbing its surveillance methods?<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\t<strong><em>Sascha Meinrath<\/em><\/strong> : \u00ab<em>I should hope so. It is clear that what the US has been doing is not sustainable over time. This has created a massive reputational crisis for the US. This is a Sputnik moment for the rest of the globe for the entire populace is in essence on edge about what the US government is doing, what is the NSA doing, what is being surveilled. I mean we are not just talking about 70 million phone calls in France. We are talking about 70 million phone calls in a single month. So in essence what we&rsquo;re saying is everyone is a suspect and everyone is being surveilled. And it is probably not just France and Germany, and Mexico and Brazil, this is probably globally.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;ampleur et la vitesse des cons\u00e9quences de la crise Snowden\/NSA, ces dix derniers jours, ont effectivement ouvert une nouvelle phase. La question et le d\u00e9bat sur l&rsquo;espionnage, la surveillance, des \u00e9coutes ; le cort\u00e8ge de banalit\u00e9s \u00e9gren\u00e9es par les d\u00e9fenseurs-Syst\u00e8me mobilis\u00e9s contre cette dynamique antiSyst\u00e8me (voir le <LIEN=http:\/\/www.dedefensa.org\/article-notes_sur_les_pathologies_de_la_modernit__28_10_2013.html<D>28 octobre 2013 : \u00ab[D]<em>eux lieux communs qui rel\u00e8vent du cynisme lorsqu&rsquo;il se fait d\u00e9guisement de la pauvret\u00e9 de l&rsquo;esprit et faux-nez du r\u00e9alisme, et qui se r\u00e9v\u00e8le comme une sorte de na\u00efvet\u00e9 invertie [par irr\u00e9flexion et inexp\u00e9rience] : Tout le monde espionne [a toujours espionn\u00e9] tout le monde, et Ces gens [les chefs d&rsquo;\u00c9tat] savent tr\u00e8s bien qu&rsquo;ils sont espionn\u00e9s, leur indignation est forc\u00e9e.<\/em>\u00bb),  tout cela est en train d&rsquo;\u00eatre pulv\u00e9ris\u00e9, d\u00e9sint\u00e9gr\u00e9 et dispers\u00e9, ne comptant plus gu\u00e8re dans le d\u00e9bat central mais s&rsquo;ils en sont des causes ou des circonstances initiales&#8230; Aujourd&rsquo;hui, cette crise, dans cette p\u00e9riode sp\u00e9cifique commenc\u00e9e il y a <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_une_col_re-poire_et_cons_quences_22_10_2013.html\" class=\"gen\">une d\u00e9cade<\/a>, et p\u00e9riode exemplaire par ailleurs d&rsquo;une dynamique nouvelle ouverte par les p\u00e9rip\u00e9ties avec le Br\u00e9sil, cette crise est en train d&rsquo;accoucher d&rsquo;un nouvel \u00e9v\u00e9nement, qui pourrait, qui devrait prendre lui-m\u00eame l&rsquo;allure d&rsquo;une nouvelle crise. A partir de l&rsquo;exemple du Br\u00e9sil o\u00f9 l&rsquo;on a vu en quelques semaines les relations USA-Br\u00e9sil en cours d&rsquo;am\u00e9lioration brutalement saccag\u00e9es, on voit cette ces relations transatlantiques caract\u00e9risant l&rsquo;axe principal Europe-USA du bloc BAO, en train de se transmuter.<\/p>\n<\/p>\n<p><p>\tLe plus remarquable, c&rsquo;est le bruit de communication g\u00e9n\u00e9ral qui s&rsquo;est \u00e9lev\u00e9 en d\u00e9but de s\u00e9quence pour contenir ses effets, selon l&rsquo;absolue certitude que la banalisation habituelle de cette sorte de tension (dite transatlantique) apaiserait cette dynamique, ce bruit de communication s&rsquo;est transform\u00e9 en une cacophonie d\u00e9risoire qui ne parvient qu&rsquo;\u00e0 se r\u00e9duire elle-m\u00eame en se ridiculisant. Les slogans-lieux communs que nous utilisons comme symboles de cette r\u00e9action (Tout le monde espionne tout le monde, et Ces gens savent tr\u00e8s bien qu&rsquo;ils sont espionn\u00e9s, leur indignation est forc\u00e9e) sont totalement inappropri\u00e9s \u00e0 la situation et ne produisent aucun effet, sinon celui d&rsquo;ouvrir le champ \u00e0 la v\u00e9ritable aggravation de la crise. Personne, de ce point de vue, n&rsquo;a r\u00e9alis\u00e9 qu&rsquo;il ne s&rsquo;agit, on le r\u00e9p\u00e8te ici avec force, aucunement d&rsquo;une question d&rsquo;espionnage, de surveillance, d&rsquo;\u00e9coute. Il s&rsquo;agit d&rsquo;une question fondamentale de confiance et de coh\u00e9sion \u00e0 l&rsquo;int\u00e9rieur du bloc BAO, mises \u00e0 mal <strong>d&rsquo;une fa\u00e7on symbolique<\/strong>, non par des r\u00e9seaux de surveillance et d&rsquo;\u00e9coute, mais par l&rsquo;expression m\u00eame de ce qui repr\u00e9sente traditonnellement le supr\u00e9matisme anglo-saxon dont on pouvait parler du temps de Toynbee (voir le <a href=\"http:\/\/www.dedefensa.org\/article-cr_puscule_de_la_civilisation_15_10_2013.html\" class=\"gen\">15 octobre 2013<\/a>), symboliquement repr\u00e9sent\u00e9 pour le domaine qui nous int\u00e9resse par les r\u00e9seaux <a href=\"http:\/\/en.wikipedia.org\/wiki\/UKUSA_Agreement\" class=\"gen\">UKUSA<\/a> (UK-USA) puis <a href=\"http:\/\/en.wikipedia.org\/wiki\/AUSCANNZUKUS\" class=\"gen\">AUSCANNZUKUS<\/a> (Australie-Canada-Nouvelle-Z\u00e9lande-UK-USA) r\u00e9unissant, depuis 1946, les capacit\u00e9s d&rsquo;\u00e9coute et de surveillance des pays de l&rsquo;anglosph\u00e8re. Cette expression du supr\u00e9matisme anglo-saxon, exprim\u00e9 bien entendu par la NSA avec son suppl\u00e9tif GCHQ britannique, est effectivement le <strong>symbole<\/strong> de la tension rupturielle (et symbole d&rsquo;un archa\u00efsme, d&rsquo;ailleurs) qui s&rsquo;effectue au sein du bloc BAO, contre le gr\u00e9 de tous les dirigeants des pays du bloc BAO, contre les pressions du Syst\u00e8me, contre la logique de leur rassemblement, etc., et simplement sous la pouss\u00e9e irr\u00e9sistible de la dynamique antiSyst\u00e8me du groupe Snowden-Greenwald &#038; compagnie, d\u00e9sormais relay\u00e9 par une infinit\u00e9 de r\u00e9seaux diffusant informations et programmes de la NSA. Ce symbolisme du supr\u00e9matisme anglo-saxon, compl\u00e8tement anachronique dans les conditions nouvelles qui pr\u00e9valent depuis 2008 pour notre propos (on verra plus loin), est devenu la repr\u00e9sentation symbolique d&rsquo;une menace qui est en train de s&rsquo;installer au cur du bloc BAO, mena\u00e7ant effectivement de le d\u00e9structurer contre les tendances et les conditions qui ont conduit \u00e0 sa formation. La crise de confiance se traduit d&rsquo;une fa\u00e7on op\u00e9rationnelle dans des menaces concernant la coop\u00e9ration des services de renseignement dans le domaine de l&rsquo;antiterrorisme, la coop\u00e9ration financi\u00e8re (menace de rupture de l&rsquo;accord SWIFT), la coop\u00e9ration commerciale (<a href=\"http:\/\/news.antiwar.com\/2013\/10\/29\/nsa-surveillance-puts-us-eu-trade-deal-in-jeopardy\/&#8236;\" class=\"gen\">difficult\u00e9s<\/a> des n\u00e9gociations sur la zone de libre-\u00e9change, etc.) ; mais elle se manifeste surtout au niveau de la communication, par des attitudes de r\u00e9crimination, de contestation, de d\u00e9fiance insultante (lorsque, par exemple, les d\u00e9put\u00e9s allemands veulent entendre Edward Snowden, ou aller l&rsquo;auditionner \u00e0 Moscou).<\/p>\n<\/p>\n<p><p>\tOn annexera \u00e0 ce fait fondamental et central de la crise Snowden\/NSA, le fait de l&rsquo;\u00e9clatement de la structure du bloc BAO au Moyen-Orient. M\u00eame si les USA vont vers un accord avec l&rsquo;Iran, comme l&rsquo;affirme <em>DEBKAFiles<\/em> ce <a href=\"http:\/\/www.debka.com\/article\/23393\/Mystery-of-missing-ayatollah-Ali-Khamenei's-three-week-seclusion-for-work-on-nuclear-deal-with-US\" class=\"gen\">27 octobre 2013<\/a>, l&rsquo;essentiel \u00e0 observer est que l&rsquo;architecture du bloc BAO dans la r\u00e9gion est en train d&rsquo;exploser, avec la r\u00e9bellion erratique et n\u00e9e d&rsquo;une fureur qu&rsquo;on qualifiera \u00e9trangement de commune, sans aucune coh\u00e9rence strat\u00e9gique et id\u00e9ologique, d&rsquo;Isra\u00ebl et de l&rsquo;Arabie Saoudite. Cette affaire suit, bien entendu, l&rsquo;\u00e9chec am\u00e9ricaniste en Syrie du mois de septembre, l&rsquo;impuissance \u00e0 ex\u00e9cuter une menace de frappe du pr\u00e9sident Obama qui a vertigineusement affaibli l&rsquo;influence US dans la r\u00e9gion et port\u00e9, l\u00e0 aussi, un rude coup \u00e0 la coh\u00e9sion du bloc BAO pr\u00e9parant la phase actuelle de tension UE-USA.<\/p>\n<h3>D\u00e9chirement \u00e0 l&rsquo;int\u00e9rieur du bloc BAO<\/h3>\n<\/p>\n<p><p>\tIl est bon, avant d&rsquo;encha\u00eener sur notre commentaire, de rappeler certaines de nos r\u00e9f\u00e9rences sp\u00e9cifiques propres au travail de ce site, tant il nous appara\u00eet, \u00e0 la lecture de ceci ou de cela,  sans intention d&rsquo;identification de notre part, qui le voudra ou le pourra s&rsquo;y reconna\u00eetra,  que ces r\u00e9f\u00e9rences sont bien souvent d\u00e9sinterpr\u00e9t\u00e9es (comme l&rsquo;on dit d&rsquo;une sorte d&rsquo;auto-d\u00e9sinformation), et cela d\u00e9formant d\u00e9cisivement par cons\u00e9quent le fondement de nos travaux. Dans un effort que nous poursuivons depuis pr\u00e8s d&rsquo;un an, nous avons \u00e9tabli un <em>Glossaire.dde<\/em> qui expose ces r\u00e9f\u00e9rences \u00e0 mesure de notre travail \u00e0 cet \u00e9gard, mais leur lecture qui demande de l&rsquo;attention et du temps peut souvent avoir d\u00e9courag\u00e9 plus d&rsquo;une bonne \u00e2me, dont l&rsquo;une ou l&rsquo;autre pr\u00e9tend pourtant disposer de tous les \u00e9l\u00e9ments pour comprendre le sens de notre d\u00e9marche. Nous signalons donc, pour le cas de ce commentaire pr\u00e9sent mais aussi dans un but de documentation g\u00e9n\u00e9rale, que nous parlons dans le cadre historique et m\u00e9taphorique de ce que nous nomme l&rsquo;\u00e8re psychopolitique (voir le <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_l_re_psychopolitique_12_10_2013.html\" class=\"gen\">12 octobre 2013<\/a>), c&rsquo;est-\u00e0-dire une \u00e9poque nouvelle, notre \u00e9poque o\u00f9 la communication est, d&rsquo;une fa\u00e7on \u00e9crasante, la principale force dynamique, d&rsquo;influence et de puissance ; que nous parlons dans le cadre structurel g\u00e9n\u00e9ral d&rsquo;un Syst\u00e8me (voir le <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_syst_me_08_07_2013.html\" class=\"gen\">8 juillet 2013<\/a>), c&rsquo;est-\u00e0-dire d&rsquo;une entit\u00e9 englobant notre civilisation (en r\u00e9alit\u00e9, notre contre-civilisation) et ne pouvant <strong>en aucun cas<\/strong> se ramener \u00e0 un seul de ses composants (f\u00fbt-ce les USA), et ne b\u00e9n\u00e9ficiant <strong>en aucun cas<\/strong> \u00e0 un seul de ses composants (f\u00fbt-ce les USA) aux d\u00e9pens des autres ; que nous parlons dans le cadre psychologique et politique du bloc BAO (voir le <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_bloc_bao_10_12_2012.html\" class=\"gen\">10 d\u00e9cembre 2012<\/a>), regroupant depuis l&rsquo;automne 2008 \u00e0 peu pr\u00e8s les pays dits occidentaux (USA, Europe type-UE, des pays satellites tels Isra\u00ebl et l&rsquo;Arabie, certains pays asiatiques type-Japon et Cor\u00e9e du sud, mais ceux-l\u00e0 plus \u00e9loign\u00e9s), et op\u00e9rationnalisant une politique-Syst\u00e8me (voir le <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_la_politique-syst_me__17_11_2012.html\" class=\"gen\">17 novembre 2012<\/a>) qui tient de moins en moins compte des sp\u00e9cificit\u00e9s nationales, et encore moins des conceptions principielles. On peut bien entendu ne pas \u00eatre d&rsquo;accord avec ces concepts qui fixent selon nous une situation nouvelle, mais on ne peut juger du sens de nos travaux qui utilisent ces concepts en \u00e9cartant leur utilisation et leurs sens fondamentaux.<\/p>\n<\/p>\n<p><p>\tJustement, encha\u00eenons sur le bloc BAO, qui est l&rsquo;objet m\u00eame de notre commentaire, et qui regroupe aussi bien des notions telles que l&rsquo;ultralib\u00e9ralisme, le supr\u00e9matisme occidental (succ\u00e9dan\u00e9 du supr\u00e9matisme anglo-saxon, qui en devenu le substitut et a compl\u00e8tement supplant\u00e9 le supr\u00e9matisme anglo-saxon) enrob\u00e9 dans des concepts moralisants et soci\u00e9taux, la guerre contre la terrorisme pr\u00e9sent\u00e9e comme une dynamique lib\u00e9ratrice et civilisatrice, la culture niveleuse (type am\u00e9ricaniste mais d\u00e9sormais hors du seul champ am\u00e9ricaniste et devenue BAO) rebaptis\u00e9e multiculturalisme, le scientisme postmodernisme, la pr\u00e9\u00e9minence des valeurs sur les principes, etc. Depuis sa formation \u00e0 l&rsquo;automne 2008, directement <strong>sous l&#8217;empire du Syst\u00e8me<\/strong>, le bloc a perdu les modalit\u00e9s hi\u00e9rarchiques qui caract\u00e9risaient l&rsquo;entit\u00e9 pr\u00e9c\u00e9dente, ce qu&rsquo;on nommait l&rsquo;Ouest. Pr\u00e9cis\u00e9ment, il n&rsquo;est plus question d&rsquo;une domination des USA, qui ne furent jamais empire au sens historique du mot, et qui le sont moins que jamais, mais qui exerc\u00e8rent une tutelle d&rsquo;influence, de culture et de surveillance pendant un demi-si\u00e8cle ; le processus continue mais il n&rsquo;est plus v\u00e9cu comme une marque de domination de l&rsquo;un sur les autres mais comme une marque d&rsquo;int\u00e9gration et d&rsquo;homog\u00e9n\u00e9isation. La globalisation a \u00e9videmment pr\u00e9par\u00e9 et op\u00e9rationnalis\u00e9 tr\u00e8s rapidement cette int\u00e9gration et cette homog\u00e9n\u00e9isation qui se sont cristallis\u00e9es avec la crise de l&rsquo;automne 2008 ; le nous sommes tous am\u00e9ricains de qui-vous-devriez-savoir est devenu une sorte de nous sommes tous globalis\u00e9s-Syst\u00e8me. Ce n&rsquo;est pas une marque de puissance, de triomphe, d&rsquo;h\u00e9g\u00e9monie, etc., de l&rsquo;un ou l&rsquo;autre sur les autres, c&rsquo;est une marque de la pr\u00e9\u00e9minence indiscut\u00e9e et de l&rsquo;avancement irr\u00e9sistible du Syst\u00e8me,  et de son avancement catastrophique puisque la dynamique de surpuissance, au plus elle s&rsquo;affirme au plus elle devient dynamique d&rsquo;autodestruction.<\/p>\n<\/p>\n<p><p>\tLe caract\u00e8re n\u00e9cessaire de ce bloc BAO tel qu&rsquo;il s&rsquo;est constitu\u00e9 est n\u00e9cessairement l&rsquo;abandon des hi\u00e9rarchies encombrantes et p\u00e9nalisantes, et qui, surtout, selon la pens\u00e9e primale des directions politiques, constituent des freins inutiles \u00e0 la promotion de mod\u00e8le g\u00e9n\u00e9ral, du mod\u00e8le-Syst\u00e8me que le bloc pr\u00e9tend repr\u00e9senter. Ainsi justifions-nous la perception d&rsquo;un processus rapide de la dissolution de l&rsquo;h\u00e9g\u00e9monie d&rsquo;influence et d&rsquo;autorit\u00e9 des USA sur le reste, qui a \u00e9t\u00e9 d&rsquo;ailleurs marqu\u00e9e ces derni\u00e8res ann\u00e9es, jusque dans des \u00e9v\u00e9nements grossiers (parce qu&rsquo;ils ne sont pas les plus importants dans le processus d\u00e9crits) quoique visibles, de type strat\u00e9gique et militaire. Quelle que soit la rh\u00e9torique d\u00e9pass\u00e9e, des experts et autres publicistes du domaine qui continuent \u00e0 utiliser le mat\u00e9riel s\u00e9mantique de la deuxi\u00e8me moiti\u00e9 du XX\u00e8me si\u00e8cle, les USA ont jou\u00e9 un r\u00f4le d&rsquo;impulsion et de communication, voire un r\u00f4le op\u00e9rationnel, <strong>de second plan<\/strong> dans les aventures si caract\u00e9ristiques de la Libye et de la Syrie. Dans le premier cas, l&rsquo;impulsion fut clairement fran\u00e7aise, et m\u00eame le Qatar joua un r\u00f4le dynamique plus marqu\u00e9 que les USA ; dans le second, le jusqu&rsquo;auboutisme des Fran\u00e7ais jusqu&rsquo;\u00e0 la mi-septembre, la col\u00e8re des Saoudiens depuis quelques semaines, ne s&#8217;embarrassent gu\u00e8re d&rsquo;une quelconque et soi-disant h\u00e9g\u00e9monie US devenue illusoire sinon disparue corps et bien. Nous n&rsquo;en sommes certainement pas \u00e0 proposer l&rsquo;id\u00e9e, qui n&rsquo;a aucun sens dans notre sch\u00e9ma m\u00e9thodologique, d&rsquo;un renversement d&rsquo;h\u00e9g\u00e9monie ; nous d\u00e9veloppons l&rsquo;id\u00e9e que, dans le concept bloc BAO directement enfant\u00e9 par le Syst\u00e8me, lequel Syst\u00e8me n&rsquo;appartient \u00e0 personne et n&rsquo;ob\u00e9it \u00e0 personne mais qui au contraire m\u00e8ne la danse, l&rsquo;id\u00e9e d&rsquo;h\u00e9g\u00e9monie entre les membres du club est compl\u00e8tement d\u00e9pass\u00e9e. La puissance brute, celle de l&rsquo;\u00e8re g\u00e9opolitique, n&rsquo;a rien \u00e0 voir dans cet arrangement, cette puissance \u00e9tant toute enti\u00e8re le fait du seul Syst\u00e8me ; comptent essentiellement la perception de la communication, avec la politique \u00e0 la fois moralisante et supr\u00e9matiste qui l&rsquo;accompagne, et dans ce cas chaque membre, ou disons divers membres du bloc BAO peuvent pr\u00e9tendre repr\u00e9senter cette dynamique \u00e0 pr\u00e9tention id\u00e9ologique et, selon les circonstances, en assurer momentan\u00e9ment l&rsquo;h\u00e9g\u00e9monie.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est essentiellement pour cette raison que l&rsquo;affaire de la NSA, dont on a vu plus haut qu&rsquo;elle d\u00e9coule en partie (en plus des obsessions US repr\u00e9sentant la modernit\u00e9, expos\u00e9es le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_les_pathologies_de_la_modernit__28_10_2013.html\" class=\"gen\">28 octobre 2013<\/a>), notamment de l&rsquo;archa\u00efque supr\u00e9matisme anglo-saxon et des arrangements UKUSA et AUSCANNZUKUS, est apparue si choquante au reste du bloc. C&rsquo;est dire si l&rsquo;on est loin des sornettes de journalistes de salon du type cynique-na\u00eff (tout le monde espionne tout le monde), rescap\u00e9es des romans d&rsquo;espionnage \u00e0-la-Pierre Nord (deux g\u00e9n\u00e9rations d&rsquo;avant Le Carr\u00e9). Il y a purement et simplement une sorte de trahison du r\u00e8glement-Syst\u00e8me du club, du bloc BAO, \u00e9tabli entre <em>gentlemen<\/em>-Syst\u00e8me, c&rsquo;est-\u00e0-dire pour dire net entre copains et coquins des m\u00eames directions politiques, des m\u00eames entreprises d\u00e9structurantes, des m\u00eames sauvetages des banques par sanctification du gangst\u00e9risme nihiliste (deux ou trois rangs en-dessous de la Mafia o\u00f9 existe un code de l&rsquo;honneur et o\u00f9 l&rsquo;on va \u00e0 l \u00e9glise le dimanche). Bref, leur indignation (essentiellement celle des Europ\u00e9ens \u00e0 l&rsquo;encontre des USA dans la crise Snowden\/NSA) n&rsquo;est pas feinte. Le plus remarquable, le plus extraordinaire par rapport aux conceptions archa\u00efques, le plus probant \u00e0 cet \u00e9gard, est que le principal responsable, l&rsquo;ex-h\u00e9g\u00e9moniste-en-chef qui dominait tout le monde jusqu&rsquo;ici, a, contrairement \u00e0 ses habitudes d&rsquo;antan o\u00f9 il traitait cette volaille europ\u00e9enne par le m\u00e9pris, r\u00e9agi dans la plus profonde confusion, voire dans un sentiment, extraordinaire pour lui, de culpabilit\u00e9. (Extraordinaire pour la psychologie am\u00e9ricaniste, qui s&rsquo;appuie fondamentalement sur <a href=\"http:\/\/www.dedefensa.org\/article-l_inculpabilite_comme_fondement_de_la_psychologie_americaniste_06_05_2006.html\" class=\"gen\">l&rsquo;inculpabilit\u00e9<\/a>. Mais cette inculpabilit\u00e9 est entr\u00e9e dans la composition de la <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_notre_psychologie_28_01_2013.html\" class=\"gen\">psychologie-Syst\u00e8me<\/a> du bloc BAO, tout comme le supr\u00e9matisme anglo-saxon, et un membre du bloc ne peut d\u00e9sormais plus en faire \u00e9tat aux d\u00e9pens des autres sous peine de faute presque-impardonnable. Washington est dans un \u00e9tat de faute presque-impardonnable, aujourd&rsquo;hui, vis-\u00e0-vis des autres membres du bloc BAO,  et il se sent coupable \u00e0 cet \u00e9gard. C&rsquo;est une \u00e9volution, voire une r\u00e9volution par rapport \u00e0 son attitude psychologique standard.)<\/p>\n<\/p>\n<p><p>\t&#8230; Ainsi en arrivons-nous \u00e0 l&rsquo;essentiel : le constat qu&rsquo;un <strong>crise grave d\u00e9chirer le bloc BAO<\/strong>. (Principalement, voire essentiellement les cons\u00e9quences transatlantiques de la crise Snowden\/NSA, mais aussi, d&rsquo;une certaine fa\u00e7on, les fureurs erratiques isra\u00e9lo-saoudiennes,  unissons-les pour le cas puisqu&rsquo;ils ont l&rsquo;air d&rsquo;y tant tenir,  vis-\u00e0-vis des USA et de leur non-politique de type-yoyo au Moyen-Orient.) C&rsquo;est une immense nouveaut\u00e9, et un pas substantiel fait en avant dans le sens de l&rsquo;autodestruction,  laquelle n&rsquo;a nulle besoin d&rsquo;attaques ext\u00e9rieures pour se manifester, au contraire qui se manifeste toute seule, d&rsquo;elle-m\u00eame contre elle-m\u00eame,  et les seules attaques ext\u00e9rieures \u00e9tant celles qui utilisent la puissance de la chose pour l&rsquo;orienter contre la chose, comme il est fait dans la tactique des r\u00e9seaux Snowden-Greenwald. Il ne s&rsquo;agit pas d&rsquo;une m\u00e9sentente, d&rsquo;une incompr\u00e9hension, d&rsquo;une passade, d&rsquo;une divergence de politique, etc., non, mais bien d&rsquo;une crise par rapport \u00e0 une r\u00e8gle non-\u00e9crite mais fondamentale du bloc, cette sorte de principe d&rsquo;\u00e9galit\u00e9 et de bonne entente sur les questions essentielles des rapports entre les parties du bloc.<\/p>\n<\/p>\n<p><p>\tPersonne ne l&rsquo;a cherch\u00e9e et personne ne l&rsquo;a voulue, cette crise ; certes, tout le monde \u00e9tait pr\u00eat \u00e0 passer \u00e0 c\u00f4t\u00e9 en d\u00e9tournant les yeux si cela \u00e9tait possible, comme on \u00e9vite un excr\u00e9ment malodorant, surtout du pied gauche. Mais d\u00e8s lors que le syst\u00e8me de la communication s&rsquo;est empar\u00e9 de la chose et l&rsquo;a r\u00e9pandue comme on le voit faire, d\u00e8s lors que le r\u00e9seau antiSyst\u00e8me Snowden-Greenwald &#038; compagnie a commenc\u00e9 \u00e0 ajuster ses coups (ses fuites) avec une incomparable maestria de communication par rapport aux opportunit\u00e9s et aux \u00e9v\u00e9nements, le cas devenait flagrant et, par cons\u00e9quent, in\u00e9vitable. C&rsquo;est ce qui se passe aujourd&rsquo;hui. <\/p>\n<\/p>\n<p><p>\tEncore une fois, cela ne signifie rien des archa\u00efsmes utilis\u00e9s pour tenter de comprendre la situation (puissance de l&#8217;empire, h\u00e9g\u00e9monie US, ind\u00e9pendance europ\u00e9enne, d\u00e9fense europ\u00e9enne, etc.). Tout cela fait partie d&rsquo;une autre \u00e9poque. Cela signifie que le bloc BAO, qui a \u00e9t\u00e9 rassembl\u00e9 avec et apr\u00e8s la crise de l&rsquo;automne 2008 pour pr\u00e9senter un front uni, \u00e0 la fois symbole de la surpuissance du Syst\u00e8me et arrangement actant une sorte de contraction de ses membres devant le processus d&rsquo;autodestruction engendr\u00e9 par le m\u00eame Syst\u00e8me, qui a \u00e9t\u00e9 rassembl\u00e9 pour tenter (avec un insucc\u00e8s \u00e9vident et logique) d&rsquo;imposer une coh\u00e9rence l\u00e0 o\u00f9 cela semblerait encore pouvoir se faire, se trouve soudain en position d&rsquo;incoh\u00e9rence, passant de la coh\u00e9sion \u00e0 l&rsquo;incoh\u00e9sion, de la structuration assembl\u00e9e en toute h\u00e2te \u00e0 une sorte de d\u00e9bandade sous la pouss\u00e9e d&rsquo;une pression d\u00e9structurante. Toutes ses entreprises, qui sont en g\u00e9n\u00e9ral des mesures d&rsquo;urgence pour tenir \u00e0 distance les cons\u00e9quences de la crise g\u00e9n\u00e9rale d&rsquo;effondrement du Syst\u00e8me en cours et qui ne cesse de se g\u00e9n\u00e9raliser, se trouvent d\u00e8s lors  dans une logique op\u00e9rationnelle o\u00f9 elles sont menac\u00e9es d&rsquo;\u00eatre compromises, entach\u00e9es du sceau de l&rsquo;incomp\u00e9tence interne, de l&rsquo;absence de rythme coordonn\u00e9.<\/p>\n<\/p>\n<p><p>\tSi cette crise interne du bloc BAO dure, ce qui est aujourd&rsquo;hui une s\u00e9rieuse possibilit\u00e9 encore \u00e0 confirmer, un courant de d\u00e9structuration pourrait s&rsquo;installer, qui p\u00e8serait sur tous les aspects de l&rsquo;action du bloc BAO, c&rsquo;est-\u00e0-dire qui pourrait faire \u00e9voluer peu \u00e0 peu le bloc BAO vers le contraire de ce pour quoi il a \u00e9t\u00e9 constitu\u00e9. Il passerait alors d&rsquo;une formation de contraction et de rassemblement autour du Syst\u00e8me vers une d\u00e9rive de querelles et d&rsquo;incompr\u00e9hensions internes produisant de plus en plus d&rsquo;occurrences antiSyst\u00e8me. On peut voir un ph\u00e9nom\u00e8ne de cette sorte dans la consid\u00e9ration extraordinaire m\u00eame si non r\u00e9alis\u00e9e en tant que telle par les commentateurs o\u00f9 est aujourd&rsquo;hui tenu un Snowden par nombre de pays du bloc BAO, soit qu&rsquo;on entende un Hollande faire son \u00e9loge (voir le <a href=\"http:\/\/www.dedefensa.org\/article-panique-turbo_washington_29_10_2013.html\" class=\"gen\">29 octobre 2013<\/a>), soit que les d\u00e9put\u00e9s allemands demandent \u00e0 l&rsquo;auditionner, en le faisant venir en Allemagne ou en se rendant \u00e0 Moscou, soit qu&rsquo;on prenne toutes les informations venant de lui comme une source indubitable que chaque capitale concern\u00e9e fourre sous le nez de l&rsquo;ambassadeur US local pour lui en faire reproche, et recueillant en \u00e9change des balbutiements embarrass\u00e9s,  car lui aussi, l&rsquo;ambassadeur US, tient la nouvelle-Snowden pour la seule information s\u00e9rieuse du domaine.<\/p>\n<\/p>\n<p><p>\tFaut-il rappeler qu&rsquo;il y a trois mois seulement, Snowden \u00e9tait un paria condamn\u00e9 par les USA et objet d&rsquo;une chasse impitoyable et d&rsquo;un rejet quasiment universel, en vue \u00e9ventuellement d&rsquo;une liquidation sommaire, notamment dans le chef de l&rsquo;Europe, membre important du bloc BAO. Faut-il rappeler que l&rsquo;Europe s&rsquo;unissait pour intercepter l&rsquo;avion d&rsquo;un pr\u00e9sident en exercice (Morales), dans une initiative extraordinaire d&rsquo;ill\u00e9galisme et d&rsquo;impudence, pour \u00e9ventuellement se saisir de Snowden, soup\u00e7onn\u00e9 d&rsquo;\u00eatre \u00e0 son, bord, et le livrer <em>manu militari<\/em> aux USA ? Comparez cette situation avec la quasi-honorabilit\u00e9 de r\u00e9f\u00e9rence dont jouit aujourd&rsquo;hui Snowden et mesurez la b\u00e9ance de la faille que cette crise fratricide vient d&rsquo;ouvrir au sein du bloc BAO. (Mais vous dira-t-on, les USA nous \u00e9coutent toujours,  la belle et co\u00fbteuse affaire, s&rsquo;ils ne sont m\u00eame pas capables d&rsquo;\u00e9viter ce genre de d\u00e9rapage, s&rsquo;ils l&rsquo;acc\u00e9l\u00e8rent au contraire d&rsquo;une fa\u00e7on vertigineuse <strong>gr\u00e2ce<\/strong> \u00e0 ces \u00e9coutes&#8230; Bref, la NSA, tant qu&rsquo;elle survit, existe-t-elle aujourd&rsquo;hui pour autre chose que pour enregistrer scrupuleusement toutes les informations, tous les bruits, aff\u00e9rant \u00e0 la crise du bloc BAO, \u00e0 la crise d&rsquo;effondrement du Syst\u00e8me et au d\u00e9clin vertigineux de l&rsquo;influence des USA ?) <\/p>\n<\/p>\n<p><p>\tIl n&rsquo;y a rien \u00e0 attendre de cette crise, dans le style des commentateurs \u00e8s-g\u00e9ostrat\u00e9gie (c&rsquo;est celui-ci qui a gagn\u00e9, c&rsquo;est celui-ci qui a perdu, etc.). Il s&rsquo;agit de la constater et de mesurer la b\u00e9ance de la fissure qui s&rsquo;est creus\u00e9e \u00e0 cause d&rsquo;elle dans le flanc du bloc BAO. La belle union des maquilleurs de la crise de l&rsquo;automne 2008, rassembl\u00e9s pour profiter de ce que le Syst\u00e8me peut encore donner de surpuissance, d\u00e9bouche sur un aliment de plus de la dynamique d&rsquo;autodestruction du Syst\u00e8me. Et ainsi le concept g\u00e9n\u00e9ral d&rsquo;une richesse exceptionnelle de crise s&rsquo;enrichit-il d&rsquo;un nouvel \u00e9l\u00e9ment, la crise fratricide.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Terrible crise fratricide 30 octobre 2013 C&rsquo;est l&rsquo;avis de Glenn Greenwald que la semaine derni\u00e8re, avec les r\u00e9v\u00e9lations des \u00e9coutes plus ou moins av\u00e9r\u00e9es de dirigeants europ\u00e9ens du calibre de G\u00e9ants Historiques que sont Hollande et Merkel, avec le sommet de l&rsquo;UE kidnapp\u00e9 en bonne part par rapport \u00e0 son calendrier original par ces affaires&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[8385,4270,10900,6039,3015,3285,398,6944,3650,15376,3634,4633,3871,12224,3807,11131,4999],"class_list":["post-75280","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-anglo-saxonisme","tag-autodestruction","tag-bao","tag-bloc","tag-communication","tag-congres","tag-europe","tag-greenwald","tag-hegemonie","tag-hegemonisme","tag-inculpabilite","tag-merkel","tag-nsa","tag-snowden","tag-suprematisme","tag-surpuissance","tag-surveillance"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75280"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75280\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}