{"id":75335,"date":"2014-06-05T18:38:22","date_gmt":"2014-06-05T18:38:22","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/06\/05\/continuez-elkabbach\/"},"modified":"2014-06-05T18:38:22","modified_gmt":"2014-06-05T18:38:22","slug":"continuez-elkabbach","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/06\/05\/continuez-elkabbach\/","title":{"rendered":"\u201cContinuez, Elkabbach !\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">\u00ab\u00a0Continuez, Elkabbach !\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>L&rsquo;interview de Poutine pour TF1 et Europe1, pass\u00e9e le 4 juin en soir\u00e9e, on l&rsquo;a vue, entendue et largement comment\u00e9e (sauf dans la presse-Syst\u00e8me anglo-saxonne o&ugrave; tout ce qui est Poutine tout en n&rsquo;\u00e9tant pas anglo-saxon ne passe gu\u00e8re). <em>Russia Today<\/em> en fait ses choux gras, ce <a class=\"gen\" href=\"http:\/\/rt.com\/news\/163676-putin-ukraine-french-us\/\">5 juin 2014<\/a>, et l&rsquo;on dira que c&rsquo;est de bonne guerre. Plus int\u00e9ressant, beaucoup plus int\u00e9ressant, l&rsquo;ensemble des impressions de Jean-Pierre Elkabbach, l&rsquo;intervieweur d&rsquo;Europe1.<\/p>\n<\/p>\n<p><p>Elkabbach est presque aussi vieux que la V\u00e8me R\u00e9publique dans le sport de l&rsquo;interview. Il en a vu de vertes et de pas m&ucirc;res, et il a su man&oelig;uvrer avec habilet\u00e9 pour rester toujours dans les fauteuils d&rsquo;orchestre. Elkabbach est un homme du Syst\u00e8me, qui sait jouer au journaliste ind\u00e9pendant mais qui sait aussi jouer jusqu&rsquo;o&ugrave; il ne faut pas aller trop loin. De sa carri\u00e8re, on a retenu ses joutes \u00e0 la fin des ann\u00e9es 1970 avec Georges Marchais, le dirigeant fameux du PC fran\u00e7ais, et le dernier stalinien de l&rsquo;Occident de l&rsquo;imm\u00e9diat avant-Gorbatchev, qui jugeait en 1980 le bilan du communisme &laquo;<em>globalement positif<\/em>&raquo;. (Cri de guerre rest\u00e9 fameux de Marchais lors de l&rsquo;une ou l&rsquo;autre de ses rencontres en studio avec Elkabbach  : &laquo;<em>Taisez-vous, Elkabbach !<\/em>&raquo;) On a retenu aussi sa tr\u00e8s longue interview de 1993, un peu path\u00e9tique, entre le parler franc et le sauvetage convenu, avec Fran\u00e7ois Mitterrand proche du terme de sa vie et tentant d&rsquo;\u00e9carter le poids de sa maladie pour r\u00e9pliquer ; c&rsquo;\u00e9tait \u00e0 la suite des r\u00e9v\u00e9lations sur les mauvaises mais chaleureuses fr\u00e9quentations du pr\u00e9sident avec des collaborateurs notoires, dont il ne se d\u00e9partit jamais d&rsquo;avoir \u00e9t\u00e9 leur ami.<\/p>\n<\/p>\n<p><p>&#8230; Mais tout cela, pour Elkabbach, est balay\u00e9, effac\u00e9, &ndash; \u00ab\u00a0il se fout du pass\u00e9\u00a0\u00bb, comme dit la chanson de cette ch\u00e8re et bien fran\u00e7aise Edith, &ndash; pour avoir v\u00e9cu le 3 juin, \u00e0 Sotchi, &laquo;<em>un moment que je n&rsquo;oublierai jamais !<\/em>&raquo; Ainsi <em>europe1.fr<\/em> donne-t-il, le <a class=\"gen\" href=\"http:\/\/www.europe1.fr\/International\/Les-coulisses-de-l-interview-de-Vladimir-Poutine-2141581\/\">4 juin 2014<\/a> un texte dit <em>Making Off<\/em>, sur les coulisses de l&rsquo;interview de Poutine. Sur la cha&icirc;ne radio on avait pu entendre le m\u00eame <a class=\"gen\" href=\"http:\/\/www.dailymotion.com\/video\/x1yf2us_un-moment-que-je-n-oublierai-jamais_news\">4 juin 2014<\/a>, peu avant l&rsquo;interview, une mini-interview d&rsquo;Elkabbach sur son exploit de Sotchi. Le texte du <em>Making Off<\/em> nous dit \u00e0 peu pr\u00e8s ceci :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo;<em>\u00ab\u00a0Un entretien tout \u00e0 fait libre\u00a0\u00bb&#8230; Jean-Pierre Elkabbach a d\u00e9voil\u00e9 les dessous de cet \u00ab\u00a0entretien tout \u00e0 fait libre\u00a0\u00bb. \u00ab\u00a0Cela peut \u00eatre surprenant\u00a0\u00bb, conc\u00e8de le journaliste d&rsquo;Europe 1, mais l&rsquo;interview avec le dirigeant controvers\u00e9 \u00ab\u00a0s&rsquo;est d\u00e9roul\u00e9e sans pr\u00e9alable, sans tabou\u00a0\u00bb. \u00ab\u00a0Ni Poutine, ni son entourage n&rsquo;ont cherch\u00e9 \u00e0 conna&icirc;tre les th\u00e8mes&quot; des questions pos\u00e9es par Jean-Pierre Elkabbach et Gilles Bouleau<\/em> [de TF1]<em>. \u00ab\u00a0Il les ma&icirc;trise, il vit avec\u00a0\u00bb, explique le journaliste. \u00ab\u00a0Il peut improviser.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&laquo;<em>Le dirigeant russe a pourtant fait attendre les deux journalistes pendant de longues heures, mais cela n&rsquo;\u00e9tait pas une strat\u00e9gie d&rsquo;intimidation, insiste Jean-Pierre Elkabbach. En pleine crise internationale, un ballet de conseillers et ministres a pr\u00e9c\u00e9d\u00e9 Europe1 et TF1 dans l&rsquo;agenda de Vladimir Poutine.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0La fermet\u00e9 et la raideur brutale d&rsquo;un timide\u00a0\u00bb. Jean-Pierre Elkabbach a \u00e9galement livr\u00e9 ses impressions sur celui qu&rsquo;on appelle le nouveau tsar. \u00ab\u00a0Il a une sorte de charisme froid\u00a0\u00bb, d\u00e9crit-il. \u00ab\u00a0Une \u00e9nergie sans exub\u00e9rance, la fermet\u00e9 et la raideur brutale d&rsquo;un timide\u00a0\u00bb, raconte le journaliste. Selon lui, Vladimir Poutine \u00ab\u00a0ne ressemble pas \u00e0 sa caricature\u00a0\u00bb, mais il conc\u00e8de qu&rsquo;il faut \u00ab\u00a0\u00eatre vigilant\u00a0\u00bb devant le pr\u00e9sident russe.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ce texte, finalement assez prudent dans l&rsquo;atmosph\u00e8re g\u00e9n\u00e9rale des salons parisiens, ne rend pas justice \u00e0 l&rsquo;enthousiasme difficilement contenu d&rsquo;Elkabbach pour Poutine, que l&rsquo;on constate \u00e0 la vision et l&rsquo;\u00e9coute de la vid\u00e9o donn\u00e9e en r\u00e9f\u00e9rence. (Sa r\u00e9plique compl\u00e8te sur la question concernant la libert\u00e9 de l&rsquo;entretien et les conditions qu&rsquo;il a rencontr\u00e9es \u00e0 Sotchi : &laquo;<em>Pas du tout, pas du tout, \u00e7&rsquo;a \u00e9t\u00e9 un entretien tout \u00e0 fait libre des deux c\u00f4t\u00e9s et je sais bien des dirigeants fran\u00e7ais qui pourraient en prendre de la graine.<\/em>&raquo; Ainsi Poutine deviendrait-il un exemplaire \u00e8s-libert\u00e9 des contacts avec la presse pour les salons parisiens&#8230;)<\/p>\n<\/p>\n<p><p>Elkabbach est un vieux routier du monde de la communication et des salons parisiens, habile comme on l&rsquo;a d\u00e9crit, toujours prudent et ainsi de suite. Le vieux routier, habitu\u00e9 aux cahots, aux d\u00e9passements interdits et ainsi de suite, plut\u00f4t dans la cat\u00e9gorie \u00ab\u00a0vieille canaille\u00a0\u00bb (genre affectueux, type-Gainsbourg ou Eddy Mitchell) que vieille midinette s&rsquo;il fallait l&rsquo;appr\u00e9cier, s&rsquo;est pourtant laiss\u00e9 surprendre, c&rsquo;est-\u00e0-dire s\u00e9duire, et il est tomb\u00e9e sous le charme de Poutine&#8230; De quel charme s&rsquo;agit-il ? A nous commentateurs de faire des hypoth\u00e8ses, et nous avons la n\u00f4tre. Il y a certes les qualit\u00e9s de l&rsquo;homme (Poutine) mais il y aussi, &ndash; et surtout pour notre propos, et cela en ayant dans l&rsquo;oreille et \u00e0 l&rsquo;esprit l&rsquo;interview o&ugrave; Poutine fut excellent, &ndash; il y a surtout la fermet\u00e9 et l&rsquo;\u00e9vidence du propos d&rsquo;un homme qui s&rsquo;appuie sur la force des principes. Il ne perd pas trop de temps, ni ne nous fait perdre le n\u00f4tre, \u00e0 nous exposer que la Russie est un grand pays, &ndash; on le sait, &ndash; ni m\u00eame un pays \u00ab\u00a0exceptionnel\u00a0\u00bb &ndash; cela est bien possible, sans avoir \u00e0 en faire le sujet d&rsquo;une doctrine strat\u00e9gique pour la communication. Poutine d\u00e9crit et explique, et alors l&rsquo;affirmation de la souverainet\u00e9 nationale dans la politique vous permet d&rsquo;exposer cette politique avec une force principielle, c&rsquo;est-\u00e0-dire qu&rsquo;elle vous donne le talent et l&rsquo;\u00e9loquence qu&rsquo;exsude la structuration \u00e9vidente du propos. On comprend la remarque d&rsquo;Elkabbach (&laquo;<em>&#8230; et je sais bien des dirigeants fran\u00e7ais qui pourraient en prendre de la graine.<\/em>&raquo;) : m\u00eame pour le vieux routier retors et d\u00e9sabus\u00e9 de la communication parisienne, le discours d&rsquo;un homme qui applique une politique principielle pulv\u00e9rise les slogans psalmodi\u00e9s des dirigeants-Syst\u00e8me du bloc BAO, qui ne peuvent s&rsquo;appuyer que sur le vide de l&rsquo;absence de substance. Par ailleurs, Poutine est habile : on ne parle pas en vain \u00e0 un journaliste fran\u00e7ais, type-vieux routier de la V\u00e8me R\u00e9publique \u00e0 qui il reste toujours un reste de sentimentalisme pour la grandeur disparu, de De Gaulle et de Mitterrand, &ndash; c&rsquo;est-\u00e0-dire, lorsqu&rsquo;il s&rsquo;agit de rappeler le souvenir de ces hommes qui surent montrer cette m\u00eame \u00e9loquence que donne la pratique d&rsquo;une politique principielle, du temps o&ugrave; un pr\u00e9sident fran\u00e7ais, quels que soient ses d\u00e9fauts et ses qualit\u00e9s, savait \u00eatre transcend\u00e9 par la fonction. (Et Elkabbach de conclure l&rsquo;une de ses interventions, au cours du m\u00eame mini-interview : &laquo;<em>A Moscou, la France compte toujours !<\/em>&raquo;)<\/p>\n<\/p>\n<p><p>Quoi qu&rsquo;il en soit, l&rsquo;interview est, du point de vue de la communication, un coup de ma&icirc;tre de Poutine. Il plante un coin dans la structure psycho-hyper-rigide antirusse et anti-poutinienne des salons parisiens en touchant des personnalit\u00e9s au c&oelig;ur du Syst\u00e8me et non plus seulement des marginaux et des dissidents hors-Syst\u00e8me et limite antiSyst\u00e8me. Il rameute l&rsquo;esquisse de ce qui pourrait \u00eatre un changement de ton parisien \u00e0 son \u00e9gard, avec son d\u00e9jeuner avec Sarkozy (dont Elkabbach, justement, est un fid\u00e8le), au moment o&ugrave; le <em>gymkhana<\/em> parisien impos\u00e9 par les exigences de communication d&rsquo;Obama (\u00e9viter \u00e0 tout prix une rencontre avec Poutine entre deux d&icirc;ners, ce 5 juin au soir, \u00e0 Paname) a un peu agac\u00e9 la cr\u00e8me politicienne de la capitale. (Pour tous ces \u00e9pisodes, voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_le_d-day_de_poutine_03_06_2014.html\">3 juin 2014<\/a>.)<\/p>\n<\/p>\n<p><p>Curieusement, on retrouve cet avis chez P\u00e9p\u00e9 Escobar ; tout cela, dirait-on, avec l&rsquo;ombre du <em>Mistral<\/em> qui se profile, qui fera plus de vagues dans le sens transatlantique que nulle part ailleurs. R\u00e9pondant \u00e0 une interview de <em>Russia Today<\/em> le <a class=\"gen\" href=\"http:\/\/rt.com\/op-edge\/163576-obama-foreign-policy-us-normandy\/\">4 juin 2014<\/a>, Escobar nous emporte dans son habituel style imag\u00e9 et ironique, pour nous faire comprendre finalement qu&rsquo;\u00e0 son point de vue, nous ne serions peut-\u00eatre plus tr\u00e8s loin d&rsquo;un certain rapprochement franco-russe coordonn\u00e9 avec une certaine et nouvelle distance entre Paris et Washington. On verra&#8230;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><strong><em>Russia Today<\/em><\/strong>: &laquo;<em>President Hollande plans to dine twice in one night, separately with Barack Obama and with Vladimir Putin. Is this smart diplomacy or exacerbating the awkwardness?<\/em>&raquo;<\/p>\n<\/p>\n<p><p><strong><em>Pepe Escobar<\/em><\/strong>: &laquo;<em>I&rsquo;ve been wondering about the menu actually. Who gets the cheeseburger, who gets the stick of foie gras. But this is really very serious because Ben Rhodes, that spectacular mediocrity that acts as one of Obama&rsquo;s foreign policy advisors, leaked to the American press that there was never supposed to be a one-on-one meeting between Obama and Putin. So, the White House actually refused to be in the same room with Hollande and Putin. So the French had to scramble to organize two dinners in a row. This is so ridiculous I cannot find words to qualify it. And coming on the heels of the $1 billion Obama hammer, which is more NATO expansion in Poland and close the Ukrainian border as well, practically giving a blank check to the extremely hysterical Polish government to keep trying telling the world that Russia is going to invade tomorrow, or the day after. It&rsquo;s completely absurd. And they are in Normandy to celebrate 70 years<\/em> [<em>since the Normandy landings in WWII<\/em>]<em>. This is an extremely serious business, the participation especially of Russia. Twenty five million to 30 million people there were dead. In fact, Russia won the war first, and then the West won the war against Nazi Germany. So Obama and Putin should be in the same room, they belong to the same room vis-\u00e0-vis the effort of the 70 years ago. Now because of schoolboy tactics of the Obama administration we have these ridiculous two dinners in a row on Thursday in France.<\/em>&raquo;<\/p>\n<\/p>\n<p><p><strong><em>Russia Today<\/em><\/strong>: &laquo;<em>Obama will get the first meal sitting, the Russian president second. That&rsquo;s probably no accident, is it?<\/em>&raquo;<\/p>\n<\/p>\n<p><p><strong><em>Pepe Escobar<\/em><\/strong>: &laquo;<em>The empire first with cheeseburgers and then Putin with borshch and beef stroganoff. Obama doesn&rsquo;t know how to drink wine and Putin is not a big fan of it, so who is going to drink the big ones? Hollande. We have been diverted into faits de guerre as the French say. Stupidity. When we should be talking about serious business like Obama, Putin and Hollande in the same room at a dinner discussing Ukraine, discussing the expansion of NATO, discussing the BRICS and NATO as opposing camps nowadays and trying to diffuse the international tensions they were stalked up essentially by the Obama administration going back to the putsch in February in Ukraine. And now we have the completely crazy narrative that over 200 or 300 civilians killed in Eastern Ukraine are terrorists. We have the victims being blamed. This is completely crazy. This should be discussed at the presidential level at the same room.<\/em>&raquo;<\/p>\n<\/p>\n<p><p><strong><em>Russia Today<\/em><\/strong>: &laquo;<em>Which of the dinners is likely to prove toughest for Hollande to digest, in your opinion?<\/em>&raquo;<\/p>\n<\/p>\n<p><p><strong><em>Pepe Escobar<\/em><\/strong>: &laquo;<em>I would say more indigestible dinner would be with Obama in fact. French big business, they are not interested in applying more sanctions on Russia. French business wants to stay in Russia and do business with Russia and the Russian sphere. The Americans are more complicated because they are trying to ram over the heads of assorted European governments, the Trans-Atlantic Partnership and the French are absolutely terrified about it. Not only parts of Hollande&rsquo;s government but the average French citizen. First of all, because of the drubbing that the Socialists got in the European Parliamentary elections, much of it had to do with the Trans-Atlantic Partnership, which is in a nutshell American big business taking over large slates of European industry and markets. This is what Obama is going to be plugging to Hollande on Thursday night: \u00ab\u00a0Please, sign the Trans-Atlantic Agreement.\u00a0\u00bb Obama is on a military trip &ndash; Poland, Brussels, NATO &ndash; and on a commercial trip, which is this very special meeting with Hollande, trying to convince Hollande to sign this agreement within the next few months. It&rsquo;s not going to happen, and public pressure in France is going to be enormous against it.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<\/p>\n<p><p>Mis en ligne le 5 juin 2014 \u00e0 18H26<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Continuez, Elkabbach !\u00a0\u00bb L&rsquo;interview de Poutine pour TF1 et Europe1, pass\u00e9e le 4 juin en soir\u00e9e, on l&rsquo;a vue, entendue et largement comment\u00e9e (sauf dans la presse-Syst\u00e8me anglo-saxonne o&ugrave; tout ce qui est Poutine tout en n&rsquo;\u00e9tant pas anglo-saxon ne passe gu\u00e8re). Russia Today en fait ses choux gras, ce 5 juin 2014, et l&rsquo;on&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2604,15853,4900,15851,2687,3203,5270,8635,5623,916,8973,10285,5456,15852],"class_list":["post-75335","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-des","tag-elkabbach","tag-escobar","tag-europe1","tag-france","tag-hollande","tag-interview","tag-mistral","tag-parti","tag-poutine","tag-salonards","tag-salons","tag-sotchi","tag-tf1"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75335"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75335\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}