{"id":75349,"date":"2014-06-14T06:27:49","date_gmt":"2014-06-14T06:27:49","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/06\/14\/que-devrait-faire-leurope-face-a-un-djihadistan-au-moyen-orient\/"},"modified":"2014-06-14T06:27:49","modified_gmt":"2014-06-14T06:27:49","slug":"que-devrait-faire-leurope-face-a-un-djihadistan-au-moyen-orient","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/06\/14\/que-devrait-faire-leurope-face-a-un-djihadistan-au-moyen-orient\/","title":{"rendered":"Que devrait faire l&rsquo;Europe face \u00e0 un \u201cDjihadistan\u201d au Moyen-Orient ?"},"content":{"rendered":"<p><h2 class=\"common-article2\">Que devrait faire l&rsquo;Europe face \u00e0 un Djihadistan au Moyen-Orient ?<\/h2>\n<\/p>\n<p><p>\tAppelons Djihadistan un nouvel Etat qui s&rsquo;installerait, \u00e0 cheval sur la Syrie (dans le nord-est du pays) et sur l&rsquo;Irak (dans l&rsquo;Ouest et le Nord). Il r\u00e9sulterait des succ\u00e8s que rencontre actuellement le groupe djihadiste dirig\u00e9 par l&rsquo;Irakien Abou Bakr Al-Baghdadi, nomm\u00e9 l&rsquo;Etat islamique en Irak et au Levant (EIIL). L&rsquo;ambition de ces combattants est de mettre en place un v\u00e9ritable nouvel Etat dans ces r\u00e9gions, contr\u00f4lant les populations, les ressources (p\u00e9troli\u00e8res) et les territoires. Il s&rsquo;agirait d&rsquo;un Etat appliquant une charia rigoureuse capable de lui donner une puissance offensive id\u00e9ologique bien au del\u00e0 de ses fronti\u00e8res. Or l&rsquo;Europe ne peut rester indiff\u00e9rente : l&rsquo;EIIL s\u00e9duit des centaines, peut-\u00eatre des milliers, de jeunes musulmans europ\u00e9ens, venus se battre dans ses rangs, essentiellement en Syrie.<\/p>\n<\/p>\n<p><p>\tQue pourrions nous conseiller, si nous \u00e9tions en charge d&rsquo;une encore improbable diplomatie europ\u00e9enne ?<\/p>\n<\/p>\n<p><p>\t Prier instamment les Am\u00e9ricains de ne pas intervenir militairement. C&rsquo;est pourtant semble-t-il ce qu&rsquo;ils se pr\u00e9parent \u00e0 faire, en se limitant d&rsquo;ailleurs \u00e0 des frappes a\u00e9riennes, envois d&rsquo;armes et autres mesures aux retomb\u00e9es plus catastrophiques les unes que les autres. Il faut rappeler aux Am\u00e9ricains que si la situation est ce qu&rsquo;elle est aujourd&rsquo;hui, c&rsquo;est dans la continuit\u00e9 des politiques belliqueuses inaugur\u00e9es par Bush. La chute de Saddam Hussein, qu&rsquo;ils avaient provoqu\u00e9e, principalement pour s&#8217;emparer de ses ressources en p\u00e9trole, a contribu\u00e9 \u00e0 soulever le couvercle d&rsquo;une marmite qui depuis ne s&rsquo;est jamais referm\u00e9e. Qu&rsquo;ils se limitent dor\u00e9navant \u00e0 d\u00e9fendre leurs int\u00e9r\u00eats directs, par exemple les voies de communication \u00e0 travers les d\u00e9troits.<\/p>\n<\/p>\n<p><p>\t Consulter les principaux Etats directement menac\u00e9s par le futur Djihadistan, afin de d\u00e9finir avec eux des politiques de pr\u00e9vention, \u00e0 moduler au cas par cas, et que l&rsquo;Europe pourrait appuyer. Ces Etats, concern\u00e9s \u00e0 des titres diff\u00e9rents sont la Russie, l&rsquo;Iran, la Turquie, l&rsquo;Egypte et, un peu plus loin, les pays du Maghreb, notamment l&rsquo;Alg\u00e9rie. Il conviendra par contre de d\u00e9ployer la plus grande prudence \u00e0 l&rsquo;\u00e9gard des pays du Golfe, notamment l&rsquo;Arabie saoudite et le Qatar. Ceux-ci jouent simultan\u00e9ment plusieurs jeu, dont ils se servent pour abuser le monde entier: le jeu de leurs int\u00e9r\u00eats p\u00e9troliers et de leurs investissements \u00e9conomiques dans le monde, le jeu de l&rsquo;Am\u00e9rique, le jeu des multiples djihadistes qu&rsquo;ils financent partout. Des contacts devront \u00e9videmment aussi \u00eatre pris avec le Pakistan, sans oublier cependant que celui-ci pourrait prochainement se radicaliser sous l&rsquo;effet des groupes djihadistes qui l&rsquo;attaqueront de plus en plus et pourraient y prendre le pouvoir un jour.<\/p>\n<\/p>\n<p><p>\t Cesser de tenter, \u00e0 la suite des Am\u00e9ricains, de renverser Bashar al Assad. La politique de la Russie, r\u00e9cemment rappel\u00e9e par Vladimir Poutine, est la bonne: sans approuver ses exc\u00e8s consid\u00e9rer qu&rsquo;il est seul \u00e0 pouvoir emp\u00eacher une extension de l&rsquo;EIIL \u00e0 toute la Syrie<\/p>\n<\/p>\n<p><p>\t Pratiquer une politique de non-intervention active \u00e0 l&rsquo;\u00e9gard des diff\u00e9rentes composantes du Djihadistan. Celles-ci sont trop diverses pour s&rsquo;entendre longtemps. On verra ressurgir les oppositions entre tribus, entre sunnites, chiites et Kurdes, entre \u00e9mirs et combattants d&rsquo;origines diff\u00e9rentes voulant exploiter \u00e0 leur seul profit les conqu\u00eates p\u00e9troli\u00e8res faites. Il y a tout lieu de penser qu&rsquo;en quelques mois, la belle union esp\u00e9r\u00e9e par l&rsquo;EIIL se sera d\u00e9sagr\u00e9g\u00e9e, et que des modus vivendi redeviendront possibles avec les voisins et avec les Europ\u00e9ens eux-m\u00eames. Il suffirait sans doute d&rsquo;attendre un peu. Malheureusement l&rsquo;attente n&rsquo;est pas une vertu que pratiquent les excit\u00e9s et n\u00e9o-cons occidentaux de tous bords.<\/p>\n<\/p>\n<p><p>\t Renforcer sur le territoire europ\u00e9en les politiques et de contr\u00f4le et de d\u00e9fense \u00e0 l&rsquo;\u00e9gard des djihadistes, ext\u00e9rieurs ou provenant de l&rsquo;Europe elle-m\u00eame, qui tenteraient de la d\u00e9stabiliser. Sur ce plan, que nous n&rsquo;aborderons pas ici, les Europ\u00e9ens auront fort \u00e0 faire. Ils ne pourront compter que sur eux-m\u00eames \u00e0 cette fin.<\/p>\n<\/p>\n<p><p>\tA partir de cela, un point tr\u00e8s difficile restera \u00e0 r\u00e9soudre: comment l&rsquo;Europe devrait-elle se comporter pour tenter de limiter les aventures de toutes sortes auxquelles pousse actuellement Isra\u00ebl, fort de l&rsquo;appui am\u00e9ricain &#8211; tout en assurant le cas \u00e9ch\u00e9ant \u00e0 l&rsquo;Etat juif la n\u00e9cessaire protection qu&rsquo;il serait en droit d&rsquo;attendre de l&rsquo;Europe en cas d&#8217;embrasement de la r\u00e9gion ?<\/p>\n<\/p>\n<p><p>\tIl semble que, pour Vladimir Poutine, se pose une question de m\u00eame nature. Ce serait une raison de plus pour que les Europ\u00e9ens se concertent avec les Russes afin de d\u00e9finir des politiques communes au Moyen Orient.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Jean-Paul Baquiast<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que devrait faire l&rsquo;Europe face \u00e0 un Djihadistan au Moyen-Orient ? Appelons Djihadistan un nouvel Etat qui s&rsquo;installerait, \u00e0 cheval sur la Syrie (dans le nord-est du pays) et sur l&rsquo;Irak (dans l&rsquo;Ouest et le Nord). Il r\u00e9sulterait des succ\u00e8s que rencontre actuellement le groupe djihadiste dirig\u00e9 par l&rsquo;Irakien Abou Bakr Al-Baghdadi, nomm\u00e9 l&rsquo;Etat islamique&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[7895,857,13758,5788],"class_list":["post-75349","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-baquiast","tag-irak","tag-isis","tag-islamistes"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=75349"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/75349\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=75349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=75349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=75349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}